{"id":1222,"date":"2024-03-07T11:56:18","date_gmt":"2024-03-07T11:56:18","guid":{"rendered":"https:\/\/ez2290.com\/hvut\/?page_id=1222"},"modified":"2025-04-29T10:08:37","modified_gmt":"2025-04-29T10:08:37","slug":"missouri-trucking-association-mota","status":"publish","type":"page","link":"https:\/\/www.ez2290.com\/hvut\/missouri-trucking-association-mota\/","title":{"rendered":"Missouri Trucking Association"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1222\" class=\"elementor elementor-1222\" data-elementor-post-type=\"page\">\n\t\t\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-3c461ce e-con-full e-flex e-con e-parent\" data-id=\"3c461ce\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-52387f7 e-con-full e-flex e-con e-child\" data-id=\"52387f7\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a29134c elementor-widget elementor-widget-heading\" data-id=\"a29134c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.21.0 - 08-05-2024 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h1 class=\"elementor-heading-title elementor-size-default\">Special 2290 eFiling Discount for Missouri Trucking Association Members<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-75884b6 elementor-widget elementor-widget-text-editor\" data-id=\"75884b6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.21.0 - 08-05-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\tUse EZ2290 Coupon <span style=\"color: #8f3a7e;\"><strong>MTA10MOT<\/strong><\/span> to get 10% OFF on HVUT eFiling fee.\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e4e44b7 elementor-widget elementor-widget-aux_modern_button\" data-id=\"e4e44b7\" data-element_type=\"widget\" data-widget_type=\"aux_modern_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t    <div class=\"aux-modern-button-wrapper aux-modern-button-align-left\" >\n                    <a class=\"aux-modern-button aux-black aux-modern-button-md aux-modern-button-curve aux-modern-button-default aux-icon-right\" href=\"https:\/\/www.ez2290.com\/Account\/Login?utm_source=LP_SDP&#038;utm_medium=referral&#038;utm_campaign=Missouri+Trucking+Association\">\n                <div class=\"aux-overlay\"><\/div>\n                                    <div class=\"aux-icon \">\n                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"28\" height=\"28\" viewBox=\"0 0 28 28\" fill=\"none\"><g id=\"arrow_outward\"><mask id=\"mask0_1_367\" style=\"mask-type:alpha\" maskUnits=\"userSpaceOnUse\" x=\"0\" y=\"0\" width=\"28\" height=\"28\"><rect id=\"Bounding box\" width=\"28\" height=\"28\" fill=\"#D9D9D9\"><\/rect><\/mask><g mask=\"url(#mask0_1_367)\"><path id=\"arrow_outward_2\" d=\"M7.53732 21.2299L5.67383 19.3664L16.7134 8.32687H6.91023V5.6727H21.2311V19.9935H18.5769V10.1904L7.53732 21.2299Z\" fill=\"white\"><\/path><\/g><\/g><\/svg>                    <\/div>\n                                <div class=\"aux-text\">\n<span class=\"aux-text-before\">eFile 2290 Now<\/span>                <\/div>\n            <\/a>\n            \n    <\/div>\n\n    \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-274186f elementor-widget elementor-widget-image\" data-id=\"274186f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.21.0 - 08-05-2024 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/ez2290.com\/hvut\/wp-content\/uploads\/2024\/03\/irslogo.png\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-a729539 e-con-full e-flex e-con e-child\" data-id=\"a729539\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cd4393c elementor-widget elementor-widget-image\" data-id=\"cd4393c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"702\" height=\"502\" src=\"https:\/\/www.ez2290.com\/hvut\/wp-content\/uploads\/2024\/03\/Group-1000005561-1.png\" class=\"attachment-large size-large wp-image-129\" alt=\"HVUT 2290\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-f2071f4 e-con-full e-flex e-con e-parent\" data-id=\"f2071f4\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-dc4a564 e-con-full e-flex e-con e-child\" data-id=\"dc4a564\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1c6a972 elementor-widget elementor-widget-heading\" data-id=\"1c6a972\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"22\" height=\"27\" viewBox=\"0 0 32 37\" fill=\"none\">\n  <path d=\"M0 19.969L32 0V17.2751L0 37V19.969Z\" fill=\"#8F3A7E\"\/>\n<\/svg> EZ2290 Discount for MTA Members<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d65b2c elementor-widget elementor-widget-heading\" data-id=\"6d65b2c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">eFile 2290 with EZ2290 and get 10% discount<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b9b0f4 elementor-widget elementor-widget-heading\" data-id=\"5b9b0f4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Bid farewell to paperwork burdens with EZ2290 eFiling Service, now complimented with 2290 Discount for eFiling. <\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c41d4e5 elementor-widget elementor-widget-aux_modern_button\" data-id=\"c41d4e5\" data-element_type=\"widget\" data-widget_type=\"aux_modern_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t    <div class=\"aux-modern-button-wrapper aux-modern-button-align-left\" >\n                    <a class=\"aux-modern-button aux-black aux-modern-button-md aux-modern-button-curve aux-modern-button-default aux-icon-right\" href=\"https:\/\/www.ez2290.com\/Account\/Login?utm_source=LP_SDP&#038;utm_medium=referral&#038;utm_campaign=Missouri+Trucking+Association\">\n                <div class=\"aux-overlay\"><\/div>\n                                    <div class=\"aux-icon \">\n                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"28\" height=\"28\" viewBox=\"0 0 28 28\" fill=\"none\"><g id=\"arrow_outward\"><mask id=\"mask0_1_367\" style=\"mask-type:alpha\" maskUnits=\"userSpaceOnUse\" x=\"0\" y=\"0\" width=\"28\" height=\"28\"><rect id=\"Bounding box\" width=\"28\" height=\"28\" fill=\"#D9D9D9\"><\/rect><\/mask><g mask=\"url(#mask0_1_367)\"><path id=\"arrow_outward_2\" d=\"M7.53732 21.2299L5.67383 19.3664L16.7134 8.32687H6.91023V5.6727H21.2311V19.9935H18.5769V10.1904L7.53732 21.2299Z\" fill=\"white\"><\/path><\/g><\/g><\/svg>                    <\/div>\n                                <div class=\"aux-text\">\n<span class=\"aux-text-before\">Avail 2290 Discount Now<\/span>                <\/div>\n            <\/a>\n            \n    <\/div>\n\n    \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-2ef4646 e-con-full e-flex e-con e-child\" data-id=\"2ef4646\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7a76fa2 elementor-widget elementor-widget-image\" data-id=\"7a76fa2\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"303\" height=\"307\" src=\"https:\/\/www.ez2290.com\/hvut\/wp-content\/uploads\/2024\/03\/Missouri-Trucking-Association.png\" class=\"attachment-large size-large wp-image-765\" alt=\"Missouri Trucking Association\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-360c4e5 e-con-full e-flex e-con e-parent\" data-id=\"360c4e5\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-7ee1e85 e-con-full e-flex e-con e-child\" data-id=\"7ee1e85\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f63e5fa elementor-widget elementor-widget-heading\" data-id=\"f63e5fa\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"22\" height=\"27\" viewBox=\"0 0 32 37\" fill=\"none\">\n  <path d=\"M0 19.969L32 0V17.2751L0 37V19.969Z\" fill=\"#8F3A7E\"\/>\n<\/svg> About the Special 2290 Discount Program \n<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0936a7f elementor-widget elementor-widget-heading\" data-id=\"0936a7f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Get the 2290 discount you deserve  <\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-98230cd elementor-widget elementor-widget-text-editor\" data-id=\"98230cd\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>For over eight decades, the <strong>Missouri Trucking Association<\/strong> (MOTA) has been a pillar of support for the state&#8217;s trucking industry, established in 1937. Representing over 600 member companies, MOTA provides a platform for advocacy, education, and cost-saving programs tailored to enhance efficiency and safety. From driver background checks to educational seminars and safety competitions, MOTA remains committed to elevating industry standards and promoting highway safety.<\/p><p>Aligned with MOTA&#8217;s mission, IRS Authorized <a href=\"https:\/\/www.ez2290.com\/irs-authorized-2290-e-file-provder\">2290 e-File provider<\/a> EZ2290 is dedicated to supporting members by offering discounts on HVUT (Heavy Vehicle Use Tax) eFiling fees. Together, we strive to ensure that Missouri&#8217;s roads are safe and that the motor carrier industry continues to thrive. Join us in our journey towards a safer and more efficient trucking community.<\/p><p>Get your 10% discount on truck tax with coupon code: <strong>MTA10MOT<\/strong>.<\/p><p>File your <strong>IRS Form 2290 online<\/strong> quickly and easily with EZ2290&#8217;s user-friendly platform. Save time and money with our secure and hassle-free eFiling process.<\/p><p>Don&#8217;t wait! File your IRS Form <a href=\"https:\/\/www.ez2290.com\/irs-form-2290-online\">2290 online<\/a> today and save with EZ2290.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ff095b4 elementor-widget elementor-widget-aux_modern_button\" data-id=\"ff095b4\" data-element_type=\"widget\" data-widget_type=\"aux_modern_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t    <div class=\"aux-modern-button-wrapper aux-modern-button-align-left\" >\n                    <a class=\"aux-modern-button aux-black aux-modern-button-md aux-modern-button-curve aux-modern-button-default aux-icon-right\" href=\"https:\/\/www.ez2290.com\/Account\/Login?utm_source=LP_SDP&#038;utm_medium=referral&#038;utm_campaign=Missouri+Trucking+Association\">\n                <div class=\"aux-overlay\"><\/div>\n                                    <div class=\"aux-icon \">\n                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"28\" height=\"28\" viewBox=\"0 0 28 28\" fill=\"none\"><g id=\"arrow_outward\"><mask id=\"mask0_1_367\" style=\"mask-type:alpha\" maskUnits=\"userSpaceOnUse\" x=\"0\" y=\"0\" width=\"28\" height=\"28\"><rect id=\"Bounding box\" width=\"28\" height=\"28\" fill=\"#D9D9D9\"><\/rect><\/mask><g mask=\"url(#mask0_1_367)\"><path id=\"arrow_outward_2\" d=\"M7.53732 21.2299L5.67383 19.3664L16.7134 8.32687H6.91023V5.6727H21.2311V19.9935H18.5769V10.1904L7.53732 21.2299Z\" fill=\"white\"><\/path><\/g><\/g><\/svg>                    <\/div>\n                                <div class=\"aux-text\">\n<span class=\"aux-text-before\">Start e-Filing 2290 Now<\/span>                <\/div>\n            <\/a>\n            \n    <\/div>\n\n    \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-1bdaeab e-con-full e-flex e-con e-child\" data-id=\"1bdaeab\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8001a73 elementor-widget elementor-widget-image\" data-id=\"8001a73\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"385\" height=\"107\" src=\"https:\/\/www.ez2290.com\/hvut\/wp-content\/uploads\/2024\/03\/Missouri-Trucking-Association-1.png\" class=\"attachment-full size-full wp-image-847\" alt=\"Missouri Trucking Association\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-70aabc4 e-con-full e-flex e-con e-parent\" data-id=\"70aabc4\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-161b90f elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"161b90f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"22\" height=\"27\" viewBox=\"0 0 32 37\" fill=\"none\">\n  <path d=\"M0 19.969L32 0V17.2751L0 37V19.969Z\" fill=\"#8F3A7E\"\/>\n<\/svg> Why Choose Us ?\n<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ea8f384 elementor-widget elementor-widget-heading\" data-id=\"ea8f384\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">EZ2290 Makes Your 2290 eFiling Easy <\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-fc4c9ec e-con-full e-flex e-con e-parent\" data-id=\"fc4c9ec\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-47e21b3 e-con-full e-flex e-con e-child\" data-id=\"47e21b3\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3f9fb45 elementor-align-left elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"3f9fb45\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/www.ez2290.com\/hvut\/wp-content\/plugins\/elementor\/assets\/css\/widget-icon-list.min.css\">\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"27\" height=\"23\" viewBox=\"0 0 27 23\" fill=\"none\"><path d=\"M26.5504 1.48711C26.5133 1.41296 26.3928 1.2832 26.3743 1.33881L26.5411 1.59833V1.48711H26.5504Z\" fill=\"#8F3A7E\"><\/path><path d=\"M25.9092 1.28207C25.9556 1.43991 26.067 1.68132 26.2806 1.8763C26.1413 1.60704 26.2342 1.69061 26.0577 1.3842C26.0763 1.31921 26.197 1.40277 26.262 1.49562C26.2249 1.42134 26.3734 1.49562 26.262 1.32849C26.0577 1.18922 25.9835 1.23565 26.0392 1.4492C25.9835 1.41206 25.9463 1.33778 25.9092 1.29136V1.28207Z\" fill=\"#8F3A7E\"><\/path><path d=\"M19.0215 6.23586C19.0215 6.23586 19.0215 6.18064 19.0031 6.16223C19.0031 6.18984 19.0031 6.21746 19.0215 6.23586Z\" fill=\"#8F3A7E\"><\/path><path d=\"M18.3794 6.34023C18.3794 6.34023 18.4077 6.34023 18.4171 6.34023C18.3888 6.3308 18.37 6.32138 18.3794 6.34023Z\" fill=\"#8F3A7E\"><\/path><path d=\"M21.5952 4.26723L21.465 4.24863C21.5208 4.33234 21.5487 4.27653 21.5952 4.26723Z\" fill=\"#8F3A7E\"><\/path><path d=\"M25.8363 2.31298C25.8363 2.31298 25.8363 2.25752 25.8178 2.22055C25.8178 2.23904 25.8178 2.25752 25.8086 2.27601L25.8363 2.31298Z\" fill=\"#8F3A7E\"><\/path><path d=\"M22.5358 3.16046L22.5544 3.14186C22.5544 3.14186 22.5172 3.07675 22.4893 3.03024L22.5358 3.16046Z\" fill=\"#8F3A7E\"><\/path><path d=\"M23.3447 2.4166C23.3447 2.4166 23.4749 2.63052 23.5493 2.72353C23.4935 2.63052 23.4749 2.58401 23.4749 2.54681C23.447 2.50961 23.4005 2.4631 23.3447 2.4166Z\" fill=\"#8F3A7E\"><\/path><path d=\"M21.8932 3.61673C21.8932 3.61673 21.8372 3.56072 21.8279 3.55139C21.8465 3.57939 21.8745 3.59806 21.8932 3.61673Z\" fill=\"#8F3A7E\"><\/path><path d=\"M0.799326 11.6575C0.799326 11.6575 0.827596 11.6386 0.837019 11.6292C0.808749 11.6292 0.789903 11.648 0.799326 11.6575Z\" fill=\"#8F3A7E\"><\/path><path d=\"M1.21851 9.87102L1.24636 9.8803L1.37635 9.81531L1.21851 9.87102Z\" fill=\"#8F3A7E\"><\/path><path d=\"M10.5801 13.1525C10.8215 13.2453 10.6636 13.4868 10.9608 13.561C10.8772 13.496 10.7843 13.1711 10.5801 13.1525Z\" fill=\"#8F3A7E\"><\/path><path d=\"M25.7896 2.30579C25.7896 2.30579 25.7708 2.32463 25.752 2.33406C25.7708 2.33406 25.7802 2.31521 25.7896 2.30579Z\" fill=\"#8F3A7E\"><\/path><path d=\"M15.7295 8.4028C15.7295 8.4028 15.7942 8.45826 15.8219 8.47674C15.8034 8.45826 15.7757 8.43977 15.7295 8.4028Z\" fill=\"#8F3A7E\"><\/path><path d=\"M15.2939 9.27798C15.2939 9.27798 15.2285 9.25931 15.2285 9.30598C15.2378 9.30598 15.2472 9.31531 15.2565 9.32465C15.2378 9.28731 15.2379 9.26865 15.2939 9.27798Z\" fill=\"#8F3A7E\"><\/path><path d=\"M14.5957 9.90973C14.5957 9.90973 14.6241 9.92869 14.6431 9.93817V9.90973H14.5957Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.6049 13.9609C2.65136 13.8959 2.7071 13.8401 2.76285 13.7844C2.62348 13.9051 2.48412 13.8401 2.6049 13.9609Z\" fill=\"#8F3A7E\"><\/path><path d=\"M25.7432 2.19324C25.7802 2.24883 25.7988 2.27662 25.7895 2.29515L25.808 2.26736C25.808 2.26736 25.7617 2.21177 25.7432 2.19324Z\" fill=\"#8F3A7E\"><\/path><path d=\"M16.6315 10.8466L16.4922 10.9116C16.5386 10.9116 16.585 10.8745 16.6315 10.8466Z\" fill=\"#8F3A7E\"><\/path><path d=\"M7.79133 20.2916H7.76367C7.76367 20.2916 7.79133 20.3285 7.79133 20.2916Z\" fill=\"#8F3A7E\"><\/path><path d=\"M16.1947 11.2389C16.1111 11.1924 16.0554 11.1645 16.0089 11.1552C16.0089 11.1738 16.0275 11.1924 16.0368 11.2203L16.1854 11.2389H16.1947Z\" fill=\"#8F3A7E\"><\/path><path d=\"M1.95357 13.227C1.75835 13.1898 1.98146 13.1526 2.08371 12.9109C1.81413 13.0132 2.08371 12.7343 1.70258 12.9946C1.91639 12.7808 1.83272 12.8551 1.96287 12.6599C1.78624 12.8366 1.66539 12.6599 1.42369 12.8458C1.67469 12.6227 1.85131 12.725 2.06512 12.4275C1.83272 12.4926 1.68398 12.4275 1.37721 12.6227C1.4051 12.5205 1.49806 12.4275 1.47947 12.3253C1.47017 12.3532 1.53525 12.3253 1.57243 12.316C1.27496 12.316 1.33073 11.972 0.912408 12.1393C1.36792 11.8698 0.76367 11.7954 1.23777 11.6281C1.18199 11.5816 0.931 11.6095 0.838039 11.6374C1.18199 11.4143 0.828743 11.4328 0.986776 11.2283C0.772966 11.3213 0.76367 11.1633 0.614933 11.1726C0.680005 11.1726 0.745078 11.154 0.828743 11.0889C0.642821 11.0982 0.782262 11.0331 0.912408 10.8658C0.745078 10.8286 0.661413 11.0517 0.456899 11.0889C0.475491 10.9494 0.670709 10.9401 0.800854 10.8379L0.363938 10.9216C0.38253 10.8751 0.438307 10.81 0.531268 10.7449C0.401123 10.7542 0.224497 10.8007 0.354642 10.6334L0.438307 10.7449L0.59634 10.5962H0.280273C0.429011 10.2244 0.856631 10.0849 1.24707 9.88969L1.35862 9.92688C1.48877 9.85251 1.53525 9.75955 1.51665 9.72236C1.59102 9.64799 2.00005 9.61081 2.08371 9.65729C2.17668 9.8804 1.67469 9.95476 1.66539 10.1593L2.00005 10.2151L1.8792 10.2987C1.81413 10.3824 1.96287 10.3173 2.00005 10.2987C1.80483 10.401 2.03723 10.4939 2.05583 10.5869L2.19527 10.4568C2.70655 10.4196 2.01864 11.0517 2.33471 11.0982L2.67866 11.0331L2.46485 11.219C2.65078 11.1911 2.8367 11.0796 2.8367 11.2469C2.70655 11.9255 3.50602 11.9999 3.5525 12.5763C3.59898 12.5391 3.59898 12.5112 3.61757 12.4647C3.3108 13.2363 4.59366 12.567 4.39844 13.2084L4.29618 13.2549C4.46351 13.3757 4.19393 13.3014 4.15674 13.5059C4.44492 13.3199 4.51929 13.5431 4.68662 13.5616C4.62155 13.5895 4.60295 13.5616 4.53788 13.5616C4.4914 13.6267 4.33337 13.7569 4.41703 13.7662C4.88184 13.5709 5.01198 13.8126 5.24438 13.8777C5.08635 14.0357 5.03058 14.296 4.80747 14.5935C4.88184 14.5563 5.03987 14.482 5.1979 14.4076C5.13283 14.5563 5.25368 14.5284 5.38383 14.4913C5.33735 14.4448 5.30016 14.3983 5.27227 14.3704H5.29087C5.29087 14.3704 5.26298 14.3611 5.25368 14.3518C5.2165 14.3239 5.1979 14.3146 5.18861 14.3332C5.30946 14.138 5.32805 14.231 5.53256 14.0636C5.56975 14.1194 5.71849 14.1752 5.57904 14.3053C5.59764 14.3425 5.59764 14.3797 5.57904 14.4355C5.62552 14.4355 5.66271 14.4355 5.66271 14.4727H5.63482C5.63482 14.4727 5.59764 14.5284 5.57904 14.547C5.57904 14.7144 5.98807 14.6121 6.20188 14.5842C5.87652 14.7051 5.9323 14.8352 5.73708 14.9839C5.75567 14.9839 5.6906 14.8724 5.58834 14.7423C5.57904 14.7701 5.55116 14.798 5.48608 14.8538C5.37453 15.1234 5.81145 14.9003 5.80215 15.1792C5.77426 15.1792 5.70919 15.1978 5.65341 15.2628C5.65341 15.3651 5.83933 15.3 5.96018 15.2164C5.79285 15.3744 5.75567 15.6068 5.88582 15.5975C6.08103 15.5324 6.14611 15.4673 6.20188 15.5789L6.03455 15.644C6.01596 15.8485 6.29484 15.5882 6.26695 15.7648C6.28555 15.6905 6.14611 15.7927 6.14611 15.8392C6.31344 15.895 6.3971 15.8578 6.70387 15.709L6.49936 15.8671C6.67598 15.8485 6.97346 15.6997 6.73176 15.9693C7.08501 15.551 7.00135 15.8485 7.03853 15.9043C7.01994 15.9043 6.95487 15.9972 6.91768 16.053C7.18727 15.8113 7.05712 16.211 7.15938 16.3133L7.03853 16.7874C7.1036 16.8432 7.3453 15.9136 7.36389 15.96L7.30812 16.1831C7.38249 16.1831 7.40108 16.2482 7.44756 16.4063L7.41967 16.7874C7.45685 16.6387 7.48474 16.6758 7.50333 16.5085C7.52193 17.0291 7.587 16.9826 7.63348 16.9175C7.66137 16.8804 7.67996 16.8711 7.70785 16.9175C7.72644 16.9175 7.75433 17.0012 7.81011 17.2522L7.69855 16.4248C7.69855 16.4248 7.69855 16.4063 7.69855 16.397C7.70785 16.3505 7.71714 16.3226 7.81011 16.7409C7.91236 17.3173 7.83799 16.6944 7.87518 16.7874C7.87518 16.6944 7.80081 16.3319 7.77292 16.2482C7.91236 16.462 7.88447 15.9972 8.16336 16.3784C8.18195 16.0437 7.96814 15.6626 8.0611 15.6161L8.10758 15.6533C8.10758 15.6533 8.20054 15.6626 8.2935 15.6905C8.40506 15.6905 8.55379 15.7183 8.72112 15.8392C8.79549 15.5882 8.44224 15.1048 8.78619 14.9932L8.86986 15.142C8.98141 15.142 8.90704 14.9189 8.88845 14.8631C8.91634 14.8445 8.96282 14.9189 9.00001 14.9561C9.14874 14.9932 9.0093 14.8166 9.0186 14.7515L9.11156 14.8631C9.47411 14.8631 9.30678 14.231 9.56707 14.0543C9.56707 14.1194 9.68792 14.2031 9.75299 14.2403C9.50199 13.8405 9.81806 13.6639 9.83665 13.5059L9.91102 13.6825C9.87384 13.3014 10.3944 13.8684 10.3572 13.4873L10.0784 13.3943C10.1992 13.3757 10.1992 13.2642 10.0412 13.134C10.2271 13.1619 10.2922 13.3757 10.4502 13.2828C10.5432 13.3664 10.4223 13.4315 10.5803 13.5059L10.9801 13.5895C10.9801 13.5895 11.0358 13.5895 11.0637 13.5152C10.6547 13.1154 11.1846 13.3571 10.7105 13.0411C10.9243 12.7808 11.3798 12.8644 11.4077 12.4833C11.8725 12.8087 11.826 12.1208 12.2908 12.6599C12.4117 12.5577 12.4117 12.3625 12.2908 12.0929C12.2257 12.0743 12.2629 12.1672 12.2629 12.2137C12.17 12.0557 12.2908 11.8976 12.3466 11.8512C12.3838 12.0371 12.3466 12.2602 12.4767 12.5112C12.5325 12.3625 12.5046 12.0278 12.4953 11.9162L12.7742 12.1579C12.6813 11.8791 13.0531 12.3067 12.8951 11.9627L12.8021 11.8976C12.9787 11.7675 12.737 11.4979 12.8579 11.3213L12.9508 11.4328C13.0438 11.4328 12.8858 11.1075 13.1647 11.3027L13.0717 11.405C13.2576 11.5816 13.4064 11.6002 13.5272 11.6652C13.583 11.5165 13.2855 11.3213 13.3134 11.2469C13.4993 11.405 13.4064 11.3399 13.5272 11.5444C13.583 11.3771 13.6759 11.154 13.5551 10.8472C13.583 10.8751 13.6202 10.9123 13.6202 10.9123C13.7689 10.8286 13.5923 10.4103 13.7968 10.4939V10.5404C14.1314 10.717 13.8247 10.0663 14.2523 10.4939C14.3731 10.5311 14.1314 10.5683 14.401 10.7263C14.6706 10.7356 14.1593 10.2615 14.401 10.2708C14.3731 10.2708 14.401 10.2987 14.4289 10.3452C14.5126 10.2522 14.5963 10.0942 14.6613 9.95476C15.1168 10.2058 14.9681 9.51785 15.498 9.81532C15.3121 9.70377 15.3771 9.61081 15.3213 9.53644C15.3213 9.53644 15.3492 9.58292 15.3771 9.60151C15.4422 9.56433 15.3213 9.41559 15.2842 9.34122C15.4422 9.43418 15.3028 9.07164 15.4143 9.12741C15.3306 9.03445 15.3957 9.01586 15.4422 8.97867C15.4422 9.17389 15.5909 9.21108 15.6839 9.397C15.8698 9.32263 15.4794 8.82994 15.6839 8.77416L15.9256 8.88571C15.7025 8.59754 15.9349 8.58824 15.8419 8.48598C15.9442 8.55105 16.0279 8.56965 16.1394 8.70909C16.1394 8.58824 16.3532 8.65331 16.2324 8.46739L16.1115 8.4488C16.3904 8.39302 16.1487 7.90033 16.4555 7.95611L16.818 8.37443C17.0597 8.45809 16.7901 7.99329 17.0969 8.17921C16.9482 8.06766 16.9761 8.11414 16.9203 7.91892C16.8552 7.91892 16.8831 8.08625 16.8273 8.13273L16.7436 7.77948L16.6507 8.06766C16.5949 7.83526 16.6228 7.87244 16.4462 7.74229C16.4462 7.5006 16.7529 7.82596 16.7251 7.56567C16.818 7.58426 16.9017 7.77018 17.0225 7.81666C16.9946 7.58426 17.478 7.94681 17.3572 7.65863C17.4223 7.67722 17.3293 7.70511 17.413 7.79807C17.4409 7.70511 17.5059 7.67722 17.413 7.53778H17.32C17.3758 7.50989 17.2363 7.33327 17.4223 7.35186C17.3944 7.21242 17.2456 6.98002 17.1899 7.0265C17.1899 6.98002 17.3386 7.04509 17.4316 7.18453C17.5803 7.06368 17.1155 6.68254 17.4316 6.75691C17.4316 6.7755 17.4316 6.81269 17.4687 6.83128C17.5338 6.83128 17.5617 6.80339 17.5617 6.75691C17.4687 6.90565 17.8871 7.05438 17.6733 7.11016C17.8778 7.31467 17.822 7.05438 17.9428 7.11016C17.8871 6.89635 17.6733 6.7848 17.6175 6.64536C17.6733 6.71972 17.7104 6.69184 17.7662 6.69184L17.5896 6.5524C17.5896 6.5524 17.6547 6.50591 17.6547 6.43155V6.5524C17.7476 6.52451 18.073 6.71043 18.0544 6.44084C18.0823 6.5338 18.1381 6.71973 18.2868 6.74761C18.324 6.5338 18.3798 6.79409 18.5564 6.85917C18.6493 6.71043 18.324 6.5431 18.5936 6.48732C18.6122 6.46873 18.5099 6.38507 18.4541 6.35718C18.6493 6.32929 18.6215 6.15266 18.8446 6.17126C18.7516 6.17126 18.6586 6.15266 18.6679 6.01322C18.7516 6.18055 18.8817 6.0597 19.0026 6.09689L18.9468 6.00393C19.0584 6.0597 19.0491 6.13407 19.0491 6.18985C19.0212 6.16196 18.9933 6.14337 18.9747 6.17126C18.9747 6.2921 19.2722 6.58958 19.393 6.5431C19.4302 6.37577 19.2164 6.16196 19.1327 6.09689C19.3466 6.069 18.9282 5.60419 19.1792 5.62279C19.2071 5.5949 19.5975 5.84589 19.7184 5.79941C19.6068 5.56701 19.4767 5.75293 19.393 5.54842C19.9601 5.89237 19.4674 4.97206 19.9229 5.08361L20.0995 5.3439C20.1646 5.31602 20.2204 5.29742 20.2576 5.22305L20.0809 5.15798C20.0809 5.06502 20.239 5.00924 20.3505 5.22305C20.2948 4.93488 20.4156 5.02784 20.5736 5.00924C20.4528 5.08361 20.5457 4.98136 20.5736 5.16728C20.7874 5.18587 20.7317 5.10221 20.7596 4.98136C20.8153 5.07432 20.9641 5.16728 21.0013 5.13939C20.9455 4.92558 21.1035 4.85121 21.1407 4.68388L21.1965 4.75825C21.2894 4.52585 21.7542 4.69318 21.7542 4.33993C21.7542 4.33993 21.7542 4.33063 21.7542 4.32133H21.7264C21.4754 4.14471 21.7264 4.05175 21.7078 3.91231C21.7635 3.95879 21.8565 4.05175 21.8844 4.02386C21.7078 3.81005 21.8565 3.85653 21.8007 3.73568C21.9216 3.75427 22.0052 3.99597 22.0982 3.89371C22.1261 3.83794 22.0331 3.72638 21.968 3.65202C22.0796 3.73568 22.219 3.77286 22.2934 3.74498C22.3213 3.81934 22.2283 3.77286 22.2283 3.79146C22.312 3.91231 22.3213 3.83794 22.4329 3.97738C22.4979 3.94949 22.2841 3.76357 22.405 3.79146L22.4886 4.00527C22.5444 4.02386 22.5165 3.9309 22.5258 3.91231C22.5258 3.98667 22.6746 4.14471 22.7582 4.23767C22.7954 3.99597 22.4143 3.76357 22.2655 3.57765C22.5072 3.59624 22.4236 3.28947 22.5165 3.19651L22.6653 3.41032C22.6931 3.33595 22.6746 3.27088 22.6281 3.17791L22.7024 3.11284C22.721 3.22439 22.7582 3.29876 22.8791 3.4568C22.9163 3.33595 23.0743 3.28947 22.8791 3.01058L22.9163 3.05707C23.1022 3.05707 23.3811 2.92692 23.4461 3.01988C23.4926 2.83396 23.7715 2.86185 23.5577 2.60156C23.5763 2.48071 24.0225 2.78748 23.7994 2.41564C24.0225 2.51789 23.8645 2.48071 23.9946 2.69452C24.2177 2.79677 23.9388 2.28549 24.2828 2.63874C24.2828 2.44352 24.1991 2.58296 24.0876 2.38775C24.3943 2.71311 24.3107 2.29479 24.571 2.41564C24.4966 2.23901 24.4594 2.35986 24.4036 2.15534C24.4687 2.24831 24.5245 2.22971 24.5431 2.22971L24.3757 1.99731L24.9149 2.45282C24.8405 2.08098 24.571 2.09957 24.6732 1.84857V1.87646C24.9149 2.06238 24.6732 1.59758 24.9428 1.66265C24.8591 1.66265 25.0079 1.7835 25.0451 1.85787V1.70913C25.0451 1.70913 25.0544 1.74632 25.0822 1.76491C25.2868 1.87646 25.0636 1.62547 25.2589 1.70913C25.2403 1.7928 25.3983 1.95083 25.482 2.00661L25.3797 1.67195L25.5842 2.00661C25.7051 1.94153 25.4727 1.33729 25.8631 1.69984L25.8445 1.7835C25.9096 1.84857 26.1234 2.04379 26.0676 1.82998C26.0676 1.7742 25.9282 1.58828 25.9096 1.62547L26.0211 1.65336C26.1513 1.86717 26.0676 2.0345 26.0304 2.15534C25.9933 2.05309 26.0026 1.94153 25.8817 1.82998C25.8631 1.95083 25.9003 2.14605 25.8817 2.2669C25.8445 2.16464 25.7609 2.0252 25.7051 1.94153C25.5377 1.90435 25.7609 2.12746 25.7051 2.19253C25.6214 2.13675 25.5563 2.09957 25.5192 2.0252C25.5192 2.16464 25.4634 2.23901 25.3053 2.20182C25.3053 2.20182 25.2775 1.98801 25.138 1.91365C25.0915 2.15534 25.2589 2.41564 25.2124 2.67593C25.3053 3.15003 24.6918 2.76889 24.7662 3.11284C24.8312 3.2058 24.9893 3.18721 24.9521 3.30806C24.822 3.12214 24.8127 3.23369 24.7476 3.16862C24.8684 3.49398 24.571 3.2244 24.6546 3.4475C24.6174 3.37313 24.5059 3.35454 24.4222 3.31736C24.2549 3.09425 24.2549 3.31736 24.1247 2.89903C24.2642 3.33595 23.818 3.01988 24.134 3.59624L24.2177 3.62413H23.9946L24.0039 3.63342C23.9202 3.64272 23.9574 3.70779 23.6878 3.54976C23.6785 3.46609 23.725 3.42891 23.7157 3.34524C23.4833 3.2151 23.6971 3.63342 23.6321 3.70779C23.5019 3.54976 23.6692 3.58694 23.4833 3.41032C23.4089 3.42891 23.4554 3.58694 23.4368 3.6799L23.3718 3.58694C23.065 3.50328 23.6785 4.06104 23.3253 3.85653C23.3718 3.90301 23.4089 3.96808 23.4554 4.01456C23.3439 3.95879 23.1208 3.87512 23.1208 3.6892C23.0743 3.72638 23.0836 3.85653 23.1394 3.96808C23.2881 4.06104 23.2416 3.98667 23.3996 4.13541L23.2788 4.38641C23.2788 4.38641 23.223 4.28415 23.2509 4.26556C22.6374 3.99597 23.1115 5.04643 22.3864 4.71177C22.5351 4.83262 22.47 4.85121 22.5258 4.97206C22.405 4.99995 22.312 5.13939 22.154 5.1208L22.0982 4.99995C21.9959 5.28813 21.9866 5.55771 21.81 5.60419C21.8379 5.65067 21.6892 5.46475 21.6892 5.41827C21.7449 5.67856 21.15 5.21376 21.4382 5.61349H21.5032C21.2615 5.71575 21.2708 6.16196 21.1221 6.37577C20.8897 6.18985 21.2151 6.25492 20.9455 6.02252C20.7317 6.05041 20.7503 6.35718 20.5457 6.41295C20.5457 6.36647 20.5179 6.33859 20.5179 6.31999C20.2483 6.3014 20.7224 6.5338 20.5736 6.59888C20.49 6.47803 20.4528 6.45943 20.3691 6.44084L20.4807 6.65465C20.4807 6.65465 20.3319 6.48732 20.3041 6.42225C20.4528 6.70113 20.146 6.68254 20.2948 6.94283C20.239 6.89635 20.0902 6.66395 19.9973 6.58958C19.8764 6.58958 19.9043 6.71043 19.9322 6.83128C19.7556 6.71043 19.6626 6.83128 19.6626 6.7848C19.4767 6.81269 19.7463 6.92424 19.7742 7.13805L19.9508 7.15664L19.83 7.35186L19.8021 7.18453C19.6533 7.16594 19.737 7.42623 19.644 7.5006L19.7928 7.59356L19.7556 7.76089C19.5232 7.50989 19.5697 7.81666 19.3651 7.46341C19.0584 7.4913 19.235 7.94681 19.077 8.11414C19.1049 8.08625 19.0491 8.04907 19.0212 7.99329C18.8725 8.02118 18.9282 8.2071 18.984 8.39302C18.9282 8.30006 18.9282 8.25358 18.8632 8.17921C18.7423 8.28147 18.9189 8.39302 18.8632 8.57894C18.8074 8.4395 18.7423 8.39302 18.6865 8.39302C18.7795 8.48598 18.8074 8.57894 18.8074 8.62542C18.4541 8.02118 18.4727 8.54176 18.1845 8.07695C18.2775 8.1978 18.2682 8.59754 18.5099 8.75557V8.6812C18.6401 8.82064 18.5471 8.81135 18.5099 8.84853C18.5099 8.81135 18.5006 8.75557 18.4727 8.72768C18.4355 9.06234 18.1009 9.07164 18.0079 9.37841C17.98 9.31333 17.98 9.146 17.8871 9.146C17.6175 9.24826 17.729 9.6294 17.6361 9.93617C17.3386 9.61081 17.822 9.69447 17.5524 9.36911C17.3944 9.6387 17.2735 9.94547 17.1806 10.3266C16.6693 9.91758 17.1155 10.7356 16.6321 10.4846C16.7901 10.6334 16.7622 10.7542 16.6879 10.8379C16.5949 10.6799 16.5112 10.7542 16.4462 10.6334C16.502 10.8472 16.3532 11.0889 16.0836 10.7635C16.3346 11.0796 15.9163 10.8844 16.0557 11.154C15.8605 11.1168 15.9163 11.3864 15.7304 11.3957C15.9442 11.5537 15.7025 11.5909 15.7304 11.7024C15.7304 11.6838 15.7304 11.6281 15.7025 11.6095C15.5166 11.47 15.7025 11.8698 15.5537 11.8326C15.4608 11.7861 15.405 11.6467 15.3399 11.6745C15.4608 11.814 15.4329 12.1208 15.2191 12.0092C15.247 11.9813 15.1912 11.9162 15.154 11.8419C15.0704 12.3439 14.494 12.3439 14.4382 12.9016L14.2802 12.6227C13.8247 12.5019 14.494 13.1061 14.3174 13.2177C13.8061 13.478 13.0903 13.5524 12.8207 14.0636C12.8486 14.1566 12.9137 14.1287 13.0066 14.2217C12.9508 14.2217 12.7649 14.045 12.8207 14.2124L12.9415 14.3239C12.4489 14.1659 12.6441 15.0304 12.0212 14.6493C12.0398 15.0025 11.6029 14.7887 11.6866 15.2721C11.5192 15.2349 11.5564 15.0025 11.4449 15.0583V15.4209V15.393C11.6401 15.9043 10.5896 15.4859 10.6547 15.96V15.9321C10.5617 15.8485 10.413 15.8113 10.413 15.8764C10.4595 15.9414 10.5153 15.9414 10.6082 15.9879C10.5803 16.3226 10.5525 16.3691 10.4409 16.555C10.3665 16.3784 10.2736 16.5271 10.0784 16.3877C10.162 16.5271 10.2922 16.5178 10.3201 16.6944C10.2178 16.8525 9.99469 16.8153 9.78088 16.9826C9.89243 17.1964 9.78088 17.2615 9.9668 17.4567C9.80877 17.7821 9.75299 18.0052 9.56707 18.4886L9.51129 18.4049C9.66003 18.879 9.251 18.6094 9.32537 18.9162C9.26959 18.7582 9.2603 18.6559 9.19522 18.5629L9.17663 18.8976C9.15804 18.6652 9.00001 18.2469 8.92564 18.3398C8.99071 18.7953 9.02789 18.4979 9.10226 18.8232L8.91634 18.47C8.88845 18.6187 9.05578 19.1486 9.16733 19.1021C8.99071 19.5483 8.86986 20.3013 8.69323 20.6546L8.62816 20.2362C8.58168 20.5709 8.47013 20.8963 8.37717 20.701C8.37717 20.6732 8.35857 20.6546 8.35857 20.636C8.37717 20.7568 8.37717 20.9706 8.41435 21.1101C8.35858 21.5842 8.31209 20.45 8.25632 20.9706C8.27491 20.8498 8.3028 20.7847 8.27491 20.5523C8.24702 20.6267 8.21913 20.6917 8.19125 20.7568C8.17265 20.7847 8.16336 20.8126 8.14477 20.8405H8.0704C8.03321 20.5802 7.8194 19.8272 7.70785 19.8923C7.70785 20.0224 7.75433 20.2455 7.78222 20.3106L7.69855 20.3292L7.62418 19.7157C7.587 19.8272 7.54982 19.9388 7.51263 20.041V19.6041C7.42897 19.6041 7.38249 20.0968 7.29882 19.9667C7.03853 19.3717 7.1036 19.3066 6.98275 18.7396C6.84331 19.4182 6.71317 18.3863 6.55513 18.8139C6.45288 18.0517 6.01596 17.9215 5.77426 17.4381H5.83004C5.87652 17.0756 5.42101 17.5869 5.34664 17.3173L5.4396 17.2987C5.45819 17.0849 5.32805 16.9175 5.18861 16.8432C5.05846 16.7688 4.87254 16.7409 4.71451 16.7409C4.80747 16.7223 4.92832 16.5922 4.87254 16.555C4.75169 16.5829 4.60295 16.8339 4.62155 16.6851C4.67732 16.6758 4.76099 16.5829 4.7424 16.555L4.46351 16.6387C4.43563 16.2947 4.37985 15.9136 4.07308 15.7834C4.11026 15.6812 4.22182 15.6533 4.29618 15.6068C4.11026 15.4581 3.7849 15.4209 3.61757 15.2814L3.84997 15.0676C3.7849 14.9839 3.43165 15.3186 3.57109 15.0397C3.58968 14.9932 3.64546 15.0955 3.7756 15.0397C3.84068 14.733 3.45954 15.1327 3.36658 14.9561L3.68264 14.7794C3.75701 14.5284 3.43165 14.7608 3.22713 14.8445C2.76233 14.9282 3.68264 14.3053 3.25502 14.2682C3.08769 14.3425 3.0598 14.4355 2.89247 14.5098C2.84599 14.2867 2.62289 14.4262 2.57641 14.2031C2.93896 13.794 2.64148 14.2867 2.96684 13.887V14.0822C3.10628 13.8033 3.09699 14.138 3.32939 13.9242C3.33869 13.7848 3.03192 13.8312 2.87388 13.7848C3.0598 13.6453 2.98544 13.887 3.20854 13.6453H3.08769C3.15277 13.6267 3.22713 13.5709 3.24573 13.6081C3.41306 13.4501 3.20854 13.5338 3.16206 13.4873C3.0598 13.5616 2.92036 13.6639 2.79951 13.7848C2.81811 13.7662 2.8367 13.7476 2.85529 13.7197C2.50204 13.8219 2.57641 13.4873 2.28823 13.5616C2.3533 13.5338 2.3626 13.5059 2.40908 13.4687C2.37189 13.3943 2.07442 13.5152 1.93498 13.4873C2.03723 13.3385 2.38119 13.1991 2.19527 13.1247C2.01864 13.2177 1.78624 13.4873 1.70258 13.3571C1.70258 13.3571 1.90709 13.3571 1.98146 13.227H1.95357ZM4.28689 15.5045C4.28689 15.5045 4.31478 15.5324 4.34266 15.551C4.34266 15.551 4.29618 15.5138 4.28689 15.5045ZM4.61225 15.5696C4.61225 15.5696 4.51929 15.5975 4.45422 15.6533C4.48211 15.6905 4.50999 15.7183 4.51929 15.7555C4.55647 15.6719 4.55647 15.5882 4.61225 15.5696ZM5.46749 14.2403L5.49538 14.2217C5.49538 14.2217 5.55116 14.2496 5.56975 14.2589C5.60693 14.2217 5.63482 14.1752 5.57904 14.1659C5.55116 14.1845 5.50468 14.2031 5.46749 14.231V14.2403Z\" fill=\"#8F3A7E\"><\/path><path d=\"M5.26323 14.3253C5.26323 14.3253 5.24482 14.3253 5.23562 14.3253C5.22642 14.3437 5.21721 14.3621 5.20801 14.3805L5.28164 14.3437L5.26323 14.3253Z\" fill=\"#8F3A7E\"><\/path><path d=\"M21.6523 4.27579C21.6523 4.27579 21.6712 4.27579 21.69 4.29463C21.6806 4.29463 21.6712 4.28521 21.6618 4.27579H21.6523Z\" fill=\"#8F3A7E\"><\/path><path d=\"M7.48508 20.1339L7.49435 20.032L7.46655 20.0876L7.48508 20.1339Z\" fill=\"#8F3A7E\"><\/path><path d=\"M23.4094 3.96896C23.4094 3.96896 23.4473 3.9974 23.4663 4.00688C23.4568 3.9974 23.4284 3.97844 23.4094 3.96896Z\" fill=\"#8F3A7E\"><\/path><path d=\"M24.4309 3.36418C24.4309 3.36418 24.3847 3.29949 24.3662 3.27176L24.4309 3.36418Z\" fill=\"#8F3A7E\"><\/path><path d=\"M19.885 6.80322C19.8943 6.85893 19.9036 6.90536 19.9036 6.95178C19.95 6.9425 19.9779 6.92393 19.885 6.80322Z\" fill=\"#8F3A7E\"><\/path><path d=\"M16.6518 10.8394L16.6318 10.8494L16.6518 10.8394Z\" fill=\"#8F3A7E\"><\/path><path d=\"M19.8203 7.01859C19.885 7.02783 19.9035 7.0001 19.9035 6.95389C19.8665 6.96313 19.8203 6.97237 19.8203 7.01859Z\" fill=\"#8F3A7E\"><\/path><path d=\"M26.1981 2.03489H26.2264C26.2264 2.03489 26.2075 2.00662 26.1981 1.99719V2.03489Z\" fill=\"#8F3A7E\"><\/path><path d=\"M26.1977 1.99845V1.96075C26.1977 1.96075 26.1789 1.9796 26.1977 1.99845Z\" fill=\"#8F3A7E\"><\/path><path d=\"M26.2079 1.8683V1.95148C26.2079 1.95148 26.2449 1.933 26.2079 1.8683Z\" fill=\"#8F3A7E\"><\/path><path d=\"M25.6025 2.37845L25.6578 2.45208C25.6578 2.45208 25.6302 2.40606 25.6025 2.37845Z\" fill=\"#8F3A7E\"><\/path><path d=\"M25.4627 2.52706C25.5183 2.50852 25.6852 2.60121 25.7037 2.51779L25.6574 2.45291C25.7223 2.58267 25.3978 2.37876 25.4627 2.52706Z\" fill=\"#8F3A7E\"><\/path><path d=\"M24.0587 2.18406L24.2354 2.12826C24.1517 2.07245 24.0308 1.98874 24.0773 1.92363C23.7145 1.83062 24.254 2.07245 24.0587 2.18406Z\" fill=\"#8F3A7E\"><\/path><path d=\"M23.5575 2.40555C23.5946 2.31271 23.4646 2.29414 23.4275 2.24771C23.4461 2.35913 23.4461 2.38698 23.5575 2.40555Z\" fill=\"#8F3A7E\"><\/path><path d=\"M20.6004 4.88834L20.4517 4.70251C20.4239 4.77684 20.5075 4.77684 20.6004 4.88834Z\" fill=\"#8F3A7E\"><\/path><path d=\"M20.833 6.30117L20.9817 6.36621L20.8702 6.18039L20.833 6.30117Z\" fill=\"#8F3A7E\"><\/path><path d=\"M19.4009 5.29716L19.4102 5.25073L19.373 5.39001L19.4009 5.29716Z\" fill=\"#8F3A7E\"><\/path><path d=\"M14.5673 9.62069L14.7804 9.8246C14.7804 9.75045 14.5673 9.5002 14.5673 9.62069Z\" fill=\"#8F3A7E\"><\/path><path d=\"M12.6902 11.7309C12.5694 11.6473 12.4486 11.6287 12.5044 11.7681C12.5601 11.7402 12.6902 11.7774 12.6902 11.7309Z\" fill=\"#8F3A7E\"><\/path><path d=\"M7.70828 16.6682L7.6897 16.4824L7.69899 16.659L7.70828 16.6682Z\" fill=\"#8F3A7E\"><\/path><path d=\"M1.70163 9.61194C1.61792 9.63054 1.4691 9.73285 1.52491 9.76076L1.81324 9.63984L1.70163 9.61194Z\" fill=\"#8F3A7E\"><\/path><path d=\"M1.38543 10.1886C1.54327 10.17 1.80325 10.0957 2.02609 9.91004C1.74754 10.0122 1.84039 9.9379 1.50613 10.0586C1.45042 10.0307 1.54327 9.92861 1.64541 9.88219C1.57113 9.90076 1.66398 9.78006 1.47828 9.85433C1.30187 10.0307 1.33901 10.1143 1.55256 10.0865C1.50613 10.1329 1.42257 10.1607 1.37615 10.1886H1.38543Z\" fill=\"#8F3A7E\"><\/path><path d=\"M6.07034 17.5318C6.07034 17.5318 6.02367 17.5318 6.005 17.5598C6.033 17.5598 6.06101 17.5598 6.07034 17.5318Z\" fill=\"#8F3A7E\"><\/path><path d=\"M6.40438 18.461C6.40438 18.461 6.38574 18.4238 6.38574 18.4051C6.38574 18.4517 6.38574 18.4797 6.40438 18.461Z\" fill=\"#8F3A7E\"><\/path><path d=\"M4.03508 14.7249L4.01648 14.8551C4.10019 14.7993 4.04438 14.7714 4.03508 14.7249Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.3788 10.391C2.3788 10.391 2.32335 10.391 2.28638 10.391C2.30486 10.391 2.32335 10.4002 2.33259 10.4095L2.3788 10.3817V10.391Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.96444 13.7376L2.94584 13.719C2.94584 13.719 2.87143 13.7562 2.83423 13.7748L2.96444 13.7376Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.26855 12.8844C2.26855 12.8844 2.49178 12.7635 2.58479 12.7077C2.49178 12.7635 2.43597 12.7728 2.40807 12.7728C2.37087 12.8007 2.32436 12.8379 2.26855 12.8937V12.8844Z\" fill=\"#8F3A7E\"><\/path><path d=\"M3.40322 14.398C3.40322 14.398 3.34722 14.4447 3.33789 14.4634C3.36589 14.4447 3.38456 14.4167 3.40322 14.398Z\" fill=\"#8F3A7E\"><\/path><path d=\"M24.3936 0.882324C24.3936 0.882324 24.4124 0.910594 24.4218 0.920017C24.4124 0.891747 24.403 0.882324 24.3936 0.882324Z\" fill=\"#8F3A7E\"><\/path><path d=\"M26.1963 1.0585V1.08636L26.2891 1.19778L26.1963 1.0585Z\" fill=\"#8F3A7E\"><\/path><path d=\"M7.32639 20.0692C7.32639 20.0692 7.32639 20.0692 7.32639 20.0592C7.29639 20.0692 7.31639 20.0792 7.32639 20.0692Z\" fill=\"#8F3A7E\"><\/path><path d=\"M13.8886 13.0136C13.6561 12.9113 13.8142 12.6788 13.5166 12.5951C13.6003 12.6602 13.684 12.995 13.8886 13.0136Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.37 10.4381C2.37 10.4381 2.38884 10.457 2.39826 10.4758C2.39826 10.457 2.38884 10.4476 2.37 10.4381Z\" fill=\"#8F3A7E\"><\/path><path d=\"M9.13905 18.7775C9.11125 18.7312 9.08346 18.6942 9.05566 18.6756C9.07419 18.7127 9.09272 18.7405 9.13905 18.7775Z\" fill=\"#8F3A7E\"><\/path><path d=\"M7.87305 19.9031L7.91937 20.005C7.90084 19.9494 7.89158 19.9216 7.87305 19.9031Z\" fill=\"#8F3A7E\"><\/path><path d=\"M9.5293 17.1406C9.5293 17.1406 9.59373 17.1407 9.59373 17.0762C9.58452 17.0762 9.57532 17.0762 9.56611 17.067C9.58452 17.1038 9.58452 17.1406 9.5385 17.1406H9.5293Z\" fill=\"#8F3A7E\"><\/path><path d=\"M10.1335 16.3052C10.1335 16.3052 10.0955 16.2957 10.0861 16.2863V16.3147L10.1335 16.3052Z\" fill=\"#8F3A7E\"><\/path><path d=\"M22.2911 2.80592C22.3562 2.85237 22.4119 2.89883 22.477 2.95457C22.3469 2.8245 22.4119 2.68513 22.2911 2.80592Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.25891 10.4761C2.31499 10.448 2.35237 10.4293 2.37106 10.4387L2.34302 10.42C2.34302 10.42 2.2776 10.4574 2.25891 10.4761Z\" fill=\"#8F3A7E\"><\/path><path d=\"M8.05957 15.6353L8.11645 15.6163C8.11645 15.6163 8.06905 15.6163 8.05957 15.6353Z\" fill=\"#8F3A7E\"><\/path><path d=\"M17.1702 7.21375V7.16635C17.1702 7.16635 17.1607 7.18531 17.1702 7.21375Z\" fill=\"#8F3A7E\"><\/path><path d=\"M8.31042 15.2827C8.40334 15.3198 8.45908 15.3198 8.50554 15.3198C8.49625 15.3013 8.48696 15.2827 8.46837 15.2641L8.31042 15.2827Z\" fill=\"#8F3A7E\"><\/path><path d=\"M22.9801 2.12785C22.9986 1.93263 23.0544 2.14644 23.2961 2.2394C23.1753 1.97911 23.4635 2.23011 23.1846 1.86756C23.417 2.07207 23.3333 1.98841 23.5378 2.09996C23.3519 1.93263 23.5099 1.80249 23.3147 1.57938C23.5564 1.81178 23.4635 1.98841 23.7795 2.18363C23.6959 1.96052 23.7516 1.80249 23.5285 1.51431C23.6308 1.5422 23.733 1.62586 23.826 1.58868C23.7981 1.58868 23.826 1.64445 23.8446 1.68164C23.8167 1.38416 24.1607 1.42135 23.9468 1.02161C24.2536 1.44923 24.2629 0.844989 24.4767 1.3005C24.5232 1.24472 24.4581 1.00302 24.4117 0.910061C24.6719 1.22613 24.6069 0.882173 24.8207 1.02161C24.6998 0.8171 24.8486 0.798508 24.8207 0.649771C24.8207 0.705547 24.8579 0.77062 24.9415 0.854285C24.895 0.668363 24.988 0.807804 25.1646 0.910061C25.1646 0.742732 24.9508 0.686955 24.8765 0.491737C25.0159 0.491737 25.0531 0.677659 25.1739 0.798508L25.0252 0.38948C25.0717 0.398776 25.1367 0.445257 25.2204 0.528921C25.1832 0.408072 25.1089 0.240743 25.2855 0.343L25.1925 0.435961L25.3599 0.566106L25.3041 0.268631C25.6666 0.361592 25.899 0.742732 26.1593 1.08669L26.1407 1.19824C26.2337 1.30979 26.3359 1.33768 26.3731 1.31909C26.4661 1.37487 26.5683 1.7746 26.5219 1.87685C26.3081 2.02559 26.1593 1.5236 25.9548 1.55149L25.9362 1.89545L25.8432 1.78389C25.7503 1.72812 25.8432 1.86756 25.8525 1.90474C25.7224 1.72812 25.6666 1.96982 25.5644 2.007L25.7131 2.12785C25.7968 2.63913 25.0903 2.02559 25.081 2.34166L25.1739 2.68561L24.9694 2.4904C25.0066 2.67632 25.1367 2.85294 24.9694 2.86224C24.2815 2.79717 24.2629 3.59663 23.6773 3.6803C23.7144 3.71748 23.7423 3.72678 23.7981 3.73607C23.0172 3.47578 23.7423 4.72146 23.0916 4.55413L23.0451 4.46117C22.9243 4.6285 22.9986 4.35891 22.7848 4.34032C22.9801 4.6192 22.7662 4.70287 22.7569 4.87949C22.7291 4.81442 22.7569 4.79583 22.7569 4.73075C22.6919 4.68427 22.5524 4.53554 22.5524 4.6192C22.7755 5.07471 22.5338 5.21415 22.4688 5.45585C22.3014 5.29782 22.0411 5.26063 21.7437 5.03752C21.7809 5.11189 21.8645 5.26993 21.9482 5.41866C21.7995 5.35359 21.8273 5.47444 21.8738 5.61388C21.9203 5.5674 21.9575 5.53022 21.9854 5.49303V5.51163C21.9854 5.51163 21.9947 5.48374 22.004 5.47444C22.0319 5.43726 22.0412 5.40937 22.0226 5.40937C22.2271 5.52092 22.1341 5.54881 22.3014 5.74403C22.2457 5.78121 22.1992 5.93925 22.0597 5.7998C22.0226 5.8184 21.9854 5.8184 21.9296 5.8184C21.9296 5.86488 21.9296 5.90206 21.8924 5.90206V5.87417C21.8924 5.87417 21.8366 5.83699 21.818 5.8184C21.6507 5.8184 21.7623 6.23672 21.7995 6.44123C21.6693 6.12517 21.5392 6.17165 21.3811 5.99502C21.3811 6.01361 21.4927 5.93925 21.6228 5.83699C21.5949 5.82769 21.5578 5.7998 21.502 5.73473C21.2324 5.63247 21.4648 6.06009 21.1859 6.06009C21.1859 6.03221 21.1673 5.97643 21.1022 5.91136C21 5.91136 21.0744 6.09728 21.158 6.21813C20.9907 6.0508 20.7676 6.02291 20.7676 6.15306C20.842 6.34827 20.907 6.40405 20.7955 6.46912L20.7304 6.31109C20.5259 6.30179 20.7955 6.57138 20.6188 6.55279C20.7025 6.57138 20.591 6.44123 20.5445 6.43194C20.4887 6.59927 20.5445 6.67364 20.6746 6.9897L20.5259 6.77589C20.5259 6.98041 20.5445 7.38014 20.3214 7.11055C20.7025 7.49169 20.2935 7.51028 20.2005 7.57536C20.2191 7.53817 20.154 7.44521 20.1169 7.39873C20.1726 7.82635 19.7636 7.7148 19.587 7.88213L19.2988 7.61254C19.2151 7.7055 19.6892 8.31904 19.5777 8.39341L19.494 8.21679C19.3546 8.4213 19.2523 8.45849 19.0664 8.54215L18.8991 8.33764C18.927 8.47708 18.8619 8.53285 18.8898 8.6723C18.3506 8.29116 18.6295 9.34161 17.9416 8.99766L18.2483 9.3788C18.1554 9.44387 18.1089 9.6112 17.83 9.3788H17.8579C17.6162 9.08132 17.7649 9.43458 17.6627 9.41598C17.6534 9.48106 17.7742 9.70416 17.8579 9.72275C17.4675 9.72275 17.3094 10.2154 16.8725 10.0109C16.7517 10.327 16.8446 10.7732 16.5658 10.9498L16.5286 10.9034C16.4077 10.9219 16.1474 10.9684 15.8778 10.6617C15.7663 10.8848 16.0359 11.4053 15.7012 11.4518L15.6454 11.2938C15.5432 11.2845 15.5897 11.4983 15.599 11.5541C15.5711 11.5634 15.5339 11.489 15.4967 11.4425C15.3573 11.3868 15.4688 11.5727 15.4595 11.6377L15.3851 11.5169C15.0319 11.4518 15.1435 12.1026 14.8925 12.242C14.9018 12.1769 14.7809 12.084 14.7158 12.0468C14.9389 12.4651 14.6229 12.5952 14.6136 12.7533L14.5485 12.5767C14.5764 12.9578 14.0744 12.3535 14.1116 12.7347L14.3812 12.8369C14.2603 12.8369 14.2603 12.9578 14.4184 13.0972C14.2324 13.0601 14.1767 12.8462 14.0186 12.9299C13.9257 12.8369 14.0465 12.7812 13.8978 12.6975L13.498 12.6045C13.498 12.6045 13.4423 12.5952 13.4144 12.6696C13.8141 13.0786 13.2935 12.8184 13.7583 13.153C13.5538 13.404 13.0983 13.311 13.0704 13.6922C12.6149 13.3668 12.6521 14.0547 12.1873 13.5156C12.0664 13.6178 12.0757 13.813 12.2059 14.0826C12.271 14.1012 12.2338 14.0083 12.2338 13.9618C12.3267 14.1198 12.2152 14.2685 12.1594 14.3243C12.1222 14.1384 12.1501 13.9246 12.02 13.6736C11.9642 13.8223 12.0014 14.1477 12.0107 14.2685L11.7318 14.0268C11.834 14.3057 11.4529 13.8781 11.6202 14.2221L11.7132 14.2871C11.5366 14.4173 11.7876 14.6869 11.6853 14.8542L11.5923 14.7426C11.4994 14.7426 11.676 15.068 11.3878 14.8821L11.4715 14.7798C11.2856 14.6032 11.1275 14.6032 11.0067 14.5381C10.9509 14.6869 11.267 14.8635 11.2484 14.9379C11.0532 14.7891 11.1554 14.8542 11.016 14.6497C10.9602 14.817 10.8951 15.0401 11.0439 15.3376C11.016 15.319 10.9788 15.2725 10.9788 15.2725C10.8394 15.3562 11.0625 15.7559 10.8487 15.6908V15.6444C10.4954 15.5049 10.8765 16.1092 10.4024 15.728C10.2816 15.7001 10.514 15.6444 10.2258 15.5142C9.95623 15.5328 10.5233 15.9418 10.2909 15.9511C10.3188 15.9511 10.2909 15.9325 10.2537 15.8861C10.1886 15.9883 10.1329 16.1464 10.0957 16.2858C9.60298 16.1185 9.90046 16.732 9.3148 16.574C9.51002 16.639 9.46354 16.7692 9.52861 16.8343C9.52861 16.8343 9.49143 16.7878 9.46354 16.7785C9.39847 16.8343 9.53791 16.983 9.58439 17.0667C9.41706 17.0016 9.58439 17.4385 9.46354 17.4013C9.54721 17.5036 9.48213 17.5501 9.43565 17.6244C9.43565 17.3455 9.28692 17.3363 9.18466 17.1131C9.02663 17.234 9.40776 17.8661 9.21255 18.0613C9.13818 18.0242 9.07311 17.987 8.99874 17.9405C9.20325 18.3867 8.99874 18.4983 9.07311 18.6656C8.98944 18.5726 8.92437 18.554 8.82211 18.303C8.82211 18.5354 8.65478 18.4239 8.74774 18.7957L8.8407 18.8236C8.72915 18.9073 8.71985 19.1955 8.70126 19.4929C8.68267 19.7811 8.65478 20.06 8.55253 19.9856L8.33872 18.9445C8.19927 18.647 8.33872 19.8462 8.17139 19.2977C8.24575 19.6417 8.23646 19.5022 8.25505 20.0042C8.29223 20.0135 8.28294 19.5952 8.32942 19.4929L8.34801 20.404L8.44097 19.6882C8.45956 20.2738 8.44097 20.1716 8.55253 20.5341C8.52464 21.0547 8.40379 20.5713 8.35731 20.7386C8.34801 20.7386 8.32942 20.7758 8.32012 20.8502C8.25505 20.6828 8.23646 20.2831 8.17139 20.06C8.12491 20.4411 7.94828 19.4093 7.9018 19.7718C7.86461 19.6417 7.94828 19.7997 7.92039 19.5673C7.85532 19.5673 7.80884 19.4744 7.79954 19.7253L7.87391 19.902C7.81813 19.809 7.82743 20.1716 7.69728 19.8276C7.64151 19.9577 7.60432 20.3296 7.68799 20.4318C7.6601 20.4504 7.57644 20.1344 7.60432 19.902C7.4277 19.6789 7.51136 20.6921 7.32544 20.0693C7.34403 20.0693 7.35333 20.0321 7.35333 19.9763C7.30685 19.8648 7.26967 19.8183 7.23248 19.8276C7.39981 19.9485 7.22318 19.1304 7.39051 19.4929C7.39051 19.0374 7.26037 19.2512 7.21389 19.0188C7.10234 19.1955 7.15811 19.5952 7.09304 19.7439C7.10234 19.6138 7.06515 19.5673 7.02797 19.4651L7.04656 19.8183C7.00008 19.7718 6.96289 19.716 6.90712 19.7253L7.00937 19.7068C6.91641 19.5394 6.86993 18.9352 6.67472 19.0281C6.73979 18.9631 6.85134 18.8236 6.79556 18.5726C6.60964 18.5726 6.78627 18.4146 6.75838 18.1264C6.60964 18.0242 6.60964 18.5633 6.44231 18.1543C6.42372 18.1264 6.38654 18.2937 6.38654 18.3867C6.28428 18.0892 6.12625 18.145 6.06117 17.8196C6.08906 17.9498 6.10765 18.0892 5.96821 18.0799C6.09836 17.9498 5.93103 17.7732 5.94032 17.6058L5.86596 17.6895C5.89384 17.5315 5.96821 17.5501 6.02399 17.5501C6.0054 17.5779 5.9961 17.6244 6.02399 17.6523C6.14484 17.6523 6.33076 17.2247 6.27498 17.0853C6.12625 17.0667 5.95892 17.327 5.91244 17.4478C5.83807 17.1782 5.44763 17.6802 5.40115 17.3548C5.36397 17.3084 5.55918 16.8529 5.50341 16.7134C5.25241 16.8064 5.48482 16.9923 5.27101 17.0667C5.56848 16.4345 4.68535 16.9551 4.78761 16.481L5.0479 16.3137C5.02001 16.2486 5.00142 16.1928 4.92705 16.1556L4.85268 16.3323C4.75972 16.3323 4.71324 16.1742 4.92705 16.0627C4.63887 16.1092 4.74113 15.9883 4.71324 15.8396C4.77831 15.9697 4.68535 15.8675 4.87127 15.8489C4.89916 15.6351 4.8062 15.6908 4.69465 15.6537C4.78761 15.5979 4.88987 15.4491 4.86198 15.4213C4.64817 15.4677 4.5738 15.3097 4.41577 15.2725L4.49013 15.2167C4.25773 15.1145 4.44365 14.6497 4.0904 14.6404C4.0904 14.6404 4.08111 14.6404 4.07181 14.6404V14.6683C3.88589 14.91 3.79293 14.6497 3.66278 14.6683C3.70926 14.6125 3.81152 14.5288 3.78363 14.4916C3.56982 14.659 3.6163 14.5102 3.49545 14.5567C3.52334 14.4359 3.76504 14.3615 3.67208 14.2685C3.6256 14.2407 3.50475 14.3243 3.42108 14.3894C3.51404 14.2778 3.55123 14.1477 3.53264 14.0733C3.60701 14.0454 3.55123 14.1384 3.57912 14.1384C3.69997 14.0547 3.6256 14.0547 3.77434 13.9432C3.75574 13.8781 3.55123 14.0826 3.57912 13.9618L3.79293 13.8874C3.82082 13.8316 3.71856 13.8502 3.69997 13.8502C3.77434 13.8502 3.94166 13.7201 4.04392 13.6364C3.81152 13.5899 3.56053 13.9618 3.36531 14.1012C3.3932 13.8595 3.08642 13.9246 2.99346 13.8223L3.21657 13.6922C3.1422 13.6643 3.07713 13.6736 2.97487 13.7201L2.9098 13.6364C3.02135 13.6364 3.09572 13.5992 3.26305 13.4784C3.1422 13.4319 3.10502 13.2832 2.81684 13.4598L2.86332 13.4319C2.87261 13.246 2.75177 12.9578 2.85402 12.902C2.6681 12.8462 2.71458 12.5674 2.4357 12.7626C2.31485 12.7347 2.64951 12.3164 2.26837 12.5116C2.38922 12.2885 2.34274 12.4558 2.56584 12.335C2.68669 12.1211 2.15682 12.3628 2.52866 12.0468C2.33344 12.0282 2.46359 12.1304 2.25907 12.2234C2.61232 11.9352 2.1847 11.991 2.32415 11.74C2.14752 11.8051 2.25907 11.8516 2.05456 11.8887C2.15682 11.833 2.13822 11.7772 2.13822 11.7493L1.89653 11.8887L2.39851 11.3868C2.01737 11.4332 2.01737 11.6935 1.77568 11.5727H1.80356C2.00808 11.3496 1.52468 11.5541 1.60835 11.2845C1.59905 11.3682 1.73849 11.2287 1.81286 11.2008L1.66412 11.1822C1.66412 11.1822 1.70131 11.1822 1.7199 11.1451C1.85005 10.9591 1.58046 11.1451 1.68272 10.9591C1.76638 10.987 1.93371 10.8476 2.00808 10.7639L1.66412 10.8197L2.01737 10.6524C1.97089 10.5222 1.33876 10.6803 1.75708 10.3363L1.84075 10.3642C1.91512 10.3084 2.13822 10.1318 1.92441 10.1597C1.86864 10.1597 1.66412 10.2619 1.70131 10.2898L1.73849 10.1876C1.97089 10.0853 2.11963 10.1876 2.23118 10.234C2.12893 10.2619 2.01737 10.234 1.89653 10.3456C2.01737 10.3828 2.2033 10.3642 2.32415 10.3921C2.22189 10.42 2.07315 10.485 1.98019 10.5222C1.92441 10.6803 2.16611 10.4943 2.23118 10.5408C2.16611 10.6245 2.11963 10.671 2.03597 10.6988C2.17541 10.7267 2.24048 10.7732 2.1847 10.9312C2.1847 10.9312 1.97089 10.9312 1.87793 11.0707C2.11034 11.1451 2.37992 11.0056 2.64021 11.0707C3.12361 11.0149 2.68669 11.5913 3.03065 11.5448C3.12361 11.489 3.12361 11.331 3.24446 11.3775C3.04924 11.4983 3.16079 11.5169 3.09572 11.5727C3.43038 11.4704 3.13291 11.7493 3.36531 11.6842C3.29094 11.7121 3.25375 11.8237 3.21657 11.898C2.98417 12.0561 3.19798 12.0654 2.77965 12.1676C3.22587 12.0561 2.87261 12.4837 3.47686 12.1955L3.51404 12.1118V12.3257V12.3164C3.51404 12.4 3.58841 12.3721 3.41179 12.6231C3.32812 12.6231 3.29094 12.5767 3.20727 12.5859C3.06783 12.8091 3.48616 12.6138 3.56053 12.6882C3.3932 12.8091 3.43968 12.6417 3.25375 12.8184C3.27235 12.8927 3.43038 12.8555 3.51404 12.8741L3.42108 12.9299C3.32812 13.2274 3.90448 12.651 3.68137 12.9857C3.72785 12.9392 3.80222 12.9113 3.8487 12.8648C3.78363 12.9764 3.69067 13.1902 3.50475 13.1809C3.54193 13.2274 3.66278 13.2274 3.78363 13.1809C3.88589 13.0415 3.81152 13.0786 3.96955 12.9299L4.22055 13.0601C4.22055 13.0601 4.11829 13.1065 4.0997 13.0786C3.80222 13.6829 4.87127 13.246 4.49943 13.9525C4.62028 13.813 4.64817 13.8688 4.75972 13.8223C4.77831 13.9432 4.91775 14.0454 4.88987 14.1942L4.76902 14.2499C5.0479 14.3615 5.31749 14.3801 5.36397 14.5567C5.41045 14.5288 5.22453 14.6683 5.16875 14.6683C5.42904 14.6218 4.94564 15.1981 5.35467 14.9193V14.8542C5.44763 15.1052 5.89384 15.0959 6.10765 15.2632C5.91244 15.4956 5.9868 15.1703 5.7544 15.4306C5.77299 15.6444 6.08906 15.6258 6.12625 15.8396C6.07977 15.8396 6.05188 15.8675 6.03328 15.8675C6.0054 16.1371 6.2471 15.663 6.32146 15.821C6.20061 15.9047 6.18202 15.9325 6.15413 16.0255L6.36794 15.9139C6.36794 15.9139 6.20061 16.0627 6.13554 16.0906C6.41442 15.9418 6.36794 16.2114 6.59105 16.0348C6.54457 16.0999 6.34006 16.2765 6.27498 16.3695C6.27498 16.4996 6.37724 16.4531 6.4795 16.3973C6.38654 16.6019 6.48879 16.6855 6.45161 16.6948C6.48879 16.89 6.56316 16.574 6.7212 16.481L6.73979 16.2951L6.86993 16.3509L6.75838 16.4438C6.74908 16.6112 6.92571 16.4252 6.96289 16.481L7.01867 16.2765C7.01867 16.2765 7.08374 16.2393 7.11163 16.2207C6.97219 16.6019 7.14882 16.388 6.96289 16.7971C7.03726 17.1596 7.24178 16.7041 7.32544 16.7506C7.30685 16.732 7.30685 16.8343 7.28826 16.9086C7.33474 17.0853 7.39981 16.8807 7.43699 16.6483C7.4184 16.7971 7.40911 16.8436 7.39051 16.9644C7.45559 17.0481 7.44629 16.7227 7.51136 16.6297C7.49277 16.8343 7.49277 16.9551 7.51136 17.0295C7.51136 16.8343 7.52996 16.7041 7.53925 16.6669C7.48347 17.6802 7.62292 17.2061 7.60432 18.0428C7.61362 17.8289 7.71588 17.4757 7.6508 16.9644V17.0295C7.62292 16.7134 7.6508 16.8621 7.6601 16.8529C7.6601 16.8993 7.6508 16.9551 7.6601 17.0202C7.68799 16.89 7.72517 16.9365 7.74377 16.9179C7.76236 16.8622 7.78095 16.8343 7.79025 16.7506C7.79025 16.7041 7.79954 16.6483 7.79954 16.574C7.81813 16.6948 7.82743 16.9458 7.85532 17.0016C7.94828 17.0016 7.88321 16.3695 7.85532 16.0627C8.03194 16.6205 7.82743 16.2579 7.96687 16.8436C8.01335 16.5368 8.03194 16.1928 7.96687 15.8582C8.15279 16.1649 8.1435 16.0534 8.11561 15.9418C8.08772 15.821 8.04124 15.7187 8.23646 15.8768C8.08772 15.7094 8.05983 15.6165 8.06913 15.5793C8.18998 15.7187 8.21787 15.6815 8.30153 15.7745C8.24575 15.6815 8.20857 15.6072 8.23646 15.5793C8.25505 15.57 8.39449 15.5142 8.55253 15.663C8.23646 15.3934 8.70126 15.4956 8.52464 15.2539C8.72915 15.2446 8.62689 14.975 8.83141 14.9286C8.59901 14.8077 8.8407 14.7241 8.79422 14.6125C8.79422 14.6404 8.79422 14.6869 8.83141 14.7055C9.02663 14.8077 8.80352 14.4359 8.97085 14.4545C9.06381 14.4824 9.13818 14.6218 9.20325 14.5846C9.06381 14.4638 9.07311 14.1384 9.29621 14.2221C9.26832 14.2499 9.3334 14.315 9.37058 14.3801C9.42636 13.8502 10.0213 13.7851 10.0585 13.2274L10.2165 13.497C10.6813 13.5899 9.98412 13.0136 10.17 12.8927C10.6906 12.5952 11.425 12.5209 11.6853 12.0003C11.6574 11.9073 11.5923 11.9352 11.4994 11.8423C11.5645 11.8423 11.7411 12.0189 11.6853 11.8516L11.5645 11.74C12.0479 11.898 11.8898 11.0242 12.5034 11.4146C12.5034 11.0614 12.931 11.2752 12.8752 10.7918C13.0425 10.8383 12.9868 11.0707 13.1076 11.0242L13.1355 10.6524V10.6803C13.0054 10.1411 14.0186 10.6245 14.0279 10.1504V10.1783C14.1023 10.2712 14.251 10.327 14.2603 10.2619C14.2231 10.1876 14.1674 10.1783 14.0744 10.1318C14.1581 9.79712 14.2045 9.74135 14.3533 9.56472C14.3905 9.75994 14.5206 9.6112 14.6879 9.78783C14.6322 9.62979 14.502 9.62979 14.5113 9.44387C14.6415 9.29513 14.911 9.33232 15.0784 9.29513C14.9854 9.09062 15.0877 9.08132 14.9203 8.88611C15.0691 8.72807 15.097 8.57004 15.2922 8.40271L15.3573 8.46778C15.1992 8.1796 15.6361 8.43989 15.5525 8.26327C15.6268 8.35623 15.6361 8.41201 15.7012 8.46778L15.7198 8.30975C15.7384 8.4213 15.9243 8.6723 16.0173 8.63511C15.9429 8.39341 15.8964 8.53285 15.8035 8.36552L16.0266 8.57004C16.0638 8.49567 15.85 8.22608 15.7198 8.21679C15.9243 8.04016 16.0266 7.76128 16.2311 7.64043L16.3426 7.80776C16.3891 7.66832 16.5286 7.54747 16.6959 7.63113C16.6587 7.58465 16.6122 7.4824 16.5565 7.44521C16.5007 7.13844 16.7796 7.67761 16.7238 7.35225C16.7424 7.43592 16.7238 7.50099 16.7982 7.59395L16.8818 7.20351C16.9841 7.31507 17.3466 7.43592 17.3559 7.24999C17.3094 7.18492 17.2072 7.12914 17.17 7.13844L17.1886 7.02689L17.4675 7.2407L17.3652 6.93393L17.5511 7.14774C17.579 7.04548 17.3745 6.73871 17.4396 6.71082C17.7742 6.66434 17.7928 6.77589 18.1182 6.85026C17.7742 6.42264 18.3692 6.66434 18.1554 6.32968C18.6202 6.46912 18.7503 6.03221 19.0943 5.89277V5.94854C19.3825 6.0415 18.9641 5.52092 19.1594 5.50233L19.178 5.58599C19.5219 5.67896 19.6242 5.24204 19.6242 4.93527C19.6428 5.01893 19.7729 5.13978 19.8101 5.0933C19.7822 4.98175 19.5219 4.83301 19.6706 4.84231C19.6799 4.89808 19.7822 4.98175 19.8008 4.96316L19.7078 4.68427C20.0425 4.64709 20.4236 4.58202 20.5445 4.26595C20.6467 4.30313 20.6839 4.40539 20.7304 4.48906C20.8698 4.29384 20.8977 3.96847 21.0279 3.80115L21.251 4.03355C21.3254 3.96847 20.9907 3.62452 21.2696 3.75466C21.3161 3.76396 21.2138 3.82903 21.2696 3.95918C21.5856 4.00566 21.1673 3.64311 21.3346 3.54085L21.5299 3.84763C21.7809 3.9127 21.5392 3.59663 21.4462 3.39212C21.3346 2.93661 22.004 3.81974 22.0226 3.39212C21.9482 3.22479 21.8459 3.2062 21.7623 3.03887C21.9761 2.98309 21.8366 2.76928 22.0504 2.7135C22.4781 3.04816 21.9668 2.77858 22.3851 3.08535H22.1899C22.4688 3.22479 22.1434 3.22479 22.3665 3.45719C22.506 3.45719 22.4502 3.15971 22.4781 2.99239C22.6361 3.17831 22.3758 3.11323 22.6361 3.31775V3.1969C22.6547 3.26197 22.7105 3.33634 22.6733 3.35493C22.8313 3.51297 22.7384 3.31775 22.7848 3.27127C22.7105 3.16901 22.5896 3.03887 22.4688 2.92731C22.4874 2.9459 22.506 2.9645 22.5338 2.98309C22.413 2.63913 22.7477 2.69491 22.664 2.41603C22.6919 2.4811 22.7198 2.4904 22.7569 2.52758C22.822 2.4904 22.6826 2.19292 22.7105 2.05348C22.8685 2.15574 23.0265 2.4811 23.0916 2.29518C22.9894 2.12785 22.7105 1.91404 22.822 1.82108C22.822 1.82108 22.822 2.02559 22.9708 2.09066L22.9801 2.12785ZM20.8327 4.54483C20.8327 4.54483 20.8048 4.57272 20.7862 4.60061C20.7862 4.60061 20.8141 4.55413 20.8234 4.54483H20.8327ZM20.7769 4.8702C20.7769 4.8702 20.749 4.77723 20.6839 4.71216C20.6467 4.74005 20.6188 4.76794 20.5817 4.78653C20.6653 4.81442 20.749 4.81442 20.7769 4.8702ZM22.1341 5.67896L22.1527 5.70684C22.1527 5.70684 22.1248 5.76262 22.1155 5.78121C22.1527 5.8184 22.1992 5.84628 22.2085 5.79051C22.1899 5.76262 22.162 5.71614 22.1341 5.67896Z\" fill=\"#8F3A7E\"><\/path><path d=\"M22.0416 5.47307C22.0416 5.47307 22.0416 5.45466 22.0416 5.44546C22.0231 5.43626 22.0047 5.42705 21.9863 5.41785L22.0231 5.49148L22.0416 5.47307Z\" fill=\"#8F3A7E\"><\/path><path d=\"M4.04395 14.6689C4.04395 14.6689 4.05317 14.6597 4.06239 14.6413C4.06239 14.6505 4.05317 14.6597 4.04395 14.6689Z\" fill=\"#8F3A7E\"><\/path><path d=\"M17.3184 6.90505L17.365 6.96105L17.3464 6.89572L17.3184 6.90505Z\" fill=\"#8F3A7E\"><\/path><path d=\"M3.82129 12.9043C3.82129 12.9043 3.84973 12.8664 3.85921 12.8474C3.84973 12.8569 3.83077 12.8759 3.82129 12.9043Z\" fill=\"#8F3A7E\"><\/path><path d=\"M3.47742 12.3441L3.49602 12.2139C3.47742 12.279 3.47742 12.3162 3.47742 12.3441Z\" fill=\"#8F3A7E\"><\/path><path d=\"M3.28078 11.8598C3.28078 11.8598 3.21608 11.8967 3.18835 11.9152L3.28078 11.8598Z\" fill=\"#8F3A7E\"><\/path><path d=\"M6.45996 16.4436C6.45996 16.4436 6.54407 16.3969 6.57211 16.3875C6.57211 16.3408 6.55342 16.3221 6.45996 16.4436Z\" fill=\"#8F3A7E\"><\/path><path d=\"M6.62872 16.4611C6.62872 16.3873 6.6195 16.3781 6.57336 16.3873C6.57336 16.4242 6.58259 16.4703 6.62872 16.4611Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.17539 10.0107V9.98242C2.17539 9.98242 2.14712 10.0013 2.1377 10.0013H2.17539V10.0107Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.12949 10.0114H2.0918C2.0918 10.0114 2.10122 10.0208 2.12949 10.0114Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.00806 9.99291H2.09124C2.09124 9.99291 2.07275 9.96519 2.00806 9.99291Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.41699 10.6243L2.50017 10.5781C2.50017 10.5781 2.45396 10.5966 2.41699 10.6243Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.55659 10.7733C2.55659 10.7177 2.65855 10.5601 2.57513 10.5416L2.51025 10.5787C2.64001 10.5231 2.39903 10.8289 2.55659 10.7733Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.07381 12.1401L2.0366 11.9541C1.97149 12.0378 1.88778 12.1494 1.82268 12.0936C1.70176 12.4471 1.9808 11.9262 2.08311 12.1401H2.07381Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.27776 12.6685C2.18469 12.622 2.15677 12.7523 2.11023 12.7895C2.22192 12.7895 2.24984 12.7895 2.27776 12.6685Z\" fill=\"#8F3A7E\"><\/path><path d=\"M4.62895 15.747L4.43384 15.8864C4.50817 15.9235 4.50817 15.8306 4.62895 15.747Z\" fill=\"#8F3A7E\"><\/path><path d=\"M6.05145 15.5506L6.11649 15.4112L5.93066 15.5134L6.05145 15.5506Z\" fill=\"#8F3A7E\"><\/path><path d=\"M5.00248 16.9545H4.95605C5.00248 16.9638 5.0489 16.973 5.10461 17.0009C5.05819 16.973 5.03962 16.973 5.00248 16.9545Z\" fill=\"#8F3A7E\"><\/path><path d=\"M10.2145 16.5729L9.97351 16.4061C9.98278 16.471 10.2423 16.6842 10.2145 16.5729Z\" fill=\"#8F3A7E\"><\/path><path d=\"M11.8059 14.4079C11.9267 14.4915 12.0475 14.5101 11.9824 14.3708C11.9267 14.3986 11.7966 14.3615 11.8059 14.4079Z\" fill=\"#8F3A7E\"><\/path><path d=\"M18.3037 9.16579L18.3223 9.2774L18.3502 9.14719L18.3037 9.16579Z\" fill=\"#8F3A7E\"><\/path><path d=\"M1.64564 9.73384C1.52494 9.65027 1.46923 9.91025 1.50637 9.71527C1.6085 9.67813 1.69207 9.65956 1.64564 9.73384Z\" fill=\"#8F3A7E\"><\/path><path d=\"M25.5929 1.03314C25.7137 1.86049 24.812 1.67457 24.7376 2.32529C24.7097 2.38107 24.4959 2.01852 24.4587 2.16726C24.4587 2.88306 23.6872 3.09687 22.9807 3.13405L22.9342 3.0318C22.804 3.0318 22.9342 3.40364 22.8133 3.44083C22.7669 3.38505 22.7761 3.33857 22.6925 3.28279C22.8133 3.46871 22.5995 3.4966 22.6646 3.64534C22.5716 3.60815 22.4694 3.46871 22.3578 3.43153L22.4694 3.66393C22.7111 4.23099 22.1068 3.91493 22.1161 4.30536C22.0882 4.24959 22.0789 4.2031 22.0232 4.17522C21.9488 4.70509 21.5305 4.97468 21.2795 5.36512C21.233 5.29075 21.14 5.15131 21.0564 5.09553C21.2051 5.30934 21.1493 5.44878 21.0936 5.56963C20.8797 5.393 21.0936 5.8857 20.8983 5.8671L20.8704 5.81133C20.9727 6.09021 20.6473 5.78344 20.8054 6.09951L20.6195 5.97866C20.8333 6.29472 20.3778 5.92288 20.4428 6.1274L20.4986 6.18317C20.4986 6.30402 20.3406 6.18317 20.3313 6.28543L20.2941 6.25754C20.229 6.44346 20.0152 6.3505 20.2104 6.57361C20.0059 6.43417 20.2662 6.37839 19.9687 6.18317C19.7363 6.78742 19.2436 7.12208 18.816 7.50322C18.6859 7.45674 18.6301 7.45674 18.5464 7.38237C18.5464 7.46603 18.4163 7.56829 18.4814 7.71703C18.4906 7.69843 18.3512 7.62407 18.3233 7.63336C18.1746 7.61477 18.4535 7.95872 18.2768 7.93084C18.2582 7.83788 18.2118 7.75421 18.1281 7.67984C18.2025 7.92154 18.0816 7.97732 18.0444 8.10746C18.0258 8.06098 18.0258 8.0145 17.9608 7.94943C18.0351 8.22831 17.747 8.06098 17.7749 8.2562L17.6912 8.09817C17.4216 8.06098 17.8864 8.40494 17.6912 8.41423C17.6912 8.34916 17.6261 8.30268 17.5889 8.2469C17.6819 8.58156 17.4402 8.65593 17.403 8.82326C17.403 8.79537 17.3658 8.76749 17.3658 8.76749C17.2729 8.89763 17.0869 8.93481 17.0498 9.14862C16.9475 9.13003 16.7895 8.82326 16.7058 8.98129C16.9382 9.23229 16.585 9.27877 16.9196 9.50188C16.7802 9.54836 16.5199 9.60413 16.5292 9.75287C16.492 9.61343 16.1945 9.48328 16.2689 9.38103L16.0644 9.28807C15.9807 9.17651 16.1666 9.26018 16.0272 9.14862C15.99 9.19511 15.9528 9.41821 15.8784 9.40891C15.9342 9.64132 16.1201 10.0039 16.0179 10.1526C15.99 9.99457 15.7297 9.90161 15.7297 9.81794L15.9807 10.478C15.9435 10.5337 15.7855 10.2827 15.7855 10.4036C15.8506 10.4687 15.8599 10.5337 15.8877 10.6081C15.8413 10.5895 15.7669 10.8312 15.5159 10.6081C15.4043 10.5244 15.5438 10.4873 15.4136 10.4408C15.3393 10.5151 15.4136 10.6081 15.33 10.6825L15.3021 10.6546C15.2184 10.6639 15.237 10.9056 15.4229 10.9892C15.4694 10.9614 15.2742 10.8498 15.3951 10.8777C15.488 11.0543 15.4322 11.1845 15.3579 11.2588C15.3579 11.1938 15.2835 11.1287 15.2277 11.045C15.3021 11.3425 15.237 11.5098 15.1905 11.6958C15.2928 11.8166 15.0418 11.4355 15.1162 11.4819C14.8094 11.4541 15.0139 12.0118 14.6607 11.8817C14.6607 11.8445 14.828 12.0397 14.7908 12.0118C14.7071 12.0676 14.5491 11.891 14.5584 11.9932C14.4654 11.891 14.5305 12.0769 14.5026 12.1606C14.5398 12.2535 14.4469 12.1234 14.4747 12.0676C14.4747 12.2163 14.3446 12.6254 14.0564 12.6254C14.1215 12.6904 14.1866 12.96 14.1401 12.9879L14.0099 12.8206C13.8891 12.7555 13.8984 12.9507 13.7682 12.8206C13.8612 13.0809 13.9263 12.3837 13.9542 12.6254C13.8054 12.5231 14.0378 13.0065 13.8612 12.7741C13.7961 12.8485 13.8798 13.0902 13.6753 13.0065C13.7218 13.0065 13.5358 12.7369 13.4894 12.802C13.4057 12.9228 13.5265 12.9042 13.4894 13.0344V13.1459C13.6288 13.304 13.3871 13.211 13.5823 13.3412C13.4522 13.2296 13.4986 13.555 13.2755 13.2947L13.1082 13.0809C13.0803 13.1366 13.2291 13.3598 13.2755 13.4806C13.257 13.4713 13.2012 13.4341 13.1733 13.4062C13.4429 13.713 13.0431 13.4806 13.2105 13.7688C13.0153 13.7502 12.9595 13.9826 12.7364 13.8339C12.7457 13.9919 12.7829 14.1592 12.6434 14.1778C12.6341 14.1313 12.6434 14.1034 12.5876 14.0384C12.4575 14.0012 12.5133 14.0848 12.5133 14.1778C12.4854 14.122 12.2437 14.1034 12.0856 14.0477C12.1042 14.2057 12.2809 14.3451 12.3645 14.4474C12.0206 14.215 12.3459 14.8285 12.0113 14.6333C11.9927 14.5682 11.9741 14.3916 11.8439 14.373C11.5 14.1406 11.9276 14.717 11.6859 14.6705L11.9462 14.8843C11.751 14.7821 11.9369 15.1725 11.7045 14.9122C11.7603 15.033 11.5093 14.9494 11.751 15.1725C11.3884 15.1446 11.4814 15.6838 10.9608 15.3863C10.9794 15.4514 10.8772 15.47 11.0166 15.5722C11.1839 15.6559 10.9701 15.4235 11.0817 15.4979C11.0724 15.5257 11.1281 15.5908 11.1653 15.628C11.0631 15.628 11.0073 15.6559 10.8493 15.4142C10.589 15.3956 11.1467 15.9162 10.9236 15.972C10.8307 15.8697 10.7749 15.8511 10.7563 15.9069L10.8586 16.1393C10.7377 16.1951 10.5797 15.9905 10.3938 15.8418C10.3752 15.9162 10.3101 15.9812 10.4309 16.1114L10.1521 15.9905C10.3566 16.0742 10.2264 16.1207 10.245 16.1858L10.2171 16.1207C10.1335 16.0649 10.1242 16.1672 10.1242 16.2229C10.245 16.3066 10.338 16.2787 10.4031 16.2694C10.4588 16.3624 10.4031 16.3903 10.4681 16.5018C10.3008 16.3438 10.2729 16.4832 10.2264 16.5111C10.1521 16.5297 10.3473 16.6878 10.3287 16.697C10.2357 16.6227 10.2543 16.7621 10.1521 16.6227C10.1335 16.5855 10.2729 16.6506 10.2078 16.5669C10.1149 16.5483 9.95684 16.4182 10.0219 16.5669C10.0684 16.6878 10.3845 16.8272 10.1985 16.8365C10.1706 16.7807 10.1056 16.7156 10.0498 16.6506L9.89177 16.6692L10.0591 16.7993C10.0126 16.7807 10.0033 16.7621 9.97543 16.7528C10.1428 16.8923 9.90106 16.9666 10.0591 17.1711C10.0219 17.2641 9.83599 17.2455 9.77092 17.3106V17.2827C9.62218 17.2827 9.61288 17.4686 9.65936 17.6638L9.63148 17.6267C9.63148 17.6267 9.53852 17.8033 9.585 18.0078C9.41767 18.0264 9.06442 17.3199 9.15738 17.7196C9.1016 17.8498 9.28752 18.3425 9.38978 18.4261C9.18526 18.5284 9.23174 19.3743 8.94357 19.207C8.97145 19.3743 9.00864 19.4208 8.99005 19.5974C8.77624 19.9228 8.70187 21.1313 8.42298 20.6851C8.44158 20.3783 8.35791 20.2482 8.31143 19.9972C8.33002 20.3597 8.26495 20.0158 8.26495 20.1087C8.26495 20.1366 8.27425 20.211 8.29284 20.3783C8.33002 20.6014 8.34862 20.7594 8.3765 20.8896C8.3951 20.9732 8.41369 21.029 8.45087 21.0383C8.45087 21.0941 8.43228 21.1406 8.42298 21.2057C8.36721 21.2428 8.30214 21.2149 8.22777 21.1499C8.19058 21.1127 8.16269 21.0662 8.12551 21.0197C8.08833 20.9454 8.05114 20.8524 8.03255 20.7687C8.08833 20.9732 8.06973 21.029 8.03255 21.0848C7.99536 20.5828 7.88381 20.3783 7.80015 20.4434V20.7316L7.72578 20.3597C7.69789 20.4155 7.70719 20.9268 7.60493 20.5363C7.60493 20.4248 7.58634 20.3039 7.57704 20.2017C7.49338 20.3318 7.33534 20.5363 7.24238 20.1831L7.17731 19.6997C7.17731 19.6997 7.03787 19.8298 7.11224 20.025C6.9542 19.5881 6.84265 19.4301 6.84265 19.0768C6.44292 19.4673 5.89445 18.863 5.55049 18.3796L5.63416 18.2681C5.60627 18.0357 5.44824 18.4168 5.42964 18.2495C5.5319 18.1751 5.5226 17.9241 5.68064 17.8684C5.64345 17.5988 5.38316 17.8684 5.25302 17.8126C5.12287 17.9427 5.39246 17.8126 5.23443 17.9706C5.17865 17.9985 5.14146 17.636 4.93695 17.8126C4.97413 17.6917 5.14147 17.5802 5.23443 17.5151H5.0671C5.20654 17.1897 5.66205 17.3478 5.82938 16.9387L5.74571 16.9016C5.89445 16.6413 6.09896 16.8272 6.04319 16.6041C5.90374 16.6413 5.55979 16.8458 5.5412 17.0038C5.35528 16.8923 5.00202 17.3664 4.85329 17.1433C4.92765 16.9852 5.02062 17.2827 5.15076 17.0968C5.23443 16.8551 4.91836 17.0038 4.93695 16.9016C4.90906 17.0317 4.64877 17.1433 4.5837 17.134C4.62088 16.9852 4.8161 17.0224 4.76032 16.9016C4.62088 16.9852 4.46285 16.9666 4.44426 17.1154C4.13749 17.3013 4.44426 16.948 4.17467 17.0689C4.342 16.883 4.70455 16.8086 4.71384 16.6227C4.53722 16.79 4.3513 16.6878 4.11889 16.9759C4.13749 16.8923 4.27693 16.7621 4.42567 16.7063C4.49074 16.5483 3.96086 16.8272 4.31411 16.5111L4.1096 16.6413C4.15608 16.5762 4.18397 16.5018 4.25834 16.3903C4.22115 16.3345 3.8586 16.4182 4.14678 16.1951C4.1003 16.1951 4.01664 16.0649 3.84931 16.2694C3.79353 16.4461 4.06312 16.2415 3.83072 16.5018C4.00734 16.2694 3.70987 16.4089 3.59831 16.4275L3.70057 16.3345C3.6355 16.3345 3.60761 16.2601 3.47746 16.3345C3.56113 16.3066 3.6262 16.2322 3.6355 16.1858L3.44028 16.288C3.26365 16.2415 3.71916 16.0277 3.58902 15.9534L3.78424 15.9255C3.78424 15.9255 3.8772 15.7674 3.78424 15.7581C3.60761 15.8604 3.3938 15.972 3.26365 16.0463C3.1521 16.0463 3.42169 15.879 3.20788 15.9441L3.45887 15.8697C3.52395 15.8418 3.67268 15.6094 3.60761 15.535C3.51465 15.535 3.22647 15.6187 3.19858 15.7674C3.1614 15.7303 3.21717 15.6001 3.35662 15.5443C3.22647 15.4979 3.19858 15.6838 3.04055 15.6838C3.11492 15.5722 3.18929 15.3491 3.29154 15.1725L3.61691 15.0516L3.57972 14.9959C3.84931 14.9029 3.70987 14.8378 3.96086 14.6984C3.96086 14.6333 3.8586 14.6519 3.77494 14.6519C3.50535 15.0423 3.18929 14.9029 2.89181 15.1911C2.6873 15.1074 3.60761 14.4846 2.97548 14.717C2.9104 14.8099 2.60363 14.9215 2.77096 14.9494C2.73378 14.8285 2.39912 15.1353 2.4456 14.9215C2.64082 14.9029 2.70589 14.5775 2.99407 14.5497C2.88252 14.624 2.96618 14.6798 3.01266 14.6705C3.10562 14.5404 3.34732 14.4288 3.27295 14.3265C3.19858 14.2894 3.12421 14.215 2.96618 14.3544C2.78026 14.5032 3.05914 14.4288 2.83603 14.5404C2.678 14.4753 2.94759 14.2336 2.58504 14.4381C2.6687 14.4939 2.49208 14.6612 2.36193 14.7542L2.2132 14.7263L2.35264 14.6519C2.33405 14.4474 2.09235 14.7821 2.02727 14.624L2.22249 14.373C2.45489 14.2429 2.27827 14.6426 2.60363 14.3544C2.54786 14.2522 2.35264 14.3544 2.38053 14.2057C2.42701 14.2057 2.45489 14.2243 2.49208 14.215C2.48278 14.1778 2.9104 13.7967 2.54786 13.871C2.39912 13.8896 2.40841 13.9454 2.27827 14.0384C2.12953 13.9268 1.9715 13.9826 1.87854 13.9082C2.14812 13.7409 1.78558 13.7316 2.12024 13.6386C2.00868 13.7967 2.17601 13.9919 2.45489 13.8617C2.71519 13.5829 2.50138 14.0012 2.82674 13.806C2.75237 13.6851 3.04984 13.4713 3.22647 13.304C3.21717 13.2668 3.11492 13.2947 3.06844 13.304C2.87322 13.4248 2.9104 13.462 2.72448 13.6107C2.678 13.4434 2.49208 13.3969 2.25968 13.462C2.31545 13.3505 2.51067 13.2296 2.56645 13.2668C2.39912 13.1552 2.30616 12.9786 2.25968 12.7927C2.02727 13.1088 2.07376 12.6811 1.86924 12.9321C1.85995 13.0623 1.69262 13.2854 1.52529 13.3412C1.50669 13.2761 1.65543 13.2482 1.71121 13.1831C1.4974 13.2389 1.90643 12.8949 1.59965 13.0251C1.79487 13.0995 1.99009 12.7834 2.24108 12.644C2.03657 12.644 2.40841 12.5231 2.34334 12.4301C2.13883 12.4301 1.94361 12.3744 1.81346 12.3C1.94361 12.0025 1.56247 11.9375 1.46951 11.8166C1.54388 11.6679 1.85065 11.5284 1.84135 11.4262C1.77628 11.3425 1.59036 11.6865 1.62754 11.4819L1.69262 11.4541C1.59965 11.4541 1.7205 11.1008 1.30218 11.3239L1.62754 11.1659C1.62754 11.1659 1.55317 11.1473 1.51599 11.1473C1.60895 11.0822 1.68332 10.9985 1.76698 10.9892C1.92502 10.7754 1.62754 10.8498 1.56247 10.7661L1.42303 10.9335C1.19063 10.8777 1.30218 10.6639 1.15344 10.5616L1.33007 10.4594L1.17203 10.4408C1.35796 10.3571 1.42303 10.2177 1.2464 10.2549L1.81346 10.2084C1.74839 10.3292 1.56247 10.2735 1.41373 10.4129C1.28359 10.5337 1.41373 10.6453 1.59036 10.5523C1.58106 10.4873 1.53458 10.5152 1.45092 10.5152C1.68332 10.3478 1.7205 10.4315 1.90643 10.3664C1.87854 10.3478 1.93431 10.2642 1.85065 10.3106C1.99939 10.2827 2.05516 10.3292 2.11094 10.4036C1.98079 10.4036 1.98079 10.5337 1.89713 10.5523C2.11094 10.4222 2.23179 10.4594 2.24108 10.5988C2.04587 10.8312 2.52926 10.6825 2.53856 10.8498C2.29686 10.9428 2.08305 10.9985 1.95291 10.98C1.89713 11.1287 2.01798 11.0636 1.95291 11.2124C2.13883 11.138 2.38982 11.0078 2.55715 11.0357L2.40841 11.1473C2.54786 11.1845 2.78026 11.0171 2.80815 11.1566C2.86392 11.3983 3.00336 11.5935 3.08703 11.7515L2.93829 11.8631C3.31943 11.705 3.25436 12.0397 3.47746 12.0397C3.46817 12.3279 3.91438 12.3279 3.71916 12.6161C4.07241 12.8485 4.39778 13.0437 4.593 13.4062L4.3327 13.5178C4.53722 13.4527 4.23974 13.6479 4.31411 13.6851C4.43496 13.4806 4.60229 13.5922 4.76962 13.5271C4.71384 13.806 5.03921 13.8524 5.2902 13.8617L5.14146 13.9826C5.5226 13.8896 5.40176 14.2429 5.48542 14.4381C5.43894 14.5032 5.31809 14.6426 5.37387 14.6798C5.68064 14.5775 5.69923 14.6333 5.95022 14.6426C6.02459 14.7356 6.08967 14.9308 6.07107 15.1074C6.37784 15.1446 6.55447 15.3026 6.7125 15.47C6.80546 15.5722 6.84265 15.6094 6.87983 15.6373C6.92631 15.6652 6.98209 15.6838 7.05646 15.6745L6.92631 15.8697C7.14942 15.7674 7.1866 15.7953 7.24238 15.8883C7.28886 15.972 7.34464 16.1114 7.40971 15.9998L7.32605 16.4925C7.34464 16.7063 7.4283 16.4646 7.4469 16.0649C7.46549 16.2694 7.51197 15.8604 7.53056 16.3624C7.56774 16.5111 7.56774 16.13 7.57704 16.0649C7.60493 16.2137 7.63282 16.288 7.65141 16.3066C7.67 16.3066 7.67 16.2137 7.67 16.13V16.1021C7.67 16.2508 7.70719 16.5297 7.72578 16.5483C7.72578 16.4739 7.72578 16.4554 7.72578 16.4368C7.73507 16.3996 7.74437 16.3438 7.6607 15.8976C7.70719 16.0742 7.71648 15.9441 7.71648 15.8511C7.71648 15.7581 7.71648 15.6931 7.80944 15.879C7.75367 15.7303 7.75367 15.6931 7.71648 15.5908C7.72578 15.5536 7.9024 15.7488 7.80015 15.5071C7.84663 15.5536 7.9117 15.7117 7.93959 15.7024C7.921 15.6466 7.84663 15.5536 7.80944 15.4793C7.76296 15.3491 7.80944 15.377 7.89311 15.3956C7.93959 15.4607 8.19988 15.2747 8.27425 15.1353C8.47876 14.4753 9.01793 14.057 9.39907 13.6015L9.46415 13.6665C9.35259 13.2761 10.0405 13.5829 9.78021 13.1088C9.87317 13.1366 9.93825 13.0158 10.0312 13.1645C9.96614 12.8857 10.496 13.0251 10.4402 12.6532C10.4216 12.6532 10.4216 12.6811 10.4402 12.7276C10.7377 12.7183 10.6912 12.3837 10.9887 12.3558C10.998 12.4023 10.9887 12.4487 11.0445 12.5231C11.2304 12.5882 10.9329 12.0955 11.2676 12.3837C11.3048 12.3465 11.1467 12.1977 11.1281 12.2256C11.6115 12.0118 11.8161 11.4355 12.1321 11.0078C12.5876 10.9428 12.6434 11.5377 12.6434 11.0915C12.7178 11.138 12.5412 10.9521 12.6062 11.0171C12.6062 10.8498 13.071 11.2588 12.9688 11.0357C12.7643 10.8591 12.9037 10.887 12.8014 10.7661C13.0896 10.7383 13.2848 10.887 13.2848 10.6174L13.3685 10.729C13.257 10.292 13.5823 10.2827 13.4057 9.81794C14.2237 8.972 14.8838 8.03309 15.7111 7.24293C16.6221 6.56431 17.3193 5.69048 18.3419 5.13271C18.7881 5.24427 18.7974 5.21638 18.9183 4.9189C18.9462 4.97468 18.9462 4.99327 18.9926 5.02116C18.8067 4.77946 19.1321 4.86313 18.9647 4.62143C19.3273 4.38903 19.569 4.07296 19.8944 3.79408C19.8665 3.85915 19.9966 4.07296 20.0431 4.00789L19.978 3.80337L20.0431 3.85915C20.0524 3.78478 20.0059 3.63604 19.8944 3.59886C20.5544 2.69714 21.7722 2.47403 22.5437 1.73034C22.8226 1.66527 23.0178 1.34921 23.1945 1.1168C24.0776 0.902993 24.8492 0.689183 25.3047 -0.0545044C25.3047 -0.0545044 25.723 0.62411 25.5836 0.977361L25.5929 1.03314Z\" fill=\"#8F3A7E\"><\/path><path d=\"M1.7481 9.85501C1.62739 9.95715 1.59954 10.0778 1.38599 10.115C1.50669 10.0314 1.61811 9.91072 1.7481 9.85501Z\" fill=\"#8F3A7E\"><\/path><path d=\"M1.8506 12.8295C1.8506 12.8295 1.82275 12.8945 1.80418 12.9131C1.77632 12.8945 1.65562 12.9409 1.70204 12.8759C1.7299 12.8945 1.78561 12.8481 1.8506 12.8202V12.8295Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.16678 13.4147C2.05536 13.489 1.87895 13.4425 1.82324 13.3775L2.16678 13.4147Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.08289 14.2437C2.02718 14.3551 1.96219 14.383 1.92505 14.318C1.98076 14.2715 2.02718 14.2715 2.08289 14.2437Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.35372 14.0857C2.35372 14.0857 2.33511 14.188 2.28857 14.2625C2.38165 14.188 2.15827 14.216 2.35372 14.0857Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.84607 15.3857C2.84607 15.3857 3.00391 15.3857 2.90178 15.5064C2.96677 15.4135 2.66966 15.4878 2.84607 15.3857Z\" fill=\"#8F3A7E\"><\/path><path d=\"M3.39329 15.7397C3.39329 15.7397 3.384 15.7861 3.43043 15.7769C3.40257 15.8418 3.30044 15.879 3.27258 15.8604L3.39329 15.7397Z\" fill=\"#8F3A7E\"><\/path><path d=\"M11.9369 14.7541L11.9462 14.8467L11.8535 14.7448L11.9369 14.7541Z\" fill=\"#8F3A7E\"><\/path><path d=\"M15.4611 11.4917C15.4611 11.3803 15.5818 11.5567 15.6003 11.5659C15.5632 11.6124 15.5075 11.4267 15.4611 11.4917Z\" fill=\"#8F3A7E\"><\/path><path d=\"M16.957 9.2601L16.9477 9.27864L16.7716 9.06546L16.957 9.2601Z\" fill=\"#8F3A7E\"><\/path><path d=\"M26.4111 1.45928C26.4761 1.32929 26.2068 1.32001 26.4111 1.32001C26.4668 1.41286 26.5039 1.49642 26.4111 1.45928Z\" fill=\"#8F3A7E\"><\/path><path d=\"M1.08847 10.4673C1.92512 10.4673 1.62764 11.3319 2.27837 11.4713C2.33415 11.4992 1.95301 11.6851 2.10174 11.7316C2.81754 11.7967 2.97558 12.5682 2.97558 13.2747L2.86402 13.3119C2.86402 13.4514 3.23587 13.3305 3.26375 13.4514C3.20798 13.4979 3.1615 13.4886 3.09642 13.5629C3.29164 13.4514 3.30094 13.6652 3.45897 13.6094C3.42179 13.6931 3.27305 13.7953 3.23587 13.9069L3.47756 13.8046C4.06322 13.5908 3.70997 14.1765 4.1097 14.1858C4.05392 14.2137 4.00744 14.2229 3.97026 14.2694C4.50013 14.3624 4.75113 14.79 5.13227 15.0596C5.0486 15.0968 4.91846 15.1897 4.85338 15.2734C5.07649 15.1247 5.20664 15.1897 5.32749 15.2548C5.15086 15.4686 5.64355 15.2548 5.61566 15.4593L5.55989 15.4872C5.84807 15.3943 5.532 15.7103 5.84807 15.5616L5.72722 15.7475C6.05258 15.543 5.66214 15.9892 5.86666 15.9334L5.92244 15.8777C6.04328 15.8777 5.92244 16.0357 6.0154 16.0543L5.98751 16.0915C6.17343 16.1658 6.06188 16.361 6.28498 16.1658C6.14554 16.3703 6.10836 16.1193 5.90384 16.4168C6.4895 16.6492 6.74049 17.049 7.08445 17.458C7.08445 17.6532 7.11233 17.7369 7.10304 17.8949C7.14952 17.8577 7.25178 17.9879 7.30755 17.8112C7.29826 17.8112 7.30755 18.0529 7.33544 18.0994C7.40051 18.3504 7.4284 17.6997 7.48418 17.9786C7.45629 18.0715 7.4377 18.2017 7.44699 18.3783C7.52136 18.1087 7.59573 18.2482 7.6608 18.211C7.6608 18.2853 7.64221 18.3132 7.64221 18.462C7.69799 18.118 7.80024 18.7316 7.84673 18.527V18.7966C7.99546 19.2893 7.82813 18.276 7.9025 18.3783C7.9025 18.5084 7.92109 18.6107 7.93039 18.7408C7.93039 18.3597 7.93969 18.2017 7.96757 18.0715C7.98617 17.9693 8.01406 17.8949 8.02335 17.7648C8.02335 17.8019 8.04194 17.8763 8.04194 17.8763C8.07913 17.6904 8.17209 17.6904 8.19068 17.3743C8.24646 17.4208 8.33942 17.9414 8.39519 17.7183C8.23716 17.2628 8.46027 17.3 8.23716 16.9188C8.31153 16.8909 8.46956 16.8537 8.45097 16.6771C8.49745 16.8537 8.72056 17.0211 8.68337 17.1605C8.73915 17.207 8.79493 17.2535 8.86 17.3C8.94366 17.458 8.77633 17.3464 8.90648 17.5045C8.93437 17.4208 8.94366 17.1047 9.00874 17.1047C8.93437 16.8073 8.72985 16.4261 8.76704 16.2774C8.82282 16.4354 9.06451 16.5098 9.08311 16.5935C8.97155 16.3703 8.84141 16.1658 8.70197 15.9892C8.71126 15.9427 8.92507 16.1472 8.89718 16.0264C8.82281 15.9799 8.79493 15.9148 8.75774 15.8498C8.80422 15.8498 8.8507 15.5895 9.12959 15.7754C9.25043 15.8405 9.12959 15.8962 9.25973 15.9148C9.3248 15.8219 9.24114 15.7475 9.29692 15.6545L9.3341 15.6824C9.41776 15.6545 9.36199 15.4221 9.16677 15.3664C9.12029 15.4036 9.3341 15.4779 9.21325 15.4779C9.0924 15.3106 9.13888 15.1711 9.21325 15.0875C9.23184 15.1526 9.30621 15.2083 9.36199 15.2827C9.25043 14.9945 9.29692 14.8179 9.3341 14.6134C9.21325 14.5018 9.51073 14.8551 9.42706 14.8179C9.73383 14.7993 9.49213 14.2694 9.86398 14.3531C9.86398 14.3903 9.68735 14.2044 9.72454 14.2415C9.8082 14.1765 9.97553 14.3438 9.96623 14.2415C10.0685 14.3345 9.99412 14.1486 10.0127 14.0742C9.96623 13.9812 10.0778 14.1114 10.0406 14.1579C10.022 14.0091 10.1522 13.5815 10.4496 13.5629C10.3846 13.4979 10.3102 13.2283 10.3567 13.2004L10.4868 13.3677C10.6077 13.4235 10.5984 13.2376 10.7285 13.3584C10.6263 13.0981 10.5798 13.8139 10.5426 13.5629C10.6913 13.6652 10.4496 13.1725 10.6356 13.4049C10.7006 13.3305 10.6077 13.0888 10.8215 13.1632C10.775 13.1632 10.9609 13.4328 11.0167 13.3677C11.0911 13.2376 10.9795 13.2655 11.0167 13.1353V13.0238C10.868 12.8657 11.1282 12.9587 10.9237 12.8192C11.0539 12.9308 11.0074 12.5961 11.2305 12.8564L11.3978 13.0702C11.4257 13.0145 11.277 12.7913 11.2305 12.6705C11.2584 12.6798 11.3049 12.7077 11.3328 12.7449C11.0539 12.4381 11.4629 12.6705 11.3049 12.3823C11.5001 12.4009 11.5559 12.1685 11.779 12.308C11.7697 12.1499 11.7325 11.9733 11.8812 11.964C11.8905 12.0105 11.8812 12.0384 11.9277 12.1034C12.0671 12.1406 12.0021 12.0477 12.0021 11.9547C12.03 12.0105 12.2717 12.0384 12.4297 12.0848C12.4204 11.9268 12.2438 11.7874 12.1601 11.6758C12.5041 11.9175 12.188 11.2947 12.5227 11.4899C12.532 11.555 12.5505 11.7316 12.6807 11.7595C13.0246 12.0012 12.6156 11.4155 12.8573 11.462L12.597 11.2389C12.7829 11.3505 12.6249 10.9507 12.848 11.211C12.8015 11.0902 13.0525 11.1738 12.8201 10.9414C13.1827 10.9879 13.1455 10.4208 13.6475 10.7555C13.6382 10.6904 13.7404 10.6718 13.6103 10.5603C13.443 10.458 13.6382 10.709 13.5359 10.6347C13.5545 10.6068 13.4987 10.5324 13.4709 10.4952C13.5731 10.4952 13.6382 10.4766 13.7683 10.7276C14.0286 10.7648 13.5173 10.1977 13.7683 10.1513C13.852 10.2628 13.8985 10.2907 13.9357 10.2256L13.8706 9.97463C14.01 9.91886 14.1402 10.1513 14.2982 10.3279C14.3261 10.2535 14.4005 10.1977 14.3075 10.049L14.5678 10.207C14.3819 10.0955 14.5213 10.0583 14.5027 9.99323V10.0583C14.5864 10.1234 14.6143 10.0211 14.6236 9.97463C14.5213 9.87238 14.4191 9.89097 14.354 9.89097C14.3168 9.78871 14.3726 9.77012 14.3261 9.64927C14.4655 9.8259 14.5213 9.68646 14.5864 9.66786C14.6701 9.66786 14.5027 9.46335 14.5306 9.45405C14.6143 9.53772 14.6236 9.39828 14.6979 9.55631C14.6979 9.60279 14.5864 9.50983 14.6236 9.61209C14.7165 9.64927 14.8467 9.8073 14.8188 9.63068C14.7909 9.50053 14.5027 9.30532 14.6979 9.32391C14.7072 9.38898 14.763 9.46335 14.8002 9.53772H14.9675L14.8374 9.38898C14.8839 9.41687 14.8839 9.43546 14.9118 9.45405C14.7909 9.26813 15.0047 9.27743 14.8653 9.08221C14.8932 9.02643 15.0605 9.1008 15.1163 9.08221V9.1008C15.2557 9.14728 15.2743 9.01714 15.2278 8.8777L15.2557 8.91488C15.2557 8.91488 15.3487 8.81262 15.3022 8.69177C15.4788 8.73826 15.8414 9.25884 15.7577 8.98925C15.8321 8.91488 15.6276 8.59881 15.5067 8.52444C15.7391 8.50585 15.6647 8.11542 16.0087 8.24556C15.9715 8.1619 15.925 8.13401 15.9343 8.06894C16.1853 7.95738 16.1946 7.51117 16.6222 7.6785C16.6222 7.79935 16.7524 7.83653 16.836 7.92949C16.7617 7.74357 17.022 8.02246 16.836 7.77146C16.7059 7.63202 16.6501 7.55765 16.5479 7.55765C16.6036 7.38103 16.7803 7.22299 16.9662 7.29736C16.8732 7.26018 16.8639 7.1951 16.8546 7.13003C17.0406 7.36243 17.1614 7.31595 17.1614 7.18581L17.0499 7.03707L17.2172 7.13933C17.2079 7.07425 16.9941 6.82326 17.18 6.89763C17.2265 6.94411 17.2823 6.99989 17.3287 7.02777C17.3008 6.85115 17.2358 6.58156 17.4124 6.62804L17.6448 6.77678C17.6541 6.7303 17.6076 6.56297 17.5054 6.55367C17.7378 6.56297 17.8307 6.50719 18.0259 6.64664C17.8772 6.03309 18.1933 5.73562 18.4722 5.5497L18.5558 5.66125C18.7046 5.69843 18.435 5.44744 18.5558 5.47533C18.6209 5.59618 18.7882 5.64266 18.844 5.80999C19.0392 5.83788 18.8161 5.52181 18.844 5.41955C18.7417 5.27081 18.8626 5.5497 18.7324 5.36377C18.7046 5.308 18.9648 5.35448 18.7975 5.13137C18.8905 5.18715 19.002 5.35448 19.0578 5.45674L19.0299 5.308C19.3088 5.48462 19.2251 5.88436 19.5598 6.10746L19.5877 6.0238C19.8201 6.19113 19.6435 6.39564 19.848 6.34916C19.8201 6.20042 19.6156 5.85647 19.4854 5.80999C19.5598 5.64266 19.1229 5.27081 19.2809 5.16856C19.4204 5.26152 19.1972 5.28941 19.3646 5.43814C19.5691 5.5497 19.4111 5.23363 19.5226 5.24293C19.3925 5.21504 19.2716 4.96404 19.2809 4.88967C19.4297 4.92686 19.4018 5.12208 19.5133 5.057C19.4297 4.92686 19.4389 4.75953 19.2902 4.74094C19.095 4.44346 19.4575 4.73164 19.3367 4.47135C19.5319 4.62938 19.6063 4.99193 19.8015 5.00123C19.6249 4.8339 19.7271 4.63868 19.4389 4.41557C19.5226 4.43417 19.6528 4.57361 19.7178 4.71305C19.8759 4.77812 19.5784 4.25754 19.913 4.6015L19.7736 4.39698C19.848 4.44346 19.913 4.46205 20.0246 4.53642C20.0804 4.48994 19.9781 4.13669 20.2198 4.42487C20.2198 4.37839 20.3407 4.29472 20.1362 4.13669C19.9595 4.08091 20.1733 4.3505 19.9038 4.12739C20.1362 4.29472 19.9874 4.00655 19.9688 3.89499L20.0711 3.99725C20.0618 3.93218 20.1455 3.90429 20.0618 3.77414C20.099 3.85781 20.164 3.92288 20.2105 3.93218L20.099 3.74626C20.1362 3.56963 20.3686 4.01584 20.4336 3.8857L20.4615 4.08091C20.4615 4.08091 20.6196 4.16458 20.6288 4.07162C20.5266 3.90429 20.3964 3.69048 20.3221 3.56033C20.3221 3.44878 20.4894 3.70907 20.415 3.50456L20.4987 3.75555C20.5266 3.81133 20.759 3.96007 20.8334 3.89499C20.8334 3.80203 20.7311 3.51385 20.5824 3.49526C20.6196 3.45808 20.7497 3.50456 20.8148 3.644C20.8612 3.51385 20.666 3.48596 20.666 3.32793C20.7869 3.4023 21.0007 3.46737 21.1866 3.56033L21.3168 3.8857L21.3725 3.83922C21.4748 4.09951 21.5399 3.96936 21.6793 4.21106C21.7444 4.21106 21.7258 4.1088 21.7165 4.01584C21.3168 3.76485 21.4376 3.44878 21.1401 3.1606C21.2145 2.95609 21.8745 3.84851 21.6142 3.22567C21.5213 3.1606 21.3911 2.86313 21.3725 3.03046C21.4934 2.99327 21.168 2.66791 21.3818 2.70509C21.4097 2.90031 21.7351 2.95609 21.7816 3.23497C21.6979 3.12342 21.6514 3.20708 21.6607 3.25356C21.8002 3.34652 21.921 3.57893 22.014 3.49526C22.0419 3.42089 22.1162 3.34652 21.9675 3.18849C21.8095 3.01186 21.8931 3.28145 21.7816 3.06764C21.8373 2.90961 22.0883 3.1699 21.8652 2.80735C21.8187 2.89101 21.6421 2.72369 21.5399 2.59354L21.5585 2.4448L21.6421 2.57495C21.8466 2.54706 21.5027 2.32395 21.6514 2.24958L21.9117 2.43551C22.0511 2.66791 21.6514 2.50058 21.9489 2.81665C22.0419 2.76087 21.9303 2.56565 22.079 2.58424C22.079 2.63072 22.0697 2.65861 22.079 2.6958C22.1162 2.6772 22.516 3.09553 22.423 2.74228C22.4044 2.59354 22.3393 2.61213 22.2371 2.48199C22.3393 2.33325 22.2743 2.17522 22.3393 2.08226C22.5253 2.34255 22.5067 1.98 22.6275 2.30536C22.4602 2.2031 22.2836 2.37973 22.4323 2.64932C22.7205 2.89101 22.2928 2.6958 22.5067 3.01186C22.6182 2.9282 22.8506 3.21638 23.0272 3.38371C23.0644 3.37441 23.0272 3.27215 23.0272 3.22567C22.8971 3.03975 22.8599 3.07694 22.7019 2.90031C22.8599 2.84453 22.8971 2.64932 22.8227 2.42621C22.9343 2.48199 23.0644 2.66791 23.0365 2.72369C23.1388 2.55636 23.3061 2.4448 23.4827 2.38903C23.1574 2.17522 23.5757 2.19381 23.3247 2.00789C23.1946 2.00789 22.9715 1.84985 22.8971 1.69182C22.9622 1.67323 22.9994 1.82196 23.0737 1.85915C22.9994 1.65464 23.3712 2.03577 23.2225 1.7383C23.1667 1.94281 23.4827 2.11014 23.6501 2.35184C23.6408 2.14733 23.7802 2.50988 23.8732 2.43551C23.8639 2.23099 23.8918 2.03577 23.9568 1.90563C24.2636 2.00789 24.2915 1.63604 24.4031 1.52449C24.5611 1.58956 24.7284 1.87774 24.8307 1.85915C24.905 1.78478 24.5425 1.63604 24.7563 1.65464L24.7842 1.71041C24.7656 1.62675 25.1375 1.71041 24.8679 1.31068L25.0631 1.61745C25.0631 1.61745 25.0724 1.54308 25.0631 1.5059C25.1374 1.58956 25.2304 1.65464 25.2397 1.7383C25.4721 1.86845 25.3606 1.58027 25.4349 1.51519L25.249 1.39434C25.2769 1.15265 25.5 1.24561 25.5744 1.07828L25.7045 1.23631V1.07828C25.8068 1.24561 25.9648 1.29209 25.8997 1.12476L26.0299 1.67323C25.8997 1.62675 25.9276 1.43153 25.7696 1.30138C25.6301 1.18983 25.5465 1.32927 25.6487 1.4966C25.7045 1.47801 25.6859 1.44083 25.6673 1.35716C25.8625 1.56167 25.7882 1.61745 25.8811 1.78478C25.8997 1.75689 25.9834 1.79408 25.9369 1.71971C25.9834 1.86845 25.9462 1.92422 25.8718 1.98929C25.8532 1.85915 25.7324 1.87774 25.6952 1.79408C25.8532 1.98929 25.8254 2.11014 25.6859 2.13803C25.4349 1.9707 25.6301 2.43551 25.4628 2.46339C25.342 2.23099 25.2676 2.02648 25.2676 1.88704C25.1189 1.84985 25.1932 1.96141 25.0445 1.91493C25.1375 2.09155 25.2955 2.33325 25.2769 2.50058L25.1467 2.36114C25.1282 2.50058 25.3048 2.71439 25.1653 2.77017C24.9236 2.84453 24.7377 3.00257 24.589 3.09553L24.4588 2.95609C24.6448 3.32793 24.3008 3.28145 24.3101 3.50456C24.0219 3.50456 24.0498 3.96007 23.7523 3.78344C23.5385 4.15528 23.3619 4.48994 22.9994 4.70375L22.8785 4.45276C22.9529 4.65727 22.7391 4.3598 22.7112 4.44346C22.9157 4.55502 22.8134 4.72234 22.8878 4.88967C22.6089 4.84319 22.581 5.17785 22.5717 5.42885L22.4416 5.28941C22.5438 5.67055 22.1906 5.55899 21.9954 5.64266C21.9303 5.59618 21.7816 5.48462 21.7537 5.5404C21.8652 5.84717 21.8095 5.86576 21.8002 6.11676C21.7072 6.19113 21.512 6.2655 21.3446 6.2469C21.2796 6.86974 20.7497 6.95341 20.5638 7.4554L20.3964 7.30666C20.3593 7.95738 19.6528 7.99457 19.5226 8.44078L19.2995 8.12471C19.1322 8.12471 19.1508 8.385 19.3553 8.56163C19.188 8.56163 19.2437 8.89629 18.9834 8.71037C18.844 8.73825 18.9834 8.94277 18.937 9.04503C18.6581 9.1008 18.6023 9.18447 18.4722 9.38898L18.5279 9.37039C18.4907 9.28672 18.3885 9.16588 18.3327 9.18447C18.3327 9.32391 18.0259 9.31461 18.3885 9.60279C18.0259 9.56561 18.091 10.1513 17.6727 10.0397C17.7657 10.1234 17.7378 10.1791 17.7749 10.2535C17.6169 10.4023 17.273 10.3651 17.2823 10.644C17.2172 10.6161 17.1893 10.4487 17.1056 10.4952C17.1056 10.5696 17.2079 10.6161 17.2079 10.709C17.0963 11.1181 16.5107 11.0065 16.3062 11.2668C16.0366 11.8246 15.5067 12.1406 15.1349 12.5404L15.0791 12.466C15.172 12.8471 14.5213 12.4939 14.763 12.9773C14.6701 12.9401 14.6143 13.0609 14.5213 12.9122C14.5771 13.1911 14.0658 13.0238 14.1123 13.3956C14.1309 13.3956 14.1309 13.3677 14.1123 13.3212C13.8148 13.3212 13.8706 13.6466 13.5731 13.6745C13.5638 13.628 13.5731 13.5815 13.5173 13.5071C13.3314 13.4421 13.6289 13.9255 13.2942 13.6373C13.257 13.6745 13.4151 13.8232 13.4337 13.7953C12.9503 14.0091 12.7551 14.5762 12.4669 14.9945C12.03 15.0596 11.937 14.4832 11.9649 14.9109C11.8905 14.8644 12.0671 15.041 12.0021 14.9759C12.0021 15.134 11.5373 14.7528 11.6488 14.9666C11.8626 15.134 11.7232 15.1061 11.8347 15.2269C11.5559 15.2548 11.3514 15.1247 11.3792 15.385L11.2863 15.2734C11.435 15.6917 11.1282 15.7196 11.3606 16.1472C11.2026 16.361 11.0539 16.5749 10.9237 16.7887L10.4403 17.6625C9.91975 18.5456 9.60369 20.0423 9.12029 21.4367C8.99014 21.7993 8.8507 22.1618 8.72056 22.5151L8.33942 22.0874L7.89321 21.5762L7.00078 20.5536C6.41513 19.8657 5.80159 19.1127 5.281 18.3225C5.20664 17.6439 5.20664 17.6625 4.77902 17.3743C4.83479 17.3464 4.86268 17.365 4.89057 17.3C4.76972 17.3929 4.70465 17.3185 4.64887 17.2628C4.61169 17.2256 4.5745 17.1791 4.45365 17.2628C4.23055 16.9002 3.92378 16.6399 3.64489 16.296C3.70997 16.3332 3.93307 16.203 3.868 16.1472L3.66349 16.203L3.71926 16.1379C3.64489 16.1193 3.49616 16.1658 3.44968 16.2774C2.55725 15.5709 2.37133 14.3345 1.66483 13.5071C1.60905 13.219 1.30228 12.9959 1.08847 12.8006C0.930435 11.8617 0.790994 11.0902 0.0751953 10.4116C0.0751953 10.4116 0.828178 10.1513 1.16284 10.3558L1.08847 10.4673Z\" fill=\"#8F3A7E\"><\/path><path d=\"M26.3094 1.58132C26.1885 1.47901 26.0676 1.47901 25.9932 1.27438C26.0955 1.3767 26.235 1.46971 26.3094 1.58132Z\" fill=\"#8F3A7E\"><\/path><path d=\"M23.3623 1.9979C23.3623 1.9979 23.2973 1.97005 23.2695 1.96076C23.288 1.93291 23.223 1.8122 23.2973 1.85863C23.2787 1.88648 23.3345 1.94219 23.3623 1.9979Z\" fill=\"#8F3A7E\"><\/path><path d=\"M22.8039 2.34232C22.7203 2.2309 22.7574 2.06377 22.8131 1.99878V2.34232H22.8039Z\" fill=\"#8F3A7E\"><\/path><path d=\"M21.9853 2.29645C21.8739 2.24074 21.846 2.18504 21.9018 2.13861C21.9482 2.19432 21.9575 2.23146 21.9853 2.29645Z\" fill=\"#8F3A7E\"><\/path><path d=\"M22.1544 2.56585C22.1544 2.56585 22.052 2.55654 21.9775 2.51001C22.052 2.59377 22.0241 2.37971 22.1544 2.56585Z\" fill=\"#8F3A7E\"><\/path><path d=\"M20.8979 3.10465C20.8979 3.10465 20.8979 3.26249 20.7772 3.16965C20.8701 3.22535 20.7772 2.93752 20.8979 3.10465Z\" fill=\"#8F3A7E\"><\/path><path d=\"M20.5632 3.65382C20.5632 3.65382 20.5168 3.65382 20.5261 3.69096C20.4611 3.6631 20.424 3.57025 20.4425 3.53311L20.5632 3.65382Z\" fill=\"#8F3A7E\"><\/path><path d=\"M12.5693 11.3684V11.275L12.6534 11.3871L12.5693 11.3684Z\" fill=\"#8F3A7E\"><\/path><path d=\"M9.03711 14.8652C9.05568 14.9767 8.90712 14.8188 8.88855 14.8188C8.9164 14.7631 8.99997 14.9488 9.03711 14.8652Z\" fill=\"#8F3A7E\"><\/path><path d=\"M8.21887 17.2635V17.2357L8.33029 17.5885L8.21887 17.2635Z\" fill=\"#8F3A7E\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Instant 2290 Schedule 1<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"27\" height=\"23\" viewBox=\"0 0 27 23\" fill=\"none\"><path d=\"M26.5504 1.48711C26.5133 1.41296 26.3928 1.2832 26.3743 1.33881L26.5411 1.59833V1.48711H26.5504Z\" fill=\"#8F3A7E\"><\/path><path d=\"M25.9092 1.28207C25.9556 1.43991 26.067 1.68132 26.2806 1.8763C26.1413 1.60704 26.2342 1.69061 26.0577 1.3842C26.0763 1.31921 26.197 1.40277 26.262 1.49562C26.2249 1.42134 26.3734 1.49562 26.262 1.32849C26.0577 1.18922 25.9835 1.23565 26.0392 1.4492C25.9835 1.41206 25.9463 1.33778 25.9092 1.29136V1.28207Z\" fill=\"#8F3A7E\"><\/path><path d=\"M19.0215 6.23586C19.0215 6.23586 19.0215 6.18064 19.0031 6.16223C19.0031 6.18984 19.0031 6.21746 19.0215 6.23586Z\" fill=\"#8F3A7E\"><\/path><path d=\"M18.3794 6.34023C18.3794 6.34023 18.4077 6.34023 18.4171 6.34023C18.3888 6.3308 18.37 6.32138 18.3794 6.34023Z\" fill=\"#8F3A7E\"><\/path><path d=\"M21.5952 4.26723L21.465 4.24863C21.5208 4.33234 21.5487 4.27653 21.5952 4.26723Z\" fill=\"#8F3A7E\"><\/path><path d=\"M25.8363 2.31298C25.8363 2.31298 25.8363 2.25752 25.8178 2.22055C25.8178 2.23904 25.8178 2.25752 25.8086 2.27601L25.8363 2.31298Z\" fill=\"#8F3A7E\"><\/path><path d=\"M22.5358 3.16046L22.5544 3.14186C22.5544 3.14186 22.5172 3.07675 22.4893 3.03024L22.5358 3.16046Z\" fill=\"#8F3A7E\"><\/path><path d=\"M23.3447 2.4166C23.3447 2.4166 23.4749 2.63052 23.5493 2.72353C23.4935 2.63052 23.4749 2.58401 23.4749 2.54681C23.447 2.50961 23.4005 2.4631 23.3447 2.4166Z\" fill=\"#8F3A7E\"><\/path><path d=\"M21.8932 3.61673C21.8932 3.61673 21.8372 3.56072 21.8279 3.55139C21.8465 3.57939 21.8745 3.59806 21.8932 3.61673Z\" fill=\"#8F3A7E\"><\/path><path d=\"M0.799326 11.6575C0.799326 11.6575 0.827596 11.6386 0.837019 11.6292C0.808749 11.6292 0.789903 11.648 0.799326 11.6575Z\" fill=\"#8F3A7E\"><\/path><path d=\"M1.21851 9.87102L1.24636 9.8803L1.37635 9.81531L1.21851 9.87102Z\" fill=\"#8F3A7E\"><\/path><path d=\"M10.5801 13.1525C10.8215 13.2453 10.6636 13.4868 10.9608 13.561C10.8772 13.496 10.7843 13.1711 10.5801 13.1525Z\" fill=\"#8F3A7E\"><\/path><path d=\"M25.7896 2.30579C25.7896 2.30579 25.7708 2.32463 25.752 2.33406C25.7708 2.33406 25.7802 2.31521 25.7896 2.30579Z\" fill=\"#8F3A7E\"><\/path><path d=\"M15.7295 8.4028C15.7295 8.4028 15.7942 8.45826 15.8219 8.47674C15.8034 8.45826 15.7757 8.43977 15.7295 8.4028Z\" fill=\"#8F3A7E\"><\/path><path d=\"M15.2939 9.27798C15.2939 9.27798 15.2285 9.25931 15.2285 9.30598C15.2378 9.30598 15.2472 9.31531 15.2565 9.32465C15.2378 9.28731 15.2379 9.26865 15.2939 9.27798Z\" fill=\"#8F3A7E\"><\/path><path d=\"M14.5957 9.90973C14.5957 9.90973 14.6241 9.92869 14.6431 9.93817V9.90973H14.5957Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.6049 13.9609C2.65136 13.8959 2.7071 13.8401 2.76285 13.7844C2.62348 13.9051 2.48412 13.8401 2.6049 13.9609Z\" fill=\"#8F3A7E\"><\/path><path d=\"M25.7432 2.19324C25.7802 2.24883 25.7988 2.27662 25.7895 2.29515L25.808 2.26736C25.808 2.26736 25.7617 2.21177 25.7432 2.19324Z\" fill=\"#8F3A7E\"><\/path><path d=\"M16.6315 10.8466L16.4922 10.9116C16.5386 10.9116 16.585 10.8745 16.6315 10.8466Z\" fill=\"#8F3A7E\"><\/path><path d=\"M7.79133 20.2916H7.76367C7.76367 20.2916 7.79133 20.3285 7.79133 20.2916Z\" fill=\"#8F3A7E\"><\/path><path d=\"M16.1947 11.2389C16.1111 11.1924 16.0554 11.1645 16.0089 11.1552C16.0089 11.1738 16.0275 11.1924 16.0368 11.2203L16.1854 11.2389H16.1947Z\" fill=\"#8F3A7E\"><\/path><path d=\"M1.95357 13.227C1.75835 13.1898 1.98146 13.1526 2.08371 12.9109C1.81413 13.0132 2.08371 12.7343 1.70258 12.9946C1.91639 12.7808 1.83272 12.8551 1.96287 12.6599C1.78624 12.8366 1.66539 12.6599 1.42369 12.8458C1.67469 12.6227 1.85131 12.725 2.06512 12.4275C1.83272 12.4926 1.68398 12.4275 1.37721 12.6227C1.4051 12.5205 1.49806 12.4275 1.47947 12.3253C1.47017 12.3532 1.53525 12.3253 1.57243 12.316C1.27496 12.316 1.33073 11.972 0.912408 12.1393C1.36792 11.8698 0.76367 11.7954 1.23777 11.6281C1.18199 11.5816 0.931 11.6095 0.838039 11.6374C1.18199 11.4143 0.828743 11.4328 0.986776 11.2283C0.772966 11.3213 0.76367 11.1633 0.614933 11.1726C0.680005 11.1726 0.745078 11.154 0.828743 11.0889C0.642821 11.0982 0.782262 11.0331 0.912408 10.8658C0.745078 10.8286 0.661413 11.0517 0.456899 11.0889C0.475491 10.9494 0.670709 10.9401 0.800854 10.8379L0.363938 10.9216C0.38253 10.8751 0.438307 10.81 0.531268 10.7449C0.401123 10.7542 0.224497 10.8007 0.354642 10.6334L0.438307 10.7449L0.59634 10.5962H0.280273C0.429011 10.2244 0.856631 10.0849 1.24707 9.88969L1.35862 9.92688C1.48877 9.85251 1.53525 9.75955 1.51665 9.72236C1.59102 9.64799 2.00005 9.61081 2.08371 9.65729C2.17668 9.8804 1.67469 9.95476 1.66539 10.1593L2.00005 10.2151L1.8792 10.2987C1.81413 10.3824 1.96287 10.3173 2.00005 10.2987C1.80483 10.401 2.03723 10.4939 2.05583 10.5869L2.19527 10.4568C2.70655 10.4196 2.01864 11.0517 2.33471 11.0982L2.67866 11.0331L2.46485 11.219C2.65078 11.1911 2.8367 11.0796 2.8367 11.2469C2.70655 11.9255 3.50602 11.9999 3.5525 12.5763C3.59898 12.5391 3.59898 12.5112 3.61757 12.4647C3.3108 13.2363 4.59366 12.567 4.39844 13.2084L4.29618 13.2549C4.46351 13.3757 4.19393 13.3014 4.15674 13.5059C4.44492 13.3199 4.51929 13.5431 4.68662 13.5616C4.62155 13.5895 4.60295 13.5616 4.53788 13.5616C4.4914 13.6267 4.33337 13.7569 4.41703 13.7662C4.88184 13.5709 5.01198 13.8126 5.24438 13.8777C5.08635 14.0357 5.03058 14.296 4.80747 14.5935C4.88184 14.5563 5.03987 14.482 5.1979 14.4076C5.13283 14.5563 5.25368 14.5284 5.38383 14.4913C5.33735 14.4448 5.30016 14.3983 5.27227 14.3704H5.29087C5.29087 14.3704 5.26298 14.3611 5.25368 14.3518C5.2165 14.3239 5.1979 14.3146 5.18861 14.3332C5.30946 14.138 5.32805 14.231 5.53256 14.0636C5.56975 14.1194 5.71849 14.1752 5.57904 14.3053C5.59764 14.3425 5.59764 14.3797 5.57904 14.4355C5.62552 14.4355 5.66271 14.4355 5.66271 14.4727H5.63482C5.63482 14.4727 5.59764 14.5284 5.57904 14.547C5.57904 14.7144 5.98807 14.6121 6.20188 14.5842C5.87652 14.7051 5.9323 14.8352 5.73708 14.9839C5.75567 14.9839 5.6906 14.8724 5.58834 14.7423C5.57904 14.7701 5.55116 14.798 5.48608 14.8538C5.37453 15.1234 5.81145 14.9003 5.80215 15.1792C5.77426 15.1792 5.70919 15.1978 5.65341 15.2628C5.65341 15.3651 5.83933 15.3 5.96018 15.2164C5.79285 15.3744 5.75567 15.6068 5.88582 15.5975C6.08103 15.5324 6.14611 15.4673 6.20188 15.5789L6.03455 15.644C6.01596 15.8485 6.29484 15.5882 6.26695 15.7648C6.28555 15.6905 6.14611 15.7927 6.14611 15.8392C6.31344 15.895 6.3971 15.8578 6.70387 15.709L6.49936 15.8671C6.67598 15.8485 6.97346 15.6997 6.73176 15.9693C7.08501 15.551 7.00135 15.8485 7.03853 15.9043C7.01994 15.9043 6.95487 15.9972 6.91768 16.053C7.18727 15.8113 7.05712 16.211 7.15938 16.3133L7.03853 16.7874C7.1036 16.8432 7.3453 15.9136 7.36389 15.96L7.30812 16.1831C7.38249 16.1831 7.40108 16.2482 7.44756 16.4063L7.41967 16.7874C7.45685 16.6387 7.48474 16.6758 7.50333 16.5085C7.52193 17.0291 7.587 16.9826 7.63348 16.9175C7.66137 16.8804 7.67996 16.8711 7.70785 16.9175C7.72644 16.9175 7.75433 17.0012 7.81011 17.2522L7.69855 16.4248C7.69855 16.4248 7.69855 16.4063 7.69855 16.397C7.70785 16.3505 7.71714 16.3226 7.81011 16.7409C7.91236 17.3173 7.83799 16.6944 7.87518 16.7874C7.87518 16.6944 7.80081 16.3319 7.77292 16.2482C7.91236 16.462 7.88447 15.9972 8.16336 16.3784C8.18195 16.0437 7.96814 15.6626 8.0611 15.6161L8.10758 15.6533C8.10758 15.6533 8.20054 15.6626 8.2935 15.6905C8.40506 15.6905 8.55379 15.7183 8.72112 15.8392C8.79549 15.5882 8.44224 15.1048 8.78619 14.9932L8.86986 15.142C8.98141 15.142 8.90704 14.9189 8.88845 14.8631C8.91634 14.8445 8.96282 14.9189 9.00001 14.9561C9.14874 14.9932 9.0093 14.8166 9.0186 14.7515L9.11156 14.8631C9.47411 14.8631 9.30678 14.231 9.56707 14.0543C9.56707 14.1194 9.68792 14.2031 9.75299 14.2403C9.50199 13.8405 9.81806 13.6639 9.83665 13.5059L9.91102 13.6825C9.87384 13.3014 10.3944 13.8684 10.3572 13.4873L10.0784 13.3943C10.1992 13.3757 10.1992 13.2642 10.0412 13.134C10.2271 13.1619 10.2922 13.3757 10.4502 13.2828C10.5432 13.3664 10.4223 13.4315 10.5803 13.5059L10.9801 13.5895C10.9801 13.5895 11.0358 13.5895 11.0637 13.5152C10.6547 13.1154 11.1846 13.3571 10.7105 13.0411C10.9243 12.7808 11.3798 12.8644 11.4077 12.4833C11.8725 12.8087 11.826 12.1208 12.2908 12.6599C12.4117 12.5577 12.4117 12.3625 12.2908 12.0929C12.2257 12.0743 12.2629 12.1672 12.2629 12.2137C12.17 12.0557 12.2908 11.8976 12.3466 11.8512C12.3838 12.0371 12.3466 12.2602 12.4767 12.5112C12.5325 12.3625 12.5046 12.0278 12.4953 11.9162L12.7742 12.1579C12.6813 11.8791 13.0531 12.3067 12.8951 11.9627L12.8021 11.8976C12.9787 11.7675 12.737 11.4979 12.8579 11.3213L12.9508 11.4328C13.0438 11.4328 12.8858 11.1075 13.1647 11.3027L13.0717 11.405C13.2576 11.5816 13.4064 11.6002 13.5272 11.6652C13.583 11.5165 13.2855 11.3213 13.3134 11.2469C13.4993 11.405 13.4064 11.3399 13.5272 11.5444C13.583 11.3771 13.6759 11.154 13.5551 10.8472C13.583 10.8751 13.6202 10.9123 13.6202 10.9123C13.7689 10.8286 13.5923 10.4103 13.7968 10.4939V10.5404C14.1314 10.717 13.8247 10.0663 14.2523 10.4939C14.3731 10.5311 14.1314 10.5683 14.401 10.7263C14.6706 10.7356 14.1593 10.2615 14.401 10.2708C14.3731 10.2708 14.401 10.2987 14.4289 10.3452C14.5126 10.2522 14.5963 10.0942 14.6613 9.95476C15.1168 10.2058 14.9681 9.51785 15.498 9.81532C15.3121 9.70377 15.3771 9.61081 15.3213 9.53644C15.3213 9.53644 15.3492 9.58292 15.3771 9.60151C15.4422 9.56433 15.3213 9.41559 15.2842 9.34122C15.4422 9.43418 15.3028 9.07164 15.4143 9.12741C15.3306 9.03445 15.3957 9.01586 15.4422 8.97867C15.4422 9.17389 15.5909 9.21108 15.6839 9.397C15.8698 9.32263 15.4794 8.82994 15.6839 8.77416L15.9256 8.88571C15.7025 8.59754 15.9349 8.58824 15.8419 8.48598C15.9442 8.55105 16.0279 8.56965 16.1394 8.70909C16.1394 8.58824 16.3532 8.65331 16.2324 8.46739L16.1115 8.4488C16.3904 8.39302 16.1487 7.90033 16.4555 7.95611L16.818 8.37443C17.0597 8.45809 16.7901 7.99329 17.0969 8.17921C16.9482 8.06766 16.9761 8.11414 16.9203 7.91892C16.8552 7.91892 16.8831 8.08625 16.8273 8.13273L16.7436 7.77948L16.6507 8.06766C16.5949 7.83526 16.6228 7.87244 16.4462 7.74229C16.4462 7.5006 16.7529 7.82596 16.7251 7.56567C16.818 7.58426 16.9017 7.77018 17.0225 7.81666C16.9946 7.58426 17.478 7.94681 17.3572 7.65863C17.4223 7.67722 17.3293 7.70511 17.413 7.79807C17.4409 7.70511 17.5059 7.67722 17.413 7.53778H17.32C17.3758 7.50989 17.2363 7.33327 17.4223 7.35186C17.3944 7.21242 17.2456 6.98002 17.1899 7.0265C17.1899 6.98002 17.3386 7.04509 17.4316 7.18453C17.5803 7.06368 17.1155 6.68254 17.4316 6.75691C17.4316 6.7755 17.4316 6.81269 17.4687 6.83128C17.5338 6.83128 17.5617 6.80339 17.5617 6.75691C17.4687 6.90565 17.8871 7.05438 17.6733 7.11016C17.8778 7.31467 17.822 7.05438 17.9428 7.11016C17.8871 6.89635 17.6733 6.7848 17.6175 6.64536C17.6733 6.71972 17.7104 6.69184 17.7662 6.69184L17.5896 6.5524C17.5896 6.5524 17.6547 6.50591 17.6547 6.43155V6.5524C17.7476 6.52451 18.073 6.71043 18.0544 6.44084C18.0823 6.5338 18.1381 6.71973 18.2868 6.74761C18.324 6.5338 18.3798 6.79409 18.5564 6.85917C18.6493 6.71043 18.324 6.5431 18.5936 6.48732C18.6122 6.46873 18.5099 6.38507 18.4541 6.35718C18.6493 6.32929 18.6215 6.15266 18.8446 6.17126C18.7516 6.17126 18.6586 6.15266 18.6679 6.01322C18.7516 6.18055 18.8817 6.0597 19.0026 6.09689L18.9468 6.00393C19.0584 6.0597 19.0491 6.13407 19.0491 6.18985C19.0212 6.16196 18.9933 6.14337 18.9747 6.17126C18.9747 6.2921 19.2722 6.58958 19.393 6.5431C19.4302 6.37577 19.2164 6.16196 19.1327 6.09689C19.3466 6.069 18.9282 5.60419 19.1792 5.62279C19.2071 5.5949 19.5975 5.84589 19.7184 5.79941C19.6068 5.56701 19.4767 5.75293 19.393 5.54842C19.9601 5.89237 19.4674 4.97206 19.9229 5.08361L20.0995 5.3439C20.1646 5.31602 20.2204 5.29742 20.2576 5.22305L20.0809 5.15798C20.0809 5.06502 20.239 5.00924 20.3505 5.22305C20.2948 4.93488 20.4156 5.02784 20.5736 5.00924C20.4528 5.08361 20.5457 4.98136 20.5736 5.16728C20.7874 5.18587 20.7317 5.10221 20.7596 4.98136C20.8153 5.07432 20.9641 5.16728 21.0013 5.13939C20.9455 4.92558 21.1035 4.85121 21.1407 4.68388L21.1965 4.75825C21.2894 4.52585 21.7542 4.69318 21.7542 4.33993C21.7542 4.33993 21.7542 4.33063 21.7542 4.32133H21.7264C21.4754 4.14471 21.7264 4.05175 21.7078 3.91231C21.7635 3.95879 21.8565 4.05175 21.8844 4.02386C21.7078 3.81005 21.8565 3.85653 21.8007 3.73568C21.9216 3.75427 22.0052 3.99597 22.0982 3.89371C22.1261 3.83794 22.0331 3.72638 21.968 3.65202C22.0796 3.73568 22.219 3.77286 22.2934 3.74498C22.3213 3.81934 22.2283 3.77286 22.2283 3.79146C22.312 3.91231 22.3213 3.83794 22.4329 3.97738C22.4979 3.94949 22.2841 3.76357 22.405 3.79146L22.4886 4.00527C22.5444 4.02386 22.5165 3.9309 22.5258 3.91231C22.5258 3.98667 22.6746 4.14471 22.7582 4.23767C22.7954 3.99597 22.4143 3.76357 22.2655 3.57765C22.5072 3.59624 22.4236 3.28947 22.5165 3.19651L22.6653 3.41032C22.6931 3.33595 22.6746 3.27088 22.6281 3.17791L22.7024 3.11284C22.721 3.22439 22.7582 3.29876 22.8791 3.4568C22.9163 3.33595 23.0743 3.28947 22.8791 3.01058L22.9163 3.05707C23.1022 3.05707 23.3811 2.92692 23.4461 3.01988C23.4926 2.83396 23.7715 2.86185 23.5577 2.60156C23.5763 2.48071 24.0225 2.78748 23.7994 2.41564C24.0225 2.51789 23.8645 2.48071 23.9946 2.69452C24.2177 2.79677 23.9388 2.28549 24.2828 2.63874C24.2828 2.44352 24.1991 2.58296 24.0876 2.38775C24.3943 2.71311 24.3107 2.29479 24.571 2.41564C24.4966 2.23901 24.4594 2.35986 24.4036 2.15534C24.4687 2.24831 24.5245 2.22971 24.5431 2.22971L24.3757 1.99731L24.9149 2.45282C24.8405 2.08098 24.571 2.09957 24.6732 1.84857V1.87646C24.9149 2.06238 24.6732 1.59758 24.9428 1.66265C24.8591 1.66265 25.0079 1.7835 25.0451 1.85787V1.70913C25.0451 1.70913 25.0544 1.74632 25.0822 1.76491C25.2868 1.87646 25.0636 1.62547 25.2589 1.70913C25.2403 1.7928 25.3983 1.95083 25.482 2.00661L25.3797 1.67195L25.5842 2.00661C25.7051 1.94153 25.4727 1.33729 25.8631 1.69984L25.8445 1.7835C25.9096 1.84857 26.1234 2.04379 26.0676 1.82998C26.0676 1.7742 25.9282 1.58828 25.9096 1.62547L26.0211 1.65336C26.1513 1.86717 26.0676 2.0345 26.0304 2.15534C25.9933 2.05309 26.0026 1.94153 25.8817 1.82998C25.8631 1.95083 25.9003 2.14605 25.8817 2.2669C25.8445 2.16464 25.7609 2.0252 25.7051 1.94153C25.5377 1.90435 25.7609 2.12746 25.7051 2.19253C25.6214 2.13675 25.5563 2.09957 25.5192 2.0252C25.5192 2.16464 25.4634 2.23901 25.3053 2.20182C25.3053 2.20182 25.2775 1.98801 25.138 1.91365C25.0915 2.15534 25.2589 2.41564 25.2124 2.67593C25.3053 3.15003 24.6918 2.76889 24.7662 3.11284C24.8312 3.2058 24.9893 3.18721 24.9521 3.30806C24.822 3.12214 24.8127 3.23369 24.7476 3.16862C24.8684 3.49398 24.571 3.2244 24.6546 3.4475C24.6174 3.37313 24.5059 3.35454 24.4222 3.31736C24.2549 3.09425 24.2549 3.31736 24.1247 2.89903C24.2642 3.33595 23.818 3.01988 24.134 3.59624L24.2177 3.62413H23.9946L24.0039 3.63342C23.9202 3.64272 23.9574 3.70779 23.6878 3.54976C23.6785 3.46609 23.725 3.42891 23.7157 3.34524C23.4833 3.2151 23.6971 3.63342 23.6321 3.70779C23.5019 3.54976 23.6692 3.58694 23.4833 3.41032C23.4089 3.42891 23.4554 3.58694 23.4368 3.6799L23.3718 3.58694C23.065 3.50328 23.6785 4.06104 23.3253 3.85653C23.3718 3.90301 23.4089 3.96808 23.4554 4.01456C23.3439 3.95879 23.1208 3.87512 23.1208 3.6892C23.0743 3.72638 23.0836 3.85653 23.1394 3.96808C23.2881 4.06104 23.2416 3.98667 23.3996 4.13541L23.2788 4.38641C23.2788 4.38641 23.223 4.28415 23.2509 4.26556C22.6374 3.99597 23.1115 5.04643 22.3864 4.71177C22.5351 4.83262 22.47 4.85121 22.5258 4.97206C22.405 4.99995 22.312 5.13939 22.154 5.1208L22.0982 4.99995C21.9959 5.28813 21.9866 5.55771 21.81 5.60419C21.8379 5.65067 21.6892 5.46475 21.6892 5.41827C21.7449 5.67856 21.15 5.21376 21.4382 5.61349H21.5032C21.2615 5.71575 21.2708 6.16196 21.1221 6.37577C20.8897 6.18985 21.2151 6.25492 20.9455 6.02252C20.7317 6.05041 20.7503 6.35718 20.5457 6.41295C20.5457 6.36647 20.5179 6.33859 20.5179 6.31999C20.2483 6.3014 20.7224 6.5338 20.5736 6.59888C20.49 6.47803 20.4528 6.45943 20.3691 6.44084L20.4807 6.65465C20.4807 6.65465 20.3319 6.48732 20.3041 6.42225C20.4528 6.70113 20.146 6.68254 20.2948 6.94283C20.239 6.89635 20.0902 6.66395 19.9973 6.58958C19.8764 6.58958 19.9043 6.71043 19.9322 6.83128C19.7556 6.71043 19.6626 6.83128 19.6626 6.7848C19.4767 6.81269 19.7463 6.92424 19.7742 7.13805L19.9508 7.15664L19.83 7.35186L19.8021 7.18453C19.6533 7.16594 19.737 7.42623 19.644 7.5006L19.7928 7.59356L19.7556 7.76089C19.5232 7.50989 19.5697 7.81666 19.3651 7.46341C19.0584 7.4913 19.235 7.94681 19.077 8.11414C19.1049 8.08625 19.0491 8.04907 19.0212 7.99329C18.8725 8.02118 18.9282 8.2071 18.984 8.39302C18.9282 8.30006 18.9282 8.25358 18.8632 8.17921C18.7423 8.28147 18.9189 8.39302 18.8632 8.57894C18.8074 8.4395 18.7423 8.39302 18.6865 8.39302C18.7795 8.48598 18.8074 8.57894 18.8074 8.62542C18.4541 8.02118 18.4727 8.54176 18.1845 8.07695C18.2775 8.1978 18.2682 8.59754 18.5099 8.75557V8.6812C18.6401 8.82064 18.5471 8.81135 18.5099 8.84853C18.5099 8.81135 18.5006 8.75557 18.4727 8.72768C18.4355 9.06234 18.1009 9.07164 18.0079 9.37841C17.98 9.31333 17.98 9.146 17.8871 9.146C17.6175 9.24826 17.729 9.6294 17.6361 9.93617C17.3386 9.61081 17.822 9.69447 17.5524 9.36911C17.3944 9.6387 17.2735 9.94547 17.1806 10.3266C16.6693 9.91758 17.1155 10.7356 16.6321 10.4846C16.7901 10.6334 16.7622 10.7542 16.6879 10.8379C16.5949 10.6799 16.5112 10.7542 16.4462 10.6334C16.502 10.8472 16.3532 11.0889 16.0836 10.7635C16.3346 11.0796 15.9163 10.8844 16.0557 11.154C15.8605 11.1168 15.9163 11.3864 15.7304 11.3957C15.9442 11.5537 15.7025 11.5909 15.7304 11.7024C15.7304 11.6838 15.7304 11.6281 15.7025 11.6095C15.5166 11.47 15.7025 11.8698 15.5537 11.8326C15.4608 11.7861 15.405 11.6467 15.3399 11.6745C15.4608 11.814 15.4329 12.1208 15.2191 12.0092C15.247 11.9813 15.1912 11.9162 15.154 11.8419C15.0704 12.3439 14.494 12.3439 14.4382 12.9016L14.2802 12.6227C13.8247 12.5019 14.494 13.1061 14.3174 13.2177C13.8061 13.478 13.0903 13.5524 12.8207 14.0636C12.8486 14.1566 12.9137 14.1287 13.0066 14.2217C12.9508 14.2217 12.7649 14.045 12.8207 14.2124L12.9415 14.3239C12.4489 14.1659 12.6441 15.0304 12.0212 14.6493C12.0398 15.0025 11.6029 14.7887 11.6866 15.2721C11.5192 15.2349 11.5564 15.0025 11.4449 15.0583V15.4209V15.393C11.6401 15.9043 10.5896 15.4859 10.6547 15.96V15.9321C10.5617 15.8485 10.413 15.8113 10.413 15.8764C10.4595 15.9414 10.5153 15.9414 10.6082 15.9879C10.5803 16.3226 10.5525 16.3691 10.4409 16.555C10.3665 16.3784 10.2736 16.5271 10.0784 16.3877C10.162 16.5271 10.2922 16.5178 10.3201 16.6944C10.2178 16.8525 9.99469 16.8153 9.78088 16.9826C9.89243 17.1964 9.78088 17.2615 9.9668 17.4567C9.80877 17.7821 9.75299 18.0052 9.56707 18.4886L9.51129 18.4049C9.66003 18.879 9.251 18.6094 9.32537 18.9162C9.26959 18.7582 9.2603 18.6559 9.19522 18.5629L9.17663 18.8976C9.15804 18.6652 9.00001 18.2469 8.92564 18.3398C8.99071 18.7953 9.02789 18.4979 9.10226 18.8232L8.91634 18.47C8.88845 18.6187 9.05578 19.1486 9.16733 19.1021C8.99071 19.5483 8.86986 20.3013 8.69323 20.6546L8.62816 20.2362C8.58168 20.5709 8.47013 20.8963 8.37717 20.701C8.37717 20.6732 8.35857 20.6546 8.35857 20.636C8.37717 20.7568 8.37717 20.9706 8.41435 21.1101C8.35858 21.5842 8.31209 20.45 8.25632 20.9706C8.27491 20.8498 8.3028 20.7847 8.27491 20.5523C8.24702 20.6267 8.21913 20.6917 8.19125 20.7568C8.17265 20.7847 8.16336 20.8126 8.14477 20.8405H8.0704C8.03321 20.5802 7.8194 19.8272 7.70785 19.8923C7.70785 20.0224 7.75433 20.2455 7.78222 20.3106L7.69855 20.3292L7.62418 19.7157C7.587 19.8272 7.54982 19.9388 7.51263 20.041V19.6041C7.42897 19.6041 7.38249 20.0968 7.29882 19.9667C7.03853 19.3717 7.1036 19.3066 6.98275 18.7396C6.84331 19.4182 6.71317 18.3863 6.55513 18.8139C6.45288 18.0517 6.01596 17.9215 5.77426 17.4381H5.83004C5.87652 17.0756 5.42101 17.5869 5.34664 17.3173L5.4396 17.2987C5.45819 17.0849 5.32805 16.9175 5.18861 16.8432C5.05846 16.7688 4.87254 16.7409 4.71451 16.7409C4.80747 16.7223 4.92832 16.5922 4.87254 16.555C4.75169 16.5829 4.60295 16.8339 4.62155 16.6851C4.67732 16.6758 4.76099 16.5829 4.7424 16.555L4.46351 16.6387C4.43563 16.2947 4.37985 15.9136 4.07308 15.7834C4.11026 15.6812 4.22182 15.6533 4.29618 15.6068C4.11026 15.4581 3.7849 15.4209 3.61757 15.2814L3.84997 15.0676C3.7849 14.9839 3.43165 15.3186 3.57109 15.0397C3.58968 14.9932 3.64546 15.0955 3.7756 15.0397C3.84068 14.733 3.45954 15.1327 3.36658 14.9561L3.68264 14.7794C3.75701 14.5284 3.43165 14.7608 3.22713 14.8445C2.76233 14.9282 3.68264 14.3053 3.25502 14.2682C3.08769 14.3425 3.0598 14.4355 2.89247 14.5098C2.84599 14.2867 2.62289 14.4262 2.57641 14.2031C2.93896 13.794 2.64148 14.2867 2.96684 13.887V14.0822C3.10628 13.8033 3.09699 14.138 3.32939 13.9242C3.33869 13.7848 3.03192 13.8312 2.87388 13.7848C3.0598 13.6453 2.98544 13.887 3.20854 13.6453H3.08769C3.15277 13.6267 3.22713 13.5709 3.24573 13.6081C3.41306 13.4501 3.20854 13.5338 3.16206 13.4873C3.0598 13.5616 2.92036 13.6639 2.79951 13.7848C2.81811 13.7662 2.8367 13.7476 2.85529 13.7197C2.50204 13.8219 2.57641 13.4873 2.28823 13.5616C2.3533 13.5338 2.3626 13.5059 2.40908 13.4687C2.37189 13.3943 2.07442 13.5152 1.93498 13.4873C2.03723 13.3385 2.38119 13.1991 2.19527 13.1247C2.01864 13.2177 1.78624 13.4873 1.70258 13.3571C1.70258 13.3571 1.90709 13.3571 1.98146 13.227H1.95357ZM4.28689 15.5045C4.28689 15.5045 4.31478 15.5324 4.34266 15.551C4.34266 15.551 4.29618 15.5138 4.28689 15.5045ZM4.61225 15.5696C4.61225 15.5696 4.51929 15.5975 4.45422 15.6533C4.48211 15.6905 4.50999 15.7183 4.51929 15.7555C4.55647 15.6719 4.55647 15.5882 4.61225 15.5696ZM5.46749 14.2403L5.49538 14.2217C5.49538 14.2217 5.55116 14.2496 5.56975 14.2589C5.60693 14.2217 5.63482 14.1752 5.57904 14.1659C5.55116 14.1845 5.50468 14.2031 5.46749 14.231V14.2403Z\" fill=\"#8F3A7E\"><\/path><path d=\"M5.26323 14.3253C5.26323 14.3253 5.24482 14.3253 5.23562 14.3253C5.22642 14.3437 5.21721 14.3621 5.20801 14.3805L5.28164 14.3437L5.26323 14.3253Z\" fill=\"#8F3A7E\"><\/path><path d=\"M21.6523 4.27579C21.6523 4.27579 21.6712 4.27579 21.69 4.29463C21.6806 4.29463 21.6712 4.28521 21.6618 4.27579H21.6523Z\" fill=\"#8F3A7E\"><\/path><path d=\"M7.48508 20.1339L7.49435 20.032L7.46655 20.0876L7.48508 20.1339Z\" fill=\"#8F3A7E\"><\/path><path d=\"M23.4094 3.96896C23.4094 3.96896 23.4473 3.9974 23.4663 4.00688C23.4568 3.9974 23.4284 3.97844 23.4094 3.96896Z\" fill=\"#8F3A7E\"><\/path><path d=\"M24.4309 3.36418C24.4309 3.36418 24.3847 3.29949 24.3662 3.27176L24.4309 3.36418Z\" fill=\"#8F3A7E\"><\/path><path d=\"M19.885 6.80322C19.8943 6.85893 19.9036 6.90536 19.9036 6.95178C19.95 6.9425 19.9779 6.92393 19.885 6.80322Z\" fill=\"#8F3A7E\"><\/path><path d=\"M16.6518 10.8394L16.6318 10.8494L16.6518 10.8394Z\" fill=\"#8F3A7E\"><\/path><path d=\"M19.8203 7.01859C19.885 7.02783 19.9035 7.0001 19.9035 6.95389C19.8665 6.96313 19.8203 6.97237 19.8203 7.01859Z\" fill=\"#8F3A7E\"><\/path><path d=\"M26.1981 2.03489H26.2264C26.2264 2.03489 26.2075 2.00662 26.1981 1.99719V2.03489Z\" fill=\"#8F3A7E\"><\/path><path d=\"M26.1977 1.99845V1.96075C26.1977 1.96075 26.1789 1.9796 26.1977 1.99845Z\" fill=\"#8F3A7E\"><\/path><path d=\"M26.2079 1.8683V1.95148C26.2079 1.95148 26.2449 1.933 26.2079 1.8683Z\" fill=\"#8F3A7E\"><\/path><path d=\"M25.6025 2.37845L25.6578 2.45208C25.6578 2.45208 25.6302 2.40606 25.6025 2.37845Z\" fill=\"#8F3A7E\"><\/path><path d=\"M25.4627 2.52706C25.5183 2.50852 25.6852 2.60121 25.7037 2.51779L25.6574 2.45291C25.7223 2.58267 25.3978 2.37876 25.4627 2.52706Z\" fill=\"#8F3A7E\"><\/path><path d=\"M24.0587 2.18406L24.2354 2.12826C24.1517 2.07245 24.0308 1.98874 24.0773 1.92363C23.7145 1.83062 24.254 2.07245 24.0587 2.18406Z\" fill=\"#8F3A7E\"><\/path><path d=\"M23.5575 2.40555C23.5946 2.31271 23.4646 2.29414 23.4275 2.24771C23.4461 2.35913 23.4461 2.38698 23.5575 2.40555Z\" fill=\"#8F3A7E\"><\/path><path d=\"M20.6004 4.88834L20.4517 4.70251C20.4239 4.77684 20.5075 4.77684 20.6004 4.88834Z\" fill=\"#8F3A7E\"><\/path><path d=\"M20.833 6.30117L20.9817 6.36621L20.8702 6.18039L20.833 6.30117Z\" fill=\"#8F3A7E\"><\/path><path d=\"M19.4009 5.29716L19.4102 5.25073L19.373 5.39001L19.4009 5.29716Z\" fill=\"#8F3A7E\"><\/path><path d=\"M14.5673 9.62069L14.7804 9.8246C14.7804 9.75045 14.5673 9.5002 14.5673 9.62069Z\" fill=\"#8F3A7E\"><\/path><path d=\"M12.6902 11.7309C12.5694 11.6473 12.4486 11.6287 12.5044 11.7681C12.5601 11.7402 12.6902 11.7774 12.6902 11.7309Z\" fill=\"#8F3A7E\"><\/path><path d=\"M7.70828 16.6682L7.6897 16.4824L7.69899 16.659L7.70828 16.6682Z\" fill=\"#8F3A7E\"><\/path><path d=\"M1.70163 9.61194C1.61792 9.63054 1.4691 9.73285 1.52491 9.76076L1.81324 9.63984L1.70163 9.61194Z\" fill=\"#8F3A7E\"><\/path><path d=\"M1.38543 10.1886C1.54327 10.17 1.80325 10.0957 2.02609 9.91004C1.74754 10.0122 1.84039 9.9379 1.50613 10.0586C1.45042 10.0307 1.54327 9.92861 1.64541 9.88219C1.57113 9.90076 1.66398 9.78006 1.47828 9.85433C1.30187 10.0307 1.33901 10.1143 1.55256 10.0865C1.50613 10.1329 1.42257 10.1607 1.37615 10.1886H1.38543Z\" fill=\"#8F3A7E\"><\/path><path d=\"M6.07034 17.5318C6.07034 17.5318 6.02367 17.5318 6.005 17.5598C6.033 17.5598 6.06101 17.5598 6.07034 17.5318Z\" fill=\"#8F3A7E\"><\/path><path d=\"M6.40438 18.461C6.40438 18.461 6.38574 18.4238 6.38574 18.4051C6.38574 18.4517 6.38574 18.4797 6.40438 18.461Z\" fill=\"#8F3A7E\"><\/path><path d=\"M4.03508 14.7249L4.01648 14.8551C4.10019 14.7993 4.04438 14.7714 4.03508 14.7249Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.3788 10.391C2.3788 10.391 2.32335 10.391 2.28638 10.391C2.30486 10.391 2.32335 10.4002 2.33259 10.4095L2.3788 10.3817V10.391Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.96444 13.7376L2.94584 13.719C2.94584 13.719 2.87143 13.7562 2.83423 13.7748L2.96444 13.7376Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.26855 12.8844C2.26855 12.8844 2.49178 12.7635 2.58479 12.7077C2.49178 12.7635 2.43597 12.7728 2.40807 12.7728C2.37087 12.8007 2.32436 12.8379 2.26855 12.8937V12.8844Z\" fill=\"#8F3A7E\"><\/path><path d=\"M3.40322 14.398C3.40322 14.398 3.34722 14.4447 3.33789 14.4634C3.36589 14.4447 3.38456 14.4167 3.40322 14.398Z\" fill=\"#8F3A7E\"><\/path><path d=\"M24.3936 0.882324C24.3936 0.882324 24.4124 0.910594 24.4218 0.920017C24.4124 0.891747 24.403 0.882324 24.3936 0.882324Z\" fill=\"#8F3A7E\"><\/path><path d=\"M26.1963 1.0585V1.08636L26.2891 1.19778L26.1963 1.0585Z\" fill=\"#8F3A7E\"><\/path><path d=\"M7.32639 20.0692C7.32639 20.0692 7.32639 20.0692 7.32639 20.0592C7.29639 20.0692 7.31639 20.0792 7.32639 20.0692Z\" fill=\"#8F3A7E\"><\/path><path d=\"M13.8886 13.0136C13.6561 12.9113 13.8142 12.6788 13.5166 12.5951C13.6003 12.6602 13.684 12.995 13.8886 13.0136Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.37 10.4381C2.37 10.4381 2.38884 10.457 2.39826 10.4758C2.39826 10.457 2.38884 10.4476 2.37 10.4381Z\" fill=\"#8F3A7E\"><\/path><path d=\"M9.13905 18.7775C9.11125 18.7312 9.08346 18.6942 9.05566 18.6756C9.07419 18.7127 9.09272 18.7405 9.13905 18.7775Z\" fill=\"#8F3A7E\"><\/path><path d=\"M7.87305 19.9031L7.91937 20.005C7.90084 19.9494 7.89158 19.9216 7.87305 19.9031Z\" fill=\"#8F3A7E\"><\/path><path d=\"M9.5293 17.1406C9.5293 17.1406 9.59373 17.1407 9.59373 17.0762C9.58452 17.0762 9.57532 17.0762 9.56611 17.067C9.58452 17.1038 9.58452 17.1406 9.5385 17.1406H9.5293Z\" fill=\"#8F3A7E\"><\/path><path d=\"M10.1335 16.3052C10.1335 16.3052 10.0955 16.2957 10.0861 16.2863V16.3147L10.1335 16.3052Z\" fill=\"#8F3A7E\"><\/path><path d=\"M22.2911 2.80592C22.3562 2.85237 22.4119 2.89883 22.477 2.95457C22.3469 2.8245 22.4119 2.68513 22.2911 2.80592Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.25891 10.4761C2.31499 10.448 2.35237 10.4293 2.37106 10.4387L2.34302 10.42C2.34302 10.42 2.2776 10.4574 2.25891 10.4761Z\" fill=\"#8F3A7E\"><\/path><path d=\"M8.05957 15.6353L8.11645 15.6163C8.11645 15.6163 8.06905 15.6163 8.05957 15.6353Z\" fill=\"#8F3A7E\"><\/path><path d=\"M17.1702 7.21375V7.16635C17.1702 7.16635 17.1607 7.18531 17.1702 7.21375Z\" fill=\"#8F3A7E\"><\/path><path d=\"M8.31042 15.2827C8.40334 15.3198 8.45908 15.3198 8.50554 15.3198C8.49625 15.3013 8.48696 15.2827 8.46837 15.2641L8.31042 15.2827Z\" fill=\"#8F3A7E\"><\/path><path d=\"M22.9801 2.12785C22.9986 1.93263 23.0544 2.14644 23.2961 2.2394C23.1753 1.97911 23.4635 2.23011 23.1846 1.86756C23.417 2.07207 23.3333 1.98841 23.5378 2.09996C23.3519 1.93263 23.5099 1.80249 23.3147 1.57938C23.5564 1.81178 23.4635 1.98841 23.7795 2.18363C23.6959 1.96052 23.7516 1.80249 23.5285 1.51431C23.6308 1.5422 23.733 1.62586 23.826 1.58868C23.7981 1.58868 23.826 1.64445 23.8446 1.68164C23.8167 1.38416 24.1607 1.42135 23.9468 1.02161C24.2536 1.44923 24.2629 0.844989 24.4767 1.3005C24.5232 1.24472 24.4581 1.00302 24.4117 0.910061C24.6719 1.22613 24.6069 0.882173 24.8207 1.02161C24.6998 0.8171 24.8486 0.798508 24.8207 0.649771C24.8207 0.705547 24.8579 0.77062 24.9415 0.854285C24.895 0.668363 24.988 0.807804 25.1646 0.910061C25.1646 0.742732 24.9508 0.686955 24.8765 0.491737C25.0159 0.491737 25.0531 0.677659 25.1739 0.798508L25.0252 0.38948C25.0717 0.398776 25.1367 0.445257 25.2204 0.528921C25.1832 0.408072 25.1089 0.240743 25.2855 0.343L25.1925 0.435961L25.3599 0.566106L25.3041 0.268631C25.6666 0.361592 25.899 0.742732 26.1593 1.08669L26.1407 1.19824C26.2337 1.30979 26.3359 1.33768 26.3731 1.31909C26.4661 1.37487 26.5683 1.7746 26.5219 1.87685C26.3081 2.02559 26.1593 1.5236 25.9548 1.55149L25.9362 1.89545L25.8432 1.78389C25.7503 1.72812 25.8432 1.86756 25.8525 1.90474C25.7224 1.72812 25.6666 1.96982 25.5644 2.007L25.7131 2.12785C25.7968 2.63913 25.0903 2.02559 25.081 2.34166L25.1739 2.68561L24.9694 2.4904C25.0066 2.67632 25.1367 2.85294 24.9694 2.86224C24.2815 2.79717 24.2629 3.59663 23.6773 3.6803C23.7144 3.71748 23.7423 3.72678 23.7981 3.73607C23.0172 3.47578 23.7423 4.72146 23.0916 4.55413L23.0451 4.46117C22.9243 4.6285 22.9986 4.35891 22.7848 4.34032C22.9801 4.6192 22.7662 4.70287 22.7569 4.87949C22.7291 4.81442 22.7569 4.79583 22.7569 4.73075C22.6919 4.68427 22.5524 4.53554 22.5524 4.6192C22.7755 5.07471 22.5338 5.21415 22.4688 5.45585C22.3014 5.29782 22.0411 5.26063 21.7437 5.03752C21.7809 5.11189 21.8645 5.26993 21.9482 5.41866C21.7995 5.35359 21.8273 5.47444 21.8738 5.61388C21.9203 5.5674 21.9575 5.53022 21.9854 5.49303V5.51163C21.9854 5.51163 21.9947 5.48374 22.004 5.47444C22.0319 5.43726 22.0412 5.40937 22.0226 5.40937C22.2271 5.52092 22.1341 5.54881 22.3014 5.74403C22.2457 5.78121 22.1992 5.93925 22.0597 5.7998C22.0226 5.8184 21.9854 5.8184 21.9296 5.8184C21.9296 5.86488 21.9296 5.90206 21.8924 5.90206V5.87417C21.8924 5.87417 21.8366 5.83699 21.818 5.8184C21.6507 5.8184 21.7623 6.23672 21.7995 6.44123C21.6693 6.12517 21.5392 6.17165 21.3811 5.99502C21.3811 6.01361 21.4927 5.93925 21.6228 5.83699C21.5949 5.82769 21.5578 5.7998 21.502 5.73473C21.2324 5.63247 21.4648 6.06009 21.1859 6.06009C21.1859 6.03221 21.1673 5.97643 21.1022 5.91136C21 5.91136 21.0744 6.09728 21.158 6.21813C20.9907 6.0508 20.7676 6.02291 20.7676 6.15306C20.842 6.34827 20.907 6.40405 20.7955 6.46912L20.7304 6.31109C20.5259 6.30179 20.7955 6.57138 20.6188 6.55279C20.7025 6.57138 20.591 6.44123 20.5445 6.43194C20.4887 6.59927 20.5445 6.67364 20.6746 6.9897L20.5259 6.77589C20.5259 6.98041 20.5445 7.38014 20.3214 7.11055C20.7025 7.49169 20.2935 7.51028 20.2005 7.57536C20.2191 7.53817 20.154 7.44521 20.1169 7.39873C20.1726 7.82635 19.7636 7.7148 19.587 7.88213L19.2988 7.61254C19.2151 7.7055 19.6892 8.31904 19.5777 8.39341L19.494 8.21679C19.3546 8.4213 19.2523 8.45849 19.0664 8.54215L18.8991 8.33764C18.927 8.47708 18.8619 8.53285 18.8898 8.6723C18.3506 8.29116 18.6295 9.34161 17.9416 8.99766L18.2483 9.3788C18.1554 9.44387 18.1089 9.6112 17.83 9.3788H17.8579C17.6162 9.08132 17.7649 9.43458 17.6627 9.41598C17.6534 9.48106 17.7742 9.70416 17.8579 9.72275C17.4675 9.72275 17.3094 10.2154 16.8725 10.0109C16.7517 10.327 16.8446 10.7732 16.5658 10.9498L16.5286 10.9034C16.4077 10.9219 16.1474 10.9684 15.8778 10.6617C15.7663 10.8848 16.0359 11.4053 15.7012 11.4518L15.6454 11.2938C15.5432 11.2845 15.5897 11.4983 15.599 11.5541C15.5711 11.5634 15.5339 11.489 15.4967 11.4425C15.3573 11.3868 15.4688 11.5727 15.4595 11.6377L15.3851 11.5169C15.0319 11.4518 15.1435 12.1026 14.8925 12.242C14.9018 12.1769 14.7809 12.084 14.7158 12.0468C14.9389 12.4651 14.6229 12.5952 14.6136 12.7533L14.5485 12.5767C14.5764 12.9578 14.0744 12.3535 14.1116 12.7347L14.3812 12.8369C14.2603 12.8369 14.2603 12.9578 14.4184 13.0972C14.2324 13.0601 14.1767 12.8462 14.0186 12.9299C13.9257 12.8369 14.0465 12.7812 13.8978 12.6975L13.498 12.6045C13.498 12.6045 13.4423 12.5952 13.4144 12.6696C13.8141 13.0786 13.2935 12.8184 13.7583 13.153C13.5538 13.404 13.0983 13.311 13.0704 13.6922C12.6149 13.3668 12.6521 14.0547 12.1873 13.5156C12.0664 13.6178 12.0757 13.813 12.2059 14.0826C12.271 14.1012 12.2338 14.0083 12.2338 13.9618C12.3267 14.1198 12.2152 14.2685 12.1594 14.3243C12.1222 14.1384 12.1501 13.9246 12.02 13.6736C11.9642 13.8223 12.0014 14.1477 12.0107 14.2685L11.7318 14.0268C11.834 14.3057 11.4529 13.8781 11.6202 14.2221L11.7132 14.2871C11.5366 14.4173 11.7876 14.6869 11.6853 14.8542L11.5923 14.7426C11.4994 14.7426 11.676 15.068 11.3878 14.8821L11.4715 14.7798C11.2856 14.6032 11.1275 14.6032 11.0067 14.5381C10.9509 14.6869 11.267 14.8635 11.2484 14.9379C11.0532 14.7891 11.1554 14.8542 11.016 14.6497C10.9602 14.817 10.8951 15.0401 11.0439 15.3376C11.016 15.319 10.9788 15.2725 10.9788 15.2725C10.8394 15.3562 11.0625 15.7559 10.8487 15.6908V15.6444C10.4954 15.5049 10.8765 16.1092 10.4024 15.728C10.2816 15.7001 10.514 15.6444 10.2258 15.5142C9.95623 15.5328 10.5233 15.9418 10.2909 15.9511C10.3188 15.9511 10.2909 15.9325 10.2537 15.8861C10.1886 15.9883 10.1329 16.1464 10.0957 16.2858C9.60298 16.1185 9.90046 16.732 9.3148 16.574C9.51002 16.639 9.46354 16.7692 9.52861 16.8343C9.52861 16.8343 9.49143 16.7878 9.46354 16.7785C9.39847 16.8343 9.53791 16.983 9.58439 17.0667C9.41706 17.0016 9.58439 17.4385 9.46354 17.4013C9.54721 17.5036 9.48213 17.5501 9.43565 17.6244C9.43565 17.3455 9.28692 17.3363 9.18466 17.1131C9.02663 17.234 9.40776 17.8661 9.21255 18.0613C9.13818 18.0242 9.07311 17.987 8.99874 17.9405C9.20325 18.3867 8.99874 18.4983 9.07311 18.6656C8.98944 18.5726 8.92437 18.554 8.82211 18.303C8.82211 18.5354 8.65478 18.4239 8.74774 18.7957L8.8407 18.8236C8.72915 18.9073 8.71985 19.1955 8.70126 19.4929C8.68267 19.7811 8.65478 20.06 8.55253 19.9856L8.33872 18.9445C8.19927 18.647 8.33872 19.8462 8.17139 19.2977C8.24575 19.6417 8.23646 19.5022 8.25505 20.0042C8.29223 20.0135 8.28294 19.5952 8.32942 19.4929L8.34801 20.404L8.44097 19.6882C8.45956 20.2738 8.44097 20.1716 8.55253 20.5341C8.52464 21.0547 8.40379 20.5713 8.35731 20.7386C8.34801 20.7386 8.32942 20.7758 8.32012 20.8502C8.25505 20.6828 8.23646 20.2831 8.17139 20.06C8.12491 20.4411 7.94828 19.4093 7.9018 19.7718C7.86461 19.6417 7.94828 19.7997 7.92039 19.5673C7.85532 19.5673 7.80884 19.4744 7.79954 19.7253L7.87391 19.902C7.81813 19.809 7.82743 20.1716 7.69728 19.8276C7.64151 19.9577 7.60432 20.3296 7.68799 20.4318C7.6601 20.4504 7.57644 20.1344 7.60432 19.902C7.4277 19.6789 7.51136 20.6921 7.32544 20.0693C7.34403 20.0693 7.35333 20.0321 7.35333 19.9763C7.30685 19.8648 7.26967 19.8183 7.23248 19.8276C7.39981 19.9485 7.22318 19.1304 7.39051 19.4929C7.39051 19.0374 7.26037 19.2512 7.21389 19.0188C7.10234 19.1955 7.15811 19.5952 7.09304 19.7439C7.10234 19.6138 7.06515 19.5673 7.02797 19.4651L7.04656 19.8183C7.00008 19.7718 6.96289 19.716 6.90712 19.7253L7.00937 19.7068C6.91641 19.5394 6.86993 18.9352 6.67472 19.0281C6.73979 18.9631 6.85134 18.8236 6.79556 18.5726C6.60964 18.5726 6.78627 18.4146 6.75838 18.1264C6.60964 18.0242 6.60964 18.5633 6.44231 18.1543C6.42372 18.1264 6.38654 18.2937 6.38654 18.3867C6.28428 18.0892 6.12625 18.145 6.06117 17.8196C6.08906 17.9498 6.10765 18.0892 5.96821 18.0799C6.09836 17.9498 5.93103 17.7732 5.94032 17.6058L5.86596 17.6895C5.89384 17.5315 5.96821 17.5501 6.02399 17.5501C6.0054 17.5779 5.9961 17.6244 6.02399 17.6523C6.14484 17.6523 6.33076 17.2247 6.27498 17.0853C6.12625 17.0667 5.95892 17.327 5.91244 17.4478C5.83807 17.1782 5.44763 17.6802 5.40115 17.3548C5.36397 17.3084 5.55918 16.8529 5.50341 16.7134C5.25241 16.8064 5.48482 16.9923 5.27101 17.0667C5.56848 16.4345 4.68535 16.9551 4.78761 16.481L5.0479 16.3137C5.02001 16.2486 5.00142 16.1928 4.92705 16.1556L4.85268 16.3323C4.75972 16.3323 4.71324 16.1742 4.92705 16.0627C4.63887 16.1092 4.74113 15.9883 4.71324 15.8396C4.77831 15.9697 4.68535 15.8675 4.87127 15.8489C4.89916 15.6351 4.8062 15.6908 4.69465 15.6537C4.78761 15.5979 4.88987 15.4491 4.86198 15.4213C4.64817 15.4677 4.5738 15.3097 4.41577 15.2725L4.49013 15.2167C4.25773 15.1145 4.44365 14.6497 4.0904 14.6404C4.0904 14.6404 4.08111 14.6404 4.07181 14.6404V14.6683C3.88589 14.91 3.79293 14.6497 3.66278 14.6683C3.70926 14.6125 3.81152 14.5288 3.78363 14.4916C3.56982 14.659 3.6163 14.5102 3.49545 14.5567C3.52334 14.4359 3.76504 14.3615 3.67208 14.2685C3.6256 14.2407 3.50475 14.3243 3.42108 14.3894C3.51404 14.2778 3.55123 14.1477 3.53264 14.0733C3.60701 14.0454 3.55123 14.1384 3.57912 14.1384C3.69997 14.0547 3.6256 14.0547 3.77434 13.9432C3.75574 13.8781 3.55123 14.0826 3.57912 13.9618L3.79293 13.8874C3.82082 13.8316 3.71856 13.8502 3.69997 13.8502C3.77434 13.8502 3.94166 13.7201 4.04392 13.6364C3.81152 13.5899 3.56053 13.9618 3.36531 14.1012C3.3932 13.8595 3.08642 13.9246 2.99346 13.8223L3.21657 13.6922C3.1422 13.6643 3.07713 13.6736 2.97487 13.7201L2.9098 13.6364C3.02135 13.6364 3.09572 13.5992 3.26305 13.4784C3.1422 13.4319 3.10502 13.2832 2.81684 13.4598L2.86332 13.4319C2.87261 13.246 2.75177 12.9578 2.85402 12.902C2.6681 12.8462 2.71458 12.5674 2.4357 12.7626C2.31485 12.7347 2.64951 12.3164 2.26837 12.5116C2.38922 12.2885 2.34274 12.4558 2.56584 12.335C2.68669 12.1211 2.15682 12.3628 2.52866 12.0468C2.33344 12.0282 2.46359 12.1304 2.25907 12.2234C2.61232 11.9352 2.1847 11.991 2.32415 11.74C2.14752 11.8051 2.25907 11.8516 2.05456 11.8887C2.15682 11.833 2.13822 11.7772 2.13822 11.7493L1.89653 11.8887L2.39851 11.3868C2.01737 11.4332 2.01737 11.6935 1.77568 11.5727H1.80356C2.00808 11.3496 1.52468 11.5541 1.60835 11.2845C1.59905 11.3682 1.73849 11.2287 1.81286 11.2008L1.66412 11.1822C1.66412 11.1822 1.70131 11.1822 1.7199 11.1451C1.85005 10.9591 1.58046 11.1451 1.68272 10.9591C1.76638 10.987 1.93371 10.8476 2.00808 10.7639L1.66412 10.8197L2.01737 10.6524C1.97089 10.5222 1.33876 10.6803 1.75708 10.3363L1.84075 10.3642C1.91512 10.3084 2.13822 10.1318 1.92441 10.1597C1.86864 10.1597 1.66412 10.2619 1.70131 10.2898L1.73849 10.1876C1.97089 10.0853 2.11963 10.1876 2.23118 10.234C2.12893 10.2619 2.01737 10.234 1.89653 10.3456C2.01737 10.3828 2.2033 10.3642 2.32415 10.3921C2.22189 10.42 2.07315 10.485 1.98019 10.5222C1.92441 10.6803 2.16611 10.4943 2.23118 10.5408C2.16611 10.6245 2.11963 10.671 2.03597 10.6988C2.17541 10.7267 2.24048 10.7732 2.1847 10.9312C2.1847 10.9312 1.97089 10.9312 1.87793 11.0707C2.11034 11.1451 2.37992 11.0056 2.64021 11.0707C3.12361 11.0149 2.68669 11.5913 3.03065 11.5448C3.12361 11.489 3.12361 11.331 3.24446 11.3775C3.04924 11.4983 3.16079 11.5169 3.09572 11.5727C3.43038 11.4704 3.13291 11.7493 3.36531 11.6842C3.29094 11.7121 3.25375 11.8237 3.21657 11.898C2.98417 12.0561 3.19798 12.0654 2.77965 12.1676C3.22587 12.0561 2.87261 12.4837 3.47686 12.1955L3.51404 12.1118V12.3257V12.3164C3.51404 12.4 3.58841 12.3721 3.41179 12.6231C3.32812 12.6231 3.29094 12.5767 3.20727 12.5859C3.06783 12.8091 3.48616 12.6138 3.56053 12.6882C3.3932 12.8091 3.43968 12.6417 3.25375 12.8184C3.27235 12.8927 3.43038 12.8555 3.51404 12.8741L3.42108 12.9299C3.32812 13.2274 3.90448 12.651 3.68137 12.9857C3.72785 12.9392 3.80222 12.9113 3.8487 12.8648C3.78363 12.9764 3.69067 13.1902 3.50475 13.1809C3.54193 13.2274 3.66278 13.2274 3.78363 13.1809C3.88589 13.0415 3.81152 13.0786 3.96955 12.9299L4.22055 13.0601C4.22055 13.0601 4.11829 13.1065 4.0997 13.0786C3.80222 13.6829 4.87127 13.246 4.49943 13.9525C4.62028 13.813 4.64817 13.8688 4.75972 13.8223C4.77831 13.9432 4.91775 14.0454 4.88987 14.1942L4.76902 14.2499C5.0479 14.3615 5.31749 14.3801 5.36397 14.5567C5.41045 14.5288 5.22453 14.6683 5.16875 14.6683C5.42904 14.6218 4.94564 15.1981 5.35467 14.9193V14.8542C5.44763 15.1052 5.89384 15.0959 6.10765 15.2632C5.91244 15.4956 5.9868 15.1703 5.7544 15.4306C5.77299 15.6444 6.08906 15.6258 6.12625 15.8396C6.07977 15.8396 6.05188 15.8675 6.03328 15.8675C6.0054 16.1371 6.2471 15.663 6.32146 15.821C6.20061 15.9047 6.18202 15.9325 6.15413 16.0255L6.36794 15.9139C6.36794 15.9139 6.20061 16.0627 6.13554 16.0906C6.41442 15.9418 6.36794 16.2114 6.59105 16.0348C6.54457 16.0999 6.34006 16.2765 6.27498 16.3695C6.27498 16.4996 6.37724 16.4531 6.4795 16.3973C6.38654 16.6019 6.48879 16.6855 6.45161 16.6948C6.48879 16.89 6.56316 16.574 6.7212 16.481L6.73979 16.2951L6.86993 16.3509L6.75838 16.4438C6.74908 16.6112 6.92571 16.4252 6.96289 16.481L7.01867 16.2765C7.01867 16.2765 7.08374 16.2393 7.11163 16.2207C6.97219 16.6019 7.14882 16.388 6.96289 16.7971C7.03726 17.1596 7.24178 16.7041 7.32544 16.7506C7.30685 16.732 7.30685 16.8343 7.28826 16.9086C7.33474 17.0853 7.39981 16.8807 7.43699 16.6483C7.4184 16.7971 7.40911 16.8436 7.39051 16.9644C7.45559 17.0481 7.44629 16.7227 7.51136 16.6297C7.49277 16.8343 7.49277 16.9551 7.51136 17.0295C7.51136 16.8343 7.52996 16.7041 7.53925 16.6669C7.48347 17.6802 7.62292 17.2061 7.60432 18.0428C7.61362 17.8289 7.71588 17.4757 7.6508 16.9644V17.0295C7.62292 16.7134 7.6508 16.8621 7.6601 16.8529C7.6601 16.8993 7.6508 16.9551 7.6601 17.0202C7.68799 16.89 7.72517 16.9365 7.74377 16.9179C7.76236 16.8622 7.78095 16.8343 7.79025 16.7506C7.79025 16.7041 7.79954 16.6483 7.79954 16.574C7.81813 16.6948 7.82743 16.9458 7.85532 17.0016C7.94828 17.0016 7.88321 16.3695 7.85532 16.0627C8.03194 16.6205 7.82743 16.2579 7.96687 16.8436C8.01335 16.5368 8.03194 16.1928 7.96687 15.8582C8.15279 16.1649 8.1435 16.0534 8.11561 15.9418C8.08772 15.821 8.04124 15.7187 8.23646 15.8768C8.08772 15.7094 8.05983 15.6165 8.06913 15.5793C8.18998 15.7187 8.21787 15.6815 8.30153 15.7745C8.24575 15.6815 8.20857 15.6072 8.23646 15.5793C8.25505 15.57 8.39449 15.5142 8.55253 15.663C8.23646 15.3934 8.70126 15.4956 8.52464 15.2539C8.72915 15.2446 8.62689 14.975 8.83141 14.9286C8.59901 14.8077 8.8407 14.7241 8.79422 14.6125C8.79422 14.6404 8.79422 14.6869 8.83141 14.7055C9.02663 14.8077 8.80352 14.4359 8.97085 14.4545C9.06381 14.4824 9.13818 14.6218 9.20325 14.5846C9.06381 14.4638 9.07311 14.1384 9.29621 14.2221C9.26832 14.2499 9.3334 14.315 9.37058 14.3801C9.42636 13.8502 10.0213 13.7851 10.0585 13.2274L10.2165 13.497C10.6813 13.5899 9.98412 13.0136 10.17 12.8927C10.6906 12.5952 11.425 12.5209 11.6853 12.0003C11.6574 11.9073 11.5923 11.9352 11.4994 11.8423C11.5645 11.8423 11.7411 12.0189 11.6853 11.8516L11.5645 11.74C12.0479 11.898 11.8898 11.0242 12.5034 11.4146C12.5034 11.0614 12.931 11.2752 12.8752 10.7918C13.0425 10.8383 12.9868 11.0707 13.1076 11.0242L13.1355 10.6524V10.6803C13.0054 10.1411 14.0186 10.6245 14.0279 10.1504V10.1783C14.1023 10.2712 14.251 10.327 14.2603 10.2619C14.2231 10.1876 14.1674 10.1783 14.0744 10.1318C14.1581 9.79712 14.2045 9.74135 14.3533 9.56472C14.3905 9.75994 14.5206 9.6112 14.6879 9.78783C14.6322 9.62979 14.502 9.62979 14.5113 9.44387C14.6415 9.29513 14.911 9.33232 15.0784 9.29513C14.9854 9.09062 15.0877 9.08132 14.9203 8.88611C15.0691 8.72807 15.097 8.57004 15.2922 8.40271L15.3573 8.46778C15.1992 8.1796 15.6361 8.43989 15.5525 8.26327C15.6268 8.35623 15.6361 8.41201 15.7012 8.46778L15.7198 8.30975C15.7384 8.4213 15.9243 8.6723 16.0173 8.63511C15.9429 8.39341 15.8964 8.53285 15.8035 8.36552L16.0266 8.57004C16.0638 8.49567 15.85 8.22608 15.7198 8.21679C15.9243 8.04016 16.0266 7.76128 16.2311 7.64043L16.3426 7.80776C16.3891 7.66832 16.5286 7.54747 16.6959 7.63113C16.6587 7.58465 16.6122 7.4824 16.5565 7.44521C16.5007 7.13844 16.7796 7.67761 16.7238 7.35225C16.7424 7.43592 16.7238 7.50099 16.7982 7.59395L16.8818 7.20351C16.9841 7.31507 17.3466 7.43592 17.3559 7.24999C17.3094 7.18492 17.2072 7.12914 17.17 7.13844L17.1886 7.02689L17.4675 7.2407L17.3652 6.93393L17.5511 7.14774C17.579 7.04548 17.3745 6.73871 17.4396 6.71082C17.7742 6.66434 17.7928 6.77589 18.1182 6.85026C17.7742 6.42264 18.3692 6.66434 18.1554 6.32968C18.6202 6.46912 18.7503 6.03221 19.0943 5.89277V5.94854C19.3825 6.0415 18.9641 5.52092 19.1594 5.50233L19.178 5.58599C19.5219 5.67896 19.6242 5.24204 19.6242 4.93527C19.6428 5.01893 19.7729 5.13978 19.8101 5.0933C19.7822 4.98175 19.5219 4.83301 19.6706 4.84231C19.6799 4.89808 19.7822 4.98175 19.8008 4.96316L19.7078 4.68427C20.0425 4.64709 20.4236 4.58202 20.5445 4.26595C20.6467 4.30313 20.6839 4.40539 20.7304 4.48906C20.8698 4.29384 20.8977 3.96847 21.0279 3.80115L21.251 4.03355C21.3254 3.96847 20.9907 3.62452 21.2696 3.75466C21.3161 3.76396 21.2138 3.82903 21.2696 3.95918C21.5856 4.00566 21.1673 3.64311 21.3346 3.54085L21.5299 3.84763C21.7809 3.9127 21.5392 3.59663 21.4462 3.39212C21.3346 2.93661 22.004 3.81974 22.0226 3.39212C21.9482 3.22479 21.8459 3.2062 21.7623 3.03887C21.9761 2.98309 21.8366 2.76928 22.0504 2.7135C22.4781 3.04816 21.9668 2.77858 22.3851 3.08535H22.1899C22.4688 3.22479 22.1434 3.22479 22.3665 3.45719C22.506 3.45719 22.4502 3.15971 22.4781 2.99239C22.6361 3.17831 22.3758 3.11323 22.6361 3.31775V3.1969C22.6547 3.26197 22.7105 3.33634 22.6733 3.35493C22.8313 3.51297 22.7384 3.31775 22.7848 3.27127C22.7105 3.16901 22.5896 3.03887 22.4688 2.92731C22.4874 2.9459 22.506 2.9645 22.5338 2.98309C22.413 2.63913 22.7477 2.69491 22.664 2.41603C22.6919 2.4811 22.7198 2.4904 22.7569 2.52758C22.822 2.4904 22.6826 2.19292 22.7105 2.05348C22.8685 2.15574 23.0265 2.4811 23.0916 2.29518C22.9894 2.12785 22.7105 1.91404 22.822 1.82108C22.822 1.82108 22.822 2.02559 22.9708 2.09066L22.9801 2.12785ZM20.8327 4.54483C20.8327 4.54483 20.8048 4.57272 20.7862 4.60061C20.7862 4.60061 20.8141 4.55413 20.8234 4.54483H20.8327ZM20.7769 4.8702C20.7769 4.8702 20.749 4.77723 20.6839 4.71216C20.6467 4.74005 20.6188 4.76794 20.5817 4.78653C20.6653 4.81442 20.749 4.81442 20.7769 4.8702ZM22.1341 5.67896L22.1527 5.70684C22.1527 5.70684 22.1248 5.76262 22.1155 5.78121C22.1527 5.8184 22.1992 5.84628 22.2085 5.79051C22.1899 5.76262 22.162 5.71614 22.1341 5.67896Z\" fill=\"#8F3A7E\"><\/path><path d=\"M22.0416 5.47307C22.0416 5.47307 22.0416 5.45466 22.0416 5.44546C22.0231 5.43626 22.0047 5.42705 21.9863 5.41785L22.0231 5.49148L22.0416 5.47307Z\" fill=\"#8F3A7E\"><\/path><path d=\"M4.04395 14.6689C4.04395 14.6689 4.05317 14.6597 4.06239 14.6413C4.06239 14.6505 4.05317 14.6597 4.04395 14.6689Z\" fill=\"#8F3A7E\"><\/path><path d=\"M17.3184 6.90505L17.365 6.96105L17.3464 6.89572L17.3184 6.90505Z\" fill=\"#8F3A7E\"><\/path><path d=\"M3.82129 12.9043C3.82129 12.9043 3.84973 12.8664 3.85921 12.8474C3.84973 12.8569 3.83077 12.8759 3.82129 12.9043Z\" fill=\"#8F3A7E\"><\/path><path d=\"M3.47742 12.3441L3.49602 12.2139C3.47742 12.279 3.47742 12.3162 3.47742 12.3441Z\" fill=\"#8F3A7E\"><\/path><path d=\"M3.28078 11.8598C3.28078 11.8598 3.21608 11.8967 3.18835 11.9152L3.28078 11.8598Z\" fill=\"#8F3A7E\"><\/path><path d=\"M6.45996 16.4436C6.45996 16.4436 6.54407 16.3969 6.57211 16.3875C6.57211 16.3408 6.55342 16.3221 6.45996 16.4436Z\" fill=\"#8F3A7E\"><\/path><path d=\"M6.62872 16.4611C6.62872 16.3873 6.6195 16.3781 6.57336 16.3873C6.57336 16.4242 6.58259 16.4703 6.62872 16.4611Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.17539 10.0107V9.98242C2.17539 9.98242 2.14712 10.0013 2.1377 10.0013H2.17539V10.0107Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.12949 10.0114H2.0918C2.0918 10.0114 2.10122 10.0208 2.12949 10.0114Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.00806 9.99291H2.09124C2.09124 9.99291 2.07275 9.96519 2.00806 9.99291Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.41699 10.6243L2.50017 10.5781C2.50017 10.5781 2.45396 10.5966 2.41699 10.6243Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.55659 10.7733C2.55659 10.7177 2.65855 10.5601 2.57513 10.5416L2.51025 10.5787C2.64001 10.5231 2.39903 10.8289 2.55659 10.7733Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.07381 12.1401L2.0366 11.9541C1.97149 12.0378 1.88778 12.1494 1.82268 12.0936C1.70176 12.4471 1.9808 11.9262 2.08311 12.1401H2.07381Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.27776 12.6685C2.18469 12.622 2.15677 12.7523 2.11023 12.7895C2.22192 12.7895 2.24984 12.7895 2.27776 12.6685Z\" fill=\"#8F3A7E\"><\/path><path d=\"M4.62895 15.747L4.43384 15.8864C4.50817 15.9235 4.50817 15.8306 4.62895 15.747Z\" fill=\"#8F3A7E\"><\/path><path d=\"M6.05145 15.5506L6.11649 15.4112L5.93066 15.5134L6.05145 15.5506Z\" fill=\"#8F3A7E\"><\/path><path d=\"M5.00248 16.9545H4.95605C5.00248 16.9638 5.0489 16.973 5.10461 17.0009C5.05819 16.973 5.03962 16.973 5.00248 16.9545Z\" fill=\"#8F3A7E\"><\/path><path d=\"M10.2145 16.5729L9.97351 16.4061C9.98278 16.471 10.2423 16.6842 10.2145 16.5729Z\" fill=\"#8F3A7E\"><\/path><path d=\"M11.8059 14.4079C11.9267 14.4915 12.0475 14.5101 11.9824 14.3708C11.9267 14.3986 11.7966 14.3615 11.8059 14.4079Z\" fill=\"#8F3A7E\"><\/path><path d=\"M18.3037 9.16579L18.3223 9.2774L18.3502 9.14719L18.3037 9.16579Z\" fill=\"#8F3A7E\"><\/path><path d=\"M1.64564 9.73384C1.52494 9.65027 1.46923 9.91025 1.50637 9.71527C1.6085 9.67813 1.69207 9.65956 1.64564 9.73384Z\" fill=\"#8F3A7E\"><\/path><path d=\"M25.5929 1.03314C25.7137 1.86049 24.812 1.67457 24.7376 2.32529C24.7097 2.38107 24.4959 2.01852 24.4587 2.16726C24.4587 2.88306 23.6872 3.09687 22.9807 3.13405L22.9342 3.0318C22.804 3.0318 22.9342 3.40364 22.8133 3.44083C22.7669 3.38505 22.7761 3.33857 22.6925 3.28279C22.8133 3.46871 22.5995 3.4966 22.6646 3.64534C22.5716 3.60815 22.4694 3.46871 22.3578 3.43153L22.4694 3.66393C22.7111 4.23099 22.1068 3.91493 22.1161 4.30536C22.0882 4.24959 22.0789 4.2031 22.0232 4.17522C21.9488 4.70509 21.5305 4.97468 21.2795 5.36512C21.233 5.29075 21.14 5.15131 21.0564 5.09553C21.2051 5.30934 21.1493 5.44878 21.0936 5.56963C20.8797 5.393 21.0936 5.8857 20.8983 5.8671L20.8704 5.81133C20.9727 6.09021 20.6473 5.78344 20.8054 6.09951L20.6195 5.97866C20.8333 6.29472 20.3778 5.92288 20.4428 6.1274L20.4986 6.18317C20.4986 6.30402 20.3406 6.18317 20.3313 6.28543L20.2941 6.25754C20.229 6.44346 20.0152 6.3505 20.2104 6.57361C20.0059 6.43417 20.2662 6.37839 19.9687 6.18317C19.7363 6.78742 19.2436 7.12208 18.816 7.50322C18.6859 7.45674 18.6301 7.45674 18.5464 7.38237C18.5464 7.46603 18.4163 7.56829 18.4814 7.71703C18.4906 7.69843 18.3512 7.62407 18.3233 7.63336C18.1746 7.61477 18.4535 7.95872 18.2768 7.93084C18.2582 7.83788 18.2118 7.75421 18.1281 7.67984C18.2025 7.92154 18.0816 7.97732 18.0444 8.10746C18.0258 8.06098 18.0258 8.0145 17.9608 7.94943C18.0351 8.22831 17.747 8.06098 17.7749 8.2562L17.6912 8.09817C17.4216 8.06098 17.8864 8.40494 17.6912 8.41423C17.6912 8.34916 17.6261 8.30268 17.5889 8.2469C17.6819 8.58156 17.4402 8.65593 17.403 8.82326C17.403 8.79537 17.3658 8.76749 17.3658 8.76749C17.2729 8.89763 17.0869 8.93481 17.0498 9.14862C16.9475 9.13003 16.7895 8.82326 16.7058 8.98129C16.9382 9.23229 16.585 9.27877 16.9196 9.50188C16.7802 9.54836 16.5199 9.60413 16.5292 9.75287C16.492 9.61343 16.1945 9.48328 16.2689 9.38103L16.0644 9.28807C15.9807 9.17651 16.1666 9.26018 16.0272 9.14862C15.99 9.19511 15.9528 9.41821 15.8784 9.40891C15.9342 9.64132 16.1201 10.0039 16.0179 10.1526C15.99 9.99457 15.7297 9.90161 15.7297 9.81794L15.9807 10.478C15.9435 10.5337 15.7855 10.2827 15.7855 10.4036C15.8506 10.4687 15.8599 10.5337 15.8877 10.6081C15.8413 10.5895 15.7669 10.8312 15.5159 10.6081C15.4043 10.5244 15.5438 10.4873 15.4136 10.4408C15.3393 10.5151 15.4136 10.6081 15.33 10.6825L15.3021 10.6546C15.2184 10.6639 15.237 10.9056 15.4229 10.9892C15.4694 10.9614 15.2742 10.8498 15.3951 10.8777C15.488 11.0543 15.4322 11.1845 15.3579 11.2588C15.3579 11.1938 15.2835 11.1287 15.2277 11.045C15.3021 11.3425 15.237 11.5098 15.1905 11.6958C15.2928 11.8166 15.0418 11.4355 15.1162 11.4819C14.8094 11.4541 15.0139 12.0118 14.6607 11.8817C14.6607 11.8445 14.828 12.0397 14.7908 12.0118C14.7071 12.0676 14.5491 11.891 14.5584 11.9932C14.4654 11.891 14.5305 12.0769 14.5026 12.1606C14.5398 12.2535 14.4469 12.1234 14.4747 12.0676C14.4747 12.2163 14.3446 12.6254 14.0564 12.6254C14.1215 12.6904 14.1866 12.96 14.1401 12.9879L14.0099 12.8206C13.8891 12.7555 13.8984 12.9507 13.7682 12.8206C13.8612 13.0809 13.9263 12.3837 13.9542 12.6254C13.8054 12.5231 14.0378 13.0065 13.8612 12.7741C13.7961 12.8485 13.8798 13.0902 13.6753 13.0065C13.7218 13.0065 13.5358 12.7369 13.4894 12.802C13.4057 12.9228 13.5265 12.9042 13.4894 13.0344V13.1459C13.6288 13.304 13.3871 13.211 13.5823 13.3412C13.4522 13.2296 13.4986 13.555 13.2755 13.2947L13.1082 13.0809C13.0803 13.1366 13.2291 13.3598 13.2755 13.4806C13.257 13.4713 13.2012 13.4341 13.1733 13.4062C13.4429 13.713 13.0431 13.4806 13.2105 13.7688C13.0153 13.7502 12.9595 13.9826 12.7364 13.8339C12.7457 13.9919 12.7829 14.1592 12.6434 14.1778C12.6341 14.1313 12.6434 14.1034 12.5876 14.0384C12.4575 14.0012 12.5133 14.0848 12.5133 14.1778C12.4854 14.122 12.2437 14.1034 12.0856 14.0477C12.1042 14.2057 12.2809 14.3451 12.3645 14.4474C12.0206 14.215 12.3459 14.8285 12.0113 14.6333C11.9927 14.5682 11.9741 14.3916 11.8439 14.373C11.5 14.1406 11.9276 14.717 11.6859 14.6705L11.9462 14.8843C11.751 14.7821 11.9369 15.1725 11.7045 14.9122C11.7603 15.033 11.5093 14.9494 11.751 15.1725C11.3884 15.1446 11.4814 15.6838 10.9608 15.3863C10.9794 15.4514 10.8772 15.47 11.0166 15.5722C11.1839 15.6559 10.9701 15.4235 11.0817 15.4979C11.0724 15.5257 11.1281 15.5908 11.1653 15.628C11.0631 15.628 11.0073 15.6559 10.8493 15.4142C10.589 15.3956 11.1467 15.9162 10.9236 15.972C10.8307 15.8697 10.7749 15.8511 10.7563 15.9069L10.8586 16.1393C10.7377 16.1951 10.5797 15.9905 10.3938 15.8418C10.3752 15.9162 10.3101 15.9812 10.4309 16.1114L10.1521 15.9905C10.3566 16.0742 10.2264 16.1207 10.245 16.1858L10.2171 16.1207C10.1335 16.0649 10.1242 16.1672 10.1242 16.2229C10.245 16.3066 10.338 16.2787 10.4031 16.2694C10.4588 16.3624 10.4031 16.3903 10.4681 16.5018C10.3008 16.3438 10.2729 16.4832 10.2264 16.5111C10.1521 16.5297 10.3473 16.6878 10.3287 16.697C10.2357 16.6227 10.2543 16.7621 10.1521 16.6227C10.1335 16.5855 10.2729 16.6506 10.2078 16.5669C10.1149 16.5483 9.95684 16.4182 10.0219 16.5669C10.0684 16.6878 10.3845 16.8272 10.1985 16.8365C10.1706 16.7807 10.1056 16.7156 10.0498 16.6506L9.89177 16.6692L10.0591 16.7993C10.0126 16.7807 10.0033 16.7621 9.97543 16.7528C10.1428 16.8923 9.90106 16.9666 10.0591 17.1711C10.0219 17.2641 9.83599 17.2455 9.77092 17.3106V17.2827C9.62218 17.2827 9.61288 17.4686 9.65936 17.6638L9.63148 17.6267C9.63148 17.6267 9.53852 17.8033 9.585 18.0078C9.41767 18.0264 9.06442 17.3199 9.15738 17.7196C9.1016 17.8498 9.28752 18.3425 9.38978 18.4261C9.18526 18.5284 9.23174 19.3743 8.94357 19.207C8.97145 19.3743 9.00864 19.4208 8.99005 19.5974C8.77624 19.9228 8.70187 21.1313 8.42298 20.6851C8.44158 20.3783 8.35791 20.2482 8.31143 19.9972C8.33002 20.3597 8.26495 20.0158 8.26495 20.1087C8.26495 20.1366 8.27425 20.211 8.29284 20.3783C8.33002 20.6014 8.34862 20.7594 8.3765 20.8896C8.3951 20.9732 8.41369 21.029 8.45087 21.0383C8.45087 21.0941 8.43228 21.1406 8.42298 21.2057C8.36721 21.2428 8.30214 21.2149 8.22777 21.1499C8.19058 21.1127 8.16269 21.0662 8.12551 21.0197C8.08833 20.9454 8.05114 20.8524 8.03255 20.7687C8.08833 20.9732 8.06973 21.029 8.03255 21.0848C7.99536 20.5828 7.88381 20.3783 7.80015 20.4434V20.7316L7.72578 20.3597C7.69789 20.4155 7.70719 20.9268 7.60493 20.5363C7.60493 20.4248 7.58634 20.3039 7.57704 20.2017C7.49338 20.3318 7.33534 20.5363 7.24238 20.1831L7.17731 19.6997C7.17731 19.6997 7.03787 19.8298 7.11224 20.025C6.9542 19.5881 6.84265 19.4301 6.84265 19.0768C6.44292 19.4673 5.89445 18.863 5.55049 18.3796L5.63416 18.2681C5.60627 18.0357 5.44824 18.4168 5.42964 18.2495C5.5319 18.1751 5.5226 17.9241 5.68064 17.8684C5.64345 17.5988 5.38316 17.8684 5.25302 17.8126C5.12287 17.9427 5.39246 17.8126 5.23443 17.9706C5.17865 17.9985 5.14146 17.636 4.93695 17.8126C4.97413 17.6917 5.14147 17.5802 5.23443 17.5151H5.0671C5.20654 17.1897 5.66205 17.3478 5.82938 16.9387L5.74571 16.9016C5.89445 16.6413 6.09896 16.8272 6.04319 16.6041C5.90374 16.6413 5.55979 16.8458 5.5412 17.0038C5.35528 16.8923 5.00202 17.3664 4.85329 17.1433C4.92765 16.9852 5.02062 17.2827 5.15076 17.0968C5.23443 16.8551 4.91836 17.0038 4.93695 16.9016C4.90906 17.0317 4.64877 17.1433 4.5837 17.134C4.62088 16.9852 4.8161 17.0224 4.76032 16.9016C4.62088 16.9852 4.46285 16.9666 4.44426 17.1154C4.13749 17.3013 4.44426 16.948 4.17467 17.0689C4.342 16.883 4.70455 16.8086 4.71384 16.6227C4.53722 16.79 4.3513 16.6878 4.11889 16.9759C4.13749 16.8923 4.27693 16.7621 4.42567 16.7063C4.49074 16.5483 3.96086 16.8272 4.31411 16.5111L4.1096 16.6413C4.15608 16.5762 4.18397 16.5018 4.25834 16.3903C4.22115 16.3345 3.8586 16.4182 4.14678 16.1951C4.1003 16.1951 4.01664 16.0649 3.84931 16.2694C3.79353 16.4461 4.06312 16.2415 3.83072 16.5018C4.00734 16.2694 3.70987 16.4089 3.59831 16.4275L3.70057 16.3345C3.6355 16.3345 3.60761 16.2601 3.47746 16.3345C3.56113 16.3066 3.6262 16.2322 3.6355 16.1858L3.44028 16.288C3.26365 16.2415 3.71916 16.0277 3.58902 15.9534L3.78424 15.9255C3.78424 15.9255 3.8772 15.7674 3.78424 15.7581C3.60761 15.8604 3.3938 15.972 3.26365 16.0463C3.1521 16.0463 3.42169 15.879 3.20788 15.9441L3.45887 15.8697C3.52395 15.8418 3.67268 15.6094 3.60761 15.535C3.51465 15.535 3.22647 15.6187 3.19858 15.7674C3.1614 15.7303 3.21717 15.6001 3.35662 15.5443C3.22647 15.4979 3.19858 15.6838 3.04055 15.6838C3.11492 15.5722 3.18929 15.3491 3.29154 15.1725L3.61691 15.0516L3.57972 14.9959C3.84931 14.9029 3.70987 14.8378 3.96086 14.6984C3.96086 14.6333 3.8586 14.6519 3.77494 14.6519C3.50535 15.0423 3.18929 14.9029 2.89181 15.1911C2.6873 15.1074 3.60761 14.4846 2.97548 14.717C2.9104 14.8099 2.60363 14.9215 2.77096 14.9494C2.73378 14.8285 2.39912 15.1353 2.4456 14.9215C2.64082 14.9029 2.70589 14.5775 2.99407 14.5497C2.88252 14.624 2.96618 14.6798 3.01266 14.6705C3.10562 14.5404 3.34732 14.4288 3.27295 14.3265C3.19858 14.2894 3.12421 14.215 2.96618 14.3544C2.78026 14.5032 3.05914 14.4288 2.83603 14.5404C2.678 14.4753 2.94759 14.2336 2.58504 14.4381C2.6687 14.4939 2.49208 14.6612 2.36193 14.7542L2.2132 14.7263L2.35264 14.6519C2.33405 14.4474 2.09235 14.7821 2.02727 14.624L2.22249 14.373C2.45489 14.2429 2.27827 14.6426 2.60363 14.3544C2.54786 14.2522 2.35264 14.3544 2.38053 14.2057C2.42701 14.2057 2.45489 14.2243 2.49208 14.215C2.48278 14.1778 2.9104 13.7967 2.54786 13.871C2.39912 13.8896 2.40841 13.9454 2.27827 14.0384C2.12953 13.9268 1.9715 13.9826 1.87854 13.9082C2.14812 13.7409 1.78558 13.7316 2.12024 13.6386C2.00868 13.7967 2.17601 13.9919 2.45489 13.8617C2.71519 13.5829 2.50138 14.0012 2.82674 13.806C2.75237 13.6851 3.04984 13.4713 3.22647 13.304C3.21717 13.2668 3.11492 13.2947 3.06844 13.304C2.87322 13.4248 2.9104 13.462 2.72448 13.6107C2.678 13.4434 2.49208 13.3969 2.25968 13.462C2.31545 13.3505 2.51067 13.2296 2.56645 13.2668C2.39912 13.1552 2.30616 12.9786 2.25968 12.7927C2.02727 13.1088 2.07376 12.6811 1.86924 12.9321C1.85995 13.0623 1.69262 13.2854 1.52529 13.3412C1.50669 13.2761 1.65543 13.2482 1.71121 13.1831C1.4974 13.2389 1.90643 12.8949 1.59965 13.0251C1.79487 13.0995 1.99009 12.7834 2.24108 12.644C2.03657 12.644 2.40841 12.5231 2.34334 12.4301C2.13883 12.4301 1.94361 12.3744 1.81346 12.3C1.94361 12.0025 1.56247 11.9375 1.46951 11.8166C1.54388 11.6679 1.85065 11.5284 1.84135 11.4262C1.77628 11.3425 1.59036 11.6865 1.62754 11.4819L1.69262 11.4541C1.59965 11.4541 1.7205 11.1008 1.30218 11.3239L1.62754 11.1659C1.62754 11.1659 1.55317 11.1473 1.51599 11.1473C1.60895 11.0822 1.68332 10.9985 1.76698 10.9892C1.92502 10.7754 1.62754 10.8498 1.56247 10.7661L1.42303 10.9335C1.19063 10.8777 1.30218 10.6639 1.15344 10.5616L1.33007 10.4594L1.17203 10.4408C1.35796 10.3571 1.42303 10.2177 1.2464 10.2549L1.81346 10.2084C1.74839 10.3292 1.56247 10.2735 1.41373 10.4129C1.28359 10.5337 1.41373 10.6453 1.59036 10.5523C1.58106 10.4873 1.53458 10.5152 1.45092 10.5152C1.68332 10.3478 1.7205 10.4315 1.90643 10.3664C1.87854 10.3478 1.93431 10.2642 1.85065 10.3106C1.99939 10.2827 2.05516 10.3292 2.11094 10.4036C1.98079 10.4036 1.98079 10.5337 1.89713 10.5523C2.11094 10.4222 2.23179 10.4594 2.24108 10.5988C2.04587 10.8312 2.52926 10.6825 2.53856 10.8498C2.29686 10.9428 2.08305 10.9985 1.95291 10.98C1.89713 11.1287 2.01798 11.0636 1.95291 11.2124C2.13883 11.138 2.38982 11.0078 2.55715 11.0357L2.40841 11.1473C2.54786 11.1845 2.78026 11.0171 2.80815 11.1566C2.86392 11.3983 3.00336 11.5935 3.08703 11.7515L2.93829 11.8631C3.31943 11.705 3.25436 12.0397 3.47746 12.0397C3.46817 12.3279 3.91438 12.3279 3.71916 12.6161C4.07241 12.8485 4.39778 13.0437 4.593 13.4062L4.3327 13.5178C4.53722 13.4527 4.23974 13.6479 4.31411 13.6851C4.43496 13.4806 4.60229 13.5922 4.76962 13.5271C4.71384 13.806 5.03921 13.8524 5.2902 13.8617L5.14146 13.9826C5.5226 13.8896 5.40176 14.2429 5.48542 14.4381C5.43894 14.5032 5.31809 14.6426 5.37387 14.6798C5.68064 14.5775 5.69923 14.6333 5.95022 14.6426C6.02459 14.7356 6.08967 14.9308 6.07107 15.1074C6.37784 15.1446 6.55447 15.3026 6.7125 15.47C6.80546 15.5722 6.84265 15.6094 6.87983 15.6373C6.92631 15.6652 6.98209 15.6838 7.05646 15.6745L6.92631 15.8697C7.14942 15.7674 7.1866 15.7953 7.24238 15.8883C7.28886 15.972 7.34464 16.1114 7.40971 15.9998L7.32605 16.4925C7.34464 16.7063 7.4283 16.4646 7.4469 16.0649C7.46549 16.2694 7.51197 15.8604 7.53056 16.3624C7.56774 16.5111 7.56774 16.13 7.57704 16.0649C7.60493 16.2137 7.63282 16.288 7.65141 16.3066C7.67 16.3066 7.67 16.2137 7.67 16.13V16.1021C7.67 16.2508 7.70719 16.5297 7.72578 16.5483C7.72578 16.4739 7.72578 16.4554 7.72578 16.4368C7.73507 16.3996 7.74437 16.3438 7.6607 15.8976C7.70719 16.0742 7.71648 15.9441 7.71648 15.8511C7.71648 15.7581 7.71648 15.6931 7.80944 15.879C7.75367 15.7303 7.75367 15.6931 7.71648 15.5908C7.72578 15.5536 7.9024 15.7488 7.80015 15.5071C7.84663 15.5536 7.9117 15.7117 7.93959 15.7024C7.921 15.6466 7.84663 15.5536 7.80944 15.4793C7.76296 15.3491 7.80944 15.377 7.89311 15.3956C7.93959 15.4607 8.19988 15.2747 8.27425 15.1353C8.47876 14.4753 9.01793 14.057 9.39907 13.6015L9.46415 13.6665C9.35259 13.2761 10.0405 13.5829 9.78021 13.1088C9.87317 13.1366 9.93825 13.0158 10.0312 13.1645C9.96614 12.8857 10.496 13.0251 10.4402 12.6532C10.4216 12.6532 10.4216 12.6811 10.4402 12.7276C10.7377 12.7183 10.6912 12.3837 10.9887 12.3558C10.998 12.4023 10.9887 12.4487 11.0445 12.5231C11.2304 12.5882 10.9329 12.0955 11.2676 12.3837C11.3048 12.3465 11.1467 12.1977 11.1281 12.2256C11.6115 12.0118 11.8161 11.4355 12.1321 11.0078C12.5876 10.9428 12.6434 11.5377 12.6434 11.0915C12.7178 11.138 12.5412 10.9521 12.6062 11.0171C12.6062 10.8498 13.071 11.2588 12.9688 11.0357C12.7643 10.8591 12.9037 10.887 12.8014 10.7661C13.0896 10.7383 13.2848 10.887 13.2848 10.6174L13.3685 10.729C13.257 10.292 13.5823 10.2827 13.4057 9.81794C14.2237 8.972 14.8838 8.03309 15.7111 7.24293C16.6221 6.56431 17.3193 5.69048 18.3419 5.13271C18.7881 5.24427 18.7974 5.21638 18.9183 4.9189C18.9462 4.97468 18.9462 4.99327 18.9926 5.02116C18.8067 4.77946 19.1321 4.86313 18.9647 4.62143C19.3273 4.38903 19.569 4.07296 19.8944 3.79408C19.8665 3.85915 19.9966 4.07296 20.0431 4.00789L19.978 3.80337L20.0431 3.85915C20.0524 3.78478 20.0059 3.63604 19.8944 3.59886C20.5544 2.69714 21.7722 2.47403 22.5437 1.73034C22.8226 1.66527 23.0178 1.34921 23.1945 1.1168C24.0776 0.902993 24.8492 0.689183 25.3047 -0.0545044C25.3047 -0.0545044 25.723 0.62411 25.5836 0.977361L25.5929 1.03314Z\" fill=\"#8F3A7E\"><\/path><path d=\"M1.7481 9.85501C1.62739 9.95715 1.59954 10.0778 1.38599 10.115C1.50669 10.0314 1.61811 9.91072 1.7481 9.85501Z\" fill=\"#8F3A7E\"><\/path><path d=\"M1.8506 12.8295C1.8506 12.8295 1.82275 12.8945 1.80418 12.9131C1.77632 12.8945 1.65562 12.9409 1.70204 12.8759C1.7299 12.8945 1.78561 12.8481 1.8506 12.8202V12.8295Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.16678 13.4147C2.05536 13.489 1.87895 13.4425 1.82324 13.3775L2.16678 13.4147Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.08289 14.2437C2.02718 14.3551 1.96219 14.383 1.92505 14.318C1.98076 14.2715 2.02718 14.2715 2.08289 14.2437Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.35372 14.0857C2.35372 14.0857 2.33511 14.188 2.28857 14.2625C2.38165 14.188 2.15827 14.216 2.35372 14.0857Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.84607 15.3857C2.84607 15.3857 3.00391 15.3857 2.90178 15.5064C2.96677 15.4135 2.66966 15.4878 2.84607 15.3857Z\" fill=\"#8F3A7E\"><\/path><path d=\"M3.39329 15.7397C3.39329 15.7397 3.384 15.7861 3.43043 15.7769C3.40257 15.8418 3.30044 15.879 3.27258 15.8604L3.39329 15.7397Z\" fill=\"#8F3A7E\"><\/path><path d=\"M11.9369 14.7541L11.9462 14.8467L11.8535 14.7448L11.9369 14.7541Z\" fill=\"#8F3A7E\"><\/path><path d=\"M15.4611 11.4917C15.4611 11.3803 15.5818 11.5567 15.6003 11.5659C15.5632 11.6124 15.5075 11.4267 15.4611 11.4917Z\" fill=\"#8F3A7E\"><\/path><path d=\"M16.957 9.2601L16.9477 9.27864L16.7716 9.06546L16.957 9.2601Z\" fill=\"#8F3A7E\"><\/path><path d=\"M26.4111 1.45928C26.4761 1.32929 26.2068 1.32001 26.4111 1.32001C26.4668 1.41286 26.5039 1.49642 26.4111 1.45928Z\" fill=\"#8F3A7E\"><\/path><path d=\"M1.08847 10.4673C1.92512 10.4673 1.62764 11.3319 2.27837 11.4713C2.33415 11.4992 1.95301 11.6851 2.10174 11.7316C2.81754 11.7967 2.97558 12.5682 2.97558 13.2747L2.86402 13.3119C2.86402 13.4514 3.23587 13.3305 3.26375 13.4514C3.20798 13.4979 3.1615 13.4886 3.09642 13.5629C3.29164 13.4514 3.30094 13.6652 3.45897 13.6094C3.42179 13.6931 3.27305 13.7953 3.23587 13.9069L3.47756 13.8046C4.06322 13.5908 3.70997 14.1765 4.1097 14.1858C4.05392 14.2137 4.00744 14.2229 3.97026 14.2694C4.50013 14.3624 4.75113 14.79 5.13227 15.0596C5.0486 15.0968 4.91846 15.1897 4.85338 15.2734C5.07649 15.1247 5.20664 15.1897 5.32749 15.2548C5.15086 15.4686 5.64355 15.2548 5.61566 15.4593L5.55989 15.4872C5.84807 15.3943 5.532 15.7103 5.84807 15.5616L5.72722 15.7475C6.05258 15.543 5.66214 15.9892 5.86666 15.9334L5.92244 15.8777C6.04328 15.8777 5.92244 16.0357 6.0154 16.0543L5.98751 16.0915C6.17343 16.1658 6.06188 16.361 6.28498 16.1658C6.14554 16.3703 6.10836 16.1193 5.90384 16.4168C6.4895 16.6492 6.74049 17.049 7.08445 17.458C7.08445 17.6532 7.11233 17.7369 7.10304 17.8949C7.14952 17.8577 7.25178 17.9879 7.30755 17.8112C7.29826 17.8112 7.30755 18.0529 7.33544 18.0994C7.40051 18.3504 7.4284 17.6997 7.48418 17.9786C7.45629 18.0715 7.4377 18.2017 7.44699 18.3783C7.52136 18.1087 7.59573 18.2482 7.6608 18.211C7.6608 18.2853 7.64221 18.3132 7.64221 18.462C7.69799 18.118 7.80024 18.7316 7.84673 18.527V18.7966C7.99546 19.2893 7.82813 18.276 7.9025 18.3783C7.9025 18.5084 7.92109 18.6107 7.93039 18.7408C7.93039 18.3597 7.93969 18.2017 7.96757 18.0715C7.98617 17.9693 8.01406 17.8949 8.02335 17.7648C8.02335 17.8019 8.04194 17.8763 8.04194 17.8763C8.07913 17.6904 8.17209 17.6904 8.19068 17.3743C8.24646 17.4208 8.33942 17.9414 8.39519 17.7183C8.23716 17.2628 8.46027 17.3 8.23716 16.9188C8.31153 16.8909 8.46956 16.8537 8.45097 16.6771C8.49745 16.8537 8.72056 17.0211 8.68337 17.1605C8.73915 17.207 8.79493 17.2535 8.86 17.3C8.94366 17.458 8.77633 17.3464 8.90648 17.5045C8.93437 17.4208 8.94366 17.1047 9.00874 17.1047C8.93437 16.8073 8.72985 16.4261 8.76704 16.2774C8.82282 16.4354 9.06451 16.5098 9.08311 16.5935C8.97155 16.3703 8.84141 16.1658 8.70197 15.9892C8.71126 15.9427 8.92507 16.1472 8.89718 16.0264C8.82281 15.9799 8.79493 15.9148 8.75774 15.8498C8.80422 15.8498 8.8507 15.5895 9.12959 15.7754C9.25043 15.8405 9.12959 15.8962 9.25973 15.9148C9.3248 15.8219 9.24114 15.7475 9.29692 15.6545L9.3341 15.6824C9.41776 15.6545 9.36199 15.4221 9.16677 15.3664C9.12029 15.4036 9.3341 15.4779 9.21325 15.4779C9.0924 15.3106 9.13888 15.1711 9.21325 15.0875C9.23184 15.1526 9.30621 15.2083 9.36199 15.2827C9.25043 14.9945 9.29692 14.8179 9.3341 14.6134C9.21325 14.5018 9.51073 14.8551 9.42706 14.8179C9.73383 14.7993 9.49213 14.2694 9.86398 14.3531C9.86398 14.3903 9.68735 14.2044 9.72454 14.2415C9.8082 14.1765 9.97553 14.3438 9.96623 14.2415C10.0685 14.3345 9.99412 14.1486 10.0127 14.0742C9.96623 13.9812 10.0778 14.1114 10.0406 14.1579C10.022 14.0091 10.1522 13.5815 10.4496 13.5629C10.3846 13.4979 10.3102 13.2283 10.3567 13.2004L10.4868 13.3677C10.6077 13.4235 10.5984 13.2376 10.7285 13.3584C10.6263 13.0981 10.5798 13.8139 10.5426 13.5629C10.6913 13.6652 10.4496 13.1725 10.6356 13.4049C10.7006 13.3305 10.6077 13.0888 10.8215 13.1632C10.775 13.1632 10.9609 13.4328 11.0167 13.3677C11.0911 13.2376 10.9795 13.2655 11.0167 13.1353V13.0238C10.868 12.8657 11.1282 12.9587 10.9237 12.8192C11.0539 12.9308 11.0074 12.5961 11.2305 12.8564L11.3978 13.0702C11.4257 13.0145 11.277 12.7913 11.2305 12.6705C11.2584 12.6798 11.3049 12.7077 11.3328 12.7449C11.0539 12.4381 11.4629 12.6705 11.3049 12.3823C11.5001 12.4009 11.5559 12.1685 11.779 12.308C11.7697 12.1499 11.7325 11.9733 11.8812 11.964C11.8905 12.0105 11.8812 12.0384 11.9277 12.1034C12.0671 12.1406 12.0021 12.0477 12.0021 11.9547C12.03 12.0105 12.2717 12.0384 12.4297 12.0848C12.4204 11.9268 12.2438 11.7874 12.1601 11.6758C12.5041 11.9175 12.188 11.2947 12.5227 11.4899C12.532 11.555 12.5505 11.7316 12.6807 11.7595C13.0246 12.0012 12.6156 11.4155 12.8573 11.462L12.597 11.2389C12.7829 11.3505 12.6249 10.9507 12.848 11.211C12.8015 11.0902 13.0525 11.1738 12.8201 10.9414C13.1827 10.9879 13.1455 10.4208 13.6475 10.7555C13.6382 10.6904 13.7404 10.6718 13.6103 10.5603C13.443 10.458 13.6382 10.709 13.5359 10.6347C13.5545 10.6068 13.4987 10.5324 13.4709 10.4952C13.5731 10.4952 13.6382 10.4766 13.7683 10.7276C14.0286 10.7648 13.5173 10.1977 13.7683 10.1513C13.852 10.2628 13.8985 10.2907 13.9357 10.2256L13.8706 9.97463C14.01 9.91886 14.1402 10.1513 14.2982 10.3279C14.3261 10.2535 14.4005 10.1977 14.3075 10.049L14.5678 10.207C14.3819 10.0955 14.5213 10.0583 14.5027 9.99323V10.0583C14.5864 10.1234 14.6143 10.0211 14.6236 9.97463C14.5213 9.87238 14.4191 9.89097 14.354 9.89097C14.3168 9.78871 14.3726 9.77012 14.3261 9.64927C14.4655 9.8259 14.5213 9.68646 14.5864 9.66786C14.6701 9.66786 14.5027 9.46335 14.5306 9.45405C14.6143 9.53772 14.6236 9.39828 14.6979 9.55631C14.6979 9.60279 14.5864 9.50983 14.6236 9.61209C14.7165 9.64927 14.8467 9.8073 14.8188 9.63068C14.7909 9.50053 14.5027 9.30532 14.6979 9.32391C14.7072 9.38898 14.763 9.46335 14.8002 9.53772H14.9675L14.8374 9.38898C14.8839 9.41687 14.8839 9.43546 14.9118 9.45405C14.7909 9.26813 15.0047 9.27743 14.8653 9.08221C14.8932 9.02643 15.0605 9.1008 15.1163 9.08221V9.1008C15.2557 9.14728 15.2743 9.01714 15.2278 8.8777L15.2557 8.91488C15.2557 8.91488 15.3487 8.81262 15.3022 8.69177C15.4788 8.73826 15.8414 9.25884 15.7577 8.98925C15.8321 8.91488 15.6276 8.59881 15.5067 8.52444C15.7391 8.50585 15.6647 8.11542 16.0087 8.24556C15.9715 8.1619 15.925 8.13401 15.9343 8.06894C16.1853 7.95738 16.1946 7.51117 16.6222 7.6785C16.6222 7.79935 16.7524 7.83653 16.836 7.92949C16.7617 7.74357 17.022 8.02246 16.836 7.77146C16.7059 7.63202 16.6501 7.55765 16.5479 7.55765C16.6036 7.38103 16.7803 7.22299 16.9662 7.29736C16.8732 7.26018 16.8639 7.1951 16.8546 7.13003C17.0406 7.36243 17.1614 7.31595 17.1614 7.18581L17.0499 7.03707L17.2172 7.13933C17.2079 7.07425 16.9941 6.82326 17.18 6.89763C17.2265 6.94411 17.2823 6.99989 17.3287 7.02777C17.3008 6.85115 17.2358 6.58156 17.4124 6.62804L17.6448 6.77678C17.6541 6.7303 17.6076 6.56297 17.5054 6.55367C17.7378 6.56297 17.8307 6.50719 18.0259 6.64664C17.8772 6.03309 18.1933 5.73562 18.4722 5.5497L18.5558 5.66125C18.7046 5.69843 18.435 5.44744 18.5558 5.47533C18.6209 5.59618 18.7882 5.64266 18.844 5.80999C19.0392 5.83788 18.8161 5.52181 18.844 5.41955C18.7417 5.27081 18.8626 5.5497 18.7324 5.36377C18.7046 5.308 18.9648 5.35448 18.7975 5.13137C18.8905 5.18715 19.002 5.35448 19.0578 5.45674L19.0299 5.308C19.3088 5.48462 19.2251 5.88436 19.5598 6.10746L19.5877 6.0238C19.8201 6.19113 19.6435 6.39564 19.848 6.34916C19.8201 6.20042 19.6156 5.85647 19.4854 5.80999C19.5598 5.64266 19.1229 5.27081 19.2809 5.16856C19.4204 5.26152 19.1972 5.28941 19.3646 5.43814C19.5691 5.5497 19.4111 5.23363 19.5226 5.24293C19.3925 5.21504 19.2716 4.96404 19.2809 4.88967C19.4297 4.92686 19.4018 5.12208 19.5133 5.057C19.4297 4.92686 19.4389 4.75953 19.2902 4.74094C19.095 4.44346 19.4575 4.73164 19.3367 4.47135C19.5319 4.62938 19.6063 4.99193 19.8015 5.00123C19.6249 4.8339 19.7271 4.63868 19.4389 4.41557C19.5226 4.43417 19.6528 4.57361 19.7178 4.71305C19.8759 4.77812 19.5784 4.25754 19.913 4.6015L19.7736 4.39698C19.848 4.44346 19.913 4.46205 20.0246 4.53642C20.0804 4.48994 19.9781 4.13669 20.2198 4.42487C20.2198 4.37839 20.3407 4.29472 20.1362 4.13669C19.9595 4.08091 20.1733 4.3505 19.9038 4.12739C20.1362 4.29472 19.9874 4.00655 19.9688 3.89499L20.0711 3.99725C20.0618 3.93218 20.1455 3.90429 20.0618 3.77414C20.099 3.85781 20.164 3.92288 20.2105 3.93218L20.099 3.74626C20.1362 3.56963 20.3686 4.01584 20.4336 3.8857L20.4615 4.08091C20.4615 4.08091 20.6196 4.16458 20.6288 4.07162C20.5266 3.90429 20.3964 3.69048 20.3221 3.56033C20.3221 3.44878 20.4894 3.70907 20.415 3.50456L20.4987 3.75555C20.5266 3.81133 20.759 3.96007 20.8334 3.89499C20.8334 3.80203 20.7311 3.51385 20.5824 3.49526C20.6196 3.45808 20.7497 3.50456 20.8148 3.644C20.8612 3.51385 20.666 3.48596 20.666 3.32793C20.7869 3.4023 21.0007 3.46737 21.1866 3.56033L21.3168 3.8857L21.3725 3.83922C21.4748 4.09951 21.5399 3.96936 21.6793 4.21106C21.7444 4.21106 21.7258 4.1088 21.7165 4.01584C21.3168 3.76485 21.4376 3.44878 21.1401 3.1606C21.2145 2.95609 21.8745 3.84851 21.6142 3.22567C21.5213 3.1606 21.3911 2.86313 21.3725 3.03046C21.4934 2.99327 21.168 2.66791 21.3818 2.70509C21.4097 2.90031 21.7351 2.95609 21.7816 3.23497C21.6979 3.12342 21.6514 3.20708 21.6607 3.25356C21.8002 3.34652 21.921 3.57893 22.014 3.49526C22.0419 3.42089 22.1162 3.34652 21.9675 3.18849C21.8095 3.01186 21.8931 3.28145 21.7816 3.06764C21.8373 2.90961 22.0883 3.1699 21.8652 2.80735C21.8187 2.89101 21.6421 2.72369 21.5399 2.59354L21.5585 2.4448L21.6421 2.57495C21.8466 2.54706 21.5027 2.32395 21.6514 2.24958L21.9117 2.43551C22.0511 2.66791 21.6514 2.50058 21.9489 2.81665C22.0419 2.76087 21.9303 2.56565 22.079 2.58424C22.079 2.63072 22.0697 2.65861 22.079 2.6958C22.1162 2.6772 22.516 3.09553 22.423 2.74228C22.4044 2.59354 22.3393 2.61213 22.2371 2.48199C22.3393 2.33325 22.2743 2.17522 22.3393 2.08226C22.5253 2.34255 22.5067 1.98 22.6275 2.30536C22.4602 2.2031 22.2836 2.37973 22.4323 2.64932C22.7205 2.89101 22.2928 2.6958 22.5067 3.01186C22.6182 2.9282 22.8506 3.21638 23.0272 3.38371C23.0644 3.37441 23.0272 3.27215 23.0272 3.22567C22.8971 3.03975 22.8599 3.07694 22.7019 2.90031C22.8599 2.84453 22.8971 2.64932 22.8227 2.42621C22.9343 2.48199 23.0644 2.66791 23.0365 2.72369C23.1388 2.55636 23.3061 2.4448 23.4827 2.38903C23.1574 2.17522 23.5757 2.19381 23.3247 2.00789C23.1946 2.00789 22.9715 1.84985 22.8971 1.69182C22.9622 1.67323 22.9994 1.82196 23.0737 1.85915C22.9994 1.65464 23.3712 2.03577 23.2225 1.7383C23.1667 1.94281 23.4827 2.11014 23.6501 2.35184C23.6408 2.14733 23.7802 2.50988 23.8732 2.43551C23.8639 2.23099 23.8918 2.03577 23.9568 1.90563C24.2636 2.00789 24.2915 1.63604 24.4031 1.52449C24.5611 1.58956 24.7284 1.87774 24.8307 1.85915C24.905 1.78478 24.5425 1.63604 24.7563 1.65464L24.7842 1.71041C24.7656 1.62675 25.1375 1.71041 24.8679 1.31068L25.0631 1.61745C25.0631 1.61745 25.0724 1.54308 25.0631 1.5059C25.1374 1.58956 25.2304 1.65464 25.2397 1.7383C25.4721 1.86845 25.3606 1.58027 25.4349 1.51519L25.249 1.39434C25.2769 1.15265 25.5 1.24561 25.5744 1.07828L25.7045 1.23631V1.07828C25.8068 1.24561 25.9648 1.29209 25.8997 1.12476L26.0299 1.67323C25.8997 1.62675 25.9276 1.43153 25.7696 1.30138C25.6301 1.18983 25.5465 1.32927 25.6487 1.4966C25.7045 1.47801 25.6859 1.44083 25.6673 1.35716C25.8625 1.56167 25.7882 1.61745 25.8811 1.78478C25.8997 1.75689 25.9834 1.79408 25.9369 1.71971C25.9834 1.86845 25.9462 1.92422 25.8718 1.98929C25.8532 1.85915 25.7324 1.87774 25.6952 1.79408C25.8532 1.98929 25.8254 2.11014 25.6859 2.13803C25.4349 1.9707 25.6301 2.43551 25.4628 2.46339C25.342 2.23099 25.2676 2.02648 25.2676 1.88704C25.1189 1.84985 25.1932 1.96141 25.0445 1.91493C25.1375 2.09155 25.2955 2.33325 25.2769 2.50058L25.1467 2.36114C25.1282 2.50058 25.3048 2.71439 25.1653 2.77017C24.9236 2.84453 24.7377 3.00257 24.589 3.09553L24.4588 2.95609C24.6448 3.32793 24.3008 3.28145 24.3101 3.50456C24.0219 3.50456 24.0498 3.96007 23.7523 3.78344C23.5385 4.15528 23.3619 4.48994 22.9994 4.70375L22.8785 4.45276C22.9529 4.65727 22.7391 4.3598 22.7112 4.44346C22.9157 4.55502 22.8134 4.72234 22.8878 4.88967C22.6089 4.84319 22.581 5.17785 22.5717 5.42885L22.4416 5.28941C22.5438 5.67055 22.1906 5.55899 21.9954 5.64266C21.9303 5.59618 21.7816 5.48462 21.7537 5.5404C21.8652 5.84717 21.8095 5.86576 21.8002 6.11676C21.7072 6.19113 21.512 6.2655 21.3446 6.2469C21.2796 6.86974 20.7497 6.95341 20.5638 7.4554L20.3964 7.30666C20.3593 7.95738 19.6528 7.99457 19.5226 8.44078L19.2995 8.12471C19.1322 8.12471 19.1508 8.385 19.3553 8.56163C19.188 8.56163 19.2437 8.89629 18.9834 8.71037C18.844 8.73825 18.9834 8.94277 18.937 9.04503C18.6581 9.1008 18.6023 9.18447 18.4722 9.38898L18.5279 9.37039C18.4907 9.28672 18.3885 9.16588 18.3327 9.18447C18.3327 9.32391 18.0259 9.31461 18.3885 9.60279C18.0259 9.56561 18.091 10.1513 17.6727 10.0397C17.7657 10.1234 17.7378 10.1791 17.7749 10.2535C17.6169 10.4023 17.273 10.3651 17.2823 10.644C17.2172 10.6161 17.1893 10.4487 17.1056 10.4952C17.1056 10.5696 17.2079 10.6161 17.2079 10.709C17.0963 11.1181 16.5107 11.0065 16.3062 11.2668C16.0366 11.8246 15.5067 12.1406 15.1349 12.5404L15.0791 12.466C15.172 12.8471 14.5213 12.4939 14.763 12.9773C14.6701 12.9401 14.6143 13.0609 14.5213 12.9122C14.5771 13.1911 14.0658 13.0238 14.1123 13.3956C14.1309 13.3956 14.1309 13.3677 14.1123 13.3212C13.8148 13.3212 13.8706 13.6466 13.5731 13.6745C13.5638 13.628 13.5731 13.5815 13.5173 13.5071C13.3314 13.4421 13.6289 13.9255 13.2942 13.6373C13.257 13.6745 13.4151 13.8232 13.4337 13.7953C12.9503 14.0091 12.7551 14.5762 12.4669 14.9945C12.03 15.0596 11.937 14.4832 11.9649 14.9109C11.8905 14.8644 12.0671 15.041 12.0021 14.9759C12.0021 15.134 11.5373 14.7528 11.6488 14.9666C11.8626 15.134 11.7232 15.1061 11.8347 15.2269C11.5559 15.2548 11.3514 15.1247 11.3792 15.385L11.2863 15.2734C11.435 15.6917 11.1282 15.7196 11.3606 16.1472C11.2026 16.361 11.0539 16.5749 10.9237 16.7887L10.4403 17.6625C9.91975 18.5456 9.60369 20.0423 9.12029 21.4367C8.99014 21.7993 8.8507 22.1618 8.72056 22.5151L8.33942 22.0874L7.89321 21.5762L7.00078 20.5536C6.41513 19.8657 5.80159 19.1127 5.281 18.3225C5.20664 17.6439 5.20664 17.6625 4.77902 17.3743C4.83479 17.3464 4.86268 17.365 4.89057 17.3C4.76972 17.3929 4.70465 17.3185 4.64887 17.2628C4.61169 17.2256 4.5745 17.1791 4.45365 17.2628C4.23055 16.9002 3.92378 16.6399 3.64489 16.296C3.70997 16.3332 3.93307 16.203 3.868 16.1472L3.66349 16.203L3.71926 16.1379C3.64489 16.1193 3.49616 16.1658 3.44968 16.2774C2.55725 15.5709 2.37133 14.3345 1.66483 13.5071C1.60905 13.219 1.30228 12.9959 1.08847 12.8006C0.930435 11.8617 0.790994 11.0902 0.0751953 10.4116C0.0751953 10.4116 0.828178 10.1513 1.16284 10.3558L1.08847 10.4673Z\" fill=\"#8F3A7E\"><\/path><path d=\"M26.3094 1.58132C26.1885 1.47901 26.0676 1.47901 25.9932 1.27438C26.0955 1.3767 26.235 1.46971 26.3094 1.58132Z\" fill=\"#8F3A7E\"><\/path><path d=\"M23.3623 1.9979C23.3623 1.9979 23.2973 1.97005 23.2695 1.96076C23.288 1.93291 23.223 1.8122 23.2973 1.85863C23.2787 1.88648 23.3345 1.94219 23.3623 1.9979Z\" fill=\"#8F3A7E\"><\/path><path d=\"M22.8039 2.34232C22.7203 2.2309 22.7574 2.06377 22.8131 1.99878V2.34232H22.8039Z\" fill=\"#8F3A7E\"><\/path><path d=\"M21.9853 2.29645C21.8739 2.24074 21.846 2.18504 21.9018 2.13861C21.9482 2.19432 21.9575 2.23146 21.9853 2.29645Z\" fill=\"#8F3A7E\"><\/path><path d=\"M22.1544 2.56585C22.1544 2.56585 22.052 2.55654 21.9775 2.51001C22.052 2.59377 22.0241 2.37971 22.1544 2.56585Z\" fill=\"#8F3A7E\"><\/path><path d=\"M20.8979 3.10465C20.8979 3.10465 20.8979 3.26249 20.7772 3.16965C20.8701 3.22535 20.7772 2.93752 20.8979 3.10465Z\" fill=\"#8F3A7E\"><\/path><path d=\"M20.5632 3.65382C20.5632 3.65382 20.5168 3.65382 20.5261 3.69096C20.4611 3.6631 20.424 3.57025 20.4425 3.53311L20.5632 3.65382Z\" fill=\"#8F3A7E\"><\/path><path d=\"M12.5693 11.3684V11.275L12.6534 11.3871L12.5693 11.3684Z\" fill=\"#8F3A7E\"><\/path><path d=\"M9.03711 14.8652C9.05568 14.9767 8.90712 14.8188 8.88855 14.8188C8.9164 14.7631 8.99997 14.9488 9.03711 14.8652Z\" fill=\"#8F3A7E\"><\/path><path d=\"M8.21887 17.2635V17.2357L8.33029 17.5885L8.21887 17.2635Z\" fill=\"#8F3A7E\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Free VIN Corrections<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"27\" height=\"23\" viewBox=\"0 0 27 23\" fill=\"none\"><path d=\"M26.5504 1.48711C26.5133 1.41296 26.3928 1.2832 26.3743 1.33881L26.5411 1.59833V1.48711H26.5504Z\" fill=\"#8F3A7E\"><\/path><path d=\"M25.9092 1.28207C25.9556 1.43991 26.067 1.68132 26.2806 1.8763C26.1413 1.60704 26.2342 1.69061 26.0577 1.3842C26.0763 1.31921 26.197 1.40277 26.262 1.49562C26.2249 1.42134 26.3734 1.49562 26.262 1.32849C26.0577 1.18922 25.9835 1.23565 26.0392 1.4492C25.9835 1.41206 25.9463 1.33778 25.9092 1.29136V1.28207Z\" fill=\"#8F3A7E\"><\/path><path d=\"M19.0215 6.23586C19.0215 6.23586 19.0215 6.18064 19.0031 6.16223C19.0031 6.18984 19.0031 6.21746 19.0215 6.23586Z\" fill=\"#8F3A7E\"><\/path><path d=\"M18.3794 6.34023C18.3794 6.34023 18.4077 6.34023 18.4171 6.34023C18.3888 6.3308 18.37 6.32138 18.3794 6.34023Z\" fill=\"#8F3A7E\"><\/path><path d=\"M21.5952 4.26723L21.465 4.24863C21.5208 4.33234 21.5487 4.27653 21.5952 4.26723Z\" fill=\"#8F3A7E\"><\/path><path d=\"M25.8363 2.31298C25.8363 2.31298 25.8363 2.25752 25.8178 2.22055C25.8178 2.23904 25.8178 2.25752 25.8086 2.27601L25.8363 2.31298Z\" fill=\"#8F3A7E\"><\/path><path d=\"M22.5358 3.16046L22.5544 3.14186C22.5544 3.14186 22.5172 3.07675 22.4893 3.03024L22.5358 3.16046Z\" fill=\"#8F3A7E\"><\/path><path d=\"M23.3447 2.4166C23.3447 2.4166 23.4749 2.63052 23.5493 2.72353C23.4935 2.63052 23.4749 2.58401 23.4749 2.54681C23.447 2.50961 23.4005 2.4631 23.3447 2.4166Z\" fill=\"#8F3A7E\"><\/path><path d=\"M21.8932 3.61673C21.8932 3.61673 21.8372 3.56072 21.8279 3.55139C21.8465 3.57939 21.8745 3.59806 21.8932 3.61673Z\" fill=\"#8F3A7E\"><\/path><path d=\"M0.799326 11.6575C0.799326 11.6575 0.827596 11.6386 0.837019 11.6292C0.808749 11.6292 0.789903 11.648 0.799326 11.6575Z\" fill=\"#8F3A7E\"><\/path><path d=\"M1.21851 9.87102L1.24636 9.8803L1.37635 9.81531L1.21851 9.87102Z\" fill=\"#8F3A7E\"><\/path><path d=\"M10.5801 13.1525C10.8215 13.2453 10.6636 13.4868 10.9608 13.561C10.8772 13.496 10.7843 13.1711 10.5801 13.1525Z\" fill=\"#8F3A7E\"><\/path><path d=\"M25.7896 2.30579C25.7896 2.30579 25.7708 2.32463 25.752 2.33406C25.7708 2.33406 25.7802 2.31521 25.7896 2.30579Z\" fill=\"#8F3A7E\"><\/path><path d=\"M15.7295 8.4028C15.7295 8.4028 15.7942 8.45826 15.8219 8.47674C15.8034 8.45826 15.7757 8.43977 15.7295 8.4028Z\" fill=\"#8F3A7E\"><\/path><path d=\"M15.2939 9.27798C15.2939 9.27798 15.2285 9.25931 15.2285 9.30598C15.2378 9.30598 15.2472 9.31531 15.2565 9.32465C15.2378 9.28731 15.2379 9.26865 15.2939 9.27798Z\" fill=\"#8F3A7E\"><\/path><path d=\"M14.5957 9.90973C14.5957 9.90973 14.6241 9.92869 14.6431 9.93817V9.90973H14.5957Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.6049 13.9609C2.65136 13.8959 2.7071 13.8401 2.76285 13.7844C2.62348 13.9051 2.48412 13.8401 2.6049 13.9609Z\" fill=\"#8F3A7E\"><\/path><path d=\"M25.7432 2.19324C25.7802 2.24883 25.7988 2.27662 25.7895 2.29515L25.808 2.26736C25.808 2.26736 25.7617 2.21177 25.7432 2.19324Z\" fill=\"#8F3A7E\"><\/path><path d=\"M16.6315 10.8466L16.4922 10.9116C16.5386 10.9116 16.585 10.8745 16.6315 10.8466Z\" fill=\"#8F3A7E\"><\/path><path d=\"M7.79133 20.2916H7.76367C7.76367 20.2916 7.79133 20.3285 7.79133 20.2916Z\" fill=\"#8F3A7E\"><\/path><path d=\"M16.1947 11.2389C16.1111 11.1924 16.0554 11.1645 16.0089 11.1552C16.0089 11.1738 16.0275 11.1924 16.0368 11.2203L16.1854 11.2389H16.1947Z\" fill=\"#8F3A7E\"><\/path><path d=\"M1.95357 13.227C1.75835 13.1898 1.98146 13.1526 2.08371 12.9109C1.81413 13.0132 2.08371 12.7343 1.70258 12.9946C1.91639 12.7808 1.83272 12.8551 1.96287 12.6599C1.78624 12.8366 1.66539 12.6599 1.42369 12.8458C1.67469 12.6227 1.85131 12.725 2.06512 12.4275C1.83272 12.4926 1.68398 12.4275 1.37721 12.6227C1.4051 12.5205 1.49806 12.4275 1.47947 12.3253C1.47017 12.3532 1.53525 12.3253 1.57243 12.316C1.27496 12.316 1.33073 11.972 0.912408 12.1393C1.36792 11.8698 0.76367 11.7954 1.23777 11.6281C1.18199 11.5816 0.931 11.6095 0.838039 11.6374C1.18199 11.4143 0.828743 11.4328 0.986776 11.2283C0.772966 11.3213 0.76367 11.1633 0.614933 11.1726C0.680005 11.1726 0.745078 11.154 0.828743 11.0889C0.642821 11.0982 0.782262 11.0331 0.912408 10.8658C0.745078 10.8286 0.661413 11.0517 0.456899 11.0889C0.475491 10.9494 0.670709 10.9401 0.800854 10.8379L0.363938 10.9216C0.38253 10.8751 0.438307 10.81 0.531268 10.7449C0.401123 10.7542 0.224497 10.8007 0.354642 10.6334L0.438307 10.7449L0.59634 10.5962H0.280273C0.429011 10.2244 0.856631 10.0849 1.24707 9.88969L1.35862 9.92688C1.48877 9.85251 1.53525 9.75955 1.51665 9.72236C1.59102 9.64799 2.00005 9.61081 2.08371 9.65729C2.17668 9.8804 1.67469 9.95476 1.66539 10.1593L2.00005 10.2151L1.8792 10.2987C1.81413 10.3824 1.96287 10.3173 2.00005 10.2987C1.80483 10.401 2.03723 10.4939 2.05583 10.5869L2.19527 10.4568C2.70655 10.4196 2.01864 11.0517 2.33471 11.0982L2.67866 11.0331L2.46485 11.219C2.65078 11.1911 2.8367 11.0796 2.8367 11.2469C2.70655 11.9255 3.50602 11.9999 3.5525 12.5763C3.59898 12.5391 3.59898 12.5112 3.61757 12.4647C3.3108 13.2363 4.59366 12.567 4.39844 13.2084L4.29618 13.2549C4.46351 13.3757 4.19393 13.3014 4.15674 13.5059C4.44492 13.3199 4.51929 13.5431 4.68662 13.5616C4.62155 13.5895 4.60295 13.5616 4.53788 13.5616C4.4914 13.6267 4.33337 13.7569 4.41703 13.7662C4.88184 13.5709 5.01198 13.8126 5.24438 13.8777C5.08635 14.0357 5.03058 14.296 4.80747 14.5935C4.88184 14.5563 5.03987 14.482 5.1979 14.4076C5.13283 14.5563 5.25368 14.5284 5.38383 14.4913C5.33735 14.4448 5.30016 14.3983 5.27227 14.3704H5.29087C5.29087 14.3704 5.26298 14.3611 5.25368 14.3518C5.2165 14.3239 5.1979 14.3146 5.18861 14.3332C5.30946 14.138 5.32805 14.231 5.53256 14.0636C5.56975 14.1194 5.71849 14.1752 5.57904 14.3053C5.59764 14.3425 5.59764 14.3797 5.57904 14.4355C5.62552 14.4355 5.66271 14.4355 5.66271 14.4727H5.63482C5.63482 14.4727 5.59764 14.5284 5.57904 14.547C5.57904 14.7144 5.98807 14.6121 6.20188 14.5842C5.87652 14.7051 5.9323 14.8352 5.73708 14.9839C5.75567 14.9839 5.6906 14.8724 5.58834 14.7423C5.57904 14.7701 5.55116 14.798 5.48608 14.8538C5.37453 15.1234 5.81145 14.9003 5.80215 15.1792C5.77426 15.1792 5.70919 15.1978 5.65341 15.2628C5.65341 15.3651 5.83933 15.3 5.96018 15.2164C5.79285 15.3744 5.75567 15.6068 5.88582 15.5975C6.08103 15.5324 6.14611 15.4673 6.20188 15.5789L6.03455 15.644C6.01596 15.8485 6.29484 15.5882 6.26695 15.7648C6.28555 15.6905 6.14611 15.7927 6.14611 15.8392C6.31344 15.895 6.3971 15.8578 6.70387 15.709L6.49936 15.8671C6.67598 15.8485 6.97346 15.6997 6.73176 15.9693C7.08501 15.551 7.00135 15.8485 7.03853 15.9043C7.01994 15.9043 6.95487 15.9972 6.91768 16.053C7.18727 15.8113 7.05712 16.211 7.15938 16.3133L7.03853 16.7874C7.1036 16.8432 7.3453 15.9136 7.36389 15.96L7.30812 16.1831C7.38249 16.1831 7.40108 16.2482 7.44756 16.4063L7.41967 16.7874C7.45685 16.6387 7.48474 16.6758 7.50333 16.5085C7.52193 17.0291 7.587 16.9826 7.63348 16.9175C7.66137 16.8804 7.67996 16.8711 7.70785 16.9175C7.72644 16.9175 7.75433 17.0012 7.81011 17.2522L7.69855 16.4248C7.69855 16.4248 7.69855 16.4063 7.69855 16.397C7.70785 16.3505 7.71714 16.3226 7.81011 16.7409C7.91236 17.3173 7.83799 16.6944 7.87518 16.7874C7.87518 16.6944 7.80081 16.3319 7.77292 16.2482C7.91236 16.462 7.88447 15.9972 8.16336 16.3784C8.18195 16.0437 7.96814 15.6626 8.0611 15.6161L8.10758 15.6533C8.10758 15.6533 8.20054 15.6626 8.2935 15.6905C8.40506 15.6905 8.55379 15.7183 8.72112 15.8392C8.79549 15.5882 8.44224 15.1048 8.78619 14.9932L8.86986 15.142C8.98141 15.142 8.90704 14.9189 8.88845 14.8631C8.91634 14.8445 8.96282 14.9189 9.00001 14.9561C9.14874 14.9932 9.0093 14.8166 9.0186 14.7515L9.11156 14.8631C9.47411 14.8631 9.30678 14.231 9.56707 14.0543C9.56707 14.1194 9.68792 14.2031 9.75299 14.2403C9.50199 13.8405 9.81806 13.6639 9.83665 13.5059L9.91102 13.6825C9.87384 13.3014 10.3944 13.8684 10.3572 13.4873L10.0784 13.3943C10.1992 13.3757 10.1992 13.2642 10.0412 13.134C10.2271 13.1619 10.2922 13.3757 10.4502 13.2828C10.5432 13.3664 10.4223 13.4315 10.5803 13.5059L10.9801 13.5895C10.9801 13.5895 11.0358 13.5895 11.0637 13.5152C10.6547 13.1154 11.1846 13.3571 10.7105 13.0411C10.9243 12.7808 11.3798 12.8644 11.4077 12.4833C11.8725 12.8087 11.826 12.1208 12.2908 12.6599C12.4117 12.5577 12.4117 12.3625 12.2908 12.0929C12.2257 12.0743 12.2629 12.1672 12.2629 12.2137C12.17 12.0557 12.2908 11.8976 12.3466 11.8512C12.3838 12.0371 12.3466 12.2602 12.4767 12.5112C12.5325 12.3625 12.5046 12.0278 12.4953 11.9162L12.7742 12.1579C12.6813 11.8791 13.0531 12.3067 12.8951 11.9627L12.8021 11.8976C12.9787 11.7675 12.737 11.4979 12.8579 11.3213L12.9508 11.4328C13.0438 11.4328 12.8858 11.1075 13.1647 11.3027L13.0717 11.405C13.2576 11.5816 13.4064 11.6002 13.5272 11.6652C13.583 11.5165 13.2855 11.3213 13.3134 11.2469C13.4993 11.405 13.4064 11.3399 13.5272 11.5444C13.583 11.3771 13.6759 11.154 13.5551 10.8472C13.583 10.8751 13.6202 10.9123 13.6202 10.9123C13.7689 10.8286 13.5923 10.4103 13.7968 10.4939V10.5404C14.1314 10.717 13.8247 10.0663 14.2523 10.4939C14.3731 10.5311 14.1314 10.5683 14.401 10.7263C14.6706 10.7356 14.1593 10.2615 14.401 10.2708C14.3731 10.2708 14.401 10.2987 14.4289 10.3452C14.5126 10.2522 14.5963 10.0942 14.6613 9.95476C15.1168 10.2058 14.9681 9.51785 15.498 9.81532C15.3121 9.70377 15.3771 9.61081 15.3213 9.53644C15.3213 9.53644 15.3492 9.58292 15.3771 9.60151C15.4422 9.56433 15.3213 9.41559 15.2842 9.34122C15.4422 9.43418 15.3028 9.07164 15.4143 9.12741C15.3306 9.03445 15.3957 9.01586 15.4422 8.97867C15.4422 9.17389 15.5909 9.21108 15.6839 9.397C15.8698 9.32263 15.4794 8.82994 15.6839 8.77416L15.9256 8.88571C15.7025 8.59754 15.9349 8.58824 15.8419 8.48598C15.9442 8.55105 16.0279 8.56965 16.1394 8.70909C16.1394 8.58824 16.3532 8.65331 16.2324 8.46739L16.1115 8.4488C16.3904 8.39302 16.1487 7.90033 16.4555 7.95611L16.818 8.37443C17.0597 8.45809 16.7901 7.99329 17.0969 8.17921C16.9482 8.06766 16.9761 8.11414 16.9203 7.91892C16.8552 7.91892 16.8831 8.08625 16.8273 8.13273L16.7436 7.77948L16.6507 8.06766C16.5949 7.83526 16.6228 7.87244 16.4462 7.74229C16.4462 7.5006 16.7529 7.82596 16.7251 7.56567C16.818 7.58426 16.9017 7.77018 17.0225 7.81666C16.9946 7.58426 17.478 7.94681 17.3572 7.65863C17.4223 7.67722 17.3293 7.70511 17.413 7.79807C17.4409 7.70511 17.5059 7.67722 17.413 7.53778H17.32C17.3758 7.50989 17.2363 7.33327 17.4223 7.35186C17.3944 7.21242 17.2456 6.98002 17.1899 7.0265C17.1899 6.98002 17.3386 7.04509 17.4316 7.18453C17.5803 7.06368 17.1155 6.68254 17.4316 6.75691C17.4316 6.7755 17.4316 6.81269 17.4687 6.83128C17.5338 6.83128 17.5617 6.80339 17.5617 6.75691C17.4687 6.90565 17.8871 7.05438 17.6733 7.11016C17.8778 7.31467 17.822 7.05438 17.9428 7.11016C17.8871 6.89635 17.6733 6.7848 17.6175 6.64536C17.6733 6.71972 17.7104 6.69184 17.7662 6.69184L17.5896 6.5524C17.5896 6.5524 17.6547 6.50591 17.6547 6.43155V6.5524C17.7476 6.52451 18.073 6.71043 18.0544 6.44084C18.0823 6.5338 18.1381 6.71973 18.2868 6.74761C18.324 6.5338 18.3798 6.79409 18.5564 6.85917C18.6493 6.71043 18.324 6.5431 18.5936 6.48732C18.6122 6.46873 18.5099 6.38507 18.4541 6.35718C18.6493 6.32929 18.6215 6.15266 18.8446 6.17126C18.7516 6.17126 18.6586 6.15266 18.6679 6.01322C18.7516 6.18055 18.8817 6.0597 19.0026 6.09689L18.9468 6.00393C19.0584 6.0597 19.0491 6.13407 19.0491 6.18985C19.0212 6.16196 18.9933 6.14337 18.9747 6.17126C18.9747 6.2921 19.2722 6.58958 19.393 6.5431C19.4302 6.37577 19.2164 6.16196 19.1327 6.09689C19.3466 6.069 18.9282 5.60419 19.1792 5.62279C19.2071 5.5949 19.5975 5.84589 19.7184 5.79941C19.6068 5.56701 19.4767 5.75293 19.393 5.54842C19.9601 5.89237 19.4674 4.97206 19.9229 5.08361L20.0995 5.3439C20.1646 5.31602 20.2204 5.29742 20.2576 5.22305L20.0809 5.15798C20.0809 5.06502 20.239 5.00924 20.3505 5.22305C20.2948 4.93488 20.4156 5.02784 20.5736 5.00924C20.4528 5.08361 20.5457 4.98136 20.5736 5.16728C20.7874 5.18587 20.7317 5.10221 20.7596 4.98136C20.8153 5.07432 20.9641 5.16728 21.0013 5.13939C20.9455 4.92558 21.1035 4.85121 21.1407 4.68388L21.1965 4.75825C21.2894 4.52585 21.7542 4.69318 21.7542 4.33993C21.7542 4.33993 21.7542 4.33063 21.7542 4.32133H21.7264C21.4754 4.14471 21.7264 4.05175 21.7078 3.91231C21.7635 3.95879 21.8565 4.05175 21.8844 4.02386C21.7078 3.81005 21.8565 3.85653 21.8007 3.73568C21.9216 3.75427 22.0052 3.99597 22.0982 3.89371C22.1261 3.83794 22.0331 3.72638 21.968 3.65202C22.0796 3.73568 22.219 3.77286 22.2934 3.74498C22.3213 3.81934 22.2283 3.77286 22.2283 3.79146C22.312 3.91231 22.3213 3.83794 22.4329 3.97738C22.4979 3.94949 22.2841 3.76357 22.405 3.79146L22.4886 4.00527C22.5444 4.02386 22.5165 3.9309 22.5258 3.91231C22.5258 3.98667 22.6746 4.14471 22.7582 4.23767C22.7954 3.99597 22.4143 3.76357 22.2655 3.57765C22.5072 3.59624 22.4236 3.28947 22.5165 3.19651L22.6653 3.41032C22.6931 3.33595 22.6746 3.27088 22.6281 3.17791L22.7024 3.11284C22.721 3.22439 22.7582 3.29876 22.8791 3.4568C22.9163 3.33595 23.0743 3.28947 22.8791 3.01058L22.9163 3.05707C23.1022 3.05707 23.3811 2.92692 23.4461 3.01988C23.4926 2.83396 23.7715 2.86185 23.5577 2.60156C23.5763 2.48071 24.0225 2.78748 23.7994 2.41564C24.0225 2.51789 23.8645 2.48071 23.9946 2.69452C24.2177 2.79677 23.9388 2.28549 24.2828 2.63874C24.2828 2.44352 24.1991 2.58296 24.0876 2.38775C24.3943 2.71311 24.3107 2.29479 24.571 2.41564C24.4966 2.23901 24.4594 2.35986 24.4036 2.15534C24.4687 2.24831 24.5245 2.22971 24.5431 2.22971L24.3757 1.99731L24.9149 2.45282C24.8405 2.08098 24.571 2.09957 24.6732 1.84857V1.87646C24.9149 2.06238 24.6732 1.59758 24.9428 1.66265C24.8591 1.66265 25.0079 1.7835 25.0451 1.85787V1.70913C25.0451 1.70913 25.0544 1.74632 25.0822 1.76491C25.2868 1.87646 25.0636 1.62547 25.2589 1.70913C25.2403 1.7928 25.3983 1.95083 25.482 2.00661L25.3797 1.67195L25.5842 2.00661C25.7051 1.94153 25.4727 1.33729 25.8631 1.69984L25.8445 1.7835C25.9096 1.84857 26.1234 2.04379 26.0676 1.82998C26.0676 1.7742 25.9282 1.58828 25.9096 1.62547L26.0211 1.65336C26.1513 1.86717 26.0676 2.0345 26.0304 2.15534C25.9933 2.05309 26.0026 1.94153 25.8817 1.82998C25.8631 1.95083 25.9003 2.14605 25.8817 2.2669C25.8445 2.16464 25.7609 2.0252 25.7051 1.94153C25.5377 1.90435 25.7609 2.12746 25.7051 2.19253C25.6214 2.13675 25.5563 2.09957 25.5192 2.0252C25.5192 2.16464 25.4634 2.23901 25.3053 2.20182C25.3053 2.20182 25.2775 1.98801 25.138 1.91365C25.0915 2.15534 25.2589 2.41564 25.2124 2.67593C25.3053 3.15003 24.6918 2.76889 24.7662 3.11284C24.8312 3.2058 24.9893 3.18721 24.9521 3.30806C24.822 3.12214 24.8127 3.23369 24.7476 3.16862C24.8684 3.49398 24.571 3.2244 24.6546 3.4475C24.6174 3.37313 24.5059 3.35454 24.4222 3.31736C24.2549 3.09425 24.2549 3.31736 24.1247 2.89903C24.2642 3.33595 23.818 3.01988 24.134 3.59624L24.2177 3.62413H23.9946L24.0039 3.63342C23.9202 3.64272 23.9574 3.70779 23.6878 3.54976C23.6785 3.46609 23.725 3.42891 23.7157 3.34524C23.4833 3.2151 23.6971 3.63342 23.6321 3.70779C23.5019 3.54976 23.6692 3.58694 23.4833 3.41032C23.4089 3.42891 23.4554 3.58694 23.4368 3.6799L23.3718 3.58694C23.065 3.50328 23.6785 4.06104 23.3253 3.85653C23.3718 3.90301 23.4089 3.96808 23.4554 4.01456C23.3439 3.95879 23.1208 3.87512 23.1208 3.6892C23.0743 3.72638 23.0836 3.85653 23.1394 3.96808C23.2881 4.06104 23.2416 3.98667 23.3996 4.13541L23.2788 4.38641C23.2788 4.38641 23.223 4.28415 23.2509 4.26556C22.6374 3.99597 23.1115 5.04643 22.3864 4.71177C22.5351 4.83262 22.47 4.85121 22.5258 4.97206C22.405 4.99995 22.312 5.13939 22.154 5.1208L22.0982 4.99995C21.9959 5.28813 21.9866 5.55771 21.81 5.60419C21.8379 5.65067 21.6892 5.46475 21.6892 5.41827C21.7449 5.67856 21.15 5.21376 21.4382 5.61349H21.5032C21.2615 5.71575 21.2708 6.16196 21.1221 6.37577C20.8897 6.18985 21.2151 6.25492 20.9455 6.02252C20.7317 6.05041 20.7503 6.35718 20.5457 6.41295C20.5457 6.36647 20.5179 6.33859 20.5179 6.31999C20.2483 6.3014 20.7224 6.5338 20.5736 6.59888C20.49 6.47803 20.4528 6.45943 20.3691 6.44084L20.4807 6.65465C20.4807 6.65465 20.3319 6.48732 20.3041 6.42225C20.4528 6.70113 20.146 6.68254 20.2948 6.94283C20.239 6.89635 20.0902 6.66395 19.9973 6.58958C19.8764 6.58958 19.9043 6.71043 19.9322 6.83128C19.7556 6.71043 19.6626 6.83128 19.6626 6.7848C19.4767 6.81269 19.7463 6.92424 19.7742 7.13805L19.9508 7.15664L19.83 7.35186L19.8021 7.18453C19.6533 7.16594 19.737 7.42623 19.644 7.5006L19.7928 7.59356L19.7556 7.76089C19.5232 7.50989 19.5697 7.81666 19.3651 7.46341C19.0584 7.4913 19.235 7.94681 19.077 8.11414C19.1049 8.08625 19.0491 8.04907 19.0212 7.99329C18.8725 8.02118 18.9282 8.2071 18.984 8.39302C18.9282 8.30006 18.9282 8.25358 18.8632 8.17921C18.7423 8.28147 18.9189 8.39302 18.8632 8.57894C18.8074 8.4395 18.7423 8.39302 18.6865 8.39302C18.7795 8.48598 18.8074 8.57894 18.8074 8.62542C18.4541 8.02118 18.4727 8.54176 18.1845 8.07695C18.2775 8.1978 18.2682 8.59754 18.5099 8.75557V8.6812C18.6401 8.82064 18.5471 8.81135 18.5099 8.84853C18.5099 8.81135 18.5006 8.75557 18.4727 8.72768C18.4355 9.06234 18.1009 9.07164 18.0079 9.37841C17.98 9.31333 17.98 9.146 17.8871 9.146C17.6175 9.24826 17.729 9.6294 17.6361 9.93617C17.3386 9.61081 17.822 9.69447 17.5524 9.36911C17.3944 9.6387 17.2735 9.94547 17.1806 10.3266C16.6693 9.91758 17.1155 10.7356 16.6321 10.4846C16.7901 10.6334 16.7622 10.7542 16.6879 10.8379C16.5949 10.6799 16.5112 10.7542 16.4462 10.6334C16.502 10.8472 16.3532 11.0889 16.0836 10.7635C16.3346 11.0796 15.9163 10.8844 16.0557 11.154C15.8605 11.1168 15.9163 11.3864 15.7304 11.3957C15.9442 11.5537 15.7025 11.5909 15.7304 11.7024C15.7304 11.6838 15.7304 11.6281 15.7025 11.6095C15.5166 11.47 15.7025 11.8698 15.5537 11.8326C15.4608 11.7861 15.405 11.6467 15.3399 11.6745C15.4608 11.814 15.4329 12.1208 15.2191 12.0092C15.247 11.9813 15.1912 11.9162 15.154 11.8419C15.0704 12.3439 14.494 12.3439 14.4382 12.9016L14.2802 12.6227C13.8247 12.5019 14.494 13.1061 14.3174 13.2177C13.8061 13.478 13.0903 13.5524 12.8207 14.0636C12.8486 14.1566 12.9137 14.1287 13.0066 14.2217C12.9508 14.2217 12.7649 14.045 12.8207 14.2124L12.9415 14.3239C12.4489 14.1659 12.6441 15.0304 12.0212 14.6493C12.0398 15.0025 11.6029 14.7887 11.6866 15.2721C11.5192 15.2349 11.5564 15.0025 11.4449 15.0583V15.4209V15.393C11.6401 15.9043 10.5896 15.4859 10.6547 15.96V15.9321C10.5617 15.8485 10.413 15.8113 10.413 15.8764C10.4595 15.9414 10.5153 15.9414 10.6082 15.9879C10.5803 16.3226 10.5525 16.3691 10.4409 16.555C10.3665 16.3784 10.2736 16.5271 10.0784 16.3877C10.162 16.5271 10.2922 16.5178 10.3201 16.6944C10.2178 16.8525 9.99469 16.8153 9.78088 16.9826C9.89243 17.1964 9.78088 17.2615 9.9668 17.4567C9.80877 17.7821 9.75299 18.0052 9.56707 18.4886L9.51129 18.4049C9.66003 18.879 9.251 18.6094 9.32537 18.9162C9.26959 18.7582 9.2603 18.6559 9.19522 18.5629L9.17663 18.8976C9.15804 18.6652 9.00001 18.2469 8.92564 18.3398C8.99071 18.7953 9.02789 18.4979 9.10226 18.8232L8.91634 18.47C8.88845 18.6187 9.05578 19.1486 9.16733 19.1021C8.99071 19.5483 8.86986 20.3013 8.69323 20.6546L8.62816 20.2362C8.58168 20.5709 8.47013 20.8963 8.37717 20.701C8.37717 20.6732 8.35857 20.6546 8.35857 20.636C8.37717 20.7568 8.37717 20.9706 8.41435 21.1101C8.35858 21.5842 8.31209 20.45 8.25632 20.9706C8.27491 20.8498 8.3028 20.7847 8.27491 20.5523C8.24702 20.6267 8.21913 20.6917 8.19125 20.7568C8.17265 20.7847 8.16336 20.8126 8.14477 20.8405H8.0704C8.03321 20.5802 7.8194 19.8272 7.70785 19.8923C7.70785 20.0224 7.75433 20.2455 7.78222 20.3106L7.69855 20.3292L7.62418 19.7157C7.587 19.8272 7.54982 19.9388 7.51263 20.041V19.6041C7.42897 19.6041 7.38249 20.0968 7.29882 19.9667C7.03853 19.3717 7.1036 19.3066 6.98275 18.7396C6.84331 19.4182 6.71317 18.3863 6.55513 18.8139C6.45288 18.0517 6.01596 17.9215 5.77426 17.4381H5.83004C5.87652 17.0756 5.42101 17.5869 5.34664 17.3173L5.4396 17.2987C5.45819 17.0849 5.32805 16.9175 5.18861 16.8432C5.05846 16.7688 4.87254 16.7409 4.71451 16.7409C4.80747 16.7223 4.92832 16.5922 4.87254 16.555C4.75169 16.5829 4.60295 16.8339 4.62155 16.6851C4.67732 16.6758 4.76099 16.5829 4.7424 16.555L4.46351 16.6387C4.43563 16.2947 4.37985 15.9136 4.07308 15.7834C4.11026 15.6812 4.22182 15.6533 4.29618 15.6068C4.11026 15.4581 3.7849 15.4209 3.61757 15.2814L3.84997 15.0676C3.7849 14.9839 3.43165 15.3186 3.57109 15.0397C3.58968 14.9932 3.64546 15.0955 3.7756 15.0397C3.84068 14.733 3.45954 15.1327 3.36658 14.9561L3.68264 14.7794C3.75701 14.5284 3.43165 14.7608 3.22713 14.8445C2.76233 14.9282 3.68264 14.3053 3.25502 14.2682C3.08769 14.3425 3.0598 14.4355 2.89247 14.5098C2.84599 14.2867 2.62289 14.4262 2.57641 14.2031C2.93896 13.794 2.64148 14.2867 2.96684 13.887V14.0822C3.10628 13.8033 3.09699 14.138 3.32939 13.9242C3.33869 13.7848 3.03192 13.8312 2.87388 13.7848C3.0598 13.6453 2.98544 13.887 3.20854 13.6453H3.08769C3.15277 13.6267 3.22713 13.5709 3.24573 13.6081C3.41306 13.4501 3.20854 13.5338 3.16206 13.4873C3.0598 13.5616 2.92036 13.6639 2.79951 13.7848C2.81811 13.7662 2.8367 13.7476 2.85529 13.7197C2.50204 13.8219 2.57641 13.4873 2.28823 13.5616C2.3533 13.5338 2.3626 13.5059 2.40908 13.4687C2.37189 13.3943 2.07442 13.5152 1.93498 13.4873C2.03723 13.3385 2.38119 13.1991 2.19527 13.1247C2.01864 13.2177 1.78624 13.4873 1.70258 13.3571C1.70258 13.3571 1.90709 13.3571 1.98146 13.227H1.95357ZM4.28689 15.5045C4.28689 15.5045 4.31478 15.5324 4.34266 15.551C4.34266 15.551 4.29618 15.5138 4.28689 15.5045ZM4.61225 15.5696C4.61225 15.5696 4.51929 15.5975 4.45422 15.6533C4.48211 15.6905 4.50999 15.7183 4.51929 15.7555C4.55647 15.6719 4.55647 15.5882 4.61225 15.5696ZM5.46749 14.2403L5.49538 14.2217C5.49538 14.2217 5.55116 14.2496 5.56975 14.2589C5.60693 14.2217 5.63482 14.1752 5.57904 14.1659C5.55116 14.1845 5.50468 14.2031 5.46749 14.231V14.2403Z\" fill=\"#8F3A7E\"><\/path><path d=\"M5.26323 14.3253C5.26323 14.3253 5.24482 14.3253 5.23562 14.3253C5.22642 14.3437 5.21721 14.3621 5.20801 14.3805L5.28164 14.3437L5.26323 14.3253Z\" fill=\"#8F3A7E\"><\/path><path d=\"M21.6523 4.27579C21.6523 4.27579 21.6712 4.27579 21.69 4.29463C21.6806 4.29463 21.6712 4.28521 21.6618 4.27579H21.6523Z\" fill=\"#8F3A7E\"><\/path><path d=\"M7.48508 20.1339L7.49435 20.032L7.46655 20.0876L7.48508 20.1339Z\" fill=\"#8F3A7E\"><\/path><path d=\"M23.4094 3.96896C23.4094 3.96896 23.4473 3.9974 23.4663 4.00688C23.4568 3.9974 23.4284 3.97844 23.4094 3.96896Z\" fill=\"#8F3A7E\"><\/path><path d=\"M24.4309 3.36418C24.4309 3.36418 24.3847 3.29949 24.3662 3.27176L24.4309 3.36418Z\" fill=\"#8F3A7E\"><\/path><path d=\"M19.885 6.80322C19.8943 6.85893 19.9036 6.90536 19.9036 6.95178C19.95 6.9425 19.9779 6.92393 19.885 6.80322Z\" fill=\"#8F3A7E\"><\/path><path d=\"M16.6518 10.8394L16.6318 10.8494L16.6518 10.8394Z\" fill=\"#8F3A7E\"><\/path><path d=\"M19.8203 7.01859C19.885 7.02783 19.9035 7.0001 19.9035 6.95389C19.8665 6.96313 19.8203 6.97237 19.8203 7.01859Z\" fill=\"#8F3A7E\"><\/path><path d=\"M26.1981 2.03489H26.2264C26.2264 2.03489 26.2075 2.00662 26.1981 1.99719V2.03489Z\" fill=\"#8F3A7E\"><\/path><path d=\"M26.1977 1.99845V1.96075C26.1977 1.96075 26.1789 1.9796 26.1977 1.99845Z\" fill=\"#8F3A7E\"><\/path><path d=\"M26.2079 1.8683V1.95148C26.2079 1.95148 26.2449 1.933 26.2079 1.8683Z\" fill=\"#8F3A7E\"><\/path><path d=\"M25.6025 2.37845L25.6578 2.45208C25.6578 2.45208 25.6302 2.40606 25.6025 2.37845Z\" fill=\"#8F3A7E\"><\/path><path d=\"M25.4627 2.52706C25.5183 2.50852 25.6852 2.60121 25.7037 2.51779L25.6574 2.45291C25.7223 2.58267 25.3978 2.37876 25.4627 2.52706Z\" fill=\"#8F3A7E\"><\/path><path d=\"M24.0587 2.18406L24.2354 2.12826C24.1517 2.07245 24.0308 1.98874 24.0773 1.92363C23.7145 1.83062 24.254 2.07245 24.0587 2.18406Z\" fill=\"#8F3A7E\"><\/path><path d=\"M23.5575 2.40555C23.5946 2.31271 23.4646 2.29414 23.4275 2.24771C23.4461 2.35913 23.4461 2.38698 23.5575 2.40555Z\" fill=\"#8F3A7E\"><\/path><path d=\"M20.6004 4.88834L20.4517 4.70251C20.4239 4.77684 20.5075 4.77684 20.6004 4.88834Z\" fill=\"#8F3A7E\"><\/path><path d=\"M20.833 6.30117L20.9817 6.36621L20.8702 6.18039L20.833 6.30117Z\" fill=\"#8F3A7E\"><\/path><path d=\"M19.4009 5.29716L19.4102 5.25073L19.373 5.39001L19.4009 5.29716Z\" fill=\"#8F3A7E\"><\/path><path d=\"M14.5673 9.62069L14.7804 9.8246C14.7804 9.75045 14.5673 9.5002 14.5673 9.62069Z\" fill=\"#8F3A7E\"><\/path><path d=\"M12.6902 11.7309C12.5694 11.6473 12.4486 11.6287 12.5044 11.7681C12.5601 11.7402 12.6902 11.7774 12.6902 11.7309Z\" fill=\"#8F3A7E\"><\/path><path d=\"M7.70828 16.6682L7.6897 16.4824L7.69899 16.659L7.70828 16.6682Z\" fill=\"#8F3A7E\"><\/path><path d=\"M1.70163 9.61194C1.61792 9.63054 1.4691 9.73285 1.52491 9.76076L1.81324 9.63984L1.70163 9.61194Z\" fill=\"#8F3A7E\"><\/path><path d=\"M1.38543 10.1886C1.54327 10.17 1.80325 10.0957 2.02609 9.91004C1.74754 10.0122 1.84039 9.9379 1.50613 10.0586C1.45042 10.0307 1.54327 9.92861 1.64541 9.88219C1.57113 9.90076 1.66398 9.78006 1.47828 9.85433C1.30187 10.0307 1.33901 10.1143 1.55256 10.0865C1.50613 10.1329 1.42257 10.1607 1.37615 10.1886H1.38543Z\" fill=\"#8F3A7E\"><\/path><path d=\"M6.07034 17.5318C6.07034 17.5318 6.02367 17.5318 6.005 17.5598C6.033 17.5598 6.06101 17.5598 6.07034 17.5318Z\" fill=\"#8F3A7E\"><\/path><path d=\"M6.40438 18.461C6.40438 18.461 6.38574 18.4238 6.38574 18.4051C6.38574 18.4517 6.38574 18.4797 6.40438 18.461Z\" fill=\"#8F3A7E\"><\/path><path d=\"M4.03508 14.7249L4.01648 14.8551C4.10019 14.7993 4.04438 14.7714 4.03508 14.7249Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.3788 10.391C2.3788 10.391 2.32335 10.391 2.28638 10.391C2.30486 10.391 2.32335 10.4002 2.33259 10.4095L2.3788 10.3817V10.391Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.96444 13.7376L2.94584 13.719C2.94584 13.719 2.87143 13.7562 2.83423 13.7748L2.96444 13.7376Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.26855 12.8844C2.26855 12.8844 2.49178 12.7635 2.58479 12.7077C2.49178 12.7635 2.43597 12.7728 2.40807 12.7728C2.37087 12.8007 2.32436 12.8379 2.26855 12.8937V12.8844Z\" fill=\"#8F3A7E\"><\/path><path d=\"M3.40322 14.398C3.40322 14.398 3.34722 14.4447 3.33789 14.4634C3.36589 14.4447 3.38456 14.4167 3.40322 14.398Z\" fill=\"#8F3A7E\"><\/path><path d=\"M24.3936 0.882324C24.3936 0.882324 24.4124 0.910594 24.4218 0.920017C24.4124 0.891747 24.403 0.882324 24.3936 0.882324Z\" fill=\"#8F3A7E\"><\/path><path d=\"M26.1963 1.0585V1.08636L26.2891 1.19778L26.1963 1.0585Z\" fill=\"#8F3A7E\"><\/path><path d=\"M7.32639 20.0692C7.32639 20.0692 7.32639 20.0692 7.32639 20.0592C7.29639 20.0692 7.31639 20.0792 7.32639 20.0692Z\" fill=\"#8F3A7E\"><\/path><path d=\"M13.8886 13.0136C13.6561 12.9113 13.8142 12.6788 13.5166 12.5951C13.6003 12.6602 13.684 12.995 13.8886 13.0136Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.37 10.4381C2.37 10.4381 2.38884 10.457 2.39826 10.4758C2.39826 10.457 2.38884 10.4476 2.37 10.4381Z\" fill=\"#8F3A7E\"><\/path><path d=\"M9.13905 18.7775C9.11125 18.7312 9.08346 18.6942 9.05566 18.6756C9.07419 18.7127 9.09272 18.7405 9.13905 18.7775Z\" fill=\"#8F3A7E\"><\/path><path d=\"M7.87305 19.9031L7.91937 20.005C7.90084 19.9494 7.89158 19.9216 7.87305 19.9031Z\" fill=\"#8F3A7E\"><\/path><path d=\"M9.5293 17.1406C9.5293 17.1406 9.59373 17.1407 9.59373 17.0762C9.58452 17.0762 9.57532 17.0762 9.56611 17.067C9.58452 17.1038 9.58452 17.1406 9.5385 17.1406H9.5293Z\" fill=\"#8F3A7E\"><\/path><path d=\"M10.1335 16.3052C10.1335 16.3052 10.0955 16.2957 10.0861 16.2863V16.3147L10.1335 16.3052Z\" fill=\"#8F3A7E\"><\/path><path d=\"M22.2911 2.80592C22.3562 2.85237 22.4119 2.89883 22.477 2.95457C22.3469 2.8245 22.4119 2.68513 22.2911 2.80592Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.25891 10.4761C2.31499 10.448 2.35237 10.4293 2.37106 10.4387L2.34302 10.42C2.34302 10.42 2.2776 10.4574 2.25891 10.4761Z\" fill=\"#8F3A7E\"><\/path><path d=\"M8.05957 15.6353L8.11645 15.6163C8.11645 15.6163 8.06905 15.6163 8.05957 15.6353Z\" fill=\"#8F3A7E\"><\/path><path d=\"M17.1702 7.21375V7.16635C17.1702 7.16635 17.1607 7.18531 17.1702 7.21375Z\" fill=\"#8F3A7E\"><\/path><path d=\"M8.31042 15.2827C8.40334 15.3198 8.45908 15.3198 8.50554 15.3198C8.49625 15.3013 8.48696 15.2827 8.46837 15.2641L8.31042 15.2827Z\" fill=\"#8F3A7E\"><\/path><path d=\"M22.9801 2.12785C22.9986 1.93263 23.0544 2.14644 23.2961 2.2394C23.1753 1.97911 23.4635 2.23011 23.1846 1.86756C23.417 2.07207 23.3333 1.98841 23.5378 2.09996C23.3519 1.93263 23.5099 1.80249 23.3147 1.57938C23.5564 1.81178 23.4635 1.98841 23.7795 2.18363C23.6959 1.96052 23.7516 1.80249 23.5285 1.51431C23.6308 1.5422 23.733 1.62586 23.826 1.58868C23.7981 1.58868 23.826 1.64445 23.8446 1.68164C23.8167 1.38416 24.1607 1.42135 23.9468 1.02161C24.2536 1.44923 24.2629 0.844989 24.4767 1.3005C24.5232 1.24472 24.4581 1.00302 24.4117 0.910061C24.6719 1.22613 24.6069 0.882173 24.8207 1.02161C24.6998 0.8171 24.8486 0.798508 24.8207 0.649771C24.8207 0.705547 24.8579 0.77062 24.9415 0.854285C24.895 0.668363 24.988 0.807804 25.1646 0.910061C25.1646 0.742732 24.9508 0.686955 24.8765 0.491737C25.0159 0.491737 25.0531 0.677659 25.1739 0.798508L25.0252 0.38948C25.0717 0.398776 25.1367 0.445257 25.2204 0.528921C25.1832 0.408072 25.1089 0.240743 25.2855 0.343L25.1925 0.435961L25.3599 0.566106L25.3041 0.268631C25.6666 0.361592 25.899 0.742732 26.1593 1.08669L26.1407 1.19824C26.2337 1.30979 26.3359 1.33768 26.3731 1.31909C26.4661 1.37487 26.5683 1.7746 26.5219 1.87685C26.3081 2.02559 26.1593 1.5236 25.9548 1.55149L25.9362 1.89545L25.8432 1.78389C25.7503 1.72812 25.8432 1.86756 25.8525 1.90474C25.7224 1.72812 25.6666 1.96982 25.5644 2.007L25.7131 2.12785C25.7968 2.63913 25.0903 2.02559 25.081 2.34166L25.1739 2.68561L24.9694 2.4904C25.0066 2.67632 25.1367 2.85294 24.9694 2.86224C24.2815 2.79717 24.2629 3.59663 23.6773 3.6803C23.7144 3.71748 23.7423 3.72678 23.7981 3.73607C23.0172 3.47578 23.7423 4.72146 23.0916 4.55413L23.0451 4.46117C22.9243 4.6285 22.9986 4.35891 22.7848 4.34032C22.9801 4.6192 22.7662 4.70287 22.7569 4.87949C22.7291 4.81442 22.7569 4.79583 22.7569 4.73075C22.6919 4.68427 22.5524 4.53554 22.5524 4.6192C22.7755 5.07471 22.5338 5.21415 22.4688 5.45585C22.3014 5.29782 22.0411 5.26063 21.7437 5.03752C21.7809 5.11189 21.8645 5.26993 21.9482 5.41866C21.7995 5.35359 21.8273 5.47444 21.8738 5.61388C21.9203 5.5674 21.9575 5.53022 21.9854 5.49303V5.51163C21.9854 5.51163 21.9947 5.48374 22.004 5.47444C22.0319 5.43726 22.0412 5.40937 22.0226 5.40937C22.2271 5.52092 22.1341 5.54881 22.3014 5.74403C22.2457 5.78121 22.1992 5.93925 22.0597 5.7998C22.0226 5.8184 21.9854 5.8184 21.9296 5.8184C21.9296 5.86488 21.9296 5.90206 21.8924 5.90206V5.87417C21.8924 5.87417 21.8366 5.83699 21.818 5.8184C21.6507 5.8184 21.7623 6.23672 21.7995 6.44123C21.6693 6.12517 21.5392 6.17165 21.3811 5.99502C21.3811 6.01361 21.4927 5.93925 21.6228 5.83699C21.5949 5.82769 21.5578 5.7998 21.502 5.73473C21.2324 5.63247 21.4648 6.06009 21.1859 6.06009C21.1859 6.03221 21.1673 5.97643 21.1022 5.91136C21 5.91136 21.0744 6.09728 21.158 6.21813C20.9907 6.0508 20.7676 6.02291 20.7676 6.15306C20.842 6.34827 20.907 6.40405 20.7955 6.46912L20.7304 6.31109C20.5259 6.30179 20.7955 6.57138 20.6188 6.55279C20.7025 6.57138 20.591 6.44123 20.5445 6.43194C20.4887 6.59927 20.5445 6.67364 20.6746 6.9897L20.5259 6.77589C20.5259 6.98041 20.5445 7.38014 20.3214 7.11055C20.7025 7.49169 20.2935 7.51028 20.2005 7.57536C20.2191 7.53817 20.154 7.44521 20.1169 7.39873C20.1726 7.82635 19.7636 7.7148 19.587 7.88213L19.2988 7.61254C19.2151 7.7055 19.6892 8.31904 19.5777 8.39341L19.494 8.21679C19.3546 8.4213 19.2523 8.45849 19.0664 8.54215L18.8991 8.33764C18.927 8.47708 18.8619 8.53285 18.8898 8.6723C18.3506 8.29116 18.6295 9.34161 17.9416 8.99766L18.2483 9.3788C18.1554 9.44387 18.1089 9.6112 17.83 9.3788H17.8579C17.6162 9.08132 17.7649 9.43458 17.6627 9.41598C17.6534 9.48106 17.7742 9.70416 17.8579 9.72275C17.4675 9.72275 17.3094 10.2154 16.8725 10.0109C16.7517 10.327 16.8446 10.7732 16.5658 10.9498L16.5286 10.9034C16.4077 10.9219 16.1474 10.9684 15.8778 10.6617C15.7663 10.8848 16.0359 11.4053 15.7012 11.4518L15.6454 11.2938C15.5432 11.2845 15.5897 11.4983 15.599 11.5541C15.5711 11.5634 15.5339 11.489 15.4967 11.4425C15.3573 11.3868 15.4688 11.5727 15.4595 11.6377L15.3851 11.5169C15.0319 11.4518 15.1435 12.1026 14.8925 12.242C14.9018 12.1769 14.7809 12.084 14.7158 12.0468C14.9389 12.4651 14.6229 12.5952 14.6136 12.7533L14.5485 12.5767C14.5764 12.9578 14.0744 12.3535 14.1116 12.7347L14.3812 12.8369C14.2603 12.8369 14.2603 12.9578 14.4184 13.0972C14.2324 13.0601 14.1767 12.8462 14.0186 12.9299C13.9257 12.8369 14.0465 12.7812 13.8978 12.6975L13.498 12.6045C13.498 12.6045 13.4423 12.5952 13.4144 12.6696C13.8141 13.0786 13.2935 12.8184 13.7583 13.153C13.5538 13.404 13.0983 13.311 13.0704 13.6922C12.6149 13.3668 12.6521 14.0547 12.1873 13.5156C12.0664 13.6178 12.0757 13.813 12.2059 14.0826C12.271 14.1012 12.2338 14.0083 12.2338 13.9618C12.3267 14.1198 12.2152 14.2685 12.1594 14.3243C12.1222 14.1384 12.1501 13.9246 12.02 13.6736C11.9642 13.8223 12.0014 14.1477 12.0107 14.2685L11.7318 14.0268C11.834 14.3057 11.4529 13.8781 11.6202 14.2221L11.7132 14.2871C11.5366 14.4173 11.7876 14.6869 11.6853 14.8542L11.5923 14.7426C11.4994 14.7426 11.676 15.068 11.3878 14.8821L11.4715 14.7798C11.2856 14.6032 11.1275 14.6032 11.0067 14.5381C10.9509 14.6869 11.267 14.8635 11.2484 14.9379C11.0532 14.7891 11.1554 14.8542 11.016 14.6497C10.9602 14.817 10.8951 15.0401 11.0439 15.3376C11.016 15.319 10.9788 15.2725 10.9788 15.2725C10.8394 15.3562 11.0625 15.7559 10.8487 15.6908V15.6444C10.4954 15.5049 10.8765 16.1092 10.4024 15.728C10.2816 15.7001 10.514 15.6444 10.2258 15.5142C9.95623 15.5328 10.5233 15.9418 10.2909 15.9511C10.3188 15.9511 10.2909 15.9325 10.2537 15.8861C10.1886 15.9883 10.1329 16.1464 10.0957 16.2858C9.60298 16.1185 9.90046 16.732 9.3148 16.574C9.51002 16.639 9.46354 16.7692 9.52861 16.8343C9.52861 16.8343 9.49143 16.7878 9.46354 16.7785C9.39847 16.8343 9.53791 16.983 9.58439 17.0667C9.41706 17.0016 9.58439 17.4385 9.46354 17.4013C9.54721 17.5036 9.48213 17.5501 9.43565 17.6244C9.43565 17.3455 9.28692 17.3363 9.18466 17.1131C9.02663 17.234 9.40776 17.8661 9.21255 18.0613C9.13818 18.0242 9.07311 17.987 8.99874 17.9405C9.20325 18.3867 8.99874 18.4983 9.07311 18.6656C8.98944 18.5726 8.92437 18.554 8.82211 18.303C8.82211 18.5354 8.65478 18.4239 8.74774 18.7957L8.8407 18.8236C8.72915 18.9073 8.71985 19.1955 8.70126 19.4929C8.68267 19.7811 8.65478 20.06 8.55253 19.9856L8.33872 18.9445C8.19927 18.647 8.33872 19.8462 8.17139 19.2977C8.24575 19.6417 8.23646 19.5022 8.25505 20.0042C8.29223 20.0135 8.28294 19.5952 8.32942 19.4929L8.34801 20.404L8.44097 19.6882C8.45956 20.2738 8.44097 20.1716 8.55253 20.5341C8.52464 21.0547 8.40379 20.5713 8.35731 20.7386C8.34801 20.7386 8.32942 20.7758 8.32012 20.8502C8.25505 20.6828 8.23646 20.2831 8.17139 20.06C8.12491 20.4411 7.94828 19.4093 7.9018 19.7718C7.86461 19.6417 7.94828 19.7997 7.92039 19.5673C7.85532 19.5673 7.80884 19.4744 7.79954 19.7253L7.87391 19.902C7.81813 19.809 7.82743 20.1716 7.69728 19.8276C7.64151 19.9577 7.60432 20.3296 7.68799 20.4318C7.6601 20.4504 7.57644 20.1344 7.60432 19.902C7.4277 19.6789 7.51136 20.6921 7.32544 20.0693C7.34403 20.0693 7.35333 20.0321 7.35333 19.9763C7.30685 19.8648 7.26967 19.8183 7.23248 19.8276C7.39981 19.9485 7.22318 19.1304 7.39051 19.4929C7.39051 19.0374 7.26037 19.2512 7.21389 19.0188C7.10234 19.1955 7.15811 19.5952 7.09304 19.7439C7.10234 19.6138 7.06515 19.5673 7.02797 19.4651L7.04656 19.8183C7.00008 19.7718 6.96289 19.716 6.90712 19.7253L7.00937 19.7068C6.91641 19.5394 6.86993 18.9352 6.67472 19.0281C6.73979 18.9631 6.85134 18.8236 6.79556 18.5726C6.60964 18.5726 6.78627 18.4146 6.75838 18.1264C6.60964 18.0242 6.60964 18.5633 6.44231 18.1543C6.42372 18.1264 6.38654 18.2937 6.38654 18.3867C6.28428 18.0892 6.12625 18.145 6.06117 17.8196C6.08906 17.9498 6.10765 18.0892 5.96821 18.0799C6.09836 17.9498 5.93103 17.7732 5.94032 17.6058L5.86596 17.6895C5.89384 17.5315 5.96821 17.5501 6.02399 17.5501C6.0054 17.5779 5.9961 17.6244 6.02399 17.6523C6.14484 17.6523 6.33076 17.2247 6.27498 17.0853C6.12625 17.0667 5.95892 17.327 5.91244 17.4478C5.83807 17.1782 5.44763 17.6802 5.40115 17.3548C5.36397 17.3084 5.55918 16.8529 5.50341 16.7134C5.25241 16.8064 5.48482 16.9923 5.27101 17.0667C5.56848 16.4345 4.68535 16.9551 4.78761 16.481L5.0479 16.3137C5.02001 16.2486 5.00142 16.1928 4.92705 16.1556L4.85268 16.3323C4.75972 16.3323 4.71324 16.1742 4.92705 16.0627C4.63887 16.1092 4.74113 15.9883 4.71324 15.8396C4.77831 15.9697 4.68535 15.8675 4.87127 15.8489C4.89916 15.6351 4.8062 15.6908 4.69465 15.6537C4.78761 15.5979 4.88987 15.4491 4.86198 15.4213C4.64817 15.4677 4.5738 15.3097 4.41577 15.2725L4.49013 15.2167C4.25773 15.1145 4.44365 14.6497 4.0904 14.6404C4.0904 14.6404 4.08111 14.6404 4.07181 14.6404V14.6683C3.88589 14.91 3.79293 14.6497 3.66278 14.6683C3.70926 14.6125 3.81152 14.5288 3.78363 14.4916C3.56982 14.659 3.6163 14.5102 3.49545 14.5567C3.52334 14.4359 3.76504 14.3615 3.67208 14.2685C3.6256 14.2407 3.50475 14.3243 3.42108 14.3894C3.51404 14.2778 3.55123 14.1477 3.53264 14.0733C3.60701 14.0454 3.55123 14.1384 3.57912 14.1384C3.69997 14.0547 3.6256 14.0547 3.77434 13.9432C3.75574 13.8781 3.55123 14.0826 3.57912 13.9618L3.79293 13.8874C3.82082 13.8316 3.71856 13.8502 3.69997 13.8502C3.77434 13.8502 3.94166 13.7201 4.04392 13.6364C3.81152 13.5899 3.56053 13.9618 3.36531 14.1012C3.3932 13.8595 3.08642 13.9246 2.99346 13.8223L3.21657 13.6922C3.1422 13.6643 3.07713 13.6736 2.97487 13.7201L2.9098 13.6364C3.02135 13.6364 3.09572 13.5992 3.26305 13.4784C3.1422 13.4319 3.10502 13.2832 2.81684 13.4598L2.86332 13.4319C2.87261 13.246 2.75177 12.9578 2.85402 12.902C2.6681 12.8462 2.71458 12.5674 2.4357 12.7626C2.31485 12.7347 2.64951 12.3164 2.26837 12.5116C2.38922 12.2885 2.34274 12.4558 2.56584 12.335C2.68669 12.1211 2.15682 12.3628 2.52866 12.0468C2.33344 12.0282 2.46359 12.1304 2.25907 12.2234C2.61232 11.9352 2.1847 11.991 2.32415 11.74C2.14752 11.8051 2.25907 11.8516 2.05456 11.8887C2.15682 11.833 2.13822 11.7772 2.13822 11.7493L1.89653 11.8887L2.39851 11.3868C2.01737 11.4332 2.01737 11.6935 1.77568 11.5727H1.80356C2.00808 11.3496 1.52468 11.5541 1.60835 11.2845C1.59905 11.3682 1.73849 11.2287 1.81286 11.2008L1.66412 11.1822C1.66412 11.1822 1.70131 11.1822 1.7199 11.1451C1.85005 10.9591 1.58046 11.1451 1.68272 10.9591C1.76638 10.987 1.93371 10.8476 2.00808 10.7639L1.66412 10.8197L2.01737 10.6524C1.97089 10.5222 1.33876 10.6803 1.75708 10.3363L1.84075 10.3642C1.91512 10.3084 2.13822 10.1318 1.92441 10.1597C1.86864 10.1597 1.66412 10.2619 1.70131 10.2898L1.73849 10.1876C1.97089 10.0853 2.11963 10.1876 2.23118 10.234C2.12893 10.2619 2.01737 10.234 1.89653 10.3456C2.01737 10.3828 2.2033 10.3642 2.32415 10.3921C2.22189 10.42 2.07315 10.485 1.98019 10.5222C1.92441 10.6803 2.16611 10.4943 2.23118 10.5408C2.16611 10.6245 2.11963 10.671 2.03597 10.6988C2.17541 10.7267 2.24048 10.7732 2.1847 10.9312C2.1847 10.9312 1.97089 10.9312 1.87793 11.0707C2.11034 11.1451 2.37992 11.0056 2.64021 11.0707C3.12361 11.0149 2.68669 11.5913 3.03065 11.5448C3.12361 11.489 3.12361 11.331 3.24446 11.3775C3.04924 11.4983 3.16079 11.5169 3.09572 11.5727C3.43038 11.4704 3.13291 11.7493 3.36531 11.6842C3.29094 11.7121 3.25375 11.8237 3.21657 11.898C2.98417 12.0561 3.19798 12.0654 2.77965 12.1676C3.22587 12.0561 2.87261 12.4837 3.47686 12.1955L3.51404 12.1118V12.3257V12.3164C3.51404 12.4 3.58841 12.3721 3.41179 12.6231C3.32812 12.6231 3.29094 12.5767 3.20727 12.5859C3.06783 12.8091 3.48616 12.6138 3.56053 12.6882C3.3932 12.8091 3.43968 12.6417 3.25375 12.8184C3.27235 12.8927 3.43038 12.8555 3.51404 12.8741L3.42108 12.9299C3.32812 13.2274 3.90448 12.651 3.68137 12.9857C3.72785 12.9392 3.80222 12.9113 3.8487 12.8648C3.78363 12.9764 3.69067 13.1902 3.50475 13.1809C3.54193 13.2274 3.66278 13.2274 3.78363 13.1809C3.88589 13.0415 3.81152 13.0786 3.96955 12.9299L4.22055 13.0601C4.22055 13.0601 4.11829 13.1065 4.0997 13.0786C3.80222 13.6829 4.87127 13.246 4.49943 13.9525C4.62028 13.813 4.64817 13.8688 4.75972 13.8223C4.77831 13.9432 4.91775 14.0454 4.88987 14.1942L4.76902 14.2499C5.0479 14.3615 5.31749 14.3801 5.36397 14.5567C5.41045 14.5288 5.22453 14.6683 5.16875 14.6683C5.42904 14.6218 4.94564 15.1981 5.35467 14.9193V14.8542C5.44763 15.1052 5.89384 15.0959 6.10765 15.2632C5.91244 15.4956 5.9868 15.1703 5.7544 15.4306C5.77299 15.6444 6.08906 15.6258 6.12625 15.8396C6.07977 15.8396 6.05188 15.8675 6.03328 15.8675C6.0054 16.1371 6.2471 15.663 6.32146 15.821C6.20061 15.9047 6.18202 15.9325 6.15413 16.0255L6.36794 15.9139C6.36794 15.9139 6.20061 16.0627 6.13554 16.0906C6.41442 15.9418 6.36794 16.2114 6.59105 16.0348C6.54457 16.0999 6.34006 16.2765 6.27498 16.3695C6.27498 16.4996 6.37724 16.4531 6.4795 16.3973C6.38654 16.6019 6.48879 16.6855 6.45161 16.6948C6.48879 16.89 6.56316 16.574 6.7212 16.481L6.73979 16.2951L6.86993 16.3509L6.75838 16.4438C6.74908 16.6112 6.92571 16.4252 6.96289 16.481L7.01867 16.2765C7.01867 16.2765 7.08374 16.2393 7.11163 16.2207C6.97219 16.6019 7.14882 16.388 6.96289 16.7971C7.03726 17.1596 7.24178 16.7041 7.32544 16.7506C7.30685 16.732 7.30685 16.8343 7.28826 16.9086C7.33474 17.0853 7.39981 16.8807 7.43699 16.6483C7.4184 16.7971 7.40911 16.8436 7.39051 16.9644C7.45559 17.0481 7.44629 16.7227 7.51136 16.6297C7.49277 16.8343 7.49277 16.9551 7.51136 17.0295C7.51136 16.8343 7.52996 16.7041 7.53925 16.6669C7.48347 17.6802 7.62292 17.2061 7.60432 18.0428C7.61362 17.8289 7.71588 17.4757 7.6508 16.9644V17.0295C7.62292 16.7134 7.6508 16.8621 7.6601 16.8529C7.6601 16.8993 7.6508 16.9551 7.6601 17.0202C7.68799 16.89 7.72517 16.9365 7.74377 16.9179C7.76236 16.8622 7.78095 16.8343 7.79025 16.7506C7.79025 16.7041 7.79954 16.6483 7.79954 16.574C7.81813 16.6948 7.82743 16.9458 7.85532 17.0016C7.94828 17.0016 7.88321 16.3695 7.85532 16.0627C8.03194 16.6205 7.82743 16.2579 7.96687 16.8436C8.01335 16.5368 8.03194 16.1928 7.96687 15.8582C8.15279 16.1649 8.1435 16.0534 8.11561 15.9418C8.08772 15.821 8.04124 15.7187 8.23646 15.8768C8.08772 15.7094 8.05983 15.6165 8.06913 15.5793C8.18998 15.7187 8.21787 15.6815 8.30153 15.7745C8.24575 15.6815 8.20857 15.6072 8.23646 15.5793C8.25505 15.57 8.39449 15.5142 8.55253 15.663C8.23646 15.3934 8.70126 15.4956 8.52464 15.2539C8.72915 15.2446 8.62689 14.975 8.83141 14.9286C8.59901 14.8077 8.8407 14.7241 8.79422 14.6125C8.79422 14.6404 8.79422 14.6869 8.83141 14.7055C9.02663 14.8077 8.80352 14.4359 8.97085 14.4545C9.06381 14.4824 9.13818 14.6218 9.20325 14.5846C9.06381 14.4638 9.07311 14.1384 9.29621 14.2221C9.26832 14.2499 9.3334 14.315 9.37058 14.3801C9.42636 13.8502 10.0213 13.7851 10.0585 13.2274L10.2165 13.497C10.6813 13.5899 9.98412 13.0136 10.17 12.8927C10.6906 12.5952 11.425 12.5209 11.6853 12.0003C11.6574 11.9073 11.5923 11.9352 11.4994 11.8423C11.5645 11.8423 11.7411 12.0189 11.6853 11.8516L11.5645 11.74C12.0479 11.898 11.8898 11.0242 12.5034 11.4146C12.5034 11.0614 12.931 11.2752 12.8752 10.7918C13.0425 10.8383 12.9868 11.0707 13.1076 11.0242L13.1355 10.6524V10.6803C13.0054 10.1411 14.0186 10.6245 14.0279 10.1504V10.1783C14.1023 10.2712 14.251 10.327 14.2603 10.2619C14.2231 10.1876 14.1674 10.1783 14.0744 10.1318C14.1581 9.79712 14.2045 9.74135 14.3533 9.56472C14.3905 9.75994 14.5206 9.6112 14.6879 9.78783C14.6322 9.62979 14.502 9.62979 14.5113 9.44387C14.6415 9.29513 14.911 9.33232 15.0784 9.29513C14.9854 9.09062 15.0877 9.08132 14.9203 8.88611C15.0691 8.72807 15.097 8.57004 15.2922 8.40271L15.3573 8.46778C15.1992 8.1796 15.6361 8.43989 15.5525 8.26327C15.6268 8.35623 15.6361 8.41201 15.7012 8.46778L15.7198 8.30975C15.7384 8.4213 15.9243 8.6723 16.0173 8.63511C15.9429 8.39341 15.8964 8.53285 15.8035 8.36552L16.0266 8.57004C16.0638 8.49567 15.85 8.22608 15.7198 8.21679C15.9243 8.04016 16.0266 7.76128 16.2311 7.64043L16.3426 7.80776C16.3891 7.66832 16.5286 7.54747 16.6959 7.63113C16.6587 7.58465 16.6122 7.4824 16.5565 7.44521C16.5007 7.13844 16.7796 7.67761 16.7238 7.35225C16.7424 7.43592 16.7238 7.50099 16.7982 7.59395L16.8818 7.20351C16.9841 7.31507 17.3466 7.43592 17.3559 7.24999C17.3094 7.18492 17.2072 7.12914 17.17 7.13844L17.1886 7.02689L17.4675 7.2407L17.3652 6.93393L17.5511 7.14774C17.579 7.04548 17.3745 6.73871 17.4396 6.71082C17.7742 6.66434 17.7928 6.77589 18.1182 6.85026C17.7742 6.42264 18.3692 6.66434 18.1554 6.32968C18.6202 6.46912 18.7503 6.03221 19.0943 5.89277V5.94854C19.3825 6.0415 18.9641 5.52092 19.1594 5.50233L19.178 5.58599C19.5219 5.67896 19.6242 5.24204 19.6242 4.93527C19.6428 5.01893 19.7729 5.13978 19.8101 5.0933C19.7822 4.98175 19.5219 4.83301 19.6706 4.84231C19.6799 4.89808 19.7822 4.98175 19.8008 4.96316L19.7078 4.68427C20.0425 4.64709 20.4236 4.58202 20.5445 4.26595C20.6467 4.30313 20.6839 4.40539 20.7304 4.48906C20.8698 4.29384 20.8977 3.96847 21.0279 3.80115L21.251 4.03355C21.3254 3.96847 20.9907 3.62452 21.2696 3.75466C21.3161 3.76396 21.2138 3.82903 21.2696 3.95918C21.5856 4.00566 21.1673 3.64311 21.3346 3.54085L21.5299 3.84763C21.7809 3.9127 21.5392 3.59663 21.4462 3.39212C21.3346 2.93661 22.004 3.81974 22.0226 3.39212C21.9482 3.22479 21.8459 3.2062 21.7623 3.03887C21.9761 2.98309 21.8366 2.76928 22.0504 2.7135C22.4781 3.04816 21.9668 2.77858 22.3851 3.08535H22.1899C22.4688 3.22479 22.1434 3.22479 22.3665 3.45719C22.506 3.45719 22.4502 3.15971 22.4781 2.99239C22.6361 3.17831 22.3758 3.11323 22.6361 3.31775V3.1969C22.6547 3.26197 22.7105 3.33634 22.6733 3.35493C22.8313 3.51297 22.7384 3.31775 22.7848 3.27127C22.7105 3.16901 22.5896 3.03887 22.4688 2.92731C22.4874 2.9459 22.506 2.9645 22.5338 2.98309C22.413 2.63913 22.7477 2.69491 22.664 2.41603C22.6919 2.4811 22.7198 2.4904 22.7569 2.52758C22.822 2.4904 22.6826 2.19292 22.7105 2.05348C22.8685 2.15574 23.0265 2.4811 23.0916 2.29518C22.9894 2.12785 22.7105 1.91404 22.822 1.82108C22.822 1.82108 22.822 2.02559 22.9708 2.09066L22.9801 2.12785ZM20.8327 4.54483C20.8327 4.54483 20.8048 4.57272 20.7862 4.60061C20.7862 4.60061 20.8141 4.55413 20.8234 4.54483H20.8327ZM20.7769 4.8702C20.7769 4.8702 20.749 4.77723 20.6839 4.71216C20.6467 4.74005 20.6188 4.76794 20.5817 4.78653C20.6653 4.81442 20.749 4.81442 20.7769 4.8702ZM22.1341 5.67896L22.1527 5.70684C22.1527 5.70684 22.1248 5.76262 22.1155 5.78121C22.1527 5.8184 22.1992 5.84628 22.2085 5.79051C22.1899 5.76262 22.162 5.71614 22.1341 5.67896Z\" fill=\"#8F3A7E\"><\/path><path d=\"M22.0416 5.47307C22.0416 5.47307 22.0416 5.45466 22.0416 5.44546C22.0231 5.43626 22.0047 5.42705 21.9863 5.41785L22.0231 5.49148L22.0416 5.47307Z\" fill=\"#8F3A7E\"><\/path><path d=\"M4.04395 14.6689C4.04395 14.6689 4.05317 14.6597 4.06239 14.6413C4.06239 14.6505 4.05317 14.6597 4.04395 14.6689Z\" fill=\"#8F3A7E\"><\/path><path d=\"M17.3184 6.90505L17.365 6.96105L17.3464 6.89572L17.3184 6.90505Z\" fill=\"#8F3A7E\"><\/path><path d=\"M3.82129 12.9043C3.82129 12.9043 3.84973 12.8664 3.85921 12.8474C3.84973 12.8569 3.83077 12.8759 3.82129 12.9043Z\" fill=\"#8F3A7E\"><\/path><path d=\"M3.47742 12.3441L3.49602 12.2139C3.47742 12.279 3.47742 12.3162 3.47742 12.3441Z\" fill=\"#8F3A7E\"><\/path><path d=\"M3.28078 11.8598C3.28078 11.8598 3.21608 11.8967 3.18835 11.9152L3.28078 11.8598Z\" fill=\"#8F3A7E\"><\/path><path d=\"M6.45996 16.4436C6.45996 16.4436 6.54407 16.3969 6.57211 16.3875C6.57211 16.3408 6.55342 16.3221 6.45996 16.4436Z\" fill=\"#8F3A7E\"><\/path><path d=\"M6.62872 16.4611C6.62872 16.3873 6.6195 16.3781 6.57336 16.3873C6.57336 16.4242 6.58259 16.4703 6.62872 16.4611Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.17539 10.0107V9.98242C2.17539 9.98242 2.14712 10.0013 2.1377 10.0013H2.17539V10.0107Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.12949 10.0114H2.0918C2.0918 10.0114 2.10122 10.0208 2.12949 10.0114Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.00806 9.99291H2.09124C2.09124 9.99291 2.07275 9.96519 2.00806 9.99291Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.41699 10.6243L2.50017 10.5781C2.50017 10.5781 2.45396 10.5966 2.41699 10.6243Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.55659 10.7733C2.55659 10.7177 2.65855 10.5601 2.57513 10.5416L2.51025 10.5787C2.64001 10.5231 2.39903 10.8289 2.55659 10.7733Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.07381 12.1401L2.0366 11.9541C1.97149 12.0378 1.88778 12.1494 1.82268 12.0936C1.70176 12.4471 1.9808 11.9262 2.08311 12.1401H2.07381Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.27776 12.6685C2.18469 12.622 2.15677 12.7523 2.11023 12.7895C2.22192 12.7895 2.24984 12.7895 2.27776 12.6685Z\" fill=\"#8F3A7E\"><\/path><path d=\"M4.62895 15.747L4.43384 15.8864C4.50817 15.9235 4.50817 15.8306 4.62895 15.747Z\" fill=\"#8F3A7E\"><\/path><path d=\"M6.05145 15.5506L6.11649 15.4112L5.93066 15.5134L6.05145 15.5506Z\" fill=\"#8F3A7E\"><\/path><path d=\"M5.00248 16.9545H4.95605C5.00248 16.9638 5.0489 16.973 5.10461 17.0009C5.05819 16.973 5.03962 16.973 5.00248 16.9545Z\" fill=\"#8F3A7E\"><\/path><path d=\"M10.2145 16.5729L9.97351 16.4061C9.98278 16.471 10.2423 16.6842 10.2145 16.5729Z\" fill=\"#8F3A7E\"><\/path><path d=\"M11.8059 14.4079C11.9267 14.4915 12.0475 14.5101 11.9824 14.3708C11.9267 14.3986 11.7966 14.3615 11.8059 14.4079Z\" fill=\"#8F3A7E\"><\/path><path d=\"M18.3037 9.16579L18.3223 9.2774L18.3502 9.14719L18.3037 9.16579Z\" fill=\"#8F3A7E\"><\/path><path d=\"M1.64564 9.73384C1.52494 9.65027 1.46923 9.91025 1.50637 9.71527C1.6085 9.67813 1.69207 9.65956 1.64564 9.73384Z\" fill=\"#8F3A7E\"><\/path><path d=\"M25.5929 1.03314C25.7137 1.86049 24.812 1.67457 24.7376 2.32529C24.7097 2.38107 24.4959 2.01852 24.4587 2.16726C24.4587 2.88306 23.6872 3.09687 22.9807 3.13405L22.9342 3.0318C22.804 3.0318 22.9342 3.40364 22.8133 3.44083C22.7669 3.38505 22.7761 3.33857 22.6925 3.28279C22.8133 3.46871 22.5995 3.4966 22.6646 3.64534C22.5716 3.60815 22.4694 3.46871 22.3578 3.43153L22.4694 3.66393C22.7111 4.23099 22.1068 3.91493 22.1161 4.30536C22.0882 4.24959 22.0789 4.2031 22.0232 4.17522C21.9488 4.70509 21.5305 4.97468 21.2795 5.36512C21.233 5.29075 21.14 5.15131 21.0564 5.09553C21.2051 5.30934 21.1493 5.44878 21.0936 5.56963C20.8797 5.393 21.0936 5.8857 20.8983 5.8671L20.8704 5.81133C20.9727 6.09021 20.6473 5.78344 20.8054 6.09951L20.6195 5.97866C20.8333 6.29472 20.3778 5.92288 20.4428 6.1274L20.4986 6.18317C20.4986 6.30402 20.3406 6.18317 20.3313 6.28543L20.2941 6.25754C20.229 6.44346 20.0152 6.3505 20.2104 6.57361C20.0059 6.43417 20.2662 6.37839 19.9687 6.18317C19.7363 6.78742 19.2436 7.12208 18.816 7.50322C18.6859 7.45674 18.6301 7.45674 18.5464 7.38237C18.5464 7.46603 18.4163 7.56829 18.4814 7.71703C18.4906 7.69843 18.3512 7.62407 18.3233 7.63336C18.1746 7.61477 18.4535 7.95872 18.2768 7.93084C18.2582 7.83788 18.2118 7.75421 18.1281 7.67984C18.2025 7.92154 18.0816 7.97732 18.0444 8.10746C18.0258 8.06098 18.0258 8.0145 17.9608 7.94943C18.0351 8.22831 17.747 8.06098 17.7749 8.2562L17.6912 8.09817C17.4216 8.06098 17.8864 8.40494 17.6912 8.41423C17.6912 8.34916 17.6261 8.30268 17.5889 8.2469C17.6819 8.58156 17.4402 8.65593 17.403 8.82326C17.403 8.79537 17.3658 8.76749 17.3658 8.76749C17.2729 8.89763 17.0869 8.93481 17.0498 9.14862C16.9475 9.13003 16.7895 8.82326 16.7058 8.98129C16.9382 9.23229 16.585 9.27877 16.9196 9.50188C16.7802 9.54836 16.5199 9.60413 16.5292 9.75287C16.492 9.61343 16.1945 9.48328 16.2689 9.38103L16.0644 9.28807C15.9807 9.17651 16.1666 9.26018 16.0272 9.14862C15.99 9.19511 15.9528 9.41821 15.8784 9.40891C15.9342 9.64132 16.1201 10.0039 16.0179 10.1526C15.99 9.99457 15.7297 9.90161 15.7297 9.81794L15.9807 10.478C15.9435 10.5337 15.7855 10.2827 15.7855 10.4036C15.8506 10.4687 15.8599 10.5337 15.8877 10.6081C15.8413 10.5895 15.7669 10.8312 15.5159 10.6081C15.4043 10.5244 15.5438 10.4873 15.4136 10.4408C15.3393 10.5151 15.4136 10.6081 15.33 10.6825L15.3021 10.6546C15.2184 10.6639 15.237 10.9056 15.4229 10.9892C15.4694 10.9614 15.2742 10.8498 15.3951 10.8777C15.488 11.0543 15.4322 11.1845 15.3579 11.2588C15.3579 11.1938 15.2835 11.1287 15.2277 11.045C15.3021 11.3425 15.237 11.5098 15.1905 11.6958C15.2928 11.8166 15.0418 11.4355 15.1162 11.4819C14.8094 11.4541 15.0139 12.0118 14.6607 11.8817C14.6607 11.8445 14.828 12.0397 14.7908 12.0118C14.7071 12.0676 14.5491 11.891 14.5584 11.9932C14.4654 11.891 14.5305 12.0769 14.5026 12.1606C14.5398 12.2535 14.4469 12.1234 14.4747 12.0676C14.4747 12.2163 14.3446 12.6254 14.0564 12.6254C14.1215 12.6904 14.1866 12.96 14.1401 12.9879L14.0099 12.8206C13.8891 12.7555 13.8984 12.9507 13.7682 12.8206C13.8612 13.0809 13.9263 12.3837 13.9542 12.6254C13.8054 12.5231 14.0378 13.0065 13.8612 12.7741C13.7961 12.8485 13.8798 13.0902 13.6753 13.0065C13.7218 13.0065 13.5358 12.7369 13.4894 12.802C13.4057 12.9228 13.5265 12.9042 13.4894 13.0344V13.1459C13.6288 13.304 13.3871 13.211 13.5823 13.3412C13.4522 13.2296 13.4986 13.555 13.2755 13.2947L13.1082 13.0809C13.0803 13.1366 13.2291 13.3598 13.2755 13.4806C13.257 13.4713 13.2012 13.4341 13.1733 13.4062C13.4429 13.713 13.0431 13.4806 13.2105 13.7688C13.0153 13.7502 12.9595 13.9826 12.7364 13.8339C12.7457 13.9919 12.7829 14.1592 12.6434 14.1778C12.6341 14.1313 12.6434 14.1034 12.5876 14.0384C12.4575 14.0012 12.5133 14.0848 12.5133 14.1778C12.4854 14.122 12.2437 14.1034 12.0856 14.0477C12.1042 14.2057 12.2809 14.3451 12.3645 14.4474C12.0206 14.215 12.3459 14.8285 12.0113 14.6333C11.9927 14.5682 11.9741 14.3916 11.8439 14.373C11.5 14.1406 11.9276 14.717 11.6859 14.6705L11.9462 14.8843C11.751 14.7821 11.9369 15.1725 11.7045 14.9122C11.7603 15.033 11.5093 14.9494 11.751 15.1725C11.3884 15.1446 11.4814 15.6838 10.9608 15.3863C10.9794 15.4514 10.8772 15.47 11.0166 15.5722C11.1839 15.6559 10.9701 15.4235 11.0817 15.4979C11.0724 15.5257 11.1281 15.5908 11.1653 15.628C11.0631 15.628 11.0073 15.6559 10.8493 15.4142C10.589 15.3956 11.1467 15.9162 10.9236 15.972C10.8307 15.8697 10.7749 15.8511 10.7563 15.9069L10.8586 16.1393C10.7377 16.1951 10.5797 15.9905 10.3938 15.8418C10.3752 15.9162 10.3101 15.9812 10.4309 16.1114L10.1521 15.9905C10.3566 16.0742 10.2264 16.1207 10.245 16.1858L10.2171 16.1207C10.1335 16.0649 10.1242 16.1672 10.1242 16.2229C10.245 16.3066 10.338 16.2787 10.4031 16.2694C10.4588 16.3624 10.4031 16.3903 10.4681 16.5018C10.3008 16.3438 10.2729 16.4832 10.2264 16.5111C10.1521 16.5297 10.3473 16.6878 10.3287 16.697C10.2357 16.6227 10.2543 16.7621 10.1521 16.6227C10.1335 16.5855 10.2729 16.6506 10.2078 16.5669C10.1149 16.5483 9.95684 16.4182 10.0219 16.5669C10.0684 16.6878 10.3845 16.8272 10.1985 16.8365C10.1706 16.7807 10.1056 16.7156 10.0498 16.6506L9.89177 16.6692L10.0591 16.7993C10.0126 16.7807 10.0033 16.7621 9.97543 16.7528C10.1428 16.8923 9.90106 16.9666 10.0591 17.1711C10.0219 17.2641 9.83599 17.2455 9.77092 17.3106V17.2827C9.62218 17.2827 9.61288 17.4686 9.65936 17.6638L9.63148 17.6267C9.63148 17.6267 9.53852 17.8033 9.585 18.0078C9.41767 18.0264 9.06442 17.3199 9.15738 17.7196C9.1016 17.8498 9.28752 18.3425 9.38978 18.4261C9.18526 18.5284 9.23174 19.3743 8.94357 19.207C8.97145 19.3743 9.00864 19.4208 8.99005 19.5974C8.77624 19.9228 8.70187 21.1313 8.42298 20.6851C8.44158 20.3783 8.35791 20.2482 8.31143 19.9972C8.33002 20.3597 8.26495 20.0158 8.26495 20.1087C8.26495 20.1366 8.27425 20.211 8.29284 20.3783C8.33002 20.6014 8.34862 20.7594 8.3765 20.8896C8.3951 20.9732 8.41369 21.029 8.45087 21.0383C8.45087 21.0941 8.43228 21.1406 8.42298 21.2057C8.36721 21.2428 8.30214 21.2149 8.22777 21.1499C8.19058 21.1127 8.16269 21.0662 8.12551 21.0197C8.08833 20.9454 8.05114 20.8524 8.03255 20.7687C8.08833 20.9732 8.06973 21.029 8.03255 21.0848C7.99536 20.5828 7.88381 20.3783 7.80015 20.4434V20.7316L7.72578 20.3597C7.69789 20.4155 7.70719 20.9268 7.60493 20.5363C7.60493 20.4248 7.58634 20.3039 7.57704 20.2017C7.49338 20.3318 7.33534 20.5363 7.24238 20.1831L7.17731 19.6997C7.17731 19.6997 7.03787 19.8298 7.11224 20.025C6.9542 19.5881 6.84265 19.4301 6.84265 19.0768C6.44292 19.4673 5.89445 18.863 5.55049 18.3796L5.63416 18.2681C5.60627 18.0357 5.44824 18.4168 5.42964 18.2495C5.5319 18.1751 5.5226 17.9241 5.68064 17.8684C5.64345 17.5988 5.38316 17.8684 5.25302 17.8126C5.12287 17.9427 5.39246 17.8126 5.23443 17.9706C5.17865 17.9985 5.14146 17.636 4.93695 17.8126C4.97413 17.6917 5.14147 17.5802 5.23443 17.5151H5.0671C5.20654 17.1897 5.66205 17.3478 5.82938 16.9387L5.74571 16.9016C5.89445 16.6413 6.09896 16.8272 6.04319 16.6041C5.90374 16.6413 5.55979 16.8458 5.5412 17.0038C5.35528 16.8923 5.00202 17.3664 4.85329 17.1433C4.92765 16.9852 5.02062 17.2827 5.15076 17.0968C5.23443 16.8551 4.91836 17.0038 4.93695 16.9016C4.90906 17.0317 4.64877 17.1433 4.5837 17.134C4.62088 16.9852 4.8161 17.0224 4.76032 16.9016C4.62088 16.9852 4.46285 16.9666 4.44426 17.1154C4.13749 17.3013 4.44426 16.948 4.17467 17.0689C4.342 16.883 4.70455 16.8086 4.71384 16.6227C4.53722 16.79 4.3513 16.6878 4.11889 16.9759C4.13749 16.8923 4.27693 16.7621 4.42567 16.7063C4.49074 16.5483 3.96086 16.8272 4.31411 16.5111L4.1096 16.6413C4.15608 16.5762 4.18397 16.5018 4.25834 16.3903C4.22115 16.3345 3.8586 16.4182 4.14678 16.1951C4.1003 16.1951 4.01664 16.0649 3.84931 16.2694C3.79353 16.4461 4.06312 16.2415 3.83072 16.5018C4.00734 16.2694 3.70987 16.4089 3.59831 16.4275L3.70057 16.3345C3.6355 16.3345 3.60761 16.2601 3.47746 16.3345C3.56113 16.3066 3.6262 16.2322 3.6355 16.1858L3.44028 16.288C3.26365 16.2415 3.71916 16.0277 3.58902 15.9534L3.78424 15.9255C3.78424 15.9255 3.8772 15.7674 3.78424 15.7581C3.60761 15.8604 3.3938 15.972 3.26365 16.0463C3.1521 16.0463 3.42169 15.879 3.20788 15.9441L3.45887 15.8697C3.52395 15.8418 3.67268 15.6094 3.60761 15.535C3.51465 15.535 3.22647 15.6187 3.19858 15.7674C3.1614 15.7303 3.21717 15.6001 3.35662 15.5443C3.22647 15.4979 3.19858 15.6838 3.04055 15.6838C3.11492 15.5722 3.18929 15.3491 3.29154 15.1725L3.61691 15.0516L3.57972 14.9959C3.84931 14.9029 3.70987 14.8378 3.96086 14.6984C3.96086 14.6333 3.8586 14.6519 3.77494 14.6519C3.50535 15.0423 3.18929 14.9029 2.89181 15.1911C2.6873 15.1074 3.60761 14.4846 2.97548 14.717C2.9104 14.8099 2.60363 14.9215 2.77096 14.9494C2.73378 14.8285 2.39912 15.1353 2.4456 14.9215C2.64082 14.9029 2.70589 14.5775 2.99407 14.5497C2.88252 14.624 2.96618 14.6798 3.01266 14.6705C3.10562 14.5404 3.34732 14.4288 3.27295 14.3265C3.19858 14.2894 3.12421 14.215 2.96618 14.3544C2.78026 14.5032 3.05914 14.4288 2.83603 14.5404C2.678 14.4753 2.94759 14.2336 2.58504 14.4381C2.6687 14.4939 2.49208 14.6612 2.36193 14.7542L2.2132 14.7263L2.35264 14.6519C2.33405 14.4474 2.09235 14.7821 2.02727 14.624L2.22249 14.373C2.45489 14.2429 2.27827 14.6426 2.60363 14.3544C2.54786 14.2522 2.35264 14.3544 2.38053 14.2057C2.42701 14.2057 2.45489 14.2243 2.49208 14.215C2.48278 14.1778 2.9104 13.7967 2.54786 13.871C2.39912 13.8896 2.40841 13.9454 2.27827 14.0384C2.12953 13.9268 1.9715 13.9826 1.87854 13.9082C2.14812 13.7409 1.78558 13.7316 2.12024 13.6386C2.00868 13.7967 2.17601 13.9919 2.45489 13.8617C2.71519 13.5829 2.50138 14.0012 2.82674 13.806C2.75237 13.6851 3.04984 13.4713 3.22647 13.304C3.21717 13.2668 3.11492 13.2947 3.06844 13.304C2.87322 13.4248 2.9104 13.462 2.72448 13.6107C2.678 13.4434 2.49208 13.3969 2.25968 13.462C2.31545 13.3505 2.51067 13.2296 2.56645 13.2668C2.39912 13.1552 2.30616 12.9786 2.25968 12.7927C2.02727 13.1088 2.07376 12.6811 1.86924 12.9321C1.85995 13.0623 1.69262 13.2854 1.52529 13.3412C1.50669 13.2761 1.65543 13.2482 1.71121 13.1831C1.4974 13.2389 1.90643 12.8949 1.59965 13.0251C1.79487 13.0995 1.99009 12.7834 2.24108 12.644C2.03657 12.644 2.40841 12.5231 2.34334 12.4301C2.13883 12.4301 1.94361 12.3744 1.81346 12.3C1.94361 12.0025 1.56247 11.9375 1.46951 11.8166C1.54388 11.6679 1.85065 11.5284 1.84135 11.4262C1.77628 11.3425 1.59036 11.6865 1.62754 11.4819L1.69262 11.4541C1.59965 11.4541 1.7205 11.1008 1.30218 11.3239L1.62754 11.1659C1.62754 11.1659 1.55317 11.1473 1.51599 11.1473C1.60895 11.0822 1.68332 10.9985 1.76698 10.9892C1.92502 10.7754 1.62754 10.8498 1.56247 10.7661L1.42303 10.9335C1.19063 10.8777 1.30218 10.6639 1.15344 10.5616L1.33007 10.4594L1.17203 10.4408C1.35796 10.3571 1.42303 10.2177 1.2464 10.2549L1.81346 10.2084C1.74839 10.3292 1.56247 10.2735 1.41373 10.4129C1.28359 10.5337 1.41373 10.6453 1.59036 10.5523C1.58106 10.4873 1.53458 10.5152 1.45092 10.5152C1.68332 10.3478 1.7205 10.4315 1.90643 10.3664C1.87854 10.3478 1.93431 10.2642 1.85065 10.3106C1.99939 10.2827 2.05516 10.3292 2.11094 10.4036C1.98079 10.4036 1.98079 10.5337 1.89713 10.5523C2.11094 10.4222 2.23179 10.4594 2.24108 10.5988C2.04587 10.8312 2.52926 10.6825 2.53856 10.8498C2.29686 10.9428 2.08305 10.9985 1.95291 10.98C1.89713 11.1287 2.01798 11.0636 1.95291 11.2124C2.13883 11.138 2.38982 11.0078 2.55715 11.0357L2.40841 11.1473C2.54786 11.1845 2.78026 11.0171 2.80815 11.1566C2.86392 11.3983 3.00336 11.5935 3.08703 11.7515L2.93829 11.8631C3.31943 11.705 3.25436 12.0397 3.47746 12.0397C3.46817 12.3279 3.91438 12.3279 3.71916 12.6161C4.07241 12.8485 4.39778 13.0437 4.593 13.4062L4.3327 13.5178C4.53722 13.4527 4.23974 13.6479 4.31411 13.6851C4.43496 13.4806 4.60229 13.5922 4.76962 13.5271C4.71384 13.806 5.03921 13.8524 5.2902 13.8617L5.14146 13.9826C5.5226 13.8896 5.40176 14.2429 5.48542 14.4381C5.43894 14.5032 5.31809 14.6426 5.37387 14.6798C5.68064 14.5775 5.69923 14.6333 5.95022 14.6426C6.02459 14.7356 6.08967 14.9308 6.07107 15.1074C6.37784 15.1446 6.55447 15.3026 6.7125 15.47C6.80546 15.5722 6.84265 15.6094 6.87983 15.6373C6.92631 15.6652 6.98209 15.6838 7.05646 15.6745L6.92631 15.8697C7.14942 15.7674 7.1866 15.7953 7.24238 15.8883C7.28886 15.972 7.34464 16.1114 7.40971 15.9998L7.32605 16.4925C7.34464 16.7063 7.4283 16.4646 7.4469 16.0649C7.46549 16.2694 7.51197 15.8604 7.53056 16.3624C7.56774 16.5111 7.56774 16.13 7.57704 16.0649C7.60493 16.2137 7.63282 16.288 7.65141 16.3066C7.67 16.3066 7.67 16.2137 7.67 16.13V16.1021C7.67 16.2508 7.70719 16.5297 7.72578 16.5483C7.72578 16.4739 7.72578 16.4554 7.72578 16.4368C7.73507 16.3996 7.74437 16.3438 7.6607 15.8976C7.70719 16.0742 7.71648 15.9441 7.71648 15.8511C7.71648 15.7581 7.71648 15.6931 7.80944 15.879C7.75367 15.7303 7.75367 15.6931 7.71648 15.5908C7.72578 15.5536 7.9024 15.7488 7.80015 15.5071C7.84663 15.5536 7.9117 15.7117 7.93959 15.7024C7.921 15.6466 7.84663 15.5536 7.80944 15.4793C7.76296 15.3491 7.80944 15.377 7.89311 15.3956C7.93959 15.4607 8.19988 15.2747 8.27425 15.1353C8.47876 14.4753 9.01793 14.057 9.39907 13.6015L9.46415 13.6665C9.35259 13.2761 10.0405 13.5829 9.78021 13.1088C9.87317 13.1366 9.93825 13.0158 10.0312 13.1645C9.96614 12.8857 10.496 13.0251 10.4402 12.6532C10.4216 12.6532 10.4216 12.6811 10.4402 12.7276C10.7377 12.7183 10.6912 12.3837 10.9887 12.3558C10.998 12.4023 10.9887 12.4487 11.0445 12.5231C11.2304 12.5882 10.9329 12.0955 11.2676 12.3837C11.3048 12.3465 11.1467 12.1977 11.1281 12.2256C11.6115 12.0118 11.8161 11.4355 12.1321 11.0078C12.5876 10.9428 12.6434 11.5377 12.6434 11.0915C12.7178 11.138 12.5412 10.9521 12.6062 11.0171C12.6062 10.8498 13.071 11.2588 12.9688 11.0357C12.7643 10.8591 12.9037 10.887 12.8014 10.7661C13.0896 10.7383 13.2848 10.887 13.2848 10.6174L13.3685 10.729C13.257 10.292 13.5823 10.2827 13.4057 9.81794C14.2237 8.972 14.8838 8.03309 15.7111 7.24293C16.6221 6.56431 17.3193 5.69048 18.3419 5.13271C18.7881 5.24427 18.7974 5.21638 18.9183 4.9189C18.9462 4.97468 18.9462 4.99327 18.9926 5.02116C18.8067 4.77946 19.1321 4.86313 18.9647 4.62143C19.3273 4.38903 19.569 4.07296 19.8944 3.79408C19.8665 3.85915 19.9966 4.07296 20.0431 4.00789L19.978 3.80337L20.0431 3.85915C20.0524 3.78478 20.0059 3.63604 19.8944 3.59886C20.5544 2.69714 21.7722 2.47403 22.5437 1.73034C22.8226 1.66527 23.0178 1.34921 23.1945 1.1168C24.0776 0.902993 24.8492 0.689183 25.3047 -0.0545044C25.3047 -0.0545044 25.723 0.62411 25.5836 0.977361L25.5929 1.03314Z\" fill=\"#8F3A7E\"><\/path><path d=\"M1.7481 9.85501C1.62739 9.95715 1.59954 10.0778 1.38599 10.115C1.50669 10.0314 1.61811 9.91072 1.7481 9.85501Z\" fill=\"#8F3A7E\"><\/path><path d=\"M1.8506 12.8295C1.8506 12.8295 1.82275 12.8945 1.80418 12.9131C1.77632 12.8945 1.65562 12.9409 1.70204 12.8759C1.7299 12.8945 1.78561 12.8481 1.8506 12.8202V12.8295Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.16678 13.4147C2.05536 13.489 1.87895 13.4425 1.82324 13.3775L2.16678 13.4147Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.08289 14.2437C2.02718 14.3551 1.96219 14.383 1.92505 14.318C1.98076 14.2715 2.02718 14.2715 2.08289 14.2437Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.35372 14.0857C2.35372 14.0857 2.33511 14.188 2.28857 14.2625C2.38165 14.188 2.15827 14.216 2.35372 14.0857Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.84607 15.3857C2.84607 15.3857 3.00391 15.3857 2.90178 15.5064C2.96677 15.4135 2.66966 15.4878 2.84607 15.3857Z\" fill=\"#8F3A7E\"><\/path><path d=\"M3.39329 15.7397C3.39329 15.7397 3.384 15.7861 3.43043 15.7769C3.40257 15.8418 3.30044 15.879 3.27258 15.8604L3.39329 15.7397Z\" fill=\"#8F3A7E\"><\/path><path d=\"M11.9369 14.7541L11.9462 14.8467L11.8535 14.7448L11.9369 14.7541Z\" fill=\"#8F3A7E\"><\/path><path d=\"M15.4611 11.4917C15.4611 11.3803 15.5818 11.5567 15.6003 11.5659C15.5632 11.6124 15.5075 11.4267 15.4611 11.4917Z\" fill=\"#8F3A7E\"><\/path><path d=\"M16.957 9.2601L16.9477 9.27864L16.7716 9.06546L16.957 9.2601Z\" fill=\"#8F3A7E\"><\/path><path d=\"M26.4111 1.45928C26.4761 1.32929 26.2068 1.32001 26.4111 1.32001C26.4668 1.41286 26.5039 1.49642 26.4111 1.45928Z\" fill=\"#8F3A7E\"><\/path><path d=\"M1.08847 10.4673C1.92512 10.4673 1.62764 11.3319 2.27837 11.4713C2.33415 11.4992 1.95301 11.6851 2.10174 11.7316C2.81754 11.7967 2.97558 12.5682 2.97558 13.2747L2.86402 13.3119C2.86402 13.4514 3.23587 13.3305 3.26375 13.4514C3.20798 13.4979 3.1615 13.4886 3.09642 13.5629C3.29164 13.4514 3.30094 13.6652 3.45897 13.6094C3.42179 13.6931 3.27305 13.7953 3.23587 13.9069L3.47756 13.8046C4.06322 13.5908 3.70997 14.1765 4.1097 14.1858C4.05392 14.2137 4.00744 14.2229 3.97026 14.2694C4.50013 14.3624 4.75113 14.79 5.13227 15.0596C5.0486 15.0968 4.91846 15.1897 4.85338 15.2734C5.07649 15.1247 5.20664 15.1897 5.32749 15.2548C5.15086 15.4686 5.64355 15.2548 5.61566 15.4593L5.55989 15.4872C5.84807 15.3943 5.532 15.7103 5.84807 15.5616L5.72722 15.7475C6.05258 15.543 5.66214 15.9892 5.86666 15.9334L5.92244 15.8777C6.04328 15.8777 5.92244 16.0357 6.0154 16.0543L5.98751 16.0915C6.17343 16.1658 6.06188 16.361 6.28498 16.1658C6.14554 16.3703 6.10836 16.1193 5.90384 16.4168C6.4895 16.6492 6.74049 17.049 7.08445 17.458C7.08445 17.6532 7.11233 17.7369 7.10304 17.8949C7.14952 17.8577 7.25178 17.9879 7.30755 17.8112C7.29826 17.8112 7.30755 18.0529 7.33544 18.0994C7.40051 18.3504 7.4284 17.6997 7.48418 17.9786C7.45629 18.0715 7.4377 18.2017 7.44699 18.3783C7.52136 18.1087 7.59573 18.2482 7.6608 18.211C7.6608 18.2853 7.64221 18.3132 7.64221 18.462C7.69799 18.118 7.80024 18.7316 7.84673 18.527V18.7966C7.99546 19.2893 7.82813 18.276 7.9025 18.3783C7.9025 18.5084 7.92109 18.6107 7.93039 18.7408C7.93039 18.3597 7.93969 18.2017 7.96757 18.0715C7.98617 17.9693 8.01406 17.8949 8.02335 17.7648C8.02335 17.8019 8.04194 17.8763 8.04194 17.8763C8.07913 17.6904 8.17209 17.6904 8.19068 17.3743C8.24646 17.4208 8.33942 17.9414 8.39519 17.7183C8.23716 17.2628 8.46027 17.3 8.23716 16.9188C8.31153 16.8909 8.46956 16.8537 8.45097 16.6771C8.49745 16.8537 8.72056 17.0211 8.68337 17.1605C8.73915 17.207 8.79493 17.2535 8.86 17.3C8.94366 17.458 8.77633 17.3464 8.90648 17.5045C8.93437 17.4208 8.94366 17.1047 9.00874 17.1047C8.93437 16.8073 8.72985 16.4261 8.76704 16.2774C8.82282 16.4354 9.06451 16.5098 9.08311 16.5935C8.97155 16.3703 8.84141 16.1658 8.70197 15.9892C8.71126 15.9427 8.92507 16.1472 8.89718 16.0264C8.82281 15.9799 8.79493 15.9148 8.75774 15.8498C8.80422 15.8498 8.8507 15.5895 9.12959 15.7754C9.25043 15.8405 9.12959 15.8962 9.25973 15.9148C9.3248 15.8219 9.24114 15.7475 9.29692 15.6545L9.3341 15.6824C9.41776 15.6545 9.36199 15.4221 9.16677 15.3664C9.12029 15.4036 9.3341 15.4779 9.21325 15.4779C9.0924 15.3106 9.13888 15.1711 9.21325 15.0875C9.23184 15.1526 9.30621 15.2083 9.36199 15.2827C9.25043 14.9945 9.29692 14.8179 9.3341 14.6134C9.21325 14.5018 9.51073 14.8551 9.42706 14.8179C9.73383 14.7993 9.49213 14.2694 9.86398 14.3531C9.86398 14.3903 9.68735 14.2044 9.72454 14.2415C9.8082 14.1765 9.97553 14.3438 9.96623 14.2415C10.0685 14.3345 9.99412 14.1486 10.0127 14.0742C9.96623 13.9812 10.0778 14.1114 10.0406 14.1579C10.022 14.0091 10.1522 13.5815 10.4496 13.5629C10.3846 13.4979 10.3102 13.2283 10.3567 13.2004L10.4868 13.3677C10.6077 13.4235 10.5984 13.2376 10.7285 13.3584C10.6263 13.0981 10.5798 13.8139 10.5426 13.5629C10.6913 13.6652 10.4496 13.1725 10.6356 13.4049C10.7006 13.3305 10.6077 13.0888 10.8215 13.1632C10.775 13.1632 10.9609 13.4328 11.0167 13.3677C11.0911 13.2376 10.9795 13.2655 11.0167 13.1353V13.0238C10.868 12.8657 11.1282 12.9587 10.9237 12.8192C11.0539 12.9308 11.0074 12.5961 11.2305 12.8564L11.3978 13.0702C11.4257 13.0145 11.277 12.7913 11.2305 12.6705C11.2584 12.6798 11.3049 12.7077 11.3328 12.7449C11.0539 12.4381 11.4629 12.6705 11.3049 12.3823C11.5001 12.4009 11.5559 12.1685 11.779 12.308C11.7697 12.1499 11.7325 11.9733 11.8812 11.964C11.8905 12.0105 11.8812 12.0384 11.9277 12.1034C12.0671 12.1406 12.0021 12.0477 12.0021 11.9547C12.03 12.0105 12.2717 12.0384 12.4297 12.0848C12.4204 11.9268 12.2438 11.7874 12.1601 11.6758C12.5041 11.9175 12.188 11.2947 12.5227 11.4899C12.532 11.555 12.5505 11.7316 12.6807 11.7595C13.0246 12.0012 12.6156 11.4155 12.8573 11.462L12.597 11.2389C12.7829 11.3505 12.6249 10.9507 12.848 11.211C12.8015 11.0902 13.0525 11.1738 12.8201 10.9414C13.1827 10.9879 13.1455 10.4208 13.6475 10.7555C13.6382 10.6904 13.7404 10.6718 13.6103 10.5603C13.443 10.458 13.6382 10.709 13.5359 10.6347C13.5545 10.6068 13.4987 10.5324 13.4709 10.4952C13.5731 10.4952 13.6382 10.4766 13.7683 10.7276C14.0286 10.7648 13.5173 10.1977 13.7683 10.1513C13.852 10.2628 13.8985 10.2907 13.9357 10.2256L13.8706 9.97463C14.01 9.91886 14.1402 10.1513 14.2982 10.3279C14.3261 10.2535 14.4005 10.1977 14.3075 10.049L14.5678 10.207C14.3819 10.0955 14.5213 10.0583 14.5027 9.99323V10.0583C14.5864 10.1234 14.6143 10.0211 14.6236 9.97463C14.5213 9.87238 14.4191 9.89097 14.354 9.89097C14.3168 9.78871 14.3726 9.77012 14.3261 9.64927C14.4655 9.8259 14.5213 9.68646 14.5864 9.66786C14.6701 9.66786 14.5027 9.46335 14.5306 9.45405C14.6143 9.53772 14.6236 9.39828 14.6979 9.55631C14.6979 9.60279 14.5864 9.50983 14.6236 9.61209C14.7165 9.64927 14.8467 9.8073 14.8188 9.63068C14.7909 9.50053 14.5027 9.30532 14.6979 9.32391C14.7072 9.38898 14.763 9.46335 14.8002 9.53772H14.9675L14.8374 9.38898C14.8839 9.41687 14.8839 9.43546 14.9118 9.45405C14.7909 9.26813 15.0047 9.27743 14.8653 9.08221C14.8932 9.02643 15.0605 9.1008 15.1163 9.08221V9.1008C15.2557 9.14728 15.2743 9.01714 15.2278 8.8777L15.2557 8.91488C15.2557 8.91488 15.3487 8.81262 15.3022 8.69177C15.4788 8.73826 15.8414 9.25884 15.7577 8.98925C15.8321 8.91488 15.6276 8.59881 15.5067 8.52444C15.7391 8.50585 15.6647 8.11542 16.0087 8.24556C15.9715 8.1619 15.925 8.13401 15.9343 8.06894C16.1853 7.95738 16.1946 7.51117 16.6222 7.6785C16.6222 7.79935 16.7524 7.83653 16.836 7.92949C16.7617 7.74357 17.022 8.02246 16.836 7.77146C16.7059 7.63202 16.6501 7.55765 16.5479 7.55765C16.6036 7.38103 16.7803 7.22299 16.9662 7.29736C16.8732 7.26018 16.8639 7.1951 16.8546 7.13003C17.0406 7.36243 17.1614 7.31595 17.1614 7.18581L17.0499 7.03707L17.2172 7.13933C17.2079 7.07425 16.9941 6.82326 17.18 6.89763C17.2265 6.94411 17.2823 6.99989 17.3287 7.02777C17.3008 6.85115 17.2358 6.58156 17.4124 6.62804L17.6448 6.77678C17.6541 6.7303 17.6076 6.56297 17.5054 6.55367C17.7378 6.56297 17.8307 6.50719 18.0259 6.64664C17.8772 6.03309 18.1933 5.73562 18.4722 5.5497L18.5558 5.66125C18.7046 5.69843 18.435 5.44744 18.5558 5.47533C18.6209 5.59618 18.7882 5.64266 18.844 5.80999C19.0392 5.83788 18.8161 5.52181 18.844 5.41955C18.7417 5.27081 18.8626 5.5497 18.7324 5.36377C18.7046 5.308 18.9648 5.35448 18.7975 5.13137C18.8905 5.18715 19.002 5.35448 19.0578 5.45674L19.0299 5.308C19.3088 5.48462 19.2251 5.88436 19.5598 6.10746L19.5877 6.0238C19.8201 6.19113 19.6435 6.39564 19.848 6.34916C19.8201 6.20042 19.6156 5.85647 19.4854 5.80999C19.5598 5.64266 19.1229 5.27081 19.2809 5.16856C19.4204 5.26152 19.1972 5.28941 19.3646 5.43814C19.5691 5.5497 19.4111 5.23363 19.5226 5.24293C19.3925 5.21504 19.2716 4.96404 19.2809 4.88967C19.4297 4.92686 19.4018 5.12208 19.5133 5.057C19.4297 4.92686 19.4389 4.75953 19.2902 4.74094C19.095 4.44346 19.4575 4.73164 19.3367 4.47135C19.5319 4.62938 19.6063 4.99193 19.8015 5.00123C19.6249 4.8339 19.7271 4.63868 19.4389 4.41557C19.5226 4.43417 19.6528 4.57361 19.7178 4.71305C19.8759 4.77812 19.5784 4.25754 19.913 4.6015L19.7736 4.39698C19.848 4.44346 19.913 4.46205 20.0246 4.53642C20.0804 4.48994 19.9781 4.13669 20.2198 4.42487C20.2198 4.37839 20.3407 4.29472 20.1362 4.13669C19.9595 4.08091 20.1733 4.3505 19.9038 4.12739C20.1362 4.29472 19.9874 4.00655 19.9688 3.89499L20.0711 3.99725C20.0618 3.93218 20.1455 3.90429 20.0618 3.77414C20.099 3.85781 20.164 3.92288 20.2105 3.93218L20.099 3.74626C20.1362 3.56963 20.3686 4.01584 20.4336 3.8857L20.4615 4.08091C20.4615 4.08091 20.6196 4.16458 20.6288 4.07162C20.5266 3.90429 20.3964 3.69048 20.3221 3.56033C20.3221 3.44878 20.4894 3.70907 20.415 3.50456L20.4987 3.75555C20.5266 3.81133 20.759 3.96007 20.8334 3.89499C20.8334 3.80203 20.7311 3.51385 20.5824 3.49526C20.6196 3.45808 20.7497 3.50456 20.8148 3.644C20.8612 3.51385 20.666 3.48596 20.666 3.32793C20.7869 3.4023 21.0007 3.46737 21.1866 3.56033L21.3168 3.8857L21.3725 3.83922C21.4748 4.09951 21.5399 3.96936 21.6793 4.21106C21.7444 4.21106 21.7258 4.1088 21.7165 4.01584C21.3168 3.76485 21.4376 3.44878 21.1401 3.1606C21.2145 2.95609 21.8745 3.84851 21.6142 3.22567C21.5213 3.1606 21.3911 2.86313 21.3725 3.03046C21.4934 2.99327 21.168 2.66791 21.3818 2.70509C21.4097 2.90031 21.7351 2.95609 21.7816 3.23497C21.6979 3.12342 21.6514 3.20708 21.6607 3.25356C21.8002 3.34652 21.921 3.57893 22.014 3.49526C22.0419 3.42089 22.1162 3.34652 21.9675 3.18849C21.8095 3.01186 21.8931 3.28145 21.7816 3.06764C21.8373 2.90961 22.0883 3.1699 21.8652 2.80735C21.8187 2.89101 21.6421 2.72369 21.5399 2.59354L21.5585 2.4448L21.6421 2.57495C21.8466 2.54706 21.5027 2.32395 21.6514 2.24958L21.9117 2.43551C22.0511 2.66791 21.6514 2.50058 21.9489 2.81665C22.0419 2.76087 21.9303 2.56565 22.079 2.58424C22.079 2.63072 22.0697 2.65861 22.079 2.6958C22.1162 2.6772 22.516 3.09553 22.423 2.74228C22.4044 2.59354 22.3393 2.61213 22.2371 2.48199C22.3393 2.33325 22.2743 2.17522 22.3393 2.08226C22.5253 2.34255 22.5067 1.98 22.6275 2.30536C22.4602 2.2031 22.2836 2.37973 22.4323 2.64932C22.7205 2.89101 22.2928 2.6958 22.5067 3.01186C22.6182 2.9282 22.8506 3.21638 23.0272 3.38371C23.0644 3.37441 23.0272 3.27215 23.0272 3.22567C22.8971 3.03975 22.8599 3.07694 22.7019 2.90031C22.8599 2.84453 22.8971 2.64932 22.8227 2.42621C22.9343 2.48199 23.0644 2.66791 23.0365 2.72369C23.1388 2.55636 23.3061 2.4448 23.4827 2.38903C23.1574 2.17522 23.5757 2.19381 23.3247 2.00789C23.1946 2.00789 22.9715 1.84985 22.8971 1.69182C22.9622 1.67323 22.9994 1.82196 23.0737 1.85915C22.9994 1.65464 23.3712 2.03577 23.2225 1.7383C23.1667 1.94281 23.4827 2.11014 23.6501 2.35184C23.6408 2.14733 23.7802 2.50988 23.8732 2.43551C23.8639 2.23099 23.8918 2.03577 23.9568 1.90563C24.2636 2.00789 24.2915 1.63604 24.4031 1.52449C24.5611 1.58956 24.7284 1.87774 24.8307 1.85915C24.905 1.78478 24.5425 1.63604 24.7563 1.65464L24.7842 1.71041C24.7656 1.62675 25.1375 1.71041 24.8679 1.31068L25.0631 1.61745C25.0631 1.61745 25.0724 1.54308 25.0631 1.5059C25.1374 1.58956 25.2304 1.65464 25.2397 1.7383C25.4721 1.86845 25.3606 1.58027 25.4349 1.51519L25.249 1.39434C25.2769 1.15265 25.5 1.24561 25.5744 1.07828L25.7045 1.23631V1.07828C25.8068 1.24561 25.9648 1.29209 25.8997 1.12476L26.0299 1.67323C25.8997 1.62675 25.9276 1.43153 25.7696 1.30138C25.6301 1.18983 25.5465 1.32927 25.6487 1.4966C25.7045 1.47801 25.6859 1.44083 25.6673 1.35716C25.8625 1.56167 25.7882 1.61745 25.8811 1.78478C25.8997 1.75689 25.9834 1.79408 25.9369 1.71971C25.9834 1.86845 25.9462 1.92422 25.8718 1.98929C25.8532 1.85915 25.7324 1.87774 25.6952 1.79408C25.8532 1.98929 25.8254 2.11014 25.6859 2.13803C25.4349 1.9707 25.6301 2.43551 25.4628 2.46339C25.342 2.23099 25.2676 2.02648 25.2676 1.88704C25.1189 1.84985 25.1932 1.96141 25.0445 1.91493C25.1375 2.09155 25.2955 2.33325 25.2769 2.50058L25.1467 2.36114C25.1282 2.50058 25.3048 2.71439 25.1653 2.77017C24.9236 2.84453 24.7377 3.00257 24.589 3.09553L24.4588 2.95609C24.6448 3.32793 24.3008 3.28145 24.3101 3.50456C24.0219 3.50456 24.0498 3.96007 23.7523 3.78344C23.5385 4.15528 23.3619 4.48994 22.9994 4.70375L22.8785 4.45276C22.9529 4.65727 22.7391 4.3598 22.7112 4.44346C22.9157 4.55502 22.8134 4.72234 22.8878 4.88967C22.6089 4.84319 22.581 5.17785 22.5717 5.42885L22.4416 5.28941C22.5438 5.67055 22.1906 5.55899 21.9954 5.64266C21.9303 5.59618 21.7816 5.48462 21.7537 5.5404C21.8652 5.84717 21.8095 5.86576 21.8002 6.11676C21.7072 6.19113 21.512 6.2655 21.3446 6.2469C21.2796 6.86974 20.7497 6.95341 20.5638 7.4554L20.3964 7.30666C20.3593 7.95738 19.6528 7.99457 19.5226 8.44078L19.2995 8.12471C19.1322 8.12471 19.1508 8.385 19.3553 8.56163C19.188 8.56163 19.2437 8.89629 18.9834 8.71037C18.844 8.73825 18.9834 8.94277 18.937 9.04503C18.6581 9.1008 18.6023 9.18447 18.4722 9.38898L18.5279 9.37039C18.4907 9.28672 18.3885 9.16588 18.3327 9.18447C18.3327 9.32391 18.0259 9.31461 18.3885 9.60279C18.0259 9.56561 18.091 10.1513 17.6727 10.0397C17.7657 10.1234 17.7378 10.1791 17.7749 10.2535C17.6169 10.4023 17.273 10.3651 17.2823 10.644C17.2172 10.6161 17.1893 10.4487 17.1056 10.4952C17.1056 10.5696 17.2079 10.6161 17.2079 10.709C17.0963 11.1181 16.5107 11.0065 16.3062 11.2668C16.0366 11.8246 15.5067 12.1406 15.1349 12.5404L15.0791 12.466C15.172 12.8471 14.5213 12.4939 14.763 12.9773C14.6701 12.9401 14.6143 13.0609 14.5213 12.9122C14.5771 13.1911 14.0658 13.0238 14.1123 13.3956C14.1309 13.3956 14.1309 13.3677 14.1123 13.3212C13.8148 13.3212 13.8706 13.6466 13.5731 13.6745C13.5638 13.628 13.5731 13.5815 13.5173 13.5071C13.3314 13.4421 13.6289 13.9255 13.2942 13.6373C13.257 13.6745 13.4151 13.8232 13.4337 13.7953C12.9503 14.0091 12.7551 14.5762 12.4669 14.9945C12.03 15.0596 11.937 14.4832 11.9649 14.9109C11.8905 14.8644 12.0671 15.041 12.0021 14.9759C12.0021 15.134 11.5373 14.7528 11.6488 14.9666C11.8626 15.134 11.7232 15.1061 11.8347 15.2269C11.5559 15.2548 11.3514 15.1247 11.3792 15.385L11.2863 15.2734C11.435 15.6917 11.1282 15.7196 11.3606 16.1472C11.2026 16.361 11.0539 16.5749 10.9237 16.7887L10.4403 17.6625C9.91975 18.5456 9.60369 20.0423 9.12029 21.4367C8.99014 21.7993 8.8507 22.1618 8.72056 22.5151L8.33942 22.0874L7.89321 21.5762L7.00078 20.5536C6.41513 19.8657 5.80159 19.1127 5.281 18.3225C5.20664 17.6439 5.20664 17.6625 4.77902 17.3743C4.83479 17.3464 4.86268 17.365 4.89057 17.3C4.76972 17.3929 4.70465 17.3185 4.64887 17.2628C4.61169 17.2256 4.5745 17.1791 4.45365 17.2628C4.23055 16.9002 3.92378 16.6399 3.64489 16.296C3.70997 16.3332 3.93307 16.203 3.868 16.1472L3.66349 16.203L3.71926 16.1379C3.64489 16.1193 3.49616 16.1658 3.44968 16.2774C2.55725 15.5709 2.37133 14.3345 1.66483 13.5071C1.60905 13.219 1.30228 12.9959 1.08847 12.8006C0.930435 11.8617 0.790994 11.0902 0.0751953 10.4116C0.0751953 10.4116 0.828178 10.1513 1.16284 10.3558L1.08847 10.4673Z\" fill=\"#8F3A7E\"><\/path><path d=\"M26.3094 1.58132C26.1885 1.47901 26.0676 1.47901 25.9932 1.27438C26.0955 1.3767 26.235 1.46971 26.3094 1.58132Z\" fill=\"#8F3A7E\"><\/path><path d=\"M23.3623 1.9979C23.3623 1.9979 23.2973 1.97005 23.2695 1.96076C23.288 1.93291 23.223 1.8122 23.2973 1.85863C23.2787 1.88648 23.3345 1.94219 23.3623 1.9979Z\" fill=\"#8F3A7E\"><\/path><path d=\"M22.8039 2.34232C22.7203 2.2309 22.7574 2.06377 22.8131 1.99878V2.34232H22.8039Z\" fill=\"#8F3A7E\"><\/path><path d=\"M21.9853 2.29645C21.8739 2.24074 21.846 2.18504 21.9018 2.13861C21.9482 2.19432 21.9575 2.23146 21.9853 2.29645Z\" fill=\"#8F3A7E\"><\/path><path d=\"M22.1544 2.56585C22.1544 2.56585 22.052 2.55654 21.9775 2.51001C22.052 2.59377 22.0241 2.37971 22.1544 2.56585Z\" fill=\"#8F3A7E\"><\/path><path d=\"M20.8979 3.10465C20.8979 3.10465 20.8979 3.26249 20.7772 3.16965C20.8701 3.22535 20.7772 2.93752 20.8979 3.10465Z\" fill=\"#8F3A7E\"><\/path><path d=\"M20.5632 3.65382C20.5632 3.65382 20.5168 3.65382 20.5261 3.69096C20.4611 3.6631 20.424 3.57025 20.4425 3.53311L20.5632 3.65382Z\" fill=\"#8F3A7E\"><\/path><path d=\"M12.5693 11.3684V11.275L12.6534 11.3871L12.5693 11.3684Z\" fill=\"#8F3A7E\"><\/path><path d=\"M9.03711 14.8652C9.05568 14.9767 8.90712 14.8188 8.88855 14.8188C8.9164 14.7631 8.99997 14.9488 9.03711 14.8652Z\" fill=\"#8F3A7E\"><\/path><path d=\"M8.21887 17.2635V17.2357L8.33029 17.5885L8.21887 17.2635Z\" fill=\"#8F3A7E\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Streamlined eFiling<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"27\" height=\"23\" viewBox=\"0 0 27 23\" fill=\"none\"><path d=\"M26.5504 1.48711C26.5133 1.41296 26.3928 1.2832 26.3743 1.33881L26.5411 1.59833V1.48711H26.5504Z\" fill=\"#8F3A7E\"><\/path><path d=\"M25.9092 1.28207C25.9556 1.43991 26.067 1.68132 26.2806 1.8763C26.1413 1.60704 26.2342 1.69061 26.0577 1.3842C26.0763 1.31921 26.197 1.40277 26.262 1.49562C26.2249 1.42134 26.3734 1.49562 26.262 1.32849C26.0577 1.18922 25.9835 1.23565 26.0392 1.4492C25.9835 1.41206 25.9463 1.33778 25.9092 1.29136V1.28207Z\" fill=\"#8F3A7E\"><\/path><path d=\"M19.0215 6.23586C19.0215 6.23586 19.0215 6.18064 19.0031 6.16223C19.0031 6.18984 19.0031 6.21746 19.0215 6.23586Z\" fill=\"#8F3A7E\"><\/path><path d=\"M18.3794 6.34023C18.3794 6.34023 18.4077 6.34023 18.4171 6.34023C18.3888 6.3308 18.37 6.32138 18.3794 6.34023Z\" fill=\"#8F3A7E\"><\/path><path d=\"M21.5952 4.26723L21.465 4.24863C21.5208 4.33234 21.5487 4.27653 21.5952 4.26723Z\" fill=\"#8F3A7E\"><\/path><path d=\"M25.8363 2.31298C25.8363 2.31298 25.8363 2.25752 25.8178 2.22055C25.8178 2.23904 25.8178 2.25752 25.8086 2.27601L25.8363 2.31298Z\" fill=\"#8F3A7E\"><\/path><path d=\"M22.5358 3.16046L22.5544 3.14186C22.5544 3.14186 22.5172 3.07675 22.4893 3.03024L22.5358 3.16046Z\" fill=\"#8F3A7E\"><\/path><path d=\"M23.3447 2.4166C23.3447 2.4166 23.4749 2.63052 23.5493 2.72353C23.4935 2.63052 23.4749 2.58401 23.4749 2.54681C23.447 2.50961 23.4005 2.4631 23.3447 2.4166Z\" fill=\"#8F3A7E\"><\/path><path d=\"M21.8932 3.61673C21.8932 3.61673 21.8372 3.56072 21.8279 3.55139C21.8465 3.57939 21.8745 3.59806 21.8932 3.61673Z\" fill=\"#8F3A7E\"><\/path><path d=\"M0.799326 11.6575C0.799326 11.6575 0.827596 11.6386 0.837019 11.6292C0.808749 11.6292 0.789903 11.648 0.799326 11.6575Z\" fill=\"#8F3A7E\"><\/path><path d=\"M1.21851 9.87102L1.24636 9.8803L1.37635 9.81531L1.21851 9.87102Z\" fill=\"#8F3A7E\"><\/path><path d=\"M10.5801 13.1525C10.8215 13.2453 10.6636 13.4868 10.9608 13.561C10.8772 13.496 10.7843 13.1711 10.5801 13.1525Z\" fill=\"#8F3A7E\"><\/path><path d=\"M25.7896 2.30579C25.7896 2.30579 25.7708 2.32463 25.752 2.33406C25.7708 2.33406 25.7802 2.31521 25.7896 2.30579Z\" fill=\"#8F3A7E\"><\/path><path d=\"M15.7295 8.4028C15.7295 8.4028 15.7942 8.45826 15.8219 8.47674C15.8034 8.45826 15.7757 8.43977 15.7295 8.4028Z\" fill=\"#8F3A7E\"><\/path><path d=\"M15.2939 9.27798C15.2939 9.27798 15.2285 9.25931 15.2285 9.30598C15.2378 9.30598 15.2472 9.31531 15.2565 9.32465C15.2378 9.28731 15.2379 9.26865 15.2939 9.27798Z\" fill=\"#8F3A7E\"><\/path><path d=\"M14.5957 9.90973C14.5957 9.90973 14.6241 9.92869 14.6431 9.93817V9.90973H14.5957Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.6049 13.9609C2.65136 13.8959 2.7071 13.8401 2.76285 13.7844C2.62348 13.9051 2.48412 13.8401 2.6049 13.9609Z\" fill=\"#8F3A7E\"><\/path><path d=\"M25.7432 2.19324C25.7802 2.24883 25.7988 2.27662 25.7895 2.29515L25.808 2.26736C25.808 2.26736 25.7617 2.21177 25.7432 2.19324Z\" fill=\"#8F3A7E\"><\/path><path d=\"M16.6315 10.8466L16.4922 10.9116C16.5386 10.9116 16.585 10.8745 16.6315 10.8466Z\" fill=\"#8F3A7E\"><\/path><path d=\"M7.79133 20.2916H7.76367C7.76367 20.2916 7.79133 20.3285 7.79133 20.2916Z\" fill=\"#8F3A7E\"><\/path><path d=\"M16.1947 11.2389C16.1111 11.1924 16.0554 11.1645 16.0089 11.1552C16.0089 11.1738 16.0275 11.1924 16.0368 11.2203L16.1854 11.2389H16.1947Z\" fill=\"#8F3A7E\"><\/path><path d=\"M1.95357 13.227C1.75835 13.1898 1.98146 13.1526 2.08371 12.9109C1.81413 13.0132 2.08371 12.7343 1.70258 12.9946C1.91639 12.7808 1.83272 12.8551 1.96287 12.6599C1.78624 12.8366 1.66539 12.6599 1.42369 12.8458C1.67469 12.6227 1.85131 12.725 2.06512 12.4275C1.83272 12.4926 1.68398 12.4275 1.37721 12.6227C1.4051 12.5205 1.49806 12.4275 1.47947 12.3253C1.47017 12.3532 1.53525 12.3253 1.57243 12.316C1.27496 12.316 1.33073 11.972 0.912408 12.1393C1.36792 11.8698 0.76367 11.7954 1.23777 11.6281C1.18199 11.5816 0.931 11.6095 0.838039 11.6374C1.18199 11.4143 0.828743 11.4328 0.986776 11.2283C0.772966 11.3213 0.76367 11.1633 0.614933 11.1726C0.680005 11.1726 0.745078 11.154 0.828743 11.0889C0.642821 11.0982 0.782262 11.0331 0.912408 10.8658C0.745078 10.8286 0.661413 11.0517 0.456899 11.0889C0.475491 10.9494 0.670709 10.9401 0.800854 10.8379L0.363938 10.9216C0.38253 10.8751 0.438307 10.81 0.531268 10.7449C0.401123 10.7542 0.224497 10.8007 0.354642 10.6334L0.438307 10.7449L0.59634 10.5962H0.280273C0.429011 10.2244 0.856631 10.0849 1.24707 9.88969L1.35862 9.92688C1.48877 9.85251 1.53525 9.75955 1.51665 9.72236C1.59102 9.64799 2.00005 9.61081 2.08371 9.65729C2.17668 9.8804 1.67469 9.95476 1.66539 10.1593L2.00005 10.2151L1.8792 10.2987C1.81413 10.3824 1.96287 10.3173 2.00005 10.2987C1.80483 10.401 2.03723 10.4939 2.05583 10.5869L2.19527 10.4568C2.70655 10.4196 2.01864 11.0517 2.33471 11.0982L2.67866 11.0331L2.46485 11.219C2.65078 11.1911 2.8367 11.0796 2.8367 11.2469C2.70655 11.9255 3.50602 11.9999 3.5525 12.5763C3.59898 12.5391 3.59898 12.5112 3.61757 12.4647C3.3108 13.2363 4.59366 12.567 4.39844 13.2084L4.29618 13.2549C4.46351 13.3757 4.19393 13.3014 4.15674 13.5059C4.44492 13.3199 4.51929 13.5431 4.68662 13.5616C4.62155 13.5895 4.60295 13.5616 4.53788 13.5616C4.4914 13.6267 4.33337 13.7569 4.41703 13.7662C4.88184 13.5709 5.01198 13.8126 5.24438 13.8777C5.08635 14.0357 5.03058 14.296 4.80747 14.5935C4.88184 14.5563 5.03987 14.482 5.1979 14.4076C5.13283 14.5563 5.25368 14.5284 5.38383 14.4913C5.33735 14.4448 5.30016 14.3983 5.27227 14.3704H5.29087C5.29087 14.3704 5.26298 14.3611 5.25368 14.3518C5.2165 14.3239 5.1979 14.3146 5.18861 14.3332C5.30946 14.138 5.32805 14.231 5.53256 14.0636C5.56975 14.1194 5.71849 14.1752 5.57904 14.3053C5.59764 14.3425 5.59764 14.3797 5.57904 14.4355C5.62552 14.4355 5.66271 14.4355 5.66271 14.4727H5.63482C5.63482 14.4727 5.59764 14.5284 5.57904 14.547C5.57904 14.7144 5.98807 14.6121 6.20188 14.5842C5.87652 14.7051 5.9323 14.8352 5.73708 14.9839C5.75567 14.9839 5.6906 14.8724 5.58834 14.7423C5.57904 14.7701 5.55116 14.798 5.48608 14.8538C5.37453 15.1234 5.81145 14.9003 5.80215 15.1792C5.77426 15.1792 5.70919 15.1978 5.65341 15.2628C5.65341 15.3651 5.83933 15.3 5.96018 15.2164C5.79285 15.3744 5.75567 15.6068 5.88582 15.5975C6.08103 15.5324 6.14611 15.4673 6.20188 15.5789L6.03455 15.644C6.01596 15.8485 6.29484 15.5882 6.26695 15.7648C6.28555 15.6905 6.14611 15.7927 6.14611 15.8392C6.31344 15.895 6.3971 15.8578 6.70387 15.709L6.49936 15.8671C6.67598 15.8485 6.97346 15.6997 6.73176 15.9693C7.08501 15.551 7.00135 15.8485 7.03853 15.9043C7.01994 15.9043 6.95487 15.9972 6.91768 16.053C7.18727 15.8113 7.05712 16.211 7.15938 16.3133L7.03853 16.7874C7.1036 16.8432 7.3453 15.9136 7.36389 15.96L7.30812 16.1831C7.38249 16.1831 7.40108 16.2482 7.44756 16.4063L7.41967 16.7874C7.45685 16.6387 7.48474 16.6758 7.50333 16.5085C7.52193 17.0291 7.587 16.9826 7.63348 16.9175C7.66137 16.8804 7.67996 16.8711 7.70785 16.9175C7.72644 16.9175 7.75433 17.0012 7.81011 17.2522L7.69855 16.4248C7.69855 16.4248 7.69855 16.4063 7.69855 16.397C7.70785 16.3505 7.71714 16.3226 7.81011 16.7409C7.91236 17.3173 7.83799 16.6944 7.87518 16.7874C7.87518 16.6944 7.80081 16.3319 7.77292 16.2482C7.91236 16.462 7.88447 15.9972 8.16336 16.3784C8.18195 16.0437 7.96814 15.6626 8.0611 15.6161L8.10758 15.6533C8.10758 15.6533 8.20054 15.6626 8.2935 15.6905C8.40506 15.6905 8.55379 15.7183 8.72112 15.8392C8.79549 15.5882 8.44224 15.1048 8.78619 14.9932L8.86986 15.142C8.98141 15.142 8.90704 14.9189 8.88845 14.8631C8.91634 14.8445 8.96282 14.9189 9.00001 14.9561C9.14874 14.9932 9.0093 14.8166 9.0186 14.7515L9.11156 14.8631C9.47411 14.8631 9.30678 14.231 9.56707 14.0543C9.56707 14.1194 9.68792 14.2031 9.75299 14.2403C9.50199 13.8405 9.81806 13.6639 9.83665 13.5059L9.91102 13.6825C9.87384 13.3014 10.3944 13.8684 10.3572 13.4873L10.0784 13.3943C10.1992 13.3757 10.1992 13.2642 10.0412 13.134C10.2271 13.1619 10.2922 13.3757 10.4502 13.2828C10.5432 13.3664 10.4223 13.4315 10.5803 13.5059L10.9801 13.5895C10.9801 13.5895 11.0358 13.5895 11.0637 13.5152C10.6547 13.1154 11.1846 13.3571 10.7105 13.0411C10.9243 12.7808 11.3798 12.8644 11.4077 12.4833C11.8725 12.8087 11.826 12.1208 12.2908 12.6599C12.4117 12.5577 12.4117 12.3625 12.2908 12.0929C12.2257 12.0743 12.2629 12.1672 12.2629 12.2137C12.17 12.0557 12.2908 11.8976 12.3466 11.8512C12.3838 12.0371 12.3466 12.2602 12.4767 12.5112C12.5325 12.3625 12.5046 12.0278 12.4953 11.9162L12.7742 12.1579C12.6813 11.8791 13.0531 12.3067 12.8951 11.9627L12.8021 11.8976C12.9787 11.7675 12.737 11.4979 12.8579 11.3213L12.9508 11.4328C13.0438 11.4328 12.8858 11.1075 13.1647 11.3027L13.0717 11.405C13.2576 11.5816 13.4064 11.6002 13.5272 11.6652C13.583 11.5165 13.2855 11.3213 13.3134 11.2469C13.4993 11.405 13.4064 11.3399 13.5272 11.5444C13.583 11.3771 13.6759 11.154 13.5551 10.8472C13.583 10.8751 13.6202 10.9123 13.6202 10.9123C13.7689 10.8286 13.5923 10.4103 13.7968 10.4939V10.5404C14.1314 10.717 13.8247 10.0663 14.2523 10.4939C14.3731 10.5311 14.1314 10.5683 14.401 10.7263C14.6706 10.7356 14.1593 10.2615 14.401 10.2708C14.3731 10.2708 14.401 10.2987 14.4289 10.3452C14.5126 10.2522 14.5963 10.0942 14.6613 9.95476C15.1168 10.2058 14.9681 9.51785 15.498 9.81532C15.3121 9.70377 15.3771 9.61081 15.3213 9.53644C15.3213 9.53644 15.3492 9.58292 15.3771 9.60151C15.4422 9.56433 15.3213 9.41559 15.2842 9.34122C15.4422 9.43418 15.3028 9.07164 15.4143 9.12741C15.3306 9.03445 15.3957 9.01586 15.4422 8.97867C15.4422 9.17389 15.5909 9.21108 15.6839 9.397C15.8698 9.32263 15.4794 8.82994 15.6839 8.77416L15.9256 8.88571C15.7025 8.59754 15.9349 8.58824 15.8419 8.48598C15.9442 8.55105 16.0279 8.56965 16.1394 8.70909C16.1394 8.58824 16.3532 8.65331 16.2324 8.46739L16.1115 8.4488C16.3904 8.39302 16.1487 7.90033 16.4555 7.95611L16.818 8.37443C17.0597 8.45809 16.7901 7.99329 17.0969 8.17921C16.9482 8.06766 16.9761 8.11414 16.9203 7.91892C16.8552 7.91892 16.8831 8.08625 16.8273 8.13273L16.7436 7.77948L16.6507 8.06766C16.5949 7.83526 16.6228 7.87244 16.4462 7.74229C16.4462 7.5006 16.7529 7.82596 16.7251 7.56567C16.818 7.58426 16.9017 7.77018 17.0225 7.81666C16.9946 7.58426 17.478 7.94681 17.3572 7.65863C17.4223 7.67722 17.3293 7.70511 17.413 7.79807C17.4409 7.70511 17.5059 7.67722 17.413 7.53778H17.32C17.3758 7.50989 17.2363 7.33327 17.4223 7.35186C17.3944 7.21242 17.2456 6.98002 17.1899 7.0265C17.1899 6.98002 17.3386 7.04509 17.4316 7.18453C17.5803 7.06368 17.1155 6.68254 17.4316 6.75691C17.4316 6.7755 17.4316 6.81269 17.4687 6.83128C17.5338 6.83128 17.5617 6.80339 17.5617 6.75691C17.4687 6.90565 17.8871 7.05438 17.6733 7.11016C17.8778 7.31467 17.822 7.05438 17.9428 7.11016C17.8871 6.89635 17.6733 6.7848 17.6175 6.64536C17.6733 6.71972 17.7104 6.69184 17.7662 6.69184L17.5896 6.5524C17.5896 6.5524 17.6547 6.50591 17.6547 6.43155V6.5524C17.7476 6.52451 18.073 6.71043 18.0544 6.44084C18.0823 6.5338 18.1381 6.71973 18.2868 6.74761C18.324 6.5338 18.3798 6.79409 18.5564 6.85917C18.6493 6.71043 18.324 6.5431 18.5936 6.48732C18.6122 6.46873 18.5099 6.38507 18.4541 6.35718C18.6493 6.32929 18.6215 6.15266 18.8446 6.17126C18.7516 6.17126 18.6586 6.15266 18.6679 6.01322C18.7516 6.18055 18.8817 6.0597 19.0026 6.09689L18.9468 6.00393C19.0584 6.0597 19.0491 6.13407 19.0491 6.18985C19.0212 6.16196 18.9933 6.14337 18.9747 6.17126C18.9747 6.2921 19.2722 6.58958 19.393 6.5431C19.4302 6.37577 19.2164 6.16196 19.1327 6.09689C19.3466 6.069 18.9282 5.60419 19.1792 5.62279C19.2071 5.5949 19.5975 5.84589 19.7184 5.79941C19.6068 5.56701 19.4767 5.75293 19.393 5.54842C19.9601 5.89237 19.4674 4.97206 19.9229 5.08361L20.0995 5.3439C20.1646 5.31602 20.2204 5.29742 20.2576 5.22305L20.0809 5.15798C20.0809 5.06502 20.239 5.00924 20.3505 5.22305C20.2948 4.93488 20.4156 5.02784 20.5736 5.00924C20.4528 5.08361 20.5457 4.98136 20.5736 5.16728C20.7874 5.18587 20.7317 5.10221 20.7596 4.98136C20.8153 5.07432 20.9641 5.16728 21.0013 5.13939C20.9455 4.92558 21.1035 4.85121 21.1407 4.68388L21.1965 4.75825C21.2894 4.52585 21.7542 4.69318 21.7542 4.33993C21.7542 4.33993 21.7542 4.33063 21.7542 4.32133H21.7264C21.4754 4.14471 21.7264 4.05175 21.7078 3.91231C21.7635 3.95879 21.8565 4.05175 21.8844 4.02386C21.7078 3.81005 21.8565 3.85653 21.8007 3.73568C21.9216 3.75427 22.0052 3.99597 22.0982 3.89371C22.1261 3.83794 22.0331 3.72638 21.968 3.65202C22.0796 3.73568 22.219 3.77286 22.2934 3.74498C22.3213 3.81934 22.2283 3.77286 22.2283 3.79146C22.312 3.91231 22.3213 3.83794 22.4329 3.97738C22.4979 3.94949 22.2841 3.76357 22.405 3.79146L22.4886 4.00527C22.5444 4.02386 22.5165 3.9309 22.5258 3.91231C22.5258 3.98667 22.6746 4.14471 22.7582 4.23767C22.7954 3.99597 22.4143 3.76357 22.2655 3.57765C22.5072 3.59624 22.4236 3.28947 22.5165 3.19651L22.6653 3.41032C22.6931 3.33595 22.6746 3.27088 22.6281 3.17791L22.7024 3.11284C22.721 3.22439 22.7582 3.29876 22.8791 3.4568C22.9163 3.33595 23.0743 3.28947 22.8791 3.01058L22.9163 3.05707C23.1022 3.05707 23.3811 2.92692 23.4461 3.01988C23.4926 2.83396 23.7715 2.86185 23.5577 2.60156C23.5763 2.48071 24.0225 2.78748 23.7994 2.41564C24.0225 2.51789 23.8645 2.48071 23.9946 2.69452C24.2177 2.79677 23.9388 2.28549 24.2828 2.63874C24.2828 2.44352 24.1991 2.58296 24.0876 2.38775C24.3943 2.71311 24.3107 2.29479 24.571 2.41564C24.4966 2.23901 24.4594 2.35986 24.4036 2.15534C24.4687 2.24831 24.5245 2.22971 24.5431 2.22971L24.3757 1.99731L24.9149 2.45282C24.8405 2.08098 24.571 2.09957 24.6732 1.84857V1.87646C24.9149 2.06238 24.6732 1.59758 24.9428 1.66265C24.8591 1.66265 25.0079 1.7835 25.0451 1.85787V1.70913C25.0451 1.70913 25.0544 1.74632 25.0822 1.76491C25.2868 1.87646 25.0636 1.62547 25.2589 1.70913C25.2403 1.7928 25.3983 1.95083 25.482 2.00661L25.3797 1.67195L25.5842 2.00661C25.7051 1.94153 25.4727 1.33729 25.8631 1.69984L25.8445 1.7835C25.9096 1.84857 26.1234 2.04379 26.0676 1.82998C26.0676 1.7742 25.9282 1.58828 25.9096 1.62547L26.0211 1.65336C26.1513 1.86717 26.0676 2.0345 26.0304 2.15534C25.9933 2.05309 26.0026 1.94153 25.8817 1.82998C25.8631 1.95083 25.9003 2.14605 25.8817 2.2669C25.8445 2.16464 25.7609 2.0252 25.7051 1.94153C25.5377 1.90435 25.7609 2.12746 25.7051 2.19253C25.6214 2.13675 25.5563 2.09957 25.5192 2.0252C25.5192 2.16464 25.4634 2.23901 25.3053 2.20182C25.3053 2.20182 25.2775 1.98801 25.138 1.91365C25.0915 2.15534 25.2589 2.41564 25.2124 2.67593C25.3053 3.15003 24.6918 2.76889 24.7662 3.11284C24.8312 3.2058 24.9893 3.18721 24.9521 3.30806C24.822 3.12214 24.8127 3.23369 24.7476 3.16862C24.8684 3.49398 24.571 3.2244 24.6546 3.4475C24.6174 3.37313 24.5059 3.35454 24.4222 3.31736C24.2549 3.09425 24.2549 3.31736 24.1247 2.89903C24.2642 3.33595 23.818 3.01988 24.134 3.59624L24.2177 3.62413H23.9946L24.0039 3.63342C23.9202 3.64272 23.9574 3.70779 23.6878 3.54976C23.6785 3.46609 23.725 3.42891 23.7157 3.34524C23.4833 3.2151 23.6971 3.63342 23.6321 3.70779C23.5019 3.54976 23.6692 3.58694 23.4833 3.41032C23.4089 3.42891 23.4554 3.58694 23.4368 3.6799L23.3718 3.58694C23.065 3.50328 23.6785 4.06104 23.3253 3.85653C23.3718 3.90301 23.4089 3.96808 23.4554 4.01456C23.3439 3.95879 23.1208 3.87512 23.1208 3.6892C23.0743 3.72638 23.0836 3.85653 23.1394 3.96808C23.2881 4.06104 23.2416 3.98667 23.3996 4.13541L23.2788 4.38641C23.2788 4.38641 23.223 4.28415 23.2509 4.26556C22.6374 3.99597 23.1115 5.04643 22.3864 4.71177C22.5351 4.83262 22.47 4.85121 22.5258 4.97206C22.405 4.99995 22.312 5.13939 22.154 5.1208L22.0982 4.99995C21.9959 5.28813 21.9866 5.55771 21.81 5.60419C21.8379 5.65067 21.6892 5.46475 21.6892 5.41827C21.7449 5.67856 21.15 5.21376 21.4382 5.61349H21.5032C21.2615 5.71575 21.2708 6.16196 21.1221 6.37577C20.8897 6.18985 21.2151 6.25492 20.9455 6.02252C20.7317 6.05041 20.7503 6.35718 20.5457 6.41295C20.5457 6.36647 20.5179 6.33859 20.5179 6.31999C20.2483 6.3014 20.7224 6.5338 20.5736 6.59888C20.49 6.47803 20.4528 6.45943 20.3691 6.44084L20.4807 6.65465C20.4807 6.65465 20.3319 6.48732 20.3041 6.42225C20.4528 6.70113 20.146 6.68254 20.2948 6.94283C20.239 6.89635 20.0902 6.66395 19.9973 6.58958C19.8764 6.58958 19.9043 6.71043 19.9322 6.83128C19.7556 6.71043 19.6626 6.83128 19.6626 6.7848C19.4767 6.81269 19.7463 6.92424 19.7742 7.13805L19.9508 7.15664L19.83 7.35186L19.8021 7.18453C19.6533 7.16594 19.737 7.42623 19.644 7.5006L19.7928 7.59356L19.7556 7.76089C19.5232 7.50989 19.5697 7.81666 19.3651 7.46341C19.0584 7.4913 19.235 7.94681 19.077 8.11414C19.1049 8.08625 19.0491 8.04907 19.0212 7.99329C18.8725 8.02118 18.9282 8.2071 18.984 8.39302C18.9282 8.30006 18.9282 8.25358 18.8632 8.17921C18.7423 8.28147 18.9189 8.39302 18.8632 8.57894C18.8074 8.4395 18.7423 8.39302 18.6865 8.39302C18.7795 8.48598 18.8074 8.57894 18.8074 8.62542C18.4541 8.02118 18.4727 8.54176 18.1845 8.07695C18.2775 8.1978 18.2682 8.59754 18.5099 8.75557V8.6812C18.6401 8.82064 18.5471 8.81135 18.5099 8.84853C18.5099 8.81135 18.5006 8.75557 18.4727 8.72768C18.4355 9.06234 18.1009 9.07164 18.0079 9.37841C17.98 9.31333 17.98 9.146 17.8871 9.146C17.6175 9.24826 17.729 9.6294 17.6361 9.93617C17.3386 9.61081 17.822 9.69447 17.5524 9.36911C17.3944 9.6387 17.2735 9.94547 17.1806 10.3266C16.6693 9.91758 17.1155 10.7356 16.6321 10.4846C16.7901 10.6334 16.7622 10.7542 16.6879 10.8379C16.5949 10.6799 16.5112 10.7542 16.4462 10.6334C16.502 10.8472 16.3532 11.0889 16.0836 10.7635C16.3346 11.0796 15.9163 10.8844 16.0557 11.154C15.8605 11.1168 15.9163 11.3864 15.7304 11.3957C15.9442 11.5537 15.7025 11.5909 15.7304 11.7024C15.7304 11.6838 15.7304 11.6281 15.7025 11.6095C15.5166 11.47 15.7025 11.8698 15.5537 11.8326C15.4608 11.7861 15.405 11.6467 15.3399 11.6745C15.4608 11.814 15.4329 12.1208 15.2191 12.0092C15.247 11.9813 15.1912 11.9162 15.154 11.8419C15.0704 12.3439 14.494 12.3439 14.4382 12.9016L14.2802 12.6227C13.8247 12.5019 14.494 13.1061 14.3174 13.2177C13.8061 13.478 13.0903 13.5524 12.8207 14.0636C12.8486 14.1566 12.9137 14.1287 13.0066 14.2217C12.9508 14.2217 12.7649 14.045 12.8207 14.2124L12.9415 14.3239C12.4489 14.1659 12.6441 15.0304 12.0212 14.6493C12.0398 15.0025 11.6029 14.7887 11.6866 15.2721C11.5192 15.2349 11.5564 15.0025 11.4449 15.0583V15.4209V15.393C11.6401 15.9043 10.5896 15.4859 10.6547 15.96V15.9321C10.5617 15.8485 10.413 15.8113 10.413 15.8764C10.4595 15.9414 10.5153 15.9414 10.6082 15.9879C10.5803 16.3226 10.5525 16.3691 10.4409 16.555C10.3665 16.3784 10.2736 16.5271 10.0784 16.3877C10.162 16.5271 10.2922 16.5178 10.3201 16.6944C10.2178 16.8525 9.99469 16.8153 9.78088 16.9826C9.89243 17.1964 9.78088 17.2615 9.9668 17.4567C9.80877 17.7821 9.75299 18.0052 9.56707 18.4886L9.51129 18.4049C9.66003 18.879 9.251 18.6094 9.32537 18.9162C9.26959 18.7582 9.2603 18.6559 9.19522 18.5629L9.17663 18.8976C9.15804 18.6652 9.00001 18.2469 8.92564 18.3398C8.99071 18.7953 9.02789 18.4979 9.10226 18.8232L8.91634 18.47C8.88845 18.6187 9.05578 19.1486 9.16733 19.1021C8.99071 19.5483 8.86986 20.3013 8.69323 20.6546L8.62816 20.2362C8.58168 20.5709 8.47013 20.8963 8.37717 20.701C8.37717 20.6732 8.35857 20.6546 8.35857 20.636C8.37717 20.7568 8.37717 20.9706 8.41435 21.1101C8.35858 21.5842 8.31209 20.45 8.25632 20.9706C8.27491 20.8498 8.3028 20.7847 8.27491 20.5523C8.24702 20.6267 8.21913 20.6917 8.19125 20.7568C8.17265 20.7847 8.16336 20.8126 8.14477 20.8405H8.0704C8.03321 20.5802 7.8194 19.8272 7.70785 19.8923C7.70785 20.0224 7.75433 20.2455 7.78222 20.3106L7.69855 20.3292L7.62418 19.7157C7.587 19.8272 7.54982 19.9388 7.51263 20.041V19.6041C7.42897 19.6041 7.38249 20.0968 7.29882 19.9667C7.03853 19.3717 7.1036 19.3066 6.98275 18.7396C6.84331 19.4182 6.71317 18.3863 6.55513 18.8139C6.45288 18.0517 6.01596 17.9215 5.77426 17.4381H5.83004C5.87652 17.0756 5.42101 17.5869 5.34664 17.3173L5.4396 17.2987C5.45819 17.0849 5.32805 16.9175 5.18861 16.8432C5.05846 16.7688 4.87254 16.7409 4.71451 16.7409C4.80747 16.7223 4.92832 16.5922 4.87254 16.555C4.75169 16.5829 4.60295 16.8339 4.62155 16.6851C4.67732 16.6758 4.76099 16.5829 4.7424 16.555L4.46351 16.6387C4.43563 16.2947 4.37985 15.9136 4.07308 15.7834C4.11026 15.6812 4.22182 15.6533 4.29618 15.6068C4.11026 15.4581 3.7849 15.4209 3.61757 15.2814L3.84997 15.0676C3.7849 14.9839 3.43165 15.3186 3.57109 15.0397C3.58968 14.9932 3.64546 15.0955 3.7756 15.0397C3.84068 14.733 3.45954 15.1327 3.36658 14.9561L3.68264 14.7794C3.75701 14.5284 3.43165 14.7608 3.22713 14.8445C2.76233 14.9282 3.68264 14.3053 3.25502 14.2682C3.08769 14.3425 3.0598 14.4355 2.89247 14.5098C2.84599 14.2867 2.62289 14.4262 2.57641 14.2031C2.93896 13.794 2.64148 14.2867 2.96684 13.887V14.0822C3.10628 13.8033 3.09699 14.138 3.32939 13.9242C3.33869 13.7848 3.03192 13.8312 2.87388 13.7848C3.0598 13.6453 2.98544 13.887 3.20854 13.6453H3.08769C3.15277 13.6267 3.22713 13.5709 3.24573 13.6081C3.41306 13.4501 3.20854 13.5338 3.16206 13.4873C3.0598 13.5616 2.92036 13.6639 2.79951 13.7848C2.81811 13.7662 2.8367 13.7476 2.85529 13.7197C2.50204 13.8219 2.57641 13.4873 2.28823 13.5616C2.3533 13.5338 2.3626 13.5059 2.40908 13.4687C2.37189 13.3943 2.07442 13.5152 1.93498 13.4873C2.03723 13.3385 2.38119 13.1991 2.19527 13.1247C2.01864 13.2177 1.78624 13.4873 1.70258 13.3571C1.70258 13.3571 1.90709 13.3571 1.98146 13.227H1.95357ZM4.28689 15.5045C4.28689 15.5045 4.31478 15.5324 4.34266 15.551C4.34266 15.551 4.29618 15.5138 4.28689 15.5045ZM4.61225 15.5696C4.61225 15.5696 4.51929 15.5975 4.45422 15.6533C4.48211 15.6905 4.50999 15.7183 4.51929 15.7555C4.55647 15.6719 4.55647 15.5882 4.61225 15.5696ZM5.46749 14.2403L5.49538 14.2217C5.49538 14.2217 5.55116 14.2496 5.56975 14.2589C5.60693 14.2217 5.63482 14.1752 5.57904 14.1659C5.55116 14.1845 5.50468 14.2031 5.46749 14.231V14.2403Z\" fill=\"#8F3A7E\"><\/path><path d=\"M5.26323 14.3253C5.26323 14.3253 5.24482 14.3253 5.23562 14.3253C5.22642 14.3437 5.21721 14.3621 5.20801 14.3805L5.28164 14.3437L5.26323 14.3253Z\" fill=\"#8F3A7E\"><\/path><path d=\"M21.6523 4.27579C21.6523 4.27579 21.6712 4.27579 21.69 4.29463C21.6806 4.29463 21.6712 4.28521 21.6618 4.27579H21.6523Z\" fill=\"#8F3A7E\"><\/path><path d=\"M7.48508 20.1339L7.49435 20.032L7.46655 20.0876L7.48508 20.1339Z\" fill=\"#8F3A7E\"><\/path><path d=\"M23.4094 3.96896C23.4094 3.96896 23.4473 3.9974 23.4663 4.00688C23.4568 3.9974 23.4284 3.97844 23.4094 3.96896Z\" fill=\"#8F3A7E\"><\/path><path d=\"M24.4309 3.36418C24.4309 3.36418 24.3847 3.29949 24.3662 3.27176L24.4309 3.36418Z\" fill=\"#8F3A7E\"><\/path><path d=\"M19.885 6.80322C19.8943 6.85893 19.9036 6.90536 19.9036 6.95178C19.95 6.9425 19.9779 6.92393 19.885 6.80322Z\" fill=\"#8F3A7E\"><\/path><path d=\"M16.6518 10.8394L16.6318 10.8494L16.6518 10.8394Z\" fill=\"#8F3A7E\"><\/path><path d=\"M19.8203 7.01859C19.885 7.02783 19.9035 7.0001 19.9035 6.95389C19.8665 6.96313 19.8203 6.97237 19.8203 7.01859Z\" fill=\"#8F3A7E\"><\/path><path d=\"M26.1981 2.03489H26.2264C26.2264 2.03489 26.2075 2.00662 26.1981 1.99719V2.03489Z\" fill=\"#8F3A7E\"><\/path><path d=\"M26.1977 1.99845V1.96075C26.1977 1.96075 26.1789 1.9796 26.1977 1.99845Z\" fill=\"#8F3A7E\"><\/path><path d=\"M26.2079 1.8683V1.95148C26.2079 1.95148 26.2449 1.933 26.2079 1.8683Z\" fill=\"#8F3A7E\"><\/path><path d=\"M25.6025 2.37845L25.6578 2.45208C25.6578 2.45208 25.6302 2.40606 25.6025 2.37845Z\" fill=\"#8F3A7E\"><\/path><path d=\"M25.4627 2.52706C25.5183 2.50852 25.6852 2.60121 25.7037 2.51779L25.6574 2.45291C25.7223 2.58267 25.3978 2.37876 25.4627 2.52706Z\" fill=\"#8F3A7E\"><\/path><path d=\"M24.0587 2.18406L24.2354 2.12826C24.1517 2.07245 24.0308 1.98874 24.0773 1.92363C23.7145 1.83062 24.254 2.07245 24.0587 2.18406Z\" fill=\"#8F3A7E\"><\/path><path d=\"M23.5575 2.40555C23.5946 2.31271 23.4646 2.29414 23.4275 2.24771C23.4461 2.35913 23.4461 2.38698 23.5575 2.40555Z\" fill=\"#8F3A7E\"><\/path><path d=\"M20.6004 4.88834L20.4517 4.70251C20.4239 4.77684 20.5075 4.77684 20.6004 4.88834Z\" fill=\"#8F3A7E\"><\/path><path d=\"M20.833 6.30117L20.9817 6.36621L20.8702 6.18039L20.833 6.30117Z\" fill=\"#8F3A7E\"><\/path><path d=\"M19.4009 5.29716L19.4102 5.25073L19.373 5.39001L19.4009 5.29716Z\" fill=\"#8F3A7E\"><\/path><path d=\"M14.5673 9.62069L14.7804 9.8246C14.7804 9.75045 14.5673 9.5002 14.5673 9.62069Z\" fill=\"#8F3A7E\"><\/path><path d=\"M12.6902 11.7309C12.5694 11.6473 12.4486 11.6287 12.5044 11.7681C12.5601 11.7402 12.6902 11.7774 12.6902 11.7309Z\" fill=\"#8F3A7E\"><\/path><path d=\"M7.70828 16.6682L7.6897 16.4824L7.69899 16.659L7.70828 16.6682Z\" fill=\"#8F3A7E\"><\/path><path d=\"M1.70163 9.61194C1.61792 9.63054 1.4691 9.73285 1.52491 9.76076L1.81324 9.63984L1.70163 9.61194Z\" fill=\"#8F3A7E\"><\/path><path d=\"M1.38543 10.1886C1.54327 10.17 1.80325 10.0957 2.02609 9.91004C1.74754 10.0122 1.84039 9.9379 1.50613 10.0586C1.45042 10.0307 1.54327 9.92861 1.64541 9.88219C1.57113 9.90076 1.66398 9.78006 1.47828 9.85433C1.30187 10.0307 1.33901 10.1143 1.55256 10.0865C1.50613 10.1329 1.42257 10.1607 1.37615 10.1886H1.38543Z\" fill=\"#8F3A7E\"><\/path><path d=\"M6.07034 17.5318C6.07034 17.5318 6.02367 17.5318 6.005 17.5598C6.033 17.5598 6.06101 17.5598 6.07034 17.5318Z\" fill=\"#8F3A7E\"><\/path><path d=\"M6.40438 18.461C6.40438 18.461 6.38574 18.4238 6.38574 18.4051C6.38574 18.4517 6.38574 18.4797 6.40438 18.461Z\" fill=\"#8F3A7E\"><\/path><path d=\"M4.03508 14.7249L4.01648 14.8551C4.10019 14.7993 4.04438 14.7714 4.03508 14.7249Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.3788 10.391C2.3788 10.391 2.32335 10.391 2.28638 10.391C2.30486 10.391 2.32335 10.4002 2.33259 10.4095L2.3788 10.3817V10.391Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.96444 13.7376L2.94584 13.719C2.94584 13.719 2.87143 13.7562 2.83423 13.7748L2.96444 13.7376Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.26855 12.8844C2.26855 12.8844 2.49178 12.7635 2.58479 12.7077C2.49178 12.7635 2.43597 12.7728 2.40807 12.7728C2.37087 12.8007 2.32436 12.8379 2.26855 12.8937V12.8844Z\" fill=\"#8F3A7E\"><\/path><path d=\"M3.40322 14.398C3.40322 14.398 3.34722 14.4447 3.33789 14.4634C3.36589 14.4447 3.38456 14.4167 3.40322 14.398Z\" fill=\"#8F3A7E\"><\/path><path d=\"M24.3936 0.882324C24.3936 0.882324 24.4124 0.910594 24.4218 0.920017C24.4124 0.891747 24.403 0.882324 24.3936 0.882324Z\" fill=\"#8F3A7E\"><\/path><path d=\"M26.1963 1.0585V1.08636L26.2891 1.19778L26.1963 1.0585Z\" fill=\"#8F3A7E\"><\/path><path d=\"M7.32639 20.0692C7.32639 20.0692 7.32639 20.0692 7.32639 20.0592C7.29639 20.0692 7.31639 20.0792 7.32639 20.0692Z\" fill=\"#8F3A7E\"><\/path><path d=\"M13.8886 13.0136C13.6561 12.9113 13.8142 12.6788 13.5166 12.5951C13.6003 12.6602 13.684 12.995 13.8886 13.0136Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.37 10.4381C2.37 10.4381 2.38884 10.457 2.39826 10.4758C2.39826 10.457 2.38884 10.4476 2.37 10.4381Z\" fill=\"#8F3A7E\"><\/path><path d=\"M9.13905 18.7775C9.11125 18.7312 9.08346 18.6942 9.05566 18.6756C9.07419 18.7127 9.09272 18.7405 9.13905 18.7775Z\" fill=\"#8F3A7E\"><\/path><path d=\"M7.87305 19.9031L7.91937 20.005C7.90084 19.9494 7.89158 19.9216 7.87305 19.9031Z\" fill=\"#8F3A7E\"><\/path><path d=\"M9.5293 17.1406C9.5293 17.1406 9.59373 17.1407 9.59373 17.0762C9.58452 17.0762 9.57532 17.0762 9.56611 17.067C9.58452 17.1038 9.58452 17.1406 9.5385 17.1406H9.5293Z\" fill=\"#8F3A7E\"><\/path><path d=\"M10.1335 16.3052C10.1335 16.3052 10.0955 16.2957 10.0861 16.2863V16.3147L10.1335 16.3052Z\" fill=\"#8F3A7E\"><\/path><path d=\"M22.2911 2.80592C22.3562 2.85237 22.4119 2.89883 22.477 2.95457C22.3469 2.8245 22.4119 2.68513 22.2911 2.80592Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.25891 10.4761C2.31499 10.448 2.35237 10.4293 2.37106 10.4387L2.34302 10.42C2.34302 10.42 2.2776 10.4574 2.25891 10.4761Z\" fill=\"#8F3A7E\"><\/path><path d=\"M8.05957 15.6353L8.11645 15.6163C8.11645 15.6163 8.06905 15.6163 8.05957 15.6353Z\" fill=\"#8F3A7E\"><\/path><path d=\"M17.1702 7.21375V7.16635C17.1702 7.16635 17.1607 7.18531 17.1702 7.21375Z\" fill=\"#8F3A7E\"><\/path><path d=\"M8.31042 15.2827C8.40334 15.3198 8.45908 15.3198 8.50554 15.3198C8.49625 15.3013 8.48696 15.2827 8.46837 15.2641L8.31042 15.2827Z\" fill=\"#8F3A7E\"><\/path><path d=\"M22.9801 2.12785C22.9986 1.93263 23.0544 2.14644 23.2961 2.2394C23.1753 1.97911 23.4635 2.23011 23.1846 1.86756C23.417 2.07207 23.3333 1.98841 23.5378 2.09996C23.3519 1.93263 23.5099 1.80249 23.3147 1.57938C23.5564 1.81178 23.4635 1.98841 23.7795 2.18363C23.6959 1.96052 23.7516 1.80249 23.5285 1.51431C23.6308 1.5422 23.733 1.62586 23.826 1.58868C23.7981 1.58868 23.826 1.64445 23.8446 1.68164C23.8167 1.38416 24.1607 1.42135 23.9468 1.02161C24.2536 1.44923 24.2629 0.844989 24.4767 1.3005C24.5232 1.24472 24.4581 1.00302 24.4117 0.910061C24.6719 1.22613 24.6069 0.882173 24.8207 1.02161C24.6998 0.8171 24.8486 0.798508 24.8207 0.649771C24.8207 0.705547 24.8579 0.77062 24.9415 0.854285C24.895 0.668363 24.988 0.807804 25.1646 0.910061C25.1646 0.742732 24.9508 0.686955 24.8765 0.491737C25.0159 0.491737 25.0531 0.677659 25.1739 0.798508L25.0252 0.38948C25.0717 0.398776 25.1367 0.445257 25.2204 0.528921C25.1832 0.408072 25.1089 0.240743 25.2855 0.343L25.1925 0.435961L25.3599 0.566106L25.3041 0.268631C25.6666 0.361592 25.899 0.742732 26.1593 1.08669L26.1407 1.19824C26.2337 1.30979 26.3359 1.33768 26.3731 1.31909C26.4661 1.37487 26.5683 1.7746 26.5219 1.87685C26.3081 2.02559 26.1593 1.5236 25.9548 1.55149L25.9362 1.89545L25.8432 1.78389C25.7503 1.72812 25.8432 1.86756 25.8525 1.90474C25.7224 1.72812 25.6666 1.96982 25.5644 2.007L25.7131 2.12785C25.7968 2.63913 25.0903 2.02559 25.081 2.34166L25.1739 2.68561L24.9694 2.4904C25.0066 2.67632 25.1367 2.85294 24.9694 2.86224C24.2815 2.79717 24.2629 3.59663 23.6773 3.6803C23.7144 3.71748 23.7423 3.72678 23.7981 3.73607C23.0172 3.47578 23.7423 4.72146 23.0916 4.55413L23.0451 4.46117C22.9243 4.6285 22.9986 4.35891 22.7848 4.34032C22.9801 4.6192 22.7662 4.70287 22.7569 4.87949C22.7291 4.81442 22.7569 4.79583 22.7569 4.73075C22.6919 4.68427 22.5524 4.53554 22.5524 4.6192C22.7755 5.07471 22.5338 5.21415 22.4688 5.45585C22.3014 5.29782 22.0411 5.26063 21.7437 5.03752C21.7809 5.11189 21.8645 5.26993 21.9482 5.41866C21.7995 5.35359 21.8273 5.47444 21.8738 5.61388C21.9203 5.5674 21.9575 5.53022 21.9854 5.49303V5.51163C21.9854 5.51163 21.9947 5.48374 22.004 5.47444C22.0319 5.43726 22.0412 5.40937 22.0226 5.40937C22.2271 5.52092 22.1341 5.54881 22.3014 5.74403C22.2457 5.78121 22.1992 5.93925 22.0597 5.7998C22.0226 5.8184 21.9854 5.8184 21.9296 5.8184C21.9296 5.86488 21.9296 5.90206 21.8924 5.90206V5.87417C21.8924 5.87417 21.8366 5.83699 21.818 5.8184C21.6507 5.8184 21.7623 6.23672 21.7995 6.44123C21.6693 6.12517 21.5392 6.17165 21.3811 5.99502C21.3811 6.01361 21.4927 5.93925 21.6228 5.83699C21.5949 5.82769 21.5578 5.7998 21.502 5.73473C21.2324 5.63247 21.4648 6.06009 21.1859 6.06009C21.1859 6.03221 21.1673 5.97643 21.1022 5.91136C21 5.91136 21.0744 6.09728 21.158 6.21813C20.9907 6.0508 20.7676 6.02291 20.7676 6.15306C20.842 6.34827 20.907 6.40405 20.7955 6.46912L20.7304 6.31109C20.5259 6.30179 20.7955 6.57138 20.6188 6.55279C20.7025 6.57138 20.591 6.44123 20.5445 6.43194C20.4887 6.59927 20.5445 6.67364 20.6746 6.9897L20.5259 6.77589C20.5259 6.98041 20.5445 7.38014 20.3214 7.11055C20.7025 7.49169 20.2935 7.51028 20.2005 7.57536C20.2191 7.53817 20.154 7.44521 20.1169 7.39873C20.1726 7.82635 19.7636 7.7148 19.587 7.88213L19.2988 7.61254C19.2151 7.7055 19.6892 8.31904 19.5777 8.39341L19.494 8.21679C19.3546 8.4213 19.2523 8.45849 19.0664 8.54215L18.8991 8.33764C18.927 8.47708 18.8619 8.53285 18.8898 8.6723C18.3506 8.29116 18.6295 9.34161 17.9416 8.99766L18.2483 9.3788C18.1554 9.44387 18.1089 9.6112 17.83 9.3788H17.8579C17.6162 9.08132 17.7649 9.43458 17.6627 9.41598C17.6534 9.48106 17.7742 9.70416 17.8579 9.72275C17.4675 9.72275 17.3094 10.2154 16.8725 10.0109C16.7517 10.327 16.8446 10.7732 16.5658 10.9498L16.5286 10.9034C16.4077 10.9219 16.1474 10.9684 15.8778 10.6617C15.7663 10.8848 16.0359 11.4053 15.7012 11.4518L15.6454 11.2938C15.5432 11.2845 15.5897 11.4983 15.599 11.5541C15.5711 11.5634 15.5339 11.489 15.4967 11.4425C15.3573 11.3868 15.4688 11.5727 15.4595 11.6377L15.3851 11.5169C15.0319 11.4518 15.1435 12.1026 14.8925 12.242C14.9018 12.1769 14.7809 12.084 14.7158 12.0468C14.9389 12.4651 14.6229 12.5952 14.6136 12.7533L14.5485 12.5767C14.5764 12.9578 14.0744 12.3535 14.1116 12.7347L14.3812 12.8369C14.2603 12.8369 14.2603 12.9578 14.4184 13.0972C14.2324 13.0601 14.1767 12.8462 14.0186 12.9299C13.9257 12.8369 14.0465 12.7812 13.8978 12.6975L13.498 12.6045C13.498 12.6045 13.4423 12.5952 13.4144 12.6696C13.8141 13.0786 13.2935 12.8184 13.7583 13.153C13.5538 13.404 13.0983 13.311 13.0704 13.6922C12.6149 13.3668 12.6521 14.0547 12.1873 13.5156C12.0664 13.6178 12.0757 13.813 12.2059 14.0826C12.271 14.1012 12.2338 14.0083 12.2338 13.9618C12.3267 14.1198 12.2152 14.2685 12.1594 14.3243C12.1222 14.1384 12.1501 13.9246 12.02 13.6736C11.9642 13.8223 12.0014 14.1477 12.0107 14.2685L11.7318 14.0268C11.834 14.3057 11.4529 13.8781 11.6202 14.2221L11.7132 14.2871C11.5366 14.4173 11.7876 14.6869 11.6853 14.8542L11.5923 14.7426C11.4994 14.7426 11.676 15.068 11.3878 14.8821L11.4715 14.7798C11.2856 14.6032 11.1275 14.6032 11.0067 14.5381C10.9509 14.6869 11.267 14.8635 11.2484 14.9379C11.0532 14.7891 11.1554 14.8542 11.016 14.6497C10.9602 14.817 10.8951 15.0401 11.0439 15.3376C11.016 15.319 10.9788 15.2725 10.9788 15.2725C10.8394 15.3562 11.0625 15.7559 10.8487 15.6908V15.6444C10.4954 15.5049 10.8765 16.1092 10.4024 15.728C10.2816 15.7001 10.514 15.6444 10.2258 15.5142C9.95623 15.5328 10.5233 15.9418 10.2909 15.9511C10.3188 15.9511 10.2909 15.9325 10.2537 15.8861C10.1886 15.9883 10.1329 16.1464 10.0957 16.2858C9.60298 16.1185 9.90046 16.732 9.3148 16.574C9.51002 16.639 9.46354 16.7692 9.52861 16.8343C9.52861 16.8343 9.49143 16.7878 9.46354 16.7785C9.39847 16.8343 9.53791 16.983 9.58439 17.0667C9.41706 17.0016 9.58439 17.4385 9.46354 17.4013C9.54721 17.5036 9.48213 17.5501 9.43565 17.6244C9.43565 17.3455 9.28692 17.3363 9.18466 17.1131C9.02663 17.234 9.40776 17.8661 9.21255 18.0613C9.13818 18.0242 9.07311 17.987 8.99874 17.9405C9.20325 18.3867 8.99874 18.4983 9.07311 18.6656C8.98944 18.5726 8.92437 18.554 8.82211 18.303C8.82211 18.5354 8.65478 18.4239 8.74774 18.7957L8.8407 18.8236C8.72915 18.9073 8.71985 19.1955 8.70126 19.4929C8.68267 19.7811 8.65478 20.06 8.55253 19.9856L8.33872 18.9445C8.19927 18.647 8.33872 19.8462 8.17139 19.2977C8.24575 19.6417 8.23646 19.5022 8.25505 20.0042C8.29223 20.0135 8.28294 19.5952 8.32942 19.4929L8.34801 20.404L8.44097 19.6882C8.45956 20.2738 8.44097 20.1716 8.55253 20.5341C8.52464 21.0547 8.40379 20.5713 8.35731 20.7386C8.34801 20.7386 8.32942 20.7758 8.32012 20.8502C8.25505 20.6828 8.23646 20.2831 8.17139 20.06C8.12491 20.4411 7.94828 19.4093 7.9018 19.7718C7.86461 19.6417 7.94828 19.7997 7.92039 19.5673C7.85532 19.5673 7.80884 19.4744 7.79954 19.7253L7.87391 19.902C7.81813 19.809 7.82743 20.1716 7.69728 19.8276C7.64151 19.9577 7.60432 20.3296 7.68799 20.4318C7.6601 20.4504 7.57644 20.1344 7.60432 19.902C7.4277 19.6789 7.51136 20.6921 7.32544 20.0693C7.34403 20.0693 7.35333 20.0321 7.35333 19.9763C7.30685 19.8648 7.26967 19.8183 7.23248 19.8276C7.39981 19.9485 7.22318 19.1304 7.39051 19.4929C7.39051 19.0374 7.26037 19.2512 7.21389 19.0188C7.10234 19.1955 7.15811 19.5952 7.09304 19.7439C7.10234 19.6138 7.06515 19.5673 7.02797 19.4651L7.04656 19.8183C7.00008 19.7718 6.96289 19.716 6.90712 19.7253L7.00937 19.7068C6.91641 19.5394 6.86993 18.9352 6.67472 19.0281C6.73979 18.9631 6.85134 18.8236 6.79556 18.5726C6.60964 18.5726 6.78627 18.4146 6.75838 18.1264C6.60964 18.0242 6.60964 18.5633 6.44231 18.1543C6.42372 18.1264 6.38654 18.2937 6.38654 18.3867C6.28428 18.0892 6.12625 18.145 6.06117 17.8196C6.08906 17.9498 6.10765 18.0892 5.96821 18.0799C6.09836 17.9498 5.93103 17.7732 5.94032 17.6058L5.86596 17.6895C5.89384 17.5315 5.96821 17.5501 6.02399 17.5501C6.0054 17.5779 5.9961 17.6244 6.02399 17.6523C6.14484 17.6523 6.33076 17.2247 6.27498 17.0853C6.12625 17.0667 5.95892 17.327 5.91244 17.4478C5.83807 17.1782 5.44763 17.6802 5.40115 17.3548C5.36397 17.3084 5.55918 16.8529 5.50341 16.7134C5.25241 16.8064 5.48482 16.9923 5.27101 17.0667C5.56848 16.4345 4.68535 16.9551 4.78761 16.481L5.0479 16.3137C5.02001 16.2486 5.00142 16.1928 4.92705 16.1556L4.85268 16.3323C4.75972 16.3323 4.71324 16.1742 4.92705 16.0627C4.63887 16.1092 4.74113 15.9883 4.71324 15.8396C4.77831 15.9697 4.68535 15.8675 4.87127 15.8489C4.89916 15.6351 4.8062 15.6908 4.69465 15.6537C4.78761 15.5979 4.88987 15.4491 4.86198 15.4213C4.64817 15.4677 4.5738 15.3097 4.41577 15.2725L4.49013 15.2167C4.25773 15.1145 4.44365 14.6497 4.0904 14.6404C4.0904 14.6404 4.08111 14.6404 4.07181 14.6404V14.6683C3.88589 14.91 3.79293 14.6497 3.66278 14.6683C3.70926 14.6125 3.81152 14.5288 3.78363 14.4916C3.56982 14.659 3.6163 14.5102 3.49545 14.5567C3.52334 14.4359 3.76504 14.3615 3.67208 14.2685C3.6256 14.2407 3.50475 14.3243 3.42108 14.3894C3.51404 14.2778 3.55123 14.1477 3.53264 14.0733C3.60701 14.0454 3.55123 14.1384 3.57912 14.1384C3.69997 14.0547 3.6256 14.0547 3.77434 13.9432C3.75574 13.8781 3.55123 14.0826 3.57912 13.9618L3.79293 13.8874C3.82082 13.8316 3.71856 13.8502 3.69997 13.8502C3.77434 13.8502 3.94166 13.7201 4.04392 13.6364C3.81152 13.5899 3.56053 13.9618 3.36531 14.1012C3.3932 13.8595 3.08642 13.9246 2.99346 13.8223L3.21657 13.6922C3.1422 13.6643 3.07713 13.6736 2.97487 13.7201L2.9098 13.6364C3.02135 13.6364 3.09572 13.5992 3.26305 13.4784C3.1422 13.4319 3.10502 13.2832 2.81684 13.4598L2.86332 13.4319C2.87261 13.246 2.75177 12.9578 2.85402 12.902C2.6681 12.8462 2.71458 12.5674 2.4357 12.7626C2.31485 12.7347 2.64951 12.3164 2.26837 12.5116C2.38922 12.2885 2.34274 12.4558 2.56584 12.335C2.68669 12.1211 2.15682 12.3628 2.52866 12.0468C2.33344 12.0282 2.46359 12.1304 2.25907 12.2234C2.61232 11.9352 2.1847 11.991 2.32415 11.74C2.14752 11.8051 2.25907 11.8516 2.05456 11.8887C2.15682 11.833 2.13822 11.7772 2.13822 11.7493L1.89653 11.8887L2.39851 11.3868C2.01737 11.4332 2.01737 11.6935 1.77568 11.5727H1.80356C2.00808 11.3496 1.52468 11.5541 1.60835 11.2845C1.59905 11.3682 1.73849 11.2287 1.81286 11.2008L1.66412 11.1822C1.66412 11.1822 1.70131 11.1822 1.7199 11.1451C1.85005 10.9591 1.58046 11.1451 1.68272 10.9591C1.76638 10.987 1.93371 10.8476 2.00808 10.7639L1.66412 10.8197L2.01737 10.6524C1.97089 10.5222 1.33876 10.6803 1.75708 10.3363L1.84075 10.3642C1.91512 10.3084 2.13822 10.1318 1.92441 10.1597C1.86864 10.1597 1.66412 10.2619 1.70131 10.2898L1.73849 10.1876C1.97089 10.0853 2.11963 10.1876 2.23118 10.234C2.12893 10.2619 2.01737 10.234 1.89653 10.3456C2.01737 10.3828 2.2033 10.3642 2.32415 10.3921C2.22189 10.42 2.07315 10.485 1.98019 10.5222C1.92441 10.6803 2.16611 10.4943 2.23118 10.5408C2.16611 10.6245 2.11963 10.671 2.03597 10.6988C2.17541 10.7267 2.24048 10.7732 2.1847 10.9312C2.1847 10.9312 1.97089 10.9312 1.87793 11.0707C2.11034 11.1451 2.37992 11.0056 2.64021 11.0707C3.12361 11.0149 2.68669 11.5913 3.03065 11.5448C3.12361 11.489 3.12361 11.331 3.24446 11.3775C3.04924 11.4983 3.16079 11.5169 3.09572 11.5727C3.43038 11.4704 3.13291 11.7493 3.36531 11.6842C3.29094 11.7121 3.25375 11.8237 3.21657 11.898C2.98417 12.0561 3.19798 12.0654 2.77965 12.1676C3.22587 12.0561 2.87261 12.4837 3.47686 12.1955L3.51404 12.1118V12.3257V12.3164C3.51404 12.4 3.58841 12.3721 3.41179 12.6231C3.32812 12.6231 3.29094 12.5767 3.20727 12.5859C3.06783 12.8091 3.48616 12.6138 3.56053 12.6882C3.3932 12.8091 3.43968 12.6417 3.25375 12.8184C3.27235 12.8927 3.43038 12.8555 3.51404 12.8741L3.42108 12.9299C3.32812 13.2274 3.90448 12.651 3.68137 12.9857C3.72785 12.9392 3.80222 12.9113 3.8487 12.8648C3.78363 12.9764 3.69067 13.1902 3.50475 13.1809C3.54193 13.2274 3.66278 13.2274 3.78363 13.1809C3.88589 13.0415 3.81152 13.0786 3.96955 12.9299L4.22055 13.0601C4.22055 13.0601 4.11829 13.1065 4.0997 13.0786C3.80222 13.6829 4.87127 13.246 4.49943 13.9525C4.62028 13.813 4.64817 13.8688 4.75972 13.8223C4.77831 13.9432 4.91775 14.0454 4.88987 14.1942L4.76902 14.2499C5.0479 14.3615 5.31749 14.3801 5.36397 14.5567C5.41045 14.5288 5.22453 14.6683 5.16875 14.6683C5.42904 14.6218 4.94564 15.1981 5.35467 14.9193V14.8542C5.44763 15.1052 5.89384 15.0959 6.10765 15.2632C5.91244 15.4956 5.9868 15.1703 5.7544 15.4306C5.77299 15.6444 6.08906 15.6258 6.12625 15.8396C6.07977 15.8396 6.05188 15.8675 6.03328 15.8675C6.0054 16.1371 6.2471 15.663 6.32146 15.821C6.20061 15.9047 6.18202 15.9325 6.15413 16.0255L6.36794 15.9139C6.36794 15.9139 6.20061 16.0627 6.13554 16.0906C6.41442 15.9418 6.36794 16.2114 6.59105 16.0348C6.54457 16.0999 6.34006 16.2765 6.27498 16.3695C6.27498 16.4996 6.37724 16.4531 6.4795 16.3973C6.38654 16.6019 6.48879 16.6855 6.45161 16.6948C6.48879 16.89 6.56316 16.574 6.7212 16.481L6.73979 16.2951L6.86993 16.3509L6.75838 16.4438C6.74908 16.6112 6.92571 16.4252 6.96289 16.481L7.01867 16.2765C7.01867 16.2765 7.08374 16.2393 7.11163 16.2207C6.97219 16.6019 7.14882 16.388 6.96289 16.7971C7.03726 17.1596 7.24178 16.7041 7.32544 16.7506C7.30685 16.732 7.30685 16.8343 7.28826 16.9086C7.33474 17.0853 7.39981 16.8807 7.43699 16.6483C7.4184 16.7971 7.40911 16.8436 7.39051 16.9644C7.45559 17.0481 7.44629 16.7227 7.51136 16.6297C7.49277 16.8343 7.49277 16.9551 7.51136 17.0295C7.51136 16.8343 7.52996 16.7041 7.53925 16.6669C7.48347 17.6802 7.62292 17.2061 7.60432 18.0428C7.61362 17.8289 7.71588 17.4757 7.6508 16.9644V17.0295C7.62292 16.7134 7.6508 16.8621 7.6601 16.8529C7.6601 16.8993 7.6508 16.9551 7.6601 17.0202C7.68799 16.89 7.72517 16.9365 7.74377 16.9179C7.76236 16.8622 7.78095 16.8343 7.79025 16.7506C7.79025 16.7041 7.79954 16.6483 7.79954 16.574C7.81813 16.6948 7.82743 16.9458 7.85532 17.0016C7.94828 17.0016 7.88321 16.3695 7.85532 16.0627C8.03194 16.6205 7.82743 16.2579 7.96687 16.8436C8.01335 16.5368 8.03194 16.1928 7.96687 15.8582C8.15279 16.1649 8.1435 16.0534 8.11561 15.9418C8.08772 15.821 8.04124 15.7187 8.23646 15.8768C8.08772 15.7094 8.05983 15.6165 8.06913 15.5793C8.18998 15.7187 8.21787 15.6815 8.30153 15.7745C8.24575 15.6815 8.20857 15.6072 8.23646 15.5793C8.25505 15.57 8.39449 15.5142 8.55253 15.663C8.23646 15.3934 8.70126 15.4956 8.52464 15.2539C8.72915 15.2446 8.62689 14.975 8.83141 14.9286C8.59901 14.8077 8.8407 14.7241 8.79422 14.6125C8.79422 14.6404 8.79422 14.6869 8.83141 14.7055C9.02663 14.8077 8.80352 14.4359 8.97085 14.4545C9.06381 14.4824 9.13818 14.6218 9.20325 14.5846C9.06381 14.4638 9.07311 14.1384 9.29621 14.2221C9.26832 14.2499 9.3334 14.315 9.37058 14.3801C9.42636 13.8502 10.0213 13.7851 10.0585 13.2274L10.2165 13.497C10.6813 13.5899 9.98412 13.0136 10.17 12.8927C10.6906 12.5952 11.425 12.5209 11.6853 12.0003C11.6574 11.9073 11.5923 11.9352 11.4994 11.8423C11.5645 11.8423 11.7411 12.0189 11.6853 11.8516L11.5645 11.74C12.0479 11.898 11.8898 11.0242 12.5034 11.4146C12.5034 11.0614 12.931 11.2752 12.8752 10.7918C13.0425 10.8383 12.9868 11.0707 13.1076 11.0242L13.1355 10.6524V10.6803C13.0054 10.1411 14.0186 10.6245 14.0279 10.1504V10.1783C14.1023 10.2712 14.251 10.327 14.2603 10.2619C14.2231 10.1876 14.1674 10.1783 14.0744 10.1318C14.1581 9.79712 14.2045 9.74135 14.3533 9.56472C14.3905 9.75994 14.5206 9.6112 14.6879 9.78783C14.6322 9.62979 14.502 9.62979 14.5113 9.44387C14.6415 9.29513 14.911 9.33232 15.0784 9.29513C14.9854 9.09062 15.0877 9.08132 14.9203 8.88611C15.0691 8.72807 15.097 8.57004 15.2922 8.40271L15.3573 8.46778C15.1992 8.1796 15.6361 8.43989 15.5525 8.26327C15.6268 8.35623 15.6361 8.41201 15.7012 8.46778L15.7198 8.30975C15.7384 8.4213 15.9243 8.6723 16.0173 8.63511C15.9429 8.39341 15.8964 8.53285 15.8035 8.36552L16.0266 8.57004C16.0638 8.49567 15.85 8.22608 15.7198 8.21679C15.9243 8.04016 16.0266 7.76128 16.2311 7.64043L16.3426 7.80776C16.3891 7.66832 16.5286 7.54747 16.6959 7.63113C16.6587 7.58465 16.6122 7.4824 16.5565 7.44521C16.5007 7.13844 16.7796 7.67761 16.7238 7.35225C16.7424 7.43592 16.7238 7.50099 16.7982 7.59395L16.8818 7.20351C16.9841 7.31507 17.3466 7.43592 17.3559 7.24999C17.3094 7.18492 17.2072 7.12914 17.17 7.13844L17.1886 7.02689L17.4675 7.2407L17.3652 6.93393L17.5511 7.14774C17.579 7.04548 17.3745 6.73871 17.4396 6.71082C17.7742 6.66434 17.7928 6.77589 18.1182 6.85026C17.7742 6.42264 18.3692 6.66434 18.1554 6.32968C18.6202 6.46912 18.7503 6.03221 19.0943 5.89277V5.94854C19.3825 6.0415 18.9641 5.52092 19.1594 5.50233L19.178 5.58599C19.5219 5.67896 19.6242 5.24204 19.6242 4.93527C19.6428 5.01893 19.7729 5.13978 19.8101 5.0933C19.7822 4.98175 19.5219 4.83301 19.6706 4.84231C19.6799 4.89808 19.7822 4.98175 19.8008 4.96316L19.7078 4.68427C20.0425 4.64709 20.4236 4.58202 20.5445 4.26595C20.6467 4.30313 20.6839 4.40539 20.7304 4.48906C20.8698 4.29384 20.8977 3.96847 21.0279 3.80115L21.251 4.03355C21.3254 3.96847 20.9907 3.62452 21.2696 3.75466C21.3161 3.76396 21.2138 3.82903 21.2696 3.95918C21.5856 4.00566 21.1673 3.64311 21.3346 3.54085L21.5299 3.84763C21.7809 3.9127 21.5392 3.59663 21.4462 3.39212C21.3346 2.93661 22.004 3.81974 22.0226 3.39212C21.9482 3.22479 21.8459 3.2062 21.7623 3.03887C21.9761 2.98309 21.8366 2.76928 22.0504 2.7135C22.4781 3.04816 21.9668 2.77858 22.3851 3.08535H22.1899C22.4688 3.22479 22.1434 3.22479 22.3665 3.45719C22.506 3.45719 22.4502 3.15971 22.4781 2.99239C22.6361 3.17831 22.3758 3.11323 22.6361 3.31775V3.1969C22.6547 3.26197 22.7105 3.33634 22.6733 3.35493C22.8313 3.51297 22.7384 3.31775 22.7848 3.27127C22.7105 3.16901 22.5896 3.03887 22.4688 2.92731C22.4874 2.9459 22.506 2.9645 22.5338 2.98309C22.413 2.63913 22.7477 2.69491 22.664 2.41603C22.6919 2.4811 22.7198 2.4904 22.7569 2.52758C22.822 2.4904 22.6826 2.19292 22.7105 2.05348C22.8685 2.15574 23.0265 2.4811 23.0916 2.29518C22.9894 2.12785 22.7105 1.91404 22.822 1.82108C22.822 1.82108 22.822 2.02559 22.9708 2.09066L22.9801 2.12785ZM20.8327 4.54483C20.8327 4.54483 20.8048 4.57272 20.7862 4.60061C20.7862 4.60061 20.8141 4.55413 20.8234 4.54483H20.8327ZM20.7769 4.8702C20.7769 4.8702 20.749 4.77723 20.6839 4.71216C20.6467 4.74005 20.6188 4.76794 20.5817 4.78653C20.6653 4.81442 20.749 4.81442 20.7769 4.8702ZM22.1341 5.67896L22.1527 5.70684C22.1527 5.70684 22.1248 5.76262 22.1155 5.78121C22.1527 5.8184 22.1992 5.84628 22.2085 5.79051C22.1899 5.76262 22.162 5.71614 22.1341 5.67896Z\" fill=\"#8F3A7E\"><\/path><path d=\"M22.0416 5.47307C22.0416 5.47307 22.0416 5.45466 22.0416 5.44546C22.0231 5.43626 22.0047 5.42705 21.9863 5.41785L22.0231 5.49148L22.0416 5.47307Z\" fill=\"#8F3A7E\"><\/path><path d=\"M4.04395 14.6689C4.04395 14.6689 4.05317 14.6597 4.06239 14.6413C4.06239 14.6505 4.05317 14.6597 4.04395 14.6689Z\" fill=\"#8F3A7E\"><\/path><path d=\"M17.3184 6.90505L17.365 6.96105L17.3464 6.89572L17.3184 6.90505Z\" fill=\"#8F3A7E\"><\/path><path d=\"M3.82129 12.9043C3.82129 12.9043 3.84973 12.8664 3.85921 12.8474C3.84973 12.8569 3.83077 12.8759 3.82129 12.9043Z\" fill=\"#8F3A7E\"><\/path><path d=\"M3.47742 12.3441L3.49602 12.2139C3.47742 12.279 3.47742 12.3162 3.47742 12.3441Z\" fill=\"#8F3A7E\"><\/path><path d=\"M3.28078 11.8598C3.28078 11.8598 3.21608 11.8967 3.18835 11.9152L3.28078 11.8598Z\" fill=\"#8F3A7E\"><\/path><path d=\"M6.45996 16.4436C6.45996 16.4436 6.54407 16.3969 6.57211 16.3875C6.57211 16.3408 6.55342 16.3221 6.45996 16.4436Z\" fill=\"#8F3A7E\"><\/path><path d=\"M6.62872 16.4611C6.62872 16.3873 6.6195 16.3781 6.57336 16.3873C6.57336 16.4242 6.58259 16.4703 6.62872 16.4611Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.17539 10.0107V9.98242C2.17539 9.98242 2.14712 10.0013 2.1377 10.0013H2.17539V10.0107Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.12949 10.0114H2.0918C2.0918 10.0114 2.10122 10.0208 2.12949 10.0114Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.00806 9.99291H2.09124C2.09124 9.99291 2.07275 9.96519 2.00806 9.99291Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.41699 10.6243L2.50017 10.5781C2.50017 10.5781 2.45396 10.5966 2.41699 10.6243Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.55659 10.7733C2.55659 10.7177 2.65855 10.5601 2.57513 10.5416L2.51025 10.5787C2.64001 10.5231 2.39903 10.8289 2.55659 10.7733Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.07381 12.1401L2.0366 11.9541C1.97149 12.0378 1.88778 12.1494 1.82268 12.0936C1.70176 12.4471 1.9808 11.9262 2.08311 12.1401H2.07381Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.27776 12.6685C2.18469 12.622 2.15677 12.7523 2.11023 12.7895C2.22192 12.7895 2.24984 12.7895 2.27776 12.6685Z\" fill=\"#8F3A7E\"><\/path><path d=\"M4.62895 15.747L4.43384 15.8864C4.50817 15.9235 4.50817 15.8306 4.62895 15.747Z\" fill=\"#8F3A7E\"><\/path><path d=\"M6.05145 15.5506L6.11649 15.4112L5.93066 15.5134L6.05145 15.5506Z\" fill=\"#8F3A7E\"><\/path><path d=\"M5.00248 16.9545H4.95605C5.00248 16.9638 5.0489 16.973 5.10461 17.0009C5.05819 16.973 5.03962 16.973 5.00248 16.9545Z\" fill=\"#8F3A7E\"><\/path><path d=\"M10.2145 16.5729L9.97351 16.4061C9.98278 16.471 10.2423 16.6842 10.2145 16.5729Z\" fill=\"#8F3A7E\"><\/path><path d=\"M11.8059 14.4079C11.9267 14.4915 12.0475 14.5101 11.9824 14.3708C11.9267 14.3986 11.7966 14.3615 11.8059 14.4079Z\" fill=\"#8F3A7E\"><\/path><path d=\"M18.3037 9.16579L18.3223 9.2774L18.3502 9.14719L18.3037 9.16579Z\" fill=\"#8F3A7E\"><\/path><path d=\"M1.64564 9.73384C1.52494 9.65027 1.46923 9.91025 1.50637 9.71527C1.6085 9.67813 1.69207 9.65956 1.64564 9.73384Z\" fill=\"#8F3A7E\"><\/path><path d=\"M25.5929 1.03314C25.7137 1.86049 24.812 1.67457 24.7376 2.32529C24.7097 2.38107 24.4959 2.01852 24.4587 2.16726C24.4587 2.88306 23.6872 3.09687 22.9807 3.13405L22.9342 3.0318C22.804 3.0318 22.9342 3.40364 22.8133 3.44083C22.7669 3.38505 22.7761 3.33857 22.6925 3.28279C22.8133 3.46871 22.5995 3.4966 22.6646 3.64534C22.5716 3.60815 22.4694 3.46871 22.3578 3.43153L22.4694 3.66393C22.7111 4.23099 22.1068 3.91493 22.1161 4.30536C22.0882 4.24959 22.0789 4.2031 22.0232 4.17522C21.9488 4.70509 21.5305 4.97468 21.2795 5.36512C21.233 5.29075 21.14 5.15131 21.0564 5.09553C21.2051 5.30934 21.1493 5.44878 21.0936 5.56963C20.8797 5.393 21.0936 5.8857 20.8983 5.8671L20.8704 5.81133C20.9727 6.09021 20.6473 5.78344 20.8054 6.09951L20.6195 5.97866C20.8333 6.29472 20.3778 5.92288 20.4428 6.1274L20.4986 6.18317C20.4986 6.30402 20.3406 6.18317 20.3313 6.28543L20.2941 6.25754C20.229 6.44346 20.0152 6.3505 20.2104 6.57361C20.0059 6.43417 20.2662 6.37839 19.9687 6.18317C19.7363 6.78742 19.2436 7.12208 18.816 7.50322C18.6859 7.45674 18.6301 7.45674 18.5464 7.38237C18.5464 7.46603 18.4163 7.56829 18.4814 7.71703C18.4906 7.69843 18.3512 7.62407 18.3233 7.63336C18.1746 7.61477 18.4535 7.95872 18.2768 7.93084C18.2582 7.83788 18.2118 7.75421 18.1281 7.67984C18.2025 7.92154 18.0816 7.97732 18.0444 8.10746C18.0258 8.06098 18.0258 8.0145 17.9608 7.94943C18.0351 8.22831 17.747 8.06098 17.7749 8.2562L17.6912 8.09817C17.4216 8.06098 17.8864 8.40494 17.6912 8.41423C17.6912 8.34916 17.6261 8.30268 17.5889 8.2469C17.6819 8.58156 17.4402 8.65593 17.403 8.82326C17.403 8.79537 17.3658 8.76749 17.3658 8.76749C17.2729 8.89763 17.0869 8.93481 17.0498 9.14862C16.9475 9.13003 16.7895 8.82326 16.7058 8.98129C16.9382 9.23229 16.585 9.27877 16.9196 9.50188C16.7802 9.54836 16.5199 9.60413 16.5292 9.75287C16.492 9.61343 16.1945 9.48328 16.2689 9.38103L16.0644 9.28807C15.9807 9.17651 16.1666 9.26018 16.0272 9.14862C15.99 9.19511 15.9528 9.41821 15.8784 9.40891C15.9342 9.64132 16.1201 10.0039 16.0179 10.1526C15.99 9.99457 15.7297 9.90161 15.7297 9.81794L15.9807 10.478C15.9435 10.5337 15.7855 10.2827 15.7855 10.4036C15.8506 10.4687 15.8599 10.5337 15.8877 10.6081C15.8413 10.5895 15.7669 10.8312 15.5159 10.6081C15.4043 10.5244 15.5438 10.4873 15.4136 10.4408C15.3393 10.5151 15.4136 10.6081 15.33 10.6825L15.3021 10.6546C15.2184 10.6639 15.237 10.9056 15.4229 10.9892C15.4694 10.9614 15.2742 10.8498 15.3951 10.8777C15.488 11.0543 15.4322 11.1845 15.3579 11.2588C15.3579 11.1938 15.2835 11.1287 15.2277 11.045C15.3021 11.3425 15.237 11.5098 15.1905 11.6958C15.2928 11.8166 15.0418 11.4355 15.1162 11.4819C14.8094 11.4541 15.0139 12.0118 14.6607 11.8817C14.6607 11.8445 14.828 12.0397 14.7908 12.0118C14.7071 12.0676 14.5491 11.891 14.5584 11.9932C14.4654 11.891 14.5305 12.0769 14.5026 12.1606C14.5398 12.2535 14.4469 12.1234 14.4747 12.0676C14.4747 12.2163 14.3446 12.6254 14.0564 12.6254C14.1215 12.6904 14.1866 12.96 14.1401 12.9879L14.0099 12.8206C13.8891 12.7555 13.8984 12.9507 13.7682 12.8206C13.8612 13.0809 13.9263 12.3837 13.9542 12.6254C13.8054 12.5231 14.0378 13.0065 13.8612 12.7741C13.7961 12.8485 13.8798 13.0902 13.6753 13.0065C13.7218 13.0065 13.5358 12.7369 13.4894 12.802C13.4057 12.9228 13.5265 12.9042 13.4894 13.0344V13.1459C13.6288 13.304 13.3871 13.211 13.5823 13.3412C13.4522 13.2296 13.4986 13.555 13.2755 13.2947L13.1082 13.0809C13.0803 13.1366 13.2291 13.3598 13.2755 13.4806C13.257 13.4713 13.2012 13.4341 13.1733 13.4062C13.4429 13.713 13.0431 13.4806 13.2105 13.7688C13.0153 13.7502 12.9595 13.9826 12.7364 13.8339C12.7457 13.9919 12.7829 14.1592 12.6434 14.1778C12.6341 14.1313 12.6434 14.1034 12.5876 14.0384C12.4575 14.0012 12.5133 14.0848 12.5133 14.1778C12.4854 14.122 12.2437 14.1034 12.0856 14.0477C12.1042 14.2057 12.2809 14.3451 12.3645 14.4474C12.0206 14.215 12.3459 14.8285 12.0113 14.6333C11.9927 14.5682 11.9741 14.3916 11.8439 14.373C11.5 14.1406 11.9276 14.717 11.6859 14.6705L11.9462 14.8843C11.751 14.7821 11.9369 15.1725 11.7045 14.9122C11.7603 15.033 11.5093 14.9494 11.751 15.1725C11.3884 15.1446 11.4814 15.6838 10.9608 15.3863C10.9794 15.4514 10.8772 15.47 11.0166 15.5722C11.1839 15.6559 10.9701 15.4235 11.0817 15.4979C11.0724 15.5257 11.1281 15.5908 11.1653 15.628C11.0631 15.628 11.0073 15.6559 10.8493 15.4142C10.589 15.3956 11.1467 15.9162 10.9236 15.972C10.8307 15.8697 10.7749 15.8511 10.7563 15.9069L10.8586 16.1393C10.7377 16.1951 10.5797 15.9905 10.3938 15.8418C10.3752 15.9162 10.3101 15.9812 10.4309 16.1114L10.1521 15.9905C10.3566 16.0742 10.2264 16.1207 10.245 16.1858L10.2171 16.1207C10.1335 16.0649 10.1242 16.1672 10.1242 16.2229C10.245 16.3066 10.338 16.2787 10.4031 16.2694C10.4588 16.3624 10.4031 16.3903 10.4681 16.5018C10.3008 16.3438 10.2729 16.4832 10.2264 16.5111C10.1521 16.5297 10.3473 16.6878 10.3287 16.697C10.2357 16.6227 10.2543 16.7621 10.1521 16.6227C10.1335 16.5855 10.2729 16.6506 10.2078 16.5669C10.1149 16.5483 9.95684 16.4182 10.0219 16.5669C10.0684 16.6878 10.3845 16.8272 10.1985 16.8365C10.1706 16.7807 10.1056 16.7156 10.0498 16.6506L9.89177 16.6692L10.0591 16.7993C10.0126 16.7807 10.0033 16.7621 9.97543 16.7528C10.1428 16.8923 9.90106 16.9666 10.0591 17.1711C10.0219 17.2641 9.83599 17.2455 9.77092 17.3106V17.2827C9.62218 17.2827 9.61288 17.4686 9.65936 17.6638L9.63148 17.6267C9.63148 17.6267 9.53852 17.8033 9.585 18.0078C9.41767 18.0264 9.06442 17.3199 9.15738 17.7196C9.1016 17.8498 9.28752 18.3425 9.38978 18.4261C9.18526 18.5284 9.23174 19.3743 8.94357 19.207C8.97145 19.3743 9.00864 19.4208 8.99005 19.5974C8.77624 19.9228 8.70187 21.1313 8.42298 20.6851C8.44158 20.3783 8.35791 20.2482 8.31143 19.9972C8.33002 20.3597 8.26495 20.0158 8.26495 20.1087C8.26495 20.1366 8.27425 20.211 8.29284 20.3783C8.33002 20.6014 8.34862 20.7594 8.3765 20.8896C8.3951 20.9732 8.41369 21.029 8.45087 21.0383C8.45087 21.0941 8.43228 21.1406 8.42298 21.2057C8.36721 21.2428 8.30214 21.2149 8.22777 21.1499C8.19058 21.1127 8.16269 21.0662 8.12551 21.0197C8.08833 20.9454 8.05114 20.8524 8.03255 20.7687C8.08833 20.9732 8.06973 21.029 8.03255 21.0848C7.99536 20.5828 7.88381 20.3783 7.80015 20.4434V20.7316L7.72578 20.3597C7.69789 20.4155 7.70719 20.9268 7.60493 20.5363C7.60493 20.4248 7.58634 20.3039 7.57704 20.2017C7.49338 20.3318 7.33534 20.5363 7.24238 20.1831L7.17731 19.6997C7.17731 19.6997 7.03787 19.8298 7.11224 20.025C6.9542 19.5881 6.84265 19.4301 6.84265 19.0768C6.44292 19.4673 5.89445 18.863 5.55049 18.3796L5.63416 18.2681C5.60627 18.0357 5.44824 18.4168 5.42964 18.2495C5.5319 18.1751 5.5226 17.9241 5.68064 17.8684C5.64345 17.5988 5.38316 17.8684 5.25302 17.8126C5.12287 17.9427 5.39246 17.8126 5.23443 17.9706C5.17865 17.9985 5.14146 17.636 4.93695 17.8126C4.97413 17.6917 5.14147 17.5802 5.23443 17.5151H5.0671C5.20654 17.1897 5.66205 17.3478 5.82938 16.9387L5.74571 16.9016C5.89445 16.6413 6.09896 16.8272 6.04319 16.6041C5.90374 16.6413 5.55979 16.8458 5.5412 17.0038C5.35528 16.8923 5.00202 17.3664 4.85329 17.1433C4.92765 16.9852 5.02062 17.2827 5.15076 17.0968C5.23443 16.8551 4.91836 17.0038 4.93695 16.9016C4.90906 17.0317 4.64877 17.1433 4.5837 17.134C4.62088 16.9852 4.8161 17.0224 4.76032 16.9016C4.62088 16.9852 4.46285 16.9666 4.44426 17.1154C4.13749 17.3013 4.44426 16.948 4.17467 17.0689C4.342 16.883 4.70455 16.8086 4.71384 16.6227C4.53722 16.79 4.3513 16.6878 4.11889 16.9759C4.13749 16.8923 4.27693 16.7621 4.42567 16.7063C4.49074 16.5483 3.96086 16.8272 4.31411 16.5111L4.1096 16.6413C4.15608 16.5762 4.18397 16.5018 4.25834 16.3903C4.22115 16.3345 3.8586 16.4182 4.14678 16.1951C4.1003 16.1951 4.01664 16.0649 3.84931 16.2694C3.79353 16.4461 4.06312 16.2415 3.83072 16.5018C4.00734 16.2694 3.70987 16.4089 3.59831 16.4275L3.70057 16.3345C3.6355 16.3345 3.60761 16.2601 3.47746 16.3345C3.56113 16.3066 3.6262 16.2322 3.6355 16.1858L3.44028 16.288C3.26365 16.2415 3.71916 16.0277 3.58902 15.9534L3.78424 15.9255C3.78424 15.9255 3.8772 15.7674 3.78424 15.7581C3.60761 15.8604 3.3938 15.972 3.26365 16.0463C3.1521 16.0463 3.42169 15.879 3.20788 15.9441L3.45887 15.8697C3.52395 15.8418 3.67268 15.6094 3.60761 15.535C3.51465 15.535 3.22647 15.6187 3.19858 15.7674C3.1614 15.7303 3.21717 15.6001 3.35662 15.5443C3.22647 15.4979 3.19858 15.6838 3.04055 15.6838C3.11492 15.5722 3.18929 15.3491 3.29154 15.1725L3.61691 15.0516L3.57972 14.9959C3.84931 14.9029 3.70987 14.8378 3.96086 14.6984C3.96086 14.6333 3.8586 14.6519 3.77494 14.6519C3.50535 15.0423 3.18929 14.9029 2.89181 15.1911C2.6873 15.1074 3.60761 14.4846 2.97548 14.717C2.9104 14.8099 2.60363 14.9215 2.77096 14.9494C2.73378 14.8285 2.39912 15.1353 2.4456 14.9215C2.64082 14.9029 2.70589 14.5775 2.99407 14.5497C2.88252 14.624 2.96618 14.6798 3.01266 14.6705C3.10562 14.5404 3.34732 14.4288 3.27295 14.3265C3.19858 14.2894 3.12421 14.215 2.96618 14.3544C2.78026 14.5032 3.05914 14.4288 2.83603 14.5404C2.678 14.4753 2.94759 14.2336 2.58504 14.4381C2.6687 14.4939 2.49208 14.6612 2.36193 14.7542L2.2132 14.7263L2.35264 14.6519C2.33405 14.4474 2.09235 14.7821 2.02727 14.624L2.22249 14.373C2.45489 14.2429 2.27827 14.6426 2.60363 14.3544C2.54786 14.2522 2.35264 14.3544 2.38053 14.2057C2.42701 14.2057 2.45489 14.2243 2.49208 14.215C2.48278 14.1778 2.9104 13.7967 2.54786 13.871C2.39912 13.8896 2.40841 13.9454 2.27827 14.0384C2.12953 13.9268 1.9715 13.9826 1.87854 13.9082C2.14812 13.7409 1.78558 13.7316 2.12024 13.6386C2.00868 13.7967 2.17601 13.9919 2.45489 13.8617C2.71519 13.5829 2.50138 14.0012 2.82674 13.806C2.75237 13.6851 3.04984 13.4713 3.22647 13.304C3.21717 13.2668 3.11492 13.2947 3.06844 13.304C2.87322 13.4248 2.9104 13.462 2.72448 13.6107C2.678 13.4434 2.49208 13.3969 2.25968 13.462C2.31545 13.3505 2.51067 13.2296 2.56645 13.2668C2.39912 13.1552 2.30616 12.9786 2.25968 12.7927C2.02727 13.1088 2.07376 12.6811 1.86924 12.9321C1.85995 13.0623 1.69262 13.2854 1.52529 13.3412C1.50669 13.2761 1.65543 13.2482 1.71121 13.1831C1.4974 13.2389 1.90643 12.8949 1.59965 13.0251C1.79487 13.0995 1.99009 12.7834 2.24108 12.644C2.03657 12.644 2.40841 12.5231 2.34334 12.4301C2.13883 12.4301 1.94361 12.3744 1.81346 12.3C1.94361 12.0025 1.56247 11.9375 1.46951 11.8166C1.54388 11.6679 1.85065 11.5284 1.84135 11.4262C1.77628 11.3425 1.59036 11.6865 1.62754 11.4819L1.69262 11.4541C1.59965 11.4541 1.7205 11.1008 1.30218 11.3239L1.62754 11.1659C1.62754 11.1659 1.55317 11.1473 1.51599 11.1473C1.60895 11.0822 1.68332 10.9985 1.76698 10.9892C1.92502 10.7754 1.62754 10.8498 1.56247 10.7661L1.42303 10.9335C1.19063 10.8777 1.30218 10.6639 1.15344 10.5616L1.33007 10.4594L1.17203 10.4408C1.35796 10.3571 1.42303 10.2177 1.2464 10.2549L1.81346 10.2084C1.74839 10.3292 1.56247 10.2735 1.41373 10.4129C1.28359 10.5337 1.41373 10.6453 1.59036 10.5523C1.58106 10.4873 1.53458 10.5152 1.45092 10.5152C1.68332 10.3478 1.7205 10.4315 1.90643 10.3664C1.87854 10.3478 1.93431 10.2642 1.85065 10.3106C1.99939 10.2827 2.05516 10.3292 2.11094 10.4036C1.98079 10.4036 1.98079 10.5337 1.89713 10.5523C2.11094 10.4222 2.23179 10.4594 2.24108 10.5988C2.04587 10.8312 2.52926 10.6825 2.53856 10.8498C2.29686 10.9428 2.08305 10.9985 1.95291 10.98C1.89713 11.1287 2.01798 11.0636 1.95291 11.2124C2.13883 11.138 2.38982 11.0078 2.55715 11.0357L2.40841 11.1473C2.54786 11.1845 2.78026 11.0171 2.80815 11.1566C2.86392 11.3983 3.00336 11.5935 3.08703 11.7515L2.93829 11.8631C3.31943 11.705 3.25436 12.0397 3.47746 12.0397C3.46817 12.3279 3.91438 12.3279 3.71916 12.6161C4.07241 12.8485 4.39778 13.0437 4.593 13.4062L4.3327 13.5178C4.53722 13.4527 4.23974 13.6479 4.31411 13.6851C4.43496 13.4806 4.60229 13.5922 4.76962 13.5271C4.71384 13.806 5.03921 13.8524 5.2902 13.8617L5.14146 13.9826C5.5226 13.8896 5.40176 14.2429 5.48542 14.4381C5.43894 14.5032 5.31809 14.6426 5.37387 14.6798C5.68064 14.5775 5.69923 14.6333 5.95022 14.6426C6.02459 14.7356 6.08967 14.9308 6.07107 15.1074C6.37784 15.1446 6.55447 15.3026 6.7125 15.47C6.80546 15.5722 6.84265 15.6094 6.87983 15.6373C6.92631 15.6652 6.98209 15.6838 7.05646 15.6745L6.92631 15.8697C7.14942 15.7674 7.1866 15.7953 7.24238 15.8883C7.28886 15.972 7.34464 16.1114 7.40971 15.9998L7.32605 16.4925C7.34464 16.7063 7.4283 16.4646 7.4469 16.0649C7.46549 16.2694 7.51197 15.8604 7.53056 16.3624C7.56774 16.5111 7.56774 16.13 7.57704 16.0649C7.60493 16.2137 7.63282 16.288 7.65141 16.3066C7.67 16.3066 7.67 16.2137 7.67 16.13V16.1021C7.67 16.2508 7.70719 16.5297 7.72578 16.5483C7.72578 16.4739 7.72578 16.4554 7.72578 16.4368C7.73507 16.3996 7.74437 16.3438 7.6607 15.8976C7.70719 16.0742 7.71648 15.9441 7.71648 15.8511C7.71648 15.7581 7.71648 15.6931 7.80944 15.879C7.75367 15.7303 7.75367 15.6931 7.71648 15.5908C7.72578 15.5536 7.9024 15.7488 7.80015 15.5071C7.84663 15.5536 7.9117 15.7117 7.93959 15.7024C7.921 15.6466 7.84663 15.5536 7.80944 15.4793C7.76296 15.3491 7.80944 15.377 7.89311 15.3956C7.93959 15.4607 8.19988 15.2747 8.27425 15.1353C8.47876 14.4753 9.01793 14.057 9.39907 13.6015L9.46415 13.6665C9.35259 13.2761 10.0405 13.5829 9.78021 13.1088C9.87317 13.1366 9.93825 13.0158 10.0312 13.1645C9.96614 12.8857 10.496 13.0251 10.4402 12.6532C10.4216 12.6532 10.4216 12.6811 10.4402 12.7276C10.7377 12.7183 10.6912 12.3837 10.9887 12.3558C10.998 12.4023 10.9887 12.4487 11.0445 12.5231C11.2304 12.5882 10.9329 12.0955 11.2676 12.3837C11.3048 12.3465 11.1467 12.1977 11.1281 12.2256C11.6115 12.0118 11.8161 11.4355 12.1321 11.0078C12.5876 10.9428 12.6434 11.5377 12.6434 11.0915C12.7178 11.138 12.5412 10.9521 12.6062 11.0171C12.6062 10.8498 13.071 11.2588 12.9688 11.0357C12.7643 10.8591 12.9037 10.887 12.8014 10.7661C13.0896 10.7383 13.2848 10.887 13.2848 10.6174L13.3685 10.729C13.257 10.292 13.5823 10.2827 13.4057 9.81794C14.2237 8.972 14.8838 8.03309 15.7111 7.24293C16.6221 6.56431 17.3193 5.69048 18.3419 5.13271C18.7881 5.24427 18.7974 5.21638 18.9183 4.9189C18.9462 4.97468 18.9462 4.99327 18.9926 5.02116C18.8067 4.77946 19.1321 4.86313 18.9647 4.62143C19.3273 4.38903 19.569 4.07296 19.8944 3.79408C19.8665 3.85915 19.9966 4.07296 20.0431 4.00789L19.978 3.80337L20.0431 3.85915C20.0524 3.78478 20.0059 3.63604 19.8944 3.59886C20.5544 2.69714 21.7722 2.47403 22.5437 1.73034C22.8226 1.66527 23.0178 1.34921 23.1945 1.1168C24.0776 0.902993 24.8492 0.689183 25.3047 -0.0545044C25.3047 -0.0545044 25.723 0.62411 25.5836 0.977361L25.5929 1.03314Z\" fill=\"#8F3A7E\"><\/path><path d=\"M1.7481 9.85501C1.62739 9.95715 1.59954 10.0778 1.38599 10.115C1.50669 10.0314 1.61811 9.91072 1.7481 9.85501Z\" fill=\"#8F3A7E\"><\/path><path d=\"M1.8506 12.8295C1.8506 12.8295 1.82275 12.8945 1.80418 12.9131C1.77632 12.8945 1.65562 12.9409 1.70204 12.8759C1.7299 12.8945 1.78561 12.8481 1.8506 12.8202V12.8295Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.16678 13.4147C2.05536 13.489 1.87895 13.4425 1.82324 13.3775L2.16678 13.4147Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.08289 14.2437C2.02718 14.3551 1.96219 14.383 1.92505 14.318C1.98076 14.2715 2.02718 14.2715 2.08289 14.2437Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.35372 14.0857C2.35372 14.0857 2.33511 14.188 2.28857 14.2625C2.38165 14.188 2.15827 14.216 2.35372 14.0857Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.84607 15.3857C2.84607 15.3857 3.00391 15.3857 2.90178 15.5064C2.96677 15.4135 2.66966 15.4878 2.84607 15.3857Z\" fill=\"#8F3A7E\"><\/path><path d=\"M3.39329 15.7397C3.39329 15.7397 3.384 15.7861 3.43043 15.7769C3.40257 15.8418 3.30044 15.879 3.27258 15.8604L3.39329 15.7397Z\" fill=\"#8F3A7E\"><\/path><path d=\"M11.9369 14.7541L11.9462 14.8467L11.8535 14.7448L11.9369 14.7541Z\" fill=\"#8F3A7E\"><\/path><path d=\"M15.4611 11.4917C15.4611 11.3803 15.5818 11.5567 15.6003 11.5659C15.5632 11.6124 15.5075 11.4267 15.4611 11.4917Z\" fill=\"#8F3A7E\"><\/path><path d=\"M16.957 9.2601L16.9477 9.27864L16.7716 9.06546L16.957 9.2601Z\" fill=\"#8F3A7E\"><\/path><path d=\"M26.4111 1.45928C26.4761 1.32929 26.2068 1.32001 26.4111 1.32001C26.4668 1.41286 26.5039 1.49642 26.4111 1.45928Z\" fill=\"#8F3A7E\"><\/path><path d=\"M1.08847 10.4673C1.92512 10.4673 1.62764 11.3319 2.27837 11.4713C2.33415 11.4992 1.95301 11.6851 2.10174 11.7316C2.81754 11.7967 2.97558 12.5682 2.97558 13.2747L2.86402 13.3119C2.86402 13.4514 3.23587 13.3305 3.26375 13.4514C3.20798 13.4979 3.1615 13.4886 3.09642 13.5629C3.29164 13.4514 3.30094 13.6652 3.45897 13.6094C3.42179 13.6931 3.27305 13.7953 3.23587 13.9069L3.47756 13.8046C4.06322 13.5908 3.70997 14.1765 4.1097 14.1858C4.05392 14.2137 4.00744 14.2229 3.97026 14.2694C4.50013 14.3624 4.75113 14.79 5.13227 15.0596C5.0486 15.0968 4.91846 15.1897 4.85338 15.2734C5.07649 15.1247 5.20664 15.1897 5.32749 15.2548C5.15086 15.4686 5.64355 15.2548 5.61566 15.4593L5.55989 15.4872C5.84807 15.3943 5.532 15.7103 5.84807 15.5616L5.72722 15.7475C6.05258 15.543 5.66214 15.9892 5.86666 15.9334L5.92244 15.8777C6.04328 15.8777 5.92244 16.0357 6.0154 16.0543L5.98751 16.0915C6.17343 16.1658 6.06188 16.361 6.28498 16.1658C6.14554 16.3703 6.10836 16.1193 5.90384 16.4168C6.4895 16.6492 6.74049 17.049 7.08445 17.458C7.08445 17.6532 7.11233 17.7369 7.10304 17.8949C7.14952 17.8577 7.25178 17.9879 7.30755 17.8112C7.29826 17.8112 7.30755 18.0529 7.33544 18.0994C7.40051 18.3504 7.4284 17.6997 7.48418 17.9786C7.45629 18.0715 7.4377 18.2017 7.44699 18.3783C7.52136 18.1087 7.59573 18.2482 7.6608 18.211C7.6608 18.2853 7.64221 18.3132 7.64221 18.462C7.69799 18.118 7.80024 18.7316 7.84673 18.527V18.7966C7.99546 19.2893 7.82813 18.276 7.9025 18.3783C7.9025 18.5084 7.92109 18.6107 7.93039 18.7408C7.93039 18.3597 7.93969 18.2017 7.96757 18.0715C7.98617 17.9693 8.01406 17.8949 8.02335 17.7648C8.02335 17.8019 8.04194 17.8763 8.04194 17.8763C8.07913 17.6904 8.17209 17.6904 8.19068 17.3743C8.24646 17.4208 8.33942 17.9414 8.39519 17.7183C8.23716 17.2628 8.46027 17.3 8.23716 16.9188C8.31153 16.8909 8.46956 16.8537 8.45097 16.6771C8.49745 16.8537 8.72056 17.0211 8.68337 17.1605C8.73915 17.207 8.79493 17.2535 8.86 17.3C8.94366 17.458 8.77633 17.3464 8.90648 17.5045C8.93437 17.4208 8.94366 17.1047 9.00874 17.1047C8.93437 16.8073 8.72985 16.4261 8.76704 16.2774C8.82282 16.4354 9.06451 16.5098 9.08311 16.5935C8.97155 16.3703 8.84141 16.1658 8.70197 15.9892C8.71126 15.9427 8.92507 16.1472 8.89718 16.0264C8.82281 15.9799 8.79493 15.9148 8.75774 15.8498C8.80422 15.8498 8.8507 15.5895 9.12959 15.7754C9.25043 15.8405 9.12959 15.8962 9.25973 15.9148C9.3248 15.8219 9.24114 15.7475 9.29692 15.6545L9.3341 15.6824C9.41776 15.6545 9.36199 15.4221 9.16677 15.3664C9.12029 15.4036 9.3341 15.4779 9.21325 15.4779C9.0924 15.3106 9.13888 15.1711 9.21325 15.0875C9.23184 15.1526 9.30621 15.2083 9.36199 15.2827C9.25043 14.9945 9.29692 14.8179 9.3341 14.6134C9.21325 14.5018 9.51073 14.8551 9.42706 14.8179C9.73383 14.7993 9.49213 14.2694 9.86398 14.3531C9.86398 14.3903 9.68735 14.2044 9.72454 14.2415C9.8082 14.1765 9.97553 14.3438 9.96623 14.2415C10.0685 14.3345 9.99412 14.1486 10.0127 14.0742C9.96623 13.9812 10.0778 14.1114 10.0406 14.1579C10.022 14.0091 10.1522 13.5815 10.4496 13.5629C10.3846 13.4979 10.3102 13.2283 10.3567 13.2004L10.4868 13.3677C10.6077 13.4235 10.5984 13.2376 10.7285 13.3584C10.6263 13.0981 10.5798 13.8139 10.5426 13.5629C10.6913 13.6652 10.4496 13.1725 10.6356 13.4049C10.7006 13.3305 10.6077 13.0888 10.8215 13.1632C10.775 13.1632 10.9609 13.4328 11.0167 13.3677C11.0911 13.2376 10.9795 13.2655 11.0167 13.1353V13.0238C10.868 12.8657 11.1282 12.9587 10.9237 12.8192C11.0539 12.9308 11.0074 12.5961 11.2305 12.8564L11.3978 13.0702C11.4257 13.0145 11.277 12.7913 11.2305 12.6705C11.2584 12.6798 11.3049 12.7077 11.3328 12.7449C11.0539 12.4381 11.4629 12.6705 11.3049 12.3823C11.5001 12.4009 11.5559 12.1685 11.779 12.308C11.7697 12.1499 11.7325 11.9733 11.8812 11.964C11.8905 12.0105 11.8812 12.0384 11.9277 12.1034C12.0671 12.1406 12.0021 12.0477 12.0021 11.9547C12.03 12.0105 12.2717 12.0384 12.4297 12.0848C12.4204 11.9268 12.2438 11.7874 12.1601 11.6758C12.5041 11.9175 12.188 11.2947 12.5227 11.4899C12.532 11.555 12.5505 11.7316 12.6807 11.7595C13.0246 12.0012 12.6156 11.4155 12.8573 11.462L12.597 11.2389C12.7829 11.3505 12.6249 10.9507 12.848 11.211C12.8015 11.0902 13.0525 11.1738 12.8201 10.9414C13.1827 10.9879 13.1455 10.4208 13.6475 10.7555C13.6382 10.6904 13.7404 10.6718 13.6103 10.5603C13.443 10.458 13.6382 10.709 13.5359 10.6347C13.5545 10.6068 13.4987 10.5324 13.4709 10.4952C13.5731 10.4952 13.6382 10.4766 13.7683 10.7276C14.0286 10.7648 13.5173 10.1977 13.7683 10.1513C13.852 10.2628 13.8985 10.2907 13.9357 10.2256L13.8706 9.97463C14.01 9.91886 14.1402 10.1513 14.2982 10.3279C14.3261 10.2535 14.4005 10.1977 14.3075 10.049L14.5678 10.207C14.3819 10.0955 14.5213 10.0583 14.5027 9.99323V10.0583C14.5864 10.1234 14.6143 10.0211 14.6236 9.97463C14.5213 9.87238 14.4191 9.89097 14.354 9.89097C14.3168 9.78871 14.3726 9.77012 14.3261 9.64927C14.4655 9.8259 14.5213 9.68646 14.5864 9.66786C14.6701 9.66786 14.5027 9.46335 14.5306 9.45405C14.6143 9.53772 14.6236 9.39828 14.6979 9.55631C14.6979 9.60279 14.5864 9.50983 14.6236 9.61209C14.7165 9.64927 14.8467 9.8073 14.8188 9.63068C14.7909 9.50053 14.5027 9.30532 14.6979 9.32391C14.7072 9.38898 14.763 9.46335 14.8002 9.53772H14.9675L14.8374 9.38898C14.8839 9.41687 14.8839 9.43546 14.9118 9.45405C14.7909 9.26813 15.0047 9.27743 14.8653 9.08221C14.8932 9.02643 15.0605 9.1008 15.1163 9.08221V9.1008C15.2557 9.14728 15.2743 9.01714 15.2278 8.8777L15.2557 8.91488C15.2557 8.91488 15.3487 8.81262 15.3022 8.69177C15.4788 8.73826 15.8414 9.25884 15.7577 8.98925C15.8321 8.91488 15.6276 8.59881 15.5067 8.52444C15.7391 8.50585 15.6647 8.11542 16.0087 8.24556C15.9715 8.1619 15.925 8.13401 15.9343 8.06894C16.1853 7.95738 16.1946 7.51117 16.6222 7.6785C16.6222 7.79935 16.7524 7.83653 16.836 7.92949C16.7617 7.74357 17.022 8.02246 16.836 7.77146C16.7059 7.63202 16.6501 7.55765 16.5479 7.55765C16.6036 7.38103 16.7803 7.22299 16.9662 7.29736C16.8732 7.26018 16.8639 7.1951 16.8546 7.13003C17.0406 7.36243 17.1614 7.31595 17.1614 7.18581L17.0499 7.03707L17.2172 7.13933C17.2079 7.07425 16.9941 6.82326 17.18 6.89763C17.2265 6.94411 17.2823 6.99989 17.3287 7.02777C17.3008 6.85115 17.2358 6.58156 17.4124 6.62804L17.6448 6.77678C17.6541 6.7303 17.6076 6.56297 17.5054 6.55367C17.7378 6.56297 17.8307 6.50719 18.0259 6.64664C17.8772 6.03309 18.1933 5.73562 18.4722 5.5497L18.5558 5.66125C18.7046 5.69843 18.435 5.44744 18.5558 5.47533C18.6209 5.59618 18.7882 5.64266 18.844 5.80999C19.0392 5.83788 18.8161 5.52181 18.844 5.41955C18.7417 5.27081 18.8626 5.5497 18.7324 5.36377C18.7046 5.308 18.9648 5.35448 18.7975 5.13137C18.8905 5.18715 19.002 5.35448 19.0578 5.45674L19.0299 5.308C19.3088 5.48462 19.2251 5.88436 19.5598 6.10746L19.5877 6.0238C19.8201 6.19113 19.6435 6.39564 19.848 6.34916C19.8201 6.20042 19.6156 5.85647 19.4854 5.80999C19.5598 5.64266 19.1229 5.27081 19.2809 5.16856C19.4204 5.26152 19.1972 5.28941 19.3646 5.43814C19.5691 5.5497 19.4111 5.23363 19.5226 5.24293C19.3925 5.21504 19.2716 4.96404 19.2809 4.88967C19.4297 4.92686 19.4018 5.12208 19.5133 5.057C19.4297 4.92686 19.4389 4.75953 19.2902 4.74094C19.095 4.44346 19.4575 4.73164 19.3367 4.47135C19.5319 4.62938 19.6063 4.99193 19.8015 5.00123C19.6249 4.8339 19.7271 4.63868 19.4389 4.41557C19.5226 4.43417 19.6528 4.57361 19.7178 4.71305C19.8759 4.77812 19.5784 4.25754 19.913 4.6015L19.7736 4.39698C19.848 4.44346 19.913 4.46205 20.0246 4.53642C20.0804 4.48994 19.9781 4.13669 20.2198 4.42487C20.2198 4.37839 20.3407 4.29472 20.1362 4.13669C19.9595 4.08091 20.1733 4.3505 19.9038 4.12739C20.1362 4.29472 19.9874 4.00655 19.9688 3.89499L20.0711 3.99725C20.0618 3.93218 20.1455 3.90429 20.0618 3.77414C20.099 3.85781 20.164 3.92288 20.2105 3.93218L20.099 3.74626C20.1362 3.56963 20.3686 4.01584 20.4336 3.8857L20.4615 4.08091C20.4615 4.08091 20.6196 4.16458 20.6288 4.07162C20.5266 3.90429 20.3964 3.69048 20.3221 3.56033C20.3221 3.44878 20.4894 3.70907 20.415 3.50456L20.4987 3.75555C20.5266 3.81133 20.759 3.96007 20.8334 3.89499C20.8334 3.80203 20.7311 3.51385 20.5824 3.49526C20.6196 3.45808 20.7497 3.50456 20.8148 3.644C20.8612 3.51385 20.666 3.48596 20.666 3.32793C20.7869 3.4023 21.0007 3.46737 21.1866 3.56033L21.3168 3.8857L21.3725 3.83922C21.4748 4.09951 21.5399 3.96936 21.6793 4.21106C21.7444 4.21106 21.7258 4.1088 21.7165 4.01584C21.3168 3.76485 21.4376 3.44878 21.1401 3.1606C21.2145 2.95609 21.8745 3.84851 21.6142 3.22567C21.5213 3.1606 21.3911 2.86313 21.3725 3.03046C21.4934 2.99327 21.168 2.66791 21.3818 2.70509C21.4097 2.90031 21.7351 2.95609 21.7816 3.23497C21.6979 3.12342 21.6514 3.20708 21.6607 3.25356C21.8002 3.34652 21.921 3.57893 22.014 3.49526C22.0419 3.42089 22.1162 3.34652 21.9675 3.18849C21.8095 3.01186 21.8931 3.28145 21.7816 3.06764C21.8373 2.90961 22.0883 3.1699 21.8652 2.80735C21.8187 2.89101 21.6421 2.72369 21.5399 2.59354L21.5585 2.4448L21.6421 2.57495C21.8466 2.54706 21.5027 2.32395 21.6514 2.24958L21.9117 2.43551C22.0511 2.66791 21.6514 2.50058 21.9489 2.81665C22.0419 2.76087 21.9303 2.56565 22.079 2.58424C22.079 2.63072 22.0697 2.65861 22.079 2.6958C22.1162 2.6772 22.516 3.09553 22.423 2.74228C22.4044 2.59354 22.3393 2.61213 22.2371 2.48199C22.3393 2.33325 22.2743 2.17522 22.3393 2.08226C22.5253 2.34255 22.5067 1.98 22.6275 2.30536C22.4602 2.2031 22.2836 2.37973 22.4323 2.64932C22.7205 2.89101 22.2928 2.6958 22.5067 3.01186C22.6182 2.9282 22.8506 3.21638 23.0272 3.38371C23.0644 3.37441 23.0272 3.27215 23.0272 3.22567C22.8971 3.03975 22.8599 3.07694 22.7019 2.90031C22.8599 2.84453 22.8971 2.64932 22.8227 2.42621C22.9343 2.48199 23.0644 2.66791 23.0365 2.72369C23.1388 2.55636 23.3061 2.4448 23.4827 2.38903C23.1574 2.17522 23.5757 2.19381 23.3247 2.00789C23.1946 2.00789 22.9715 1.84985 22.8971 1.69182C22.9622 1.67323 22.9994 1.82196 23.0737 1.85915C22.9994 1.65464 23.3712 2.03577 23.2225 1.7383C23.1667 1.94281 23.4827 2.11014 23.6501 2.35184C23.6408 2.14733 23.7802 2.50988 23.8732 2.43551C23.8639 2.23099 23.8918 2.03577 23.9568 1.90563C24.2636 2.00789 24.2915 1.63604 24.4031 1.52449C24.5611 1.58956 24.7284 1.87774 24.8307 1.85915C24.905 1.78478 24.5425 1.63604 24.7563 1.65464L24.7842 1.71041C24.7656 1.62675 25.1375 1.71041 24.8679 1.31068L25.0631 1.61745C25.0631 1.61745 25.0724 1.54308 25.0631 1.5059C25.1374 1.58956 25.2304 1.65464 25.2397 1.7383C25.4721 1.86845 25.3606 1.58027 25.4349 1.51519L25.249 1.39434C25.2769 1.15265 25.5 1.24561 25.5744 1.07828L25.7045 1.23631V1.07828C25.8068 1.24561 25.9648 1.29209 25.8997 1.12476L26.0299 1.67323C25.8997 1.62675 25.9276 1.43153 25.7696 1.30138C25.6301 1.18983 25.5465 1.32927 25.6487 1.4966C25.7045 1.47801 25.6859 1.44083 25.6673 1.35716C25.8625 1.56167 25.7882 1.61745 25.8811 1.78478C25.8997 1.75689 25.9834 1.79408 25.9369 1.71971C25.9834 1.86845 25.9462 1.92422 25.8718 1.98929C25.8532 1.85915 25.7324 1.87774 25.6952 1.79408C25.8532 1.98929 25.8254 2.11014 25.6859 2.13803C25.4349 1.9707 25.6301 2.43551 25.4628 2.46339C25.342 2.23099 25.2676 2.02648 25.2676 1.88704C25.1189 1.84985 25.1932 1.96141 25.0445 1.91493C25.1375 2.09155 25.2955 2.33325 25.2769 2.50058L25.1467 2.36114C25.1282 2.50058 25.3048 2.71439 25.1653 2.77017C24.9236 2.84453 24.7377 3.00257 24.589 3.09553L24.4588 2.95609C24.6448 3.32793 24.3008 3.28145 24.3101 3.50456C24.0219 3.50456 24.0498 3.96007 23.7523 3.78344C23.5385 4.15528 23.3619 4.48994 22.9994 4.70375L22.8785 4.45276C22.9529 4.65727 22.7391 4.3598 22.7112 4.44346C22.9157 4.55502 22.8134 4.72234 22.8878 4.88967C22.6089 4.84319 22.581 5.17785 22.5717 5.42885L22.4416 5.28941C22.5438 5.67055 22.1906 5.55899 21.9954 5.64266C21.9303 5.59618 21.7816 5.48462 21.7537 5.5404C21.8652 5.84717 21.8095 5.86576 21.8002 6.11676C21.7072 6.19113 21.512 6.2655 21.3446 6.2469C21.2796 6.86974 20.7497 6.95341 20.5638 7.4554L20.3964 7.30666C20.3593 7.95738 19.6528 7.99457 19.5226 8.44078L19.2995 8.12471C19.1322 8.12471 19.1508 8.385 19.3553 8.56163C19.188 8.56163 19.2437 8.89629 18.9834 8.71037C18.844 8.73825 18.9834 8.94277 18.937 9.04503C18.6581 9.1008 18.6023 9.18447 18.4722 9.38898L18.5279 9.37039C18.4907 9.28672 18.3885 9.16588 18.3327 9.18447C18.3327 9.32391 18.0259 9.31461 18.3885 9.60279C18.0259 9.56561 18.091 10.1513 17.6727 10.0397C17.7657 10.1234 17.7378 10.1791 17.7749 10.2535C17.6169 10.4023 17.273 10.3651 17.2823 10.644C17.2172 10.6161 17.1893 10.4487 17.1056 10.4952C17.1056 10.5696 17.2079 10.6161 17.2079 10.709C17.0963 11.1181 16.5107 11.0065 16.3062 11.2668C16.0366 11.8246 15.5067 12.1406 15.1349 12.5404L15.0791 12.466C15.172 12.8471 14.5213 12.4939 14.763 12.9773C14.6701 12.9401 14.6143 13.0609 14.5213 12.9122C14.5771 13.1911 14.0658 13.0238 14.1123 13.3956C14.1309 13.3956 14.1309 13.3677 14.1123 13.3212C13.8148 13.3212 13.8706 13.6466 13.5731 13.6745C13.5638 13.628 13.5731 13.5815 13.5173 13.5071C13.3314 13.4421 13.6289 13.9255 13.2942 13.6373C13.257 13.6745 13.4151 13.8232 13.4337 13.7953C12.9503 14.0091 12.7551 14.5762 12.4669 14.9945C12.03 15.0596 11.937 14.4832 11.9649 14.9109C11.8905 14.8644 12.0671 15.041 12.0021 14.9759C12.0021 15.134 11.5373 14.7528 11.6488 14.9666C11.8626 15.134 11.7232 15.1061 11.8347 15.2269C11.5559 15.2548 11.3514 15.1247 11.3792 15.385L11.2863 15.2734C11.435 15.6917 11.1282 15.7196 11.3606 16.1472C11.2026 16.361 11.0539 16.5749 10.9237 16.7887L10.4403 17.6625C9.91975 18.5456 9.60369 20.0423 9.12029 21.4367C8.99014 21.7993 8.8507 22.1618 8.72056 22.5151L8.33942 22.0874L7.89321 21.5762L7.00078 20.5536C6.41513 19.8657 5.80159 19.1127 5.281 18.3225C5.20664 17.6439 5.20664 17.6625 4.77902 17.3743C4.83479 17.3464 4.86268 17.365 4.89057 17.3C4.76972 17.3929 4.70465 17.3185 4.64887 17.2628C4.61169 17.2256 4.5745 17.1791 4.45365 17.2628C4.23055 16.9002 3.92378 16.6399 3.64489 16.296C3.70997 16.3332 3.93307 16.203 3.868 16.1472L3.66349 16.203L3.71926 16.1379C3.64489 16.1193 3.49616 16.1658 3.44968 16.2774C2.55725 15.5709 2.37133 14.3345 1.66483 13.5071C1.60905 13.219 1.30228 12.9959 1.08847 12.8006C0.930435 11.8617 0.790994 11.0902 0.0751953 10.4116C0.0751953 10.4116 0.828178 10.1513 1.16284 10.3558L1.08847 10.4673Z\" fill=\"#8F3A7E\"><\/path><path d=\"M26.3094 1.58132C26.1885 1.47901 26.0676 1.47901 25.9932 1.27438C26.0955 1.3767 26.235 1.46971 26.3094 1.58132Z\" fill=\"#8F3A7E\"><\/path><path d=\"M23.3623 1.9979C23.3623 1.9979 23.2973 1.97005 23.2695 1.96076C23.288 1.93291 23.223 1.8122 23.2973 1.85863C23.2787 1.88648 23.3345 1.94219 23.3623 1.9979Z\" fill=\"#8F3A7E\"><\/path><path d=\"M22.8039 2.34232C22.7203 2.2309 22.7574 2.06377 22.8131 1.99878V2.34232H22.8039Z\" fill=\"#8F3A7E\"><\/path><path d=\"M21.9853 2.29645C21.8739 2.24074 21.846 2.18504 21.9018 2.13861C21.9482 2.19432 21.9575 2.23146 21.9853 2.29645Z\" fill=\"#8F3A7E\"><\/path><path d=\"M22.1544 2.56585C22.1544 2.56585 22.052 2.55654 21.9775 2.51001C22.052 2.59377 22.0241 2.37971 22.1544 2.56585Z\" fill=\"#8F3A7E\"><\/path><path d=\"M20.8979 3.10465C20.8979 3.10465 20.8979 3.26249 20.7772 3.16965C20.8701 3.22535 20.7772 2.93752 20.8979 3.10465Z\" fill=\"#8F3A7E\"><\/path><path d=\"M20.5632 3.65382C20.5632 3.65382 20.5168 3.65382 20.5261 3.69096C20.4611 3.6631 20.424 3.57025 20.4425 3.53311L20.5632 3.65382Z\" fill=\"#8F3A7E\"><\/path><path d=\"M12.5693 11.3684V11.275L12.6534 11.3871L12.5693 11.3684Z\" fill=\"#8F3A7E\"><\/path><path d=\"M9.03711 14.8652C9.05568 14.9767 8.90712 14.8188 8.88855 14.8188C8.9164 14.7631 8.99997 14.9488 9.03711 14.8652Z\" fill=\"#8F3A7E\"><\/path><path d=\"M8.21887 17.2635V17.2357L8.33029 17.5885L8.21887 17.2635Z\" fill=\"#8F3A7E\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">2290 Penalty Prevention<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-e08e27f e-con-full e-flex e-con e-child\" data-id=\"e08e27f\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0863b75 elementor-align-left elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"0863b75\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"27\" height=\"23\" viewBox=\"0 0 27 23\" fill=\"none\"><path d=\"M26.5504 1.48711C26.5133 1.41296 26.3928 1.2832 26.3743 1.33881L26.5411 1.59833V1.48711H26.5504Z\" fill=\"#8F3A7E\"><\/path><path d=\"M25.9092 1.28207C25.9556 1.43991 26.067 1.68132 26.2806 1.8763C26.1413 1.60704 26.2342 1.69061 26.0577 1.3842C26.0763 1.31921 26.197 1.40277 26.262 1.49562C26.2249 1.42134 26.3734 1.49562 26.262 1.32849C26.0577 1.18922 25.9835 1.23565 26.0392 1.4492C25.9835 1.41206 25.9463 1.33778 25.9092 1.29136V1.28207Z\" fill=\"#8F3A7E\"><\/path><path d=\"M19.0215 6.23586C19.0215 6.23586 19.0215 6.18064 19.0031 6.16223C19.0031 6.18984 19.0031 6.21746 19.0215 6.23586Z\" fill=\"#8F3A7E\"><\/path><path d=\"M18.3794 6.34023C18.3794 6.34023 18.4077 6.34023 18.4171 6.34023C18.3888 6.3308 18.37 6.32138 18.3794 6.34023Z\" fill=\"#8F3A7E\"><\/path><path d=\"M21.5952 4.26723L21.465 4.24863C21.5208 4.33234 21.5487 4.27653 21.5952 4.26723Z\" fill=\"#8F3A7E\"><\/path><path d=\"M25.8363 2.31298C25.8363 2.31298 25.8363 2.25752 25.8178 2.22055C25.8178 2.23904 25.8178 2.25752 25.8086 2.27601L25.8363 2.31298Z\" fill=\"#8F3A7E\"><\/path><path d=\"M22.5358 3.16046L22.5544 3.14186C22.5544 3.14186 22.5172 3.07675 22.4893 3.03024L22.5358 3.16046Z\" fill=\"#8F3A7E\"><\/path><path d=\"M23.3447 2.4166C23.3447 2.4166 23.4749 2.63052 23.5493 2.72353C23.4935 2.63052 23.4749 2.58401 23.4749 2.54681C23.447 2.50961 23.4005 2.4631 23.3447 2.4166Z\" fill=\"#8F3A7E\"><\/path><path d=\"M21.8932 3.61673C21.8932 3.61673 21.8372 3.56072 21.8279 3.55139C21.8465 3.57939 21.8745 3.59806 21.8932 3.61673Z\" fill=\"#8F3A7E\"><\/path><path d=\"M0.799326 11.6575C0.799326 11.6575 0.827596 11.6386 0.837019 11.6292C0.808749 11.6292 0.789903 11.648 0.799326 11.6575Z\" fill=\"#8F3A7E\"><\/path><path d=\"M1.21851 9.87102L1.24636 9.8803L1.37635 9.81531L1.21851 9.87102Z\" fill=\"#8F3A7E\"><\/path><path d=\"M10.5801 13.1525C10.8215 13.2453 10.6636 13.4868 10.9608 13.561C10.8772 13.496 10.7843 13.1711 10.5801 13.1525Z\" fill=\"#8F3A7E\"><\/path><path d=\"M25.7896 2.30579C25.7896 2.30579 25.7708 2.32463 25.752 2.33406C25.7708 2.33406 25.7802 2.31521 25.7896 2.30579Z\" fill=\"#8F3A7E\"><\/path><path d=\"M15.7295 8.4028C15.7295 8.4028 15.7942 8.45826 15.8219 8.47674C15.8034 8.45826 15.7757 8.43977 15.7295 8.4028Z\" fill=\"#8F3A7E\"><\/path><path d=\"M15.2939 9.27798C15.2939 9.27798 15.2285 9.25931 15.2285 9.30598C15.2378 9.30598 15.2472 9.31531 15.2565 9.32465C15.2378 9.28731 15.2379 9.26865 15.2939 9.27798Z\" fill=\"#8F3A7E\"><\/path><path d=\"M14.5957 9.90973C14.5957 9.90973 14.6241 9.92869 14.6431 9.93817V9.90973H14.5957Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.6049 13.9609C2.65136 13.8959 2.7071 13.8401 2.76285 13.7844C2.62348 13.9051 2.48412 13.8401 2.6049 13.9609Z\" fill=\"#8F3A7E\"><\/path><path d=\"M25.7432 2.19324C25.7802 2.24883 25.7988 2.27662 25.7895 2.29515L25.808 2.26736C25.808 2.26736 25.7617 2.21177 25.7432 2.19324Z\" fill=\"#8F3A7E\"><\/path><path d=\"M16.6315 10.8466L16.4922 10.9116C16.5386 10.9116 16.585 10.8745 16.6315 10.8466Z\" fill=\"#8F3A7E\"><\/path><path d=\"M7.79133 20.2916H7.76367C7.76367 20.2916 7.79133 20.3285 7.79133 20.2916Z\" fill=\"#8F3A7E\"><\/path><path d=\"M16.1947 11.2389C16.1111 11.1924 16.0554 11.1645 16.0089 11.1552C16.0089 11.1738 16.0275 11.1924 16.0368 11.2203L16.1854 11.2389H16.1947Z\" fill=\"#8F3A7E\"><\/path><path d=\"M1.95357 13.227C1.75835 13.1898 1.98146 13.1526 2.08371 12.9109C1.81413 13.0132 2.08371 12.7343 1.70258 12.9946C1.91639 12.7808 1.83272 12.8551 1.96287 12.6599C1.78624 12.8366 1.66539 12.6599 1.42369 12.8458C1.67469 12.6227 1.85131 12.725 2.06512 12.4275C1.83272 12.4926 1.68398 12.4275 1.37721 12.6227C1.4051 12.5205 1.49806 12.4275 1.47947 12.3253C1.47017 12.3532 1.53525 12.3253 1.57243 12.316C1.27496 12.316 1.33073 11.972 0.912408 12.1393C1.36792 11.8698 0.76367 11.7954 1.23777 11.6281C1.18199 11.5816 0.931 11.6095 0.838039 11.6374C1.18199 11.4143 0.828743 11.4328 0.986776 11.2283C0.772966 11.3213 0.76367 11.1633 0.614933 11.1726C0.680005 11.1726 0.745078 11.154 0.828743 11.0889C0.642821 11.0982 0.782262 11.0331 0.912408 10.8658C0.745078 10.8286 0.661413 11.0517 0.456899 11.0889C0.475491 10.9494 0.670709 10.9401 0.800854 10.8379L0.363938 10.9216C0.38253 10.8751 0.438307 10.81 0.531268 10.7449C0.401123 10.7542 0.224497 10.8007 0.354642 10.6334L0.438307 10.7449L0.59634 10.5962H0.280273C0.429011 10.2244 0.856631 10.0849 1.24707 9.88969L1.35862 9.92688C1.48877 9.85251 1.53525 9.75955 1.51665 9.72236C1.59102 9.64799 2.00005 9.61081 2.08371 9.65729C2.17668 9.8804 1.67469 9.95476 1.66539 10.1593L2.00005 10.2151L1.8792 10.2987C1.81413 10.3824 1.96287 10.3173 2.00005 10.2987C1.80483 10.401 2.03723 10.4939 2.05583 10.5869L2.19527 10.4568C2.70655 10.4196 2.01864 11.0517 2.33471 11.0982L2.67866 11.0331L2.46485 11.219C2.65078 11.1911 2.8367 11.0796 2.8367 11.2469C2.70655 11.9255 3.50602 11.9999 3.5525 12.5763C3.59898 12.5391 3.59898 12.5112 3.61757 12.4647C3.3108 13.2363 4.59366 12.567 4.39844 13.2084L4.29618 13.2549C4.46351 13.3757 4.19393 13.3014 4.15674 13.5059C4.44492 13.3199 4.51929 13.5431 4.68662 13.5616C4.62155 13.5895 4.60295 13.5616 4.53788 13.5616C4.4914 13.6267 4.33337 13.7569 4.41703 13.7662C4.88184 13.5709 5.01198 13.8126 5.24438 13.8777C5.08635 14.0357 5.03058 14.296 4.80747 14.5935C4.88184 14.5563 5.03987 14.482 5.1979 14.4076C5.13283 14.5563 5.25368 14.5284 5.38383 14.4913C5.33735 14.4448 5.30016 14.3983 5.27227 14.3704H5.29087C5.29087 14.3704 5.26298 14.3611 5.25368 14.3518C5.2165 14.3239 5.1979 14.3146 5.18861 14.3332C5.30946 14.138 5.32805 14.231 5.53256 14.0636C5.56975 14.1194 5.71849 14.1752 5.57904 14.3053C5.59764 14.3425 5.59764 14.3797 5.57904 14.4355C5.62552 14.4355 5.66271 14.4355 5.66271 14.4727H5.63482C5.63482 14.4727 5.59764 14.5284 5.57904 14.547C5.57904 14.7144 5.98807 14.6121 6.20188 14.5842C5.87652 14.7051 5.9323 14.8352 5.73708 14.9839C5.75567 14.9839 5.6906 14.8724 5.58834 14.7423C5.57904 14.7701 5.55116 14.798 5.48608 14.8538C5.37453 15.1234 5.81145 14.9003 5.80215 15.1792C5.77426 15.1792 5.70919 15.1978 5.65341 15.2628C5.65341 15.3651 5.83933 15.3 5.96018 15.2164C5.79285 15.3744 5.75567 15.6068 5.88582 15.5975C6.08103 15.5324 6.14611 15.4673 6.20188 15.5789L6.03455 15.644C6.01596 15.8485 6.29484 15.5882 6.26695 15.7648C6.28555 15.6905 6.14611 15.7927 6.14611 15.8392C6.31344 15.895 6.3971 15.8578 6.70387 15.709L6.49936 15.8671C6.67598 15.8485 6.97346 15.6997 6.73176 15.9693C7.08501 15.551 7.00135 15.8485 7.03853 15.9043C7.01994 15.9043 6.95487 15.9972 6.91768 16.053C7.18727 15.8113 7.05712 16.211 7.15938 16.3133L7.03853 16.7874C7.1036 16.8432 7.3453 15.9136 7.36389 15.96L7.30812 16.1831C7.38249 16.1831 7.40108 16.2482 7.44756 16.4063L7.41967 16.7874C7.45685 16.6387 7.48474 16.6758 7.50333 16.5085C7.52193 17.0291 7.587 16.9826 7.63348 16.9175C7.66137 16.8804 7.67996 16.8711 7.70785 16.9175C7.72644 16.9175 7.75433 17.0012 7.81011 17.2522L7.69855 16.4248C7.69855 16.4248 7.69855 16.4063 7.69855 16.397C7.70785 16.3505 7.71714 16.3226 7.81011 16.7409C7.91236 17.3173 7.83799 16.6944 7.87518 16.7874C7.87518 16.6944 7.80081 16.3319 7.77292 16.2482C7.91236 16.462 7.88447 15.9972 8.16336 16.3784C8.18195 16.0437 7.96814 15.6626 8.0611 15.6161L8.10758 15.6533C8.10758 15.6533 8.20054 15.6626 8.2935 15.6905C8.40506 15.6905 8.55379 15.7183 8.72112 15.8392C8.79549 15.5882 8.44224 15.1048 8.78619 14.9932L8.86986 15.142C8.98141 15.142 8.90704 14.9189 8.88845 14.8631C8.91634 14.8445 8.96282 14.9189 9.00001 14.9561C9.14874 14.9932 9.0093 14.8166 9.0186 14.7515L9.11156 14.8631C9.47411 14.8631 9.30678 14.231 9.56707 14.0543C9.56707 14.1194 9.68792 14.2031 9.75299 14.2403C9.50199 13.8405 9.81806 13.6639 9.83665 13.5059L9.91102 13.6825C9.87384 13.3014 10.3944 13.8684 10.3572 13.4873L10.0784 13.3943C10.1992 13.3757 10.1992 13.2642 10.0412 13.134C10.2271 13.1619 10.2922 13.3757 10.4502 13.2828C10.5432 13.3664 10.4223 13.4315 10.5803 13.5059L10.9801 13.5895C10.9801 13.5895 11.0358 13.5895 11.0637 13.5152C10.6547 13.1154 11.1846 13.3571 10.7105 13.0411C10.9243 12.7808 11.3798 12.8644 11.4077 12.4833C11.8725 12.8087 11.826 12.1208 12.2908 12.6599C12.4117 12.5577 12.4117 12.3625 12.2908 12.0929C12.2257 12.0743 12.2629 12.1672 12.2629 12.2137C12.17 12.0557 12.2908 11.8976 12.3466 11.8512C12.3838 12.0371 12.3466 12.2602 12.4767 12.5112C12.5325 12.3625 12.5046 12.0278 12.4953 11.9162L12.7742 12.1579C12.6813 11.8791 13.0531 12.3067 12.8951 11.9627L12.8021 11.8976C12.9787 11.7675 12.737 11.4979 12.8579 11.3213L12.9508 11.4328C13.0438 11.4328 12.8858 11.1075 13.1647 11.3027L13.0717 11.405C13.2576 11.5816 13.4064 11.6002 13.5272 11.6652C13.583 11.5165 13.2855 11.3213 13.3134 11.2469C13.4993 11.405 13.4064 11.3399 13.5272 11.5444C13.583 11.3771 13.6759 11.154 13.5551 10.8472C13.583 10.8751 13.6202 10.9123 13.6202 10.9123C13.7689 10.8286 13.5923 10.4103 13.7968 10.4939V10.5404C14.1314 10.717 13.8247 10.0663 14.2523 10.4939C14.3731 10.5311 14.1314 10.5683 14.401 10.7263C14.6706 10.7356 14.1593 10.2615 14.401 10.2708C14.3731 10.2708 14.401 10.2987 14.4289 10.3452C14.5126 10.2522 14.5963 10.0942 14.6613 9.95476C15.1168 10.2058 14.9681 9.51785 15.498 9.81532C15.3121 9.70377 15.3771 9.61081 15.3213 9.53644C15.3213 9.53644 15.3492 9.58292 15.3771 9.60151C15.4422 9.56433 15.3213 9.41559 15.2842 9.34122C15.4422 9.43418 15.3028 9.07164 15.4143 9.12741C15.3306 9.03445 15.3957 9.01586 15.4422 8.97867C15.4422 9.17389 15.5909 9.21108 15.6839 9.397C15.8698 9.32263 15.4794 8.82994 15.6839 8.77416L15.9256 8.88571C15.7025 8.59754 15.9349 8.58824 15.8419 8.48598C15.9442 8.55105 16.0279 8.56965 16.1394 8.70909C16.1394 8.58824 16.3532 8.65331 16.2324 8.46739L16.1115 8.4488C16.3904 8.39302 16.1487 7.90033 16.4555 7.95611L16.818 8.37443C17.0597 8.45809 16.7901 7.99329 17.0969 8.17921C16.9482 8.06766 16.9761 8.11414 16.9203 7.91892C16.8552 7.91892 16.8831 8.08625 16.8273 8.13273L16.7436 7.77948L16.6507 8.06766C16.5949 7.83526 16.6228 7.87244 16.4462 7.74229C16.4462 7.5006 16.7529 7.82596 16.7251 7.56567C16.818 7.58426 16.9017 7.77018 17.0225 7.81666C16.9946 7.58426 17.478 7.94681 17.3572 7.65863C17.4223 7.67722 17.3293 7.70511 17.413 7.79807C17.4409 7.70511 17.5059 7.67722 17.413 7.53778H17.32C17.3758 7.50989 17.2363 7.33327 17.4223 7.35186C17.3944 7.21242 17.2456 6.98002 17.1899 7.0265C17.1899 6.98002 17.3386 7.04509 17.4316 7.18453C17.5803 7.06368 17.1155 6.68254 17.4316 6.75691C17.4316 6.7755 17.4316 6.81269 17.4687 6.83128C17.5338 6.83128 17.5617 6.80339 17.5617 6.75691C17.4687 6.90565 17.8871 7.05438 17.6733 7.11016C17.8778 7.31467 17.822 7.05438 17.9428 7.11016C17.8871 6.89635 17.6733 6.7848 17.6175 6.64536C17.6733 6.71972 17.7104 6.69184 17.7662 6.69184L17.5896 6.5524C17.5896 6.5524 17.6547 6.50591 17.6547 6.43155V6.5524C17.7476 6.52451 18.073 6.71043 18.0544 6.44084C18.0823 6.5338 18.1381 6.71973 18.2868 6.74761C18.324 6.5338 18.3798 6.79409 18.5564 6.85917C18.6493 6.71043 18.324 6.5431 18.5936 6.48732C18.6122 6.46873 18.5099 6.38507 18.4541 6.35718C18.6493 6.32929 18.6215 6.15266 18.8446 6.17126C18.7516 6.17126 18.6586 6.15266 18.6679 6.01322C18.7516 6.18055 18.8817 6.0597 19.0026 6.09689L18.9468 6.00393C19.0584 6.0597 19.0491 6.13407 19.0491 6.18985C19.0212 6.16196 18.9933 6.14337 18.9747 6.17126C18.9747 6.2921 19.2722 6.58958 19.393 6.5431C19.4302 6.37577 19.2164 6.16196 19.1327 6.09689C19.3466 6.069 18.9282 5.60419 19.1792 5.62279C19.2071 5.5949 19.5975 5.84589 19.7184 5.79941C19.6068 5.56701 19.4767 5.75293 19.393 5.54842C19.9601 5.89237 19.4674 4.97206 19.9229 5.08361L20.0995 5.3439C20.1646 5.31602 20.2204 5.29742 20.2576 5.22305L20.0809 5.15798C20.0809 5.06502 20.239 5.00924 20.3505 5.22305C20.2948 4.93488 20.4156 5.02784 20.5736 5.00924C20.4528 5.08361 20.5457 4.98136 20.5736 5.16728C20.7874 5.18587 20.7317 5.10221 20.7596 4.98136C20.8153 5.07432 20.9641 5.16728 21.0013 5.13939C20.9455 4.92558 21.1035 4.85121 21.1407 4.68388L21.1965 4.75825C21.2894 4.52585 21.7542 4.69318 21.7542 4.33993C21.7542 4.33993 21.7542 4.33063 21.7542 4.32133H21.7264C21.4754 4.14471 21.7264 4.05175 21.7078 3.91231C21.7635 3.95879 21.8565 4.05175 21.8844 4.02386C21.7078 3.81005 21.8565 3.85653 21.8007 3.73568C21.9216 3.75427 22.0052 3.99597 22.0982 3.89371C22.1261 3.83794 22.0331 3.72638 21.968 3.65202C22.0796 3.73568 22.219 3.77286 22.2934 3.74498C22.3213 3.81934 22.2283 3.77286 22.2283 3.79146C22.312 3.91231 22.3213 3.83794 22.4329 3.97738C22.4979 3.94949 22.2841 3.76357 22.405 3.79146L22.4886 4.00527C22.5444 4.02386 22.5165 3.9309 22.5258 3.91231C22.5258 3.98667 22.6746 4.14471 22.7582 4.23767C22.7954 3.99597 22.4143 3.76357 22.2655 3.57765C22.5072 3.59624 22.4236 3.28947 22.5165 3.19651L22.6653 3.41032C22.6931 3.33595 22.6746 3.27088 22.6281 3.17791L22.7024 3.11284C22.721 3.22439 22.7582 3.29876 22.8791 3.4568C22.9163 3.33595 23.0743 3.28947 22.8791 3.01058L22.9163 3.05707C23.1022 3.05707 23.3811 2.92692 23.4461 3.01988C23.4926 2.83396 23.7715 2.86185 23.5577 2.60156C23.5763 2.48071 24.0225 2.78748 23.7994 2.41564C24.0225 2.51789 23.8645 2.48071 23.9946 2.69452C24.2177 2.79677 23.9388 2.28549 24.2828 2.63874C24.2828 2.44352 24.1991 2.58296 24.0876 2.38775C24.3943 2.71311 24.3107 2.29479 24.571 2.41564C24.4966 2.23901 24.4594 2.35986 24.4036 2.15534C24.4687 2.24831 24.5245 2.22971 24.5431 2.22971L24.3757 1.99731L24.9149 2.45282C24.8405 2.08098 24.571 2.09957 24.6732 1.84857V1.87646C24.9149 2.06238 24.6732 1.59758 24.9428 1.66265C24.8591 1.66265 25.0079 1.7835 25.0451 1.85787V1.70913C25.0451 1.70913 25.0544 1.74632 25.0822 1.76491C25.2868 1.87646 25.0636 1.62547 25.2589 1.70913C25.2403 1.7928 25.3983 1.95083 25.482 2.00661L25.3797 1.67195L25.5842 2.00661C25.7051 1.94153 25.4727 1.33729 25.8631 1.69984L25.8445 1.7835C25.9096 1.84857 26.1234 2.04379 26.0676 1.82998C26.0676 1.7742 25.9282 1.58828 25.9096 1.62547L26.0211 1.65336C26.1513 1.86717 26.0676 2.0345 26.0304 2.15534C25.9933 2.05309 26.0026 1.94153 25.8817 1.82998C25.8631 1.95083 25.9003 2.14605 25.8817 2.2669C25.8445 2.16464 25.7609 2.0252 25.7051 1.94153C25.5377 1.90435 25.7609 2.12746 25.7051 2.19253C25.6214 2.13675 25.5563 2.09957 25.5192 2.0252C25.5192 2.16464 25.4634 2.23901 25.3053 2.20182C25.3053 2.20182 25.2775 1.98801 25.138 1.91365C25.0915 2.15534 25.2589 2.41564 25.2124 2.67593C25.3053 3.15003 24.6918 2.76889 24.7662 3.11284C24.8312 3.2058 24.9893 3.18721 24.9521 3.30806C24.822 3.12214 24.8127 3.23369 24.7476 3.16862C24.8684 3.49398 24.571 3.2244 24.6546 3.4475C24.6174 3.37313 24.5059 3.35454 24.4222 3.31736C24.2549 3.09425 24.2549 3.31736 24.1247 2.89903C24.2642 3.33595 23.818 3.01988 24.134 3.59624L24.2177 3.62413H23.9946L24.0039 3.63342C23.9202 3.64272 23.9574 3.70779 23.6878 3.54976C23.6785 3.46609 23.725 3.42891 23.7157 3.34524C23.4833 3.2151 23.6971 3.63342 23.6321 3.70779C23.5019 3.54976 23.6692 3.58694 23.4833 3.41032C23.4089 3.42891 23.4554 3.58694 23.4368 3.6799L23.3718 3.58694C23.065 3.50328 23.6785 4.06104 23.3253 3.85653C23.3718 3.90301 23.4089 3.96808 23.4554 4.01456C23.3439 3.95879 23.1208 3.87512 23.1208 3.6892C23.0743 3.72638 23.0836 3.85653 23.1394 3.96808C23.2881 4.06104 23.2416 3.98667 23.3996 4.13541L23.2788 4.38641C23.2788 4.38641 23.223 4.28415 23.2509 4.26556C22.6374 3.99597 23.1115 5.04643 22.3864 4.71177C22.5351 4.83262 22.47 4.85121 22.5258 4.97206C22.405 4.99995 22.312 5.13939 22.154 5.1208L22.0982 4.99995C21.9959 5.28813 21.9866 5.55771 21.81 5.60419C21.8379 5.65067 21.6892 5.46475 21.6892 5.41827C21.7449 5.67856 21.15 5.21376 21.4382 5.61349H21.5032C21.2615 5.71575 21.2708 6.16196 21.1221 6.37577C20.8897 6.18985 21.2151 6.25492 20.9455 6.02252C20.7317 6.05041 20.7503 6.35718 20.5457 6.41295C20.5457 6.36647 20.5179 6.33859 20.5179 6.31999C20.2483 6.3014 20.7224 6.5338 20.5736 6.59888C20.49 6.47803 20.4528 6.45943 20.3691 6.44084L20.4807 6.65465C20.4807 6.65465 20.3319 6.48732 20.3041 6.42225C20.4528 6.70113 20.146 6.68254 20.2948 6.94283C20.239 6.89635 20.0902 6.66395 19.9973 6.58958C19.8764 6.58958 19.9043 6.71043 19.9322 6.83128C19.7556 6.71043 19.6626 6.83128 19.6626 6.7848C19.4767 6.81269 19.7463 6.92424 19.7742 7.13805L19.9508 7.15664L19.83 7.35186L19.8021 7.18453C19.6533 7.16594 19.737 7.42623 19.644 7.5006L19.7928 7.59356L19.7556 7.76089C19.5232 7.50989 19.5697 7.81666 19.3651 7.46341C19.0584 7.4913 19.235 7.94681 19.077 8.11414C19.1049 8.08625 19.0491 8.04907 19.0212 7.99329C18.8725 8.02118 18.9282 8.2071 18.984 8.39302C18.9282 8.30006 18.9282 8.25358 18.8632 8.17921C18.7423 8.28147 18.9189 8.39302 18.8632 8.57894C18.8074 8.4395 18.7423 8.39302 18.6865 8.39302C18.7795 8.48598 18.8074 8.57894 18.8074 8.62542C18.4541 8.02118 18.4727 8.54176 18.1845 8.07695C18.2775 8.1978 18.2682 8.59754 18.5099 8.75557V8.6812C18.6401 8.82064 18.5471 8.81135 18.5099 8.84853C18.5099 8.81135 18.5006 8.75557 18.4727 8.72768C18.4355 9.06234 18.1009 9.07164 18.0079 9.37841C17.98 9.31333 17.98 9.146 17.8871 9.146C17.6175 9.24826 17.729 9.6294 17.6361 9.93617C17.3386 9.61081 17.822 9.69447 17.5524 9.36911C17.3944 9.6387 17.2735 9.94547 17.1806 10.3266C16.6693 9.91758 17.1155 10.7356 16.6321 10.4846C16.7901 10.6334 16.7622 10.7542 16.6879 10.8379C16.5949 10.6799 16.5112 10.7542 16.4462 10.6334C16.502 10.8472 16.3532 11.0889 16.0836 10.7635C16.3346 11.0796 15.9163 10.8844 16.0557 11.154C15.8605 11.1168 15.9163 11.3864 15.7304 11.3957C15.9442 11.5537 15.7025 11.5909 15.7304 11.7024C15.7304 11.6838 15.7304 11.6281 15.7025 11.6095C15.5166 11.47 15.7025 11.8698 15.5537 11.8326C15.4608 11.7861 15.405 11.6467 15.3399 11.6745C15.4608 11.814 15.4329 12.1208 15.2191 12.0092C15.247 11.9813 15.1912 11.9162 15.154 11.8419C15.0704 12.3439 14.494 12.3439 14.4382 12.9016L14.2802 12.6227C13.8247 12.5019 14.494 13.1061 14.3174 13.2177C13.8061 13.478 13.0903 13.5524 12.8207 14.0636C12.8486 14.1566 12.9137 14.1287 13.0066 14.2217C12.9508 14.2217 12.7649 14.045 12.8207 14.2124L12.9415 14.3239C12.4489 14.1659 12.6441 15.0304 12.0212 14.6493C12.0398 15.0025 11.6029 14.7887 11.6866 15.2721C11.5192 15.2349 11.5564 15.0025 11.4449 15.0583V15.4209V15.393C11.6401 15.9043 10.5896 15.4859 10.6547 15.96V15.9321C10.5617 15.8485 10.413 15.8113 10.413 15.8764C10.4595 15.9414 10.5153 15.9414 10.6082 15.9879C10.5803 16.3226 10.5525 16.3691 10.4409 16.555C10.3665 16.3784 10.2736 16.5271 10.0784 16.3877C10.162 16.5271 10.2922 16.5178 10.3201 16.6944C10.2178 16.8525 9.99469 16.8153 9.78088 16.9826C9.89243 17.1964 9.78088 17.2615 9.9668 17.4567C9.80877 17.7821 9.75299 18.0052 9.56707 18.4886L9.51129 18.4049C9.66003 18.879 9.251 18.6094 9.32537 18.9162C9.26959 18.7582 9.2603 18.6559 9.19522 18.5629L9.17663 18.8976C9.15804 18.6652 9.00001 18.2469 8.92564 18.3398C8.99071 18.7953 9.02789 18.4979 9.10226 18.8232L8.91634 18.47C8.88845 18.6187 9.05578 19.1486 9.16733 19.1021C8.99071 19.5483 8.86986 20.3013 8.69323 20.6546L8.62816 20.2362C8.58168 20.5709 8.47013 20.8963 8.37717 20.701C8.37717 20.6732 8.35857 20.6546 8.35857 20.636C8.37717 20.7568 8.37717 20.9706 8.41435 21.1101C8.35858 21.5842 8.31209 20.45 8.25632 20.9706C8.27491 20.8498 8.3028 20.7847 8.27491 20.5523C8.24702 20.6267 8.21913 20.6917 8.19125 20.7568C8.17265 20.7847 8.16336 20.8126 8.14477 20.8405H8.0704C8.03321 20.5802 7.8194 19.8272 7.70785 19.8923C7.70785 20.0224 7.75433 20.2455 7.78222 20.3106L7.69855 20.3292L7.62418 19.7157C7.587 19.8272 7.54982 19.9388 7.51263 20.041V19.6041C7.42897 19.6041 7.38249 20.0968 7.29882 19.9667C7.03853 19.3717 7.1036 19.3066 6.98275 18.7396C6.84331 19.4182 6.71317 18.3863 6.55513 18.8139C6.45288 18.0517 6.01596 17.9215 5.77426 17.4381H5.83004C5.87652 17.0756 5.42101 17.5869 5.34664 17.3173L5.4396 17.2987C5.45819 17.0849 5.32805 16.9175 5.18861 16.8432C5.05846 16.7688 4.87254 16.7409 4.71451 16.7409C4.80747 16.7223 4.92832 16.5922 4.87254 16.555C4.75169 16.5829 4.60295 16.8339 4.62155 16.6851C4.67732 16.6758 4.76099 16.5829 4.7424 16.555L4.46351 16.6387C4.43563 16.2947 4.37985 15.9136 4.07308 15.7834C4.11026 15.6812 4.22182 15.6533 4.29618 15.6068C4.11026 15.4581 3.7849 15.4209 3.61757 15.2814L3.84997 15.0676C3.7849 14.9839 3.43165 15.3186 3.57109 15.0397C3.58968 14.9932 3.64546 15.0955 3.7756 15.0397C3.84068 14.733 3.45954 15.1327 3.36658 14.9561L3.68264 14.7794C3.75701 14.5284 3.43165 14.7608 3.22713 14.8445C2.76233 14.9282 3.68264 14.3053 3.25502 14.2682C3.08769 14.3425 3.0598 14.4355 2.89247 14.5098C2.84599 14.2867 2.62289 14.4262 2.57641 14.2031C2.93896 13.794 2.64148 14.2867 2.96684 13.887V14.0822C3.10628 13.8033 3.09699 14.138 3.32939 13.9242C3.33869 13.7848 3.03192 13.8312 2.87388 13.7848C3.0598 13.6453 2.98544 13.887 3.20854 13.6453H3.08769C3.15277 13.6267 3.22713 13.5709 3.24573 13.6081C3.41306 13.4501 3.20854 13.5338 3.16206 13.4873C3.0598 13.5616 2.92036 13.6639 2.79951 13.7848C2.81811 13.7662 2.8367 13.7476 2.85529 13.7197C2.50204 13.8219 2.57641 13.4873 2.28823 13.5616C2.3533 13.5338 2.3626 13.5059 2.40908 13.4687C2.37189 13.3943 2.07442 13.5152 1.93498 13.4873C2.03723 13.3385 2.38119 13.1991 2.19527 13.1247C2.01864 13.2177 1.78624 13.4873 1.70258 13.3571C1.70258 13.3571 1.90709 13.3571 1.98146 13.227H1.95357ZM4.28689 15.5045C4.28689 15.5045 4.31478 15.5324 4.34266 15.551C4.34266 15.551 4.29618 15.5138 4.28689 15.5045ZM4.61225 15.5696C4.61225 15.5696 4.51929 15.5975 4.45422 15.6533C4.48211 15.6905 4.50999 15.7183 4.51929 15.7555C4.55647 15.6719 4.55647 15.5882 4.61225 15.5696ZM5.46749 14.2403L5.49538 14.2217C5.49538 14.2217 5.55116 14.2496 5.56975 14.2589C5.60693 14.2217 5.63482 14.1752 5.57904 14.1659C5.55116 14.1845 5.50468 14.2031 5.46749 14.231V14.2403Z\" fill=\"#8F3A7E\"><\/path><path d=\"M5.26323 14.3253C5.26323 14.3253 5.24482 14.3253 5.23562 14.3253C5.22642 14.3437 5.21721 14.3621 5.20801 14.3805L5.28164 14.3437L5.26323 14.3253Z\" fill=\"#8F3A7E\"><\/path><path d=\"M21.6523 4.27579C21.6523 4.27579 21.6712 4.27579 21.69 4.29463C21.6806 4.29463 21.6712 4.28521 21.6618 4.27579H21.6523Z\" fill=\"#8F3A7E\"><\/path><path d=\"M7.48508 20.1339L7.49435 20.032L7.46655 20.0876L7.48508 20.1339Z\" fill=\"#8F3A7E\"><\/path><path d=\"M23.4094 3.96896C23.4094 3.96896 23.4473 3.9974 23.4663 4.00688C23.4568 3.9974 23.4284 3.97844 23.4094 3.96896Z\" fill=\"#8F3A7E\"><\/path><path d=\"M24.4309 3.36418C24.4309 3.36418 24.3847 3.29949 24.3662 3.27176L24.4309 3.36418Z\" fill=\"#8F3A7E\"><\/path><path d=\"M19.885 6.80322C19.8943 6.85893 19.9036 6.90536 19.9036 6.95178C19.95 6.9425 19.9779 6.92393 19.885 6.80322Z\" fill=\"#8F3A7E\"><\/path><path d=\"M16.6518 10.8394L16.6318 10.8494L16.6518 10.8394Z\" fill=\"#8F3A7E\"><\/path><path d=\"M19.8203 7.01859C19.885 7.02783 19.9035 7.0001 19.9035 6.95389C19.8665 6.96313 19.8203 6.97237 19.8203 7.01859Z\" fill=\"#8F3A7E\"><\/path><path d=\"M26.1981 2.03489H26.2264C26.2264 2.03489 26.2075 2.00662 26.1981 1.99719V2.03489Z\" fill=\"#8F3A7E\"><\/path><path d=\"M26.1977 1.99845V1.96075C26.1977 1.96075 26.1789 1.9796 26.1977 1.99845Z\" fill=\"#8F3A7E\"><\/path><path d=\"M26.2079 1.8683V1.95148C26.2079 1.95148 26.2449 1.933 26.2079 1.8683Z\" fill=\"#8F3A7E\"><\/path><path d=\"M25.6025 2.37845L25.6578 2.45208C25.6578 2.45208 25.6302 2.40606 25.6025 2.37845Z\" fill=\"#8F3A7E\"><\/path><path d=\"M25.4627 2.52706C25.5183 2.50852 25.6852 2.60121 25.7037 2.51779L25.6574 2.45291C25.7223 2.58267 25.3978 2.37876 25.4627 2.52706Z\" fill=\"#8F3A7E\"><\/path><path d=\"M24.0587 2.18406L24.2354 2.12826C24.1517 2.07245 24.0308 1.98874 24.0773 1.92363C23.7145 1.83062 24.254 2.07245 24.0587 2.18406Z\" fill=\"#8F3A7E\"><\/path><path d=\"M23.5575 2.40555C23.5946 2.31271 23.4646 2.29414 23.4275 2.24771C23.4461 2.35913 23.4461 2.38698 23.5575 2.40555Z\" fill=\"#8F3A7E\"><\/path><path d=\"M20.6004 4.88834L20.4517 4.70251C20.4239 4.77684 20.5075 4.77684 20.6004 4.88834Z\" fill=\"#8F3A7E\"><\/path><path d=\"M20.833 6.30117L20.9817 6.36621L20.8702 6.18039L20.833 6.30117Z\" fill=\"#8F3A7E\"><\/path><path d=\"M19.4009 5.29716L19.4102 5.25073L19.373 5.39001L19.4009 5.29716Z\" fill=\"#8F3A7E\"><\/path><path d=\"M14.5673 9.62069L14.7804 9.8246C14.7804 9.75045 14.5673 9.5002 14.5673 9.62069Z\" fill=\"#8F3A7E\"><\/path><path d=\"M12.6902 11.7309C12.5694 11.6473 12.4486 11.6287 12.5044 11.7681C12.5601 11.7402 12.6902 11.7774 12.6902 11.7309Z\" fill=\"#8F3A7E\"><\/path><path d=\"M7.70828 16.6682L7.6897 16.4824L7.69899 16.659L7.70828 16.6682Z\" fill=\"#8F3A7E\"><\/path><path d=\"M1.70163 9.61194C1.61792 9.63054 1.4691 9.73285 1.52491 9.76076L1.81324 9.63984L1.70163 9.61194Z\" fill=\"#8F3A7E\"><\/path><path d=\"M1.38543 10.1886C1.54327 10.17 1.80325 10.0957 2.02609 9.91004C1.74754 10.0122 1.84039 9.9379 1.50613 10.0586C1.45042 10.0307 1.54327 9.92861 1.64541 9.88219C1.57113 9.90076 1.66398 9.78006 1.47828 9.85433C1.30187 10.0307 1.33901 10.1143 1.55256 10.0865C1.50613 10.1329 1.42257 10.1607 1.37615 10.1886H1.38543Z\" fill=\"#8F3A7E\"><\/path><path d=\"M6.07034 17.5318C6.07034 17.5318 6.02367 17.5318 6.005 17.5598C6.033 17.5598 6.06101 17.5598 6.07034 17.5318Z\" fill=\"#8F3A7E\"><\/path><path d=\"M6.40438 18.461C6.40438 18.461 6.38574 18.4238 6.38574 18.4051C6.38574 18.4517 6.38574 18.4797 6.40438 18.461Z\" fill=\"#8F3A7E\"><\/path><path d=\"M4.03508 14.7249L4.01648 14.8551C4.10019 14.7993 4.04438 14.7714 4.03508 14.7249Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.3788 10.391C2.3788 10.391 2.32335 10.391 2.28638 10.391C2.30486 10.391 2.32335 10.4002 2.33259 10.4095L2.3788 10.3817V10.391Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.96444 13.7376L2.94584 13.719C2.94584 13.719 2.87143 13.7562 2.83423 13.7748L2.96444 13.7376Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.26855 12.8844C2.26855 12.8844 2.49178 12.7635 2.58479 12.7077C2.49178 12.7635 2.43597 12.7728 2.40807 12.7728C2.37087 12.8007 2.32436 12.8379 2.26855 12.8937V12.8844Z\" fill=\"#8F3A7E\"><\/path><path d=\"M3.40322 14.398C3.40322 14.398 3.34722 14.4447 3.33789 14.4634C3.36589 14.4447 3.38456 14.4167 3.40322 14.398Z\" fill=\"#8F3A7E\"><\/path><path d=\"M24.3936 0.882324C24.3936 0.882324 24.4124 0.910594 24.4218 0.920017C24.4124 0.891747 24.403 0.882324 24.3936 0.882324Z\" fill=\"#8F3A7E\"><\/path><path d=\"M26.1963 1.0585V1.08636L26.2891 1.19778L26.1963 1.0585Z\" fill=\"#8F3A7E\"><\/path><path d=\"M7.32639 20.0692C7.32639 20.0692 7.32639 20.0692 7.32639 20.0592C7.29639 20.0692 7.31639 20.0792 7.32639 20.0692Z\" fill=\"#8F3A7E\"><\/path><path d=\"M13.8886 13.0136C13.6561 12.9113 13.8142 12.6788 13.5166 12.5951C13.6003 12.6602 13.684 12.995 13.8886 13.0136Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.37 10.4381C2.37 10.4381 2.38884 10.457 2.39826 10.4758C2.39826 10.457 2.38884 10.4476 2.37 10.4381Z\" fill=\"#8F3A7E\"><\/path><path d=\"M9.13905 18.7775C9.11125 18.7312 9.08346 18.6942 9.05566 18.6756C9.07419 18.7127 9.09272 18.7405 9.13905 18.7775Z\" fill=\"#8F3A7E\"><\/path><path d=\"M7.87305 19.9031L7.91937 20.005C7.90084 19.9494 7.89158 19.9216 7.87305 19.9031Z\" fill=\"#8F3A7E\"><\/path><path d=\"M9.5293 17.1406C9.5293 17.1406 9.59373 17.1407 9.59373 17.0762C9.58452 17.0762 9.57532 17.0762 9.56611 17.067C9.58452 17.1038 9.58452 17.1406 9.5385 17.1406H9.5293Z\" fill=\"#8F3A7E\"><\/path><path d=\"M10.1335 16.3052C10.1335 16.3052 10.0955 16.2957 10.0861 16.2863V16.3147L10.1335 16.3052Z\" fill=\"#8F3A7E\"><\/path><path d=\"M22.2911 2.80592C22.3562 2.85237 22.4119 2.89883 22.477 2.95457C22.3469 2.8245 22.4119 2.68513 22.2911 2.80592Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.25891 10.4761C2.31499 10.448 2.35237 10.4293 2.37106 10.4387L2.34302 10.42C2.34302 10.42 2.2776 10.4574 2.25891 10.4761Z\" fill=\"#8F3A7E\"><\/path><path d=\"M8.05957 15.6353L8.11645 15.6163C8.11645 15.6163 8.06905 15.6163 8.05957 15.6353Z\" fill=\"#8F3A7E\"><\/path><path d=\"M17.1702 7.21375V7.16635C17.1702 7.16635 17.1607 7.18531 17.1702 7.21375Z\" fill=\"#8F3A7E\"><\/path><path d=\"M8.31042 15.2827C8.40334 15.3198 8.45908 15.3198 8.50554 15.3198C8.49625 15.3013 8.48696 15.2827 8.46837 15.2641L8.31042 15.2827Z\" fill=\"#8F3A7E\"><\/path><path d=\"M22.9801 2.12785C22.9986 1.93263 23.0544 2.14644 23.2961 2.2394C23.1753 1.97911 23.4635 2.23011 23.1846 1.86756C23.417 2.07207 23.3333 1.98841 23.5378 2.09996C23.3519 1.93263 23.5099 1.80249 23.3147 1.57938C23.5564 1.81178 23.4635 1.98841 23.7795 2.18363C23.6959 1.96052 23.7516 1.80249 23.5285 1.51431C23.6308 1.5422 23.733 1.62586 23.826 1.58868C23.7981 1.58868 23.826 1.64445 23.8446 1.68164C23.8167 1.38416 24.1607 1.42135 23.9468 1.02161C24.2536 1.44923 24.2629 0.844989 24.4767 1.3005C24.5232 1.24472 24.4581 1.00302 24.4117 0.910061C24.6719 1.22613 24.6069 0.882173 24.8207 1.02161C24.6998 0.8171 24.8486 0.798508 24.8207 0.649771C24.8207 0.705547 24.8579 0.77062 24.9415 0.854285C24.895 0.668363 24.988 0.807804 25.1646 0.910061C25.1646 0.742732 24.9508 0.686955 24.8765 0.491737C25.0159 0.491737 25.0531 0.677659 25.1739 0.798508L25.0252 0.38948C25.0717 0.398776 25.1367 0.445257 25.2204 0.528921C25.1832 0.408072 25.1089 0.240743 25.2855 0.343L25.1925 0.435961L25.3599 0.566106L25.3041 0.268631C25.6666 0.361592 25.899 0.742732 26.1593 1.08669L26.1407 1.19824C26.2337 1.30979 26.3359 1.33768 26.3731 1.31909C26.4661 1.37487 26.5683 1.7746 26.5219 1.87685C26.3081 2.02559 26.1593 1.5236 25.9548 1.55149L25.9362 1.89545L25.8432 1.78389C25.7503 1.72812 25.8432 1.86756 25.8525 1.90474C25.7224 1.72812 25.6666 1.96982 25.5644 2.007L25.7131 2.12785C25.7968 2.63913 25.0903 2.02559 25.081 2.34166L25.1739 2.68561L24.9694 2.4904C25.0066 2.67632 25.1367 2.85294 24.9694 2.86224C24.2815 2.79717 24.2629 3.59663 23.6773 3.6803C23.7144 3.71748 23.7423 3.72678 23.7981 3.73607C23.0172 3.47578 23.7423 4.72146 23.0916 4.55413L23.0451 4.46117C22.9243 4.6285 22.9986 4.35891 22.7848 4.34032C22.9801 4.6192 22.7662 4.70287 22.7569 4.87949C22.7291 4.81442 22.7569 4.79583 22.7569 4.73075C22.6919 4.68427 22.5524 4.53554 22.5524 4.6192C22.7755 5.07471 22.5338 5.21415 22.4688 5.45585C22.3014 5.29782 22.0411 5.26063 21.7437 5.03752C21.7809 5.11189 21.8645 5.26993 21.9482 5.41866C21.7995 5.35359 21.8273 5.47444 21.8738 5.61388C21.9203 5.5674 21.9575 5.53022 21.9854 5.49303V5.51163C21.9854 5.51163 21.9947 5.48374 22.004 5.47444C22.0319 5.43726 22.0412 5.40937 22.0226 5.40937C22.2271 5.52092 22.1341 5.54881 22.3014 5.74403C22.2457 5.78121 22.1992 5.93925 22.0597 5.7998C22.0226 5.8184 21.9854 5.8184 21.9296 5.8184C21.9296 5.86488 21.9296 5.90206 21.8924 5.90206V5.87417C21.8924 5.87417 21.8366 5.83699 21.818 5.8184C21.6507 5.8184 21.7623 6.23672 21.7995 6.44123C21.6693 6.12517 21.5392 6.17165 21.3811 5.99502C21.3811 6.01361 21.4927 5.93925 21.6228 5.83699C21.5949 5.82769 21.5578 5.7998 21.502 5.73473C21.2324 5.63247 21.4648 6.06009 21.1859 6.06009C21.1859 6.03221 21.1673 5.97643 21.1022 5.91136C21 5.91136 21.0744 6.09728 21.158 6.21813C20.9907 6.0508 20.7676 6.02291 20.7676 6.15306C20.842 6.34827 20.907 6.40405 20.7955 6.46912L20.7304 6.31109C20.5259 6.30179 20.7955 6.57138 20.6188 6.55279C20.7025 6.57138 20.591 6.44123 20.5445 6.43194C20.4887 6.59927 20.5445 6.67364 20.6746 6.9897L20.5259 6.77589C20.5259 6.98041 20.5445 7.38014 20.3214 7.11055C20.7025 7.49169 20.2935 7.51028 20.2005 7.57536C20.2191 7.53817 20.154 7.44521 20.1169 7.39873C20.1726 7.82635 19.7636 7.7148 19.587 7.88213L19.2988 7.61254C19.2151 7.7055 19.6892 8.31904 19.5777 8.39341L19.494 8.21679C19.3546 8.4213 19.2523 8.45849 19.0664 8.54215L18.8991 8.33764C18.927 8.47708 18.8619 8.53285 18.8898 8.6723C18.3506 8.29116 18.6295 9.34161 17.9416 8.99766L18.2483 9.3788C18.1554 9.44387 18.1089 9.6112 17.83 9.3788H17.8579C17.6162 9.08132 17.7649 9.43458 17.6627 9.41598C17.6534 9.48106 17.7742 9.70416 17.8579 9.72275C17.4675 9.72275 17.3094 10.2154 16.8725 10.0109C16.7517 10.327 16.8446 10.7732 16.5658 10.9498L16.5286 10.9034C16.4077 10.9219 16.1474 10.9684 15.8778 10.6617C15.7663 10.8848 16.0359 11.4053 15.7012 11.4518L15.6454 11.2938C15.5432 11.2845 15.5897 11.4983 15.599 11.5541C15.5711 11.5634 15.5339 11.489 15.4967 11.4425C15.3573 11.3868 15.4688 11.5727 15.4595 11.6377L15.3851 11.5169C15.0319 11.4518 15.1435 12.1026 14.8925 12.242C14.9018 12.1769 14.7809 12.084 14.7158 12.0468C14.9389 12.4651 14.6229 12.5952 14.6136 12.7533L14.5485 12.5767C14.5764 12.9578 14.0744 12.3535 14.1116 12.7347L14.3812 12.8369C14.2603 12.8369 14.2603 12.9578 14.4184 13.0972C14.2324 13.0601 14.1767 12.8462 14.0186 12.9299C13.9257 12.8369 14.0465 12.7812 13.8978 12.6975L13.498 12.6045C13.498 12.6045 13.4423 12.5952 13.4144 12.6696C13.8141 13.0786 13.2935 12.8184 13.7583 13.153C13.5538 13.404 13.0983 13.311 13.0704 13.6922C12.6149 13.3668 12.6521 14.0547 12.1873 13.5156C12.0664 13.6178 12.0757 13.813 12.2059 14.0826C12.271 14.1012 12.2338 14.0083 12.2338 13.9618C12.3267 14.1198 12.2152 14.2685 12.1594 14.3243C12.1222 14.1384 12.1501 13.9246 12.02 13.6736C11.9642 13.8223 12.0014 14.1477 12.0107 14.2685L11.7318 14.0268C11.834 14.3057 11.4529 13.8781 11.6202 14.2221L11.7132 14.2871C11.5366 14.4173 11.7876 14.6869 11.6853 14.8542L11.5923 14.7426C11.4994 14.7426 11.676 15.068 11.3878 14.8821L11.4715 14.7798C11.2856 14.6032 11.1275 14.6032 11.0067 14.5381C10.9509 14.6869 11.267 14.8635 11.2484 14.9379C11.0532 14.7891 11.1554 14.8542 11.016 14.6497C10.9602 14.817 10.8951 15.0401 11.0439 15.3376C11.016 15.319 10.9788 15.2725 10.9788 15.2725C10.8394 15.3562 11.0625 15.7559 10.8487 15.6908V15.6444C10.4954 15.5049 10.8765 16.1092 10.4024 15.728C10.2816 15.7001 10.514 15.6444 10.2258 15.5142C9.95623 15.5328 10.5233 15.9418 10.2909 15.9511C10.3188 15.9511 10.2909 15.9325 10.2537 15.8861C10.1886 15.9883 10.1329 16.1464 10.0957 16.2858C9.60298 16.1185 9.90046 16.732 9.3148 16.574C9.51002 16.639 9.46354 16.7692 9.52861 16.8343C9.52861 16.8343 9.49143 16.7878 9.46354 16.7785C9.39847 16.8343 9.53791 16.983 9.58439 17.0667C9.41706 17.0016 9.58439 17.4385 9.46354 17.4013C9.54721 17.5036 9.48213 17.5501 9.43565 17.6244C9.43565 17.3455 9.28692 17.3363 9.18466 17.1131C9.02663 17.234 9.40776 17.8661 9.21255 18.0613C9.13818 18.0242 9.07311 17.987 8.99874 17.9405C9.20325 18.3867 8.99874 18.4983 9.07311 18.6656C8.98944 18.5726 8.92437 18.554 8.82211 18.303C8.82211 18.5354 8.65478 18.4239 8.74774 18.7957L8.8407 18.8236C8.72915 18.9073 8.71985 19.1955 8.70126 19.4929C8.68267 19.7811 8.65478 20.06 8.55253 19.9856L8.33872 18.9445C8.19927 18.647 8.33872 19.8462 8.17139 19.2977C8.24575 19.6417 8.23646 19.5022 8.25505 20.0042C8.29223 20.0135 8.28294 19.5952 8.32942 19.4929L8.34801 20.404L8.44097 19.6882C8.45956 20.2738 8.44097 20.1716 8.55253 20.5341C8.52464 21.0547 8.40379 20.5713 8.35731 20.7386C8.34801 20.7386 8.32942 20.7758 8.32012 20.8502C8.25505 20.6828 8.23646 20.2831 8.17139 20.06C8.12491 20.4411 7.94828 19.4093 7.9018 19.7718C7.86461 19.6417 7.94828 19.7997 7.92039 19.5673C7.85532 19.5673 7.80884 19.4744 7.79954 19.7253L7.87391 19.902C7.81813 19.809 7.82743 20.1716 7.69728 19.8276C7.64151 19.9577 7.60432 20.3296 7.68799 20.4318C7.6601 20.4504 7.57644 20.1344 7.60432 19.902C7.4277 19.6789 7.51136 20.6921 7.32544 20.0693C7.34403 20.0693 7.35333 20.0321 7.35333 19.9763C7.30685 19.8648 7.26967 19.8183 7.23248 19.8276C7.39981 19.9485 7.22318 19.1304 7.39051 19.4929C7.39051 19.0374 7.26037 19.2512 7.21389 19.0188C7.10234 19.1955 7.15811 19.5952 7.09304 19.7439C7.10234 19.6138 7.06515 19.5673 7.02797 19.4651L7.04656 19.8183C7.00008 19.7718 6.96289 19.716 6.90712 19.7253L7.00937 19.7068C6.91641 19.5394 6.86993 18.9352 6.67472 19.0281C6.73979 18.9631 6.85134 18.8236 6.79556 18.5726C6.60964 18.5726 6.78627 18.4146 6.75838 18.1264C6.60964 18.0242 6.60964 18.5633 6.44231 18.1543C6.42372 18.1264 6.38654 18.2937 6.38654 18.3867C6.28428 18.0892 6.12625 18.145 6.06117 17.8196C6.08906 17.9498 6.10765 18.0892 5.96821 18.0799C6.09836 17.9498 5.93103 17.7732 5.94032 17.6058L5.86596 17.6895C5.89384 17.5315 5.96821 17.5501 6.02399 17.5501C6.0054 17.5779 5.9961 17.6244 6.02399 17.6523C6.14484 17.6523 6.33076 17.2247 6.27498 17.0853C6.12625 17.0667 5.95892 17.327 5.91244 17.4478C5.83807 17.1782 5.44763 17.6802 5.40115 17.3548C5.36397 17.3084 5.55918 16.8529 5.50341 16.7134C5.25241 16.8064 5.48482 16.9923 5.27101 17.0667C5.56848 16.4345 4.68535 16.9551 4.78761 16.481L5.0479 16.3137C5.02001 16.2486 5.00142 16.1928 4.92705 16.1556L4.85268 16.3323C4.75972 16.3323 4.71324 16.1742 4.92705 16.0627C4.63887 16.1092 4.74113 15.9883 4.71324 15.8396C4.77831 15.9697 4.68535 15.8675 4.87127 15.8489C4.89916 15.6351 4.8062 15.6908 4.69465 15.6537C4.78761 15.5979 4.88987 15.4491 4.86198 15.4213C4.64817 15.4677 4.5738 15.3097 4.41577 15.2725L4.49013 15.2167C4.25773 15.1145 4.44365 14.6497 4.0904 14.6404C4.0904 14.6404 4.08111 14.6404 4.07181 14.6404V14.6683C3.88589 14.91 3.79293 14.6497 3.66278 14.6683C3.70926 14.6125 3.81152 14.5288 3.78363 14.4916C3.56982 14.659 3.6163 14.5102 3.49545 14.5567C3.52334 14.4359 3.76504 14.3615 3.67208 14.2685C3.6256 14.2407 3.50475 14.3243 3.42108 14.3894C3.51404 14.2778 3.55123 14.1477 3.53264 14.0733C3.60701 14.0454 3.55123 14.1384 3.57912 14.1384C3.69997 14.0547 3.6256 14.0547 3.77434 13.9432C3.75574 13.8781 3.55123 14.0826 3.57912 13.9618L3.79293 13.8874C3.82082 13.8316 3.71856 13.8502 3.69997 13.8502C3.77434 13.8502 3.94166 13.7201 4.04392 13.6364C3.81152 13.5899 3.56053 13.9618 3.36531 14.1012C3.3932 13.8595 3.08642 13.9246 2.99346 13.8223L3.21657 13.6922C3.1422 13.6643 3.07713 13.6736 2.97487 13.7201L2.9098 13.6364C3.02135 13.6364 3.09572 13.5992 3.26305 13.4784C3.1422 13.4319 3.10502 13.2832 2.81684 13.4598L2.86332 13.4319C2.87261 13.246 2.75177 12.9578 2.85402 12.902C2.6681 12.8462 2.71458 12.5674 2.4357 12.7626C2.31485 12.7347 2.64951 12.3164 2.26837 12.5116C2.38922 12.2885 2.34274 12.4558 2.56584 12.335C2.68669 12.1211 2.15682 12.3628 2.52866 12.0468C2.33344 12.0282 2.46359 12.1304 2.25907 12.2234C2.61232 11.9352 2.1847 11.991 2.32415 11.74C2.14752 11.8051 2.25907 11.8516 2.05456 11.8887C2.15682 11.833 2.13822 11.7772 2.13822 11.7493L1.89653 11.8887L2.39851 11.3868C2.01737 11.4332 2.01737 11.6935 1.77568 11.5727H1.80356C2.00808 11.3496 1.52468 11.5541 1.60835 11.2845C1.59905 11.3682 1.73849 11.2287 1.81286 11.2008L1.66412 11.1822C1.66412 11.1822 1.70131 11.1822 1.7199 11.1451C1.85005 10.9591 1.58046 11.1451 1.68272 10.9591C1.76638 10.987 1.93371 10.8476 2.00808 10.7639L1.66412 10.8197L2.01737 10.6524C1.97089 10.5222 1.33876 10.6803 1.75708 10.3363L1.84075 10.3642C1.91512 10.3084 2.13822 10.1318 1.92441 10.1597C1.86864 10.1597 1.66412 10.2619 1.70131 10.2898L1.73849 10.1876C1.97089 10.0853 2.11963 10.1876 2.23118 10.234C2.12893 10.2619 2.01737 10.234 1.89653 10.3456C2.01737 10.3828 2.2033 10.3642 2.32415 10.3921C2.22189 10.42 2.07315 10.485 1.98019 10.5222C1.92441 10.6803 2.16611 10.4943 2.23118 10.5408C2.16611 10.6245 2.11963 10.671 2.03597 10.6988C2.17541 10.7267 2.24048 10.7732 2.1847 10.9312C2.1847 10.9312 1.97089 10.9312 1.87793 11.0707C2.11034 11.1451 2.37992 11.0056 2.64021 11.0707C3.12361 11.0149 2.68669 11.5913 3.03065 11.5448C3.12361 11.489 3.12361 11.331 3.24446 11.3775C3.04924 11.4983 3.16079 11.5169 3.09572 11.5727C3.43038 11.4704 3.13291 11.7493 3.36531 11.6842C3.29094 11.7121 3.25375 11.8237 3.21657 11.898C2.98417 12.0561 3.19798 12.0654 2.77965 12.1676C3.22587 12.0561 2.87261 12.4837 3.47686 12.1955L3.51404 12.1118V12.3257V12.3164C3.51404 12.4 3.58841 12.3721 3.41179 12.6231C3.32812 12.6231 3.29094 12.5767 3.20727 12.5859C3.06783 12.8091 3.48616 12.6138 3.56053 12.6882C3.3932 12.8091 3.43968 12.6417 3.25375 12.8184C3.27235 12.8927 3.43038 12.8555 3.51404 12.8741L3.42108 12.9299C3.32812 13.2274 3.90448 12.651 3.68137 12.9857C3.72785 12.9392 3.80222 12.9113 3.8487 12.8648C3.78363 12.9764 3.69067 13.1902 3.50475 13.1809C3.54193 13.2274 3.66278 13.2274 3.78363 13.1809C3.88589 13.0415 3.81152 13.0786 3.96955 12.9299L4.22055 13.0601C4.22055 13.0601 4.11829 13.1065 4.0997 13.0786C3.80222 13.6829 4.87127 13.246 4.49943 13.9525C4.62028 13.813 4.64817 13.8688 4.75972 13.8223C4.77831 13.9432 4.91775 14.0454 4.88987 14.1942L4.76902 14.2499C5.0479 14.3615 5.31749 14.3801 5.36397 14.5567C5.41045 14.5288 5.22453 14.6683 5.16875 14.6683C5.42904 14.6218 4.94564 15.1981 5.35467 14.9193V14.8542C5.44763 15.1052 5.89384 15.0959 6.10765 15.2632C5.91244 15.4956 5.9868 15.1703 5.7544 15.4306C5.77299 15.6444 6.08906 15.6258 6.12625 15.8396C6.07977 15.8396 6.05188 15.8675 6.03328 15.8675C6.0054 16.1371 6.2471 15.663 6.32146 15.821C6.20061 15.9047 6.18202 15.9325 6.15413 16.0255L6.36794 15.9139C6.36794 15.9139 6.20061 16.0627 6.13554 16.0906C6.41442 15.9418 6.36794 16.2114 6.59105 16.0348C6.54457 16.0999 6.34006 16.2765 6.27498 16.3695C6.27498 16.4996 6.37724 16.4531 6.4795 16.3973C6.38654 16.6019 6.48879 16.6855 6.45161 16.6948C6.48879 16.89 6.56316 16.574 6.7212 16.481L6.73979 16.2951L6.86993 16.3509L6.75838 16.4438C6.74908 16.6112 6.92571 16.4252 6.96289 16.481L7.01867 16.2765C7.01867 16.2765 7.08374 16.2393 7.11163 16.2207C6.97219 16.6019 7.14882 16.388 6.96289 16.7971C7.03726 17.1596 7.24178 16.7041 7.32544 16.7506C7.30685 16.732 7.30685 16.8343 7.28826 16.9086C7.33474 17.0853 7.39981 16.8807 7.43699 16.6483C7.4184 16.7971 7.40911 16.8436 7.39051 16.9644C7.45559 17.0481 7.44629 16.7227 7.51136 16.6297C7.49277 16.8343 7.49277 16.9551 7.51136 17.0295C7.51136 16.8343 7.52996 16.7041 7.53925 16.6669C7.48347 17.6802 7.62292 17.2061 7.60432 18.0428C7.61362 17.8289 7.71588 17.4757 7.6508 16.9644V17.0295C7.62292 16.7134 7.6508 16.8621 7.6601 16.8529C7.6601 16.8993 7.6508 16.9551 7.6601 17.0202C7.68799 16.89 7.72517 16.9365 7.74377 16.9179C7.76236 16.8622 7.78095 16.8343 7.79025 16.7506C7.79025 16.7041 7.79954 16.6483 7.79954 16.574C7.81813 16.6948 7.82743 16.9458 7.85532 17.0016C7.94828 17.0016 7.88321 16.3695 7.85532 16.0627C8.03194 16.6205 7.82743 16.2579 7.96687 16.8436C8.01335 16.5368 8.03194 16.1928 7.96687 15.8582C8.15279 16.1649 8.1435 16.0534 8.11561 15.9418C8.08772 15.821 8.04124 15.7187 8.23646 15.8768C8.08772 15.7094 8.05983 15.6165 8.06913 15.5793C8.18998 15.7187 8.21787 15.6815 8.30153 15.7745C8.24575 15.6815 8.20857 15.6072 8.23646 15.5793C8.25505 15.57 8.39449 15.5142 8.55253 15.663C8.23646 15.3934 8.70126 15.4956 8.52464 15.2539C8.72915 15.2446 8.62689 14.975 8.83141 14.9286C8.59901 14.8077 8.8407 14.7241 8.79422 14.6125C8.79422 14.6404 8.79422 14.6869 8.83141 14.7055C9.02663 14.8077 8.80352 14.4359 8.97085 14.4545C9.06381 14.4824 9.13818 14.6218 9.20325 14.5846C9.06381 14.4638 9.07311 14.1384 9.29621 14.2221C9.26832 14.2499 9.3334 14.315 9.37058 14.3801C9.42636 13.8502 10.0213 13.7851 10.0585 13.2274L10.2165 13.497C10.6813 13.5899 9.98412 13.0136 10.17 12.8927C10.6906 12.5952 11.425 12.5209 11.6853 12.0003C11.6574 11.9073 11.5923 11.9352 11.4994 11.8423C11.5645 11.8423 11.7411 12.0189 11.6853 11.8516L11.5645 11.74C12.0479 11.898 11.8898 11.0242 12.5034 11.4146C12.5034 11.0614 12.931 11.2752 12.8752 10.7918C13.0425 10.8383 12.9868 11.0707 13.1076 11.0242L13.1355 10.6524V10.6803C13.0054 10.1411 14.0186 10.6245 14.0279 10.1504V10.1783C14.1023 10.2712 14.251 10.327 14.2603 10.2619C14.2231 10.1876 14.1674 10.1783 14.0744 10.1318C14.1581 9.79712 14.2045 9.74135 14.3533 9.56472C14.3905 9.75994 14.5206 9.6112 14.6879 9.78783C14.6322 9.62979 14.502 9.62979 14.5113 9.44387C14.6415 9.29513 14.911 9.33232 15.0784 9.29513C14.9854 9.09062 15.0877 9.08132 14.9203 8.88611C15.0691 8.72807 15.097 8.57004 15.2922 8.40271L15.3573 8.46778C15.1992 8.1796 15.6361 8.43989 15.5525 8.26327C15.6268 8.35623 15.6361 8.41201 15.7012 8.46778L15.7198 8.30975C15.7384 8.4213 15.9243 8.6723 16.0173 8.63511C15.9429 8.39341 15.8964 8.53285 15.8035 8.36552L16.0266 8.57004C16.0638 8.49567 15.85 8.22608 15.7198 8.21679C15.9243 8.04016 16.0266 7.76128 16.2311 7.64043L16.3426 7.80776C16.3891 7.66832 16.5286 7.54747 16.6959 7.63113C16.6587 7.58465 16.6122 7.4824 16.5565 7.44521C16.5007 7.13844 16.7796 7.67761 16.7238 7.35225C16.7424 7.43592 16.7238 7.50099 16.7982 7.59395L16.8818 7.20351C16.9841 7.31507 17.3466 7.43592 17.3559 7.24999C17.3094 7.18492 17.2072 7.12914 17.17 7.13844L17.1886 7.02689L17.4675 7.2407L17.3652 6.93393L17.5511 7.14774C17.579 7.04548 17.3745 6.73871 17.4396 6.71082C17.7742 6.66434 17.7928 6.77589 18.1182 6.85026C17.7742 6.42264 18.3692 6.66434 18.1554 6.32968C18.6202 6.46912 18.7503 6.03221 19.0943 5.89277V5.94854C19.3825 6.0415 18.9641 5.52092 19.1594 5.50233L19.178 5.58599C19.5219 5.67896 19.6242 5.24204 19.6242 4.93527C19.6428 5.01893 19.7729 5.13978 19.8101 5.0933C19.7822 4.98175 19.5219 4.83301 19.6706 4.84231C19.6799 4.89808 19.7822 4.98175 19.8008 4.96316L19.7078 4.68427C20.0425 4.64709 20.4236 4.58202 20.5445 4.26595C20.6467 4.30313 20.6839 4.40539 20.7304 4.48906C20.8698 4.29384 20.8977 3.96847 21.0279 3.80115L21.251 4.03355C21.3254 3.96847 20.9907 3.62452 21.2696 3.75466C21.3161 3.76396 21.2138 3.82903 21.2696 3.95918C21.5856 4.00566 21.1673 3.64311 21.3346 3.54085L21.5299 3.84763C21.7809 3.9127 21.5392 3.59663 21.4462 3.39212C21.3346 2.93661 22.004 3.81974 22.0226 3.39212C21.9482 3.22479 21.8459 3.2062 21.7623 3.03887C21.9761 2.98309 21.8366 2.76928 22.0504 2.7135C22.4781 3.04816 21.9668 2.77858 22.3851 3.08535H22.1899C22.4688 3.22479 22.1434 3.22479 22.3665 3.45719C22.506 3.45719 22.4502 3.15971 22.4781 2.99239C22.6361 3.17831 22.3758 3.11323 22.6361 3.31775V3.1969C22.6547 3.26197 22.7105 3.33634 22.6733 3.35493C22.8313 3.51297 22.7384 3.31775 22.7848 3.27127C22.7105 3.16901 22.5896 3.03887 22.4688 2.92731C22.4874 2.9459 22.506 2.9645 22.5338 2.98309C22.413 2.63913 22.7477 2.69491 22.664 2.41603C22.6919 2.4811 22.7198 2.4904 22.7569 2.52758C22.822 2.4904 22.6826 2.19292 22.7105 2.05348C22.8685 2.15574 23.0265 2.4811 23.0916 2.29518C22.9894 2.12785 22.7105 1.91404 22.822 1.82108C22.822 1.82108 22.822 2.02559 22.9708 2.09066L22.9801 2.12785ZM20.8327 4.54483C20.8327 4.54483 20.8048 4.57272 20.7862 4.60061C20.7862 4.60061 20.8141 4.55413 20.8234 4.54483H20.8327ZM20.7769 4.8702C20.7769 4.8702 20.749 4.77723 20.6839 4.71216C20.6467 4.74005 20.6188 4.76794 20.5817 4.78653C20.6653 4.81442 20.749 4.81442 20.7769 4.8702ZM22.1341 5.67896L22.1527 5.70684C22.1527 5.70684 22.1248 5.76262 22.1155 5.78121C22.1527 5.8184 22.1992 5.84628 22.2085 5.79051C22.1899 5.76262 22.162 5.71614 22.1341 5.67896Z\" fill=\"#8F3A7E\"><\/path><path d=\"M22.0416 5.47307C22.0416 5.47307 22.0416 5.45466 22.0416 5.44546C22.0231 5.43626 22.0047 5.42705 21.9863 5.41785L22.0231 5.49148L22.0416 5.47307Z\" fill=\"#8F3A7E\"><\/path><path d=\"M4.04395 14.6689C4.04395 14.6689 4.05317 14.6597 4.06239 14.6413C4.06239 14.6505 4.05317 14.6597 4.04395 14.6689Z\" fill=\"#8F3A7E\"><\/path><path d=\"M17.3184 6.90505L17.365 6.96105L17.3464 6.89572L17.3184 6.90505Z\" fill=\"#8F3A7E\"><\/path><path d=\"M3.82129 12.9043C3.82129 12.9043 3.84973 12.8664 3.85921 12.8474C3.84973 12.8569 3.83077 12.8759 3.82129 12.9043Z\" fill=\"#8F3A7E\"><\/path><path d=\"M3.47742 12.3441L3.49602 12.2139C3.47742 12.279 3.47742 12.3162 3.47742 12.3441Z\" fill=\"#8F3A7E\"><\/path><path d=\"M3.28078 11.8598C3.28078 11.8598 3.21608 11.8967 3.18835 11.9152L3.28078 11.8598Z\" fill=\"#8F3A7E\"><\/path><path d=\"M6.45996 16.4436C6.45996 16.4436 6.54407 16.3969 6.57211 16.3875C6.57211 16.3408 6.55342 16.3221 6.45996 16.4436Z\" fill=\"#8F3A7E\"><\/path><path d=\"M6.62872 16.4611C6.62872 16.3873 6.6195 16.3781 6.57336 16.3873C6.57336 16.4242 6.58259 16.4703 6.62872 16.4611Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.17539 10.0107V9.98242C2.17539 9.98242 2.14712 10.0013 2.1377 10.0013H2.17539V10.0107Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.12949 10.0114H2.0918C2.0918 10.0114 2.10122 10.0208 2.12949 10.0114Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.00806 9.99291H2.09124C2.09124 9.99291 2.07275 9.96519 2.00806 9.99291Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.41699 10.6243L2.50017 10.5781C2.50017 10.5781 2.45396 10.5966 2.41699 10.6243Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.55659 10.7733C2.55659 10.7177 2.65855 10.5601 2.57513 10.5416L2.51025 10.5787C2.64001 10.5231 2.39903 10.8289 2.55659 10.7733Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.07381 12.1401L2.0366 11.9541C1.97149 12.0378 1.88778 12.1494 1.82268 12.0936C1.70176 12.4471 1.9808 11.9262 2.08311 12.1401H2.07381Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.27776 12.6685C2.18469 12.622 2.15677 12.7523 2.11023 12.7895C2.22192 12.7895 2.24984 12.7895 2.27776 12.6685Z\" fill=\"#8F3A7E\"><\/path><path d=\"M4.62895 15.747L4.43384 15.8864C4.50817 15.9235 4.50817 15.8306 4.62895 15.747Z\" fill=\"#8F3A7E\"><\/path><path d=\"M6.05145 15.5506L6.11649 15.4112L5.93066 15.5134L6.05145 15.5506Z\" fill=\"#8F3A7E\"><\/path><path d=\"M5.00248 16.9545H4.95605C5.00248 16.9638 5.0489 16.973 5.10461 17.0009C5.05819 16.973 5.03962 16.973 5.00248 16.9545Z\" fill=\"#8F3A7E\"><\/path><path d=\"M10.2145 16.5729L9.97351 16.4061C9.98278 16.471 10.2423 16.6842 10.2145 16.5729Z\" fill=\"#8F3A7E\"><\/path><path d=\"M11.8059 14.4079C11.9267 14.4915 12.0475 14.5101 11.9824 14.3708C11.9267 14.3986 11.7966 14.3615 11.8059 14.4079Z\" fill=\"#8F3A7E\"><\/path><path d=\"M18.3037 9.16579L18.3223 9.2774L18.3502 9.14719L18.3037 9.16579Z\" fill=\"#8F3A7E\"><\/path><path d=\"M1.64564 9.73384C1.52494 9.65027 1.46923 9.91025 1.50637 9.71527C1.6085 9.67813 1.69207 9.65956 1.64564 9.73384Z\" fill=\"#8F3A7E\"><\/path><path d=\"M25.5929 1.03314C25.7137 1.86049 24.812 1.67457 24.7376 2.32529C24.7097 2.38107 24.4959 2.01852 24.4587 2.16726C24.4587 2.88306 23.6872 3.09687 22.9807 3.13405L22.9342 3.0318C22.804 3.0318 22.9342 3.40364 22.8133 3.44083C22.7669 3.38505 22.7761 3.33857 22.6925 3.28279C22.8133 3.46871 22.5995 3.4966 22.6646 3.64534C22.5716 3.60815 22.4694 3.46871 22.3578 3.43153L22.4694 3.66393C22.7111 4.23099 22.1068 3.91493 22.1161 4.30536C22.0882 4.24959 22.0789 4.2031 22.0232 4.17522C21.9488 4.70509 21.5305 4.97468 21.2795 5.36512C21.233 5.29075 21.14 5.15131 21.0564 5.09553C21.2051 5.30934 21.1493 5.44878 21.0936 5.56963C20.8797 5.393 21.0936 5.8857 20.8983 5.8671L20.8704 5.81133C20.9727 6.09021 20.6473 5.78344 20.8054 6.09951L20.6195 5.97866C20.8333 6.29472 20.3778 5.92288 20.4428 6.1274L20.4986 6.18317C20.4986 6.30402 20.3406 6.18317 20.3313 6.28543L20.2941 6.25754C20.229 6.44346 20.0152 6.3505 20.2104 6.57361C20.0059 6.43417 20.2662 6.37839 19.9687 6.18317C19.7363 6.78742 19.2436 7.12208 18.816 7.50322C18.6859 7.45674 18.6301 7.45674 18.5464 7.38237C18.5464 7.46603 18.4163 7.56829 18.4814 7.71703C18.4906 7.69843 18.3512 7.62407 18.3233 7.63336C18.1746 7.61477 18.4535 7.95872 18.2768 7.93084C18.2582 7.83788 18.2118 7.75421 18.1281 7.67984C18.2025 7.92154 18.0816 7.97732 18.0444 8.10746C18.0258 8.06098 18.0258 8.0145 17.9608 7.94943C18.0351 8.22831 17.747 8.06098 17.7749 8.2562L17.6912 8.09817C17.4216 8.06098 17.8864 8.40494 17.6912 8.41423C17.6912 8.34916 17.6261 8.30268 17.5889 8.2469C17.6819 8.58156 17.4402 8.65593 17.403 8.82326C17.403 8.79537 17.3658 8.76749 17.3658 8.76749C17.2729 8.89763 17.0869 8.93481 17.0498 9.14862C16.9475 9.13003 16.7895 8.82326 16.7058 8.98129C16.9382 9.23229 16.585 9.27877 16.9196 9.50188C16.7802 9.54836 16.5199 9.60413 16.5292 9.75287C16.492 9.61343 16.1945 9.48328 16.2689 9.38103L16.0644 9.28807C15.9807 9.17651 16.1666 9.26018 16.0272 9.14862C15.99 9.19511 15.9528 9.41821 15.8784 9.40891C15.9342 9.64132 16.1201 10.0039 16.0179 10.1526C15.99 9.99457 15.7297 9.90161 15.7297 9.81794L15.9807 10.478C15.9435 10.5337 15.7855 10.2827 15.7855 10.4036C15.8506 10.4687 15.8599 10.5337 15.8877 10.6081C15.8413 10.5895 15.7669 10.8312 15.5159 10.6081C15.4043 10.5244 15.5438 10.4873 15.4136 10.4408C15.3393 10.5151 15.4136 10.6081 15.33 10.6825L15.3021 10.6546C15.2184 10.6639 15.237 10.9056 15.4229 10.9892C15.4694 10.9614 15.2742 10.8498 15.3951 10.8777C15.488 11.0543 15.4322 11.1845 15.3579 11.2588C15.3579 11.1938 15.2835 11.1287 15.2277 11.045C15.3021 11.3425 15.237 11.5098 15.1905 11.6958C15.2928 11.8166 15.0418 11.4355 15.1162 11.4819C14.8094 11.4541 15.0139 12.0118 14.6607 11.8817C14.6607 11.8445 14.828 12.0397 14.7908 12.0118C14.7071 12.0676 14.5491 11.891 14.5584 11.9932C14.4654 11.891 14.5305 12.0769 14.5026 12.1606C14.5398 12.2535 14.4469 12.1234 14.4747 12.0676C14.4747 12.2163 14.3446 12.6254 14.0564 12.6254C14.1215 12.6904 14.1866 12.96 14.1401 12.9879L14.0099 12.8206C13.8891 12.7555 13.8984 12.9507 13.7682 12.8206C13.8612 13.0809 13.9263 12.3837 13.9542 12.6254C13.8054 12.5231 14.0378 13.0065 13.8612 12.7741C13.7961 12.8485 13.8798 13.0902 13.6753 13.0065C13.7218 13.0065 13.5358 12.7369 13.4894 12.802C13.4057 12.9228 13.5265 12.9042 13.4894 13.0344V13.1459C13.6288 13.304 13.3871 13.211 13.5823 13.3412C13.4522 13.2296 13.4986 13.555 13.2755 13.2947L13.1082 13.0809C13.0803 13.1366 13.2291 13.3598 13.2755 13.4806C13.257 13.4713 13.2012 13.4341 13.1733 13.4062C13.4429 13.713 13.0431 13.4806 13.2105 13.7688C13.0153 13.7502 12.9595 13.9826 12.7364 13.8339C12.7457 13.9919 12.7829 14.1592 12.6434 14.1778C12.6341 14.1313 12.6434 14.1034 12.5876 14.0384C12.4575 14.0012 12.5133 14.0848 12.5133 14.1778C12.4854 14.122 12.2437 14.1034 12.0856 14.0477C12.1042 14.2057 12.2809 14.3451 12.3645 14.4474C12.0206 14.215 12.3459 14.8285 12.0113 14.6333C11.9927 14.5682 11.9741 14.3916 11.8439 14.373C11.5 14.1406 11.9276 14.717 11.6859 14.6705L11.9462 14.8843C11.751 14.7821 11.9369 15.1725 11.7045 14.9122C11.7603 15.033 11.5093 14.9494 11.751 15.1725C11.3884 15.1446 11.4814 15.6838 10.9608 15.3863C10.9794 15.4514 10.8772 15.47 11.0166 15.5722C11.1839 15.6559 10.9701 15.4235 11.0817 15.4979C11.0724 15.5257 11.1281 15.5908 11.1653 15.628C11.0631 15.628 11.0073 15.6559 10.8493 15.4142C10.589 15.3956 11.1467 15.9162 10.9236 15.972C10.8307 15.8697 10.7749 15.8511 10.7563 15.9069L10.8586 16.1393C10.7377 16.1951 10.5797 15.9905 10.3938 15.8418C10.3752 15.9162 10.3101 15.9812 10.4309 16.1114L10.1521 15.9905C10.3566 16.0742 10.2264 16.1207 10.245 16.1858L10.2171 16.1207C10.1335 16.0649 10.1242 16.1672 10.1242 16.2229C10.245 16.3066 10.338 16.2787 10.4031 16.2694C10.4588 16.3624 10.4031 16.3903 10.4681 16.5018C10.3008 16.3438 10.2729 16.4832 10.2264 16.5111C10.1521 16.5297 10.3473 16.6878 10.3287 16.697C10.2357 16.6227 10.2543 16.7621 10.1521 16.6227C10.1335 16.5855 10.2729 16.6506 10.2078 16.5669C10.1149 16.5483 9.95684 16.4182 10.0219 16.5669C10.0684 16.6878 10.3845 16.8272 10.1985 16.8365C10.1706 16.7807 10.1056 16.7156 10.0498 16.6506L9.89177 16.6692L10.0591 16.7993C10.0126 16.7807 10.0033 16.7621 9.97543 16.7528C10.1428 16.8923 9.90106 16.9666 10.0591 17.1711C10.0219 17.2641 9.83599 17.2455 9.77092 17.3106V17.2827C9.62218 17.2827 9.61288 17.4686 9.65936 17.6638L9.63148 17.6267C9.63148 17.6267 9.53852 17.8033 9.585 18.0078C9.41767 18.0264 9.06442 17.3199 9.15738 17.7196C9.1016 17.8498 9.28752 18.3425 9.38978 18.4261C9.18526 18.5284 9.23174 19.3743 8.94357 19.207C8.97145 19.3743 9.00864 19.4208 8.99005 19.5974C8.77624 19.9228 8.70187 21.1313 8.42298 20.6851C8.44158 20.3783 8.35791 20.2482 8.31143 19.9972C8.33002 20.3597 8.26495 20.0158 8.26495 20.1087C8.26495 20.1366 8.27425 20.211 8.29284 20.3783C8.33002 20.6014 8.34862 20.7594 8.3765 20.8896C8.3951 20.9732 8.41369 21.029 8.45087 21.0383C8.45087 21.0941 8.43228 21.1406 8.42298 21.2057C8.36721 21.2428 8.30214 21.2149 8.22777 21.1499C8.19058 21.1127 8.16269 21.0662 8.12551 21.0197C8.08833 20.9454 8.05114 20.8524 8.03255 20.7687C8.08833 20.9732 8.06973 21.029 8.03255 21.0848C7.99536 20.5828 7.88381 20.3783 7.80015 20.4434V20.7316L7.72578 20.3597C7.69789 20.4155 7.70719 20.9268 7.60493 20.5363C7.60493 20.4248 7.58634 20.3039 7.57704 20.2017C7.49338 20.3318 7.33534 20.5363 7.24238 20.1831L7.17731 19.6997C7.17731 19.6997 7.03787 19.8298 7.11224 20.025C6.9542 19.5881 6.84265 19.4301 6.84265 19.0768C6.44292 19.4673 5.89445 18.863 5.55049 18.3796L5.63416 18.2681C5.60627 18.0357 5.44824 18.4168 5.42964 18.2495C5.5319 18.1751 5.5226 17.9241 5.68064 17.8684C5.64345 17.5988 5.38316 17.8684 5.25302 17.8126C5.12287 17.9427 5.39246 17.8126 5.23443 17.9706C5.17865 17.9985 5.14146 17.636 4.93695 17.8126C4.97413 17.6917 5.14147 17.5802 5.23443 17.5151H5.0671C5.20654 17.1897 5.66205 17.3478 5.82938 16.9387L5.74571 16.9016C5.89445 16.6413 6.09896 16.8272 6.04319 16.6041C5.90374 16.6413 5.55979 16.8458 5.5412 17.0038C5.35528 16.8923 5.00202 17.3664 4.85329 17.1433C4.92765 16.9852 5.02062 17.2827 5.15076 17.0968C5.23443 16.8551 4.91836 17.0038 4.93695 16.9016C4.90906 17.0317 4.64877 17.1433 4.5837 17.134C4.62088 16.9852 4.8161 17.0224 4.76032 16.9016C4.62088 16.9852 4.46285 16.9666 4.44426 17.1154C4.13749 17.3013 4.44426 16.948 4.17467 17.0689C4.342 16.883 4.70455 16.8086 4.71384 16.6227C4.53722 16.79 4.3513 16.6878 4.11889 16.9759C4.13749 16.8923 4.27693 16.7621 4.42567 16.7063C4.49074 16.5483 3.96086 16.8272 4.31411 16.5111L4.1096 16.6413C4.15608 16.5762 4.18397 16.5018 4.25834 16.3903C4.22115 16.3345 3.8586 16.4182 4.14678 16.1951C4.1003 16.1951 4.01664 16.0649 3.84931 16.2694C3.79353 16.4461 4.06312 16.2415 3.83072 16.5018C4.00734 16.2694 3.70987 16.4089 3.59831 16.4275L3.70057 16.3345C3.6355 16.3345 3.60761 16.2601 3.47746 16.3345C3.56113 16.3066 3.6262 16.2322 3.6355 16.1858L3.44028 16.288C3.26365 16.2415 3.71916 16.0277 3.58902 15.9534L3.78424 15.9255C3.78424 15.9255 3.8772 15.7674 3.78424 15.7581C3.60761 15.8604 3.3938 15.972 3.26365 16.0463C3.1521 16.0463 3.42169 15.879 3.20788 15.9441L3.45887 15.8697C3.52395 15.8418 3.67268 15.6094 3.60761 15.535C3.51465 15.535 3.22647 15.6187 3.19858 15.7674C3.1614 15.7303 3.21717 15.6001 3.35662 15.5443C3.22647 15.4979 3.19858 15.6838 3.04055 15.6838C3.11492 15.5722 3.18929 15.3491 3.29154 15.1725L3.61691 15.0516L3.57972 14.9959C3.84931 14.9029 3.70987 14.8378 3.96086 14.6984C3.96086 14.6333 3.8586 14.6519 3.77494 14.6519C3.50535 15.0423 3.18929 14.9029 2.89181 15.1911C2.6873 15.1074 3.60761 14.4846 2.97548 14.717C2.9104 14.8099 2.60363 14.9215 2.77096 14.9494C2.73378 14.8285 2.39912 15.1353 2.4456 14.9215C2.64082 14.9029 2.70589 14.5775 2.99407 14.5497C2.88252 14.624 2.96618 14.6798 3.01266 14.6705C3.10562 14.5404 3.34732 14.4288 3.27295 14.3265C3.19858 14.2894 3.12421 14.215 2.96618 14.3544C2.78026 14.5032 3.05914 14.4288 2.83603 14.5404C2.678 14.4753 2.94759 14.2336 2.58504 14.4381C2.6687 14.4939 2.49208 14.6612 2.36193 14.7542L2.2132 14.7263L2.35264 14.6519C2.33405 14.4474 2.09235 14.7821 2.02727 14.624L2.22249 14.373C2.45489 14.2429 2.27827 14.6426 2.60363 14.3544C2.54786 14.2522 2.35264 14.3544 2.38053 14.2057C2.42701 14.2057 2.45489 14.2243 2.49208 14.215C2.48278 14.1778 2.9104 13.7967 2.54786 13.871C2.39912 13.8896 2.40841 13.9454 2.27827 14.0384C2.12953 13.9268 1.9715 13.9826 1.87854 13.9082C2.14812 13.7409 1.78558 13.7316 2.12024 13.6386C2.00868 13.7967 2.17601 13.9919 2.45489 13.8617C2.71519 13.5829 2.50138 14.0012 2.82674 13.806C2.75237 13.6851 3.04984 13.4713 3.22647 13.304C3.21717 13.2668 3.11492 13.2947 3.06844 13.304C2.87322 13.4248 2.9104 13.462 2.72448 13.6107C2.678 13.4434 2.49208 13.3969 2.25968 13.462C2.31545 13.3505 2.51067 13.2296 2.56645 13.2668C2.39912 13.1552 2.30616 12.9786 2.25968 12.7927C2.02727 13.1088 2.07376 12.6811 1.86924 12.9321C1.85995 13.0623 1.69262 13.2854 1.52529 13.3412C1.50669 13.2761 1.65543 13.2482 1.71121 13.1831C1.4974 13.2389 1.90643 12.8949 1.59965 13.0251C1.79487 13.0995 1.99009 12.7834 2.24108 12.644C2.03657 12.644 2.40841 12.5231 2.34334 12.4301C2.13883 12.4301 1.94361 12.3744 1.81346 12.3C1.94361 12.0025 1.56247 11.9375 1.46951 11.8166C1.54388 11.6679 1.85065 11.5284 1.84135 11.4262C1.77628 11.3425 1.59036 11.6865 1.62754 11.4819L1.69262 11.4541C1.59965 11.4541 1.7205 11.1008 1.30218 11.3239L1.62754 11.1659C1.62754 11.1659 1.55317 11.1473 1.51599 11.1473C1.60895 11.0822 1.68332 10.9985 1.76698 10.9892C1.92502 10.7754 1.62754 10.8498 1.56247 10.7661L1.42303 10.9335C1.19063 10.8777 1.30218 10.6639 1.15344 10.5616L1.33007 10.4594L1.17203 10.4408C1.35796 10.3571 1.42303 10.2177 1.2464 10.2549L1.81346 10.2084C1.74839 10.3292 1.56247 10.2735 1.41373 10.4129C1.28359 10.5337 1.41373 10.6453 1.59036 10.5523C1.58106 10.4873 1.53458 10.5152 1.45092 10.5152C1.68332 10.3478 1.7205 10.4315 1.90643 10.3664C1.87854 10.3478 1.93431 10.2642 1.85065 10.3106C1.99939 10.2827 2.05516 10.3292 2.11094 10.4036C1.98079 10.4036 1.98079 10.5337 1.89713 10.5523C2.11094 10.4222 2.23179 10.4594 2.24108 10.5988C2.04587 10.8312 2.52926 10.6825 2.53856 10.8498C2.29686 10.9428 2.08305 10.9985 1.95291 10.98C1.89713 11.1287 2.01798 11.0636 1.95291 11.2124C2.13883 11.138 2.38982 11.0078 2.55715 11.0357L2.40841 11.1473C2.54786 11.1845 2.78026 11.0171 2.80815 11.1566C2.86392 11.3983 3.00336 11.5935 3.08703 11.7515L2.93829 11.8631C3.31943 11.705 3.25436 12.0397 3.47746 12.0397C3.46817 12.3279 3.91438 12.3279 3.71916 12.6161C4.07241 12.8485 4.39778 13.0437 4.593 13.4062L4.3327 13.5178C4.53722 13.4527 4.23974 13.6479 4.31411 13.6851C4.43496 13.4806 4.60229 13.5922 4.76962 13.5271C4.71384 13.806 5.03921 13.8524 5.2902 13.8617L5.14146 13.9826C5.5226 13.8896 5.40176 14.2429 5.48542 14.4381C5.43894 14.5032 5.31809 14.6426 5.37387 14.6798C5.68064 14.5775 5.69923 14.6333 5.95022 14.6426C6.02459 14.7356 6.08967 14.9308 6.07107 15.1074C6.37784 15.1446 6.55447 15.3026 6.7125 15.47C6.80546 15.5722 6.84265 15.6094 6.87983 15.6373C6.92631 15.6652 6.98209 15.6838 7.05646 15.6745L6.92631 15.8697C7.14942 15.7674 7.1866 15.7953 7.24238 15.8883C7.28886 15.972 7.34464 16.1114 7.40971 15.9998L7.32605 16.4925C7.34464 16.7063 7.4283 16.4646 7.4469 16.0649C7.46549 16.2694 7.51197 15.8604 7.53056 16.3624C7.56774 16.5111 7.56774 16.13 7.57704 16.0649C7.60493 16.2137 7.63282 16.288 7.65141 16.3066C7.67 16.3066 7.67 16.2137 7.67 16.13V16.1021C7.67 16.2508 7.70719 16.5297 7.72578 16.5483C7.72578 16.4739 7.72578 16.4554 7.72578 16.4368C7.73507 16.3996 7.74437 16.3438 7.6607 15.8976C7.70719 16.0742 7.71648 15.9441 7.71648 15.8511C7.71648 15.7581 7.71648 15.6931 7.80944 15.879C7.75367 15.7303 7.75367 15.6931 7.71648 15.5908C7.72578 15.5536 7.9024 15.7488 7.80015 15.5071C7.84663 15.5536 7.9117 15.7117 7.93959 15.7024C7.921 15.6466 7.84663 15.5536 7.80944 15.4793C7.76296 15.3491 7.80944 15.377 7.89311 15.3956C7.93959 15.4607 8.19988 15.2747 8.27425 15.1353C8.47876 14.4753 9.01793 14.057 9.39907 13.6015L9.46415 13.6665C9.35259 13.2761 10.0405 13.5829 9.78021 13.1088C9.87317 13.1366 9.93825 13.0158 10.0312 13.1645C9.96614 12.8857 10.496 13.0251 10.4402 12.6532C10.4216 12.6532 10.4216 12.6811 10.4402 12.7276C10.7377 12.7183 10.6912 12.3837 10.9887 12.3558C10.998 12.4023 10.9887 12.4487 11.0445 12.5231C11.2304 12.5882 10.9329 12.0955 11.2676 12.3837C11.3048 12.3465 11.1467 12.1977 11.1281 12.2256C11.6115 12.0118 11.8161 11.4355 12.1321 11.0078C12.5876 10.9428 12.6434 11.5377 12.6434 11.0915C12.7178 11.138 12.5412 10.9521 12.6062 11.0171C12.6062 10.8498 13.071 11.2588 12.9688 11.0357C12.7643 10.8591 12.9037 10.887 12.8014 10.7661C13.0896 10.7383 13.2848 10.887 13.2848 10.6174L13.3685 10.729C13.257 10.292 13.5823 10.2827 13.4057 9.81794C14.2237 8.972 14.8838 8.03309 15.7111 7.24293C16.6221 6.56431 17.3193 5.69048 18.3419 5.13271C18.7881 5.24427 18.7974 5.21638 18.9183 4.9189C18.9462 4.97468 18.9462 4.99327 18.9926 5.02116C18.8067 4.77946 19.1321 4.86313 18.9647 4.62143C19.3273 4.38903 19.569 4.07296 19.8944 3.79408C19.8665 3.85915 19.9966 4.07296 20.0431 4.00789L19.978 3.80337L20.0431 3.85915C20.0524 3.78478 20.0059 3.63604 19.8944 3.59886C20.5544 2.69714 21.7722 2.47403 22.5437 1.73034C22.8226 1.66527 23.0178 1.34921 23.1945 1.1168C24.0776 0.902993 24.8492 0.689183 25.3047 -0.0545044C25.3047 -0.0545044 25.723 0.62411 25.5836 0.977361L25.5929 1.03314Z\" fill=\"#8F3A7E\"><\/path><path d=\"M1.7481 9.85501C1.62739 9.95715 1.59954 10.0778 1.38599 10.115C1.50669 10.0314 1.61811 9.91072 1.7481 9.85501Z\" fill=\"#8F3A7E\"><\/path><path d=\"M1.8506 12.8295C1.8506 12.8295 1.82275 12.8945 1.80418 12.9131C1.77632 12.8945 1.65562 12.9409 1.70204 12.8759C1.7299 12.8945 1.78561 12.8481 1.8506 12.8202V12.8295Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.16678 13.4147C2.05536 13.489 1.87895 13.4425 1.82324 13.3775L2.16678 13.4147Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.08289 14.2437C2.02718 14.3551 1.96219 14.383 1.92505 14.318C1.98076 14.2715 2.02718 14.2715 2.08289 14.2437Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.35372 14.0857C2.35372 14.0857 2.33511 14.188 2.28857 14.2625C2.38165 14.188 2.15827 14.216 2.35372 14.0857Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.84607 15.3857C2.84607 15.3857 3.00391 15.3857 2.90178 15.5064C2.96677 15.4135 2.66966 15.4878 2.84607 15.3857Z\" fill=\"#8F3A7E\"><\/path><path d=\"M3.39329 15.7397C3.39329 15.7397 3.384 15.7861 3.43043 15.7769C3.40257 15.8418 3.30044 15.879 3.27258 15.8604L3.39329 15.7397Z\" fill=\"#8F3A7E\"><\/path><path d=\"M11.9369 14.7541L11.9462 14.8467L11.8535 14.7448L11.9369 14.7541Z\" fill=\"#8F3A7E\"><\/path><path d=\"M15.4611 11.4917C15.4611 11.3803 15.5818 11.5567 15.6003 11.5659C15.5632 11.6124 15.5075 11.4267 15.4611 11.4917Z\" fill=\"#8F3A7E\"><\/path><path d=\"M16.957 9.2601L16.9477 9.27864L16.7716 9.06546L16.957 9.2601Z\" fill=\"#8F3A7E\"><\/path><path d=\"M26.4111 1.45928C26.4761 1.32929 26.2068 1.32001 26.4111 1.32001C26.4668 1.41286 26.5039 1.49642 26.4111 1.45928Z\" fill=\"#8F3A7E\"><\/path><path d=\"M1.08847 10.4673C1.92512 10.4673 1.62764 11.3319 2.27837 11.4713C2.33415 11.4992 1.95301 11.6851 2.10174 11.7316C2.81754 11.7967 2.97558 12.5682 2.97558 13.2747L2.86402 13.3119C2.86402 13.4514 3.23587 13.3305 3.26375 13.4514C3.20798 13.4979 3.1615 13.4886 3.09642 13.5629C3.29164 13.4514 3.30094 13.6652 3.45897 13.6094C3.42179 13.6931 3.27305 13.7953 3.23587 13.9069L3.47756 13.8046C4.06322 13.5908 3.70997 14.1765 4.1097 14.1858C4.05392 14.2137 4.00744 14.2229 3.97026 14.2694C4.50013 14.3624 4.75113 14.79 5.13227 15.0596C5.0486 15.0968 4.91846 15.1897 4.85338 15.2734C5.07649 15.1247 5.20664 15.1897 5.32749 15.2548C5.15086 15.4686 5.64355 15.2548 5.61566 15.4593L5.55989 15.4872C5.84807 15.3943 5.532 15.7103 5.84807 15.5616L5.72722 15.7475C6.05258 15.543 5.66214 15.9892 5.86666 15.9334L5.92244 15.8777C6.04328 15.8777 5.92244 16.0357 6.0154 16.0543L5.98751 16.0915C6.17343 16.1658 6.06188 16.361 6.28498 16.1658C6.14554 16.3703 6.10836 16.1193 5.90384 16.4168C6.4895 16.6492 6.74049 17.049 7.08445 17.458C7.08445 17.6532 7.11233 17.7369 7.10304 17.8949C7.14952 17.8577 7.25178 17.9879 7.30755 17.8112C7.29826 17.8112 7.30755 18.0529 7.33544 18.0994C7.40051 18.3504 7.4284 17.6997 7.48418 17.9786C7.45629 18.0715 7.4377 18.2017 7.44699 18.3783C7.52136 18.1087 7.59573 18.2482 7.6608 18.211C7.6608 18.2853 7.64221 18.3132 7.64221 18.462C7.69799 18.118 7.80024 18.7316 7.84673 18.527V18.7966C7.99546 19.2893 7.82813 18.276 7.9025 18.3783C7.9025 18.5084 7.92109 18.6107 7.93039 18.7408C7.93039 18.3597 7.93969 18.2017 7.96757 18.0715C7.98617 17.9693 8.01406 17.8949 8.02335 17.7648C8.02335 17.8019 8.04194 17.8763 8.04194 17.8763C8.07913 17.6904 8.17209 17.6904 8.19068 17.3743C8.24646 17.4208 8.33942 17.9414 8.39519 17.7183C8.23716 17.2628 8.46027 17.3 8.23716 16.9188C8.31153 16.8909 8.46956 16.8537 8.45097 16.6771C8.49745 16.8537 8.72056 17.0211 8.68337 17.1605C8.73915 17.207 8.79493 17.2535 8.86 17.3C8.94366 17.458 8.77633 17.3464 8.90648 17.5045C8.93437 17.4208 8.94366 17.1047 9.00874 17.1047C8.93437 16.8073 8.72985 16.4261 8.76704 16.2774C8.82282 16.4354 9.06451 16.5098 9.08311 16.5935C8.97155 16.3703 8.84141 16.1658 8.70197 15.9892C8.71126 15.9427 8.92507 16.1472 8.89718 16.0264C8.82281 15.9799 8.79493 15.9148 8.75774 15.8498C8.80422 15.8498 8.8507 15.5895 9.12959 15.7754C9.25043 15.8405 9.12959 15.8962 9.25973 15.9148C9.3248 15.8219 9.24114 15.7475 9.29692 15.6545L9.3341 15.6824C9.41776 15.6545 9.36199 15.4221 9.16677 15.3664C9.12029 15.4036 9.3341 15.4779 9.21325 15.4779C9.0924 15.3106 9.13888 15.1711 9.21325 15.0875C9.23184 15.1526 9.30621 15.2083 9.36199 15.2827C9.25043 14.9945 9.29692 14.8179 9.3341 14.6134C9.21325 14.5018 9.51073 14.8551 9.42706 14.8179C9.73383 14.7993 9.49213 14.2694 9.86398 14.3531C9.86398 14.3903 9.68735 14.2044 9.72454 14.2415C9.8082 14.1765 9.97553 14.3438 9.96623 14.2415C10.0685 14.3345 9.99412 14.1486 10.0127 14.0742C9.96623 13.9812 10.0778 14.1114 10.0406 14.1579C10.022 14.0091 10.1522 13.5815 10.4496 13.5629C10.3846 13.4979 10.3102 13.2283 10.3567 13.2004L10.4868 13.3677C10.6077 13.4235 10.5984 13.2376 10.7285 13.3584C10.6263 13.0981 10.5798 13.8139 10.5426 13.5629C10.6913 13.6652 10.4496 13.1725 10.6356 13.4049C10.7006 13.3305 10.6077 13.0888 10.8215 13.1632C10.775 13.1632 10.9609 13.4328 11.0167 13.3677C11.0911 13.2376 10.9795 13.2655 11.0167 13.1353V13.0238C10.868 12.8657 11.1282 12.9587 10.9237 12.8192C11.0539 12.9308 11.0074 12.5961 11.2305 12.8564L11.3978 13.0702C11.4257 13.0145 11.277 12.7913 11.2305 12.6705C11.2584 12.6798 11.3049 12.7077 11.3328 12.7449C11.0539 12.4381 11.4629 12.6705 11.3049 12.3823C11.5001 12.4009 11.5559 12.1685 11.779 12.308C11.7697 12.1499 11.7325 11.9733 11.8812 11.964C11.8905 12.0105 11.8812 12.0384 11.9277 12.1034C12.0671 12.1406 12.0021 12.0477 12.0021 11.9547C12.03 12.0105 12.2717 12.0384 12.4297 12.0848C12.4204 11.9268 12.2438 11.7874 12.1601 11.6758C12.5041 11.9175 12.188 11.2947 12.5227 11.4899C12.532 11.555 12.5505 11.7316 12.6807 11.7595C13.0246 12.0012 12.6156 11.4155 12.8573 11.462L12.597 11.2389C12.7829 11.3505 12.6249 10.9507 12.848 11.211C12.8015 11.0902 13.0525 11.1738 12.8201 10.9414C13.1827 10.9879 13.1455 10.4208 13.6475 10.7555C13.6382 10.6904 13.7404 10.6718 13.6103 10.5603C13.443 10.458 13.6382 10.709 13.5359 10.6347C13.5545 10.6068 13.4987 10.5324 13.4709 10.4952C13.5731 10.4952 13.6382 10.4766 13.7683 10.7276C14.0286 10.7648 13.5173 10.1977 13.7683 10.1513C13.852 10.2628 13.8985 10.2907 13.9357 10.2256L13.8706 9.97463C14.01 9.91886 14.1402 10.1513 14.2982 10.3279C14.3261 10.2535 14.4005 10.1977 14.3075 10.049L14.5678 10.207C14.3819 10.0955 14.5213 10.0583 14.5027 9.99323V10.0583C14.5864 10.1234 14.6143 10.0211 14.6236 9.97463C14.5213 9.87238 14.4191 9.89097 14.354 9.89097C14.3168 9.78871 14.3726 9.77012 14.3261 9.64927C14.4655 9.8259 14.5213 9.68646 14.5864 9.66786C14.6701 9.66786 14.5027 9.46335 14.5306 9.45405C14.6143 9.53772 14.6236 9.39828 14.6979 9.55631C14.6979 9.60279 14.5864 9.50983 14.6236 9.61209C14.7165 9.64927 14.8467 9.8073 14.8188 9.63068C14.7909 9.50053 14.5027 9.30532 14.6979 9.32391C14.7072 9.38898 14.763 9.46335 14.8002 9.53772H14.9675L14.8374 9.38898C14.8839 9.41687 14.8839 9.43546 14.9118 9.45405C14.7909 9.26813 15.0047 9.27743 14.8653 9.08221C14.8932 9.02643 15.0605 9.1008 15.1163 9.08221V9.1008C15.2557 9.14728 15.2743 9.01714 15.2278 8.8777L15.2557 8.91488C15.2557 8.91488 15.3487 8.81262 15.3022 8.69177C15.4788 8.73826 15.8414 9.25884 15.7577 8.98925C15.8321 8.91488 15.6276 8.59881 15.5067 8.52444C15.7391 8.50585 15.6647 8.11542 16.0087 8.24556C15.9715 8.1619 15.925 8.13401 15.9343 8.06894C16.1853 7.95738 16.1946 7.51117 16.6222 7.6785C16.6222 7.79935 16.7524 7.83653 16.836 7.92949C16.7617 7.74357 17.022 8.02246 16.836 7.77146C16.7059 7.63202 16.6501 7.55765 16.5479 7.55765C16.6036 7.38103 16.7803 7.22299 16.9662 7.29736C16.8732 7.26018 16.8639 7.1951 16.8546 7.13003C17.0406 7.36243 17.1614 7.31595 17.1614 7.18581L17.0499 7.03707L17.2172 7.13933C17.2079 7.07425 16.9941 6.82326 17.18 6.89763C17.2265 6.94411 17.2823 6.99989 17.3287 7.02777C17.3008 6.85115 17.2358 6.58156 17.4124 6.62804L17.6448 6.77678C17.6541 6.7303 17.6076 6.56297 17.5054 6.55367C17.7378 6.56297 17.8307 6.50719 18.0259 6.64664C17.8772 6.03309 18.1933 5.73562 18.4722 5.5497L18.5558 5.66125C18.7046 5.69843 18.435 5.44744 18.5558 5.47533C18.6209 5.59618 18.7882 5.64266 18.844 5.80999C19.0392 5.83788 18.8161 5.52181 18.844 5.41955C18.7417 5.27081 18.8626 5.5497 18.7324 5.36377C18.7046 5.308 18.9648 5.35448 18.7975 5.13137C18.8905 5.18715 19.002 5.35448 19.0578 5.45674L19.0299 5.308C19.3088 5.48462 19.2251 5.88436 19.5598 6.10746L19.5877 6.0238C19.8201 6.19113 19.6435 6.39564 19.848 6.34916C19.8201 6.20042 19.6156 5.85647 19.4854 5.80999C19.5598 5.64266 19.1229 5.27081 19.2809 5.16856C19.4204 5.26152 19.1972 5.28941 19.3646 5.43814C19.5691 5.5497 19.4111 5.23363 19.5226 5.24293C19.3925 5.21504 19.2716 4.96404 19.2809 4.88967C19.4297 4.92686 19.4018 5.12208 19.5133 5.057C19.4297 4.92686 19.4389 4.75953 19.2902 4.74094C19.095 4.44346 19.4575 4.73164 19.3367 4.47135C19.5319 4.62938 19.6063 4.99193 19.8015 5.00123C19.6249 4.8339 19.7271 4.63868 19.4389 4.41557C19.5226 4.43417 19.6528 4.57361 19.7178 4.71305C19.8759 4.77812 19.5784 4.25754 19.913 4.6015L19.7736 4.39698C19.848 4.44346 19.913 4.46205 20.0246 4.53642C20.0804 4.48994 19.9781 4.13669 20.2198 4.42487C20.2198 4.37839 20.3407 4.29472 20.1362 4.13669C19.9595 4.08091 20.1733 4.3505 19.9038 4.12739C20.1362 4.29472 19.9874 4.00655 19.9688 3.89499L20.0711 3.99725C20.0618 3.93218 20.1455 3.90429 20.0618 3.77414C20.099 3.85781 20.164 3.92288 20.2105 3.93218L20.099 3.74626C20.1362 3.56963 20.3686 4.01584 20.4336 3.8857L20.4615 4.08091C20.4615 4.08091 20.6196 4.16458 20.6288 4.07162C20.5266 3.90429 20.3964 3.69048 20.3221 3.56033C20.3221 3.44878 20.4894 3.70907 20.415 3.50456L20.4987 3.75555C20.5266 3.81133 20.759 3.96007 20.8334 3.89499C20.8334 3.80203 20.7311 3.51385 20.5824 3.49526C20.6196 3.45808 20.7497 3.50456 20.8148 3.644C20.8612 3.51385 20.666 3.48596 20.666 3.32793C20.7869 3.4023 21.0007 3.46737 21.1866 3.56033L21.3168 3.8857L21.3725 3.83922C21.4748 4.09951 21.5399 3.96936 21.6793 4.21106C21.7444 4.21106 21.7258 4.1088 21.7165 4.01584C21.3168 3.76485 21.4376 3.44878 21.1401 3.1606C21.2145 2.95609 21.8745 3.84851 21.6142 3.22567C21.5213 3.1606 21.3911 2.86313 21.3725 3.03046C21.4934 2.99327 21.168 2.66791 21.3818 2.70509C21.4097 2.90031 21.7351 2.95609 21.7816 3.23497C21.6979 3.12342 21.6514 3.20708 21.6607 3.25356C21.8002 3.34652 21.921 3.57893 22.014 3.49526C22.0419 3.42089 22.1162 3.34652 21.9675 3.18849C21.8095 3.01186 21.8931 3.28145 21.7816 3.06764C21.8373 2.90961 22.0883 3.1699 21.8652 2.80735C21.8187 2.89101 21.6421 2.72369 21.5399 2.59354L21.5585 2.4448L21.6421 2.57495C21.8466 2.54706 21.5027 2.32395 21.6514 2.24958L21.9117 2.43551C22.0511 2.66791 21.6514 2.50058 21.9489 2.81665C22.0419 2.76087 21.9303 2.56565 22.079 2.58424C22.079 2.63072 22.0697 2.65861 22.079 2.6958C22.1162 2.6772 22.516 3.09553 22.423 2.74228C22.4044 2.59354 22.3393 2.61213 22.2371 2.48199C22.3393 2.33325 22.2743 2.17522 22.3393 2.08226C22.5253 2.34255 22.5067 1.98 22.6275 2.30536C22.4602 2.2031 22.2836 2.37973 22.4323 2.64932C22.7205 2.89101 22.2928 2.6958 22.5067 3.01186C22.6182 2.9282 22.8506 3.21638 23.0272 3.38371C23.0644 3.37441 23.0272 3.27215 23.0272 3.22567C22.8971 3.03975 22.8599 3.07694 22.7019 2.90031C22.8599 2.84453 22.8971 2.64932 22.8227 2.42621C22.9343 2.48199 23.0644 2.66791 23.0365 2.72369C23.1388 2.55636 23.3061 2.4448 23.4827 2.38903C23.1574 2.17522 23.5757 2.19381 23.3247 2.00789C23.1946 2.00789 22.9715 1.84985 22.8971 1.69182C22.9622 1.67323 22.9994 1.82196 23.0737 1.85915C22.9994 1.65464 23.3712 2.03577 23.2225 1.7383C23.1667 1.94281 23.4827 2.11014 23.6501 2.35184C23.6408 2.14733 23.7802 2.50988 23.8732 2.43551C23.8639 2.23099 23.8918 2.03577 23.9568 1.90563C24.2636 2.00789 24.2915 1.63604 24.4031 1.52449C24.5611 1.58956 24.7284 1.87774 24.8307 1.85915C24.905 1.78478 24.5425 1.63604 24.7563 1.65464L24.7842 1.71041C24.7656 1.62675 25.1375 1.71041 24.8679 1.31068L25.0631 1.61745C25.0631 1.61745 25.0724 1.54308 25.0631 1.5059C25.1374 1.58956 25.2304 1.65464 25.2397 1.7383C25.4721 1.86845 25.3606 1.58027 25.4349 1.51519L25.249 1.39434C25.2769 1.15265 25.5 1.24561 25.5744 1.07828L25.7045 1.23631V1.07828C25.8068 1.24561 25.9648 1.29209 25.8997 1.12476L26.0299 1.67323C25.8997 1.62675 25.9276 1.43153 25.7696 1.30138C25.6301 1.18983 25.5465 1.32927 25.6487 1.4966C25.7045 1.47801 25.6859 1.44083 25.6673 1.35716C25.8625 1.56167 25.7882 1.61745 25.8811 1.78478C25.8997 1.75689 25.9834 1.79408 25.9369 1.71971C25.9834 1.86845 25.9462 1.92422 25.8718 1.98929C25.8532 1.85915 25.7324 1.87774 25.6952 1.79408C25.8532 1.98929 25.8254 2.11014 25.6859 2.13803C25.4349 1.9707 25.6301 2.43551 25.4628 2.46339C25.342 2.23099 25.2676 2.02648 25.2676 1.88704C25.1189 1.84985 25.1932 1.96141 25.0445 1.91493C25.1375 2.09155 25.2955 2.33325 25.2769 2.50058L25.1467 2.36114C25.1282 2.50058 25.3048 2.71439 25.1653 2.77017C24.9236 2.84453 24.7377 3.00257 24.589 3.09553L24.4588 2.95609C24.6448 3.32793 24.3008 3.28145 24.3101 3.50456C24.0219 3.50456 24.0498 3.96007 23.7523 3.78344C23.5385 4.15528 23.3619 4.48994 22.9994 4.70375L22.8785 4.45276C22.9529 4.65727 22.7391 4.3598 22.7112 4.44346C22.9157 4.55502 22.8134 4.72234 22.8878 4.88967C22.6089 4.84319 22.581 5.17785 22.5717 5.42885L22.4416 5.28941C22.5438 5.67055 22.1906 5.55899 21.9954 5.64266C21.9303 5.59618 21.7816 5.48462 21.7537 5.5404C21.8652 5.84717 21.8095 5.86576 21.8002 6.11676C21.7072 6.19113 21.512 6.2655 21.3446 6.2469C21.2796 6.86974 20.7497 6.95341 20.5638 7.4554L20.3964 7.30666C20.3593 7.95738 19.6528 7.99457 19.5226 8.44078L19.2995 8.12471C19.1322 8.12471 19.1508 8.385 19.3553 8.56163C19.188 8.56163 19.2437 8.89629 18.9834 8.71037C18.844 8.73825 18.9834 8.94277 18.937 9.04503C18.6581 9.1008 18.6023 9.18447 18.4722 9.38898L18.5279 9.37039C18.4907 9.28672 18.3885 9.16588 18.3327 9.18447C18.3327 9.32391 18.0259 9.31461 18.3885 9.60279C18.0259 9.56561 18.091 10.1513 17.6727 10.0397C17.7657 10.1234 17.7378 10.1791 17.7749 10.2535C17.6169 10.4023 17.273 10.3651 17.2823 10.644C17.2172 10.6161 17.1893 10.4487 17.1056 10.4952C17.1056 10.5696 17.2079 10.6161 17.2079 10.709C17.0963 11.1181 16.5107 11.0065 16.3062 11.2668C16.0366 11.8246 15.5067 12.1406 15.1349 12.5404L15.0791 12.466C15.172 12.8471 14.5213 12.4939 14.763 12.9773C14.6701 12.9401 14.6143 13.0609 14.5213 12.9122C14.5771 13.1911 14.0658 13.0238 14.1123 13.3956C14.1309 13.3956 14.1309 13.3677 14.1123 13.3212C13.8148 13.3212 13.8706 13.6466 13.5731 13.6745C13.5638 13.628 13.5731 13.5815 13.5173 13.5071C13.3314 13.4421 13.6289 13.9255 13.2942 13.6373C13.257 13.6745 13.4151 13.8232 13.4337 13.7953C12.9503 14.0091 12.7551 14.5762 12.4669 14.9945C12.03 15.0596 11.937 14.4832 11.9649 14.9109C11.8905 14.8644 12.0671 15.041 12.0021 14.9759C12.0021 15.134 11.5373 14.7528 11.6488 14.9666C11.8626 15.134 11.7232 15.1061 11.8347 15.2269C11.5559 15.2548 11.3514 15.1247 11.3792 15.385L11.2863 15.2734C11.435 15.6917 11.1282 15.7196 11.3606 16.1472C11.2026 16.361 11.0539 16.5749 10.9237 16.7887L10.4403 17.6625C9.91975 18.5456 9.60369 20.0423 9.12029 21.4367C8.99014 21.7993 8.8507 22.1618 8.72056 22.5151L8.33942 22.0874L7.89321 21.5762L7.00078 20.5536C6.41513 19.8657 5.80159 19.1127 5.281 18.3225C5.20664 17.6439 5.20664 17.6625 4.77902 17.3743C4.83479 17.3464 4.86268 17.365 4.89057 17.3C4.76972 17.3929 4.70465 17.3185 4.64887 17.2628C4.61169 17.2256 4.5745 17.1791 4.45365 17.2628C4.23055 16.9002 3.92378 16.6399 3.64489 16.296C3.70997 16.3332 3.93307 16.203 3.868 16.1472L3.66349 16.203L3.71926 16.1379C3.64489 16.1193 3.49616 16.1658 3.44968 16.2774C2.55725 15.5709 2.37133 14.3345 1.66483 13.5071C1.60905 13.219 1.30228 12.9959 1.08847 12.8006C0.930435 11.8617 0.790994 11.0902 0.0751953 10.4116C0.0751953 10.4116 0.828178 10.1513 1.16284 10.3558L1.08847 10.4673Z\" fill=\"#8F3A7E\"><\/path><path d=\"M26.3094 1.58132C26.1885 1.47901 26.0676 1.47901 25.9932 1.27438C26.0955 1.3767 26.235 1.46971 26.3094 1.58132Z\" fill=\"#8F3A7E\"><\/path><path d=\"M23.3623 1.9979C23.3623 1.9979 23.2973 1.97005 23.2695 1.96076C23.288 1.93291 23.223 1.8122 23.2973 1.85863C23.2787 1.88648 23.3345 1.94219 23.3623 1.9979Z\" fill=\"#8F3A7E\"><\/path><path d=\"M22.8039 2.34232C22.7203 2.2309 22.7574 2.06377 22.8131 1.99878V2.34232H22.8039Z\" fill=\"#8F3A7E\"><\/path><path d=\"M21.9853 2.29645C21.8739 2.24074 21.846 2.18504 21.9018 2.13861C21.9482 2.19432 21.9575 2.23146 21.9853 2.29645Z\" fill=\"#8F3A7E\"><\/path><path d=\"M22.1544 2.56585C22.1544 2.56585 22.052 2.55654 21.9775 2.51001C22.052 2.59377 22.0241 2.37971 22.1544 2.56585Z\" fill=\"#8F3A7E\"><\/path><path d=\"M20.8979 3.10465C20.8979 3.10465 20.8979 3.26249 20.7772 3.16965C20.8701 3.22535 20.7772 2.93752 20.8979 3.10465Z\" fill=\"#8F3A7E\"><\/path><path d=\"M20.5632 3.65382C20.5632 3.65382 20.5168 3.65382 20.5261 3.69096C20.4611 3.6631 20.424 3.57025 20.4425 3.53311L20.5632 3.65382Z\" fill=\"#8F3A7E\"><\/path><path d=\"M12.5693 11.3684V11.275L12.6534 11.3871L12.5693 11.3684Z\" fill=\"#8F3A7E\"><\/path><path d=\"M9.03711 14.8652C9.05568 14.9767 8.90712 14.8188 8.88855 14.8188C8.9164 14.7631 8.99997 14.9488 9.03711 14.8652Z\" fill=\"#8F3A7E\"><\/path><path d=\"M8.21887 17.2635V17.2357L8.33029 17.5885L8.21887 17.2635Z\" fill=\"#8F3A7E\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Automatic Tax Calculations<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"27\" height=\"23\" viewBox=\"0 0 27 23\" fill=\"none\"><path d=\"M26.5504 1.48711C26.5133 1.41296 26.3928 1.2832 26.3743 1.33881L26.5411 1.59833V1.48711H26.5504Z\" fill=\"#8F3A7E\"><\/path><path d=\"M25.9092 1.28207C25.9556 1.43991 26.067 1.68132 26.2806 1.8763C26.1413 1.60704 26.2342 1.69061 26.0577 1.3842C26.0763 1.31921 26.197 1.40277 26.262 1.49562C26.2249 1.42134 26.3734 1.49562 26.262 1.32849C26.0577 1.18922 25.9835 1.23565 26.0392 1.4492C25.9835 1.41206 25.9463 1.33778 25.9092 1.29136V1.28207Z\" fill=\"#8F3A7E\"><\/path><path d=\"M19.0215 6.23586C19.0215 6.23586 19.0215 6.18064 19.0031 6.16223C19.0031 6.18984 19.0031 6.21746 19.0215 6.23586Z\" fill=\"#8F3A7E\"><\/path><path d=\"M18.3794 6.34023C18.3794 6.34023 18.4077 6.34023 18.4171 6.34023C18.3888 6.3308 18.37 6.32138 18.3794 6.34023Z\" fill=\"#8F3A7E\"><\/path><path d=\"M21.5952 4.26723L21.465 4.24863C21.5208 4.33234 21.5487 4.27653 21.5952 4.26723Z\" fill=\"#8F3A7E\"><\/path><path d=\"M25.8363 2.31298C25.8363 2.31298 25.8363 2.25752 25.8178 2.22055C25.8178 2.23904 25.8178 2.25752 25.8086 2.27601L25.8363 2.31298Z\" fill=\"#8F3A7E\"><\/path><path d=\"M22.5358 3.16046L22.5544 3.14186C22.5544 3.14186 22.5172 3.07675 22.4893 3.03024L22.5358 3.16046Z\" fill=\"#8F3A7E\"><\/path><path d=\"M23.3447 2.4166C23.3447 2.4166 23.4749 2.63052 23.5493 2.72353C23.4935 2.63052 23.4749 2.58401 23.4749 2.54681C23.447 2.50961 23.4005 2.4631 23.3447 2.4166Z\" fill=\"#8F3A7E\"><\/path><path d=\"M21.8932 3.61673C21.8932 3.61673 21.8372 3.56072 21.8279 3.55139C21.8465 3.57939 21.8745 3.59806 21.8932 3.61673Z\" fill=\"#8F3A7E\"><\/path><path d=\"M0.799326 11.6575C0.799326 11.6575 0.827596 11.6386 0.837019 11.6292C0.808749 11.6292 0.789903 11.648 0.799326 11.6575Z\" fill=\"#8F3A7E\"><\/path><path d=\"M1.21851 9.87102L1.24636 9.8803L1.37635 9.81531L1.21851 9.87102Z\" fill=\"#8F3A7E\"><\/path><path d=\"M10.5801 13.1525C10.8215 13.2453 10.6636 13.4868 10.9608 13.561C10.8772 13.496 10.7843 13.1711 10.5801 13.1525Z\" fill=\"#8F3A7E\"><\/path><path d=\"M25.7896 2.30579C25.7896 2.30579 25.7708 2.32463 25.752 2.33406C25.7708 2.33406 25.7802 2.31521 25.7896 2.30579Z\" fill=\"#8F3A7E\"><\/path><path d=\"M15.7295 8.4028C15.7295 8.4028 15.7942 8.45826 15.8219 8.47674C15.8034 8.45826 15.7757 8.43977 15.7295 8.4028Z\" fill=\"#8F3A7E\"><\/path><path d=\"M15.2939 9.27798C15.2939 9.27798 15.2285 9.25931 15.2285 9.30598C15.2378 9.30598 15.2472 9.31531 15.2565 9.32465C15.2378 9.28731 15.2379 9.26865 15.2939 9.27798Z\" fill=\"#8F3A7E\"><\/path><path d=\"M14.5957 9.90973C14.5957 9.90973 14.6241 9.92869 14.6431 9.93817V9.90973H14.5957Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.6049 13.9609C2.65136 13.8959 2.7071 13.8401 2.76285 13.7844C2.62348 13.9051 2.48412 13.8401 2.6049 13.9609Z\" fill=\"#8F3A7E\"><\/path><path d=\"M25.7432 2.19324C25.7802 2.24883 25.7988 2.27662 25.7895 2.29515L25.808 2.26736C25.808 2.26736 25.7617 2.21177 25.7432 2.19324Z\" fill=\"#8F3A7E\"><\/path><path d=\"M16.6315 10.8466L16.4922 10.9116C16.5386 10.9116 16.585 10.8745 16.6315 10.8466Z\" fill=\"#8F3A7E\"><\/path><path d=\"M7.79133 20.2916H7.76367C7.76367 20.2916 7.79133 20.3285 7.79133 20.2916Z\" fill=\"#8F3A7E\"><\/path><path d=\"M16.1947 11.2389C16.1111 11.1924 16.0554 11.1645 16.0089 11.1552C16.0089 11.1738 16.0275 11.1924 16.0368 11.2203L16.1854 11.2389H16.1947Z\" fill=\"#8F3A7E\"><\/path><path d=\"M1.95357 13.227C1.75835 13.1898 1.98146 13.1526 2.08371 12.9109C1.81413 13.0132 2.08371 12.7343 1.70258 12.9946C1.91639 12.7808 1.83272 12.8551 1.96287 12.6599C1.78624 12.8366 1.66539 12.6599 1.42369 12.8458C1.67469 12.6227 1.85131 12.725 2.06512 12.4275C1.83272 12.4926 1.68398 12.4275 1.37721 12.6227C1.4051 12.5205 1.49806 12.4275 1.47947 12.3253C1.47017 12.3532 1.53525 12.3253 1.57243 12.316C1.27496 12.316 1.33073 11.972 0.912408 12.1393C1.36792 11.8698 0.76367 11.7954 1.23777 11.6281C1.18199 11.5816 0.931 11.6095 0.838039 11.6374C1.18199 11.4143 0.828743 11.4328 0.986776 11.2283C0.772966 11.3213 0.76367 11.1633 0.614933 11.1726C0.680005 11.1726 0.745078 11.154 0.828743 11.0889C0.642821 11.0982 0.782262 11.0331 0.912408 10.8658C0.745078 10.8286 0.661413 11.0517 0.456899 11.0889C0.475491 10.9494 0.670709 10.9401 0.800854 10.8379L0.363938 10.9216C0.38253 10.8751 0.438307 10.81 0.531268 10.7449C0.401123 10.7542 0.224497 10.8007 0.354642 10.6334L0.438307 10.7449L0.59634 10.5962H0.280273C0.429011 10.2244 0.856631 10.0849 1.24707 9.88969L1.35862 9.92688C1.48877 9.85251 1.53525 9.75955 1.51665 9.72236C1.59102 9.64799 2.00005 9.61081 2.08371 9.65729C2.17668 9.8804 1.67469 9.95476 1.66539 10.1593L2.00005 10.2151L1.8792 10.2987C1.81413 10.3824 1.96287 10.3173 2.00005 10.2987C1.80483 10.401 2.03723 10.4939 2.05583 10.5869L2.19527 10.4568C2.70655 10.4196 2.01864 11.0517 2.33471 11.0982L2.67866 11.0331L2.46485 11.219C2.65078 11.1911 2.8367 11.0796 2.8367 11.2469C2.70655 11.9255 3.50602 11.9999 3.5525 12.5763C3.59898 12.5391 3.59898 12.5112 3.61757 12.4647C3.3108 13.2363 4.59366 12.567 4.39844 13.2084L4.29618 13.2549C4.46351 13.3757 4.19393 13.3014 4.15674 13.5059C4.44492 13.3199 4.51929 13.5431 4.68662 13.5616C4.62155 13.5895 4.60295 13.5616 4.53788 13.5616C4.4914 13.6267 4.33337 13.7569 4.41703 13.7662C4.88184 13.5709 5.01198 13.8126 5.24438 13.8777C5.08635 14.0357 5.03058 14.296 4.80747 14.5935C4.88184 14.5563 5.03987 14.482 5.1979 14.4076C5.13283 14.5563 5.25368 14.5284 5.38383 14.4913C5.33735 14.4448 5.30016 14.3983 5.27227 14.3704H5.29087C5.29087 14.3704 5.26298 14.3611 5.25368 14.3518C5.2165 14.3239 5.1979 14.3146 5.18861 14.3332C5.30946 14.138 5.32805 14.231 5.53256 14.0636C5.56975 14.1194 5.71849 14.1752 5.57904 14.3053C5.59764 14.3425 5.59764 14.3797 5.57904 14.4355C5.62552 14.4355 5.66271 14.4355 5.66271 14.4727H5.63482C5.63482 14.4727 5.59764 14.5284 5.57904 14.547C5.57904 14.7144 5.98807 14.6121 6.20188 14.5842C5.87652 14.7051 5.9323 14.8352 5.73708 14.9839C5.75567 14.9839 5.6906 14.8724 5.58834 14.7423C5.57904 14.7701 5.55116 14.798 5.48608 14.8538C5.37453 15.1234 5.81145 14.9003 5.80215 15.1792C5.77426 15.1792 5.70919 15.1978 5.65341 15.2628C5.65341 15.3651 5.83933 15.3 5.96018 15.2164C5.79285 15.3744 5.75567 15.6068 5.88582 15.5975C6.08103 15.5324 6.14611 15.4673 6.20188 15.5789L6.03455 15.644C6.01596 15.8485 6.29484 15.5882 6.26695 15.7648C6.28555 15.6905 6.14611 15.7927 6.14611 15.8392C6.31344 15.895 6.3971 15.8578 6.70387 15.709L6.49936 15.8671C6.67598 15.8485 6.97346 15.6997 6.73176 15.9693C7.08501 15.551 7.00135 15.8485 7.03853 15.9043C7.01994 15.9043 6.95487 15.9972 6.91768 16.053C7.18727 15.8113 7.05712 16.211 7.15938 16.3133L7.03853 16.7874C7.1036 16.8432 7.3453 15.9136 7.36389 15.96L7.30812 16.1831C7.38249 16.1831 7.40108 16.2482 7.44756 16.4063L7.41967 16.7874C7.45685 16.6387 7.48474 16.6758 7.50333 16.5085C7.52193 17.0291 7.587 16.9826 7.63348 16.9175C7.66137 16.8804 7.67996 16.8711 7.70785 16.9175C7.72644 16.9175 7.75433 17.0012 7.81011 17.2522L7.69855 16.4248C7.69855 16.4248 7.69855 16.4063 7.69855 16.397C7.70785 16.3505 7.71714 16.3226 7.81011 16.7409C7.91236 17.3173 7.83799 16.6944 7.87518 16.7874C7.87518 16.6944 7.80081 16.3319 7.77292 16.2482C7.91236 16.462 7.88447 15.9972 8.16336 16.3784C8.18195 16.0437 7.96814 15.6626 8.0611 15.6161L8.10758 15.6533C8.10758 15.6533 8.20054 15.6626 8.2935 15.6905C8.40506 15.6905 8.55379 15.7183 8.72112 15.8392C8.79549 15.5882 8.44224 15.1048 8.78619 14.9932L8.86986 15.142C8.98141 15.142 8.90704 14.9189 8.88845 14.8631C8.91634 14.8445 8.96282 14.9189 9.00001 14.9561C9.14874 14.9932 9.0093 14.8166 9.0186 14.7515L9.11156 14.8631C9.47411 14.8631 9.30678 14.231 9.56707 14.0543C9.56707 14.1194 9.68792 14.2031 9.75299 14.2403C9.50199 13.8405 9.81806 13.6639 9.83665 13.5059L9.91102 13.6825C9.87384 13.3014 10.3944 13.8684 10.3572 13.4873L10.0784 13.3943C10.1992 13.3757 10.1992 13.2642 10.0412 13.134C10.2271 13.1619 10.2922 13.3757 10.4502 13.2828C10.5432 13.3664 10.4223 13.4315 10.5803 13.5059L10.9801 13.5895C10.9801 13.5895 11.0358 13.5895 11.0637 13.5152C10.6547 13.1154 11.1846 13.3571 10.7105 13.0411C10.9243 12.7808 11.3798 12.8644 11.4077 12.4833C11.8725 12.8087 11.826 12.1208 12.2908 12.6599C12.4117 12.5577 12.4117 12.3625 12.2908 12.0929C12.2257 12.0743 12.2629 12.1672 12.2629 12.2137C12.17 12.0557 12.2908 11.8976 12.3466 11.8512C12.3838 12.0371 12.3466 12.2602 12.4767 12.5112C12.5325 12.3625 12.5046 12.0278 12.4953 11.9162L12.7742 12.1579C12.6813 11.8791 13.0531 12.3067 12.8951 11.9627L12.8021 11.8976C12.9787 11.7675 12.737 11.4979 12.8579 11.3213L12.9508 11.4328C13.0438 11.4328 12.8858 11.1075 13.1647 11.3027L13.0717 11.405C13.2576 11.5816 13.4064 11.6002 13.5272 11.6652C13.583 11.5165 13.2855 11.3213 13.3134 11.2469C13.4993 11.405 13.4064 11.3399 13.5272 11.5444C13.583 11.3771 13.6759 11.154 13.5551 10.8472C13.583 10.8751 13.6202 10.9123 13.6202 10.9123C13.7689 10.8286 13.5923 10.4103 13.7968 10.4939V10.5404C14.1314 10.717 13.8247 10.0663 14.2523 10.4939C14.3731 10.5311 14.1314 10.5683 14.401 10.7263C14.6706 10.7356 14.1593 10.2615 14.401 10.2708C14.3731 10.2708 14.401 10.2987 14.4289 10.3452C14.5126 10.2522 14.5963 10.0942 14.6613 9.95476C15.1168 10.2058 14.9681 9.51785 15.498 9.81532C15.3121 9.70377 15.3771 9.61081 15.3213 9.53644C15.3213 9.53644 15.3492 9.58292 15.3771 9.60151C15.4422 9.56433 15.3213 9.41559 15.2842 9.34122C15.4422 9.43418 15.3028 9.07164 15.4143 9.12741C15.3306 9.03445 15.3957 9.01586 15.4422 8.97867C15.4422 9.17389 15.5909 9.21108 15.6839 9.397C15.8698 9.32263 15.4794 8.82994 15.6839 8.77416L15.9256 8.88571C15.7025 8.59754 15.9349 8.58824 15.8419 8.48598C15.9442 8.55105 16.0279 8.56965 16.1394 8.70909C16.1394 8.58824 16.3532 8.65331 16.2324 8.46739L16.1115 8.4488C16.3904 8.39302 16.1487 7.90033 16.4555 7.95611L16.818 8.37443C17.0597 8.45809 16.7901 7.99329 17.0969 8.17921C16.9482 8.06766 16.9761 8.11414 16.9203 7.91892C16.8552 7.91892 16.8831 8.08625 16.8273 8.13273L16.7436 7.77948L16.6507 8.06766C16.5949 7.83526 16.6228 7.87244 16.4462 7.74229C16.4462 7.5006 16.7529 7.82596 16.7251 7.56567C16.818 7.58426 16.9017 7.77018 17.0225 7.81666C16.9946 7.58426 17.478 7.94681 17.3572 7.65863C17.4223 7.67722 17.3293 7.70511 17.413 7.79807C17.4409 7.70511 17.5059 7.67722 17.413 7.53778H17.32C17.3758 7.50989 17.2363 7.33327 17.4223 7.35186C17.3944 7.21242 17.2456 6.98002 17.1899 7.0265C17.1899 6.98002 17.3386 7.04509 17.4316 7.18453C17.5803 7.06368 17.1155 6.68254 17.4316 6.75691C17.4316 6.7755 17.4316 6.81269 17.4687 6.83128C17.5338 6.83128 17.5617 6.80339 17.5617 6.75691C17.4687 6.90565 17.8871 7.05438 17.6733 7.11016C17.8778 7.31467 17.822 7.05438 17.9428 7.11016C17.8871 6.89635 17.6733 6.7848 17.6175 6.64536C17.6733 6.71972 17.7104 6.69184 17.7662 6.69184L17.5896 6.5524C17.5896 6.5524 17.6547 6.50591 17.6547 6.43155V6.5524C17.7476 6.52451 18.073 6.71043 18.0544 6.44084C18.0823 6.5338 18.1381 6.71973 18.2868 6.74761C18.324 6.5338 18.3798 6.79409 18.5564 6.85917C18.6493 6.71043 18.324 6.5431 18.5936 6.48732C18.6122 6.46873 18.5099 6.38507 18.4541 6.35718C18.6493 6.32929 18.6215 6.15266 18.8446 6.17126C18.7516 6.17126 18.6586 6.15266 18.6679 6.01322C18.7516 6.18055 18.8817 6.0597 19.0026 6.09689L18.9468 6.00393C19.0584 6.0597 19.0491 6.13407 19.0491 6.18985C19.0212 6.16196 18.9933 6.14337 18.9747 6.17126C18.9747 6.2921 19.2722 6.58958 19.393 6.5431C19.4302 6.37577 19.2164 6.16196 19.1327 6.09689C19.3466 6.069 18.9282 5.60419 19.1792 5.62279C19.2071 5.5949 19.5975 5.84589 19.7184 5.79941C19.6068 5.56701 19.4767 5.75293 19.393 5.54842C19.9601 5.89237 19.4674 4.97206 19.9229 5.08361L20.0995 5.3439C20.1646 5.31602 20.2204 5.29742 20.2576 5.22305L20.0809 5.15798C20.0809 5.06502 20.239 5.00924 20.3505 5.22305C20.2948 4.93488 20.4156 5.02784 20.5736 5.00924C20.4528 5.08361 20.5457 4.98136 20.5736 5.16728C20.7874 5.18587 20.7317 5.10221 20.7596 4.98136C20.8153 5.07432 20.9641 5.16728 21.0013 5.13939C20.9455 4.92558 21.1035 4.85121 21.1407 4.68388L21.1965 4.75825C21.2894 4.52585 21.7542 4.69318 21.7542 4.33993C21.7542 4.33993 21.7542 4.33063 21.7542 4.32133H21.7264C21.4754 4.14471 21.7264 4.05175 21.7078 3.91231C21.7635 3.95879 21.8565 4.05175 21.8844 4.02386C21.7078 3.81005 21.8565 3.85653 21.8007 3.73568C21.9216 3.75427 22.0052 3.99597 22.0982 3.89371C22.1261 3.83794 22.0331 3.72638 21.968 3.65202C22.0796 3.73568 22.219 3.77286 22.2934 3.74498C22.3213 3.81934 22.2283 3.77286 22.2283 3.79146C22.312 3.91231 22.3213 3.83794 22.4329 3.97738C22.4979 3.94949 22.2841 3.76357 22.405 3.79146L22.4886 4.00527C22.5444 4.02386 22.5165 3.9309 22.5258 3.91231C22.5258 3.98667 22.6746 4.14471 22.7582 4.23767C22.7954 3.99597 22.4143 3.76357 22.2655 3.57765C22.5072 3.59624 22.4236 3.28947 22.5165 3.19651L22.6653 3.41032C22.6931 3.33595 22.6746 3.27088 22.6281 3.17791L22.7024 3.11284C22.721 3.22439 22.7582 3.29876 22.8791 3.4568C22.9163 3.33595 23.0743 3.28947 22.8791 3.01058L22.9163 3.05707C23.1022 3.05707 23.3811 2.92692 23.4461 3.01988C23.4926 2.83396 23.7715 2.86185 23.5577 2.60156C23.5763 2.48071 24.0225 2.78748 23.7994 2.41564C24.0225 2.51789 23.8645 2.48071 23.9946 2.69452C24.2177 2.79677 23.9388 2.28549 24.2828 2.63874C24.2828 2.44352 24.1991 2.58296 24.0876 2.38775C24.3943 2.71311 24.3107 2.29479 24.571 2.41564C24.4966 2.23901 24.4594 2.35986 24.4036 2.15534C24.4687 2.24831 24.5245 2.22971 24.5431 2.22971L24.3757 1.99731L24.9149 2.45282C24.8405 2.08098 24.571 2.09957 24.6732 1.84857V1.87646C24.9149 2.06238 24.6732 1.59758 24.9428 1.66265C24.8591 1.66265 25.0079 1.7835 25.0451 1.85787V1.70913C25.0451 1.70913 25.0544 1.74632 25.0822 1.76491C25.2868 1.87646 25.0636 1.62547 25.2589 1.70913C25.2403 1.7928 25.3983 1.95083 25.482 2.00661L25.3797 1.67195L25.5842 2.00661C25.7051 1.94153 25.4727 1.33729 25.8631 1.69984L25.8445 1.7835C25.9096 1.84857 26.1234 2.04379 26.0676 1.82998C26.0676 1.7742 25.9282 1.58828 25.9096 1.62547L26.0211 1.65336C26.1513 1.86717 26.0676 2.0345 26.0304 2.15534C25.9933 2.05309 26.0026 1.94153 25.8817 1.82998C25.8631 1.95083 25.9003 2.14605 25.8817 2.2669C25.8445 2.16464 25.7609 2.0252 25.7051 1.94153C25.5377 1.90435 25.7609 2.12746 25.7051 2.19253C25.6214 2.13675 25.5563 2.09957 25.5192 2.0252C25.5192 2.16464 25.4634 2.23901 25.3053 2.20182C25.3053 2.20182 25.2775 1.98801 25.138 1.91365C25.0915 2.15534 25.2589 2.41564 25.2124 2.67593C25.3053 3.15003 24.6918 2.76889 24.7662 3.11284C24.8312 3.2058 24.9893 3.18721 24.9521 3.30806C24.822 3.12214 24.8127 3.23369 24.7476 3.16862C24.8684 3.49398 24.571 3.2244 24.6546 3.4475C24.6174 3.37313 24.5059 3.35454 24.4222 3.31736C24.2549 3.09425 24.2549 3.31736 24.1247 2.89903C24.2642 3.33595 23.818 3.01988 24.134 3.59624L24.2177 3.62413H23.9946L24.0039 3.63342C23.9202 3.64272 23.9574 3.70779 23.6878 3.54976C23.6785 3.46609 23.725 3.42891 23.7157 3.34524C23.4833 3.2151 23.6971 3.63342 23.6321 3.70779C23.5019 3.54976 23.6692 3.58694 23.4833 3.41032C23.4089 3.42891 23.4554 3.58694 23.4368 3.6799L23.3718 3.58694C23.065 3.50328 23.6785 4.06104 23.3253 3.85653C23.3718 3.90301 23.4089 3.96808 23.4554 4.01456C23.3439 3.95879 23.1208 3.87512 23.1208 3.6892C23.0743 3.72638 23.0836 3.85653 23.1394 3.96808C23.2881 4.06104 23.2416 3.98667 23.3996 4.13541L23.2788 4.38641C23.2788 4.38641 23.223 4.28415 23.2509 4.26556C22.6374 3.99597 23.1115 5.04643 22.3864 4.71177C22.5351 4.83262 22.47 4.85121 22.5258 4.97206C22.405 4.99995 22.312 5.13939 22.154 5.1208L22.0982 4.99995C21.9959 5.28813 21.9866 5.55771 21.81 5.60419C21.8379 5.65067 21.6892 5.46475 21.6892 5.41827C21.7449 5.67856 21.15 5.21376 21.4382 5.61349H21.5032C21.2615 5.71575 21.2708 6.16196 21.1221 6.37577C20.8897 6.18985 21.2151 6.25492 20.9455 6.02252C20.7317 6.05041 20.7503 6.35718 20.5457 6.41295C20.5457 6.36647 20.5179 6.33859 20.5179 6.31999C20.2483 6.3014 20.7224 6.5338 20.5736 6.59888C20.49 6.47803 20.4528 6.45943 20.3691 6.44084L20.4807 6.65465C20.4807 6.65465 20.3319 6.48732 20.3041 6.42225C20.4528 6.70113 20.146 6.68254 20.2948 6.94283C20.239 6.89635 20.0902 6.66395 19.9973 6.58958C19.8764 6.58958 19.9043 6.71043 19.9322 6.83128C19.7556 6.71043 19.6626 6.83128 19.6626 6.7848C19.4767 6.81269 19.7463 6.92424 19.7742 7.13805L19.9508 7.15664L19.83 7.35186L19.8021 7.18453C19.6533 7.16594 19.737 7.42623 19.644 7.5006L19.7928 7.59356L19.7556 7.76089C19.5232 7.50989 19.5697 7.81666 19.3651 7.46341C19.0584 7.4913 19.235 7.94681 19.077 8.11414C19.1049 8.08625 19.0491 8.04907 19.0212 7.99329C18.8725 8.02118 18.9282 8.2071 18.984 8.39302C18.9282 8.30006 18.9282 8.25358 18.8632 8.17921C18.7423 8.28147 18.9189 8.39302 18.8632 8.57894C18.8074 8.4395 18.7423 8.39302 18.6865 8.39302C18.7795 8.48598 18.8074 8.57894 18.8074 8.62542C18.4541 8.02118 18.4727 8.54176 18.1845 8.07695C18.2775 8.1978 18.2682 8.59754 18.5099 8.75557V8.6812C18.6401 8.82064 18.5471 8.81135 18.5099 8.84853C18.5099 8.81135 18.5006 8.75557 18.4727 8.72768C18.4355 9.06234 18.1009 9.07164 18.0079 9.37841C17.98 9.31333 17.98 9.146 17.8871 9.146C17.6175 9.24826 17.729 9.6294 17.6361 9.93617C17.3386 9.61081 17.822 9.69447 17.5524 9.36911C17.3944 9.6387 17.2735 9.94547 17.1806 10.3266C16.6693 9.91758 17.1155 10.7356 16.6321 10.4846C16.7901 10.6334 16.7622 10.7542 16.6879 10.8379C16.5949 10.6799 16.5112 10.7542 16.4462 10.6334C16.502 10.8472 16.3532 11.0889 16.0836 10.7635C16.3346 11.0796 15.9163 10.8844 16.0557 11.154C15.8605 11.1168 15.9163 11.3864 15.7304 11.3957C15.9442 11.5537 15.7025 11.5909 15.7304 11.7024C15.7304 11.6838 15.7304 11.6281 15.7025 11.6095C15.5166 11.47 15.7025 11.8698 15.5537 11.8326C15.4608 11.7861 15.405 11.6467 15.3399 11.6745C15.4608 11.814 15.4329 12.1208 15.2191 12.0092C15.247 11.9813 15.1912 11.9162 15.154 11.8419C15.0704 12.3439 14.494 12.3439 14.4382 12.9016L14.2802 12.6227C13.8247 12.5019 14.494 13.1061 14.3174 13.2177C13.8061 13.478 13.0903 13.5524 12.8207 14.0636C12.8486 14.1566 12.9137 14.1287 13.0066 14.2217C12.9508 14.2217 12.7649 14.045 12.8207 14.2124L12.9415 14.3239C12.4489 14.1659 12.6441 15.0304 12.0212 14.6493C12.0398 15.0025 11.6029 14.7887 11.6866 15.2721C11.5192 15.2349 11.5564 15.0025 11.4449 15.0583V15.4209V15.393C11.6401 15.9043 10.5896 15.4859 10.6547 15.96V15.9321C10.5617 15.8485 10.413 15.8113 10.413 15.8764C10.4595 15.9414 10.5153 15.9414 10.6082 15.9879C10.5803 16.3226 10.5525 16.3691 10.4409 16.555C10.3665 16.3784 10.2736 16.5271 10.0784 16.3877C10.162 16.5271 10.2922 16.5178 10.3201 16.6944C10.2178 16.8525 9.99469 16.8153 9.78088 16.9826C9.89243 17.1964 9.78088 17.2615 9.9668 17.4567C9.80877 17.7821 9.75299 18.0052 9.56707 18.4886L9.51129 18.4049C9.66003 18.879 9.251 18.6094 9.32537 18.9162C9.26959 18.7582 9.2603 18.6559 9.19522 18.5629L9.17663 18.8976C9.15804 18.6652 9.00001 18.2469 8.92564 18.3398C8.99071 18.7953 9.02789 18.4979 9.10226 18.8232L8.91634 18.47C8.88845 18.6187 9.05578 19.1486 9.16733 19.1021C8.99071 19.5483 8.86986 20.3013 8.69323 20.6546L8.62816 20.2362C8.58168 20.5709 8.47013 20.8963 8.37717 20.701C8.37717 20.6732 8.35857 20.6546 8.35857 20.636C8.37717 20.7568 8.37717 20.9706 8.41435 21.1101C8.35858 21.5842 8.31209 20.45 8.25632 20.9706C8.27491 20.8498 8.3028 20.7847 8.27491 20.5523C8.24702 20.6267 8.21913 20.6917 8.19125 20.7568C8.17265 20.7847 8.16336 20.8126 8.14477 20.8405H8.0704C8.03321 20.5802 7.8194 19.8272 7.70785 19.8923C7.70785 20.0224 7.75433 20.2455 7.78222 20.3106L7.69855 20.3292L7.62418 19.7157C7.587 19.8272 7.54982 19.9388 7.51263 20.041V19.6041C7.42897 19.6041 7.38249 20.0968 7.29882 19.9667C7.03853 19.3717 7.1036 19.3066 6.98275 18.7396C6.84331 19.4182 6.71317 18.3863 6.55513 18.8139C6.45288 18.0517 6.01596 17.9215 5.77426 17.4381H5.83004C5.87652 17.0756 5.42101 17.5869 5.34664 17.3173L5.4396 17.2987C5.45819 17.0849 5.32805 16.9175 5.18861 16.8432C5.05846 16.7688 4.87254 16.7409 4.71451 16.7409C4.80747 16.7223 4.92832 16.5922 4.87254 16.555C4.75169 16.5829 4.60295 16.8339 4.62155 16.6851C4.67732 16.6758 4.76099 16.5829 4.7424 16.555L4.46351 16.6387C4.43563 16.2947 4.37985 15.9136 4.07308 15.7834C4.11026 15.6812 4.22182 15.6533 4.29618 15.6068C4.11026 15.4581 3.7849 15.4209 3.61757 15.2814L3.84997 15.0676C3.7849 14.9839 3.43165 15.3186 3.57109 15.0397C3.58968 14.9932 3.64546 15.0955 3.7756 15.0397C3.84068 14.733 3.45954 15.1327 3.36658 14.9561L3.68264 14.7794C3.75701 14.5284 3.43165 14.7608 3.22713 14.8445C2.76233 14.9282 3.68264 14.3053 3.25502 14.2682C3.08769 14.3425 3.0598 14.4355 2.89247 14.5098C2.84599 14.2867 2.62289 14.4262 2.57641 14.2031C2.93896 13.794 2.64148 14.2867 2.96684 13.887V14.0822C3.10628 13.8033 3.09699 14.138 3.32939 13.9242C3.33869 13.7848 3.03192 13.8312 2.87388 13.7848C3.0598 13.6453 2.98544 13.887 3.20854 13.6453H3.08769C3.15277 13.6267 3.22713 13.5709 3.24573 13.6081C3.41306 13.4501 3.20854 13.5338 3.16206 13.4873C3.0598 13.5616 2.92036 13.6639 2.79951 13.7848C2.81811 13.7662 2.8367 13.7476 2.85529 13.7197C2.50204 13.8219 2.57641 13.4873 2.28823 13.5616C2.3533 13.5338 2.3626 13.5059 2.40908 13.4687C2.37189 13.3943 2.07442 13.5152 1.93498 13.4873C2.03723 13.3385 2.38119 13.1991 2.19527 13.1247C2.01864 13.2177 1.78624 13.4873 1.70258 13.3571C1.70258 13.3571 1.90709 13.3571 1.98146 13.227H1.95357ZM4.28689 15.5045C4.28689 15.5045 4.31478 15.5324 4.34266 15.551C4.34266 15.551 4.29618 15.5138 4.28689 15.5045ZM4.61225 15.5696C4.61225 15.5696 4.51929 15.5975 4.45422 15.6533C4.48211 15.6905 4.50999 15.7183 4.51929 15.7555C4.55647 15.6719 4.55647 15.5882 4.61225 15.5696ZM5.46749 14.2403L5.49538 14.2217C5.49538 14.2217 5.55116 14.2496 5.56975 14.2589C5.60693 14.2217 5.63482 14.1752 5.57904 14.1659C5.55116 14.1845 5.50468 14.2031 5.46749 14.231V14.2403Z\" fill=\"#8F3A7E\"><\/path><path d=\"M5.26323 14.3253C5.26323 14.3253 5.24482 14.3253 5.23562 14.3253C5.22642 14.3437 5.21721 14.3621 5.20801 14.3805L5.28164 14.3437L5.26323 14.3253Z\" fill=\"#8F3A7E\"><\/path><path d=\"M21.6523 4.27579C21.6523 4.27579 21.6712 4.27579 21.69 4.29463C21.6806 4.29463 21.6712 4.28521 21.6618 4.27579H21.6523Z\" fill=\"#8F3A7E\"><\/path><path d=\"M7.48508 20.1339L7.49435 20.032L7.46655 20.0876L7.48508 20.1339Z\" fill=\"#8F3A7E\"><\/path><path d=\"M23.4094 3.96896C23.4094 3.96896 23.4473 3.9974 23.4663 4.00688C23.4568 3.9974 23.4284 3.97844 23.4094 3.96896Z\" fill=\"#8F3A7E\"><\/path><path d=\"M24.4309 3.36418C24.4309 3.36418 24.3847 3.29949 24.3662 3.27176L24.4309 3.36418Z\" fill=\"#8F3A7E\"><\/path><path d=\"M19.885 6.80322C19.8943 6.85893 19.9036 6.90536 19.9036 6.95178C19.95 6.9425 19.9779 6.92393 19.885 6.80322Z\" fill=\"#8F3A7E\"><\/path><path d=\"M16.6518 10.8394L16.6318 10.8494L16.6518 10.8394Z\" fill=\"#8F3A7E\"><\/path><path d=\"M19.8203 7.01859C19.885 7.02783 19.9035 7.0001 19.9035 6.95389C19.8665 6.96313 19.8203 6.97237 19.8203 7.01859Z\" fill=\"#8F3A7E\"><\/path><path d=\"M26.1981 2.03489H26.2264C26.2264 2.03489 26.2075 2.00662 26.1981 1.99719V2.03489Z\" fill=\"#8F3A7E\"><\/path><path d=\"M26.1977 1.99845V1.96075C26.1977 1.96075 26.1789 1.9796 26.1977 1.99845Z\" fill=\"#8F3A7E\"><\/path><path d=\"M26.2079 1.8683V1.95148C26.2079 1.95148 26.2449 1.933 26.2079 1.8683Z\" fill=\"#8F3A7E\"><\/path><path d=\"M25.6025 2.37845L25.6578 2.45208C25.6578 2.45208 25.6302 2.40606 25.6025 2.37845Z\" fill=\"#8F3A7E\"><\/path><path d=\"M25.4627 2.52706C25.5183 2.50852 25.6852 2.60121 25.7037 2.51779L25.6574 2.45291C25.7223 2.58267 25.3978 2.37876 25.4627 2.52706Z\" fill=\"#8F3A7E\"><\/path><path d=\"M24.0587 2.18406L24.2354 2.12826C24.1517 2.07245 24.0308 1.98874 24.0773 1.92363C23.7145 1.83062 24.254 2.07245 24.0587 2.18406Z\" fill=\"#8F3A7E\"><\/path><path d=\"M23.5575 2.40555C23.5946 2.31271 23.4646 2.29414 23.4275 2.24771C23.4461 2.35913 23.4461 2.38698 23.5575 2.40555Z\" fill=\"#8F3A7E\"><\/path><path d=\"M20.6004 4.88834L20.4517 4.70251C20.4239 4.77684 20.5075 4.77684 20.6004 4.88834Z\" fill=\"#8F3A7E\"><\/path><path d=\"M20.833 6.30117L20.9817 6.36621L20.8702 6.18039L20.833 6.30117Z\" fill=\"#8F3A7E\"><\/path><path d=\"M19.4009 5.29716L19.4102 5.25073L19.373 5.39001L19.4009 5.29716Z\" fill=\"#8F3A7E\"><\/path><path d=\"M14.5673 9.62069L14.7804 9.8246C14.7804 9.75045 14.5673 9.5002 14.5673 9.62069Z\" fill=\"#8F3A7E\"><\/path><path d=\"M12.6902 11.7309C12.5694 11.6473 12.4486 11.6287 12.5044 11.7681C12.5601 11.7402 12.6902 11.7774 12.6902 11.7309Z\" fill=\"#8F3A7E\"><\/path><path d=\"M7.70828 16.6682L7.6897 16.4824L7.69899 16.659L7.70828 16.6682Z\" fill=\"#8F3A7E\"><\/path><path d=\"M1.70163 9.61194C1.61792 9.63054 1.4691 9.73285 1.52491 9.76076L1.81324 9.63984L1.70163 9.61194Z\" fill=\"#8F3A7E\"><\/path><path d=\"M1.38543 10.1886C1.54327 10.17 1.80325 10.0957 2.02609 9.91004C1.74754 10.0122 1.84039 9.9379 1.50613 10.0586C1.45042 10.0307 1.54327 9.92861 1.64541 9.88219C1.57113 9.90076 1.66398 9.78006 1.47828 9.85433C1.30187 10.0307 1.33901 10.1143 1.55256 10.0865C1.50613 10.1329 1.42257 10.1607 1.37615 10.1886H1.38543Z\" fill=\"#8F3A7E\"><\/path><path d=\"M6.07034 17.5318C6.07034 17.5318 6.02367 17.5318 6.005 17.5598C6.033 17.5598 6.06101 17.5598 6.07034 17.5318Z\" fill=\"#8F3A7E\"><\/path><path d=\"M6.40438 18.461C6.40438 18.461 6.38574 18.4238 6.38574 18.4051C6.38574 18.4517 6.38574 18.4797 6.40438 18.461Z\" fill=\"#8F3A7E\"><\/path><path d=\"M4.03508 14.7249L4.01648 14.8551C4.10019 14.7993 4.04438 14.7714 4.03508 14.7249Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.3788 10.391C2.3788 10.391 2.32335 10.391 2.28638 10.391C2.30486 10.391 2.32335 10.4002 2.33259 10.4095L2.3788 10.3817V10.391Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.96444 13.7376L2.94584 13.719C2.94584 13.719 2.87143 13.7562 2.83423 13.7748L2.96444 13.7376Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.26855 12.8844C2.26855 12.8844 2.49178 12.7635 2.58479 12.7077C2.49178 12.7635 2.43597 12.7728 2.40807 12.7728C2.37087 12.8007 2.32436 12.8379 2.26855 12.8937V12.8844Z\" fill=\"#8F3A7E\"><\/path><path d=\"M3.40322 14.398C3.40322 14.398 3.34722 14.4447 3.33789 14.4634C3.36589 14.4447 3.38456 14.4167 3.40322 14.398Z\" fill=\"#8F3A7E\"><\/path><path d=\"M24.3936 0.882324C24.3936 0.882324 24.4124 0.910594 24.4218 0.920017C24.4124 0.891747 24.403 0.882324 24.3936 0.882324Z\" fill=\"#8F3A7E\"><\/path><path d=\"M26.1963 1.0585V1.08636L26.2891 1.19778L26.1963 1.0585Z\" fill=\"#8F3A7E\"><\/path><path d=\"M7.32639 20.0692C7.32639 20.0692 7.32639 20.0692 7.32639 20.0592C7.29639 20.0692 7.31639 20.0792 7.32639 20.0692Z\" fill=\"#8F3A7E\"><\/path><path d=\"M13.8886 13.0136C13.6561 12.9113 13.8142 12.6788 13.5166 12.5951C13.6003 12.6602 13.684 12.995 13.8886 13.0136Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.37 10.4381C2.37 10.4381 2.38884 10.457 2.39826 10.4758C2.39826 10.457 2.38884 10.4476 2.37 10.4381Z\" fill=\"#8F3A7E\"><\/path><path d=\"M9.13905 18.7775C9.11125 18.7312 9.08346 18.6942 9.05566 18.6756C9.07419 18.7127 9.09272 18.7405 9.13905 18.7775Z\" fill=\"#8F3A7E\"><\/path><path d=\"M7.87305 19.9031L7.91937 20.005C7.90084 19.9494 7.89158 19.9216 7.87305 19.9031Z\" fill=\"#8F3A7E\"><\/path><path d=\"M9.5293 17.1406C9.5293 17.1406 9.59373 17.1407 9.59373 17.0762C9.58452 17.0762 9.57532 17.0762 9.56611 17.067C9.58452 17.1038 9.58452 17.1406 9.5385 17.1406H9.5293Z\" fill=\"#8F3A7E\"><\/path><path d=\"M10.1335 16.3052C10.1335 16.3052 10.0955 16.2957 10.0861 16.2863V16.3147L10.1335 16.3052Z\" fill=\"#8F3A7E\"><\/path><path d=\"M22.2911 2.80592C22.3562 2.85237 22.4119 2.89883 22.477 2.95457C22.3469 2.8245 22.4119 2.68513 22.2911 2.80592Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.25891 10.4761C2.31499 10.448 2.35237 10.4293 2.37106 10.4387L2.34302 10.42C2.34302 10.42 2.2776 10.4574 2.25891 10.4761Z\" fill=\"#8F3A7E\"><\/path><path d=\"M8.05957 15.6353L8.11645 15.6163C8.11645 15.6163 8.06905 15.6163 8.05957 15.6353Z\" fill=\"#8F3A7E\"><\/path><path d=\"M17.1702 7.21375V7.16635C17.1702 7.16635 17.1607 7.18531 17.1702 7.21375Z\" fill=\"#8F3A7E\"><\/path><path d=\"M8.31042 15.2827C8.40334 15.3198 8.45908 15.3198 8.50554 15.3198C8.49625 15.3013 8.48696 15.2827 8.46837 15.2641L8.31042 15.2827Z\" fill=\"#8F3A7E\"><\/path><path d=\"M22.9801 2.12785C22.9986 1.93263 23.0544 2.14644 23.2961 2.2394C23.1753 1.97911 23.4635 2.23011 23.1846 1.86756C23.417 2.07207 23.3333 1.98841 23.5378 2.09996C23.3519 1.93263 23.5099 1.80249 23.3147 1.57938C23.5564 1.81178 23.4635 1.98841 23.7795 2.18363C23.6959 1.96052 23.7516 1.80249 23.5285 1.51431C23.6308 1.5422 23.733 1.62586 23.826 1.58868C23.7981 1.58868 23.826 1.64445 23.8446 1.68164C23.8167 1.38416 24.1607 1.42135 23.9468 1.02161C24.2536 1.44923 24.2629 0.844989 24.4767 1.3005C24.5232 1.24472 24.4581 1.00302 24.4117 0.910061C24.6719 1.22613 24.6069 0.882173 24.8207 1.02161C24.6998 0.8171 24.8486 0.798508 24.8207 0.649771C24.8207 0.705547 24.8579 0.77062 24.9415 0.854285C24.895 0.668363 24.988 0.807804 25.1646 0.910061C25.1646 0.742732 24.9508 0.686955 24.8765 0.491737C25.0159 0.491737 25.0531 0.677659 25.1739 0.798508L25.0252 0.38948C25.0717 0.398776 25.1367 0.445257 25.2204 0.528921C25.1832 0.408072 25.1089 0.240743 25.2855 0.343L25.1925 0.435961L25.3599 0.566106L25.3041 0.268631C25.6666 0.361592 25.899 0.742732 26.1593 1.08669L26.1407 1.19824C26.2337 1.30979 26.3359 1.33768 26.3731 1.31909C26.4661 1.37487 26.5683 1.7746 26.5219 1.87685C26.3081 2.02559 26.1593 1.5236 25.9548 1.55149L25.9362 1.89545L25.8432 1.78389C25.7503 1.72812 25.8432 1.86756 25.8525 1.90474C25.7224 1.72812 25.6666 1.96982 25.5644 2.007L25.7131 2.12785C25.7968 2.63913 25.0903 2.02559 25.081 2.34166L25.1739 2.68561L24.9694 2.4904C25.0066 2.67632 25.1367 2.85294 24.9694 2.86224C24.2815 2.79717 24.2629 3.59663 23.6773 3.6803C23.7144 3.71748 23.7423 3.72678 23.7981 3.73607C23.0172 3.47578 23.7423 4.72146 23.0916 4.55413L23.0451 4.46117C22.9243 4.6285 22.9986 4.35891 22.7848 4.34032C22.9801 4.6192 22.7662 4.70287 22.7569 4.87949C22.7291 4.81442 22.7569 4.79583 22.7569 4.73075C22.6919 4.68427 22.5524 4.53554 22.5524 4.6192C22.7755 5.07471 22.5338 5.21415 22.4688 5.45585C22.3014 5.29782 22.0411 5.26063 21.7437 5.03752C21.7809 5.11189 21.8645 5.26993 21.9482 5.41866C21.7995 5.35359 21.8273 5.47444 21.8738 5.61388C21.9203 5.5674 21.9575 5.53022 21.9854 5.49303V5.51163C21.9854 5.51163 21.9947 5.48374 22.004 5.47444C22.0319 5.43726 22.0412 5.40937 22.0226 5.40937C22.2271 5.52092 22.1341 5.54881 22.3014 5.74403C22.2457 5.78121 22.1992 5.93925 22.0597 5.7998C22.0226 5.8184 21.9854 5.8184 21.9296 5.8184C21.9296 5.86488 21.9296 5.90206 21.8924 5.90206V5.87417C21.8924 5.87417 21.8366 5.83699 21.818 5.8184C21.6507 5.8184 21.7623 6.23672 21.7995 6.44123C21.6693 6.12517 21.5392 6.17165 21.3811 5.99502C21.3811 6.01361 21.4927 5.93925 21.6228 5.83699C21.5949 5.82769 21.5578 5.7998 21.502 5.73473C21.2324 5.63247 21.4648 6.06009 21.1859 6.06009C21.1859 6.03221 21.1673 5.97643 21.1022 5.91136C21 5.91136 21.0744 6.09728 21.158 6.21813C20.9907 6.0508 20.7676 6.02291 20.7676 6.15306C20.842 6.34827 20.907 6.40405 20.7955 6.46912L20.7304 6.31109C20.5259 6.30179 20.7955 6.57138 20.6188 6.55279C20.7025 6.57138 20.591 6.44123 20.5445 6.43194C20.4887 6.59927 20.5445 6.67364 20.6746 6.9897L20.5259 6.77589C20.5259 6.98041 20.5445 7.38014 20.3214 7.11055C20.7025 7.49169 20.2935 7.51028 20.2005 7.57536C20.2191 7.53817 20.154 7.44521 20.1169 7.39873C20.1726 7.82635 19.7636 7.7148 19.587 7.88213L19.2988 7.61254C19.2151 7.7055 19.6892 8.31904 19.5777 8.39341L19.494 8.21679C19.3546 8.4213 19.2523 8.45849 19.0664 8.54215L18.8991 8.33764C18.927 8.47708 18.8619 8.53285 18.8898 8.6723C18.3506 8.29116 18.6295 9.34161 17.9416 8.99766L18.2483 9.3788C18.1554 9.44387 18.1089 9.6112 17.83 9.3788H17.8579C17.6162 9.08132 17.7649 9.43458 17.6627 9.41598C17.6534 9.48106 17.7742 9.70416 17.8579 9.72275C17.4675 9.72275 17.3094 10.2154 16.8725 10.0109C16.7517 10.327 16.8446 10.7732 16.5658 10.9498L16.5286 10.9034C16.4077 10.9219 16.1474 10.9684 15.8778 10.6617C15.7663 10.8848 16.0359 11.4053 15.7012 11.4518L15.6454 11.2938C15.5432 11.2845 15.5897 11.4983 15.599 11.5541C15.5711 11.5634 15.5339 11.489 15.4967 11.4425C15.3573 11.3868 15.4688 11.5727 15.4595 11.6377L15.3851 11.5169C15.0319 11.4518 15.1435 12.1026 14.8925 12.242C14.9018 12.1769 14.7809 12.084 14.7158 12.0468C14.9389 12.4651 14.6229 12.5952 14.6136 12.7533L14.5485 12.5767C14.5764 12.9578 14.0744 12.3535 14.1116 12.7347L14.3812 12.8369C14.2603 12.8369 14.2603 12.9578 14.4184 13.0972C14.2324 13.0601 14.1767 12.8462 14.0186 12.9299C13.9257 12.8369 14.0465 12.7812 13.8978 12.6975L13.498 12.6045C13.498 12.6045 13.4423 12.5952 13.4144 12.6696C13.8141 13.0786 13.2935 12.8184 13.7583 13.153C13.5538 13.404 13.0983 13.311 13.0704 13.6922C12.6149 13.3668 12.6521 14.0547 12.1873 13.5156C12.0664 13.6178 12.0757 13.813 12.2059 14.0826C12.271 14.1012 12.2338 14.0083 12.2338 13.9618C12.3267 14.1198 12.2152 14.2685 12.1594 14.3243C12.1222 14.1384 12.1501 13.9246 12.02 13.6736C11.9642 13.8223 12.0014 14.1477 12.0107 14.2685L11.7318 14.0268C11.834 14.3057 11.4529 13.8781 11.6202 14.2221L11.7132 14.2871C11.5366 14.4173 11.7876 14.6869 11.6853 14.8542L11.5923 14.7426C11.4994 14.7426 11.676 15.068 11.3878 14.8821L11.4715 14.7798C11.2856 14.6032 11.1275 14.6032 11.0067 14.5381C10.9509 14.6869 11.267 14.8635 11.2484 14.9379C11.0532 14.7891 11.1554 14.8542 11.016 14.6497C10.9602 14.817 10.8951 15.0401 11.0439 15.3376C11.016 15.319 10.9788 15.2725 10.9788 15.2725C10.8394 15.3562 11.0625 15.7559 10.8487 15.6908V15.6444C10.4954 15.5049 10.8765 16.1092 10.4024 15.728C10.2816 15.7001 10.514 15.6444 10.2258 15.5142C9.95623 15.5328 10.5233 15.9418 10.2909 15.9511C10.3188 15.9511 10.2909 15.9325 10.2537 15.8861C10.1886 15.9883 10.1329 16.1464 10.0957 16.2858C9.60298 16.1185 9.90046 16.732 9.3148 16.574C9.51002 16.639 9.46354 16.7692 9.52861 16.8343C9.52861 16.8343 9.49143 16.7878 9.46354 16.7785C9.39847 16.8343 9.53791 16.983 9.58439 17.0667C9.41706 17.0016 9.58439 17.4385 9.46354 17.4013C9.54721 17.5036 9.48213 17.5501 9.43565 17.6244C9.43565 17.3455 9.28692 17.3363 9.18466 17.1131C9.02663 17.234 9.40776 17.8661 9.21255 18.0613C9.13818 18.0242 9.07311 17.987 8.99874 17.9405C9.20325 18.3867 8.99874 18.4983 9.07311 18.6656C8.98944 18.5726 8.92437 18.554 8.82211 18.303C8.82211 18.5354 8.65478 18.4239 8.74774 18.7957L8.8407 18.8236C8.72915 18.9073 8.71985 19.1955 8.70126 19.4929C8.68267 19.7811 8.65478 20.06 8.55253 19.9856L8.33872 18.9445C8.19927 18.647 8.33872 19.8462 8.17139 19.2977C8.24575 19.6417 8.23646 19.5022 8.25505 20.0042C8.29223 20.0135 8.28294 19.5952 8.32942 19.4929L8.34801 20.404L8.44097 19.6882C8.45956 20.2738 8.44097 20.1716 8.55253 20.5341C8.52464 21.0547 8.40379 20.5713 8.35731 20.7386C8.34801 20.7386 8.32942 20.7758 8.32012 20.8502C8.25505 20.6828 8.23646 20.2831 8.17139 20.06C8.12491 20.4411 7.94828 19.4093 7.9018 19.7718C7.86461 19.6417 7.94828 19.7997 7.92039 19.5673C7.85532 19.5673 7.80884 19.4744 7.79954 19.7253L7.87391 19.902C7.81813 19.809 7.82743 20.1716 7.69728 19.8276C7.64151 19.9577 7.60432 20.3296 7.68799 20.4318C7.6601 20.4504 7.57644 20.1344 7.60432 19.902C7.4277 19.6789 7.51136 20.6921 7.32544 20.0693C7.34403 20.0693 7.35333 20.0321 7.35333 19.9763C7.30685 19.8648 7.26967 19.8183 7.23248 19.8276C7.39981 19.9485 7.22318 19.1304 7.39051 19.4929C7.39051 19.0374 7.26037 19.2512 7.21389 19.0188C7.10234 19.1955 7.15811 19.5952 7.09304 19.7439C7.10234 19.6138 7.06515 19.5673 7.02797 19.4651L7.04656 19.8183C7.00008 19.7718 6.96289 19.716 6.90712 19.7253L7.00937 19.7068C6.91641 19.5394 6.86993 18.9352 6.67472 19.0281C6.73979 18.9631 6.85134 18.8236 6.79556 18.5726C6.60964 18.5726 6.78627 18.4146 6.75838 18.1264C6.60964 18.0242 6.60964 18.5633 6.44231 18.1543C6.42372 18.1264 6.38654 18.2937 6.38654 18.3867C6.28428 18.0892 6.12625 18.145 6.06117 17.8196C6.08906 17.9498 6.10765 18.0892 5.96821 18.0799C6.09836 17.9498 5.93103 17.7732 5.94032 17.6058L5.86596 17.6895C5.89384 17.5315 5.96821 17.5501 6.02399 17.5501C6.0054 17.5779 5.9961 17.6244 6.02399 17.6523C6.14484 17.6523 6.33076 17.2247 6.27498 17.0853C6.12625 17.0667 5.95892 17.327 5.91244 17.4478C5.83807 17.1782 5.44763 17.6802 5.40115 17.3548C5.36397 17.3084 5.55918 16.8529 5.50341 16.7134C5.25241 16.8064 5.48482 16.9923 5.27101 17.0667C5.56848 16.4345 4.68535 16.9551 4.78761 16.481L5.0479 16.3137C5.02001 16.2486 5.00142 16.1928 4.92705 16.1556L4.85268 16.3323C4.75972 16.3323 4.71324 16.1742 4.92705 16.0627C4.63887 16.1092 4.74113 15.9883 4.71324 15.8396C4.77831 15.9697 4.68535 15.8675 4.87127 15.8489C4.89916 15.6351 4.8062 15.6908 4.69465 15.6537C4.78761 15.5979 4.88987 15.4491 4.86198 15.4213C4.64817 15.4677 4.5738 15.3097 4.41577 15.2725L4.49013 15.2167C4.25773 15.1145 4.44365 14.6497 4.0904 14.6404C4.0904 14.6404 4.08111 14.6404 4.07181 14.6404V14.6683C3.88589 14.91 3.79293 14.6497 3.66278 14.6683C3.70926 14.6125 3.81152 14.5288 3.78363 14.4916C3.56982 14.659 3.6163 14.5102 3.49545 14.5567C3.52334 14.4359 3.76504 14.3615 3.67208 14.2685C3.6256 14.2407 3.50475 14.3243 3.42108 14.3894C3.51404 14.2778 3.55123 14.1477 3.53264 14.0733C3.60701 14.0454 3.55123 14.1384 3.57912 14.1384C3.69997 14.0547 3.6256 14.0547 3.77434 13.9432C3.75574 13.8781 3.55123 14.0826 3.57912 13.9618L3.79293 13.8874C3.82082 13.8316 3.71856 13.8502 3.69997 13.8502C3.77434 13.8502 3.94166 13.7201 4.04392 13.6364C3.81152 13.5899 3.56053 13.9618 3.36531 14.1012C3.3932 13.8595 3.08642 13.9246 2.99346 13.8223L3.21657 13.6922C3.1422 13.6643 3.07713 13.6736 2.97487 13.7201L2.9098 13.6364C3.02135 13.6364 3.09572 13.5992 3.26305 13.4784C3.1422 13.4319 3.10502 13.2832 2.81684 13.4598L2.86332 13.4319C2.87261 13.246 2.75177 12.9578 2.85402 12.902C2.6681 12.8462 2.71458 12.5674 2.4357 12.7626C2.31485 12.7347 2.64951 12.3164 2.26837 12.5116C2.38922 12.2885 2.34274 12.4558 2.56584 12.335C2.68669 12.1211 2.15682 12.3628 2.52866 12.0468C2.33344 12.0282 2.46359 12.1304 2.25907 12.2234C2.61232 11.9352 2.1847 11.991 2.32415 11.74C2.14752 11.8051 2.25907 11.8516 2.05456 11.8887C2.15682 11.833 2.13822 11.7772 2.13822 11.7493L1.89653 11.8887L2.39851 11.3868C2.01737 11.4332 2.01737 11.6935 1.77568 11.5727H1.80356C2.00808 11.3496 1.52468 11.5541 1.60835 11.2845C1.59905 11.3682 1.73849 11.2287 1.81286 11.2008L1.66412 11.1822C1.66412 11.1822 1.70131 11.1822 1.7199 11.1451C1.85005 10.9591 1.58046 11.1451 1.68272 10.9591C1.76638 10.987 1.93371 10.8476 2.00808 10.7639L1.66412 10.8197L2.01737 10.6524C1.97089 10.5222 1.33876 10.6803 1.75708 10.3363L1.84075 10.3642C1.91512 10.3084 2.13822 10.1318 1.92441 10.1597C1.86864 10.1597 1.66412 10.2619 1.70131 10.2898L1.73849 10.1876C1.97089 10.0853 2.11963 10.1876 2.23118 10.234C2.12893 10.2619 2.01737 10.234 1.89653 10.3456C2.01737 10.3828 2.2033 10.3642 2.32415 10.3921C2.22189 10.42 2.07315 10.485 1.98019 10.5222C1.92441 10.6803 2.16611 10.4943 2.23118 10.5408C2.16611 10.6245 2.11963 10.671 2.03597 10.6988C2.17541 10.7267 2.24048 10.7732 2.1847 10.9312C2.1847 10.9312 1.97089 10.9312 1.87793 11.0707C2.11034 11.1451 2.37992 11.0056 2.64021 11.0707C3.12361 11.0149 2.68669 11.5913 3.03065 11.5448C3.12361 11.489 3.12361 11.331 3.24446 11.3775C3.04924 11.4983 3.16079 11.5169 3.09572 11.5727C3.43038 11.4704 3.13291 11.7493 3.36531 11.6842C3.29094 11.7121 3.25375 11.8237 3.21657 11.898C2.98417 12.0561 3.19798 12.0654 2.77965 12.1676C3.22587 12.0561 2.87261 12.4837 3.47686 12.1955L3.51404 12.1118V12.3257V12.3164C3.51404 12.4 3.58841 12.3721 3.41179 12.6231C3.32812 12.6231 3.29094 12.5767 3.20727 12.5859C3.06783 12.8091 3.48616 12.6138 3.56053 12.6882C3.3932 12.8091 3.43968 12.6417 3.25375 12.8184C3.27235 12.8927 3.43038 12.8555 3.51404 12.8741L3.42108 12.9299C3.32812 13.2274 3.90448 12.651 3.68137 12.9857C3.72785 12.9392 3.80222 12.9113 3.8487 12.8648C3.78363 12.9764 3.69067 13.1902 3.50475 13.1809C3.54193 13.2274 3.66278 13.2274 3.78363 13.1809C3.88589 13.0415 3.81152 13.0786 3.96955 12.9299L4.22055 13.0601C4.22055 13.0601 4.11829 13.1065 4.0997 13.0786C3.80222 13.6829 4.87127 13.246 4.49943 13.9525C4.62028 13.813 4.64817 13.8688 4.75972 13.8223C4.77831 13.9432 4.91775 14.0454 4.88987 14.1942L4.76902 14.2499C5.0479 14.3615 5.31749 14.3801 5.36397 14.5567C5.41045 14.5288 5.22453 14.6683 5.16875 14.6683C5.42904 14.6218 4.94564 15.1981 5.35467 14.9193V14.8542C5.44763 15.1052 5.89384 15.0959 6.10765 15.2632C5.91244 15.4956 5.9868 15.1703 5.7544 15.4306C5.77299 15.6444 6.08906 15.6258 6.12625 15.8396C6.07977 15.8396 6.05188 15.8675 6.03328 15.8675C6.0054 16.1371 6.2471 15.663 6.32146 15.821C6.20061 15.9047 6.18202 15.9325 6.15413 16.0255L6.36794 15.9139C6.36794 15.9139 6.20061 16.0627 6.13554 16.0906C6.41442 15.9418 6.36794 16.2114 6.59105 16.0348C6.54457 16.0999 6.34006 16.2765 6.27498 16.3695C6.27498 16.4996 6.37724 16.4531 6.4795 16.3973C6.38654 16.6019 6.48879 16.6855 6.45161 16.6948C6.48879 16.89 6.56316 16.574 6.7212 16.481L6.73979 16.2951L6.86993 16.3509L6.75838 16.4438C6.74908 16.6112 6.92571 16.4252 6.96289 16.481L7.01867 16.2765C7.01867 16.2765 7.08374 16.2393 7.11163 16.2207C6.97219 16.6019 7.14882 16.388 6.96289 16.7971C7.03726 17.1596 7.24178 16.7041 7.32544 16.7506C7.30685 16.732 7.30685 16.8343 7.28826 16.9086C7.33474 17.0853 7.39981 16.8807 7.43699 16.6483C7.4184 16.7971 7.40911 16.8436 7.39051 16.9644C7.45559 17.0481 7.44629 16.7227 7.51136 16.6297C7.49277 16.8343 7.49277 16.9551 7.51136 17.0295C7.51136 16.8343 7.52996 16.7041 7.53925 16.6669C7.48347 17.6802 7.62292 17.2061 7.60432 18.0428C7.61362 17.8289 7.71588 17.4757 7.6508 16.9644V17.0295C7.62292 16.7134 7.6508 16.8621 7.6601 16.8529C7.6601 16.8993 7.6508 16.9551 7.6601 17.0202C7.68799 16.89 7.72517 16.9365 7.74377 16.9179C7.76236 16.8622 7.78095 16.8343 7.79025 16.7506C7.79025 16.7041 7.79954 16.6483 7.79954 16.574C7.81813 16.6948 7.82743 16.9458 7.85532 17.0016C7.94828 17.0016 7.88321 16.3695 7.85532 16.0627C8.03194 16.6205 7.82743 16.2579 7.96687 16.8436C8.01335 16.5368 8.03194 16.1928 7.96687 15.8582C8.15279 16.1649 8.1435 16.0534 8.11561 15.9418C8.08772 15.821 8.04124 15.7187 8.23646 15.8768C8.08772 15.7094 8.05983 15.6165 8.06913 15.5793C8.18998 15.7187 8.21787 15.6815 8.30153 15.7745C8.24575 15.6815 8.20857 15.6072 8.23646 15.5793C8.25505 15.57 8.39449 15.5142 8.55253 15.663C8.23646 15.3934 8.70126 15.4956 8.52464 15.2539C8.72915 15.2446 8.62689 14.975 8.83141 14.9286C8.59901 14.8077 8.8407 14.7241 8.79422 14.6125C8.79422 14.6404 8.79422 14.6869 8.83141 14.7055C9.02663 14.8077 8.80352 14.4359 8.97085 14.4545C9.06381 14.4824 9.13818 14.6218 9.20325 14.5846C9.06381 14.4638 9.07311 14.1384 9.29621 14.2221C9.26832 14.2499 9.3334 14.315 9.37058 14.3801C9.42636 13.8502 10.0213 13.7851 10.0585 13.2274L10.2165 13.497C10.6813 13.5899 9.98412 13.0136 10.17 12.8927C10.6906 12.5952 11.425 12.5209 11.6853 12.0003C11.6574 11.9073 11.5923 11.9352 11.4994 11.8423C11.5645 11.8423 11.7411 12.0189 11.6853 11.8516L11.5645 11.74C12.0479 11.898 11.8898 11.0242 12.5034 11.4146C12.5034 11.0614 12.931 11.2752 12.8752 10.7918C13.0425 10.8383 12.9868 11.0707 13.1076 11.0242L13.1355 10.6524V10.6803C13.0054 10.1411 14.0186 10.6245 14.0279 10.1504V10.1783C14.1023 10.2712 14.251 10.327 14.2603 10.2619C14.2231 10.1876 14.1674 10.1783 14.0744 10.1318C14.1581 9.79712 14.2045 9.74135 14.3533 9.56472C14.3905 9.75994 14.5206 9.6112 14.6879 9.78783C14.6322 9.62979 14.502 9.62979 14.5113 9.44387C14.6415 9.29513 14.911 9.33232 15.0784 9.29513C14.9854 9.09062 15.0877 9.08132 14.9203 8.88611C15.0691 8.72807 15.097 8.57004 15.2922 8.40271L15.3573 8.46778C15.1992 8.1796 15.6361 8.43989 15.5525 8.26327C15.6268 8.35623 15.6361 8.41201 15.7012 8.46778L15.7198 8.30975C15.7384 8.4213 15.9243 8.6723 16.0173 8.63511C15.9429 8.39341 15.8964 8.53285 15.8035 8.36552L16.0266 8.57004C16.0638 8.49567 15.85 8.22608 15.7198 8.21679C15.9243 8.04016 16.0266 7.76128 16.2311 7.64043L16.3426 7.80776C16.3891 7.66832 16.5286 7.54747 16.6959 7.63113C16.6587 7.58465 16.6122 7.4824 16.5565 7.44521C16.5007 7.13844 16.7796 7.67761 16.7238 7.35225C16.7424 7.43592 16.7238 7.50099 16.7982 7.59395L16.8818 7.20351C16.9841 7.31507 17.3466 7.43592 17.3559 7.24999C17.3094 7.18492 17.2072 7.12914 17.17 7.13844L17.1886 7.02689L17.4675 7.2407L17.3652 6.93393L17.5511 7.14774C17.579 7.04548 17.3745 6.73871 17.4396 6.71082C17.7742 6.66434 17.7928 6.77589 18.1182 6.85026C17.7742 6.42264 18.3692 6.66434 18.1554 6.32968C18.6202 6.46912 18.7503 6.03221 19.0943 5.89277V5.94854C19.3825 6.0415 18.9641 5.52092 19.1594 5.50233L19.178 5.58599C19.5219 5.67896 19.6242 5.24204 19.6242 4.93527C19.6428 5.01893 19.7729 5.13978 19.8101 5.0933C19.7822 4.98175 19.5219 4.83301 19.6706 4.84231C19.6799 4.89808 19.7822 4.98175 19.8008 4.96316L19.7078 4.68427C20.0425 4.64709 20.4236 4.58202 20.5445 4.26595C20.6467 4.30313 20.6839 4.40539 20.7304 4.48906C20.8698 4.29384 20.8977 3.96847 21.0279 3.80115L21.251 4.03355C21.3254 3.96847 20.9907 3.62452 21.2696 3.75466C21.3161 3.76396 21.2138 3.82903 21.2696 3.95918C21.5856 4.00566 21.1673 3.64311 21.3346 3.54085L21.5299 3.84763C21.7809 3.9127 21.5392 3.59663 21.4462 3.39212C21.3346 2.93661 22.004 3.81974 22.0226 3.39212C21.9482 3.22479 21.8459 3.2062 21.7623 3.03887C21.9761 2.98309 21.8366 2.76928 22.0504 2.7135C22.4781 3.04816 21.9668 2.77858 22.3851 3.08535H22.1899C22.4688 3.22479 22.1434 3.22479 22.3665 3.45719C22.506 3.45719 22.4502 3.15971 22.4781 2.99239C22.6361 3.17831 22.3758 3.11323 22.6361 3.31775V3.1969C22.6547 3.26197 22.7105 3.33634 22.6733 3.35493C22.8313 3.51297 22.7384 3.31775 22.7848 3.27127C22.7105 3.16901 22.5896 3.03887 22.4688 2.92731C22.4874 2.9459 22.506 2.9645 22.5338 2.98309C22.413 2.63913 22.7477 2.69491 22.664 2.41603C22.6919 2.4811 22.7198 2.4904 22.7569 2.52758C22.822 2.4904 22.6826 2.19292 22.7105 2.05348C22.8685 2.15574 23.0265 2.4811 23.0916 2.29518C22.9894 2.12785 22.7105 1.91404 22.822 1.82108C22.822 1.82108 22.822 2.02559 22.9708 2.09066L22.9801 2.12785ZM20.8327 4.54483C20.8327 4.54483 20.8048 4.57272 20.7862 4.60061C20.7862 4.60061 20.8141 4.55413 20.8234 4.54483H20.8327ZM20.7769 4.8702C20.7769 4.8702 20.749 4.77723 20.6839 4.71216C20.6467 4.74005 20.6188 4.76794 20.5817 4.78653C20.6653 4.81442 20.749 4.81442 20.7769 4.8702ZM22.1341 5.67896L22.1527 5.70684C22.1527 5.70684 22.1248 5.76262 22.1155 5.78121C22.1527 5.8184 22.1992 5.84628 22.2085 5.79051C22.1899 5.76262 22.162 5.71614 22.1341 5.67896Z\" fill=\"#8F3A7E\"><\/path><path d=\"M22.0416 5.47307C22.0416 5.47307 22.0416 5.45466 22.0416 5.44546C22.0231 5.43626 22.0047 5.42705 21.9863 5.41785L22.0231 5.49148L22.0416 5.47307Z\" fill=\"#8F3A7E\"><\/path><path d=\"M4.04395 14.6689C4.04395 14.6689 4.05317 14.6597 4.06239 14.6413C4.06239 14.6505 4.05317 14.6597 4.04395 14.6689Z\" fill=\"#8F3A7E\"><\/path><path d=\"M17.3184 6.90505L17.365 6.96105L17.3464 6.89572L17.3184 6.90505Z\" fill=\"#8F3A7E\"><\/path><path d=\"M3.82129 12.9043C3.82129 12.9043 3.84973 12.8664 3.85921 12.8474C3.84973 12.8569 3.83077 12.8759 3.82129 12.9043Z\" fill=\"#8F3A7E\"><\/path><path d=\"M3.47742 12.3441L3.49602 12.2139C3.47742 12.279 3.47742 12.3162 3.47742 12.3441Z\" fill=\"#8F3A7E\"><\/path><path d=\"M3.28078 11.8598C3.28078 11.8598 3.21608 11.8967 3.18835 11.9152L3.28078 11.8598Z\" fill=\"#8F3A7E\"><\/path><path d=\"M6.45996 16.4436C6.45996 16.4436 6.54407 16.3969 6.57211 16.3875C6.57211 16.3408 6.55342 16.3221 6.45996 16.4436Z\" fill=\"#8F3A7E\"><\/path><path d=\"M6.62872 16.4611C6.62872 16.3873 6.6195 16.3781 6.57336 16.3873C6.57336 16.4242 6.58259 16.4703 6.62872 16.4611Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.17539 10.0107V9.98242C2.17539 9.98242 2.14712 10.0013 2.1377 10.0013H2.17539V10.0107Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.12949 10.0114H2.0918C2.0918 10.0114 2.10122 10.0208 2.12949 10.0114Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.00806 9.99291H2.09124C2.09124 9.99291 2.07275 9.96519 2.00806 9.99291Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.41699 10.6243L2.50017 10.5781C2.50017 10.5781 2.45396 10.5966 2.41699 10.6243Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.55659 10.7733C2.55659 10.7177 2.65855 10.5601 2.57513 10.5416L2.51025 10.5787C2.64001 10.5231 2.39903 10.8289 2.55659 10.7733Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.07381 12.1401L2.0366 11.9541C1.97149 12.0378 1.88778 12.1494 1.82268 12.0936C1.70176 12.4471 1.9808 11.9262 2.08311 12.1401H2.07381Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.27776 12.6685C2.18469 12.622 2.15677 12.7523 2.11023 12.7895C2.22192 12.7895 2.24984 12.7895 2.27776 12.6685Z\" fill=\"#8F3A7E\"><\/path><path d=\"M4.62895 15.747L4.43384 15.8864C4.50817 15.9235 4.50817 15.8306 4.62895 15.747Z\" fill=\"#8F3A7E\"><\/path><path d=\"M6.05145 15.5506L6.11649 15.4112L5.93066 15.5134L6.05145 15.5506Z\" fill=\"#8F3A7E\"><\/path><path d=\"M5.00248 16.9545H4.95605C5.00248 16.9638 5.0489 16.973 5.10461 17.0009C5.05819 16.973 5.03962 16.973 5.00248 16.9545Z\" fill=\"#8F3A7E\"><\/path><path d=\"M10.2145 16.5729L9.97351 16.4061C9.98278 16.471 10.2423 16.6842 10.2145 16.5729Z\" fill=\"#8F3A7E\"><\/path><path d=\"M11.8059 14.4079C11.9267 14.4915 12.0475 14.5101 11.9824 14.3708C11.9267 14.3986 11.7966 14.3615 11.8059 14.4079Z\" fill=\"#8F3A7E\"><\/path><path d=\"M18.3037 9.16579L18.3223 9.2774L18.3502 9.14719L18.3037 9.16579Z\" fill=\"#8F3A7E\"><\/path><path d=\"M1.64564 9.73384C1.52494 9.65027 1.46923 9.91025 1.50637 9.71527C1.6085 9.67813 1.69207 9.65956 1.64564 9.73384Z\" fill=\"#8F3A7E\"><\/path><path d=\"M25.5929 1.03314C25.7137 1.86049 24.812 1.67457 24.7376 2.32529C24.7097 2.38107 24.4959 2.01852 24.4587 2.16726C24.4587 2.88306 23.6872 3.09687 22.9807 3.13405L22.9342 3.0318C22.804 3.0318 22.9342 3.40364 22.8133 3.44083C22.7669 3.38505 22.7761 3.33857 22.6925 3.28279C22.8133 3.46871 22.5995 3.4966 22.6646 3.64534C22.5716 3.60815 22.4694 3.46871 22.3578 3.43153L22.4694 3.66393C22.7111 4.23099 22.1068 3.91493 22.1161 4.30536C22.0882 4.24959 22.0789 4.2031 22.0232 4.17522C21.9488 4.70509 21.5305 4.97468 21.2795 5.36512C21.233 5.29075 21.14 5.15131 21.0564 5.09553C21.2051 5.30934 21.1493 5.44878 21.0936 5.56963C20.8797 5.393 21.0936 5.8857 20.8983 5.8671L20.8704 5.81133C20.9727 6.09021 20.6473 5.78344 20.8054 6.09951L20.6195 5.97866C20.8333 6.29472 20.3778 5.92288 20.4428 6.1274L20.4986 6.18317C20.4986 6.30402 20.3406 6.18317 20.3313 6.28543L20.2941 6.25754C20.229 6.44346 20.0152 6.3505 20.2104 6.57361C20.0059 6.43417 20.2662 6.37839 19.9687 6.18317C19.7363 6.78742 19.2436 7.12208 18.816 7.50322C18.6859 7.45674 18.6301 7.45674 18.5464 7.38237C18.5464 7.46603 18.4163 7.56829 18.4814 7.71703C18.4906 7.69843 18.3512 7.62407 18.3233 7.63336C18.1746 7.61477 18.4535 7.95872 18.2768 7.93084C18.2582 7.83788 18.2118 7.75421 18.1281 7.67984C18.2025 7.92154 18.0816 7.97732 18.0444 8.10746C18.0258 8.06098 18.0258 8.0145 17.9608 7.94943C18.0351 8.22831 17.747 8.06098 17.7749 8.2562L17.6912 8.09817C17.4216 8.06098 17.8864 8.40494 17.6912 8.41423C17.6912 8.34916 17.6261 8.30268 17.5889 8.2469C17.6819 8.58156 17.4402 8.65593 17.403 8.82326C17.403 8.79537 17.3658 8.76749 17.3658 8.76749C17.2729 8.89763 17.0869 8.93481 17.0498 9.14862C16.9475 9.13003 16.7895 8.82326 16.7058 8.98129C16.9382 9.23229 16.585 9.27877 16.9196 9.50188C16.7802 9.54836 16.5199 9.60413 16.5292 9.75287C16.492 9.61343 16.1945 9.48328 16.2689 9.38103L16.0644 9.28807C15.9807 9.17651 16.1666 9.26018 16.0272 9.14862C15.99 9.19511 15.9528 9.41821 15.8784 9.40891C15.9342 9.64132 16.1201 10.0039 16.0179 10.1526C15.99 9.99457 15.7297 9.90161 15.7297 9.81794L15.9807 10.478C15.9435 10.5337 15.7855 10.2827 15.7855 10.4036C15.8506 10.4687 15.8599 10.5337 15.8877 10.6081C15.8413 10.5895 15.7669 10.8312 15.5159 10.6081C15.4043 10.5244 15.5438 10.4873 15.4136 10.4408C15.3393 10.5151 15.4136 10.6081 15.33 10.6825L15.3021 10.6546C15.2184 10.6639 15.237 10.9056 15.4229 10.9892C15.4694 10.9614 15.2742 10.8498 15.3951 10.8777C15.488 11.0543 15.4322 11.1845 15.3579 11.2588C15.3579 11.1938 15.2835 11.1287 15.2277 11.045C15.3021 11.3425 15.237 11.5098 15.1905 11.6958C15.2928 11.8166 15.0418 11.4355 15.1162 11.4819C14.8094 11.4541 15.0139 12.0118 14.6607 11.8817C14.6607 11.8445 14.828 12.0397 14.7908 12.0118C14.7071 12.0676 14.5491 11.891 14.5584 11.9932C14.4654 11.891 14.5305 12.0769 14.5026 12.1606C14.5398 12.2535 14.4469 12.1234 14.4747 12.0676C14.4747 12.2163 14.3446 12.6254 14.0564 12.6254C14.1215 12.6904 14.1866 12.96 14.1401 12.9879L14.0099 12.8206C13.8891 12.7555 13.8984 12.9507 13.7682 12.8206C13.8612 13.0809 13.9263 12.3837 13.9542 12.6254C13.8054 12.5231 14.0378 13.0065 13.8612 12.7741C13.7961 12.8485 13.8798 13.0902 13.6753 13.0065C13.7218 13.0065 13.5358 12.7369 13.4894 12.802C13.4057 12.9228 13.5265 12.9042 13.4894 13.0344V13.1459C13.6288 13.304 13.3871 13.211 13.5823 13.3412C13.4522 13.2296 13.4986 13.555 13.2755 13.2947L13.1082 13.0809C13.0803 13.1366 13.2291 13.3598 13.2755 13.4806C13.257 13.4713 13.2012 13.4341 13.1733 13.4062C13.4429 13.713 13.0431 13.4806 13.2105 13.7688C13.0153 13.7502 12.9595 13.9826 12.7364 13.8339C12.7457 13.9919 12.7829 14.1592 12.6434 14.1778C12.6341 14.1313 12.6434 14.1034 12.5876 14.0384C12.4575 14.0012 12.5133 14.0848 12.5133 14.1778C12.4854 14.122 12.2437 14.1034 12.0856 14.0477C12.1042 14.2057 12.2809 14.3451 12.3645 14.4474C12.0206 14.215 12.3459 14.8285 12.0113 14.6333C11.9927 14.5682 11.9741 14.3916 11.8439 14.373C11.5 14.1406 11.9276 14.717 11.6859 14.6705L11.9462 14.8843C11.751 14.7821 11.9369 15.1725 11.7045 14.9122C11.7603 15.033 11.5093 14.9494 11.751 15.1725C11.3884 15.1446 11.4814 15.6838 10.9608 15.3863C10.9794 15.4514 10.8772 15.47 11.0166 15.5722C11.1839 15.6559 10.9701 15.4235 11.0817 15.4979C11.0724 15.5257 11.1281 15.5908 11.1653 15.628C11.0631 15.628 11.0073 15.6559 10.8493 15.4142C10.589 15.3956 11.1467 15.9162 10.9236 15.972C10.8307 15.8697 10.7749 15.8511 10.7563 15.9069L10.8586 16.1393C10.7377 16.1951 10.5797 15.9905 10.3938 15.8418C10.3752 15.9162 10.3101 15.9812 10.4309 16.1114L10.1521 15.9905C10.3566 16.0742 10.2264 16.1207 10.245 16.1858L10.2171 16.1207C10.1335 16.0649 10.1242 16.1672 10.1242 16.2229C10.245 16.3066 10.338 16.2787 10.4031 16.2694C10.4588 16.3624 10.4031 16.3903 10.4681 16.5018C10.3008 16.3438 10.2729 16.4832 10.2264 16.5111C10.1521 16.5297 10.3473 16.6878 10.3287 16.697C10.2357 16.6227 10.2543 16.7621 10.1521 16.6227C10.1335 16.5855 10.2729 16.6506 10.2078 16.5669C10.1149 16.5483 9.95684 16.4182 10.0219 16.5669C10.0684 16.6878 10.3845 16.8272 10.1985 16.8365C10.1706 16.7807 10.1056 16.7156 10.0498 16.6506L9.89177 16.6692L10.0591 16.7993C10.0126 16.7807 10.0033 16.7621 9.97543 16.7528C10.1428 16.8923 9.90106 16.9666 10.0591 17.1711C10.0219 17.2641 9.83599 17.2455 9.77092 17.3106V17.2827C9.62218 17.2827 9.61288 17.4686 9.65936 17.6638L9.63148 17.6267C9.63148 17.6267 9.53852 17.8033 9.585 18.0078C9.41767 18.0264 9.06442 17.3199 9.15738 17.7196C9.1016 17.8498 9.28752 18.3425 9.38978 18.4261C9.18526 18.5284 9.23174 19.3743 8.94357 19.207C8.97145 19.3743 9.00864 19.4208 8.99005 19.5974C8.77624 19.9228 8.70187 21.1313 8.42298 20.6851C8.44158 20.3783 8.35791 20.2482 8.31143 19.9972C8.33002 20.3597 8.26495 20.0158 8.26495 20.1087C8.26495 20.1366 8.27425 20.211 8.29284 20.3783C8.33002 20.6014 8.34862 20.7594 8.3765 20.8896C8.3951 20.9732 8.41369 21.029 8.45087 21.0383C8.45087 21.0941 8.43228 21.1406 8.42298 21.2057C8.36721 21.2428 8.30214 21.2149 8.22777 21.1499C8.19058 21.1127 8.16269 21.0662 8.12551 21.0197C8.08833 20.9454 8.05114 20.8524 8.03255 20.7687C8.08833 20.9732 8.06973 21.029 8.03255 21.0848C7.99536 20.5828 7.88381 20.3783 7.80015 20.4434V20.7316L7.72578 20.3597C7.69789 20.4155 7.70719 20.9268 7.60493 20.5363C7.60493 20.4248 7.58634 20.3039 7.57704 20.2017C7.49338 20.3318 7.33534 20.5363 7.24238 20.1831L7.17731 19.6997C7.17731 19.6997 7.03787 19.8298 7.11224 20.025C6.9542 19.5881 6.84265 19.4301 6.84265 19.0768C6.44292 19.4673 5.89445 18.863 5.55049 18.3796L5.63416 18.2681C5.60627 18.0357 5.44824 18.4168 5.42964 18.2495C5.5319 18.1751 5.5226 17.9241 5.68064 17.8684C5.64345 17.5988 5.38316 17.8684 5.25302 17.8126C5.12287 17.9427 5.39246 17.8126 5.23443 17.9706C5.17865 17.9985 5.14146 17.636 4.93695 17.8126C4.97413 17.6917 5.14147 17.5802 5.23443 17.5151H5.0671C5.20654 17.1897 5.66205 17.3478 5.82938 16.9387L5.74571 16.9016C5.89445 16.6413 6.09896 16.8272 6.04319 16.6041C5.90374 16.6413 5.55979 16.8458 5.5412 17.0038C5.35528 16.8923 5.00202 17.3664 4.85329 17.1433C4.92765 16.9852 5.02062 17.2827 5.15076 17.0968C5.23443 16.8551 4.91836 17.0038 4.93695 16.9016C4.90906 17.0317 4.64877 17.1433 4.5837 17.134C4.62088 16.9852 4.8161 17.0224 4.76032 16.9016C4.62088 16.9852 4.46285 16.9666 4.44426 17.1154C4.13749 17.3013 4.44426 16.948 4.17467 17.0689C4.342 16.883 4.70455 16.8086 4.71384 16.6227C4.53722 16.79 4.3513 16.6878 4.11889 16.9759C4.13749 16.8923 4.27693 16.7621 4.42567 16.7063C4.49074 16.5483 3.96086 16.8272 4.31411 16.5111L4.1096 16.6413C4.15608 16.5762 4.18397 16.5018 4.25834 16.3903C4.22115 16.3345 3.8586 16.4182 4.14678 16.1951C4.1003 16.1951 4.01664 16.0649 3.84931 16.2694C3.79353 16.4461 4.06312 16.2415 3.83072 16.5018C4.00734 16.2694 3.70987 16.4089 3.59831 16.4275L3.70057 16.3345C3.6355 16.3345 3.60761 16.2601 3.47746 16.3345C3.56113 16.3066 3.6262 16.2322 3.6355 16.1858L3.44028 16.288C3.26365 16.2415 3.71916 16.0277 3.58902 15.9534L3.78424 15.9255C3.78424 15.9255 3.8772 15.7674 3.78424 15.7581C3.60761 15.8604 3.3938 15.972 3.26365 16.0463C3.1521 16.0463 3.42169 15.879 3.20788 15.9441L3.45887 15.8697C3.52395 15.8418 3.67268 15.6094 3.60761 15.535C3.51465 15.535 3.22647 15.6187 3.19858 15.7674C3.1614 15.7303 3.21717 15.6001 3.35662 15.5443C3.22647 15.4979 3.19858 15.6838 3.04055 15.6838C3.11492 15.5722 3.18929 15.3491 3.29154 15.1725L3.61691 15.0516L3.57972 14.9959C3.84931 14.9029 3.70987 14.8378 3.96086 14.6984C3.96086 14.6333 3.8586 14.6519 3.77494 14.6519C3.50535 15.0423 3.18929 14.9029 2.89181 15.1911C2.6873 15.1074 3.60761 14.4846 2.97548 14.717C2.9104 14.8099 2.60363 14.9215 2.77096 14.9494C2.73378 14.8285 2.39912 15.1353 2.4456 14.9215C2.64082 14.9029 2.70589 14.5775 2.99407 14.5497C2.88252 14.624 2.96618 14.6798 3.01266 14.6705C3.10562 14.5404 3.34732 14.4288 3.27295 14.3265C3.19858 14.2894 3.12421 14.215 2.96618 14.3544C2.78026 14.5032 3.05914 14.4288 2.83603 14.5404C2.678 14.4753 2.94759 14.2336 2.58504 14.4381C2.6687 14.4939 2.49208 14.6612 2.36193 14.7542L2.2132 14.7263L2.35264 14.6519C2.33405 14.4474 2.09235 14.7821 2.02727 14.624L2.22249 14.373C2.45489 14.2429 2.27827 14.6426 2.60363 14.3544C2.54786 14.2522 2.35264 14.3544 2.38053 14.2057C2.42701 14.2057 2.45489 14.2243 2.49208 14.215C2.48278 14.1778 2.9104 13.7967 2.54786 13.871C2.39912 13.8896 2.40841 13.9454 2.27827 14.0384C2.12953 13.9268 1.9715 13.9826 1.87854 13.9082C2.14812 13.7409 1.78558 13.7316 2.12024 13.6386C2.00868 13.7967 2.17601 13.9919 2.45489 13.8617C2.71519 13.5829 2.50138 14.0012 2.82674 13.806C2.75237 13.6851 3.04984 13.4713 3.22647 13.304C3.21717 13.2668 3.11492 13.2947 3.06844 13.304C2.87322 13.4248 2.9104 13.462 2.72448 13.6107C2.678 13.4434 2.49208 13.3969 2.25968 13.462C2.31545 13.3505 2.51067 13.2296 2.56645 13.2668C2.39912 13.1552 2.30616 12.9786 2.25968 12.7927C2.02727 13.1088 2.07376 12.6811 1.86924 12.9321C1.85995 13.0623 1.69262 13.2854 1.52529 13.3412C1.50669 13.2761 1.65543 13.2482 1.71121 13.1831C1.4974 13.2389 1.90643 12.8949 1.59965 13.0251C1.79487 13.0995 1.99009 12.7834 2.24108 12.644C2.03657 12.644 2.40841 12.5231 2.34334 12.4301C2.13883 12.4301 1.94361 12.3744 1.81346 12.3C1.94361 12.0025 1.56247 11.9375 1.46951 11.8166C1.54388 11.6679 1.85065 11.5284 1.84135 11.4262C1.77628 11.3425 1.59036 11.6865 1.62754 11.4819L1.69262 11.4541C1.59965 11.4541 1.7205 11.1008 1.30218 11.3239L1.62754 11.1659C1.62754 11.1659 1.55317 11.1473 1.51599 11.1473C1.60895 11.0822 1.68332 10.9985 1.76698 10.9892C1.92502 10.7754 1.62754 10.8498 1.56247 10.7661L1.42303 10.9335C1.19063 10.8777 1.30218 10.6639 1.15344 10.5616L1.33007 10.4594L1.17203 10.4408C1.35796 10.3571 1.42303 10.2177 1.2464 10.2549L1.81346 10.2084C1.74839 10.3292 1.56247 10.2735 1.41373 10.4129C1.28359 10.5337 1.41373 10.6453 1.59036 10.5523C1.58106 10.4873 1.53458 10.5152 1.45092 10.5152C1.68332 10.3478 1.7205 10.4315 1.90643 10.3664C1.87854 10.3478 1.93431 10.2642 1.85065 10.3106C1.99939 10.2827 2.05516 10.3292 2.11094 10.4036C1.98079 10.4036 1.98079 10.5337 1.89713 10.5523C2.11094 10.4222 2.23179 10.4594 2.24108 10.5988C2.04587 10.8312 2.52926 10.6825 2.53856 10.8498C2.29686 10.9428 2.08305 10.9985 1.95291 10.98C1.89713 11.1287 2.01798 11.0636 1.95291 11.2124C2.13883 11.138 2.38982 11.0078 2.55715 11.0357L2.40841 11.1473C2.54786 11.1845 2.78026 11.0171 2.80815 11.1566C2.86392 11.3983 3.00336 11.5935 3.08703 11.7515L2.93829 11.8631C3.31943 11.705 3.25436 12.0397 3.47746 12.0397C3.46817 12.3279 3.91438 12.3279 3.71916 12.6161C4.07241 12.8485 4.39778 13.0437 4.593 13.4062L4.3327 13.5178C4.53722 13.4527 4.23974 13.6479 4.31411 13.6851C4.43496 13.4806 4.60229 13.5922 4.76962 13.5271C4.71384 13.806 5.03921 13.8524 5.2902 13.8617L5.14146 13.9826C5.5226 13.8896 5.40176 14.2429 5.48542 14.4381C5.43894 14.5032 5.31809 14.6426 5.37387 14.6798C5.68064 14.5775 5.69923 14.6333 5.95022 14.6426C6.02459 14.7356 6.08967 14.9308 6.07107 15.1074C6.37784 15.1446 6.55447 15.3026 6.7125 15.47C6.80546 15.5722 6.84265 15.6094 6.87983 15.6373C6.92631 15.6652 6.98209 15.6838 7.05646 15.6745L6.92631 15.8697C7.14942 15.7674 7.1866 15.7953 7.24238 15.8883C7.28886 15.972 7.34464 16.1114 7.40971 15.9998L7.32605 16.4925C7.34464 16.7063 7.4283 16.4646 7.4469 16.0649C7.46549 16.2694 7.51197 15.8604 7.53056 16.3624C7.56774 16.5111 7.56774 16.13 7.57704 16.0649C7.60493 16.2137 7.63282 16.288 7.65141 16.3066C7.67 16.3066 7.67 16.2137 7.67 16.13V16.1021C7.67 16.2508 7.70719 16.5297 7.72578 16.5483C7.72578 16.4739 7.72578 16.4554 7.72578 16.4368C7.73507 16.3996 7.74437 16.3438 7.6607 15.8976C7.70719 16.0742 7.71648 15.9441 7.71648 15.8511C7.71648 15.7581 7.71648 15.6931 7.80944 15.879C7.75367 15.7303 7.75367 15.6931 7.71648 15.5908C7.72578 15.5536 7.9024 15.7488 7.80015 15.5071C7.84663 15.5536 7.9117 15.7117 7.93959 15.7024C7.921 15.6466 7.84663 15.5536 7.80944 15.4793C7.76296 15.3491 7.80944 15.377 7.89311 15.3956C7.93959 15.4607 8.19988 15.2747 8.27425 15.1353C8.47876 14.4753 9.01793 14.057 9.39907 13.6015L9.46415 13.6665C9.35259 13.2761 10.0405 13.5829 9.78021 13.1088C9.87317 13.1366 9.93825 13.0158 10.0312 13.1645C9.96614 12.8857 10.496 13.0251 10.4402 12.6532C10.4216 12.6532 10.4216 12.6811 10.4402 12.7276C10.7377 12.7183 10.6912 12.3837 10.9887 12.3558C10.998 12.4023 10.9887 12.4487 11.0445 12.5231C11.2304 12.5882 10.9329 12.0955 11.2676 12.3837C11.3048 12.3465 11.1467 12.1977 11.1281 12.2256C11.6115 12.0118 11.8161 11.4355 12.1321 11.0078C12.5876 10.9428 12.6434 11.5377 12.6434 11.0915C12.7178 11.138 12.5412 10.9521 12.6062 11.0171C12.6062 10.8498 13.071 11.2588 12.9688 11.0357C12.7643 10.8591 12.9037 10.887 12.8014 10.7661C13.0896 10.7383 13.2848 10.887 13.2848 10.6174L13.3685 10.729C13.257 10.292 13.5823 10.2827 13.4057 9.81794C14.2237 8.972 14.8838 8.03309 15.7111 7.24293C16.6221 6.56431 17.3193 5.69048 18.3419 5.13271C18.7881 5.24427 18.7974 5.21638 18.9183 4.9189C18.9462 4.97468 18.9462 4.99327 18.9926 5.02116C18.8067 4.77946 19.1321 4.86313 18.9647 4.62143C19.3273 4.38903 19.569 4.07296 19.8944 3.79408C19.8665 3.85915 19.9966 4.07296 20.0431 4.00789L19.978 3.80337L20.0431 3.85915C20.0524 3.78478 20.0059 3.63604 19.8944 3.59886C20.5544 2.69714 21.7722 2.47403 22.5437 1.73034C22.8226 1.66527 23.0178 1.34921 23.1945 1.1168C24.0776 0.902993 24.8492 0.689183 25.3047 -0.0545044C25.3047 -0.0545044 25.723 0.62411 25.5836 0.977361L25.5929 1.03314Z\" fill=\"#8F3A7E\"><\/path><path d=\"M1.7481 9.85501C1.62739 9.95715 1.59954 10.0778 1.38599 10.115C1.50669 10.0314 1.61811 9.91072 1.7481 9.85501Z\" fill=\"#8F3A7E\"><\/path><path d=\"M1.8506 12.8295C1.8506 12.8295 1.82275 12.8945 1.80418 12.9131C1.77632 12.8945 1.65562 12.9409 1.70204 12.8759C1.7299 12.8945 1.78561 12.8481 1.8506 12.8202V12.8295Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.16678 13.4147C2.05536 13.489 1.87895 13.4425 1.82324 13.3775L2.16678 13.4147Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.08289 14.2437C2.02718 14.3551 1.96219 14.383 1.92505 14.318C1.98076 14.2715 2.02718 14.2715 2.08289 14.2437Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.35372 14.0857C2.35372 14.0857 2.33511 14.188 2.28857 14.2625C2.38165 14.188 2.15827 14.216 2.35372 14.0857Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.84607 15.3857C2.84607 15.3857 3.00391 15.3857 2.90178 15.5064C2.96677 15.4135 2.66966 15.4878 2.84607 15.3857Z\" fill=\"#8F3A7E\"><\/path><path d=\"M3.39329 15.7397C3.39329 15.7397 3.384 15.7861 3.43043 15.7769C3.40257 15.8418 3.30044 15.879 3.27258 15.8604L3.39329 15.7397Z\" fill=\"#8F3A7E\"><\/path><path d=\"M11.9369 14.7541L11.9462 14.8467L11.8535 14.7448L11.9369 14.7541Z\" fill=\"#8F3A7E\"><\/path><path d=\"M15.4611 11.4917C15.4611 11.3803 15.5818 11.5567 15.6003 11.5659C15.5632 11.6124 15.5075 11.4267 15.4611 11.4917Z\" fill=\"#8F3A7E\"><\/path><path d=\"M16.957 9.2601L16.9477 9.27864L16.7716 9.06546L16.957 9.2601Z\" fill=\"#8F3A7E\"><\/path><path d=\"M26.4111 1.45928C26.4761 1.32929 26.2068 1.32001 26.4111 1.32001C26.4668 1.41286 26.5039 1.49642 26.4111 1.45928Z\" fill=\"#8F3A7E\"><\/path><path d=\"M1.08847 10.4673C1.92512 10.4673 1.62764 11.3319 2.27837 11.4713C2.33415 11.4992 1.95301 11.6851 2.10174 11.7316C2.81754 11.7967 2.97558 12.5682 2.97558 13.2747L2.86402 13.3119C2.86402 13.4514 3.23587 13.3305 3.26375 13.4514C3.20798 13.4979 3.1615 13.4886 3.09642 13.5629C3.29164 13.4514 3.30094 13.6652 3.45897 13.6094C3.42179 13.6931 3.27305 13.7953 3.23587 13.9069L3.47756 13.8046C4.06322 13.5908 3.70997 14.1765 4.1097 14.1858C4.05392 14.2137 4.00744 14.2229 3.97026 14.2694C4.50013 14.3624 4.75113 14.79 5.13227 15.0596C5.0486 15.0968 4.91846 15.1897 4.85338 15.2734C5.07649 15.1247 5.20664 15.1897 5.32749 15.2548C5.15086 15.4686 5.64355 15.2548 5.61566 15.4593L5.55989 15.4872C5.84807 15.3943 5.532 15.7103 5.84807 15.5616L5.72722 15.7475C6.05258 15.543 5.66214 15.9892 5.86666 15.9334L5.92244 15.8777C6.04328 15.8777 5.92244 16.0357 6.0154 16.0543L5.98751 16.0915C6.17343 16.1658 6.06188 16.361 6.28498 16.1658C6.14554 16.3703 6.10836 16.1193 5.90384 16.4168C6.4895 16.6492 6.74049 17.049 7.08445 17.458C7.08445 17.6532 7.11233 17.7369 7.10304 17.8949C7.14952 17.8577 7.25178 17.9879 7.30755 17.8112C7.29826 17.8112 7.30755 18.0529 7.33544 18.0994C7.40051 18.3504 7.4284 17.6997 7.48418 17.9786C7.45629 18.0715 7.4377 18.2017 7.44699 18.3783C7.52136 18.1087 7.59573 18.2482 7.6608 18.211C7.6608 18.2853 7.64221 18.3132 7.64221 18.462C7.69799 18.118 7.80024 18.7316 7.84673 18.527V18.7966C7.99546 19.2893 7.82813 18.276 7.9025 18.3783C7.9025 18.5084 7.92109 18.6107 7.93039 18.7408C7.93039 18.3597 7.93969 18.2017 7.96757 18.0715C7.98617 17.9693 8.01406 17.8949 8.02335 17.7648C8.02335 17.8019 8.04194 17.8763 8.04194 17.8763C8.07913 17.6904 8.17209 17.6904 8.19068 17.3743C8.24646 17.4208 8.33942 17.9414 8.39519 17.7183C8.23716 17.2628 8.46027 17.3 8.23716 16.9188C8.31153 16.8909 8.46956 16.8537 8.45097 16.6771C8.49745 16.8537 8.72056 17.0211 8.68337 17.1605C8.73915 17.207 8.79493 17.2535 8.86 17.3C8.94366 17.458 8.77633 17.3464 8.90648 17.5045C8.93437 17.4208 8.94366 17.1047 9.00874 17.1047C8.93437 16.8073 8.72985 16.4261 8.76704 16.2774C8.82282 16.4354 9.06451 16.5098 9.08311 16.5935C8.97155 16.3703 8.84141 16.1658 8.70197 15.9892C8.71126 15.9427 8.92507 16.1472 8.89718 16.0264C8.82281 15.9799 8.79493 15.9148 8.75774 15.8498C8.80422 15.8498 8.8507 15.5895 9.12959 15.7754C9.25043 15.8405 9.12959 15.8962 9.25973 15.9148C9.3248 15.8219 9.24114 15.7475 9.29692 15.6545L9.3341 15.6824C9.41776 15.6545 9.36199 15.4221 9.16677 15.3664C9.12029 15.4036 9.3341 15.4779 9.21325 15.4779C9.0924 15.3106 9.13888 15.1711 9.21325 15.0875C9.23184 15.1526 9.30621 15.2083 9.36199 15.2827C9.25043 14.9945 9.29692 14.8179 9.3341 14.6134C9.21325 14.5018 9.51073 14.8551 9.42706 14.8179C9.73383 14.7993 9.49213 14.2694 9.86398 14.3531C9.86398 14.3903 9.68735 14.2044 9.72454 14.2415C9.8082 14.1765 9.97553 14.3438 9.96623 14.2415C10.0685 14.3345 9.99412 14.1486 10.0127 14.0742C9.96623 13.9812 10.0778 14.1114 10.0406 14.1579C10.022 14.0091 10.1522 13.5815 10.4496 13.5629C10.3846 13.4979 10.3102 13.2283 10.3567 13.2004L10.4868 13.3677C10.6077 13.4235 10.5984 13.2376 10.7285 13.3584C10.6263 13.0981 10.5798 13.8139 10.5426 13.5629C10.6913 13.6652 10.4496 13.1725 10.6356 13.4049C10.7006 13.3305 10.6077 13.0888 10.8215 13.1632C10.775 13.1632 10.9609 13.4328 11.0167 13.3677C11.0911 13.2376 10.9795 13.2655 11.0167 13.1353V13.0238C10.868 12.8657 11.1282 12.9587 10.9237 12.8192C11.0539 12.9308 11.0074 12.5961 11.2305 12.8564L11.3978 13.0702C11.4257 13.0145 11.277 12.7913 11.2305 12.6705C11.2584 12.6798 11.3049 12.7077 11.3328 12.7449C11.0539 12.4381 11.4629 12.6705 11.3049 12.3823C11.5001 12.4009 11.5559 12.1685 11.779 12.308C11.7697 12.1499 11.7325 11.9733 11.8812 11.964C11.8905 12.0105 11.8812 12.0384 11.9277 12.1034C12.0671 12.1406 12.0021 12.0477 12.0021 11.9547C12.03 12.0105 12.2717 12.0384 12.4297 12.0848C12.4204 11.9268 12.2438 11.7874 12.1601 11.6758C12.5041 11.9175 12.188 11.2947 12.5227 11.4899C12.532 11.555 12.5505 11.7316 12.6807 11.7595C13.0246 12.0012 12.6156 11.4155 12.8573 11.462L12.597 11.2389C12.7829 11.3505 12.6249 10.9507 12.848 11.211C12.8015 11.0902 13.0525 11.1738 12.8201 10.9414C13.1827 10.9879 13.1455 10.4208 13.6475 10.7555C13.6382 10.6904 13.7404 10.6718 13.6103 10.5603C13.443 10.458 13.6382 10.709 13.5359 10.6347C13.5545 10.6068 13.4987 10.5324 13.4709 10.4952C13.5731 10.4952 13.6382 10.4766 13.7683 10.7276C14.0286 10.7648 13.5173 10.1977 13.7683 10.1513C13.852 10.2628 13.8985 10.2907 13.9357 10.2256L13.8706 9.97463C14.01 9.91886 14.1402 10.1513 14.2982 10.3279C14.3261 10.2535 14.4005 10.1977 14.3075 10.049L14.5678 10.207C14.3819 10.0955 14.5213 10.0583 14.5027 9.99323V10.0583C14.5864 10.1234 14.6143 10.0211 14.6236 9.97463C14.5213 9.87238 14.4191 9.89097 14.354 9.89097C14.3168 9.78871 14.3726 9.77012 14.3261 9.64927C14.4655 9.8259 14.5213 9.68646 14.5864 9.66786C14.6701 9.66786 14.5027 9.46335 14.5306 9.45405C14.6143 9.53772 14.6236 9.39828 14.6979 9.55631C14.6979 9.60279 14.5864 9.50983 14.6236 9.61209C14.7165 9.64927 14.8467 9.8073 14.8188 9.63068C14.7909 9.50053 14.5027 9.30532 14.6979 9.32391C14.7072 9.38898 14.763 9.46335 14.8002 9.53772H14.9675L14.8374 9.38898C14.8839 9.41687 14.8839 9.43546 14.9118 9.45405C14.7909 9.26813 15.0047 9.27743 14.8653 9.08221C14.8932 9.02643 15.0605 9.1008 15.1163 9.08221V9.1008C15.2557 9.14728 15.2743 9.01714 15.2278 8.8777L15.2557 8.91488C15.2557 8.91488 15.3487 8.81262 15.3022 8.69177C15.4788 8.73826 15.8414 9.25884 15.7577 8.98925C15.8321 8.91488 15.6276 8.59881 15.5067 8.52444C15.7391 8.50585 15.6647 8.11542 16.0087 8.24556C15.9715 8.1619 15.925 8.13401 15.9343 8.06894C16.1853 7.95738 16.1946 7.51117 16.6222 7.6785C16.6222 7.79935 16.7524 7.83653 16.836 7.92949C16.7617 7.74357 17.022 8.02246 16.836 7.77146C16.7059 7.63202 16.6501 7.55765 16.5479 7.55765C16.6036 7.38103 16.7803 7.22299 16.9662 7.29736C16.8732 7.26018 16.8639 7.1951 16.8546 7.13003C17.0406 7.36243 17.1614 7.31595 17.1614 7.18581L17.0499 7.03707L17.2172 7.13933C17.2079 7.07425 16.9941 6.82326 17.18 6.89763C17.2265 6.94411 17.2823 6.99989 17.3287 7.02777C17.3008 6.85115 17.2358 6.58156 17.4124 6.62804L17.6448 6.77678C17.6541 6.7303 17.6076 6.56297 17.5054 6.55367C17.7378 6.56297 17.8307 6.50719 18.0259 6.64664C17.8772 6.03309 18.1933 5.73562 18.4722 5.5497L18.5558 5.66125C18.7046 5.69843 18.435 5.44744 18.5558 5.47533C18.6209 5.59618 18.7882 5.64266 18.844 5.80999C19.0392 5.83788 18.8161 5.52181 18.844 5.41955C18.7417 5.27081 18.8626 5.5497 18.7324 5.36377C18.7046 5.308 18.9648 5.35448 18.7975 5.13137C18.8905 5.18715 19.002 5.35448 19.0578 5.45674L19.0299 5.308C19.3088 5.48462 19.2251 5.88436 19.5598 6.10746L19.5877 6.0238C19.8201 6.19113 19.6435 6.39564 19.848 6.34916C19.8201 6.20042 19.6156 5.85647 19.4854 5.80999C19.5598 5.64266 19.1229 5.27081 19.2809 5.16856C19.4204 5.26152 19.1972 5.28941 19.3646 5.43814C19.5691 5.5497 19.4111 5.23363 19.5226 5.24293C19.3925 5.21504 19.2716 4.96404 19.2809 4.88967C19.4297 4.92686 19.4018 5.12208 19.5133 5.057C19.4297 4.92686 19.4389 4.75953 19.2902 4.74094C19.095 4.44346 19.4575 4.73164 19.3367 4.47135C19.5319 4.62938 19.6063 4.99193 19.8015 5.00123C19.6249 4.8339 19.7271 4.63868 19.4389 4.41557C19.5226 4.43417 19.6528 4.57361 19.7178 4.71305C19.8759 4.77812 19.5784 4.25754 19.913 4.6015L19.7736 4.39698C19.848 4.44346 19.913 4.46205 20.0246 4.53642C20.0804 4.48994 19.9781 4.13669 20.2198 4.42487C20.2198 4.37839 20.3407 4.29472 20.1362 4.13669C19.9595 4.08091 20.1733 4.3505 19.9038 4.12739C20.1362 4.29472 19.9874 4.00655 19.9688 3.89499L20.0711 3.99725C20.0618 3.93218 20.1455 3.90429 20.0618 3.77414C20.099 3.85781 20.164 3.92288 20.2105 3.93218L20.099 3.74626C20.1362 3.56963 20.3686 4.01584 20.4336 3.8857L20.4615 4.08091C20.4615 4.08091 20.6196 4.16458 20.6288 4.07162C20.5266 3.90429 20.3964 3.69048 20.3221 3.56033C20.3221 3.44878 20.4894 3.70907 20.415 3.50456L20.4987 3.75555C20.5266 3.81133 20.759 3.96007 20.8334 3.89499C20.8334 3.80203 20.7311 3.51385 20.5824 3.49526C20.6196 3.45808 20.7497 3.50456 20.8148 3.644C20.8612 3.51385 20.666 3.48596 20.666 3.32793C20.7869 3.4023 21.0007 3.46737 21.1866 3.56033L21.3168 3.8857L21.3725 3.83922C21.4748 4.09951 21.5399 3.96936 21.6793 4.21106C21.7444 4.21106 21.7258 4.1088 21.7165 4.01584C21.3168 3.76485 21.4376 3.44878 21.1401 3.1606C21.2145 2.95609 21.8745 3.84851 21.6142 3.22567C21.5213 3.1606 21.3911 2.86313 21.3725 3.03046C21.4934 2.99327 21.168 2.66791 21.3818 2.70509C21.4097 2.90031 21.7351 2.95609 21.7816 3.23497C21.6979 3.12342 21.6514 3.20708 21.6607 3.25356C21.8002 3.34652 21.921 3.57893 22.014 3.49526C22.0419 3.42089 22.1162 3.34652 21.9675 3.18849C21.8095 3.01186 21.8931 3.28145 21.7816 3.06764C21.8373 2.90961 22.0883 3.1699 21.8652 2.80735C21.8187 2.89101 21.6421 2.72369 21.5399 2.59354L21.5585 2.4448L21.6421 2.57495C21.8466 2.54706 21.5027 2.32395 21.6514 2.24958L21.9117 2.43551C22.0511 2.66791 21.6514 2.50058 21.9489 2.81665C22.0419 2.76087 21.9303 2.56565 22.079 2.58424C22.079 2.63072 22.0697 2.65861 22.079 2.6958C22.1162 2.6772 22.516 3.09553 22.423 2.74228C22.4044 2.59354 22.3393 2.61213 22.2371 2.48199C22.3393 2.33325 22.2743 2.17522 22.3393 2.08226C22.5253 2.34255 22.5067 1.98 22.6275 2.30536C22.4602 2.2031 22.2836 2.37973 22.4323 2.64932C22.7205 2.89101 22.2928 2.6958 22.5067 3.01186C22.6182 2.9282 22.8506 3.21638 23.0272 3.38371C23.0644 3.37441 23.0272 3.27215 23.0272 3.22567C22.8971 3.03975 22.8599 3.07694 22.7019 2.90031C22.8599 2.84453 22.8971 2.64932 22.8227 2.42621C22.9343 2.48199 23.0644 2.66791 23.0365 2.72369C23.1388 2.55636 23.3061 2.4448 23.4827 2.38903C23.1574 2.17522 23.5757 2.19381 23.3247 2.00789C23.1946 2.00789 22.9715 1.84985 22.8971 1.69182C22.9622 1.67323 22.9994 1.82196 23.0737 1.85915C22.9994 1.65464 23.3712 2.03577 23.2225 1.7383C23.1667 1.94281 23.4827 2.11014 23.6501 2.35184C23.6408 2.14733 23.7802 2.50988 23.8732 2.43551C23.8639 2.23099 23.8918 2.03577 23.9568 1.90563C24.2636 2.00789 24.2915 1.63604 24.4031 1.52449C24.5611 1.58956 24.7284 1.87774 24.8307 1.85915C24.905 1.78478 24.5425 1.63604 24.7563 1.65464L24.7842 1.71041C24.7656 1.62675 25.1375 1.71041 24.8679 1.31068L25.0631 1.61745C25.0631 1.61745 25.0724 1.54308 25.0631 1.5059C25.1374 1.58956 25.2304 1.65464 25.2397 1.7383C25.4721 1.86845 25.3606 1.58027 25.4349 1.51519L25.249 1.39434C25.2769 1.15265 25.5 1.24561 25.5744 1.07828L25.7045 1.23631V1.07828C25.8068 1.24561 25.9648 1.29209 25.8997 1.12476L26.0299 1.67323C25.8997 1.62675 25.9276 1.43153 25.7696 1.30138C25.6301 1.18983 25.5465 1.32927 25.6487 1.4966C25.7045 1.47801 25.6859 1.44083 25.6673 1.35716C25.8625 1.56167 25.7882 1.61745 25.8811 1.78478C25.8997 1.75689 25.9834 1.79408 25.9369 1.71971C25.9834 1.86845 25.9462 1.92422 25.8718 1.98929C25.8532 1.85915 25.7324 1.87774 25.6952 1.79408C25.8532 1.98929 25.8254 2.11014 25.6859 2.13803C25.4349 1.9707 25.6301 2.43551 25.4628 2.46339C25.342 2.23099 25.2676 2.02648 25.2676 1.88704C25.1189 1.84985 25.1932 1.96141 25.0445 1.91493C25.1375 2.09155 25.2955 2.33325 25.2769 2.50058L25.1467 2.36114C25.1282 2.50058 25.3048 2.71439 25.1653 2.77017C24.9236 2.84453 24.7377 3.00257 24.589 3.09553L24.4588 2.95609C24.6448 3.32793 24.3008 3.28145 24.3101 3.50456C24.0219 3.50456 24.0498 3.96007 23.7523 3.78344C23.5385 4.15528 23.3619 4.48994 22.9994 4.70375L22.8785 4.45276C22.9529 4.65727 22.7391 4.3598 22.7112 4.44346C22.9157 4.55502 22.8134 4.72234 22.8878 4.88967C22.6089 4.84319 22.581 5.17785 22.5717 5.42885L22.4416 5.28941C22.5438 5.67055 22.1906 5.55899 21.9954 5.64266C21.9303 5.59618 21.7816 5.48462 21.7537 5.5404C21.8652 5.84717 21.8095 5.86576 21.8002 6.11676C21.7072 6.19113 21.512 6.2655 21.3446 6.2469C21.2796 6.86974 20.7497 6.95341 20.5638 7.4554L20.3964 7.30666C20.3593 7.95738 19.6528 7.99457 19.5226 8.44078L19.2995 8.12471C19.1322 8.12471 19.1508 8.385 19.3553 8.56163C19.188 8.56163 19.2437 8.89629 18.9834 8.71037C18.844 8.73825 18.9834 8.94277 18.937 9.04503C18.6581 9.1008 18.6023 9.18447 18.4722 9.38898L18.5279 9.37039C18.4907 9.28672 18.3885 9.16588 18.3327 9.18447C18.3327 9.32391 18.0259 9.31461 18.3885 9.60279C18.0259 9.56561 18.091 10.1513 17.6727 10.0397C17.7657 10.1234 17.7378 10.1791 17.7749 10.2535C17.6169 10.4023 17.273 10.3651 17.2823 10.644C17.2172 10.6161 17.1893 10.4487 17.1056 10.4952C17.1056 10.5696 17.2079 10.6161 17.2079 10.709C17.0963 11.1181 16.5107 11.0065 16.3062 11.2668C16.0366 11.8246 15.5067 12.1406 15.1349 12.5404L15.0791 12.466C15.172 12.8471 14.5213 12.4939 14.763 12.9773C14.6701 12.9401 14.6143 13.0609 14.5213 12.9122C14.5771 13.1911 14.0658 13.0238 14.1123 13.3956C14.1309 13.3956 14.1309 13.3677 14.1123 13.3212C13.8148 13.3212 13.8706 13.6466 13.5731 13.6745C13.5638 13.628 13.5731 13.5815 13.5173 13.5071C13.3314 13.4421 13.6289 13.9255 13.2942 13.6373C13.257 13.6745 13.4151 13.8232 13.4337 13.7953C12.9503 14.0091 12.7551 14.5762 12.4669 14.9945C12.03 15.0596 11.937 14.4832 11.9649 14.9109C11.8905 14.8644 12.0671 15.041 12.0021 14.9759C12.0021 15.134 11.5373 14.7528 11.6488 14.9666C11.8626 15.134 11.7232 15.1061 11.8347 15.2269C11.5559 15.2548 11.3514 15.1247 11.3792 15.385L11.2863 15.2734C11.435 15.6917 11.1282 15.7196 11.3606 16.1472C11.2026 16.361 11.0539 16.5749 10.9237 16.7887L10.4403 17.6625C9.91975 18.5456 9.60369 20.0423 9.12029 21.4367C8.99014 21.7993 8.8507 22.1618 8.72056 22.5151L8.33942 22.0874L7.89321 21.5762L7.00078 20.5536C6.41513 19.8657 5.80159 19.1127 5.281 18.3225C5.20664 17.6439 5.20664 17.6625 4.77902 17.3743C4.83479 17.3464 4.86268 17.365 4.89057 17.3C4.76972 17.3929 4.70465 17.3185 4.64887 17.2628C4.61169 17.2256 4.5745 17.1791 4.45365 17.2628C4.23055 16.9002 3.92378 16.6399 3.64489 16.296C3.70997 16.3332 3.93307 16.203 3.868 16.1472L3.66349 16.203L3.71926 16.1379C3.64489 16.1193 3.49616 16.1658 3.44968 16.2774C2.55725 15.5709 2.37133 14.3345 1.66483 13.5071C1.60905 13.219 1.30228 12.9959 1.08847 12.8006C0.930435 11.8617 0.790994 11.0902 0.0751953 10.4116C0.0751953 10.4116 0.828178 10.1513 1.16284 10.3558L1.08847 10.4673Z\" fill=\"#8F3A7E\"><\/path><path d=\"M26.3094 1.58132C26.1885 1.47901 26.0676 1.47901 25.9932 1.27438C26.0955 1.3767 26.235 1.46971 26.3094 1.58132Z\" fill=\"#8F3A7E\"><\/path><path d=\"M23.3623 1.9979C23.3623 1.9979 23.2973 1.97005 23.2695 1.96076C23.288 1.93291 23.223 1.8122 23.2973 1.85863C23.2787 1.88648 23.3345 1.94219 23.3623 1.9979Z\" fill=\"#8F3A7E\"><\/path><path d=\"M22.8039 2.34232C22.7203 2.2309 22.7574 2.06377 22.8131 1.99878V2.34232H22.8039Z\" fill=\"#8F3A7E\"><\/path><path d=\"M21.9853 2.29645C21.8739 2.24074 21.846 2.18504 21.9018 2.13861C21.9482 2.19432 21.9575 2.23146 21.9853 2.29645Z\" fill=\"#8F3A7E\"><\/path><path d=\"M22.1544 2.56585C22.1544 2.56585 22.052 2.55654 21.9775 2.51001C22.052 2.59377 22.0241 2.37971 22.1544 2.56585Z\" fill=\"#8F3A7E\"><\/path><path d=\"M20.8979 3.10465C20.8979 3.10465 20.8979 3.26249 20.7772 3.16965C20.8701 3.22535 20.7772 2.93752 20.8979 3.10465Z\" fill=\"#8F3A7E\"><\/path><path d=\"M20.5632 3.65382C20.5632 3.65382 20.5168 3.65382 20.5261 3.69096C20.4611 3.6631 20.424 3.57025 20.4425 3.53311L20.5632 3.65382Z\" fill=\"#8F3A7E\"><\/path><path d=\"M12.5693 11.3684V11.275L12.6534 11.3871L12.5693 11.3684Z\" fill=\"#8F3A7E\"><\/path><path d=\"M9.03711 14.8652C9.05568 14.9767 8.90712 14.8188 8.88855 14.8188C8.9164 14.7631 8.99997 14.9488 9.03711 14.8652Z\" fill=\"#8F3A7E\"><\/path><path d=\"M8.21887 17.2635V17.2357L8.33029 17.5885L8.21887 17.2635Z\" fill=\"#8F3A7E\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Competitive Pricing<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"27\" height=\"23\" viewBox=\"0 0 27 23\" fill=\"none\"><path d=\"M26.5504 1.48711C26.5133 1.41296 26.3928 1.2832 26.3743 1.33881L26.5411 1.59833V1.48711H26.5504Z\" fill=\"#8F3A7E\"><\/path><path d=\"M25.9092 1.28207C25.9556 1.43991 26.067 1.68132 26.2806 1.8763C26.1413 1.60704 26.2342 1.69061 26.0577 1.3842C26.0763 1.31921 26.197 1.40277 26.262 1.49562C26.2249 1.42134 26.3734 1.49562 26.262 1.32849C26.0577 1.18922 25.9835 1.23565 26.0392 1.4492C25.9835 1.41206 25.9463 1.33778 25.9092 1.29136V1.28207Z\" fill=\"#8F3A7E\"><\/path><path d=\"M19.0215 6.23586C19.0215 6.23586 19.0215 6.18064 19.0031 6.16223C19.0031 6.18984 19.0031 6.21746 19.0215 6.23586Z\" fill=\"#8F3A7E\"><\/path><path d=\"M18.3794 6.34023C18.3794 6.34023 18.4077 6.34023 18.4171 6.34023C18.3888 6.3308 18.37 6.32138 18.3794 6.34023Z\" fill=\"#8F3A7E\"><\/path><path d=\"M21.5952 4.26723L21.465 4.24863C21.5208 4.33234 21.5487 4.27653 21.5952 4.26723Z\" fill=\"#8F3A7E\"><\/path><path d=\"M25.8363 2.31298C25.8363 2.31298 25.8363 2.25752 25.8178 2.22055C25.8178 2.23904 25.8178 2.25752 25.8086 2.27601L25.8363 2.31298Z\" fill=\"#8F3A7E\"><\/path><path d=\"M22.5358 3.16046L22.5544 3.14186C22.5544 3.14186 22.5172 3.07675 22.4893 3.03024L22.5358 3.16046Z\" fill=\"#8F3A7E\"><\/path><path d=\"M23.3447 2.4166C23.3447 2.4166 23.4749 2.63052 23.5493 2.72353C23.4935 2.63052 23.4749 2.58401 23.4749 2.54681C23.447 2.50961 23.4005 2.4631 23.3447 2.4166Z\" fill=\"#8F3A7E\"><\/path><path d=\"M21.8932 3.61673C21.8932 3.61673 21.8372 3.56072 21.8279 3.55139C21.8465 3.57939 21.8745 3.59806 21.8932 3.61673Z\" fill=\"#8F3A7E\"><\/path><path d=\"M0.799326 11.6575C0.799326 11.6575 0.827596 11.6386 0.837019 11.6292C0.808749 11.6292 0.789903 11.648 0.799326 11.6575Z\" fill=\"#8F3A7E\"><\/path><path d=\"M1.21851 9.87102L1.24636 9.8803L1.37635 9.81531L1.21851 9.87102Z\" fill=\"#8F3A7E\"><\/path><path d=\"M10.5801 13.1525C10.8215 13.2453 10.6636 13.4868 10.9608 13.561C10.8772 13.496 10.7843 13.1711 10.5801 13.1525Z\" fill=\"#8F3A7E\"><\/path><path d=\"M25.7896 2.30579C25.7896 2.30579 25.7708 2.32463 25.752 2.33406C25.7708 2.33406 25.7802 2.31521 25.7896 2.30579Z\" fill=\"#8F3A7E\"><\/path><path d=\"M15.7295 8.4028C15.7295 8.4028 15.7942 8.45826 15.8219 8.47674C15.8034 8.45826 15.7757 8.43977 15.7295 8.4028Z\" fill=\"#8F3A7E\"><\/path><path d=\"M15.2939 9.27798C15.2939 9.27798 15.2285 9.25931 15.2285 9.30598C15.2378 9.30598 15.2472 9.31531 15.2565 9.32465C15.2378 9.28731 15.2379 9.26865 15.2939 9.27798Z\" fill=\"#8F3A7E\"><\/path><path d=\"M14.5957 9.90973C14.5957 9.90973 14.6241 9.92869 14.6431 9.93817V9.90973H14.5957Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.6049 13.9609C2.65136 13.8959 2.7071 13.8401 2.76285 13.7844C2.62348 13.9051 2.48412 13.8401 2.6049 13.9609Z\" fill=\"#8F3A7E\"><\/path><path d=\"M25.7432 2.19324C25.7802 2.24883 25.7988 2.27662 25.7895 2.29515L25.808 2.26736C25.808 2.26736 25.7617 2.21177 25.7432 2.19324Z\" fill=\"#8F3A7E\"><\/path><path d=\"M16.6315 10.8466L16.4922 10.9116C16.5386 10.9116 16.585 10.8745 16.6315 10.8466Z\" fill=\"#8F3A7E\"><\/path><path d=\"M7.79133 20.2916H7.76367C7.76367 20.2916 7.79133 20.3285 7.79133 20.2916Z\" fill=\"#8F3A7E\"><\/path><path d=\"M16.1947 11.2389C16.1111 11.1924 16.0554 11.1645 16.0089 11.1552C16.0089 11.1738 16.0275 11.1924 16.0368 11.2203L16.1854 11.2389H16.1947Z\" fill=\"#8F3A7E\"><\/path><path d=\"M1.95357 13.227C1.75835 13.1898 1.98146 13.1526 2.08371 12.9109C1.81413 13.0132 2.08371 12.7343 1.70258 12.9946C1.91639 12.7808 1.83272 12.8551 1.96287 12.6599C1.78624 12.8366 1.66539 12.6599 1.42369 12.8458C1.67469 12.6227 1.85131 12.725 2.06512 12.4275C1.83272 12.4926 1.68398 12.4275 1.37721 12.6227C1.4051 12.5205 1.49806 12.4275 1.47947 12.3253C1.47017 12.3532 1.53525 12.3253 1.57243 12.316C1.27496 12.316 1.33073 11.972 0.912408 12.1393C1.36792 11.8698 0.76367 11.7954 1.23777 11.6281C1.18199 11.5816 0.931 11.6095 0.838039 11.6374C1.18199 11.4143 0.828743 11.4328 0.986776 11.2283C0.772966 11.3213 0.76367 11.1633 0.614933 11.1726C0.680005 11.1726 0.745078 11.154 0.828743 11.0889C0.642821 11.0982 0.782262 11.0331 0.912408 10.8658C0.745078 10.8286 0.661413 11.0517 0.456899 11.0889C0.475491 10.9494 0.670709 10.9401 0.800854 10.8379L0.363938 10.9216C0.38253 10.8751 0.438307 10.81 0.531268 10.7449C0.401123 10.7542 0.224497 10.8007 0.354642 10.6334L0.438307 10.7449L0.59634 10.5962H0.280273C0.429011 10.2244 0.856631 10.0849 1.24707 9.88969L1.35862 9.92688C1.48877 9.85251 1.53525 9.75955 1.51665 9.72236C1.59102 9.64799 2.00005 9.61081 2.08371 9.65729C2.17668 9.8804 1.67469 9.95476 1.66539 10.1593L2.00005 10.2151L1.8792 10.2987C1.81413 10.3824 1.96287 10.3173 2.00005 10.2987C1.80483 10.401 2.03723 10.4939 2.05583 10.5869L2.19527 10.4568C2.70655 10.4196 2.01864 11.0517 2.33471 11.0982L2.67866 11.0331L2.46485 11.219C2.65078 11.1911 2.8367 11.0796 2.8367 11.2469C2.70655 11.9255 3.50602 11.9999 3.5525 12.5763C3.59898 12.5391 3.59898 12.5112 3.61757 12.4647C3.3108 13.2363 4.59366 12.567 4.39844 13.2084L4.29618 13.2549C4.46351 13.3757 4.19393 13.3014 4.15674 13.5059C4.44492 13.3199 4.51929 13.5431 4.68662 13.5616C4.62155 13.5895 4.60295 13.5616 4.53788 13.5616C4.4914 13.6267 4.33337 13.7569 4.41703 13.7662C4.88184 13.5709 5.01198 13.8126 5.24438 13.8777C5.08635 14.0357 5.03058 14.296 4.80747 14.5935C4.88184 14.5563 5.03987 14.482 5.1979 14.4076C5.13283 14.5563 5.25368 14.5284 5.38383 14.4913C5.33735 14.4448 5.30016 14.3983 5.27227 14.3704H5.29087C5.29087 14.3704 5.26298 14.3611 5.25368 14.3518C5.2165 14.3239 5.1979 14.3146 5.18861 14.3332C5.30946 14.138 5.32805 14.231 5.53256 14.0636C5.56975 14.1194 5.71849 14.1752 5.57904 14.3053C5.59764 14.3425 5.59764 14.3797 5.57904 14.4355C5.62552 14.4355 5.66271 14.4355 5.66271 14.4727H5.63482C5.63482 14.4727 5.59764 14.5284 5.57904 14.547C5.57904 14.7144 5.98807 14.6121 6.20188 14.5842C5.87652 14.7051 5.9323 14.8352 5.73708 14.9839C5.75567 14.9839 5.6906 14.8724 5.58834 14.7423C5.57904 14.7701 5.55116 14.798 5.48608 14.8538C5.37453 15.1234 5.81145 14.9003 5.80215 15.1792C5.77426 15.1792 5.70919 15.1978 5.65341 15.2628C5.65341 15.3651 5.83933 15.3 5.96018 15.2164C5.79285 15.3744 5.75567 15.6068 5.88582 15.5975C6.08103 15.5324 6.14611 15.4673 6.20188 15.5789L6.03455 15.644C6.01596 15.8485 6.29484 15.5882 6.26695 15.7648C6.28555 15.6905 6.14611 15.7927 6.14611 15.8392C6.31344 15.895 6.3971 15.8578 6.70387 15.709L6.49936 15.8671C6.67598 15.8485 6.97346 15.6997 6.73176 15.9693C7.08501 15.551 7.00135 15.8485 7.03853 15.9043C7.01994 15.9043 6.95487 15.9972 6.91768 16.053C7.18727 15.8113 7.05712 16.211 7.15938 16.3133L7.03853 16.7874C7.1036 16.8432 7.3453 15.9136 7.36389 15.96L7.30812 16.1831C7.38249 16.1831 7.40108 16.2482 7.44756 16.4063L7.41967 16.7874C7.45685 16.6387 7.48474 16.6758 7.50333 16.5085C7.52193 17.0291 7.587 16.9826 7.63348 16.9175C7.66137 16.8804 7.67996 16.8711 7.70785 16.9175C7.72644 16.9175 7.75433 17.0012 7.81011 17.2522L7.69855 16.4248C7.69855 16.4248 7.69855 16.4063 7.69855 16.397C7.70785 16.3505 7.71714 16.3226 7.81011 16.7409C7.91236 17.3173 7.83799 16.6944 7.87518 16.7874C7.87518 16.6944 7.80081 16.3319 7.77292 16.2482C7.91236 16.462 7.88447 15.9972 8.16336 16.3784C8.18195 16.0437 7.96814 15.6626 8.0611 15.6161L8.10758 15.6533C8.10758 15.6533 8.20054 15.6626 8.2935 15.6905C8.40506 15.6905 8.55379 15.7183 8.72112 15.8392C8.79549 15.5882 8.44224 15.1048 8.78619 14.9932L8.86986 15.142C8.98141 15.142 8.90704 14.9189 8.88845 14.8631C8.91634 14.8445 8.96282 14.9189 9.00001 14.9561C9.14874 14.9932 9.0093 14.8166 9.0186 14.7515L9.11156 14.8631C9.47411 14.8631 9.30678 14.231 9.56707 14.0543C9.56707 14.1194 9.68792 14.2031 9.75299 14.2403C9.50199 13.8405 9.81806 13.6639 9.83665 13.5059L9.91102 13.6825C9.87384 13.3014 10.3944 13.8684 10.3572 13.4873L10.0784 13.3943C10.1992 13.3757 10.1992 13.2642 10.0412 13.134C10.2271 13.1619 10.2922 13.3757 10.4502 13.2828C10.5432 13.3664 10.4223 13.4315 10.5803 13.5059L10.9801 13.5895C10.9801 13.5895 11.0358 13.5895 11.0637 13.5152C10.6547 13.1154 11.1846 13.3571 10.7105 13.0411C10.9243 12.7808 11.3798 12.8644 11.4077 12.4833C11.8725 12.8087 11.826 12.1208 12.2908 12.6599C12.4117 12.5577 12.4117 12.3625 12.2908 12.0929C12.2257 12.0743 12.2629 12.1672 12.2629 12.2137C12.17 12.0557 12.2908 11.8976 12.3466 11.8512C12.3838 12.0371 12.3466 12.2602 12.4767 12.5112C12.5325 12.3625 12.5046 12.0278 12.4953 11.9162L12.7742 12.1579C12.6813 11.8791 13.0531 12.3067 12.8951 11.9627L12.8021 11.8976C12.9787 11.7675 12.737 11.4979 12.8579 11.3213L12.9508 11.4328C13.0438 11.4328 12.8858 11.1075 13.1647 11.3027L13.0717 11.405C13.2576 11.5816 13.4064 11.6002 13.5272 11.6652C13.583 11.5165 13.2855 11.3213 13.3134 11.2469C13.4993 11.405 13.4064 11.3399 13.5272 11.5444C13.583 11.3771 13.6759 11.154 13.5551 10.8472C13.583 10.8751 13.6202 10.9123 13.6202 10.9123C13.7689 10.8286 13.5923 10.4103 13.7968 10.4939V10.5404C14.1314 10.717 13.8247 10.0663 14.2523 10.4939C14.3731 10.5311 14.1314 10.5683 14.401 10.7263C14.6706 10.7356 14.1593 10.2615 14.401 10.2708C14.3731 10.2708 14.401 10.2987 14.4289 10.3452C14.5126 10.2522 14.5963 10.0942 14.6613 9.95476C15.1168 10.2058 14.9681 9.51785 15.498 9.81532C15.3121 9.70377 15.3771 9.61081 15.3213 9.53644C15.3213 9.53644 15.3492 9.58292 15.3771 9.60151C15.4422 9.56433 15.3213 9.41559 15.2842 9.34122C15.4422 9.43418 15.3028 9.07164 15.4143 9.12741C15.3306 9.03445 15.3957 9.01586 15.4422 8.97867C15.4422 9.17389 15.5909 9.21108 15.6839 9.397C15.8698 9.32263 15.4794 8.82994 15.6839 8.77416L15.9256 8.88571C15.7025 8.59754 15.9349 8.58824 15.8419 8.48598C15.9442 8.55105 16.0279 8.56965 16.1394 8.70909C16.1394 8.58824 16.3532 8.65331 16.2324 8.46739L16.1115 8.4488C16.3904 8.39302 16.1487 7.90033 16.4555 7.95611L16.818 8.37443C17.0597 8.45809 16.7901 7.99329 17.0969 8.17921C16.9482 8.06766 16.9761 8.11414 16.9203 7.91892C16.8552 7.91892 16.8831 8.08625 16.8273 8.13273L16.7436 7.77948L16.6507 8.06766C16.5949 7.83526 16.6228 7.87244 16.4462 7.74229C16.4462 7.5006 16.7529 7.82596 16.7251 7.56567C16.818 7.58426 16.9017 7.77018 17.0225 7.81666C16.9946 7.58426 17.478 7.94681 17.3572 7.65863C17.4223 7.67722 17.3293 7.70511 17.413 7.79807C17.4409 7.70511 17.5059 7.67722 17.413 7.53778H17.32C17.3758 7.50989 17.2363 7.33327 17.4223 7.35186C17.3944 7.21242 17.2456 6.98002 17.1899 7.0265C17.1899 6.98002 17.3386 7.04509 17.4316 7.18453C17.5803 7.06368 17.1155 6.68254 17.4316 6.75691C17.4316 6.7755 17.4316 6.81269 17.4687 6.83128C17.5338 6.83128 17.5617 6.80339 17.5617 6.75691C17.4687 6.90565 17.8871 7.05438 17.6733 7.11016C17.8778 7.31467 17.822 7.05438 17.9428 7.11016C17.8871 6.89635 17.6733 6.7848 17.6175 6.64536C17.6733 6.71972 17.7104 6.69184 17.7662 6.69184L17.5896 6.5524C17.5896 6.5524 17.6547 6.50591 17.6547 6.43155V6.5524C17.7476 6.52451 18.073 6.71043 18.0544 6.44084C18.0823 6.5338 18.1381 6.71973 18.2868 6.74761C18.324 6.5338 18.3798 6.79409 18.5564 6.85917C18.6493 6.71043 18.324 6.5431 18.5936 6.48732C18.6122 6.46873 18.5099 6.38507 18.4541 6.35718C18.6493 6.32929 18.6215 6.15266 18.8446 6.17126C18.7516 6.17126 18.6586 6.15266 18.6679 6.01322C18.7516 6.18055 18.8817 6.0597 19.0026 6.09689L18.9468 6.00393C19.0584 6.0597 19.0491 6.13407 19.0491 6.18985C19.0212 6.16196 18.9933 6.14337 18.9747 6.17126C18.9747 6.2921 19.2722 6.58958 19.393 6.5431C19.4302 6.37577 19.2164 6.16196 19.1327 6.09689C19.3466 6.069 18.9282 5.60419 19.1792 5.62279C19.2071 5.5949 19.5975 5.84589 19.7184 5.79941C19.6068 5.56701 19.4767 5.75293 19.393 5.54842C19.9601 5.89237 19.4674 4.97206 19.9229 5.08361L20.0995 5.3439C20.1646 5.31602 20.2204 5.29742 20.2576 5.22305L20.0809 5.15798C20.0809 5.06502 20.239 5.00924 20.3505 5.22305C20.2948 4.93488 20.4156 5.02784 20.5736 5.00924C20.4528 5.08361 20.5457 4.98136 20.5736 5.16728C20.7874 5.18587 20.7317 5.10221 20.7596 4.98136C20.8153 5.07432 20.9641 5.16728 21.0013 5.13939C20.9455 4.92558 21.1035 4.85121 21.1407 4.68388L21.1965 4.75825C21.2894 4.52585 21.7542 4.69318 21.7542 4.33993C21.7542 4.33993 21.7542 4.33063 21.7542 4.32133H21.7264C21.4754 4.14471 21.7264 4.05175 21.7078 3.91231C21.7635 3.95879 21.8565 4.05175 21.8844 4.02386C21.7078 3.81005 21.8565 3.85653 21.8007 3.73568C21.9216 3.75427 22.0052 3.99597 22.0982 3.89371C22.1261 3.83794 22.0331 3.72638 21.968 3.65202C22.0796 3.73568 22.219 3.77286 22.2934 3.74498C22.3213 3.81934 22.2283 3.77286 22.2283 3.79146C22.312 3.91231 22.3213 3.83794 22.4329 3.97738C22.4979 3.94949 22.2841 3.76357 22.405 3.79146L22.4886 4.00527C22.5444 4.02386 22.5165 3.9309 22.5258 3.91231C22.5258 3.98667 22.6746 4.14471 22.7582 4.23767C22.7954 3.99597 22.4143 3.76357 22.2655 3.57765C22.5072 3.59624 22.4236 3.28947 22.5165 3.19651L22.6653 3.41032C22.6931 3.33595 22.6746 3.27088 22.6281 3.17791L22.7024 3.11284C22.721 3.22439 22.7582 3.29876 22.8791 3.4568C22.9163 3.33595 23.0743 3.28947 22.8791 3.01058L22.9163 3.05707C23.1022 3.05707 23.3811 2.92692 23.4461 3.01988C23.4926 2.83396 23.7715 2.86185 23.5577 2.60156C23.5763 2.48071 24.0225 2.78748 23.7994 2.41564C24.0225 2.51789 23.8645 2.48071 23.9946 2.69452C24.2177 2.79677 23.9388 2.28549 24.2828 2.63874C24.2828 2.44352 24.1991 2.58296 24.0876 2.38775C24.3943 2.71311 24.3107 2.29479 24.571 2.41564C24.4966 2.23901 24.4594 2.35986 24.4036 2.15534C24.4687 2.24831 24.5245 2.22971 24.5431 2.22971L24.3757 1.99731L24.9149 2.45282C24.8405 2.08098 24.571 2.09957 24.6732 1.84857V1.87646C24.9149 2.06238 24.6732 1.59758 24.9428 1.66265C24.8591 1.66265 25.0079 1.7835 25.0451 1.85787V1.70913C25.0451 1.70913 25.0544 1.74632 25.0822 1.76491C25.2868 1.87646 25.0636 1.62547 25.2589 1.70913C25.2403 1.7928 25.3983 1.95083 25.482 2.00661L25.3797 1.67195L25.5842 2.00661C25.7051 1.94153 25.4727 1.33729 25.8631 1.69984L25.8445 1.7835C25.9096 1.84857 26.1234 2.04379 26.0676 1.82998C26.0676 1.7742 25.9282 1.58828 25.9096 1.62547L26.0211 1.65336C26.1513 1.86717 26.0676 2.0345 26.0304 2.15534C25.9933 2.05309 26.0026 1.94153 25.8817 1.82998C25.8631 1.95083 25.9003 2.14605 25.8817 2.2669C25.8445 2.16464 25.7609 2.0252 25.7051 1.94153C25.5377 1.90435 25.7609 2.12746 25.7051 2.19253C25.6214 2.13675 25.5563 2.09957 25.5192 2.0252C25.5192 2.16464 25.4634 2.23901 25.3053 2.20182C25.3053 2.20182 25.2775 1.98801 25.138 1.91365C25.0915 2.15534 25.2589 2.41564 25.2124 2.67593C25.3053 3.15003 24.6918 2.76889 24.7662 3.11284C24.8312 3.2058 24.9893 3.18721 24.9521 3.30806C24.822 3.12214 24.8127 3.23369 24.7476 3.16862C24.8684 3.49398 24.571 3.2244 24.6546 3.4475C24.6174 3.37313 24.5059 3.35454 24.4222 3.31736C24.2549 3.09425 24.2549 3.31736 24.1247 2.89903C24.2642 3.33595 23.818 3.01988 24.134 3.59624L24.2177 3.62413H23.9946L24.0039 3.63342C23.9202 3.64272 23.9574 3.70779 23.6878 3.54976C23.6785 3.46609 23.725 3.42891 23.7157 3.34524C23.4833 3.2151 23.6971 3.63342 23.6321 3.70779C23.5019 3.54976 23.6692 3.58694 23.4833 3.41032C23.4089 3.42891 23.4554 3.58694 23.4368 3.6799L23.3718 3.58694C23.065 3.50328 23.6785 4.06104 23.3253 3.85653C23.3718 3.90301 23.4089 3.96808 23.4554 4.01456C23.3439 3.95879 23.1208 3.87512 23.1208 3.6892C23.0743 3.72638 23.0836 3.85653 23.1394 3.96808C23.2881 4.06104 23.2416 3.98667 23.3996 4.13541L23.2788 4.38641C23.2788 4.38641 23.223 4.28415 23.2509 4.26556C22.6374 3.99597 23.1115 5.04643 22.3864 4.71177C22.5351 4.83262 22.47 4.85121 22.5258 4.97206C22.405 4.99995 22.312 5.13939 22.154 5.1208L22.0982 4.99995C21.9959 5.28813 21.9866 5.55771 21.81 5.60419C21.8379 5.65067 21.6892 5.46475 21.6892 5.41827C21.7449 5.67856 21.15 5.21376 21.4382 5.61349H21.5032C21.2615 5.71575 21.2708 6.16196 21.1221 6.37577C20.8897 6.18985 21.2151 6.25492 20.9455 6.02252C20.7317 6.05041 20.7503 6.35718 20.5457 6.41295C20.5457 6.36647 20.5179 6.33859 20.5179 6.31999C20.2483 6.3014 20.7224 6.5338 20.5736 6.59888C20.49 6.47803 20.4528 6.45943 20.3691 6.44084L20.4807 6.65465C20.4807 6.65465 20.3319 6.48732 20.3041 6.42225C20.4528 6.70113 20.146 6.68254 20.2948 6.94283C20.239 6.89635 20.0902 6.66395 19.9973 6.58958C19.8764 6.58958 19.9043 6.71043 19.9322 6.83128C19.7556 6.71043 19.6626 6.83128 19.6626 6.7848C19.4767 6.81269 19.7463 6.92424 19.7742 7.13805L19.9508 7.15664L19.83 7.35186L19.8021 7.18453C19.6533 7.16594 19.737 7.42623 19.644 7.5006L19.7928 7.59356L19.7556 7.76089C19.5232 7.50989 19.5697 7.81666 19.3651 7.46341C19.0584 7.4913 19.235 7.94681 19.077 8.11414C19.1049 8.08625 19.0491 8.04907 19.0212 7.99329C18.8725 8.02118 18.9282 8.2071 18.984 8.39302C18.9282 8.30006 18.9282 8.25358 18.8632 8.17921C18.7423 8.28147 18.9189 8.39302 18.8632 8.57894C18.8074 8.4395 18.7423 8.39302 18.6865 8.39302C18.7795 8.48598 18.8074 8.57894 18.8074 8.62542C18.4541 8.02118 18.4727 8.54176 18.1845 8.07695C18.2775 8.1978 18.2682 8.59754 18.5099 8.75557V8.6812C18.6401 8.82064 18.5471 8.81135 18.5099 8.84853C18.5099 8.81135 18.5006 8.75557 18.4727 8.72768C18.4355 9.06234 18.1009 9.07164 18.0079 9.37841C17.98 9.31333 17.98 9.146 17.8871 9.146C17.6175 9.24826 17.729 9.6294 17.6361 9.93617C17.3386 9.61081 17.822 9.69447 17.5524 9.36911C17.3944 9.6387 17.2735 9.94547 17.1806 10.3266C16.6693 9.91758 17.1155 10.7356 16.6321 10.4846C16.7901 10.6334 16.7622 10.7542 16.6879 10.8379C16.5949 10.6799 16.5112 10.7542 16.4462 10.6334C16.502 10.8472 16.3532 11.0889 16.0836 10.7635C16.3346 11.0796 15.9163 10.8844 16.0557 11.154C15.8605 11.1168 15.9163 11.3864 15.7304 11.3957C15.9442 11.5537 15.7025 11.5909 15.7304 11.7024C15.7304 11.6838 15.7304 11.6281 15.7025 11.6095C15.5166 11.47 15.7025 11.8698 15.5537 11.8326C15.4608 11.7861 15.405 11.6467 15.3399 11.6745C15.4608 11.814 15.4329 12.1208 15.2191 12.0092C15.247 11.9813 15.1912 11.9162 15.154 11.8419C15.0704 12.3439 14.494 12.3439 14.4382 12.9016L14.2802 12.6227C13.8247 12.5019 14.494 13.1061 14.3174 13.2177C13.8061 13.478 13.0903 13.5524 12.8207 14.0636C12.8486 14.1566 12.9137 14.1287 13.0066 14.2217C12.9508 14.2217 12.7649 14.045 12.8207 14.2124L12.9415 14.3239C12.4489 14.1659 12.6441 15.0304 12.0212 14.6493C12.0398 15.0025 11.6029 14.7887 11.6866 15.2721C11.5192 15.2349 11.5564 15.0025 11.4449 15.0583V15.4209V15.393C11.6401 15.9043 10.5896 15.4859 10.6547 15.96V15.9321C10.5617 15.8485 10.413 15.8113 10.413 15.8764C10.4595 15.9414 10.5153 15.9414 10.6082 15.9879C10.5803 16.3226 10.5525 16.3691 10.4409 16.555C10.3665 16.3784 10.2736 16.5271 10.0784 16.3877C10.162 16.5271 10.2922 16.5178 10.3201 16.6944C10.2178 16.8525 9.99469 16.8153 9.78088 16.9826C9.89243 17.1964 9.78088 17.2615 9.9668 17.4567C9.80877 17.7821 9.75299 18.0052 9.56707 18.4886L9.51129 18.4049C9.66003 18.879 9.251 18.6094 9.32537 18.9162C9.26959 18.7582 9.2603 18.6559 9.19522 18.5629L9.17663 18.8976C9.15804 18.6652 9.00001 18.2469 8.92564 18.3398C8.99071 18.7953 9.02789 18.4979 9.10226 18.8232L8.91634 18.47C8.88845 18.6187 9.05578 19.1486 9.16733 19.1021C8.99071 19.5483 8.86986 20.3013 8.69323 20.6546L8.62816 20.2362C8.58168 20.5709 8.47013 20.8963 8.37717 20.701C8.37717 20.6732 8.35857 20.6546 8.35857 20.636C8.37717 20.7568 8.37717 20.9706 8.41435 21.1101C8.35858 21.5842 8.31209 20.45 8.25632 20.9706C8.27491 20.8498 8.3028 20.7847 8.27491 20.5523C8.24702 20.6267 8.21913 20.6917 8.19125 20.7568C8.17265 20.7847 8.16336 20.8126 8.14477 20.8405H8.0704C8.03321 20.5802 7.8194 19.8272 7.70785 19.8923C7.70785 20.0224 7.75433 20.2455 7.78222 20.3106L7.69855 20.3292L7.62418 19.7157C7.587 19.8272 7.54982 19.9388 7.51263 20.041V19.6041C7.42897 19.6041 7.38249 20.0968 7.29882 19.9667C7.03853 19.3717 7.1036 19.3066 6.98275 18.7396C6.84331 19.4182 6.71317 18.3863 6.55513 18.8139C6.45288 18.0517 6.01596 17.9215 5.77426 17.4381H5.83004C5.87652 17.0756 5.42101 17.5869 5.34664 17.3173L5.4396 17.2987C5.45819 17.0849 5.32805 16.9175 5.18861 16.8432C5.05846 16.7688 4.87254 16.7409 4.71451 16.7409C4.80747 16.7223 4.92832 16.5922 4.87254 16.555C4.75169 16.5829 4.60295 16.8339 4.62155 16.6851C4.67732 16.6758 4.76099 16.5829 4.7424 16.555L4.46351 16.6387C4.43563 16.2947 4.37985 15.9136 4.07308 15.7834C4.11026 15.6812 4.22182 15.6533 4.29618 15.6068C4.11026 15.4581 3.7849 15.4209 3.61757 15.2814L3.84997 15.0676C3.7849 14.9839 3.43165 15.3186 3.57109 15.0397C3.58968 14.9932 3.64546 15.0955 3.7756 15.0397C3.84068 14.733 3.45954 15.1327 3.36658 14.9561L3.68264 14.7794C3.75701 14.5284 3.43165 14.7608 3.22713 14.8445C2.76233 14.9282 3.68264 14.3053 3.25502 14.2682C3.08769 14.3425 3.0598 14.4355 2.89247 14.5098C2.84599 14.2867 2.62289 14.4262 2.57641 14.2031C2.93896 13.794 2.64148 14.2867 2.96684 13.887V14.0822C3.10628 13.8033 3.09699 14.138 3.32939 13.9242C3.33869 13.7848 3.03192 13.8312 2.87388 13.7848C3.0598 13.6453 2.98544 13.887 3.20854 13.6453H3.08769C3.15277 13.6267 3.22713 13.5709 3.24573 13.6081C3.41306 13.4501 3.20854 13.5338 3.16206 13.4873C3.0598 13.5616 2.92036 13.6639 2.79951 13.7848C2.81811 13.7662 2.8367 13.7476 2.85529 13.7197C2.50204 13.8219 2.57641 13.4873 2.28823 13.5616C2.3533 13.5338 2.3626 13.5059 2.40908 13.4687C2.37189 13.3943 2.07442 13.5152 1.93498 13.4873C2.03723 13.3385 2.38119 13.1991 2.19527 13.1247C2.01864 13.2177 1.78624 13.4873 1.70258 13.3571C1.70258 13.3571 1.90709 13.3571 1.98146 13.227H1.95357ZM4.28689 15.5045C4.28689 15.5045 4.31478 15.5324 4.34266 15.551C4.34266 15.551 4.29618 15.5138 4.28689 15.5045ZM4.61225 15.5696C4.61225 15.5696 4.51929 15.5975 4.45422 15.6533C4.48211 15.6905 4.50999 15.7183 4.51929 15.7555C4.55647 15.6719 4.55647 15.5882 4.61225 15.5696ZM5.46749 14.2403L5.49538 14.2217C5.49538 14.2217 5.55116 14.2496 5.56975 14.2589C5.60693 14.2217 5.63482 14.1752 5.57904 14.1659C5.55116 14.1845 5.50468 14.2031 5.46749 14.231V14.2403Z\" fill=\"#8F3A7E\"><\/path><path d=\"M5.26323 14.3253C5.26323 14.3253 5.24482 14.3253 5.23562 14.3253C5.22642 14.3437 5.21721 14.3621 5.20801 14.3805L5.28164 14.3437L5.26323 14.3253Z\" fill=\"#8F3A7E\"><\/path><path d=\"M21.6523 4.27579C21.6523 4.27579 21.6712 4.27579 21.69 4.29463C21.6806 4.29463 21.6712 4.28521 21.6618 4.27579H21.6523Z\" fill=\"#8F3A7E\"><\/path><path d=\"M7.48508 20.1339L7.49435 20.032L7.46655 20.0876L7.48508 20.1339Z\" fill=\"#8F3A7E\"><\/path><path d=\"M23.4094 3.96896C23.4094 3.96896 23.4473 3.9974 23.4663 4.00688C23.4568 3.9974 23.4284 3.97844 23.4094 3.96896Z\" fill=\"#8F3A7E\"><\/path><path d=\"M24.4309 3.36418C24.4309 3.36418 24.3847 3.29949 24.3662 3.27176L24.4309 3.36418Z\" fill=\"#8F3A7E\"><\/path><path d=\"M19.885 6.80322C19.8943 6.85893 19.9036 6.90536 19.9036 6.95178C19.95 6.9425 19.9779 6.92393 19.885 6.80322Z\" fill=\"#8F3A7E\"><\/path><path d=\"M16.6518 10.8394L16.6318 10.8494L16.6518 10.8394Z\" fill=\"#8F3A7E\"><\/path><path d=\"M19.8203 7.01859C19.885 7.02783 19.9035 7.0001 19.9035 6.95389C19.8665 6.96313 19.8203 6.97237 19.8203 7.01859Z\" fill=\"#8F3A7E\"><\/path><path d=\"M26.1981 2.03489H26.2264C26.2264 2.03489 26.2075 2.00662 26.1981 1.99719V2.03489Z\" fill=\"#8F3A7E\"><\/path><path d=\"M26.1977 1.99845V1.96075C26.1977 1.96075 26.1789 1.9796 26.1977 1.99845Z\" fill=\"#8F3A7E\"><\/path><path d=\"M26.2079 1.8683V1.95148C26.2079 1.95148 26.2449 1.933 26.2079 1.8683Z\" fill=\"#8F3A7E\"><\/path><path d=\"M25.6025 2.37845L25.6578 2.45208C25.6578 2.45208 25.6302 2.40606 25.6025 2.37845Z\" fill=\"#8F3A7E\"><\/path><path d=\"M25.4627 2.52706C25.5183 2.50852 25.6852 2.60121 25.7037 2.51779L25.6574 2.45291C25.7223 2.58267 25.3978 2.37876 25.4627 2.52706Z\" fill=\"#8F3A7E\"><\/path><path d=\"M24.0587 2.18406L24.2354 2.12826C24.1517 2.07245 24.0308 1.98874 24.0773 1.92363C23.7145 1.83062 24.254 2.07245 24.0587 2.18406Z\" fill=\"#8F3A7E\"><\/path><path d=\"M23.5575 2.40555C23.5946 2.31271 23.4646 2.29414 23.4275 2.24771C23.4461 2.35913 23.4461 2.38698 23.5575 2.40555Z\" fill=\"#8F3A7E\"><\/path><path d=\"M20.6004 4.88834L20.4517 4.70251C20.4239 4.77684 20.5075 4.77684 20.6004 4.88834Z\" fill=\"#8F3A7E\"><\/path><path d=\"M20.833 6.30117L20.9817 6.36621L20.8702 6.18039L20.833 6.30117Z\" fill=\"#8F3A7E\"><\/path><path d=\"M19.4009 5.29716L19.4102 5.25073L19.373 5.39001L19.4009 5.29716Z\" fill=\"#8F3A7E\"><\/path><path d=\"M14.5673 9.62069L14.7804 9.8246C14.7804 9.75045 14.5673 9.5002 14.5673 9.62069Z\" fill=\"#8F3A7E\"><\/path><path d=\"M12.6902 11.7309C12.5694 11.6473 12.4486 11.6287 12.5044 11.7681C12.5601 11.7402 12.6902 11.7774 12.6902 11.7309Z\" fill=\"#8F3A7E\"><\/path><path d=\"M7.70828 16.6682L7.6897 16.4824L7.69899 16.659L7.70828 16.6682Z\" fill=\"#8F3A7E\"><\/path><path d=\"M1.70163 9.61194C1.61792 9.63054 1.4691 9.73285 1.52491 9.76076L1.81324 9.63984L1.70163 9.61194Z\" fill=\"#8F3A7E\"><\/path><path d=\"M1.38543 10.1886C1.54327 10.17 1.80325 10.0957 2.02609 9.91004C1.74754 10.0122 1.84039 9.9379 1.50613 10.0586C1.45042 10.0307 1.54327 9.92861 1.64541 9.88219C1.57113 9.90076 1.66398 9.78006 1.47828 9.85433C1.30187 10.0307 1.33901 10.1143 1.55256 10.0865C1.50613 10.1329 1.42257 10.1607 1.37615 10.1886H1.38543Z\" fill=\"#8F3A7E\"><\/path><path d=\"M6.07034 17.5318C6.07034 17.5318 6.02367 17.5318 6.005 17.5598C6.033 17.5598 6.06101 17.5598 6.07034 17.5318Z\" fill=\"#8F3A7E\"><\/path><path d=\"M6.40438 18.461C6.40438 18.461 6.38574 18.4238 6.38574 18.4051C6.38574 18.4517 6.38574 18.4797 6.40438 18.461Z\" fill=\"#8F3A7E\"><\/path><path d=\"M4.03508 14.7249L4.01648 14.8551C4.10019 14.7993 4.04438 14.7714 4.03508 14.7249Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.3788 10.391C2.3788 10.391 2.32335 10.391 2.28638 10.391C2.30486 10.391 2.32335 10.4002 2.33259 10.4095L2.3788 10.3817V10.391Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.96444 13.7376L2.94584 13.719C2.94584 13.719 2.87143 13.7562 2.83423 13.7748L2.96444 13.7376Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.26855 12.8844C2.26855 12.8844 2.49178 12.7635 2.58479 12.7077C2.49178 12.7635 2.43597 12.7728 2.40807 12.7728C2.37087 12.8007 2.32436 12.8379 2.26855 12.8937V12.8844Z\" fill=\"#8F3A7E\"><\/path><path d=\"M3.40322 14.398C3.40322 14.398 3.34722 14.4447 3.33789 14.4634C3.36589 14.4447 3.38456 14.4167 3.40322 14.398Z\" fill=\"#8F3A7E\"><\/path><path d=\"M24.3936 0.882324C24.3936 0.882324 24.4124 0.910594 24.4218 0.920017C24.4124 0.891747 24.403 0.882324 24.3936 0.882324Z\" fill=\"#8F3A7E\"><\/path><path d=\"M26.1963 1.0585V1.08636L26.2891 1.19778L26.1963 1.0585Z\" fill=\"#8F3A7E\"><\/path><path d=\"M7.32639 20.0692C7.32639 20.0692 7.32639 20.0692 7.32639 20.0592C7.29639 20.0692 7.31639 20.0792 7.32639 20.0692Z\" fill=\"#8F3A7E\"><\/path><path d=\"M13.8886 13.0136C13.6561 12.9113 13.8142 12.6788 13.5166 12.5951C13.6003 12.6602 13.684 12.995 13.8886 13.0136Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.37 10.4381C2.37 10.4381 2.38884 10.457 2.39826 10.4758C2.39826 10.457 2.38884 10.4476 2.37 10.4381Z\" fill=\"#8F3A7E\"><\/path><path d=\"M9.13905 18.7775C9.11125 18.7312 9.08346 18.6942 9.05566 18.6756C9.07419 18.7127 9.09272 18.7405 9.13905 18.7775Z\" fill=\"#8F3A7E\"><\/path><path d=\"M7.87305 19.9031L7.91937 20.005C7.90084 19.9494 7.89158 19.9216 7.87305 19.9031Z\" fill=\"#8F3A7E\"><\/path><path d=\"M9.5293 17.1406C9.5293 17.1406 9.59373 17.1407 9.59373 17.0762C9.58452 17.0762 9.57532 17.0762 9.56611 17.067C9.58452 17.1038 9.58452 17.1406 9.5385 17.1406H9.5293Z\" fill=\"#8F3A7E\"><\/path><path d=\"M10.1335 16.3052C10.1335 16.3052 10.0955 16.2957 10.0861 16.2863V16.3147L10.1335 16.3052Z\" fill=\"#8F3A7E\"><\/path><path d=\"M22.2911 2.80592C22.3562 2.85237 22.4119 2.89883 22.477 2.95457C22.3469 2.8245 22.4119 2.68513 22.2911 2.80592Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.25891 10.4761C2.31499 10.448 2.35237 10.4293 2.37106 10.4387L2.34302 10.42C2.34302 10.42 2.2776 10.4574 2.25891 10.4761Z\" fill=\"#8F3A7E\"><\/path><path d=\"M8.05957 15.6353L8.11645 15.6163C8.11645 15.6163 8.06905 15.6163 8.05957 15.6353Z\" fill=\"#8F3A7E\"><\/path><path d=\"M17.1702 7.21375V7.16635C17.1702 7.16635 17.1607 7.18531 17.1702 7.21375Z\" fill=\"#8F3A7E\"><\/path><path d=\"M8.31042 15.2827C8.40334 15.3198 8.45908 15.3198 8.50554 15.3198C8.49625 15.3013 8.48696 15.2827 8.46837 15.2641L8.31042 15.2827Z\" fill=\"#8F3A7E\"><\/path><path d=\"M22.9801 2.12785C22.9986 1.93263 23.0544 2.14644 23.2961 2.2394C23.1753 1.97911 23.4635 2.23011 23.1846 1.86756C23.417 2.07207 23.3333 1.98841 23.5378 2.09996C23.3519 1.93263 23.5099 1.80249 23.3147 1.57938C23.5564 1.81178 23.4635 1.98841 23.7795 2.18363C23.6959 1.96052 23.7516 1.80249 23.5285 1.51431C23.6308 1.5422 23.733 1.62586 23.826 1.58868C23.7981 1.58868 23.826 1.64445 23.8446 1.68164C23.8167 1.38416 24.1607 1.42135 23.9468 1.02161C24.2536 1.44923 24.2629 0.844989 24.4767 1.3005C24.5232 1.24472 24.4581 1.00302 24.4117 0.910061C24.6719 1.22613 24.6069 0.882173 24.8207 1.02161C24.6998 0.8171 24.8486 0.798508 24.8207 0.649771C24.8207 0.705547 24.8579 0.77062 24.9415 0.854285C24.895 0.668363 24.988 0.807804 25.1646 0.910061C25.1646 0.742732 24.9508 0.686955 24.8765 0.491737C25.0159 0.491737 25.0531 0.677659 25.1739 0.798508L25.0252 0.38948C25.0717 0.398776 25.1367 0.445257 25.2204 0.528921C25.1832 0.408072 25.1089 0.240743 25.2855 0.343L25.1925 0.435961L25.3599 0.566106L25.3041 0.268631C25.6666 0.361592 25.899 0.742732 26.1593 1.08669L26.1407 1.19824C26.2337 1.30979 26.3359 1.33768 26.3731 1.31909C26.4661 1.37487 26.5683 1.7746 26.5219 1.87685C26.3081 2.02559 26.1593 1.5236 25.9548 1.55149L25.9362 1.89545L25.8432 1.78389C25.7503 1.72812 25.8432 1.86756 25.8525 1.90474C25.7224 1.72812 25.6666 1.96982 25.5644 2.007L25.7131 2.12785C25.7968 2.63913 25.0903 2.02559 25.081 2.34166L25.1739 2.68561L24.9694 2.4904C25.0066 2.67632 25.1367 2.85294 24.9694 2.86224C24.2815 2.79717 24.2629 3.59663 23.6773 3.6803C23.7144 3.71748 23.7423 3.72678 23.7981 3.73607C23.0172 3.47578 23.7423 4.72146 23.0916 4.55413L23.0451 4.46117C22.9243 4.6285 22.9986 4.35891 22.7848 4.34032C22.9801 4.6192 22.7662 4.70287 22.7569 4.87949C22.7291 4.81442 22.7569 4.79583 22.7569 4.73075C22.6919 4.68427 22.5524 4.53554 22.5524 4.6192C22.7755 5.07471 22.5338 5.21415 22.4688 5.45585C22.3014 5.29782 22.0411 5.26063 21.7437 5.03752C21.7809 5.11189 21.8645 5.26993 21.9482 5.41866C21.7995 5.35359 21.8273 5.47444 21.8738 5.61388C21.9203 5.5674 21.9575 5.53022 21.9854 5.49303V5.51163C21.9854 5.51163 21.9947 5.48374 22.004 5.47444C22.0319 5.43726 22.0412 5.40937 22.0226 5.40937C22.2271 5.52092 22.1341 5.54881 22.3014 5.74403C22.2457 5.78121 22.1992 5.93925 22.0597 5.7998C22.0226 5.8184 21.9854 5.8184 21.9296 5.8184C21.9296 5.86488 21.9296 5.90206 21.8924 5.90206V5.87417C21.8924 5.87417 21.8366 5.83699 21.818 5.8184C21.6507 5.8184 21.7623 6.23672 21.7995 6.44123C21.6693 6.12517 21.5392 6.17165 21.3811 5.99502C21.3811 6.01361 21.4927 5.93925 21.6228 5.83699C21.5949 5.82769 21.5578 5.7998 21.502 5.73473C21.2324 5.63247 21.4648 6.06009 21.1859 6.06009C21.1859 6.03221 21.1673 5.97643 21.1022 5.91136C21 5.91136 21.0744 6.09728 21.158 6.21813C20.9907 6.0508 20.7676 6.02291 20.7676 6.15306C20.842 6.34827 20.907 6.40405 20.7955 6.46912L20.7304 6.31109C20.5259 6.30179 20.7955 6.57138 20.6188 6.55279C20.7025 6.57138 20.591 6.44123 20.5445 6.43194C20.4887 6.59927 20.5445 6.67364 20.6746 6.9897L20.5259 6.77589C20.5259 6.98041 20.5445 7.38014 20.3214 7.11055C20.7025 7.49169 20.2935 7.51028 20.2005 7.57536C20.2191 7.53817 20.154 7.44521 20.1169 7.39873C20.1726 7.82635 19.7636 7.7148 19.587 7.88213L19.2988 7.61254C19.2151 7.7055 19.6892 8.31904 19.5777 8.39341L19.494 8.21679C19.3546 8.4213 19.2523 8.45849 19.0664 8.54215L18.8991 8.33764C18.927 8.47708 18.8619 8.53285 18.8898 8.6723C18.3506 8.29116 18.6295 9.34161 17.9416 8.99766L18.2483 9.3788C18.1554 9.44387 18.1089 9.6112 17.83 9.3788H17.8579C17.6162 9.08132 17.7649 9.43458 17.6627 9.41598C17.6534 9.48106 17.7742 9.70416 17.8579 9.72275C17.4675 9.72275 17.3094 10.2154 16.8725 10.0109C16.7517 10.327 16.8446 10.7732 16.5658 10.9498L16.5286 10.9034C16.4077 10.9219 16.1474 10.9684 15.8778 10.6617C15.7663 10.8848 16.0359 11.4053 15.7012 11.4518L15.6454 11.2938C15.5432 11.2845 15.5897 11.4983 15.599 11.5541C15.5711 11.5634 15.5339 11.489 15.4967 11.4425C15.3573 11.3868 15.4688 11.5727 15.4595 11.6377L15.3851 11.5169C15.0319 11.4518 15.1435 12.1026 14.8925 12.242C14.9018 12.1769 14.7809 12.084 14.7158 12.0468C14.9389 12.4651 14.6229 12.5952 14.6136 12.7533L14.5485 12.5767C14.5764 12.9578 14.0744 12.3535 14.1116 12.7347L14.3812 12.8369C14.2603 12.8369 14.2603 12.9578 14.4184 13.0972C14.2324 13.0601 14.1767 12.8462 14.0186 12.9299C13.9257 12.8369 14.0465 12.7812 13.8978 12.6975L13.498 12.6045C13.498 12.6045 13.4423 12.5952 13.4144 12.6696C13.8141 13.0786 13.2935 12.8184 13.7583 13.153C13.5538 13.404 13.0983 13.311 13.0704 13.6922C12.6149 13.3668 12.6521 14.0547 12.1873 13.5156C12.0664 13.6178 12.0757 13.813 12.2059 14.0826C12.271 14.1012 12.2338 14.0083 12.2338 13.9618C12.3267 14.1198 12.2152 14.2685 12.1594 14.3243C12.1222 14.1384 12.1501 13.9246 12.02 13.6736C11.9642 13.8223 12.0014 14.1477 12.0107 14.2685L11.7318 14.0268C11.834 14.3057 11.4529 13.8781 11.6202 14.2221L11.7132 14.2871C11.5366 14.4173 11.7876 14.6869 11.6853 14.8542L11.5923 14.7426C11.4994 14.7426 11.676 15.068 11.3878 14.8821L11.4715 14.7798C11.2856 14.6032 11.1275 14.6032 11.0067 14.5381C10.9509 14.6869 11.267 14.8635 11.2484 14.9379C11.0532 14.7891 11.1554 14.8542 11.016 14.6497C10.9602 14.817 10.8951 15.0401 11.0439 15.3376C11.016 15.319 10.9788 15.2725 10.9788 15.2725C10.8394 15.3562 11.0625 15.7559 10.8487 15.6908V15.6444C10.4954 15.5049 10.8765 16.1092 10.4024 15.728C10.2816 15.7001 10.514 15.6444 10.2258 15.5142C9.95623 15.5328 10.5233 15.9418 10.2909 15.9511C10.3188 15.9511 10.2909 15.9325 10.2537 15.8861C10.1886 15.9883 10.1329 16.1464 10.0957 16.2858C9.60298 16.1185 9.90046 16.732 9.3148 16.574C9.51002 16.639 9.46354 16.7692 9.52861 16.8343C9.52861 16.8343 9.49143 16.7878 9.46354 16.7785C9.39847 16.8343 9.53791 16.983 9.58439 17.0667C9.41706 17.0016 9.58439 17.4385 9.46354 17.4013C9.54721 17.5036 9.48213 17.5501 9.43565 17.6244C9.43565 17.3455 9.28692 17.3363 9.18466 17.1131C9.02663 17.234 9.40776 17.8661 9.21255 18.0613C9.13818 18.0242 9.07311 17.987 8.99874 17.9405C9.20325 18.3867 8.99874 18.4983 9.07311 18.6656C8.98944 18.5726 8.92437 18.554 8.82211 18.303C8.82211 18.5354 8.65478 18.4239 8.74774 18.7957L8.8407 18.8236C8.72915 18.9073 8.71985 19.1955 8.70126 19.4929C8.68267 19.7811 8.65478 20.06 8.55253 19.9856L8.33872 18.9445C8.19927 18.647 8.33872 19.8462 8.17139 19.2977C8.24575 19.6417 8.23646 19.5022 8.25505 20.0042C8.29223 20.0135 8.28294 19.5952 8.32942 19.4929L8.34801 20.404L8.44097 19.6882C8.45956 20.2738 8.44097 20.1716 8.55253 20.5341C8.52464 21.0547 8.40379 20.5713 8.35731 20.7386C8.34801 20.7386 8.32942 20.7758 8.32012 20.8502C8.25505 20.6828 8.23646 20.2831 8.17139 20.06C8.12491 20.4411 7.94828 19.4093 7.9018 19.7718C7.86461 19.6417 7.94828 19.7997 7.92039 19.5673C7.85532 19.5673 7.80884 19.4744 7.79954 19.7253L7.87391 19.902C7.81813 19.809 7.82743 20.1716 7.69728 19.8276C7.64151 19.9577 7.60432 20.3296 7.68799 20.4318C7.6601 20.4504 7.57644 20.1344 7.60432 19.902C7.4277 19.6789 7.51136 20.6921 7.32544 20.0693C7.34403 20.0693 7.35333 20.0321 7.35333 19.9763C7.30685 19.8648 7.26967 19.8183 7.23248 19.8276C7.39981 19.9485 7.22318 19.1304 7.39051 19.4929C7.39051 19.0374 7.26037 19.2512 7.21389 19.0188C7.10234 19.1955 7.15811 19.5952 7.09304 19.7439C7.10234 19.6138 7.06515 19.5673 7.02797 19.4651L7.04656 19.8183C7.00008 19.7718 6.96289 19.716 6.90712 19.7253L7.00937 19.7068C6.91641 19.5394 6.86993 18.9352 6.67472 19.0281C6.73979 18.9631 6.85134 18.8236 6.79556 18.5726C6.60964 18.5726 6.78627 18.4146 6.75838 18.1264C6.60964 18.0242 6.60964 18.5633 6.44231 18.1543C6.42372 18.1264 6.38654 18.2937 6.38654 18.3867C6.28428 18.0892 6.12625 18.145 6.06117 17.8196C6.08906 17.9498 6.10765 18.0892 5.96821 18.0799C6.09836 17.9498 5.93103 17.7732 5.94032 17.6058L5.86596 17.6895C5.89384 17.5315 5.96821 17.5501 6.02399 17.5501C6.0054 17.5779 5.9961 17.6244 6.02399 17.6523C6.14484 17.6523 6.33076 17.2247 6.27498 17.0853C6.12625 17.0667 5.95892 17.327 5.91244 17.4478C5.83807 17.1782 5.44763 17.6802 5.40115 17.3548C5.36397 17.3084 5.55918 16.8529 5.50341 16.7134C5.25241 16.8064 5.48482 16.9923 5.27101 17.0667C5.56848 16.4345 4.68535 16.9551 4.78761 16.481L5.0479 16.3137C5.02001 16.2486 5.00142 16.1928 4.92705 16.1556L4.85268 16.3323C4.75972 16.3323 4.71324 16.1742 4.92705 16.0627C4.63887 16.1092 4.74113 15.9883 4.71324 15.8396C4.77831 15.9697 4.68535 15.8675 4.87127 15.8489C4.89916 15.6351 4.8062 15.6908 4.69465 15.6537C4.78761 15.5979 4.88987 15.4491 4.86198 15.4213C4.64817 15.4677 4.5738 15.3097 4.41577 15.2725L4.49013 15.2167C4.25773 15.1145 4.44365 14.6497 4.0904 14.6404C4.0904 14.6404 4.08111 14.6404 4.07181 14.6404V14.6683C3.88589 14.91 3.79293 14.6497 3.66278 14.6683C3.70926 14.6125 3.81152 14.5288 3.78363 14.4916C3.56982 14.659 3.6163 14.5102 3.49545 14.5567C3.52334 14.4359 3.76504 14.3615 3.67208 14.2685C3.6256 14.2407 3.50475 14.3243 3.42108 14.3894C3.51404 14.2778 3.55123 14.1477 3.53264 14.0733C3.60701 14.0454 3.55123 14.1384 3.57912 14.1384C3.69997 14.0547 3.6256 14.0547 3.77434 13.9432C3.75574 13.8781 3.55123 14.0826 3.57912 13.9618L3.79293 13.8874C3.82082 13.8316 3.71856 13.8502 3.69997 13.8502C3.77434 13.8502 3.94166 13.7201 4.04392 13.6364C3.81152 13.5899 3.56053 13.9618 3.36531 14.1012C3.3932 13.8595 3.08642 13.9246 2.99346 13.8223L3.21657 13.6922C3.1422 13.6643 3.07713 13.6736 2.97487 13.7201L2.9098 13.6364C3.02135 13.6364 3.09572 13.5992 3.26305 13.4784C3.1422 13.4319 3.10502 13.2832 2.81684 13.4598L2.86332 13.4319C2.87261 13.246 2.75177 12.9578 2.85402 12.902C2.6681 12.8462 2.71458 12.5674 2.4357 12.7626C2.31485 12.7347 2.64951 12.3164 2.26837 12.5116C2.38922 12.2885 2.34274 12.4558 2.56584 12.335C2.68669 12.1211 2.15682 12.3628 2.52866 12.0468C2.33344 12.0282 2.46359 12.1304 2.25907 12.2234C2.61232 11.9352 2.1847 11.991 2.32415 11.74C2.14752 11.8051 2.25907 11.8516 2.05456 11.8887C2.15682 11.833 2.13822 11.7772 2.13822 11.7493L1.89653 11.8887L2.39851 11.3868C2.01737 11.4332 2.01737 11.6935 1.77568 11.5727H1.80356C2.00808 11.3496 1.52468 11.5541 1.60835 11.2845C1.59905 11.3682 1.73849 11.2287 1.81286 11.2008L1.66412 11.1822C1.66412 11.1822 1.70131 11.1822 1.7199 11.1451C1.85005 10.9591 1.58046 11.1451 1.68272 10.9591C1.76638 10.987 1.93371 10.8476 2.00808 10.7639L1.66412 10.8197L2.01737 10.6524C1.97089 10.5222 1.33876 10.6803 1.75708 10.3363L1.84075 10.3642C1.91512 10.3084 2.13822 10.1318 1.92441 10.1597C1.86864 10.1597 1.66412 10.2619 1.70131 10.2898L1.73849 10.1876C1.97089 10.0853 2.11963 10.1876 2.23118 10.234C2.12893 10.2619 2.01737 10.234 1.89653 10.3456C2.01737 10.3828 2.2033 10.3642 2.32415 10.3921C2.22189 10.42 2.07315 10.485 1.98019 10.5222C1.92441 10.6803 2.16611 10.4943 2.23118 10.5408C2.16611 10.6245 2.11963 10.671 2.03597 10.6988C2.17541 10.7267 2.24048 10.7732 2.1847 10.9312C2.1847 10.9312 1.97089 10.9312 1.87793 11.0707C2.11034 11.1451 2.37992 11.0056 2.64021 11.0707C3.12361 11.0149 2.68669 11.5913 3.03065 11.5448C3.12361 11.489 3.12361 11.331 3.24446 11.3775C3.04924 11.4983 3.16079 11.5169 3.09572 11.5727C3.43038 11.4704 3.13291 11.7493 3.36531 11.6842C3.29094 11.7121 3.25375 11.8237 3.21657 11.898C2.98417 12.0561 3.19798 12.0654 2.77965 12.1676C3.22587 12.0561 2.87261 12.4837 3.47686 12.1955L3.51404 12.1118V12.3257V12.3164C3.51404 12.4 3.58841 12.3721 3.41179 12.6231C3.32812 12.6231 3.29094 12.5767 3.20727 12.5859C3.06783 12.8091 3.48616 12.6138 3.56053 12.6882C3.3932 12.8091 3.43968 12.6417 3.25375 12.8184C3.27235 12.8927 3.43038 12.8555 3.51404 12.8741L3.42108 12.9299C3.32812 13.2274 3.90448 12.651 3.68137 12.9857C3.72785 12.9392 3.80222 12.9113 3.8487 12.8648C3.78363 12.9764 3.69067 13.1902 3.50475 13.1809C3.54193 13.2274 3.66278 13.2274 3.78363 13.1809C3.88589 13.0415 3.81152 13.0786 3.96955 12.9299L4.22055 13.0601C4.22055 13.0601 4.11829 13.1065 4.0997 13.0786C3.80222 13.6829 4.87127 13.246 4.49943 13.9525C4.62028 13.813 4.64817 13.8688 4.75972 13.8223C4.77831 13.9432 4.91775 14.0454 4.88987 14.1942L4.76902 14.2499C5.0479 14.3615 5.31749 14.3801 5.36397 14.5567C5.41045 14.5288 5.22453 14.6683 5.16875 14.6683C5.42904 14.6218 4.94564 15.1981 5.35467 14.9193V14.8542C5.44763 15.1052 5.89384 15.0959 6.10765 15.2632C5.91244 15.4956 5.9868 15.1703 5.7544 15.4306C5.77299 15.6444 6.08906 15.6258 6.12625 15.8396C6.07977 15.8396 6.05188 15.8675 6.03328 15.8675C6.0054 16.1371 6.2471 15.663 6.32146 15.821C6.20061 15.9047 6.18202 15.9325 6.15413 16.0255L6.36794 15.9139C6.36794 15.9139 6.20061 16.0627 6.13554 16.0906C6.41442 15.9418 6.36794 16.2114 6.59105 16.0348C6.54457 16.0999 6.34006 16.2765 6.27498 16.3695C6.27498 16.4996 6.37724 16.4531 6.4795 16.3973C6.38654 16.6019 6.48879 16.6855 6.45161 16.6948C6.48879 16.89 6.56316 16.574 6.7212 16.481L6.73979 16.2951L6.86993 16.3509L6.75838 16.4438C6.74908 16.6112 6.92571 16.4252 6.96289 16.481L7.01867 16.2765C7.01867 16.2765 7.08374 16.2393 7.11163 16.2207C6.97219 16.6019 7.14882 16.388 6.96289 16.7971C7.03726 17.1596 7.24178 16.7041 7.32544 16.7506C7.30685 16.732 7.30685 16.8343 7.28826 16.9086C7.33474 17.0853 7.39981 16.8807 7.43699 16.6483C7.4184 16.7971 7.40911 16.8436 7.39051 16.9644C7.45559 17.0481 7.44629 16.7227 7.51136 16.6297C7.49277 16.8343 7.49277 16.9551 7.51136 17.0295C7.51136 16.8343 7.52996 16.7041 7.53925 16.6669C7.48347 17.6802 7.62292 17.2061 7.60432 18.0428C7.61362 17.8289 7.71588 17.4757 7.6508 16.9644V17.0295C7.62292 16.7134 7.6508 16.8621 7.6601 16.8529C7.6601 16.8993 7.6508 16.9551 7.6601 17.0202C7.68799 16.89 7.72517 16.9365 7.74377 16.9179C7.76236 16.8622 7.78095 16.8343 7.79025 16.7506C7.79025 16.7041 7.79954 16.6483 7.79954 16.574C7.81813 16.6948 7.82743 16.9458 7.85532 17.0016C7.94828 17.0016 7.88321 16.3695 7.85532 16.0627C8.03194 16.6205 7.82743 16.2579 7.96687 16.8436C8.01335 16.5368 8.03194 16.1928 7.96687 15.8582C8.15279 16.1649 8.1435 16.0534 8.11561 15.9418C8.08772 15.821 8.04124 15.7187 8.23646 15.8768C8.08772 15.7094 8.05983 15.6165 8.06913 15.5793C8.18998 15.7187 8.21787 15.6815 8.30153 15.7745C8.24575 15.6815 8.20857 15.6072 8.23646 15.5793C8.25505 15.57 8.39449 15.5142 8.55253 15.663C8.23646 15.3934 8.70126 15.4956 8.52464 15.2539C8.72915 15.2446 8.62689 14.975 8.83141 14.9286C8.59901 14.8077 8.8407 14.7241 8.79422 14.6125C8.79422 14.6404 8.79422 14.6869 8.83141 14.7055C9.02663 14.8077 8.80352 14.4359 8.97085 14.4545C9.06381 14.4824 9.13818 14.6218 9.20325 14.5846C9.06381 14.4638 9.07311 14.1384 9.29621 14.2221C9.26832 14.2499 9.3334 14.315 9.37058 14.3801C9.42636 13.8502 10.0213 13.7851 10.0585 13.2274L10.2165 13.497C10.6813 13.5899 9.98412 13.0136 10.17 12.8927C10.6906 12.5952 11.425 12.5209 11.6853 12.0003C11.6574 11.9073 11.5923 11.9352 11.4994 11.8423C11.5645 11.8423 11.7411 12.0189 11.6853 11.8516L11.5645 11.74C12.0479 11.898 11.8898 11.0242 12.5034 11.4146C12.5034 11.0614 12.931 11.2752 12.8752 10.7918C13.0425 10.8383 12.9868 11.0707 13.1076 11.0242L13.1355 10.6524V10.6803C13.0054 10.1411 14.0186 10.6245 14.0279 10.1504V10.1783C14.1023 10.2712 14.251 10.327 14.2603 10.2619C14.2231 10.1876 14.1674 10.1783 14.0744 10.1318C14.1581 9.79712 14.2045 9.74135 14.3533 9.56472C14.3905 9.75994 14.5206 9.6112 14.6879 9.78783C14.6322 9.62979 14.502 9.62979 14.5113 9.44387C14.6415 9.29513 14.911 9.33232 15.0784 9.29513C14.9854 9.09062 15.0877 9.08132 14.9203 8.88611C15.0691 8.72807 15.097 8.57004 15.2922 8.40271L15.3573 8.46778C15.1992 8.1796 15.6361 8.43989 15.5525 8.26327C15.6268 8.35623 15.6361 8.41201 15.7012 8.46778L15.7198 8.30975C15.7384 8.4213 15.9243 8.6723 16.0173 8.63511C15.9429 8.39341 15.8964 8.53285 15.8035 8.36552L16.0266 8.57004C16.0638 8.49567 15.85 8.22608 15.7198 8.21679C15.9243 8.04016 16.0266 7.76128 16.2311 7.64043L16.3426 7.80776C16.3891 7.66832 16.5286 7.54747 16.6959 7.63113C16.6587 7.58465 16.6122 7.4824 16.5565 7.44521C16.5007 7.13844 16.7796 7.67761 16.7238 7.35225C16.7424 7.43592 16.7238 7.50099 16.7982 7.59395L16.8818 7.20351C16.9841 7.31507 17.3466 7.43592 17.3559 7.24999C17.3094 7.18492 17.2072 7.12914 17.17 7.13844L17.1886 7.02689L17.4675 7.2407L17.3652 6.93393L17.5511 7.14774C17.579 7.04548 17.3745 6.73871 17.4396 6.71082C17.7742 6.66434 17.7928 6.77589 18.1182 6.85026C17.7742 6.42264 18.3692 6.66434 18.1554 6.32968C18.6202 6.46912 18.7503 6.03221 19.0943 5.89277V5.94854C19.3825 6.0415 18.9641 5.52092 19.1594 5.50233L19.178 5.58599C19.5219 5.67896 19.6242 5.24204 19.6242 4.93527C19.6428 5.01893 19.7729 5.13978 19.8101 5.0933C19.7822 4.98175 19.5219 4.83301 19.6706 4.84231C19.6799 4.89808 19.7822 4.98175 19.8008 4.96316L19.7078 4.68427C20.0425 4.64709 20.4236 4.58202 20.5445 4.26595C20.6467 4.30313 20.6839 4.40539 20.7304 4.48906C20.8698 4.29384 20.8977 3.96847 21.0279 3.80115L21.251 4.03355C21.3254 3.96847 20.9907 3.62452 21.2696 3.75466C21.3161 3.76396 21.2138 3.82903 21.2696 3.95918C21.5856 4.00566 21.1673 3.64311 21.3346 3.54085L21.5299 3.84763C21.7809 3.9127 21.5392 3.59663 21.4462 3.39212C21.3346 2.93661 22.004 3.81974 22.0226 3.39212C21.9482 3.22479 21.8459 3.2062 21.7623 3.03887C21.9761 2.98309 21.8366 2.76928 22.0504 2.7135C22.4781 3.04816 21.9668 2.77858 22.3851 3.08535H22.1899C22.4688 3.22479 22.1434 3.22479 22.3665 3.45719C22.506 3.45719 22.4502 3.15971 22.4781 2.99239C22.6361 3.17831 22.3758 3.11323 22.6361 3.31775V3.1969C22.6547 3.26197 22.7105 3.33634 22.6733 3.35493C22.8313 3.51297 22.7384 3.31775 22.7848 3.27127C22.7105 3.16901 22.5896 3.03887 22.4688 2.92731C22.4874 2.9459 22.506 2.9645 22.5338 2.98309C22.413 2.63913 22.7477 2.69491 22.664 2.41603C22.6919 2.4811 22.7198 2.4904 22.7569 2.52758C22.822 2.4904 22.6826 2.19292 22.7105 2.05348C22.8685 2.15574 23.0265 2.4811 23.0916 2.29518C22.9894 2.12785 22.7105 1.91404 22.822 1.82108C22.822 1.82108 22.822 2.02559 22.9708 2.09066L22.9801 2.12785ZM20.8327 4.54483C20.8327 4.54483 20.8048 4.57272 20.7862 4.60061C20.7862 4.60061 20.8141 4.55413 20.8234 4.54483H20.8327ZM20.7769 4.8702C20.7769 4.8702 20.749 4.77723 20.6839 4.71216C20.6467 4.74005 20.6188 4.76794 20.5817 4.78653C20.6653 4.81442 20.749 4.81442 20.7769 4.8702ZM22.1341 5.67896L22.1527 5.70684C22.1527 5.70684 22.1248 5.76262 22.1155 5.78121C22.1527 5.8184 22.1992 5.84628 22.2085 5.79051C22.1899 5.76262 22.162 5.71614 22.1341 5.67896Z\" fill=\"#8F3A7E\"><\/path><path d=\"M22.0416 5.47307C22.0416 5.47307 22.0416 5.45466 22.0416 5.44546C22.0231 5.43626 22.0047 5.42705 21.9863 5.41785L22.0231 5.49148L22.0416 5.47307Z\" fill=\"#8F3A7E\"><\/path><path d=\"M4.04395 14.6689C4.04395 14.6689 4.05317 14.6597 4.06239 14.6413C4.06239 14.6505 4.05317 14.6597 4.04395 14.6689Z\" fill=\"#8F3A7E\"><\/path><path d=\"M17.3184 6.90505L17.365 6.96105L17.3464 6.89572L17.3184 6.90505Z\" fill=\"#8F3A7E\"><\/path><path d=\"M3.82129 12.9043C3.82129 12.9043 3.84973 12.8664 3.85921 12.8474C3.84973 12.8569 3.83077 12.8759 3.82129 12.9043Z\" fill=\"#8F3A7E\"><\/path><path d=\"M3.47742 12.3441L3.49602 12.2139C3.47742 12.279 3.47742 12.3162 3.47742 12.3441Z\" fill=\"#8F3A7E\"><\/path><path d=\"M3.28078 11.8598C3.28078 11.8598 3.21608 11.8967 3.18835 11.9152L3.28078 11.8598Z\" fill=\"#8F3A7E\"><\/path><path d=\"M6.45996 16.4436C6.45996 16.4436 6.54407 16.3969 6.57211 16.3875C6.57211 16.3408 6.55342 16.3221 6.45996 16.4436Z\" fill=\"#8F3A7E\"><\/path><path d=\"M6.62872 16.4611C6.62872 16.3873 6.6195 16.3781 6.57336 16.3873C6.57336 16.4242 6.58259 16.4703 6.62872 16.4611Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.17539 10.0107V9.98242C2.17539 9.98242 2.14712 10.0013 2.1377 10.0013H2.17539V10.0107Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.12949 10.0114H2.0918C2.0918 10.0114 2.10122 10.0208 2.12949 10.0114Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.00806 9.99291H2.09124C2.09124 9.99291 2.07275 9.96519 2.00806 9.99291Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.41699 10.6243L2.50017 10.5781C2.50017 10.5781 2.45396 10.5966 2.41699 10.6243Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.55659 10.7733C2.55659 10.7177 2.65855 10.5601 2.57513 10.5416L2.51025 10.5787C2.64001 10.5231 2.39903 10.8289 2.55659 10.7733Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.07381 12.1401L2.0366 11.9541C1.97149 12.0378 1.88778 12.1494 1.82268 12.0936C1.70176 12.4471 1.9808 11.9262 2.08311 12.1401H2.07381Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.27776 12.6685C2.18469 12.622 2.15677 12.7523 2.11023 12.7895C2.22192 12.7895 2.24984 12.7895 2.27776 12.6685Z\" fill=\"#8F3A7E\"><\/path><path d=\"M4.62895 15.747L4.43384 15.8864C4.50817 15.9235 4.50817 15.8306 4.62895 15.747Z\" fill=\"#8F3A7E\"><\/path><path d=\"M6.05145 15.5506L6.11649 15.4112L5.93066 15.5134L6.05145 15.5506Z\" fill=\"#8F3A7E\"><\/path><path d=\"M5.00248 16.9545H4.95605C5.00248 16.9638 5.0489 16.973 5.10461 17.0009C5.05819 16.973 5.03962 16.973 5.00248 16.9545Z\" fill=\"#8F3A7E\"><\/path><path d=\"M10.2145 16.5729L9.97351 16.4061C9.98278 16.471 10.2423 16.6842 10.2145 16.5729Z\" fill=\"#8F3A7E\"><\/path><path d=\"M11.8059 14.4079C11.9267 14.4915 12.0475 14.5101 11.9824 14.3708C11.9267 14.3986 11.7966 14.3615 11.8059 14.4079Z\" fill=\"#8F3A7E\"><\/path><path d=\"M18.3037 9.16579L18.3223 9.2774L18.3502 9.14719L18.3037 9.16579Z\" fill=\"#8F3A7E\"><\/path><path d=\"M1.64564 9.73384C1.52494 9.65027 1.46923 9.91025 1.50637 9.71527C1.6085 9.67813 1.69207 9.65956 1.64564 9.73384Z\" fill=\"#8F3A7E\"><\/path><path d=\"M25.5929 1.03314C25.7137 1.86049 24.812 1.67457 24.7376 2.32529C24.7097 2.38107 24.4959 2.01852 24.4587 2.16726C24.4587 2.88306 23.6872 3.09687 22.9807 3.13405L22.9342 3.0318C22.804 3.0318 22.9342 3.40364 22.8133 3.44083C22.7669 3.38505 22.7761 3.33857 22.6925 3.28279C22.8133 3.46871 22.5995 3.4966 22.6646 3.64534C22.5716 3.60815 22.4694 3.46871 22.3578 3.43153L22.4694 3.66393C22.7111 4.23099 22.1068 3.91493 22.1161 4.30536C22.0882 4.24959 22.0789 4.2031 22.0232 4.17522C21.9488 4.70509 21.5305 4.97468 21.2795 5.36512C21.233 5.29075 21.14 5.15131 21.0564 5.09553C21.2051 5.30934 21.1493 5.44878 21.0936 5.56963C20.8797 5.393 21.0936 5.8857 20.8983 5.8671L20.8704 5.81133C20.9727 6.09021 20.6473 5.78344 20.8054 6.09951L20.6195 5.97866C20.8333 6.29472 20.3778 5.92288 20.4428 6.1274L20.4986 6.18317C20.4986 6.30402 20.3406 6.18317 20.3313 6.28543L20.2941 6.25754C20.229 6.44346 20.0152 6.3505 20.2104 6.57361C20.0059 6.43417 20.2662 6.37839 19.9687 6.18317C19.7363 6.78742 19.2436 7.12208 18.816 7.50322C18.6859 7.45674 18.6301 7.45674 18.5464 7.38237C18.5464 7.46603 18.4163 7.56829 18.4814 7.71703C18.4906 7.69843 18.3512 7.62407 18.3233 7.63336C18.1746 7.61477 18.4535 7.95872 18.2768 7.93084C18.2582 7.83788 18.2118 7.75421 18.1281 7.67984C18.2025 7.92154 18.0816 7.97732 18.0444 8.10746C18.0258 8.06098 18.0258 8.0145 17.9608 7.94943C18.0351 8.22831 17.747 8.06098 17.7749 8.2562L17.6912 8.09817C17.4216 8.06098 17.8864 8.40494 17.6912 8.41423C17.6912 8.34916 17.6261 8.30268 17.5889 8.2469C17.6819 8.58156 17.4402 8.65593 17.403 8.82326C17.403 8.79537 17.3658 8.76749 17.3658 8.76749C17.2729 8.89763 17.0869 8.93481 17.0498 9.14862C16.9475 9.13003 16.7895 8.82326 16.7058 8.98129C16.9382 9.23229 16.585 9.27877 16.9196 9.50188C16.7802 9.54836 16.5199 9.60413 16.5292 9.75287C16.492 9.61343 16.1945 9.48328 16.2689 9.38103L16.0644 9.28807C15.9807 9.17651 16.1666 9.26018 16.0272 9.14862C15.99 9.19511 15.9528 9.41821 15.8784 9.40891C15.9342 9.64132 16.1201 10.0039 16.0179 10.1526C15.99 9.99457 15.7297 9.90161 15.7297 9.81794L15.9807 10.478C15.9435 10.5337 15.7855 10.2827 15.7855 10.4036C15.8506 10.4687 15.8599 10.5337 15.8877 10.6081C15.8413 10.5895 15.7669 10.8312 15.5159 10.6081C15.4043 10.5244 15.5438 10.4873 15.4136 10.4408C15.3393 10.5151 15.4136 10.6081 15.33 10.6825L15.3021 10.6546C15.2184 10.6639 15.237 10.9056 15.4229 10.9892C15.4694 10.9614 15.2742 10.8498 15.3951 10.8777C15.488 11.0543 15.4322 11.1845 15.3579 11.2588C15.3579 11.1938 15.2835 11.1287 15.2277 11.045C15.3021 11.3425 15.237 11.5098 15.1905 11.6958C15.2928 11.8166 15.0418 11.4355 15.1162 11.4819C14.8094 11.4541 15.0139 12.0118 14.6607 11.8817C14.6607 11.8445 14.828 12.0397 14.7908 12.0118C14.7071 12.0676 14.5491 11.891 14.5584 11.9932C14.4654 11.891 14.5305 12.0769 14.5026 12.1606C14.5398 12.2535 14.4469 12.1234 14.4747 12.0676C14.4747 12.2163 14.3446 12.6254 14.0564 12.6254C14.1215 12.6904 14.1866 12.96 14.1401 12.9879L14.0099 12.8206C13.8891 12.7555 13.8984 12.9507 13.7682 12.8206C13.8612 13.0809 13.9263 12.3837 13.9542 12.6254C13.8054 12.5231 14.0378 13.0065 13.8612 12.7741C13.7961 12.8485 13.8798 13.0902 13.6753 13.0065C13.7218 13.0065 13.5358 12.7369 13.4894 12.802C13.4057 12.9228 13.5265 12.9042 13.4894 13.0344V13.1459C13.6288 13.304 13.3871 13.211 13.5823 13.3412C13.4522 13.2296 13.4986 13.555 13.2755 13.2947L13.1082 13.0809C13.0803 13.1366 13.2291 13.3598 13.2755 13.4806C13.257 13.4713 13.2012 13.4341 13.1733 13.4062C13.4429 13.713 13.0431 13.4806 13.2105 13.7688C13.0153 13.7502 12.9595 13.9826 12.7364 13.8339C12.7457 13.9919 12.7829 14.1592 12.6434 14.1778C12.6341 14.1313 12.6434 14.1034 12.5876 14.0384C12.4575 14.0012 12.5133 14.0848 12.5133 14.1778C12.4854 14.122 12.2437 14.1034 12.0856 14.0477C12.1042 14.2057 12.2809 14.3451 12.3645 14.4474C12.0206 14.215 12.3459 14.8285 12.0113 14.6333C11.9927 14.5682 11.9741 14.3916 11.8439 14.373C11.5 14.1406 11.9276 14.717 11.6859 14.6705L11.9462 14.8843C11.751 14.7821 11.9369 15.1725 11.7045 14.9122C11.7603 15.033 11.5093 14.9494 11.751 15.1725C11.3884 15.1446 11.4814 15.6838 10.9608 15.3863C10.9794 15.4514 10.8772 15.47 11.0166 15.5722C11.1839 15.6559 10.9701 15.4235 11.0817 15.4979C11.0724 15.5257 11.1281 15.5908 11.1653 15.628C11.0631 15.628 11.0073 15.6559 10.8493 15.4142C10.589 15.3956 11.1467 15.9162 10.9236 15.972C10.8307 15.8697 10.7749 15.8511 10.7563 15.9069L10.8586 16.1393C10.7377 16.1951 10.5797 15.9905 10.3938 15.8418C10.3752 15.9162 10.3101 15.9812 10.4309 16.1114L10.1521 15.9905C10.3566 16.0742 10.2264 16.1207 10.245 16.1858L10.2171 16.1207C10.1335 16.0649 10.1242 16.1672 10.1242 16.2229C10.245 16.3066 10.338 16.2787 10.4031 16.2694C10.4588 16.3624 10.4031 16.3903 10.4681 16.5018C10.3008 16.3438 10.2729 16.4832 10.2264 16.5111C10.1521 16.5297 10.3473 16.6878 10.3287 16.697C10.2357 16.6227 10.2543 16.7621 10.1521 16.6227C10.1335 16.5855 10.2729 16.6506 10.2078 16.5669C10.1149 16.5483 9.95684 16.4182 10.0219 16.5669C10.0684 16.6878 10.3845 16.8272 10.1985 16.8365C10.1706 16.7807 10.1056 16.7156 10.0498 16.6506L9.89177 16.6692L10.0591 16.7993C10.0126 16.7807 10.0033 16.7621 9.97543 16.7528C10.1428 16.8923 9.90106 16.9666 10.0591 17.1711C10.0219 17.2641 9.83599 17.2455 9.77092 17.3106V17.2827C9.62218 17.2827 9.61288 17.4686 9.65936 17.6638L9.63148 17.6267C9.63148 17.6267 9.53852 17.8033 9.585 18.0078C9.41767 18.0264 9.06442 17.3199 9.15738 17.7196C9.1016 17.8498 9.28752 18.3425 9.38978 18.4261C9.18526 18.5284 9.23174 19.3743 8.94357 19.207C8.97145 19.3743 9.00864 19.4208 8.99005 19.5974C8.77624 19.9228 8.70187 21.1313 8.42298 20.6851C8.44158 20.3783 8.35791 20.2482 8.31143 19.9972C8.33002 20.3597 8.26495 20.0158 8.26495 20.1087C8.26495 20.1366 8.27425 20.211 8.29284 20.3783C8.33002 20.6014 8.34862 20.7594 8.3765 20.8896C8.3951 20.9732 8.41369 21.029 8.45087 21.0383C8.45087 21.0941 8.43228 21.1406 8.42298 21.2057C8.36721 21.2428 8.30214 21.2149 8.22777 21.1499C8.19058 21.1127 8.16269 21.0662 8.12551 21.0197C8.08833 20.9454 8.05114 20.8524 8.03255 20.7687C8.08833 20.9732 8.06973 21.029 8.03255 21.0848C7.99536 20.5828 7.88381 20.3783 7.80015 20.4434V20.7316L7.72578 20.3597C7.69789 20.4155 7.70719 20.9268 7.60493 20.5363C7.60493 20.4248 7.58634 20.3039 7.57704 20.2017C7.49338 20.3318 7.33534 20.5363 7.24238 20.1831L7.17731 19.6997C7.17731 19.6997 7.03787 19.8298 7.11224 20.025C6.9542 19.5881 6.84265 19.4301 6.84265 19.0768C6.44292 19.4673 5.89445 18.863 5.55049 18.3796L5.63416 18.2681C5.60627 18.0357 5.44824 18.4168 5.42964 18.2495C5.5319 18.1751 5.5226 17.9241 5.68064 17.8684C5.64345 17.5988 5.38316 17.8684 5.25302 17.8126C5.12287 17.9427 5.39246 17.8126 5.23443 17.9706C5.17865 17.9985 5.14146 17.636 4.93695 17.8126C4.97413 17.6917 5.14147 17.5802 5.23443 17.5151H5.0671C5.20654 17.1897 5.66205 17.3478 5.82938 16.9387L5.74571 16.9016C5.89445 16.6413 6.09896 16.8272 6.04319 16.6041C5.90374 16.6413 5.55979 16.8458 5.5412 17.0038C5.35528 16.8923 5.00202 17.3664 4.85329 17.1433C4.92765 16.9852 5.02062 17.2827 5.15076 17.0968C5.23443 16.8551 4.91836 17.0038 4.93695 16.9016C4.90906 17.0317 4.64877 17.1433 4.5837 17.134C4.62088 16.9852 4.8161 17.0224 4.76032 16.9016C4.62088 16.9852 4.46285 16.9666 4.44426 17.1154C4.13749 17.3013 4.44426 16.948 4.17467 17.0689C4.342 16.883 4.70455 16.8086 4.71384 16.6227C4.53722 16.79 4.3513 16.6878 4.11889 16.9759C4.13749 16.8923 4.27693 16.7621 4.42567 16.7063C4.49074 16.5483 3.96086 16.8272 4.31411 16.5111L4.1096 16.6413C4.15608 16.5762 4.18397 16.5018 4.25834 16.3903C4.22115 16.3345 3.8586 16.4182 4.14678 16.1951C4.1003 16.1951 4.01664 16.0649 3.84931 16.2694C3.79353 16.4461 4.06312 16.2415 3.83072 16.5018C4.00734 16.2694 3.70987 16.4089 3.59831 16.4275L3.70057 16.3345C3.6355 16.3345 3.60761 16.2601 3.47746 16.3345C3.56113 16.3066 3.6262 16.2322 3.6355 16.1858L3.44028 16.288C3.26365 16.2415 3.71916 16.0277 3.58902 15.9534L3.78424 15.9255C3.78424 15.9255 3.8772 15.7674 3.78424 15.7581C3.60761 15.8604 3.3938 15.972 3.26365 16.0463C3.1521 16.0463 3.42169 15.879 3.20788 15.9441L3.45887 15.8697C3.52395 15.8418 3.67268 15.6094 3.60761 15.535C3.51465 15.535 3.22647 15.6187 3.19858 15.7674C3.1614 15.7303 3.21717 15.6001 3.35662 15.5443C3.22647 15.4979 3.19858 15.6838 3.04055 15.6838C3.11492 15.5722 3.18929 15.3491 3.29154 15.1725L3.61691 15.0516L3.57972 14.9959C3.84931 14.9029 3.70987 14.8378 3.96086 14.6984C3.96086 14.6333 3.8586 14.6519 3.77494 14.6519C3.50535 15.0423 3.18929 14.9029 2.89181 15.1911C2.6873 15.1074 3.60761 14.4846 2.97548 14.717C2.9104 14.8099 2.60363 14.9215 2.77096 14.9494C2.73378 14.8285 2.39912 15.1353 2.4456 14.9215C2.64082 14.9029 2.70589 14.5775 2.99407 14.5497C2.88252 14.624 2.96618 14.6798 3.01266 14.6705C3.10562 14.5404 3.34732 14.4288 3.27295 14.3265C3.19858 14.2894 3.12421 14.215 2.96618 14.3544C2.78026 14.5032 3.05914 14.4288 2.83603 14.5404C2.678 14.4753 2.94759 14.2336 2.58504 14.4381C2.6687 14.4939 2.49208 14.6612 2.36193 14.7542L2.2132 14.7263L2.35264 14.6519C2.33405 14.4474 2.09235 14.7821 2.02727 14.624L2.22249 14.373C2.45489 14.2429 2.27827 14.6426 2.60363 14.3544C2.54786 14.2522 2.35264 14.3544 2.38053 14.2057C2.42701 14.2057 2.45489 14.2243 2.49208 14.215C2.48278 14.1778 2.9104 13.7967 2.54786 13.871C2.39912 13.8896 2.40841 13.9454 2.27827 14.0384C2.12953 13.9268 1.9715 13.9826 1.87854 13.9082C2.14812 13.7409 1.78558 13.7316 2.12024 13.6386C2.00868 13.7967 2.17601 13.9919 2.45489 13.8617C2.71519 13.5829 2.50138 14.0012 2.82674 13.806C2.75237 13.6851 3.04984 13.4713 3.22647 13.304C3.21717 13.2668 3.11492 13.2947 3.06844 13.304C2.87322 13.4248 2.9104 13.462 2.72448 13.6107C2.678 13.4434 2.49208 13.3969 2.25968 13.462C2.31545 13.3505 2.51067 13.2296 2.56645 13.2668C2.39912 13.1552 2.30616 12.9786 2.25968 12.7927C2.02727 13.1088 2.07376 12.6811 1.86924 12.9321C1.85995 13.0623 1.69262 13.2854 1.52529 13.3412C1.50669 13.2761 1.65543 13.2482 1.71121 13.1831C1.4974 13.2389 1.90643 12.8949 1.59965 13.0251C1.79487 13.0995 1.99009 12.7834 2.24108 12.644C2.03657 12.644 2.40841 12.5231 2.34334 12.4301C2.13883 12.4301 1.94361 12.3744 1.81346 12.3C1.94361 12.0025 1.56247 11.9375 1.46951 11.8166C1.54388 11.6679 1.85065 11.5284 1.84135 11.4262C1.77628 11.3425 1.59036 11.6865 1.62754 11.4819L1.69262 11.4541C1.59965 11.4541 1.7205 11.1008 1.30218 11.3239L1.62754 11.1659C1.62754 11.1659 1.55317 11.1473 1.51599 11.1473C1.60895 11.0822 1.68332 10.9985 1.76698 10.9892C1.92502 10.7754 1.62754 10.8498 1.56247 10.7661L1.42303 10.9335C1.19063 10.8777 1.30218 10.6639 1.15344 10.5616L1.33007 10.4594L1.17203 10.4408C1.35796 10.3571 1.42303 10.2177 1.2464 10.2549L1.81346 10.2084C1.74839 10.3292 1.56247 10.2735 1.41373 10.4129C1.28359 10.5337 1.41373 10.6453 1.59036 10.5523C1.58106 10.4873 1.53458 10.5152 1.45092 10.5152C1.68332 10.3478 1.7205 10.4315 1.90643 10.3664C1.87854 10.3478 1.93431 10.2642 1.85065 10.3106C1.99939 10.2827 2.05516 10.3292 2.11094 10.4036C1.98079 10.4036 1.98079 10.5337 1.89713 10.5523C2.11094 10.4222 2.23179 10.4594 2.24108 10.5988C2.04587 10.8312 2.52926 10.6825 2.53856 10.8498C2.29686 10.9428 2.08305 10.9985 1.95291 10.98C1.89713 11.1287 2.01798 11.0636 1.95291 11.2124C2.13883 11.138 2.38982 11.0078 2.55715 11.0357L2.40841 11.1473C2.54786 11.1845 2.78026 11.0171 2.80815 11.1566C2.86392 11.3983 3.00336 11.5935 3.08703 11.7515L2.93829 11.8631C3.31943 11.705 3.25436 12.0397 3.47746 12.0397C3.46817 12.3279 3.91438 12.3279 3.71916 12.6161C4.07241 12.8485 4.39778 13.0437 4.593 13.4062L4.3327 13.5178C4.53722 13.4527 4.23974 13.6479 4.31411 13.6851C4.43496 13.4806 4.60229 13.5922 4.76962 13.5271C4.71384 13.806 5.03921 13.8524 5.2902 13.8617L5.14146 13.9826C5.5226 13.8896 5.40176 14.2429 5.48542 14.4381C5.43894 14.5032 5.31809 14.6426 5.37387 14.6798C5.68064 14.5775 5.69923 14.6333 5.95022 14.6426C6.02459 14.7356 6.08967 14.9308 6.07107 15.1074C6.37784 15.1446 6.55447 15.3026 6.7125 15.47C6.80546 15.5722 6.84265 15.6094 6.87983 15.6373C6.92631 15.6652 6.98209 15.6838 7.05646 15.6745L6.92631 15.8697C7.14942 15.7674 7.1866 15.7953 7.24238 15.8883C7.28886 15.972 7.34464 16.1114 7.40971 15.9998L7.32605 16.4925C7.34464 16.7063 7.4283 16.4646 7.4469 16.0649C7.46549 16.2694 7.51197 15.8604 7.53056 16.3624C7.56774 16.5111 7.56774 16.13 7.57704 16.0649C7.60493 16.2137 7.63282 16.288 7.65141 16.3066C7.67 16.3066 7.67 16.2137 7.67 16.13V16.1021C7.67 16.2508 7.70719 16.5297 7.72578 16.5483C7.72578 16.4739 7.72578 16.4554 7.72578 16.4368C7.73507 16.3996 7.74437 16.3438 7.6607 15.8976C7.70719 16.0742 7.71648 15.9441 7.71648 15.8511C7.71648 15.7581 7.71648 15.6931 7.80944 15.879C7.75367 15.7303 7.75367 15.6931 7.71648 15.5908C7.72578 15.5536 7.9024 15.7488 7.80015 15.5071C7.84663 15.5536 7.9117 15.7117 7.93959 15.7024C7.921 15.6466 7.84663 15.5536 7.80944 15.4793C7.76296 15.3491 7.80944 15.377 7.89311 15.3956C7.93959 15.4607 8.19988 15.2747 8.27425 15.1353C8.47876 14.4753 9.01793 14.057 9.39907 13.6015L9.46415 13.6665C9.35259 13.2761 10.0405 13.5829 9.78021 13.1088C9.87317 13.1366 9.93825 13.0158 10.0312 13.1645C9.96614 12.8857 10.496 13.0251 10.4402 12.6532C10.4216 12.6532 10.4216 12.6811 10.4402 12.7276C10.7377 12.7183 10.6912 12.3837 10.9887 12.3558C10.998 12.4023 10.9887 12.4487 11.0445 12.5231C11.2304 12.5882 10.9329 12.0955 11.2676 12.3837C11.3048 12.3465 11.1467 12.1977 11.1281 12.2256C11.6115 12.0118 11.8161 11.4355 12.1321 11.0078C12.5876 10.9428 12.6434 11.5377 12.6434 11.0915C12.7178 11.138 12.5412 10.9521 12.6062 11.0171C12.6062 10.8498 13.071 11.2588 12.9688 11.0357C12.7643 10.8591 12.9037 10.887 12.8014 10.7661C13.0896 10.7383 13.2848 10.887 13.2848 10.6174L13.3685 10.729C13.257 10.292 13.5823 10.2827 13.4057 9.81794C14.2237 8.972 14.8838 8.03309 15.7111 7.24293C16.6221 6.56431 17.3193 5.69048 18.3419 5.13271C18.7881 5.24427 18.7974 5.21638 18.9183 4.9189C18.9462 4.97468 18.9462 4.99327 18.9926 5.02116C18.8067 4.77946 19.1321 4.86313 18.9647 4.62143C19.3273 4.38903 19.569 4.07296 19.8944 3.79408C19.8665 3.85915 19.9966 4.07296 20.0431 4.00789L19.978 3.80337L20.0431 3.85915C20.0524 3.78478 20.0059 3.63604 19.8944 3.59886C20.5544 2.69714 21.7722 2.47403 22.5437 1.73034C22.8226 1.66527 23.0178 1.34921 23.1945 1.1168C24.0776 0.902993 24.8492 0.689183 25.3047 -0.0545044C25.3047 -0.0545044 25.723 0.62411 25.5836 0.977361L25.5929 1.03314Z\" fill=\"#8F3A7E\"><\/path><path d=\"M1.7481 9.85501C1.62739 9.95715 1.59954 10.0778 1.38599 10.115C1.50669 10.0314 1.61811 9.91072 1.7481 9.85501Z\" fill=\"#8F3A7E\"><\/path><path d=\"M1.8506 12.8295C1.8506 12.8295 1.82275 12.8945 1.80418 12.9131C1.77632 12.8945 1.65562 12.9409 1.70204 12.8759C1.7299 12.8945 1.78561 12.8481 1.8506 12.8202V12.8295Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.16678 13.4147C2.05536 13.489 1.87895 13.4425 1.82324 13.3775L2.16678 13.4147Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.08289 14.2437C2.02718 14.3551 1.96219 14.383 1.92505 14.318C1.98076 14.2715 2.02718 14.2715 2.08289 14.2437Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.35372 14.0857C2.35372 14.0857 2.33511 14.188 2.28857 14.2625C2.38165 14.188 2.15827 14.216 2.35372 14.0857Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.84607 15.3857C2.84607 15.3857 3.00391 15.3857 2.90178 15.5064C2.96677 15.4135 2.66966 15.4878 2.84607 15.3857Z\" fill=\"#8F3A7E\"><\/path><path d=\"M3.39329 15.7397C3.39329 15.7397 3.384 15.7861 3.43043 15.7769C3.40257 15.8418 3.30044 15.879 3.27258 15.8604L3.39329 15.7397Z\" fill=\"#8F3A7E\"><\/path><path d=\"M11.9369 14.7541L11.9462 14.8467L11.8535 14.7448L11.9369 14.7541Z\" fill=\"#8F3A7E\"><\/path><path d=\"M15.4611 11.4917C15.4611 11.3803 15.5818 11.5567 15.6003 11.5659C15.5632 11.6124 15.5075 11.4267 15.4611 11.4917Z\" fill=\"#8F3A7E\"><\/path><path d=\"M16.957 9.2601L16.9477 9.27864L16.7716 9.06546L16.957 9.2601Z\" fill=\"#8F3A7E\"><\/path><path d=\"M26.4111 1.45928C26.4761 1.32929 26.2068 1.32001 26.4111 1.32001C26.4668 1.41286 26.5039 1.49642 26.4111 1.45928Z\" fill=\"#8F3A7E\"><\/path><path d=\"M1.08847 10.4673C1.92512 10.4673 1.62764 11.3319 2.27837 11.4713C2.33415 11.4992 1.95301 11.6851 2.10174 11.7316C2.81754 11.7967 2.97558 12.5682 2.97558 13.2747L2.86402 13.3119C2.86402 13.4514 3.23587 13.3305 3.26375 13.4514C3.20798 13.4979 3.1615 13.4886 3.09642 13.5629C3.29164 13.4514 3.30094 13.6652 3.45897 13.6094C3.42179 13.6931 3.27305 13.7953 3.23587 13.9069L3.47756 13.8046C4.06322 13.5908 3.70997 14.1765 4.1097 14.1858C4.05392 14.2137 4.00744 14.2229 3.97026 14.2694C4.50013 14.3624 4.75113 14.79 5.13227 15.0596C5.0486 15.0968 4.91846 15.1897 4.85338 15.2734C5.07649 15.1247 5.20664 15.1897 5.32749 15.2548C5.15086 15.4686 5.64355 15.2548 5.61566 15.4593L5.55989 15.4872C5.84807 15.3943 5.532 15.7103 5.84807 15.5616L5.72722 15.7475C6.05258 15.543 5.66214 15.9892 5.86666 15.9334L5.92244 15.8777C6.04328 15.8777 5.92244 16.0357 6.0154 16.0543L5.98751 16.0915C6.17343 16.1658 6.06188 16.361 6.28498 16.1658C6.14554 16.3703 6.10836 16.1193 5.90384 16.4168C6.4895 16.6492 6.74049 17.049 7.08445 17.458C7.08445 17.6532 7.11233 17.7369 7.10304 17.8949C7.14952 17.8577 7.25178 17.9879 7.30755 17.8112C7.29826 17.8112 7.30755 18.0529 7.33544 18.0994C7.40051 18.3504 7.4284 17.6997 7.48418 17.9786C7.45629 18.0715 7.4377 18.2017 7.44699 18.3783C7.52136 18.1087 7.59573 18.2482 7.6608 18.211C7.6608 18.2853 7.64221 18.3132 7.64221 18.462C7.69799 18.118 7.80024 18.7316 7.84673 18.527V18.7966C7.99546 19.2893 7.82813 18.276 7.9025 18.3783C7.9025 18.5084 7.92109 18.6107 7.93039 18.7408C7.93039 18.3597 7.93969 18.2017 7.96757 18.0715C7.98617 17.9693 8.01406 17.8949 8.02335 17.7648C8.02335 17.8019 8.04194 17.8763 8.04194 17.8763C8.07913 17.6904 8.17209 17.6904 8.19068 17.3743C8.24646 17.4208 8.33942 17.9414 8.39519 17.7183C8.23716 17.2628 8.46027 17.3 8.23716 16.9188C8.31153 16.8909 8.46956 16.8537 8.45097 16.6771C8.49745 16.8537 8.72056 17.0211 8.68337 17.1605C8.73915 17.207 8.79493 17.2535 8.86 17.3C8.94366 17.458 8.77633 17.3464 8.90648 17.5045C8.93437 17.4208 8.94366 17.1047 9.00874 17.1047C8.93437 16.8073 8.72985 16.4261 8.76704 16.2774C8.82282 16.4354 9.06451 16.5098 9.08311 16.5935C8.97155 16.3703 8.84141 16.1658 8.70197 15.9892C8.71126 15.9427 8.92507 16.1472 8.89718 16.0264C8.82281 15.9799 8.79493 15.9148 8.75774 15.8498C8.80422 15.8498 8.8507 15.5895 9.12959 15.7754C9.25043 15.8405 9.12959 15.8962 9.25973 15.9148C9.3248 15.8219 9.24114 15.7475 9.29692 15.6545L9.3341 15.6824C9.41776 15.6545 9.36199 15.4221 9.16677 15.3664C9.12029 15.4036 9.3341 15.4779 9.21325 15.4779C9.0924 15.3106 9.13888 15.1711 9.21325 15.0875C9.23184 15.1526 9.30621 15.2083 9.36199 15.2827C9.25043 14.9945 9.29692 14.8179 9.3341 14.6134C9.21325 14.5018 9.51073 14.8551 9.42706 14.8179C9.73383 14.7993 9.49213 14.2694 9.86398 14.3531C9.86398 14.3903 9.68735 14.2044 9.72454 14.2415C9.8082 14.1765 9.97553 14.3438 9.96623 14.2415C10.0685 14.3345 9.99412 14.1486 10.0127 14.0742C9.96623 13.9812 10.0778 14.1114 10.0406 14.1579C10.022 14.0091 10.1522 13.5815 10.4496 13.5629C10.3846 13.4979 10.3102 13.2283 10.3567 13.2004L10.4868 13.3677C10.6077 13.4235 10.5984 13.2376 10.7285 13.3584C10.6263 13.0981 10.5798 13.8139 10.5426 13.5629C10.6913 13.6652 10.4496 13.1725 10.6356 13.4049C10.7006 13.3305 10.6077 13.0888 10.8215 13.1632C10.775 13.1632 10.9609 13.4328 11.0167 13.3677C11.0911 13.2376 10.9795 13.2655 11.0167 13.1353V13.0238C10.868 12.8657 11.1282 12.9587 10.9237 12.8192C11.0539 12.9308 11.0074 12.5961 11.2305 12.8564L11.3978 13.0702C11.4257 13.0145 11.277 12.7913 11.2305 12.6705C11.2584 12.6798 11.3049 12.7077 11.3328 12.7449C11.0539 12.4381 11.4629 12.6705 11.3049 12.3823C11.5001 12.4009 11.5559 12.1685 11.779 12.308C11.7697 12.1499 11.7325 11.9733 11.8812 11.964C11.8905 12.0105 11.8812 12.0384 11.9277 12.1034C12.0671 12.1406 12.0021 12.0477 12.0021 11.9547C12.03 12.0105 12.2717 12.0384 12.4297 12.0848C12.4204 11.9268 12.2438 11.7874 12.1601 11.6758C12.5041 11.9175 12.188 11.2947 12.5227 11.4899C12.532 11.555 12.5505 11.7316 12.6807 11.7595C13.0246 12.0012 12.6156 11.4155 12.8573 11.462L12.597 11.2389C12.7829 11.3505 12.6249 10.9507 12.848 11.211C12.8015 11.0902 13.0525 11.1738 12.8201 10.9414C13.1827 10.9879 13.1455 10.4208 13.6475 10.7555C13.6382 10.6904 13.7404 10.6718 13.6103 10.5603C13.443 10.458 13.6382 10.709 13.5359 10.6347C13.5545 10.6068 13.4987 10.5324 13.4709 10.4952C13.5731 10.4952 13.6382 10.4766 13.7683 10.7276C14.0286 10.7648 13.5173 10.1977 13.7683 10.1513C13.852 10.2628 13.8985 10.2907 13.9357 10.2256L13.8706 9.97463C14.01 9.91886 14.1402 10.1513 14.2982 10.3279C14.3261 10.2535 14.4005 10.1977 14.3075 10.049L14.5678 10.207C14.3819 10.0955 14.5213 10.0583 14.5027 9.99323V10.0583C14.5864 10.1234 14.6143 10.0211 14.6236 9.97463C14.5213 9.87238 14.4191 9.89097 14.354 9.89097C14.3168 9.78871 14.3726 9.77012 14.3261 9.64927C14.4655 9.8259 14.5213 9.68646 14.5864 9.66786C14.6701 9.66786 14.5027 9.46335 14.5306 9.45405C14.6143 9.53772 14.6236 9.39828 14.6979 9.55631C14.6979 9.60279 14.5864 9.50983 14.6236 9.61209C14.7165 9.64927 14.8467 9.8073 14.8188 9.63068C14.7909 9.50053 14.5027 9.30532 14.6979 9.32391C14.7072 9.38898 14.763 9.46335 14.8002 9.53772H14.9675L14.8374 9.38898C14.8839 9.41687 14.8839 9.43546 14.9118 9.45405C14.7909 9.26813 15.0047 9.27743 14.8653 9.08221C14.8932 9.02643 15.0605 9.1008 15.1163 9.08221V9.1008C15.2557 9.14728 15.2743 9.01714 15.2278 8.8777L15.2557 8.91488C15.2557 8.91488 15.3487 8.81262 15.3022 8.69177C15.4788 8.73826 15.8414 9.25884 15.7577 8.98925C15.8321 8.91488 15.6276 8.59881 15.5067 8.52444C15.7391 8.50585 15.6647 8.11542 16.0087 8.24556C15.9715 8.1619 15.925 8.13401 15.9343 8.06894C16.1853 7.95738 16.1946 7.51117 16.6222 7.6785C16.6222 7.79935 16.7524 7.83653 16.836 7.92949C16.7617 7.74357 17.022 8.02246 16.836 7.77146C16.7059 7.63202 16.6501 7.55765 16.5479 7.55765C16.6036 7.38103 16.7803 7.22299 16.9662 7.29736C16.8732 7.26018 16.8639 7.1951 16.8546 7.13003C17.0406 7.36243 17.1614 7.31595 17.1614 7.18581L17.0499 7.03707L17.2172 7.13933C17.2079 7.07425 16.9941 6.82326 17.18 6.89763C17.2265 6.94411 17.2823 6.99989 17.3287 7.02777C17.3008 6.85115 17.2358 6.58156 17.4124 6.62804L17.6448 6.77678C17.6541 6.7303 17.6076 6.56297 17.5054 6.55367C17.7378 6.56297 17.8307 6.50719 18.0259 6.64664C17.8772 6.03309 18.1933 5.73562 18.4722 5.5497L18.5558 5.66125C18.7046 5.69843 18.435 5.44744 18.5558 5.47533C18.6209 5.59618 18.7882 5.64266 18.844 5.80999C19.0392 5.83788 18.8161 5.52181 18.844 5.41955C18.7417 5.27081 18.8626 5.5497 18.7324 5.36377C18.7046 5.308 18.9648 5.35448 18.7975 5.13137C18.8905 5.18715 19.002 5.35448 19.0578 5.45674L19.0299 5.308C19.3088 5.48462 19.2251 5.88436 19.5598 6.10746L19.5877 6.0238C19.8201 6.19113 19.6435 6.39564 19.848 6.34916C19.8201 6.20042 19.6156 5.85647 19.4854 5.80999C19.5598 5.64266 19.1229 5.27081 19.2809 5.16856C19.4204 5.26152 19.1972 5.28941 19.3646 5.43814C19.5691 5.5497 19.4111 5.23363 19.5226 5.24293C19.3925 5.21504 19.2716 4.96404 19.2809 4.88967C19.4297 4.92686 19.4018 5.12208 19.5133 5.057C19.4297 4.92686 19.4389 4.75953 19.2902 4.74094C19.095 4.44346 19.4575 4.73164 19.3367 4.47135C19.5319 4.62938 19.6063 4.99193 19.8015 5.00123C19.6249 4.8339 19.7271 4.63868 19.4389 4.41557C19.5226 4.43417 19.6528 4.57361 19.7178 4.71305C19.8759 4.77812 19.5784 4.25754 19.913 4.6015L19.7736 4.39698C19.848 4.44346 19.913 4.46205 20.0246 4.53642C20.0804 4.48994 19.9781 4.13669 20.2198 4.42487C20.2198 4.37839 20.3407 4.29472 20.1362 4.13669C19.9595 4.08091 20.1733 4.3505 19.9038 4.12739C20.1362 4.29472 19.9874 4.00655 19.9688 3.89499L20.0711 3.99725C20.0618 3.93218 20.1455 3.90429 20.0618 3.77414C20.099 3.85781 20.164 3.92288 20.2105 3.93218L20.099 3.74626C20.1362 3.56963 20.3686 4.01584 20.4336 3.8857L20.4615 4.08091C20.4615 4.08091 20.6196 4.16458 20.6288 4.07162C20.5266 3.90429 20.3964 3.69048 20.3221 3.56033C20.3221 3.44878 20.4894 3.70907 20.415 3.50456L20.4987 3.75555C20.5266 3.81133 20.759 3.96007 20.8334 3.89499C20.8334 3.80203 20.7311 3.51385 20.5824 3.49526C20.6196 3.45808 20.7497 3.50456 20.8148 3.644C20.8612 3.51385 20.666 3.48596 20.666 3.32793C20.7869 3.4023 21.0007 3.46737 21.1866 3.56033L21.3168 3.8857L21.3725 3.83922C21.4748 4.09951 21.5399 3.96936 21.6793 4.21106C21.7444 4.21106 21.7258 4.1088 21.7165 4.01584C21.3168 3.76485 21.4376 3.44878 21.1401 3.1606C21.2145 2.95609 21.8745 3.84851 21.6142 3.22567C21.5213 3.1606 21.3911 2.86313 21.3725 3.03046C21.4934 2.99327 21.168 2.66791 21.3818 2.70509C21.4097 2.90031 21.7351 2.95609 21.7816 3.23497C21.6979 3.12342 21.6514 3.20708 21.6607 3.25356C21.8002 3.34652 21.921 3.57893 22.014 3.49526C22.0419 3.42089 22.1162 3.34652 21.9675 3.18849C21.8095 3.01186 21.8931 3.28145 21.7816 3.06764C21.8373 2.90961 22.0883 3.1699 21.8652 2.80735C21.8187 2.89101 21.6421 2.72369 21.5399 2.59354L21.5585 2.4448L21.6421 2.57495C21.8466 2.54706 21.5027 2.32395 21.6514 2.24958L21.9117 2.43551C22.0511 2.66791 21.6514 2.50058 21.9489 2.81665C22.0419 2.76087 21.9303 2.56565 22.079 2.58424C22.079 2.63072 22.0697 2.65861 22.079 2.6958C22.1162 2.6772 22.516 3.09553 22.423 2.74228C22.4044 2.59354 22.3393 2.61213 22.2371 2.48199C22.3393 2.33325 22.2743 2.17522 22.3393 2.08226C22.5253 2.34255 22.5067 1.98 22.6275 2.30536C22.4602 2.2031 22.2836 2.37973 22.4323 2.64932C22.7205 2.89101 22.2928 2.6958 22.5067 3.01186C22.6182 2.9282 22.8506 3.21638 23.0272 3.38371C23.0644 3.37441 23.0272 3.27215 23.0272 3.22567C22.8971 3.03975 22.8599 3.07694 22.7019 2.90031C22.8599 2.84453 22.8971 2.64932 22.8227 2.42621C22.9343 2.48199 23.0644 2.66791 23.0365 2.72369C23.1388 2.55636 23.3061 2.4448 23.4827 2.38903C23.1574 2.17522 23.5757 2.19381 23.3247 2.00789C23.1946 2.00789 22.9715 1.84985 22.8971 1.69182C22.9622 1.67323 22.9994 1.82196 23.0737 1.85915C22.9994 1.65464 23.3712 2.03577 23.2225 1.7383C23.1667 1.94281 23.4827 2.11014 23.6501 2.35184C23.6408 2.14733 23.7802 2.50988 23.8732 2.43551C23.8639 2.23099 23.8918 2.03577 23.9568 1.90563C24.2636 2.00789 24.2915 1.63604 24.4031 1.52449C24.5611 1.58956 24.7284 1.87774 24.8307 1.85915C24.905 1.78478 24.5425 1.63604 24.7563 1.65464L24.7842 1.71041C24.7656 1.62675 25.1375 1.71041 24.8679 1.31068L25.0631 1.61745C25.0631 1.61745 25.0724 1.54308 25.0631 1.5059C25.1374 1.58956 25.2304 1.65464 25.2397 1.7383C25.4721 1.86845 25.3606 1.58027 25.4349 1.51519L25.249 1.39434C25.2769 1.15265 25.5 1.24561 25.5744 1.07828L25.7045 1.23631V1.07828C25.8068 1.24561 25.9648 1.29209 25.8997 1.12476L26.0299 1.67323C25.8997 1.62675 25.9276 1.43153 25.7696 1.30138C25.6301 1.18983 25.5465 1.32927 25.6487 1.4966C25.7045 1.47801 25.6859 1.44083 25.6673 1.35716C25.8625 1.56167 25.7882 1.61745 25.8811 1.78478C25.8997 1.75689 25.9834 1.79408 25.9369 1.71971C25.9834 1.86845 25.9462 1.92422 25.8718 1.98929C25.8532 1.85915 25.7324 1.87774 25.6952 1.79408C25.8532 1.98929 25.8254 2.11014 25.6859 2.13803C25.4349 1.9707 25.6301 2.43551 25.4628 2.46339C25.342 2.23099 25.2676 2.02648 25.2676 1.88704C25.1189 1.84985 25.1932 1.96141 25.0445 1.91493C25.1375 2.09155 25.2955 2.33325 25.2769 2.50058L25.1467 2.36114C25.1282 2.50058 25.3048 2.71439 25.1653 2.77017C24.9236 2.84453 24.7377 3.00257 24.589 3.09553L24.4588 2.95609C24.6448 3.32793 24.3008 3.28145 24.3101 3.50456C24.0219 3.50456 24.0498 3.96007 23.7523 3.78344C23.5385 4.15528 23.3619 4.48994 22.9994 4.70375L22.8785 4.45276C22.9529 4.65727 22.7391 4.3598 22.7112 4.44346C22.9157 4.55502 22.8134 4.72234 22.8878 4.88967C22.6089 4.84319 22.581 5.17785 22.5717 5.42885L22.4416 5.28941C22.5438 5.67055 22.1906 5.55899 21.9954 5.64266C21.9303 5.59618 21.7816 5.48462 21.7537 5.5404C21.8652 5.84717 21.8095 5.86576 21.8002 6.11676C21.7072 6.19113 21.512 6.2655 21.3446 6.2469C21.2796 6.86974 20.7497 6.95341 20.5638 7.4554L20.3964 7.30666C20.3593 7.95738 19.6528 7.99457 19.5226 8.44078L19.2995 8.12471C19.1322 8.12471 19.1508 8.385 19.3553 8.56163C19.188 8.56163 19.2437 8.89629 18.9834 8.71037C18.844 8.73825 18.9834 8.94277 18.937 9.04503C18.6581 9.1008 18.6023 9.18447 18.4722 9.38898L18.5279 9.37039C18.4907 9.28672 18.3885 9.16588 18.3327 9.18447C18.3327 9.32391 18.0259 9.31461 18.3885 9.60279C18.0259 9.56561 18.091 10.1513 17.6727 10.0397C17.7657 10.1234 17.7378 10.1791 17.7749 10.2535C17.6169 10.4023 17.273 10.3651 17.2823 10.644C17.2172 10.6161 17.1893 10.4487 17.1056 10.4952C17.1056 10.5696 17.2079 10.6161 17.2079 10.709C17.0963 11.1181 16.5107 11.0065 16.3062 11.2668C16.0366 11.8246 15.5067 12.1406 15.1349 12.5404L15.0791 12.466C15.172 12.8471 14.5213 12.4939 14.763 12.9773C14.6701 12.9401 14.6143 13.0609 14.5213 12.9122C14.5771 13.1911 14.0658 13.0238 14.1123 13.3956C14.1309 13.3956 14.1309 13.3677 14.1123 13.3212C13.8148 13.3212 13.8706 13.6466 13.5731 13.6745C13.5638 13.628 13.5731 13.5815 13.5173 13.5071C13.3314 13.4421 13.6289 13.9255 13.2942 13.6373C13.257 13.6745 13.4151 13.8232 13.4337 13.7953C12.9503 14.0091 12.7551 14.5762 12.4669 14.9945C12.03 15.0596 11.937 14.4832 11.9649 14.9109C11.8905 14.8644 12.0671 15.041 12.0021 14.9759C12.0021 15.134 11.5373 14.7528 11.6488 14.9666C11.8626 15.134 11.7232 15.1061 11.8347 15.2269C11.5559 15.2548 11.3514 15.1247 11.3792 15.385L11.2863 15.2734C11.435 15.6917 11.1282 15.7196 11.3606 16.1472C11.2026 16.361 11.0539 16.5749 10.9237 16.7887L10.4403 17.6625C9.91975 18.5456 9.60369 20.0423 9.12029 21.4367C8.99014 21.7993 8.8507 22.1618 8.72056 22.5151L8.33942 22.0874L7.89321 21.5762L7.00078 20.5536C6.41513 19.8657 5.80159 19.1127 5.281 18.3225C5.20664 17.6439 5.20664 17.6625 4.77902 17.3743C4.83479 17.3464 4.86268 17.365 4.89057 17.3C4.76972 17.3929 4.70465 17.3185 4.64887 17.2628C4.61169 17.2256 4.5745 17.1791 4.45365 17.2628C4.23055 16.9002 3.92378 16.6399 3.64489 16.296C3.70997 16.3332 3.93307 16.203 3.868 16.1472L3.66349 16.203L3.71926 16.1379C3.64489 16.1193 3.49616 16.1658 3.44968 16.2774C2.55725 15.5709 2.37133 14.3345 1.66483 13.5071C1.60905 13.219 1.30228 12.9959 1.08847 12.8006C0.930435 11.8617 0.790994 11.0902 0.0751953 10.4116C0.0751953 10.4116 0.828178 10.1513 1.16284 10.3558L1.08847 10.4673Z\" fill=\"#8F3A7E\"><\/path><path d=\"M26.3094 1.58132C26.1885 1.47901 26.0676 1.47901 25.9932 1.27438C26.0955 1.3767 26.235 1.46971 26.3094 1.58132Z\" fill=\"#8F3A7E\"><\/path><path d=\"M23.3623 1.9979C23.3623 1.9979 23.2973 1.97005 23.2695 1.96076C23.288 1.93291 23.223 1.8122 23.2973 1.85863C23.2787 1.88648 23.3345 1.94219 23.3623 1.9979Z\" fill=\"#8F3A7E\"><\/path><path d=\"M22.8039 2.34232C22.7203 2.2309 22.7574 2.06377 22.8131 1.99878V2.34232H22.8039Z\" fill=\"#8F3A7E\"><\/path><path d=\"M21.9853 2.29645C21.8739 2.24074 21.846 2.18504 21.9018 2.13861C21.9482 2.19432 21.9575 2.23146 21.9853 2.29645Z\" fill=\"#8F3A7E\"><\/path><path d=\"M22.1544 2.56585C22.1544 2.56585 22.052 2.55654 21.9775 2.51001C22.052 2.59377 22.0241 2.37971 22.1544 2.56585Z\" fill=\"#8F3A7E\"><\/path><path d=\"M20.8979 3.10465C20.8979 3.10465 20.8979 3.26249 20.7772 3.16965C20.8701 3.22535 20.7772 2.93752 20.8979 3.10465Z\" fill=\"#8F3A7E\"><\/path><path d=\"M20.5632 3.65382C20.5632 3.65382 20.5168 3.65382 20.5261 3.69096C20.4611 3.6631 20.424 3.57025 20.4425 3.53311L20.5632 3.65382Z\" fill=\"#8F3A7E\"><\/path><path d=\"M12.5693 11.3684V11.275L12.6534 11.3871L12.5693 11.3684Z\" fill=\"#8F3A7E\"><\/path><path d=\"M9.03711 14.8652C9.05568 14.9767 8.90712 14.8188 8.88855 14.8188C8.9164 14.7631 8.99997 14.9488 9.03711 14.8652Z\" fill=\"#8F3A7E\"><\/path><path d=\"M8.21887 17.2635V17.2357L8.33029 17.5885L8.21887 17.2635Z\" fill=\"#8F3A7E\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Bank-grade Security<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"27\" height=\"23\" viewBox=\"0 0 27 23\" fill=\"none\"><path d=\"M26.5504 1.48711C26.5133 1.41296 26.3928 1.2832 26.3743 1.33881L26.5411 1.59833V1.48711H26.5504Z\" fill=\"#8F3A7E\"><\/path><path d=\"M25.9092 1.28207C25.9556 1.43991 26.067 1.68132 26.2806 1.8763C26.1413 1.60704 26.2342 1.69061 26.0577 1.3842C26.0763 1.31921 26.197 1.40277 26.262 1.49562C26.2249 1.42134 26.3734 1.49562 26.262 1.32849C26.0577 1.18922 25.9835 1.23565 26.0392 1.4492C25.9835 1.41206 25.9463 1.33778 25.9092 1.29136V1.28207Z\" fill=\"#8F3A7E\"><\/path><path d=\"M19.0215 6.23586C19.0215 6.23586 19.0215 6.18064 19.0031 6.16223C19.0031 6.18984 19.0031 6.21746 19.0215 6.23586Z\" fill=\"#8F3A7E\"><\/path><path d=\"M18.3794 6.34023C18.3794 6.34023 18.4077 6.34023 18.4171 6.34023C18.3888 6.3308 18.37 6.32138 18.3794 6.34023Z\" fill=\"#8F3A7E\"><\/path><path d=\"M21.5952 4.26723L21.465 4.24863C21.5208 4.33234 21.5487 4.27653 21.5952 4.26723Z\" fill=\"#8F3A7E\"><\/path><path d=\"M25.8363 2.31298C25.8363 2.31298 25.8363 2.25752 25.8178 2.22055C25.8178 2.23904 25.8178 2.25752 25.8086 2.27601L25.8363 2.31298Z\" fill=\"#8F3A7E\"><\/path><path d=\"M22.5358 3.16046L22.5544 3.14186C22.5544 3.14186 22.5172 3.07675 22.4893 3.03024L22.5358 3.16046Z\" fill=\"#8F3A7E\"><\/path><path d=\"M23.3447 2.4166C23.3447 2.4166 23.4749 2.63052 23.5493 2.72353C23.4935 2.63052 23.4749 2.58401 23.4749 2.54681C23.447 2.50961 23.4005 2.4631 23.3447 2.4166Z\" fill=\"#8F3A7E\"><\/path><path d=\"M21.8932 3.61673C21.8932 3.61673 21.8372 3.56072 21.8279 3.55139C21.8465 3.57939 21.8745 3.59806 21.8932 3.61673Z\" fill=\"#8F3A7E\"><\/path><path d=\"M0.799326 11.6575C0.799326 11.6575 0.827596 11.6386 0.837019 11.6292C0.808749 11.6292 0.789903 11.648 0.799326 11.6575Z\" fill=\"#8F3A7E\"><\/path><path d=\"M1.21851 9.87102L1.24636 9.8803L1.37635 9.81531L1.21851 9.87102Z\" fill=\"#8F3A7E\"><\/path><path d=\"M10.5801 13.1525C10.8215 13.2453 10.6636 13.4868 10.9608 13.561C10.8772 13.496 10.7843 13.1711 10.5801 13.1525Z\" fill=\"#8F3A7E\"><\/path><path d=\"M25.7896 2.30579C25.7896 2.30579 25.7708 2.32463 25.752 2.33406C25.7708 2.33406 25.7802 2.31521 25.7896 2.30579Z\" fill=\"#8F3A7E\"><\/path><path d=\"M15.7295 8.4028C15.7295 8.4028 15.7942 8.45826 15.8219 8.47674C15.8034 8.45826 15.7757 8.43977 15.7295 8.4028Z\" fill=\"#8F3A7E\"><\/path><path d=\"M15.2939 9.27798C15.2939 9.27798 15.2285 9.25931 15.2285 9.30598C15.2378 9.30598 15.2472 9.31531 15.2565 9.32465C15.2378 9.28731 15.2379 9.26865 15.2939 9.27798Z\" fill=\"#8F3A7E\"><\/path><path d=\"M14.5957 9.90973C14.5957 9.90973 14.6241 9.92869 14.6431 9.93817V9.90973H14.5957Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.6049 13.9609C2.65136 13.8959 2.7071 13.8401 2.76285 13.7844C2.62348 13.9051 2.48412 13.8401 2.6049 13.9609Z\" fill=\"#8F3A7E\"><\/path><path d=\"M25.7432 2.19324C25.7802 2.24883 25.7988 2.27662 25.7895 2.29515L25.808 2.26736C25.808 2.26736 25.7617 2.21177 25.7432 2.19324Z\" fill=\"#8F3A7E\"><\/path><path d=\"M16.6315 10.8466L16.4922 10.9116C16.5386 10.9116 16.585 10.8745 16.6315 10.8466Z\" fill=\"#8F3A7E\"><\/path><path d=\"M7.79133 20.2916H7.76367C7.76367 20.2916 7.79133 20.3285 7.79133 20.2916Z\" fill=\"#8F3A7E\"><\/path><path d=\"M16.1947 11.2389C16.1111 11.1924 16.0554 11.1645 16.0089 11.1552C16.0089 11.1738 16.0275 11.1924 16.0368 11.2203L16.1854 11.2389H16.1947Z\" fill=\"#8F3A7E\"><\/path><path d=\"M1.95357 13.227C1.75835 13.1898 1.98146 13.1526 2.08371 12.9109C1.81413 13.0132 2.08371 12.7343 1.70258 12.9946C1.91639 12.7808 1.83272 12.8551 1.96287 12.6599C1.78624 12.8366 1.66539 12.6599 1.42369 12.8458C1.67469 12.6227 1.85131 12.725 2.06512 12.4275C1.83272 12.4926 1.68398 12.4275 1.37721 12.6227C1.4051 12.5205 1.49806 12.4275 1.47947 12.3253C1.47017 12.3532 1.53525 12.3253 1.57243 12.316C1.27496 12.316 1.33073 11.972 0.912408 12.1393C1.36792 11.8698 0.76367 11.7954 1.23777 11.6281C1.18199 11.5816 0.931 11.6095 0.838039 11.6374C1.18199 11.4143 0.828743 11.4328 0.986776 11.2283C0.772966 11.3213 0.76367 11.1633 0.614933 11.1726C0.680005 11.1726 0.745078 11.154 0.828743 11.0889C0.642821 11.0982 0.782262 11.0331 0.912408 10.8658C0.745078 10.8286 0.661413 11.0517 0.456899 11.0889C0.475491 10.9494 0.670709 10.9401 0.800854 10.8379L0.363938 10.9216C0.38253 10.8751 0.438307 10.81 0.531268 10.7449C0.401123 10.7542 0.224497 10.8007 0.354642 10.6334L0.438307 10.7449L0.59634 10.5962H0.280273C0.429011 10.2244 0.856631 10.0849 1.24707 9.88969L1.35862 9.92688C1.48877 9.85251 1.53525 9.75955 1.51665 9.72236C1.59102 9.64799 2.00005 9.61081 2.08371 9.65729C2.17668 9.8804 1.67469 9.95476 1.66539 10.1593L2.00005 10.2151L1.8792 10.2987C1.81413 10.3824 1.96287 10.3173 2.00005 10.2987C1.80483 10.401 2.03723 10.4939 2.05583 10.5869L2.19527 10.4568C2.70655 10.4196 2.01864 11.0517 2.33471 11.0982L2.67866 11.0331L2.46485 11.219C2.65078 11.1911 2.8367 11.0796 2.8367 11.2469C2.70655 11.9255 3.50602 11.9999 3.5525 12.5763C3.59898 12.5391 3.59898 12.5112 3.61757 12.4647C3.3108 13.2363 4.59366 12.567 4.39844 13.2084L4.29618 13.2549C4.46351 13.3757 4.19393 13.3014 4.15674 13.5059C4.44492 13.3199 4.51929 13.5431 4.68662 13.5616C4.62155 13.5895 4.60295 13.5616 4.53788 13.5616C4.4914 13.6267 4.33337 13.7569 4.41703 13.7662C4.88184 13.5709 5.01198 13.8126 5.24438 13.8777C5.08635 14.0357 5.03058 14.296 4.80747 14.5935C4.88184 14.5563 5.03987 14.482 5.1979 14.4076C5.13283 14.5563 5.25368 14.5284 5.38383 14.4913C5.33735 14.4448 5.30016 14.3983 5.27227 14.3704H5.29087C5.29087 14.3704 5.26298 14.3611 5.25368 14.3518C5.2165 14.3239 5.1979 14.3146 5.18861 14.3332C5.30946 14.138 5.32805 14.231 5.53256 14.0636C5.56975 14.1194 5.71849 14.1752 5.57904 14.3053C5.59764 14.3425 5.59764 14.3797 5.57904 14.4355C5.62552 14.4355 5.66271 14.4355 5.66271 14.4727H5.63482C5.63482 14.4727 5.59764 14.5284 5.57904 14.547C5.57904 14.7144 5.98807 14.6121 6.20188 14.5842C5.87652 14.7051 5.9323 14.8352 5.73708 14.9839C5.75567 14.9839 5.6906 14.8724 5.58834 14.7423C5.57904 14.7701 5.55116 14.798 5.48608 14.8538C5.37453 15.1234 5.81145 14.9003 5.80215 15.1792C5.77426 15.1792 5.70919 15.1978 5.65341 15.2628C5.65341 15.3651 5.83933 15.3 5.96018 15.2164C5.79285 15.3744 5.75567 15.6068 5.88582 15.5975C6.08103 15.5324 6.14611 15.4673 6.20188 15.5789L6.03455 15.644C6.01596 15.8485 6.29484 15.5882 6.26695 15.7648C6.28555 15.6905 6.14611 15.7927 6.14611 15.8392C6.31344 15.895 6.3971 15.8578 6.70387 15.709L6.49936 15.8671C6.67598 15.8485 6.97346 15.6997 6.73176 15.9693C7.08501 15.551 7.00135 15.8485 7.03853 15.9043C7.01994 15.9043 6.95487 15.9972 6.91768 16.053C7.18727 15.8113 7.05712 16.211 7.15938 16.3133L7.03853 16.7874C7.1036 16.8432 7.3453 15.9136 7.36389 15.96L7.30812 16.1831C7.38249 16.1831 7.40108 16.2482 7.44756 16.4063L7.41967 16.7874C7.45685 16.6387 7.48474 16.6758 7.50333 16.5085C7.52193 17.0291 7.587 16.9826 7.63348 16.9175C7.66137 16.8804 7.67996 16.8711 7.70785 16.9175C7.72644 16.9175 7.75433 17.0012 7.81011 17.2522L7.69855 16.4248C7.69855 16.4248 7.69855 16.4063 7.69855 16.397C7.70785 16.3505 7.71714 16.3226 7.81011 16.7409C7.91236 17.3173 7.83799 16.6944 7.87518 16.7874C7.87518 16.6944 7.80081 16.3319 7.77292 16.2482C7.91236 16.462 7.88447 15.9972 8.16336 16.3784C8.18195 16.0437 7.96814 15.6626 8.0611 15.6161L8.10758 15.6533C8.10758 15.6533 8.20054 15.6626 8.2935 15.6905C8.40506 15.6905 8.55379 15.7183 8.72112 15.8392C8.79549 15.5882 8.44224 15.1048 8.78619 14.9932L8.86986 15.142C8.98141 15.142 8.90704 14.9189 8.88845 14.8631C8.91634 14.8445 8.96282 14.9189 9.00001 14.9561C9.14874 14.9932 9.0093 14.8166 9.0186 14.7515L9.11156 14.8631C9.47411 14.8631 9.30678 14.231 9.56707 14.0543C9.56707 14.1194 9.68792 14.2031 9.75299 14.2403C9.50199 13.8405 9.81806 13.6639 9.83665 13.5059L9.91102 13.6825C9.87384 13.3014 10.3944 13.8684 10.3572 13.4873L10.0784 13.3943C10.1992 13.3757 10.1992 13.2642 10.0412 13.134C10.2271 13.1619 10.2922 13.3757 10.4502 13.2828C10.5432 13.3664 10.4223 13.4315 10.5803 13.5059L10.9801 13.5895C10.9801 13.5895 11.0358 13.5895 11.0637 13.5152C10.6547 13.1154 11.1846 13.3571 10.7105 13.0411C10.9243 12.7808 11.3798 12.8644 11.4077 12.4833C11.8725 12.8087 11.826 12.1208 12.2908 12.6599C12.4117 12.5577 12.4117 12.3625 12.2908 12.0929C12.2257 12.0743 12.2629 12.1672 12.2629 12.2137C12.17 12.0557 12.2908 11.8976 12.3466 11.8512C12.3838 12.0371 12.3466 12.2602 12.4767 12.5112C12.5325 12.3625 12.5046 12.0278 12.4953 11.9162L12.7742 12.1579C12.6813 11.8791 13.0531 12.3067 12.8951 11.9627L12.8021 11.8976C12.9787 11.7675 12.737 11.4979 12.8579 11.3213L12.9508 11.4328C13.0438 11.4328 12.8858 11.1075 13.1647 11.3027L13.0717 11.405C13.2576 11.5816 13.4064 11.6002 13.5272 11.6652C13.583 11.5165 13.2855 11.3213 13.3134 11.2469C13.4993 11.405 13.4064 11.3399 13.5272 11.5444C13.583 11.3771 13.6759 11.154 13.5551 10.8472C13.583 10.8751 13.6202 10.9123 13.6202 10.9123C13.7689 10.8286 13.5923 10.4103 13.7968 10.4939V10.5404C14.1314 10.717 13.8247 10.0663 14.2523 10.4939C14.3731 10.5311 14.1314 10.5683 14.401 10.7263C14.6706 10.7356 14.1593 10.2615 14.401 10.2708C14.3731 10.2708 14.401 10.2987 14.4289 10.3452C14.5126 10.2522 14.5963 10.0942 14.6613 9.95476C15.1168 10.2058 14.9681 9.51785 15.498 9.81532C15.3121 9.70377 15.3771 9.61081 15.3213 9.53644C15.3213 9.53644 15.3492 9.58292 15.3771 9.60151C15.4422 9.56433 15.3213 9.41559 15.2842 9.34122C15.4422 9.43418 15.3028 9.07164 15.4143 9.12741C15.3306 9.03445 15.3957 9.01586 15.4422 8.97867C15.4422 9.17389 15.5909 9.21108 15.6839 9.397C15.8698 9.32263 15.4794 8.82994 15.6839 8.77416L15.9256 8.88571C15.7025 8.59754 15.9349 8.58824 15.8419 8.48598C15.9442 8.55105 16.0279 8.56965 16.1394 8.70909C16.1394 8.58824 16.3532 8.65331 16.2324 8.46739L16.1115 8.4488C16.3904 8.39302 16.1487 7.90033 16.4555 7.95611L16.818 8.37443C17.0597 8.45809 16.7901 7.99329 17.0969 8.17921C16.9482 8.06766 16.9761 8.11414 16.9203 7.91892C16.8552 7.91892 16.8831 8.08625 16.8273 8.13273L16.7436 7.77948L16.6507 8.06766C16.5949 7.83526 16.6228 7.87244 16.4462 7.74229C16.4462 7.5006 16.7529 7.82596 16.7251 7.56567C16.818 7.58426 16.9017 7.77018 17.0225 7.81666C16.9946 7.58426 17.478 7.94681 17.3572 7.65863C17.4223 7.67722 17.3293 7.70511 17.413 7.79807C17.4409 7.70511 17.5059 7.67722 17.413 7.53778H17.32C17.3758 7.50989 17.2363 7.33327 17.4223 7.35186C17.3944 7.21242 17.2456 6.98002 17.1899 7.0265C17.1899 6.98002 17.3386 7.04509 17.4316 7.18453C17.5803 7.06368 17.1155 6.68254 17.4316 6.75691C17.4316 6.7755 17.4316 6.81269 17.4687 6.83128C17.5338 6.83128 17.5617 6.80339 17.5617 6.75691C17.4687 6.90565 17.8871 7.05438 17.6733 7.11016C17.8778 7.31467 17.822 7.05438 17.9428 7.11016C17.8871 6.89635 17.6733 6.7848 17.6175 6.64536C17.6733 6.71972 17.7104 6.69184 17.7662 6.69184L17.5896 6.5524C17.5896 6.5524 17.6547 6.50591 17.6547 6.43155V6.5524C17.7476 6.52451 18.073 6.71043 18.0544 6.44084C18.0823 6.5338 18.1381 6.71973 18.2868 6.74761C18.324 6.5338 18.3798 6.79409 18.5564 6.85917C18.6493 6.71043 18.324 6.5431 18.5936 6.48732C18.6122 6.46873 18.5099 6.38507 18.4541 6.35718C18.6493 6.32929 18.6215 6.15266 18.8446 6.17126C18.7516 6.17126 18.6586 6.15266 18.6679 6.01322C18.7516 6.18055 18.8817 6.0597 19.0026 6.09689L18.9468 6.00393C19.0584 6.0597 19.0491 6.13407 19.0491 6.18985C19.0212 6.16196 18.9933 6.14337 18.9747 6.17126C18.9747 6.2921 19.2722 6.58958 19.393 6.5431C19.4302 6.37577 19.2164 6.16196 19.1327 6.09689C19.3466 6.069 18.9282 5.60419 19.1792 5.62279C19.2071 5.5949 19.5975 5.84589 19.7184 5.79941C19.6068 5.56701 19.4767 5.75293 19.393 5.54842C19.9601 5.89237 19.4674 4.97206 19.9229 5.08361L20.0995 5.3439C20.1646 5.31602 20.2204 5.29742 20.2576 5.22305L20.0809 5.15798C20.0809 5.06502 20.239 5.00924 20.3505 5.22305C20.2948 4.93488 20.4156 5.02784 20.5736 5.00924C20.4528 5.08361 20.5457 4.98136 20.5736 5.16728C20.7874 5.18587 20.7317 5.10221 20.7596 4.98136C20.8153 5.07432 20.9641 5.16728 21.0013 5.13939C20.9455 4.92558 21.1035 4.85121 21.1407 4.68388L21.1965 4.75825C21.2894 4.52585 21.7542 4.69318 21.7542 4.33993C21.7542 4.33993 21.7542 4.33063 21.7542 4.32133H21.7264C21.4754 4.14471 21.7264 4.05175 21.7078 3.91231C21.7635 3.95879 21.8565 4.05175 21.8844 4.02386C21.7078 3.81005 21.8565 3.85653 21.8007 3.73568C21.9216 3.75427 22.0052 3.99597 22.0982 3.89371C22.1261 3.83794 22.0331 3.72638 21.968 3.65202C22.0796 3.73568 22.219 3.77286 22.2934 3.74498C22.3213 3.81934 22.2283 3.77286 22.2283 3.79146C22.312 3.91231 22.3213 3.83794 22.4329 3.97738C22.4979 3.94949 22.2841 3.76357 22.405 3.79146L22.4886 4.00527C22.5444 4.02386 22.5165 3.9309 22.5258 3.91231C22.5258 3.98667 22.6746 4.14471 22.7582 4.23767C22.7954 3.99597 22.4143 3.76357 22.2655 3.57765C22.5072 3.59624 22.4236 3.28947 22.5165 3.19651L22.6653 3.41032C22.6931 3.33595 22.6746 3.27088 22.6281 3.17791L22.7024 3.11284C22.721 3.22439 22.7582 3.29876 22.8791 3.4568C22.9163 3.33595 23.0743 3.28947 22.8791 3.01058L22.9163 3.05707C23.1022 3.05707 23.3811 2.92692 23.4461 3.01988C23.4926 2.83396 23.7715 2.86185 23.5577 2.60156C23.5763 2.48071 24.0225 2.78748 23.7994 2.41564C24.0225 2.51789 23.8645 2.48071 23.9946 2.69452C24.2177 2.79677 23.9388 2.28549 24.2828 2.63874C24.2828 2.44352 24.1991 2.58296 24.0876 2.38775C24.3943 2.71311 24.3107 2.29479 24.571 2.41564C24.4966 2.23901 24.4594 2.35986 24.4036 2.15534C24.4687 2.24831 24.5245 2.22971 24.5431 2.22971L24.3757 1.99731L24.9149 2.45282C24.8405 2.08098 24.571 2.09957 24.6732 1.84857V1.87646C24.9149 2.06238 24.6732 1.59758 24.9428 1.66265C24.8591 1.66265 25.0079 1.7835 25.0451 1.85787V1.70913C25.0451 1.70913 25.0544 1.74632 25.0822 1.76491C25.2868 1.87646 25.0636 1.62547 25.2589 1.70913C25.2403 1.7928 25.3983 1.95083 25.482 2.00661L25.3797 1.67195L25.5842 2.00661C25.7051 1.94153 25.4727 1.33729 25.8631 1.69984L25.8445 1.7835C25.9096 1.84857 26.1234 2.04379 26.0676 1.82998C26.0676 1.7742 25.9282 1.58828 25.9096 1.62547L26.0211 1.65336C26.1513 1.86717 26.0676 2.0345 26.0304 2.15534C25.9933 2.05309 26.0026 1.94153 25.8817 1.82998C25.8631 1.95083 25.9003 2.14605 25.8817 2.2669C25.8445 2.16464 25.7609 2.0252 25.7051 1.94153C25.5377 1.90435 25.7609 2.12746 25.7051 2.19253C25.6214 2.13675 25.5563 2.09957 25.5192 2.0252C25.5192 2.16464 25.4634 2.23901 25.3053 2.20182C25.3053 2.20182 25.2775 1.98801 25.138 1.91365C25.0915 2.15534 25.2589 2.41564 25.2124 2.67593C25.3053 3.15003 24.6918 2.76889 24.7662 3.11284C24.8312 3.2058 24.9893 3.18721 24.9521 3.30806C24.822 3.12214 24.8127 3.23369 24.7476 3.16862C24.8684 3.49398 24.571 3.2244 24.6546 3.4475C24.6174 3.37313 24.5059 3.35454 24.4222 3.31736C24.2549 3.09425 24.2549 3.31736 24.1247 2.89903C24.2642 3.33595 23.818 3.01988 24.134 3.59624L24.2177 3.62413H23.9946L24.0039 3.63342C23.9202 3.64272 23.9574 3.70779 23.6878 3.54976C23.6785 3.46609 23.725 3.42891 23.7157 3.34524C23.4833 3.2151 23.6971 3.63342 23.6321 3.70779C23.5019 3.54976 23.6692 3.58694 23.4833 3.41032C23.4089 3.42891 23.4554 3.58694 23.4368 3.6799L23.3718 3.58694C23.065 3.50328 23.6785 4.06104 23.3253 3.85653C23.3718 3.90301 23.4089 3.96808 23.4554 4.01456C23.3439 3.95879 23.1208 3.87512 23.1208 3.6892C23.0743 3.72638 23.0836 3.85653 23.1394 3.96808C23.2881 4.06104 23.2416 3.98667 23.3996 4.13541L23.2788 4.38641C23.2788 4.38641 23.223 4.28415 23.2509 4.26556C22.6374 3.99597 23.1115 5.04643 22.3864 4.71177C22.5351 4.83262 22.47 4.85121 22.5258 4.97206C22.405 4.99995 22.312 5.13939 22.154 5.1208L22.0982 4.99995C21.9959 5.28813 21.9866 5.55771 21.81 5.60419C21.8379 5.65067 21.6892 5.46475 21.6892 5.41827C21.7449 5.67856 21.15 5.21376 21.4382 5.61349H21.5032C21.2615 5.71575 21.2708 6.16196 21.1221 6.37577C20.8897 6.18985 21.2151 6.25492 20.9455 6.02252C20.7317 6.05041 20.7503 6.35718 20.5457 6.41295C20.5457 6.36647 20.5179 6.33859 20.5179 6.31999C20.2483 6.3014 20.7224 6.5338 20.5736 6.59888C20.49 6.47803 20.4528 6.45943 20.3691 6.44084L20.4807 6.65465C20.4807 6.65465 20.3319 6.48732 20.3041 6.42225C20.4528 6.70113 20.146 6.68254 20.2948 6.94283C20.239 6.89635 20.0902 6.66395 19.9973 6.58958C19.8764 6.58958 19.9043 6.71043 19.9322 6.83128C19.7556 6.71043 19.6626 6.83128 19.6626 6.7848C19.4767 6.81269 19.7463 6.92424 19.7742 7.13805L19.9508 7.15664L19.83 7.35186L19.8021 7.18453C19.6533 7.16594 19.737 7.42623 19.644 7.5006L19.7928 7.59356L19.7556 7.76089C19.5232 7.50989 19.5697 7.81666 19.3651 7.46341C19.0584 7.4913 19.235 7.94681 19.077 8.11414C19.1049 8.08625 19.0491 8.04907 19.0212 7.99329C18.8725 8.02118 18.9282 8.2071 18.984 8.39302C18.9282 8.30006 18.9282 8.25358 18.8632 8.17921C18.7423 8.28147 18.9189 8.39302 18.8632 8.57894C18.8074 8.4395 18.7423 8.39302 18.6865 8.39302C18.7795 8.48598 18.8074 8.57894 18.8074 8.62542C18.4541 8.02118 18.4727 8.54176 18.1845 8.07695C18.2775 8.1978 18.2682 8.59754 18.5099 8.75557V8.6812C18.6401 8.82064 18.5471 8.81135 18.5099 8.84853C18.5099 8.81135 18.5006 8.75557 18.4727 8.72768C18.4355 9.06234 18.1009 9.07164 18.0079 9.37841C17.98 9.31333 17.98 9.146 17.8871 9.146C17.6175 9.24826 17.729 9.6294 17.6361 9.93617C17.3386 9.61081 17.822 9.69447 17.5524 9.36911C17.3944 9.6387 17.2735 9.94547 17.1806 10.3266C16.6693 9.91758 17.1155 10.7356 16.6321 10.4846C16.7901 10.6334 16.7622 10.7542 16.6879 10.8379C16.5949 10.6799 16.5112 10.7542 16.4462 10.6334C16.502 10.8472 16.3532 11.0889 16.0836 10.7635C16.3346 11.0796 15.9163 10.8844 16.0557 11.154C15.8605 11.1168 15.9163 11.3864 15.7304 11.3957C15.9442 11.5537 15.7025 11.5909 15.7304 11.7024C15.7304 11.6838 15.7304 11.6281 15.7025 11.6095C15.5166 11.47 15.7025 11.8698 15.5537 11.8326C15.4608 11.7861 15.405 11.6467 15.3399 11.6745C15.4608 11.814 15.4329 12.1208 15.2191 12.0092C15.247 11.9813 15.1912 11.9162 15.154 11.8419C15.0704 12.3439 14.494 12.3439 14.4382 12.9016L14.2802 12.6227C13.8247 12.5019 14.494 13.1061 14.3174 13.2177C13.8061 13.478 13.0903 13.5524 12.8207 14.0636C12.8486 14.1566 12.9137 14.1287 13.0066 14.2217C12.9508 14.2217 12.7649 14.045 12.8207 14.2124L12.9415 14.3239C12.4489 14.1659 12.6441 15.0304 12.0212 14.6493C12.0398 15.0025 11.6029 14.7887 11.6866 15.2721C11.5192 15.2349 11.5564 15.0025 11.4449 15.0583V15.4209V15.393C11.6401 15.9043 10.5896 15.4859 10.6547 15.96V15.9321C10.5617 15.8485 10.413 15.8113 10.413 15.8764C10.4595 15.9414 10.5153 15.9414 10.6082 15.9879C10.5803 16.3226 10.5525 16.3691 10.4409 16.555C10.3665 16.3784 10.2736 16.5271 10.0784 16.3877C10.162 16.5271 10.2922 16.5178 10.3201 16.6944C10.2178 16.8525 9.99469 16.8153 9.78088 16.9826C9.89243 17.1964 9.78088 17.2615 9.9668 17.4567C9.80877 17.7821 9.75299 18.0052 9.56707 18.4886L9.51129 18.4049C9.66003 18.879 9.251 18.6094 9.32537 18.9162C9.26959 18.7582 9.2603 18.6559 9.19522 18.5629L9.17663 18.8976C9.15804 18.6652 9.00001 18.2469 8.92564 18.3398C8.99071 18.7953 9.02789 18.4979 9.10226 18.8232L8.91634 18.47C8.88845 18.6187 9.05578 19.1486 9.16733 19.1021C8.99071 19.5483 8.86986 20.3013 8.69323 20.6546L8.62816 20.2362C8.58168 20.5709 8.47013 20.8963 8.37717 20.701C8.37717 20.6732 8.35857 20.6546 8.35857 20.636C8.37717 20.7568 8.37717 20.9706 8.41435 21.1101C8.35858 21.5842 8.31209 20.45 8.25632 20.9706C8.27491 20.8498 8.3028 20.7847 8.27491 20.5523C8.24702 20.6267 8.21913 20.6917 8.19125 20.7568C8.17265 20.7847 8.16336 20.8126 8.14477 20.8405H8.0704C8.03321 20.5802 7.8194 19.8272 7.70785 19.8923C7.70785 20.0224 7.75433 20.2455 7.78222 20.3106L7.69855 20.3292L7.62418 19.7157C7.587 19.8272 7.54982 19.9388 7.51263 20.041V19.6041C7.42897 19.6041 7.38249 20.0968 7.29882 19.9667C7.03853 19.3717 7.1036 19.3066 6.98275 18.7396C6.84331 19.4182 6.71317 18.3863 6.55513 18.8139C6.45288 18.0517 6.01596 17.9215 5.77426 17.4381H5.83004C5.87652 17.0756 5.42101 17.5869 5.34664 17.3173L5.4396 17.2987C5.45819 17.0849 5.32805 16.9175 5.18861 16.8432C5.05846 16.7688 4.87254 16.7409 4.71451 16.7409C4.80747 16.7223 4.92832 16.5922 4.87254 16.555C4.75169 16.5829 4.60295 16.8339 4.62155 16.6851C4.67732 16.6758 4.76099 16.5829 4.7424 16.555L4.46351 16.6387C4.43563 16.2947 4.37985 15.9136 4.07308 15.7834C4.11026 15.6812 4.22182 15.6533 4.29618 15.6068C4.11026 15.4581 3.7849 15.4209 3.61757 15.2814L3.84997 15.0676C3.7849 14.9839 3.43165 15.3186 3.57109 15.0397C3.58968 14.9932 3.64546 15.0955 3.7756 15.0397C3.84068 14.733 3.45954 15.1327 3.36658 14.9561L3.68264 14.7794C3.75701 14.5284 3.43165 14.7608 3.22713 14.8445C2.76233 14.9282 3.68264 14.3053 3.25502 14.2682C3.08769 14.3425 3.0598 14.4355 2.89247 14.5098C2.84599 14.2867 2.62289 14.4262 2.57641 14.2031C2.93896 13.794 2.64148 14.2867 2.96684 13.887V14.0822C3.10628 13.8033 3.09699 14.138 3.32939 13.9242C3.33869 13.7848 3.03192 13.8312 2.87388 13.7848C3.0598 13.6453 2.98544 13.887 3.20854 13.6453H3.08769C3.15277 13.6267 3.22713 13.5709 3.24573 13.6081C3.41306 13.4501 3.20854 13.5338 3.16206 13.4873C3.0598 13.5616 2.92036 13.6639 2.79951 13.7848C2.81811 13.7662 2.8367 13.7476 2.85529 13.7197C2.50204 13.8219 2.57641 13.4873 2.28823 13.5616C2.3533 13.5338 2.3626 13.5059 2.40908 13.4687C2.37189 13.3943 2.07442 13.5152 1.93498 13.4873C2.03723 13.3385 2.38119 13.1991 2.19527 13.1247C2.01864 13.2177 1.78624 13.4873 1.70258 13.3571C1.70258 13.3571 1.90709 13.3571 1.98146 13.227H1.95357ZM4.28689 15.5045C4.28689 15.5045 4.31478 15.5324 4.34266 15.551C4.34266 15.551 4.29618 15.5138 4.28689 15.5045ZM4.61225 15.5696C4.61225 15.5696 4.51929 15.5975 4.45422 15.6533C4.48211 15.6905 4.50999 15.7183 4.51929 15.7555C4.55647 15.6719 4.55647 15.5882 4.61225 15.5696ZM5.46749 14.2403L5.49538 14.2217C5.49538 14.2217 5.55116 14.2496 5.56975 14.2589C5.60693 14.2217 5.63482 14.1752 5.57904 14.1659C5.55116 14.1845 5.50468 14.2031 5.46749 14.231V14.2403Z\" fill=\"#8F3A7E\"><\/path><path d=\"M5.26323 14.3253C5.26323 14.3253 5.24482 14.3253 5.23562 14.3253C5.22642 14.3437 5.21721 14.3621 5.20801 14.3805L5.28164 14.3437L5.26323 14.3253Z\" fill=\"#8F3A7E\"><\/path><path d=\"M21.6523 4.27579C21.6523 4.27579 21.6712 4.27579 21.69 4.29463C21.6806 4.29463 21.6712 4.28521 21.6618 4.27579H21.6523Z\" fill=\"#8F3A7E\"><\/path><path d=\"M7.48508 20.1339L7.49435 20.032L7.46655 20.0876L7.48508 20.1339Z\" fill=\"#8F3A7E\"><\/path><path d=\"M23.4094 3.96896C23.4094 3.96896 23.4473 3.9974 23.4663 4.00688C23.4568 3.9974 23.4284 3.97844 23.4094 3.96896Z\" fill=\"#8F3A7E\"><\/path><path d=\"M24.4309 3.36418C24.4309 3.36418 24.3847 3.29949 24.3662 3.27176L24.4309 3.36418Z\" fill=\"#8F3A7E\"><\/path><path d=\"M19.885 6.80322C19.8943 6.85893 19.9036 6.90536 19.9036 6.95178C19.95 6.9425 19.9779 6.92393 19.885 6.80322Z\" fill=\"#8F3A7E\"><\/path><path d=\"M16.6518 10.8394L16.6318 10.8494L16.6518 10.8394Z\" fill=\"#8F3A7E\"><\/path><path d=\"M19.8203 7.01859C19.885 7.02783 19.9035 7.0001 19.9035 6.95389C19.8665 6.96313 19.8203 6.97237 19.8203 7.01859Z\" fill=\"#8F3A7E\"><\/path><path d=\"M26.1981 2.03489H26.2264C26.2264 2.03489 26.2075 2.00662 26.1981 1.99719V2.03489Z\" fill=\"#8F3A7E\"><\/path><path d=\"M26.1977 1.99845V1.96075C26.1977 1.96075 26.1789 1.9796 26.1977 1.99845Z\" fill=\"#8F3A7E\"><\/path><path d=\"M26.2079 1.8683V1.95148C26.2079 1.95148 26.2449 1.933 26.2079 1.8683Z\" fill=\"#8F3A7E\"><\/path><path d=\"M25.6025 2.37845L25.6578 2.45208C25.6578 2.45208 25.6302 2.40606 25.6025 2.37845Z\" fill=\"#8F3A7E\"><\/path><path d=\"M25.4627 2.52706C25.5183 2.50852 25.6852 2.60121 25.7037 2.51779L25.6574 2.45291C25.7223 2.58267 25.3978 2.37876 25.4627 2.52706Z\" fill=\"#8F3A7E\"><\/path><path d=\"M24.0587 2.18406L24.2354 2.12826C24.1517 2.07245 24.0308 1.98874 24.0773 1.92363C23.7145 1.83062 24.254 2.07245 24.0587 2.18406Z\" fill=\"#8F3A7E\"><\/path><path d=\"M23.5575 2.40555C23.5946 2.31271 23.4646 2.29414 23.4275 2.24771C23.4461 2.35913 23.4461 2.38698 23.5575 2.40555Z\" fill=\"#8F3A7E\"><\/path><path d=\"M20.6004 4.88834L20.4517 4.70251C20.4239 4.77684 20.5075 4.77684 20.6004 4.88834Z\" fill=\"#8F3A7E\"><\/path><path d=\"M20.833 6.30117L20.9817 6.36621L20.8702 6.18039L20.833 6.30117Z\" fill=\"#8F3A7E\"><\/path><path d=\"M19.4009 5.29716L19.4102 5.25073L19.373 5.39001L19.4009 5.29716Z\" fill=\"#8F3A7E\"><\/path><path d=\"M14.5673 9.62069L14.7804 9.8246C14.7804 9.75045 14.5673 9.5002 14.5673 9.62069Z\" fill=\"#8F3A7E\"><\/path><path d=\"M12.6902 11.7309C12.5694 11.6473 12.4486 11.6287 12.5044 11.7681C12.5601 11.7402 12.6902 11.7774 12.6902 11.7309Z\" fill=\"#8F3A7E\"><\/path><path d=\"M7.70828 16.6682L7.6897 16.4824L7.69899 16.659L7.70828 16.6682Z\" fill=\"#8F3A7E\"><\/path><path d=\"M1.70163 9.61194C1.61792 9.63054 1.4691 9.73285 1.52491 9.76076L1.81324 9.63984L1.70163 9.61194Z\" fill=\"#8F3A7E\"><\/path><path d=\"M1.38543 10.1886C1.54327 10.17 1.80325 10.0957 2.02609 9.91004C1.74754 10.0122 1.84039 9.9379 1.50613 10.0586C1.45042 10.0307 1.54327 9.92861 1.64541 9.88219C1.57113 9.90076 1.66398 9.78006 1.47828 9.85433C1.30187 10.0307 1.33901 10.1143 1.55256 10.0865C1.50613 10.1329 1.42257 10.1607 1.37615 10.1886H1.38543Z\" fill=\"#8F3A7E\"><\/path><path d=\"M6.07034 17.5318C6.07034 17.5318 6.02367 17.5318 6.005 17.5598C6.033 17.5598 6.06101 17.5598 6.07034 17.5318Z\" fill=\"#8F3A7E\"><\/path><path d=\"M6.40438 18.461C6.40438 18.461 6.38574 18.4238 6.38574 18.4051C6.38574 18.4517 6.38574 18.4797 6.40438 18.461Z\" fill=\"#8F3A7E\"><\/path><path d=\"M4.03508 14.7249L4.01648 14.8551C4.10019 14.7993 4.04438 14.7714 4.03508 14.7249Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.3788 10.391C2.3788 10.391 2.32335 10.391 2.28638 10.391C2.30486 10.391 2.32335 10.4002 2.33259 10.4095L2.3788 10.3817V10.391Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.96444 13.7376L2.94584 13.719C2.94584 13.719 2.87143 13.7562 2.83423 13.7748L2.96444 13.7376Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.26855 12.8844C2.26855 12.8844 2.49178 12.7635 2.58479 12.7077C2.49178 12.7635 2.43597 12.7728 2.40807 12.7728C2.37087 12.8007 2.32436 12.8379 2.26855 12.8937V12.8844Z\" fill=\"#8F3A7E\"><\/path><path d=\"M3.40322 14.398C3.40322 14.398 3.34722 14.4447 3.33789 14.4634C3.36589 14.4447 3.38456 14.4167 3.40322 14.398Z\" fill=\"#8F3A7E\"><\/path><path d=\"M24.3936 0.882324C24.3936 0.882324 24.4124 0.910594 24.4218 0.920017C24.4124 0.891747 24.403 0.882324 24.3936 0.882324Z\" fill=\"#8F3A7E\"><\/path><path d=\"M26.1963 1.0585V1.08636L26.2891 1.19778L26.1963 1.0585Z\" fill=\"#8F3A7E\"><\/path><path d=\"M7.32639 20.0692C7.32639 20.0692 7.32639 20.0692 7.32639 20.0592C7.29639 20.0692 7.31639 20.0792 7.32639 20.0692Z\" fill=\"#8F3A7E\"><\/path><path d=\"M13.8886 13.0136C13.6561 12.9113 13.8142 12.6788 13.5166 12.5951C13.6003 12.6602 13.684 12.995 13.8886 13.0136Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.37 10.4381C2.37 10.4381 2.38884 10.457 2.39826 10.4758C2.39826 10.457 2.38884 10.4476 2.37 10.4381Z\" fill=\"#8F3A7E\"><\/path><path d=\"M9.13905 18.7775C9.11125 18.7312 9.08346 18.6942 9.05566 18.6756C9.07419 18.7127 9.09272 18.7405 9.13905 18.7775Z\" fill=\"#8F3A7E\"><\/path><path d=\"M7.87305 19.9031L7.91937 20.005C7.90084 19.9494 7.89158 19.9216 7.87305 19.9031Z\" fill=\"#8F3A7E\"><\/path><path d=\"M9.5293 17.1406C9.5293 17.1406 9.59373 17.1407 9.59373 17.0762C9.58452 17.0762 9.57532 17.0762 9.56611 17.067C9.58452 17.1038 9.58452 17.1406 9.5385 17.1406H9.5293Z\" fill=\"#8F3A7E\"><\/path><path d=\"M10.1335 16.3052C10.1335 16.3052 10.0955 16.2957 10.0861 16.2863V16.3147L10.1335 16.3052Z\" fill=\"#8F3A7E\"><\/path><path d=\"M22.2911 2.80592C22.3562 2.85237 22.4119 2.89883 22.477 2.95457C22.3469 2.8245 22.4119 2.68513 22.2911 2.80592Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.25891 10.4761C2.31499 10.448 2.35237 10.4293 2.37106 10.4387L2.34302 10.42C2.34302 10.42 2.2776 10.4574 2.25891 10.4761Z\" fill=\"#8F3A7E\"><\/path><path d=\"M8.05957 15.6353L8.11645 15.6163C8.11645 15.6163 8.06905 15.6163 8.05957 15.6353Z\" fill=\"#8F3A7E\"><\/path><path d=\"M17.1702 7.21375V7.16635C17.1702 7.16635 17.1607 7.18531 17.1702 7.21375Z\" fill=\"#8F3A7E\"><\/path><path d=\"M8.31042 15.2827C8.40334 15.3198 8.45908 15.3198 8.50554 15.3198C8.49625 15.3013 8.48696 15.2827 8.46837 15.2641L8.31042 15.2827Z\" fill=\"#8F3A7E\"><\/path><path d=\"M22.9801 2.12785C22.9986 1.93263 23.0544 2.14644 23.2961 2.2394C23.1753 1.97911 23.4635 2.23011 23.1846 1.86756C23.417 2.07207 23.3333 1.98841 23.5378 2.09996C23.3519 1.93263 23.5099 1.80249 23.3147 1.57938C23.5564 1.81178 23.4635 1.98841 23.7795 2.18363C23.6959 1.96052 23.7516 1.80249 23.5285 1.51431C23.6308 1.5422 23.733 1.62586 23.826 1.58868C23.7981 1.58868 23.826 1.64445 23.8446 1.68164C23.8167 1.38416 24.1607 1.42135 23.9468 1.02161C24.2536 1.44923 24.2629 0.844989 24.4767 1.3005C24.5232 1.24472 24.4581 1.00302 24.4117 0.910061C24.6719 1.22613 24.6069 0.882173 24.8207 1.02161C24.6998 0.8171 24.8486 0.798508 24.8207 0.649771C24.8207 0.705547 24.8579 0.77062 24.9415 0.854285C24.895 0.668363 24.988 0.807804 25.1646 0.910061C25.1646 0.742732 24.9508 0.686955 24.8765 0.491737C25.0159 0.491737 25.0531 0.677659 25.1739 0.798508L25.0252 0.38948C25.0717 0.398776 25.1367 0.445257 25.2204 0.528921C25.1832 0.408072 25.1089 0.240743 25.2855 0.343L25.1925 0.435961L25.3599 0.566106L25.3041 0.268631C25.6666 0.361592 25.899 0.742732 26.1593 1.08669L26.1407 1.19824C26.2337 1.30979 26.3359 1.33768 26.3731 1.31909C26.4661 1.37487 26.5683 1.7746 26.5219 1.87685C26.3081 2.02559 26.1593 1.5236 25.9548 1.55149L25.9362 1.89545L25.8432 1.78389C25.7503 1.72812 25.8432 1.86756 25.8525 1.90474C25.7224 1.72812 25.6666 1.96982 25.5644 2.007L25.7131 2.12785C25.7968 2.63913 25.0903 2.02559 25.081 2.34166L25.1739 2.68561L24.9694 2.4904C25.0066 2.67632 25.1367 2.85294 24.9694 2.86224C24.2815 2.79717 24.2629 3.59663 23.6773 3.6803C23.7144 3.71748 23.7423 3.72678 23.7981 3.73607C23.0172 3.47578 23.7423 4.72146 23.0916 4.55413L23.0451 4.46117C22.9243 4.6285 22.9986 4.35891 22.7848 4.34032C22.9801 4.6192 22.7662 4.70287 22.7569 4.87949C22.7291 4.81442 22.7569 4.79583 22.7569 4.73075C22.6919 4.68427 22.5524 4.53554 22.5524 4.6192C22.7755 5.07471 22.5338 5.21415 22.4688 5.45585C22.3014 5.29782 22.0411 5.26063 21.7437 5.03752C21.7809 5.11189 21.8645 5.26993 21.9482 5.41866C21.7995 5.35359 21.8273 5.47444 21.8738 5.61388C21.9203 5.5674 21.9575 5.53022 21.9854 5.49303V5.51163C21.9854 5.51163 21.9947 5.48374 22.004 5.47444C22.0319 5.43726 22.0412 5.40937 22.0226 5.40937C22.2271 5.52092 22.1341 5.54881 22.3014 5.74403C22.2457 5.78121 22.1992 5.93925 22.0597 5.7998C22.0226 5.8184 21.9854 5.8184 21.9296 5.8184C21.9296 5.86488 21.9296 5.90206 21.8924 5.90206V5.87417C21.8924 5.87417 21.8366 5.83699 21.818 5.8184C21.6507 5.8184 21.7623 6.23672 21.7995 6.44123C21.6693 6.12517 21.5392 6.17165 21.3811 5.99502C21.3811 6.01361 21.4927 5.93925 21.6228 5.83699C21.5949 5.82769 21.5578 5.7998 21.502 5.73473C21.2324 5.63247 21.4648 6.06009 21.1859 6.06009C21.1859 6.03221 21.1673 5.97643 21.1022 5.91136C21 5.91136 21.0744 6.09728 21.158 6.21813C20.9907 6.0508 20.7676 6.02291 20.7676 6.15306C20.842 6.34827 20.907 6.40405 20.7955 6.46912L20.7304 6.31109C20.5259 6.30179 20.7955 6.57138 20.6188 6.55279C20.7025 6.57138 20.591 6.44123 20.5445 6.43194C20.4887 6.59927 20.5445 6.67364 20.6746 6.9897L20.5259 6.77589C20.5259 6.98041 20.5445 7.38014 20.3214 7.11055C20.7025 7.49169 20.2935 7.51028 20.2005 7.57536C20.2191 7.53817 20.154 7.44521 20.1169 7.39873C20.1726 7.82635 19.7636 7.7148 19.587 7.88213L19.2988 7.61254C19.2151 7.7055 19.6892 8.31904 19.5777 8.39341L19.494 8.21679C19.3546 8.4213 19.2523 8.45849 19.0664 8.54215L18.8991 8.33764C18.927 8.47708 18.8619 8.53285 18.8898 8.6723C18.3506 8.29116 18.6295 9.34161 17.9416 8.99766L18.2483 9.3788C18.1554 9.44387 18.1089 9.6112 17.83 9.3788H17.8579C17.6162 9.08132 17.7649 9.43458 17.6627 9.41598C17.6534 9.48106 17.7742 9.70416 17.8579 9.72275C17.4675 9.72275 17.3094 10.2154 16.8725 10.0109C16.7517 10.327 16.8446 10.7732 16.5658 10.9498L16.5286 10.9034C16.4077 10.9219 16.1474 10.9684 15.8778 10.6617C15.7663 10.8848 16.0359 11.4053 15.7012 11.4518L15.6454 11.2938C15.5432 11.2845 15.5897 11.4983 15.599 11.5541C15.5711 11.5634 15.5339 11.489 15.4967 11.4425C15.3573 11.3868 15.4688 11.5727 15.4595 11.6377L15.3851 11.5169C15.0319 11.4518 15.1435 12.1026 14.8925 12.242C14.9018 12.1769 14.7809 12.084 14.7158 12.0468C14.9389 12.4651 14.6229 12.5952 14.6136 12.7533L14.5485 12.5767C14.5764 12.9578 14.0744 12.3535 14.1116 12.7347L14.3812 12.8369C14.2603 12.8369 14.2603 12.9578 14.4184 13.0972C14.2324 13.0601 14.1767 12.8462 14.0186 12.9299C13.9257 12.8369 14.0465 12.7812 13.8978 12.6975L13.498 12.6045C13.498 12.6045 13.4423 12.5952 13.4144 12.6696C13.8141 13.0786 13.2935 12.8184 13.7583 13.153C13.5538 13.404 13.0983 13.311 13.0704 13.6922C12.6149 13.3668 12.6521 14.0547 12.1873 13.5156C12.0664 13.6178 12.0757 13.813 12.2059 14.0826C12.271 14.1012 12.2338 14.0083 12.2338 13.9618C12.3267 14.1198 12.2152 14.2685 12.1594 14.3243C12.1222 14.1384 12.1501 13.9246 12.02 13.6736C11.9642 13.8223 12.0014 14.1477 12.0107 14.2685L11.7318 14.0268C11.834 14.3057 11.4529 13.8781 11.6202 14.2221L11.7132 14.2871C11.5366 14.4173 11.7876 14.6869 11.6853 14.8542L11.5923 14.7426C11.4994 14.7426 11.676 15.068 11.3878 14.8821L11.4715 14.7798C11.2856 14.6032 11.1275 14.6032 11.0067 14.5381C10.9509 14.6869 11.267 14.8635 11.2484 14.9379C11.0532 14.7891 11.1554 14.8542 11.016 14.6497C10.9602 14.817 10.8951 15.0401 11.0439 15.3376C11.016 15.319 10.9788 15.2725 10.9788 15.2725C10.8394 15.3562 11.0625 15.7559 10.8487 15.6908V15.6444C10.4954 15.5049 10.8765 16.1092 10.4024 15.728C10.2816 15.7001 10.514 15.6444 10.2258 15.5142C9.95623 15.5328 10.5233 15.9418 10.2909 15.9511C10.3188 15.9511 10.2909 15.9325 10.2537 15.8861C10.1886 15.9883 10.1329 16.1464 10.0957 16.2858C9.60298 16.1185 9.90046 16.732 9.3148 16.574C9.51002 16.639 9.46354 16.7692 9.52861 16.8343C9.52861 16.8343 9.49143 16.7878 9.46354 16.7785C9.39847 16.8343 9.53791 16.983 9.58439 17.0667C9.41706 17.0016 9.58439 17.4385 9.46354 17.4013C9.54721 17.5036 9.48213 17.5501 9.43565 17.6244C9.43565 17.3455 9.28692 17.3363 9.18466 17.1131C9.02663 17.234 9.40776 17.8661 9.21255 18.0613C9.13818 18.0242 9.07311 17.987 8.99874 17.9405C9.20325 18.3867 8.99874 18.4983 9.07311 18.6656C8.98944 18.5726 8.92437 18.554 8.82211 18.303C8.82211 18.5354 8.65478 18.4239 8.74774 18.7957L8.8407 18.8236C8.72915 18.9073 8.71985 19.1955 8.70126 19.4929C8.68267 19.7811 8.65478 20.06 8.55253 19.9856L8.33872 18.9445C8.19927 18.647 8.33872 19.8462 8.17139 19.2977C8.24575 19.6417 8.23646 19.5022 8.25505 20.0042C8.29223 20.0135 8.28294 19.5952 8.32942 19.4929L8.34801 20.404L8.44097 19.6882C8.45956 20.2738 8.44097 20.1716 8.55253 20.5341C8.52464 21.0547 8.40379 20.5713 8.35731 20.7386C8.34801 20.7386 8.32942 20.7758 8.32012 20.8502C8.25505 20.6828 8.23646 20.2831 8.17139 20.06C8.12491 20.4411 7.94828 19.4093 7.9018 19.7718C7.86461 19.6417 7.94828 19.7997 7.92039 19.5673C7.85532 19.5673 7.80884 19.4744 7.79954 19.7253L7.87391 19.902C7.81813 19.809 7.82743 20.1716 7.69728 19.8276C7.64151 19.9577 7.60432 20.3296 7.68799 20.4318C7.6601 20.4504 7.57644 20.1344 7.60432 19.902C7.4277 19.6789 7.51136 20.6921 7.32544 20.0693C7.34403 20.0693 7.35333 20.0321 7.35333 19.9763C7.30685 19.8648 7.26967 19.8183 7.23248 19.8276C7.39981 19.9485 7.22318 19.1304 7.39051 19.4929C7.39051 19.0374 7.26037 19.2512 7.21389 19.0188C7.10234 19.1955 7.15811 19.5952 7.09304 19.7439C7.10234 19.6138 7.06515 19.5673 7.02797 19.4651L7.04656 19.8183C7.00008 19.7718 6.96289 19.716 6.90712 19.7253L7.00937 19.7068C6.91641 19.5394 6.86993 18.9352 6.67472 19.0281C6.73979 18.9631 6.85134 18.8236 6.79556 18.5726C6.60964 18.5726 6.78627 18.4146 6.75838 18.1264C6.60964 18.0242 6.60964 18.5633 6.44231 18.1543C6.42372 18.1264 6.38654 18.2937 6.38654 18.3867C6.28428 18.0892 6.12625 18.145 6.06117 17.8196C6.08906 17.9498 6.10765 18.0892 5.96821 18.0799C6.09836 17.9498 5.93103 17.7732 5.94032 17.6058L5.86596 17.6895C5.89384 17.5315 5.96821 17.5501 6.02399 17.5501C6.0054 17.5779 5.9961 17.6244 6.02399 17.6523C6.14484 17.6523 6.33076 17.2247 6.27498 17.0853C6.12625 17.0667 5.95892 17.327 5.91244 17.4478C5.83807 17.1782 5.44763 17.6802 5.40115 17.3548C5.36397 17.3084 5.55918 16.8529 5.50341 16.7134C5.25241 16.8064 5.48482 16.9923 5.27101 17.0667C5.56848 16.4345 4.68535 16.9551 4.78761 16.481L5.0479 16.3137C5.02001 16.2486 5.00142 16.1928 4.92705 16.1556L4.85268 16.3323C4.75972 16.3323 4.71324 16.1742 4.92705 16.0627C4.63887 16.1092 4.74113 15.9883 4.71324 15.8396C4.77831 15.9697 4.68535 15.8675 4.87127 15.8489C4.89916 15.6351 4.8062 15.6908 4.69465 15.6537C4.78761 15.5979 4.88987 15.4491 4.86198 15.4213C4.64817 15.4677 4.5738 15.3097 4.41577 15.2725L4.49013 15.2167C4.25773 15.1145 4.44365 14.6497 4.0904 14.6404C4.0904 14.6404 4.08111 14.6404 4.07181 14.6404V14.6683C3.88589 14.91 3.79293 14.6497 3.66278 14.6683C3.70926 14.6125 3.81152 14.5288 3.78363 14.4916C3.56982 14.659 3.6163 14.5102 3.49545 14.5567C3.52334 14.4359 3.76504 14.3615 3.67208 14.2685C3.6256 14.2407 3.50475 14.3243 3.42108 14.3894C3.51404 14.2778 3.55123 14.1477 3.53264 14.0733C3.60701 14.0454 3.55123 14.1384 3.57912 14.1384C3.69997 14.0547 3.6256 14.0547 3.77434 13.9432C3.75574 13.8781 3.55123 14.0826 3.57912 13.9618L3.79293 13.8874C3.82082 13.8316 3.71856 13.8502 3.69997 13.8502C3.77434 13.8502 3.94166 13.7201 4.04392 13.6364C3.81152 13.5899 3.56053 13.9618 3.36531 14.1012C3.3932 13.8595 3.08642 13.9246 2.99346 13.8223L3.21657 13.6922C3.1422 13.6643 3.07713 13.6736 2.97487 13.7201L2.9098 13.6364C3.02135 13.6364 3.09572 13.5992 3.26305 13.4784C3.1422 13.4319 3.10502 13.2832 2.81684 13.4598L2.86332 13.4319C2.87261 13.246 2.75177 12.9578 2.85402 12.902C2.6681 12.8462 2.71458 12.5674 2.4357 12.7626C2.31485 12.7347 2.64951 12.3164 2.26837 12.5116C2.38922 12.2885 2.34274 12.4558 2.56584 12.335C2.68669 12.1211 2.15682 12.3628 2.52866 12.0468C2.33344 12.0282 2.46359 12.1304 2.25907 12.2234C2.61232 11.9352 2.1847 11.991 2.32415 11.74C2.14752 11.8051 2.25907 11.8516 2.05456 11.8887C2.15682 11.833 2.13822 11.7772 2.13822 11.7493L1.89653 11.8887L2.39851 11.3868C2.01737 11.4332 2.01737 11.6935 1.77568 11.5727H1.80356C2.00808 11.3496 1.52468 11.5541 1.60835 11.2845C1.59905 11.3682 1.73849 11.2287 1.81286 11.2008L1.66412 11.1822C1.66412 11.1822 1.70131 11.1822 1.7199 11.1451C1.85005 10.9591 1.58046 11.1451 1.68272 10.9591C1.76638 10.987 1.93371 10.8476 2.00808 10.7639L1.66412 10.8197L2.01737 10.6524C1.97089 10.5222 1.33876 10.6803 1.75708 10.3363L1.84075 10.3642C1.91512 10.3084 2.13822 10.1318 1.92441 10.1597C1.86864 10.1597 1.66412 10.2619 1.70131 10.2898L1.73849 10.1876C1.97089 10.0853 2.11963 10.1876 2.23118 10.234C2.12893 10.2619 2.01737 10.234 1.89653 10.3456C2.01737 10.3828 2.2033 10.3642 2.32415 10.3921C2.22189 10.42 2.07315 10.485 1.98019 10.5222C1.92441 10.6803 2.16611 10.4943 2.23118 10.5408C2.16611 10.6245 2.11963 10.671 2.03597 10.6988C2.17541 10.7267 2.24048 10.7732 2.1847 10.9312C2.1847 10.9312 1.97089 10.9312 1.87793 11.0707C2.11034 11.1451 2.37992 11.0056 2.64021 11.0707C3.12361 11.0149 2.68669 11.5913 3.03065 11.5448C3.12361 11.489 3.12361 11.331 3.24446 11.3775C3.04924 11.4983 3.16079 11.5169 3.09572 11.5727C3.43038 11.4704 3.13291 11.7493 3.36531 11.6842C3.29094 11.7121 3.25375 11.8237 3.21657 11.898C2.98417 12.0561 3.19798 12.0654 2.77965 12.1676C3.22587 12.0561 2.87261 12.4837 3.47686 12.1955L3.51404 12.1118V12.3257V12.3164C3.51404 12.4 3.58841 12.3721 3.41179 12.6231C3.32812 12.6231 3.29094 12.5767 3.20727 12.5859C3.06783 12.8091 3.48616 12.6138 3.56053 12.6882C3.3932 12.8091 3.43968 12.6417 3.25375 12.8184C3.27235 12.8927 3.43038 12.8555 3.51404 12.8741L3.42108 12.9299C3.32812 13.2274 3.90448 12.651 3.68137 12.9857C3.72785 12.9392 3.80222 12.9113 3.8487 12.8648C3.78363 12.9764 3.69067 13.1902 3.50475 13.1809C3.54193 13.2274 3.66278 13.2274 3.78363 13.1809C3.88589 13.0415 3.81152 13.0786 3.96955 12.9299L4.22055 13.0601C4.22055 13.0601 4.11829 13.1065 4.0997 13.0786C3.80222 13.6829 4.87127 13.246 4.49943 13.9525C4.62028 13.813 4.64817 13.8688 4.75972 13.8223C4.77831 13.9432 4.91775 14.0454 4.88987 14.1942L4.76902 14.2499C5.0479 14.3615 5.31749 14.3801 5.36397 14.5567C5.41045 14.5288 5.22453 14.6683 5.16875 14.6683C5.42904 14.6218 4.94564 15.1981 5.35467 14.9193V14.8542C5.44763 15.1052 5.89384 15.0959 6.10765 15.2632C5.91244 15.4956 5.9868 15.1703 5.7544 15.4306C5.77299 15.6444 6.08906 15.6258 6.12625 15.8396C6.07977 15.8396 6.05188 15.8675 6.03328 15.8675C6.0054 16.1371 6.2471 15.663 6.32146 15.821C6.20061 15.9047 6.18202 15.9325 6.15413 16.0255L6.36794 15.9139C6.36794 15.9139 6.20061 16.0627 6.13554 16.0906C6.41442 15.9418 6.36794 16.2114 6.59105 16.0348C6.54457 16.0999 6.34006 16.2765 6.27498 16.3695C6.27498 16.4996 6.37724 16.4531 6.4795 16.3973C6.38654 16.6019 6.48879 16.6855 6.45161 16.6948C6.48879 16.89 6.56316 16.574 6.7212 16.481L6.73979 16.2951L6.86993 16.3509L6.75838 16.4438C6.74908 16.6112 6.92571 16.4252 6.96289 16.481L7.01867 16.2765C7.01867 16.2765 7.08374 16.2393 7.11163 16.2207C6.97219 16.6019 7.14882 16.388 6.96289 16.7971C7.03726 17.1596 7.24178 16.7041 7.32544 16.7506C7.30685 16.732 7.30685 16.8343 7.28826 16.9086C7.33474 17.0853 7.39981 16.8807 7.43699 16.6483C7.4184 16.7971 7.40911 16.8436 7.39051 16.9644C7.45559 17.0481 7.44629 16.7227 7.51136 16.6297C7.49277 16.8343 7.49277 16.9551 7.51136 17.0295C7.51136 16.8343 7.52996 16.7041 7.53925 16.6669C7.48347 17.6802 7.62292 17.2061 7.60432 18.0428C7.61362 17.8289 7.71588 17.4757 7.6508 16.9644V17.0295C7.62292 16.7134 7.6508 16.8621 7.6601 16.8529C7.6601 16.8993 7.6508 16.9551 7.6601 17.0202C7.68799 16.89 7.72517 16.9365 7.74377 16.9179C7.76236 16.8622 7.78095 16.8343 7.79025 16.7506C7.79025 16.7041 7.79954 16.6483 7.79954 16.574C7.81813 16.6948 7.82743 16.9458 7.85532 17.0016C7.94828 17.0016 7.88321 16.3695 7.85532 16.0627C8.03194 16.6205 7.82743 16.2579 7.96687 16.8436C8.01335 16.5368 8.03194 16.1928 7.96687 15.8582C8.15279 16.1649 8.1435 16.0534 8.11561 15.9418C8.08772 15.821 8.04124 15.7187 8.23646 15.8768C8.08772 15.7094 8.05983 15.6165 8.06913 15.5793C8.18998 15.7187 8.21787 15.6815 8.30153 15.7745C8.24575 15.6815 8.20857 15.6072 8.23646 15.5793C8.25505 15.57 8.39449 15.5142 8.55253 15.663C8.23646 15.3934 8.70126 15.4956 8.52464 15.2539C8.72915 15.2446 8.62689 14.975 8.83141 14.9286C8.59901 14.8077 8.8407 14.7241 8.79422 14.6125C8.79422 14.6404 8.79422 14.6869 8.83141 14.7055C9.02663 14.8077 8.80352 14.4359 8.97085 14.4545C9.06381 14.4824 9.13818 14.6218 9.20325 14.5846C9.06381 14.4638 9.07311 14.1384 9.29621 14.2221C9.26832 14.2499 9.3334 14.315 9.37058 14.3801C9.42636 13.8502 10.0213 13.7851 10.0585 13.2274L10.2165 13.497C10.6813 13.5899 9.98412 13.0136 10.17 12.8927C10.6906 12.5952 11.425 12.5209 11.6853 12.0003C11.6574 11.9073 11.5923 11.9352 11.4994 11.8423C11.5645 11.8423 11.7411 12.0189 11.6853 11.8516L11.5645 11.74C12.0479 11.898 11.8898 11.0242 12.5034 11.4146C12.5034 11.0614 12.931 11.2752 12.8752 10.7918C13.0425 10.8383 12.9868 11.0707 13.1076 11.0242L13.1355 10.6524V10.6803C13.0054 10.1411 14.0186 10.6245 14.0279 10.1504V10.1783C14.1023 10.2712 14.251 10.327 14.2603 10.2619C14.2231 10.1876 14.1674 10.1783 14.0744 10.1318C14.1581 9.79712 14.2045 9.74135 14.3533 9.56472C14.3905 9.75994 14.5206 9.6112 14.6879 9.78783C14.6322 9.62979 14.502 9.62979 14.5113 9.44387C14.6415 9.29513 14.911 9.33232 15.0784 9.29513C14.9854 9.09062 15.0877 9.08132 14.9203 8.88611C15.0691 8.72807 15.097 8.57004 15.2922 8.40271L15.3573 8.46778C15.1992 8.1796 15.6361 8.43989 15.5525 8.26327C15.6268 8.35623 15.6361 8.41201 15.7012 8.46778L15.7198 8.30975C15.7384 8.4213 15.9243 8.6723 16.0173 8.63511C15.9429 8.39341 15.8964 8.53285 15.8035 8.36552L16.0266 8.57004C16.0638 8.49567 15.85 8.22608 15.7198 8.21679C15.9243 8.04016 16.0266 7.76128 16.2311 7.64043L16.3426 7.80776C16.3891 7.66832 16.5286 7.54747 16.6959 7.63113C16.6587 7.58465 16.6122 7.4824 16.5565 7.44521C16.5007 7.13844 16.7796 7.67761 16.7238 7.35225C16.7424 7.43592 16.7238 7.50099 16.7982 7.59395L16.8818 7.20351C16.9841 7.31507 17.3466 7.43592 17.3559 7.24999C17.3094 7.18492 17.2072 7.12914 17.17 7.13844L17.1886 7.02689L17.4675 7.2407L17.3652 6.93393L17.5511 7.14774C17.579 7.04548 17.3745 6.73871 17.4396 6.71082C17.7742 6.66434 17.7928 6.77589 18.1182 6.85026C17.7742 6.42264 18.3692 6.66434 18.1554 6.32968C18.6202 6.46912 18.7503 6.03221 19.0943 5.89277V5.94854C19.3825 6.0415 18.9641 5.52092 19.1594 5.50233L19.178 5.58599C19.5219 5.67896 19.6242 5.24204 19.6242 4.93527C19.6428 5.01893 19.7729 5.13978 19.8101 5.0933C19.7822 4.98175 19.5219 4.83301 19.6706 4.84231C19.6799 4.89808 19.7822 4.98175 19.8008 4.96316L19.7078 4.68427C20.0425 4.64709 20.4236 4.58202 20.5445 4.26595C20.6467 4.30313 20.6839 4.40539 20.7304 4.48906C20.8698 4.29384 20.8977 3.96847 21.0279 3.80115L21.251 4.03355C21.3254 3.96847 20.9907 3.62452 21.2696 3.75466C21.3161 3.76396 21.2138 3.82903 21.2696 3.95918C21.5856 4.00566 21.1673 3.64311 21.3346 3.54085L21.5299 3.84763C21.7809 3.9127 21.5392 3.59663 21.4462 3.39212C21.3346 2.93661 22.004 3.81974 22.0226 3.39212C21.9482 3.22479 21.8459 3.2062 21.7623 3.03887C21.9761 2.98309 21.8366 2.76928 22.0504 2.7135C22.4781 3.04816 21.9668 2.77858 22.3851 3.08535H22.1899C22.4688 3.22479 22.1434 3.22479 22.3665 3.45719C22.506 3.45719 22.4502 3.15971 22.4781 2.99239C22.6361 3.17831 22.3758 3.11323 22.6361 3.31775V3.1969C22.6547 3.26197 22.7105 3.33634 22.6733 3.35493C22.8313 3.51297 22.7384 3.31775 22.7848 3.27127C22.7105 3.16901 22.5896 3.03887 22.4688 2.92731C22.4874 2.9459 22.506 2.9645 22.5338 2.98309C22.413 2.63913 22.7477 2.69491 22.664 2.41603C22.6919 2.4811 22.7198 2.4904 22.7569 2.52758C22.822 2.4904 22.6826 2.19292 22.7105 2.05348C22.8685 2.15574 23.0265 2.4811 23.0916 2.29518C22.9894 2.12785 22.7105 1.91404 22.822 1.82108C22.822 1.82108 22.822 2.02559 22.9708 2.09066L22.9801 2.12785ZM20.8327 4.54483C20.8327 4.54483 20.8048 4.57272 20.7862 4.60061C20.7862 4.60061 20.8141 4.55413 20.8234 4.54483H20.8327ZM20.7769 4.8702C20.7769 4.8702 20.749 4.77723 20.6839 4.71216C20.6467 4.74005 20.6188 4.76794 20.5817 4.78653C20.6653 4.81442 20.749 4.81442 20.7769 4.8702ZM22.1341 5.67896L22.1527 5.70684C22.1527 5.70684 22.1248 5.76262 22.1155 5.78121C22.1527 5.8184 22.1992 5.84628 22.2085 5.79051C22.1899 5.76262 22.162 5.71614 22.1341 5.67896Z\" fill=\"#8F3A7E\"><\/path><path d=\"M22.0416 5.47307C22.0416 5.47307 22.0416 5.45466 22.0416 5.44546C22.0231 5.43626 22.0047 5.42705 21.9863 5.41785L22.0231 5.49148L22.0416 5.47307Z\" fill=\"#8F3A7E\"><\/path><path d=\"M4.04395 14.6689C4.04395 14.6689 4.05317 14.6597 4.06239 14.6413C4.06239 14.6505 4.05317 14.6597 4.04395 14.6689Z\" fill=\"#8F3A7E\"><\/path><path d=\"M17.3184 6.90505L17.365 6.96105L17.3464 6.89572L17.3184 6.90505Z\" fill=\"#8F3A7E\"><\/path><path d=\"M3.82129 12.9043C3.82129 12.9043 3.84973 12.8664 3.85921 12.8474C3.84973 12.8569 3.83077 12.8759 3.82129 12.9043Z\" fill=\"#8F3A7E\"><\/path><path d=\"M3.47742 12.3441L3.49602 12.2139C3.47742 12.279 3.47742 12.3162 3.47742 12.3441Z\" fill=\"#8F3A7E\"><\/path><path d=\"M3.28078 11.8598C3.28078 11.8598 3.21608 11.8967 3.18835 11.9152L3.28078 11.8598Z\" fill=\"#8F3A7E\"><\/path><path d=\"M6.45996 16.4436C6.45996 16.4436 6.54407 16.3969 6.57211 16.3875C6.57211 16.3408 6.55342 16.3221 6.45996 16.4436Z\" fill=\"#8F3A7E\"><\/path><path d=\"M6.62872 16.4611C6.62872 16.3873 6.6195 16.3781 6.57336 16.3873C6.57336 16.4242 6.58259 16.4703 6.62872 16.4611Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.17539 10.0107V9.98242C2.17539 9.98242 2.14712 10.0013 2.1377 10.0013H2.17539V10.0107Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.12949 10.0114H2.0918C2.0918 10.0114 2.10122 10.0208 2.12949 10.0114Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.00806 9.99291H2.09124C2.09124 9.99291 2.07275 9.96519 2.00806 9.99291Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.41699 10.6243L2.50017 10.5781C2.50017 10.5781 2.45396 10.5966 2.41699 10.6243Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.55659 10.7733C2.55659 10.7177 2.65855 10.5601 2.57513 10.5416L2.51025 10.5787C2.64001 10.5231 2.39903 10.8289 2.55659 10.7733Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.07381 12.1401L2.0366 11.9541C1.97149 12.0378 1.88778 12.1494 1.82268 12.0936C1.70176 12.4471 1.9808 11.9262 2.08311 12.1401H2.07381Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.27776 12.6685C2.18469 12.622 2.15677 12.7523 2.11023 12.7895C2.22192 12.7895 2.24984 12.7895 2.27776 12.6685Z\" fill=\"#8F3A7E\"><\/path><path d=\"M4.62895 15.747L4.43384 15.8864C4.50817 15.9235 4.50817 15.8306 4.62895 15.747Z\" fill=\"#8F3A7E\"><\/path><path d=\"M6.05145 15.5506L6.11649 15.4112L5.93066 15.5134L6.05145 15.5506Z\" fill=\"#8F3A7E\"><\/path><path d=\"M5.00248 16.9545H4.95605C5.00248 16.9638 5.0489 16.973 5.10461 17.0009C5.05819 16.973 5.03962 16.973 5.00248 16.9545Z\" fill=\"#8F3A7E\"><\/path><path d=\"M10.2145 16.5729L9.97351 16.4061C9.98278 16.471 10.2423 16.6842 10.2145 16.5729Z\" fill=\"#8F3A7E\"><\/path><path d=\"M11.8059 14.4079C11.9267 14.4915 12.0475 14.5101 11.9824 14.3708C11.9267 14.3986 11.7966 14.3615 11.8059 14.4079Z\" fill=\"#8F3A7E\"><\/path><path d=\"M18.3037 9.16579L18.3223 9.2774L18.3502 9.14719L18.3037 9.16579Z\" fill=\"#8F3A7E\"><\/path><path d=\"M1.64564 9.73384C1.52494 9.65027 1.46923 9.91025 1.50637 9.71527C1.6085 9.67813 1.69207 9.65956 1.64564 9.73384Z\" fill=\"#8F3A7E\"><\/path><path d=\"M25.5929 1.03314C25.7137 1.86049 24.812 1.67457 24.7376 2.32529C24.7097 2.38107 24.4959 2.01852 24.4587 2.16726C24.4587 2.88306 23.6872 3.09687 22.9807 3.13405L22.9342 3.0318C22.804 3.0318 22.9342 3.40364 22.8133 3.44083C22.7669 3.38505 22.7761 3.33857 22.6925 3.28279C22.8133 3.46871 22.5995 3.4966 22.6646 3.64534C22.5716 3.60815 22.4694 3.46871 22.3578 3.43153L22.4694 3.66393C22.7111 4.23099 22.1068 3.91493 22.1161 4.30536C22.0882 4.24959 22.0789 4.2031 22.0232 4.17522C21.9488 4.70509 21.5305 4.97468 21.2795 5.36512C21.233 5.29075 21.14 5.15131 21.0564 5.09553C21.2051 5.30934 21.1493 5.44878 21.0936 5.56963C20.8797 5.393 21.0936 5.8857 20.8983 5.8671L20.8704 5.81133C20.9727 6.09021 20.6473 5.78344 20.8054 6.09951L20.6195 5.97866C20.8333 6.29472 20.3778 5.92288 20.4428 6.1274L20.4986 6.18317C20.4986 6.30402 20.3406 6.18317 20.3313 6.28543L20.2941 6.25754C20.229 6.44346 20.0152 6.3505 20.2104 6.57361C20.0059 6.43417 20.2662 6.37839 19.9687 6.18317C19.7363 6.78742 19.2436 7.12208 18.816 7.50322C18.6859 7.45674 18.6301 7.45674 18.5464 7.38237C18.5464 7.46603 18.4163 7.56829 18.4814 7.71703C18.4906 7.69843 18.3512 7.62407 18.3233 7.63336C18.1746 7.61477 18.4535 7.95872 18.2768 7.93084C18.2582 7.83788 18.2118 7.75421 18.1281 7.67984C18.2025 7.92154 18.0816 7.97732 18.0444 8.10746C18.0258 8.06098 18.0258 8.0145 17.9608 7.94943C18.0351 8.22831 17.747 8.06098 17.7749 8.2562L17.6912 8.09817C17.4216 8.06098 17.8864 8.40494 17.6912 8.41423C17.6912 8.34916 17.6261 8.30268 17.5889 8.2469C17.6819 8.58156 17.4402 8.65593 17.403 8.82326C17.403 8.79537 17.3658 8.76749 17.3658 8.76749C17.2729 8.89763 17.0869 8.93481 17.0498 9.14862C16.9475 9.13003 16.7895 8.82326 16.7058 8.98129C16.9382 9.23229 16.585 9.27877 16.9196 9.50188C16.7802 9.54836 16.5199 9.60413 16.5292 9.75287C16.492 9.61343 16.1945 9.48328 16.2689 9.38103L16.0644 9.28807C15.9807 9.17651 16.1666 9.26018 16.0272 9.14862C15.99 9.19511 15.9528 9.41821 15.8784 9.40891C15.9342 9.64132 16.1201 10.0039 16.0179 10.1526C15.99 9.99457 15.7297 9.90161 15.7297 9.81794L15.9807 10.478C15.9435 10.5337 15.7855 10.2827 15.7855 10.4036C15.8506 10.4687 15.8599 10.5337 15.8877 10.6081C15.8413 10.5895 15.7669 10.8312 15.5159 10.6081C15.4043 10.5244 15.5438 10.4873 15.4136 10.4408C15.3393 10.5151 15.4136 10.6081 15.33 10.6825L15.3021 10.6546C15.2184 10.6639 15.237 10.9056 15.4229 10.9892C15.4694 10.9614 15.2742 10.8498 15.3951 10.8777C15.488 11.0543 15.4322 11.1845 15.3579 11.2588C15.3579 11.1938 15.2835 11.1287 15.2277 11.045C15.3021 11.3425 15.237 11.5098 15.1905 11.6958C15.2928 11.8166 15.0418 11.4355 15.1162 11.4819C14.8094 11.4541 15.0139 12.0118 14.6607 11.8817C14.6607 11.8445 14.828 12.0397 14.7908 12.0118C14.7071 12.0676 14.5491 11.891 14.5584 11.9932C14.4654 11.891 14.5305 12.0769 14.5026 12.1606C14.5398 12.2535 14.4469 12.1234 14.4747 12.0676C14.4747 12.2163 14.3446 12.6254 14.0564 12.6254C14.1215 12.6904 14.1866 12.96 14.1401 12.9879L14.0099 12.8206C13.8891 12.7555 13.8984 12.9507 13.7682 12.8206C13.8612 13.0809 13.9263 12.3837 13.9542 12.6254C13.8054 12.5231 14.0378 13.0065 13.8612 12.7741C13.7961 12.8485 13.8798 13.0902 13.6753 13.0065C13.7218 13.0065 13.5358 12.7369 13.4894 12.802C13.4057 12.9228 13.5265 12.9042 13.4894 13.0344V13.1459C13.6288 13.304 13.3871 13.211 13.5823 13.3412C13.4522 13.2296 13.4986 13.555 13.2755 13.2947L13.1082 13.0809C13.0803 13.1366 13.2291 13.3598 13.2755 13.4806C13.257 13.4713 13.2012 13.4341 13.1733 13.4062C13.4429 13.713 13.0431 13.4806 13.2105 13.7688C13.0153 13.7502 12.9595 13.9826 12.7364 13.8339C12.7457 13.9919 12.7829 14.1592 12.6434 14.1778C12.6341 14.1313 12.6434 14.1034 12.5876 14.0384C12.4575 14.0012 12.5133 14.0848 12.5133 14.1778C12.4854 14.122 12.2437 14.1034 12.0856 14.0477C12.1042 14.2057 12.2809 14.3451 12.3645 14.4474C12.0206 14.215 12.3459 14.8285 12.0113 14.6333C11.9927 14.5682 11.9741 14.3916 11.8439 14.373C11.5 14.1406 11.9276 14.717 11.6859 14.6705L11.9462 14.8843C11.751 14.7821 11.9369 15.1725 11.7045 14.9122C11.7603 15.033 11.5093 14.9494 11.751 15.1725C11.3884 15.1446 11.4814 15.6838 10.9608 15.3863C10.9794 15.4514 10.8772 15.47 11.0166 15.5722C11.1839 15.6559 10.9701 15.4235 11.0817 15.4979C11.0724 15.5257 11.1281 15.5908 11.1653 15.628C11.0631 15.628 11.0073 15.6559 10.8493 15.4142C10.589 15.3956 11.1467 15.9162 10.9236 15.972C10.8307 15.8697 10.7749 15.8511 10.7563 15.9069L10.8586 16.1393C10.7377 16.1951 10.5797 15.9905 10.3938 15.8418C10.3752 15.9162 10.3101 15.9812 10.4309 16.1114L10.1521 15.9905C10.3566 16.0742 10.2264 16.1207 10.245 16.1858L10.2171 16.1207C10.1335 16.0649 10.1242 16.1672 10.1242 16.2229C10.245 16.3066 10.338 16.2787 10.4031 16.2694C10.4588 16.3624 10.4031 16.3903 10.4681 16.5018C10.3008 16.3438 10.2729 16.4832 10.2264 16.5111C10.1521 16.5297 10.3473 16.6878 10.3287 16.697C10.2357 16.6227 10.2543 16.7621 10.1521 16.6227C10.1335 16.5855 10.2729 16.6506 10.2078 16.5669C10.1149 16.5483 9.95684 16.4182 10.0219 16.5669C10.0684 16.6878 10.3845 16.8272 10.1985 16.8365C10.1706 16.7807 10.1056 16.7156 10.0498 16.6506L9.89177 16.6692L10.0591 16.7993C10.0126 16.7807 10.0033 16.7621 9.97543 16.7528C10.1428 16.8923 9.90106 16.9666 10.0591 17.1711C10.0219 17.2641 9.83599 17.2455 9.77092 17.3106V17.2827C9.62218 17.2827 9.61288 17.4686 9.65936 17.6638L9.63148 17.6267C9.63148 17.6267 9.53852 17.8033 9.585 18.0078C9.41767 18.0264 9.06442 17.3199 9.15738 17.7196C9.1016 17.8498 9.28752 18.3425 9.38978 18.4261C9.18526 18.5284 9.23174 19.3743 8.94357 19.207C8.97145 19.3743 9.00864 19.4208 8.99005 19.5974C8.77624 19.9228 8.70187 21.1313 8.42298 20.6851C8.44158 20.3783 8.35791 20.2482 8.31143 19.9972C8.33002 20.3597 8.26495 20.0158 8.26495 20.1087C8.26495 20.1366 8.27425 20.211 8.29284 20.3783C8.33002 20.6014 8.34862 20.7594 8.3765 20.8896C8.3951 20.9732 8.41369 21.029 8.45087 21.0383C8.45087 21.0941 8.43228 21.1406 8.42298 21.2057C8.36721 21.2428 8.30214 21.2149 8.22777 21.1499C8.19058 21.1127 8.16269 21.0662 8.12551 21.0197C8.08833 20.9454 8.05114 20.8524 8.03255 20.7687C8.08833 20.9732 8.06973 21.029 8.03255 21.0848C7.99536 20.5828 7.88381 20.3783 7.80015 20.4434V20.7316L7.72578 20.3597C7.69789 20.4155 7.70719 20.9268 7.60493 20.5363C7.60493 20.4248 7.58634 20.3039 7.57704 20.2017C7.49338 20.3318 7.33534 20.5363 7.24238 20.1831L7.17731 19.6997C7.17731 19.6997 7.03787 19.8298 7.11224 20.025C6.9542 19.5881 6.84265 19.4301 6.84265 19.0768C6.44292 19.4673 5.89445 18.863 5.55049 18.3796L5.63416 18.2681C5.60627 18.0357 5.44824 18.4168 5.42964 18.2495C5.5319 18.1751 5.5226 17.9241 5.68064 17.8684C5.64345 17.5988 5.38316 17.8684 5.25302 17.8126C5.12287 17.9427 5.39246 17.8126 5.23443 17.9706C5.17865 17.9985 5.14146 17.636 4.93695 17.8126C4.97413 17.6917 5.14147 17.5802 5.23443 17.5151H5.0671C5.20654 17.1897 5.66205 17.3478 5.82938 16.9387L5.74571 16.9016C5.89445 16.6413 6.09896 16.8272 6.04319 16.6041C5.90374 16.6413 5.55979 16.8458 5.5412 17.0038C5.35528 16.8923 5.00202 17.3664 4.85329 17.1433C4.92765 16.9852 5.02062 17.2827 5.15076 17.0968C5.23443 16.8551 4.91836 17.0038 4.93695 16.9016C4.90906 17.0317 4.64877 17.1433 4.5837 17.134C4.62088 16.9852 4.8161 17.0224 4.76032 16.9016C4.62088 16.9852 4.46285 16.9666 4.44426 17.1154C4.13749 17.3013 4.44426 16.948 4.17467 17.0689C4.342 16.883 4.70455 16.8086 4.71384 16.6227C4.53722 16.79 4.3513 16.6878 4.11889 16.9759C4.13749 16.8923 4.27693 16.7621 4.42567 16.7063C4.49074 16.5483 3.96086 16.8272 4.31411 16.5111L4.1096 16.6413C4.15608 16.5762 4.18397 16.5018 4.25834 16.3903C4.22115 16.3345 3.8586 16.4182 4.14678 16.1951C4.1003 16.1951 4.01664 16.0649 3.84931 16.2694C3.79353 16.4461 4.06312 16.2415 3.83072 16.5018C4.00734 16.2694 3.70987 16.4089 3.59831 16.4275L3.70057 16.3345C3.6355 16.3345 3.60761 16.2601 3.47746 16.3345C3.56113 16.3066 3.6262 16.2322 3.6355 16.1858L3.44028 16.288C3.26365 16.2415 3.71916 16.0277 3.58902 15.9534L3.78424 15.9255C3.78424 15.9255 3.8772 15.7674 3.78424 15.7581C3.60761 15.8604 3.3938 15.972 3.26365 16.0463C3.1521 16.0463 3.42169 15.879 3.20788 15.9441L3.45887 15.8697C3.52395 15.8418 3.67268 15.6094 3.60761 15.535C3.51465 15.535 3.22647 15.6187 3.19858 15.7674C3.1614 15.7303 3.21717 15.6001 3.35662 15.5443C3.22647 15.4979 3.19858 15.6838 3.04055 15.6838C3.11492 15.5722 3.18929 15.3491 3.29154 15.1725L3.61691 15.0516L3.57972 14.9959C3.84931 14.9029 3.70987 14.8378 3.96086 14.6984C3.96086 14.6333 3.8586 14.6519 3.77494 14.6519C3.50535 15.0423 3.18929 14.9029 2.89181 15.1911C2.6873 15.1074 3.60761 14.4846 2.97548 14.717C2.9104 14.8099 2.60363 14.9215 2.77096 14.9494C2.73378 14.8285 2.39912 15.1353 2.4456 14.9215C2.64082 14.9029 2.70589 14.5775 2.99407 14.5497C2.88252 14.624 2.96618 14.6798 3.01266 14.6705C3.10562 14.5404 3.34732 14.4288 3.27295 14.3265C3.19858 14.2894 3.12421 14.215 2.96618 14.3544C2.78026 14.5032 3.05914 14.4288 2.83603 14.5404C2.678 14.4753 2.94759 14.2336 2.58504 14.4381C2.6687 14.4939 2.49208 14.6612 2.36193 14.7542L2.2132 14.7263L2.35264 14.6519C2.33405 14.4474 2.09235 14.7821 2.02727 14.624L2.22249 14.373C2.45489 14.2429 2.27827 14.6426 2.60363 14.3544C2.54786 14.2522 2.35264 14.3544 2.38053 14.2057C2.42701 14.2057 2.45489 14.2243 2.49208 14.215C2.48278 14.1778 2.9104 13.7967 2.54786 13.871C2.39912 13.8896 2.40841 13.9454 2.27827 14.0384C2.12953 13.9268 1.9715 13.9826 1.87854 13.9082C2.14812 13.7409 1.78558 13.7316 2.12024 13.6386C2.00868 13.7967 2.17601 13.9919 2.45489 13.8617C2.71519 13.5829 2.50138 14.0012 2.82674 13.806C2.75237 13.6851 3.04984 13.4713 3.22647 13.304C3.21717 13.2668 3.11492 13.2947 3.06844 13.304C2.87322 13.4248 2.9104 13.462 2.72448 13.6107C2.678 13.4434 2.49208 13.3969 2.25968 13.462C2.31545 13.3505 2.51067 13.2296 2.56645 13.2668C2.39912 13.1552 2.30616 12.9786 2.25968 12.7927C2.02727 13.1088 2.07376 12.6811 1.86924 12.9321C1.85995 13.0623 1.69262 13.2854 1.52529 13.3412C1.50669 13.2761 1.65543 13.2482 1.71121 13.1831C1.4974 13.2389 1.90643 12.8949 1.59965 13.0251C1.79487 13.0995 1.99009 12.7834 2.24108 12.644C2.03657 12.644 2.40841 12.5231 2.34334 12.4301C2.13883 12.4301 1.94361 12.3744 1.81346 12.3C1.94361 12.0025 1.56247 11.9375 1.46951 11.8166C1.54388 11.6679 1.85065 11.5284 1.84135 11.4262C1.77628 11.3425 1.59036 11.6865 1.62754 11.4819L1.69262 11.4541C1.59965 11.4541 1.7205 11.1008 1.30218 11.3239L1.62754 11.1659C1.62754 11.1659 1.55317 11.1473 1.51599 11.1473C1.60895 11.0822 1.68332 10.9985 1.76698 10.9892C1.92502 10.7754 1.62754 10.8498 1.56247 10.7661L1.42303 10.9335C1.19063 10.8777 1.30218 10.6639 1.15344 10.5616L1.33007 10.4594L1.17203 10.4408C1.35796 10.3571 1.42303 10.2177 1.2464 10.2549L1.81346 10.2084C1.74839 10.3292 1.56247 10.2735 1.41373 10.4129C1.28359 10.5337 1.41373 10.6453 1.59036 10.5523C1.58106 10.4873 1.53458 10.5152 1.45092 10.5152C1.68332 10.3478 1.7205 10.4315 1.90643 10.3664C1.87854 10.3478 1.93431 10.2642 1.85065 10.3106C1.99939 10.2827 2.05516 10.3292 2.11094 10.4036C1.98079 10.4036 1.98079 10.5337 1.89713 10.5523C2.11094 10.4222 2.23179 10.4594 2.24108 10.5988C2.04587 10.8312 2.52926 10.6825 2.53856 10.8498C2.29686 10.9428 2.08305 10.9985 1.95291 10.98C1.89713 11.1287 2.01798 11.0636 1.95291 11.2124C2.13883 11.138 2.38982 11.0078 2.55715 11.0357L2.40841 11.1473C2.54786 11.1845 2.78026 11.0171 2.80815 11.1566C2.86392 11.3983 3.00336 11.5935 3.08703 11.7515L2.93829 11.8631C3.31943 11.705 3.25436 12.0397 3.47746 12.0397C3.46817 12.3279 3.91438 12.3279 3.71916 12.6161C4.07241 12.8485 4.39778 13.0437 4.593 13.4062L4.3327 13.5178C4.53722 13.4527 4.23974 13.6479 4.31411 13.6851C4.43496 13.4806 4.60229 13.5922 4.76962 13.5271C4.71384 13.806 5.03921 13.8524 5.2902 13.8617L5.14146 13.9826C5.5226 13.8896 5.40176 14.2429 5.48542 14.4381C5.43894 14.5032 5.31809 14.6426 5.37387 14.6798C5.68064 14.5775 5.69923 14.6333 5.95022 14.6426C6.02459 14.7356 6.08967 14.9308 6.07107 15.1074C6.37784 15.1446 6.55447 15.3026 6.7125 15.47C6.80546 15.5722 6.84265 15.6094 6.87983 15.6373C6.92631 15.6652 6.98209 15.6838 7.05646 15.6745L6.92631 15.8697C7.14942 15.7674 7.1866 15.7953 7.24238 15.8883C7.28886 15.972 7.34464 16.1114 7.40971 15.9998L7.32605 16.4925C7.34464 16.7063 7.4283 16.4646 7.4469 16.0649C7.46549 16.2694 7.51197 15.8604 7.53056 16.3624C7.56774 16.5111 7.56774 16.13 7.57704 16.0649C7.60493 16.2137 7.63282 16.288 7.65141 16.3066C7.67 16.3066 7.67 16.2137 7.67 16.13V16.1021C7.67 16.2508 7.70719 16.5297 7.72578 16.5483C7.72578 16.4739 7.72578 16.4554 7.72578 16.4368C7.73507 16.3996 7.74437 16.3438 7.6607 15.8976C7.70719 16.0742 7.71648 15.9441 7.71648 15.8511C7.71648 15.7581 7.71648 15.6931 7.80944 15.879C7.75367 15.7303 7.75367 15.6931 7.71648 15.5908C7.72578 15.5536 7.9024 15.7488 7.80015 15.5071C7.84663 15.5536 7.9117 15.7117 7.93959 15.7024C7.921 15.6466 7.84663 15.5536 7.80944 15.4793C7.76296 15.3491 7.80944 15.377 7.89311 15.3956C7.93959 15.4607 8.19988 15.2747 8.27425 15.1353C8.47876 14.4753 9.01793 14.057 9.39907 13.6015L9.46415 13.6665C9.35259 13.2761 10.0405 13.5829 9.78021 13.1088C9.87317 13.1366 9.93825 13.0158 10.0312 13.1645C9.96614 12.8857 10.496 13.0251 10.4402 12.6532C10.4216 12.6532 10.4216 12.6811 10.4402 12.7276C10.7377 12.7183 10.6912 12.3837 10.9887 12.3558C10.998 12.4023 10.9887 12.4487 11.0445 12.5231C11.2304 12.5882 10.9329 12.0955 11.2676 12.3837C11.3048 12.3465 11.1467 12.1977 11.1281 12.2256C11.6115 12.0118 11.8161 11.4355 12.1321 11.0078C12.5876 10.9428 12.6434 11.5377 12.6434 11.0915C12.7178 11.138 12.5412 10.9521 12.6062 11.0171C12.6062 10.8498 13.071 11.2588 12.9688 11.0357C12.7643 10.8591 12.9037 10.887 12.8014 10.7661C13.0896 10.7383 13.2848 10.887 13.2848 10.6174L13.3685 10.729C13.257 10.292 13.5823 10.2827 13.4057 9.81794C14.2237 8.972 14.8838 8.03309 15.7111 7.24293C16.6221 6.56431 17.3193 5.69048 18.3419 5.13271C18.7881 5.24427 18.7974 5.21638 18.9183 4.9189C18.9462 4.97468 18.9462 4.99327 18.9926 5.02116C18.8067 4.77946 19.1321 4.86313 18.9647 4.62143C19.3273 4.38903 19.569 4.07296 19.8944 3.79408C19.8665 3.85915 19.9966 4.07296 20.0431 4.00789L19.978 3.80337L20.0431 3.85915C20.0524 3.78478 20.0059 3.63604 19.8944 3.59886C20.5544 2.69714 21.7722 2.47403 22.5437 1.73034C22.8226 1.66527 23.0178 1.34921 23.1945 1.1168C24.0776 0.902993 24.8492 0.689183 25.3047 -0.0545044C25.3047 -0.0545044 25.723 0.62411 25.5836 0.977361L25.5929 1.03314Z\" fill=\"#8F3A7E\"><\/path><path d=\"M1.7481 9.85501C1.62739 9.95715 1.59954 10.0778 1.38599 10.115C1.50669 10.0314 1.61811 9.91072 1.7481 9.85501Z\" fill=\"#8F3A7E\"><\/path><path d=\"M1.8506 12.8295C1.8506 12.8295 1.82275 12.8945 1.80418 12.9131C1.77632 12.8945 1.65562 12.9409 1.70204 12.8759C1.7299 12.8945 1.78561 12.8481 1.8506 12.8202V12.8295Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.16678 13.4147C2.05536 13.489 1.87895 13.4425 1.82324 13.3775L2.16678 13.4147Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.08289 14.2437C2.02718 14.3551 1.96219 14.383 1.92505 14.318C1.98076 14.2715 2.02718 14.2715 2.08289 14.2437Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.35372 14.0857C2.35372 14.0857 2.33511 14.188 2.28857 14.2625C2.38165 14.188 2.15827 14.216 2.35372 14.0857Z\" fill=\"#8F3A7E\"><\/path><path d=\"M2.84607 15.3857C2.84607 15.3857 3.00391 15.3857 2.90178 15.5064C2.96677 15.4135 2.66966 15.4878 2.84607 15.3857Z\" fill=\"#8F3A7E\"><\/path><path d=\"M3.39329 15.7397C3.39329 15.7397 3.384 15.7861 3.43043 15.7769C3.40257 15.8418 3.30044 15.879 3.27258 15.8604L3.39329 15.7397Z\" fill=\"#8F3A7E\"><\/path><path d=\"M11.9369 14.7541L11.9462 14.8467L11.8535 14.7448L11.9369 14.7541Z\" fill=\"#8F3A7E\"><\/path><path d=\"M15.4611 11.4917C15.4611 11.3803 15.5818 11.5567 15.6003 11.5659C15.5632 11.6124 15.5075 11.4267 15.4611 11.4917Z\" fill=\"#8F3A7E\"><\/path><path d=\"M16.957 9.2601L16.9477 9.27864L16.7716 9.06546L16.957 9.2601Z\" fill=\"#8F3A7E\"><\/path><path d=\"M26.4111 1.45928C26.4761 1.32929 26.2068 1.32001 26.4111 1.32001C26.4668 1.41286 26.5039 1.49642 26.4111 1.45928Z\" fill=\"#8F3A7E\"><\/path><path d=\"M1.08847 10.4673C1.92512 10.4673 1.62764 11.3319 2.27837 11.4713C2.33415 11.4992 1.95301 11.6851 2.10174 11.7316C2.81754 11.7967 2.97558 12.5682 2.97558 13.2747L2.86402 13.3119C2.86402 13.4514 3.23587 13.3305 3.26375 13.4514C3.20798 13.4979 3.1615 13.4886 3.09642 13.5629C3.29164 13.4514 3.30094 13.6652 3.45897 13.6094C3.42179 13.6931 3.27305 13.7953 3.23587 13.9069L3.47756 13.8046C4.06322 13.5908 3.70997 14.1765 4.1097 14.1858C4.05392 14.2137 4.00744 14.2229 3.97026 14.2694C4.50013 14.3624 4.75113 14.79 5.13227 15.0596C5.0486 15.0968 4.91846 15.1897 4.85338 15.2734C5.07649 15.1247 5.20664 15.1897 5.32749 15.2548C5.15086 15.4686 5.64355 15.2548 5.61566 15.4593L5.55989 15.4872C5.84807 15.3943 5.532 15.7103 5.84807 15.5616L5.72722 15.7475C6.05258 15.543 5.66214 15.9892 5.86666 15.9334L5.92244 15.8777C6.04328 15.8777 5.92244 16.0357 6.0154 16.0543L5.98751 16.0915C6.17343 16.1658 6.06188 16.361 6.28498 16.1658C6.14554 16.3703 6.10836 16.1193 5.90384 16.4168C6.4895 16.6492 6.74049 17.049 7.08445 17.458C7.08445 17.6532 7.11233 17.7369 7.10304 17.8949C7.14952 17.8577 7.25178 17.9879 7.30755 17.8112C7.29826 17.8112 7.30755 18.0529 7.33544 18.0994C7.40051 18.3504 7.4284 17.6997 7.48418 17.9786C7.45629 18.0715 7.4377 18.2017 7.44699 18.3783C7.52136 18.1087 7.59573 18.2482 7.6608 18.211C7.6608 18.2853 7.64221 18.3132 7.64221 18.462C7.69799 18.118 7.80024 18.7316 7.84673 18.527V18.7966C7.99546 19.2893 7.82813 18.276 7.9025 18.3783C7.9025 18.5084 7.92109 18.6107 7.93039 18.7408C7.93039 18.3597 7.93969 18.2017 7.96757 18.0715C7.98617 17.9693 8.01406 17.8949 8.02335 17.7648C8.02335 17.8019 8.04194 17.8763 8.04194 17.8763C8.07913 17.6904 8.17209 17.6904 8.19068 17.3743C8.24646 17.4208 8.33942 17.9414 8.39519 17.7183C8.23716 17.2628 8.46027 17.3 8.23716 16.9188C8.31153 16.8909 8.46956 16.8537 8.45097 16.6771C8.49745 16.8537 8.72056 17.0211 8.68337 17.1605C8.73915 17.207 8.79493 17.2535 8.86 17.3C8.94366 17.458 8.77633 17.3464 8.90648 17.5045C8.93437 17.4208 8.94366 17.1047 9.00874 17.1047C8.93437 16.8073 8.72985 16.4261 8.76704 16.2774C8.82282 16.4354 9.06451 16.5098 9.08311 16.5935C8.97155 16.3703 8.84141 16.1658 8.70197 15.9892C8.71126 15.9427 8.92507 16.1472 8.89718 16.0264C8.82281 15.9799 8.79493 15.9148 8.75774 15.8498C8.80422 15.8498 8.8507 15.5895 9.12959 15.7754C9.25043 15.8405 9.12959 15.8962 9.25973 15.9148C9.3248 15.8219 9.24114 15.7475 9.29692 15.6545L9.3341 15.6824C9.41776 15.6545 9.36199 15.4221 9.16677 15.3664C9.12029 15.4036 9.3341 15.4779 9.21325 15.4779C9.0924 15.3106 9.13888 15.1711 9.21325 15.0875C9.23184 15.1526 9.30621 15.2083 9.36199 15.2827C9.25043 14.9945 9.29692 14.8179 9.3341 14.6134C9.21325 14.5018 9.51073 14.8551 9.42706 14.8179C9.73383 14.7993 9.49213 14.2694 9.86398 14.3531C9.86398 14.3903 9.68735 14.2044 9.72454 14.2415C9.8082 14.1765 9.97553 14.3438 9.96623 14.2415C10.0685 14.3345 9.99412 14.1486 10.0127 14.0742C9.96623 13.9812 10.0778 14.1114 10.0406 14.1579C10.022 14.0091 10.1522 13.5815 10.4496 13.5629C10.3846 13.4979 10.3102 13.2283 10.3567 13.2004L10.4868 13.3677C10.6077 13.4235 10.5984 13.2376 10.7285 13.3584C10.6263 13.0981 10.5798 13.8139 10.5426 13.5629C10.6913 13.6652 10.4496 13.1725 10.6356 13.4049C10.7006 13.3305 10.6077 13.0888 10.8215 13.1632C10.775 13.1632 10.9609 13.4328 11.0167 13.3677C11.0911 13.2376 10.9795 13.2655 11.0167 13.1353V13.0238C10.868 12.8657 11.1282 12.9587 10.9237 12.8192C11.0539 12.9308 11.0074 12.5961 11.2305 12.8564L11.3978 13.0702C11.4257 13.0145 11.277 12.7913 11.2305 12.6705C11.2584 12.6798 11.3049 12.7077 11.3328 12.7449C11.0539 12.4381 11.4629 12.6705 11.3049 12.3823C11.5001 12.4009 11.5559 12.1685 11.779 12.308C11.7697 12.1499 11.7325 11.9733 11.8812 11.964C11.8905 12.0105 11.8812 12.0384 11.9277 12.1034C12.0671 12.1406 12.0021 12.0477 12.0021 11.9547C12.03 12.0105 12.2717 12.0384 12.4297 12.0848C12.4204 11.9268 12.2438 11.7874 12.1601 11.6758C12.5041 11.9175 12.188 11.2947 12.5227 11.4899C12.532 11.555 12.5505 11.7316 12.6807 11.7595C13.0246 12.0012 12.6156 11.4155 12.8573 11.462L12.597 11.2389C12.7829 11.3505 12.6249 10.9507 12.848 11.211C12.8015 11.0902 13.0525 11.1738 12.8201 10.9414C13.1827 10.9879 13.1455 10.4208 13.6475 10.7555C13.6382 10.6904 13.7404 10.6718 13.6103 10.5603C13.443 10.458 13.6382 10.709 13.5359 10.6347C13.5545 10.6068 13.4987 10.5324 13.4709 10.4952C13.5731 10.4952 13.6382 10.4766 13.7683 10.7276C14.0286 10.7648 13.5173 10.1977 13.7683 10.1513C13.852 10.2628 13.8985 10.2907 13.9357 10.2256L13.8706 9.97463C14.01 9.91886 14.1402 10.1513 14.2982 10.3279C14.3261 10.2535 14.4005 10.1977 14.3075 10.049L14.5678 10.207C14.3819 10.0955 14.5213 10.0583 14.5027 9.99323V10.0583C14.5864 10.1234 14.6143 10.0211 14.6236 9.97463C14.5213 9.87238 14.4191 9.89097 14.354 9.89097C14.3168 9.78871 14.3726 9.77012 14.3261 9.64927C14.4655 9.8259 14.5213 9.68646 14.5864 9.66786C14.6701 9.66786 14.5027 9.46335 14.5306 9.45405C14.6143 9.53772 14.6236 9.39828 14.6979 9.55631C14.6979 9.60279 14.5864 9.50983 14.6236 9.61209C14.7165 9.64927 14.8467 9.8073 14.8188 9.63068C14.7909 9.50053 14.5027 9.30532 14.6979 9.32391C14.7072 9.38898 14.763 9.46335 14.8002 9.53772H14.9675L14.8374 9.38898C14.8839 9.41687 14.8839 9.43546 14.9118 9.45405C14.7909 9.26813 15.0047 9.27743 14.8653 9.08221C14.8932 9.02643 15.0605 9.1008 15.1163 9.08221V9.1008C15.2557 9.14728 15.2743 9.01714 15.2278 8.8777L15.2557 8.91488C15.2557 8.91488 15.3487 8.81262 15.3022 8.69177C15.4788 8.73826 15.8414 9.25884 15.7577 8.98925C15.8321 8.91488 15.6276 8.59881 15.5067 8.52444C15.7391 8.50585 15.6647 8.11542 16.0087 8.24556C15.9715 8.1619 15.925 8.13401 15.9343 8.06894C16.1853 7.95738 16.1946 7.51117 16.6222 7.6785C16.6222 7.79935 16.7524 7.83653 16.836 7.92949C16.7617 7.74357 17.022 8.02246 16.836 7.77146C16.7059 7.63202 16.6501 7.55765 16.5479 7.55765C16.6036 7.38103 16.7803 7.22299 16.9662 7.29736C16.8732 7.26018 16.8639 7.1951 16.8546 7.13003C17.0406 7.36243 17.1614 7.31595 17.1614 7.18581L17.0499 7.03707L17.2172 7.13933C17.2079 7.07425 16.9941 6.82326 17.18 6.89763C17.2265 6.94411 17.2823 6.99989 17.3287 7.02777C17.3008 6.85115 17.2358 6.58156 17.4124 6.62804L17.6448 6.77678C17.6541 6.7303 17.6076 6.56297 17.5054 6.55367C17.7378 6.56297 17.8307 6.50719 18.0259 6.64664C17.8772 6.03309 18.1933 5.73562 18.4722 5.5497L18.5558 5.66125C18.7046 5.69843 18.435 5.44744 18.5558 5.47533C18.6209 5.59618 18.7882 5.64266 18.844 5.80999C19.0392 5.83788 18.8161 5.52181 18.844 5.41955C18.7417 5.27081 18.8626 5.5497 18.7324 5.36377C18.7046 5.308 18.9648 5.35448 18.7975 5.13137C18.8905 5.18715 19.002 5.35448 19.0578 5.45674L19.0299 5.308C19.3088 5.48462 19.2251 5.88436 19.5598 6.10746L19.5877 6.0238C19.8201 6.19113 19.6435 6.39564 19.848 6.34916C19.8201 6.20042 19.6156 5.85647 19.4854 5.80999C19.5598 5.64266 19.1229 5.27081 19.2809 5.16856C19.4204 5.26152 19.1972 5.28941 19.3646 5.43814C19.5691 5.5497 19.4111 5.23363 19.5226 5.24293C19.3925 5.21504 19.2716 4.96404 19.2809 4.88967C19.4297 4.92686 19.4018 5.12208 19.5133 5.057C19.4297 4.92686 19.4389 4.75953 19.2902 4.74094C19.095 4.44346 19.4575 4.73164 19.3367 4.47135C19.5319 4.62938 19.6063 4.99193 19.8015 5.00123C19.6249 4.8339 19.7271 4.63868 19.4389 4.41557C19.5226 4.43417 19.6528 4.57361 19.7178 4.71305C19.8759 4.77812 19.5784 4.25754 19.913 4.6015L19.7736 4.39698C19.848 4.44346 19.913 4.46205 20.0246 4.53642C20.0804 4.48994 19.9781 4.13669 20.2198 4.42487C20.2198 4.37839 20.3407 4.29472 20.1362 4.13669C19.9595 4.08091 20.1733 4.3505 19.9038 4.12739C20.1362 4.29472 19.9874 4.00655 19.9688 3.89499L20.0711 3.99725C20.0618 3.93218 20.1455 3.90429 20.0618 3.77414C20.099 3.85781 20.164 3.92288 20.2105 3.93218L20.099 3.74626C20.1362 3.56963 20.3686 4.01584 20.4336 3.8857L20.4615 4.08091C20.4615 4.08091 20.6196 4.16458 20.6288 4.07162C20.5266 3.90429 20.3964 3.69048 20.3221 3.56033C20.3221 3.44878 20.4894 3.70907 20.415 3.50456L20.4987 3.75555C20.5266 3.81133 20.759 3.96007 20.8334 3.89499C20.8334 3.80203 20.7311 3.51385 20.5824 3.49526C20.6196 3.45808 20.7497 3.50456 20.8148 3.644C20.8612 3.51385 20.666 3.48596 20.666 3.32793C20.7869 3.4023 21.0007 3.46737 21.1866 3.56033L21.3168 3.8857L21.3725 3.83922C21.4748 4.09951 21.5399 3.96936 21.6793 4.21106C21.7444 4.21106 21.7258 4.1088 21.7165 4.01584C21.3168 3.76485 21.4376 3.44878 21.1401 3.1606C21.2145 2.95609 21.8745 3.84851 21.6142 3.22567C21.5213 3.1606 21.3911 2.86313 21.3725 3.03046C21.4934 2.99327 21.168 2.66791 21.3818 2.70509C21.4097 2.90031 21.7351 2.95609 21.7816 3.23497C21.6979 3.12342 21.6514 3.20708 21.6607 3.25356C21.8002 3.34652 21.921 3.57893 22.014 3.49526C22.0419 3.42089 22.1162 3.34652 21.9675 3.18849C21.8095 3.01186 21.8931 3.28145 21.7816 3.06764C21.8373 2.90961 22.0883 3.1699 21.8652 2.80735C21.8187 2.89101 21.6421 2.72369 21.5399 2.59354L21.5585 2.4448L21.6421 2.57495C21.8466 2.54706 21.5027 2.32395 21.6514 2.24958L21.9117 2.43551C22.0511 2.66791 21.6514 2.50058 21.9489 2.81665C22.0419 2.76087 21.9303 2.56565 22.079 2.58424C22.079 2.63072 22.0697 2.65861 22.079 2.6958C22.1162 2.6772 22.516 3.09553 22.423 2.74228C22.4044 2.59354 22.3393 2.61213 22.2371 2.48199C22.3393 2.33325 22.2743 2.17522 22.3393 2.08226C22.5253 2.34255 22.5067 1.98 22.6275 2.30536C22.4602 2.2031 22.2836 2.37973 22.4323 2.64932C22.7205 2.89101 22.2928 2.6958 22.5067 3.01186C22.6182 2.9282 22.8506 3.21638 23.0272 3.38371C23.0644 3.37441 23.0272 3.27215 23.0272 3.22567C22.8971 3.03975 22.8599 3.07694 22.7019 2.90031C22.8599 2.84453 22.8971 2.64932 22.8227 2.42621C22.9343 2.48199 23.0644 2.66791 23.0365 2.72369C23.1388 2.55636 23.3061 2.4448 23.4827 2.38903C23.1574 2.17522 23.5757 2.19381 23.3247 2.00789C23.1946 2.00789 22.9715 1.84985 22.8971 1.69182C22.9622 1.67323 22.9994 1.82196 23.0737 1.85915C22.9994 1.65464 23.3712 2.03577 23.2225 1.7383C23.1667 1.94281 23.4827 2.11014 23.6501 2.35184C23.6408 2.14733 23.7802 2.50988 23.8732 2.43551C23.8639 2.23099 23.8918 2.03577 23.9568 1.90563C24.2636 2.00789 24.2915 1.63604 24.4031 1.52449C24.5611 1.58956 24.7284 1.87774 24.8307 1.85915C24.905 1.78478 24.5425 1.63604 24.7563 1.65464L24.7842 1.71041C24.7656 1.62675 25.1375 1.71041 24.8679 1.31068L25.0631 1.61745C25.0631 1.61745 25.0724 1.54308 25.0631 1.5059C25.1374 1.58956 25.2304 1.65464 25.2397 1.7383C25.4721 1.86845 25.3606 1.58027 25.4349 1.51519L25.249 1.39434C25.2769 1.15265 25.5 1.24561 25.5744 1.07828L25.7045 1.23631V1.07828C25.8068 1.24561 25.9648 1.29209 25.8997 1.12476L26.0299 1.67323C25.8997 1.62675 25.9276 1.43153 25.7696 1.30138C25.6301 1.18983 25.5465 1.32927 25.6487 1.4966C25.7045 1.47801 25.6859 1.44083 25.6673 1.35716C25.8625 1.56167 25.7882 1.61745 25.8811 1.78478C25.8997 1.75689 25.9834 1.79408 25.9369 1.71971C25.9834 1.86845 25.9462 1.92422 25.8718 1.98929C25.8532 1.85915 25.7324 1.87774 25.6952 1.79408C25.8532 1.98929 25.8254 2.11014 25.6859 2.13803C25.4349 1.9707 25.6301 2.43551 25.4628 2.46339C25.342 2.23099 25.2676 2.02648 25.2676 1.88704C25.1189 1.84985 25.1932 1.96141 25.0445 1.91493C25.1375 2.09155 25.2955 2.33325 25.2769 2.50058L25.1467 2.36114C25.1282 2.50058 25.3048 2.71439 25.1653 2.77017C24.9236 2.84453 24.7377 3.00257 24.589 3.09553L24.4588 2.95609C24.6448 3.32793 24.3008 3.28145 24.3101 3.50456C24.0219 3.50456 24.0498 3.96007 23.7523 3.78344C23.5385 4.15528 23.3619 4.48994 22.9994 4.70375L22.8785 4.45276C22.9529 4.65727 22.7391 4.3598 22.7112 4.44346C22.9157 4.55502 22.8134 4.72234 22.8878 4.88967C22.6089 4.84319 22.581 5.17785 22.5717 5.42885L22.4416 5.28941C22.5438 5.67055 22.1906 5.55899 21.9954 5.64266C21.9303 5.59618 21.7816 5.48462 21.7537 5.5404C21.8652 5.84717 21.8095 5.86576 21.8002 6.11676C21.7072 6.19113 21.512 6.2655 21.3446 6.2469C21.2796 6.86974 20.7497 6.95341 20.5638 7.4554L20.3964 7.30666C20.3593 7.95738 19.6528 7.99457 19.5226 8.44078L19.2995 8.12471C19.1322 8.12471 19.1508 8.385 19.3553 8.56163C19.188 8.56163 19.2437 8.89629 18.9834 8.71037C18.844 8.73825 18.9834 8.94277 18.937 9.04503C18.6581 9.1008 18.6023 9.18447 18.4722 9.38898L18.5279 9.37039C18.4907 9.28672 18.3885 9.16588 18.3327 9.18447C18.3327 9.32391 18.0259 9.31461 18.3885 9.60279C18.0259 9.56561 18.091 10.1513 17.6727 10.0397C17.7657 10.1234 17.7378 10.1791 17.7749 10.2535C17.6169 10.4023 17.273 10.3651 17.2823 10.644C17.2172 10.6161 17.1893 10.4487 17.1056 10.4952C17.1056 10.5696 17.2079 10.6161 17.2079 10.709C17.0963 11.1181 16.5107 11.0065 16.3062 11.2668C16.0366 11.8246 15.5067 12.1406 15.1349 12.5404L15.0791 12.466C15.172 12.8471 14.5213 12.4939 14.763 12.9773C14.6701 12.9401 14.6143 13.0609 14.5213 12.9122C14.5771 13.1911 14.0658 13.0238 14.1123 13.3956C14.1309 13.3956 14.1309 13.3677 14.1123 13.3212C13.8148 13.3212 13.8706 13.6466 13.5731 13.6745C13.5638 13.628 13.5731 13.5815 13.5173 13.5071C13.3314 13.4421 13.6289 13.9255 13.2942 13.6373C13.257 13.6745 13.4151 13.8232 13.4337 13.7953C12.9503 14.0091 12.7551 14.5762 12.4669 14.9945C12.03 15.0596 11.937 14.4832 11.9649 14.9109C11.8905 14.8644 12.0671 15.041 12.0021 14.9759C12.0021 15.134 11.5373 14.7528 11.6488 14.9666C11.8626 15.134 11.7232 15.1061 11.8347 15.2269C11.5559 15.2548 11.3514 15.1247 11.3792 15.385L11.2863 15.2734C11.435 15.6917 11.1282 15.7196 11.3606 16.1472C11.2026 16.361 11.0539 16.5749 10.9237 16.7887L10.4403 17.6625C9.91975 18.5456 9.60369 20.0423 9.12029 21.4367C8.99014 21.7993 8.8507 22.1618 8.72056 22.5151L8.33942 22.0874L7.89321 21.5762L7.00078 20.5536C6.41513 19.8657 5.80159 19.1127 5.281 18.3225C5.20664 17.6439 5.20664 17.6625 4.77902 17.3743C4.83479 17.3464 4.86268 17.365 4.89057 17.3C4.76972 17.3929 4.70465 17.3185 4.64887 17.2628C4.61169 17.2256 4.5745 17.1791 4.45365 17.2628C4.23055 16.9002 3.92378 16.6399 3.64489 16.296C3.70997 16.3332 3.93307 16.203 3.868 16.1472L3.66349 16.203L3.71926 16.1379C3.64489 16.1193 3.49616 16.1658 3.44968 16.2774C2.55725 15.5709 2.37133 14.3345 1.66483 13.5071C1.60905 13.219 1.30228 12.9959 1.08847 12.8006C0.930435 11.8617 0.790994 11.0902 0.0751953 10.4116C0.0751953 10.4116 0.828178 10.1513 1.16284 10.3558L1.08847 10.4673Z\" fill=\"#8F3A7E\"><\/path><path d=\"M26.3094 1.58132C26.1885 1.47901 26.0676 1.47901 25.9932 1.27438C26.0955 1.3767 26.235 1.46971 26.3094 1.58132Z\" fill=\"#8F3A7E\"><\/path><path d=\"M23.3623 1.9979C23.3623 1.9979 23.2973 1.97005 23.2695 1.96076C23.288 1.93291 23.223 1.8122 23.2973 1.85863C23.2787 1.88648 23.3345 1.94219 23.3623 1.9979Z\" fill=\"#8F3A7E\"><\/path><path d=\"M22.8039 2.34232C22.7203 2.2309 22.7574 2.06377 22.8131 1.99878V2.34232H22.8039Z\" fill=\"#8F3A7E\"><\/path><path d=\"M21.9853 2.29645C21.8739 2.24074 21.846 2.18504 21.9018 2.13861C21.9482 2.19432 21.9575 2.23146 21.9853 2.29645Z\" fill=\"#8F3A7E\"><\/path><path d=\"M22.1544 2.56585C22.1544 2.56585 22.052 2.55654 21.9775 2.51001C22.052 2.59377 22.0241 2.37971 22.1544 2.56585Z\" fill=\"#8F3A7E\"><\/path><path d=\"M20.8979 3.10465C20.8979 3.10465 20.8979 3.26249 20.7772 3.16965C20.8701 3.22535 20.7772 2.93752 20.8979 3.10465Z\" fill=\"#8F3A7E\"><\/path><path d=\"M20.5632 3.65382C20.5632 3.65382 20.5168 3.65382 20.5261 3.69096C20.4611 3.6631 20.424 3.57025 20.4425 3.53311L20.5632 3.65382Z\" fill=\"#8F3A7E\"><\/path><path d=\"M12.5693 11.3684V11.275L12.6534 11.3871L12.5693 11.3684Z\" fill=\"#8F3A7E\"><\/path><path d=\"M9.03711 14.8652C9.05568 14.9767 8.90712 14.8188 8.88855 14.8188C8.9164 14.7631 8.99997 14.9488 9.03711 14.8652Z\" fill=\"#8F3A7E\"><\/path><path d=\"M8.21887 17.2635V17.2357L8.33029 17.5885L8.21887 17.2635Z\" fill=\"#8F3A7E\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Free Re-file for Rejected Returns<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-23e84b6b e-con-full e-flex e-con e-parent\" data-id=\"23e84b6b\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-134574ed e-con-full e-flex e-con e-child\" data-id=\"134574ed\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-18e7d41 elementor-widget elementor-widget-heading\" data-id=\"18e7d41\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Get Your Stamped Schedule 1 and<br\/> stay compliant.<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-61f55415 e-con-full e-flex e-con e-child\" data-id=\"61f55415\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-55f3adb2 elementor-widget__width-inherit elementor-widget elementor-widget-aux_modern_button\" data-id=\"55f3adb2\" data-element_type=\"widget\" data-widget_type=\"aux_modern_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t    <div class=\"aux-modern-button-wrapper aux-modern-button-align-center\" >\n                    <a class=\"aux-modern-button aux-black aux-modern-button-lg aux-modern-button-curve aux-modern-button-default aux-icon-right\" href=\"https:\/\/www.ez2290.com\/Account\/Login?utm_source=LP_SDP&#038;utm_medium=referral&#038;utm_campaign=Missouri+Trucking+Association\">\n                <div class=\"aux-overlay\"><\/div>\n                                    <div class=\"aux-icon \">\n                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"28\" height=\"28\" viewBox=\"0 0 28 28\" fill=\"none\"><g id=\"arrow_outward\"><mask id=\"mask0_1_367\" style=\"mask-type:alpha\" maskUnits=\"userSpaceOnUse\" x=\"0\" y=\"0\" width=\"28\" height=\"28\"><rect id=\"Bounding box\" width=\"28\" height=\"28\" fill=\"#D9D9D9\"><\/rect><\/mask><g mask=\"url(#mask0_1_367)\"><path id=\"arrow_outward_2\" d=\"M7.53732 21.2299L5.67383 19.3664L16.7134 8.32687H6.91023V5.6727H21.2311V19.9935H18.5769V10.1904L7.53732 21.2299Z\" fill=\"white\"><\/path><\/g><\/g><\/svg>                    <\/div>\n                                <div class=\"aux-text\">\n<span class=\"aux-text-before\">eFile 2290 Now<\/span>                <\/div>\n            <\/a>\n            \n    <\/div>\n\n    \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-e88eddf e-con-full e-flex e-con e-parent\" data-id=\"e88eddf\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-76504b7 elementor-widget elementor-widget-heading\" data-id=\"76504b7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"22\" height=\"27\" viewBox=\"0 0 32 37\" fill=\"none\">\n  <path d=\"M0 19.969L32 0V17.2751L0 37V19.969Z\" fill=\"#8F3A7E\"\/>\n<\/svg> 3 Easy Steps<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45336bb elementor-widget elementor-widget-heading\" data-id=\"45336bb\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">eFile IRS Form 2290\nwith EZ2290\n\n<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ea8aa42 elementor-widget elementor-widget-image\" data-id=\"ea8aa42\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2064\" height=\"800\" src=\"https:\/\/www.ez2290.com\/hvut\/wp-content\/uploads\/2024\/03\/easysteps.gif\" class=\"attachment-full size-full wp-image-64\" alt=\"EZ2290 e-File Service\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-2a08eee e-con-full e-flex e-con e-parent\" data-id=\"2a08eee\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4c663f8 elementor-widget elementor-widget-heading\" data-id=\"4c663f8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"22\" height=\"27\" viewBox=\"0 0 32 37\" fill=\"none\">\n  <path d=\"M0 19.969L32 0V17.2751L0 37V19.969Z\" fill=\"#8F3A7E\"\/>\n<\/svg> Testimonials<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bfd5a07 elementor-widget elementor-widget-heading\" data-id=\"bfd5a07\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Here\u2019s What Our Customers Say About EZ2290\n<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-be57ec1 e-con-full e-flex e-con e-parent\" data-id=\"be57ec1\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-522e7ea elementor-widget elementor-widget-eael-testimonial-slider\" data-id=\"522e7ea\" data-element_type=\"widget\" data-settings=\"{&quot;items&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:3,&quot;sizes&quot;:[]},&quot;items_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;items_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;slide_items&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;slide_items_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;slide_items_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]}}\" data-widget_type=\"eael-testimonial-slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"swiper-container-wrap eael-testimonial-slider middle-style\" id=\"eael-testimonial-522e7ea\">\n\t\t\t            <div class=\"swiper swiper-8 eael-testimonial-slider-main swiper-container-522e7ea\" data-pagination=\".swiper-pagination-522e7ea\" data-arrow-next=\".swiper-button-next-522e7ea\" data-arrow-prev=\".swiper-button-prev-522e7ea\" data-items=\"3\" data-items-tablet=\"1\" data-items-mobile=\"1\" data-slide-items=\"1\" data-slide-items-tablet=\"1\" data-slide-items-mobile=\"1\" data-margin=\"50\" data-effect=\"slide\" data-speed=\"3000\" data-loop=\"1\" data-autoplay_speed=\"3000\">\n\n                <div class=\"swiper-wrapper\">\n\t\t\t\t\t\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t                        <div class=\"eael-testimonial-item clearfix swiper-slide testimonial-avatar-rounded eael-testimonial-align-left\">\n                            <div class=\"eael-testimonial-item-inner clearfix\">\n                                <div class=\"eael-testimonial-content \" style=\" height: %;\">\n\t\t\t\t\t\t\t\t\t<span class=\"eael-testimonial-quote\"><\/span><div class=\"eael-testimonial-text \"><p>Keeping my trucks on the road is the most important thing for me. But filing my 2290\u2019s seemed like such a chaotic thing. There are so many complex things that I had to worry about. Thankfully, I found EZ2290 from an online advertisement. It has been extremely helpful with completing my 2290 eFiles. I just finish the whole thing in a few minutes now. Their support team provides a whole new level of service. They\u2019re extremely helpful.<\/p><\/div>\t\t\t\t\t\t\t\t\t        <div class=\"eael-testimonial-image\">\n\t\t\t            <figure>\n                <img decoding=\"async\" src=\"https:\/\/ez2290.com\/hvut\/wp-content\/uploads\/2024\/03\/4-1.png\" alt=\"Owner Operator\">\n            <\/figure>\n        <\/div>\n\t\t                                    <div class=\"middle-style-content\">\n\t\t\t\t\t\t\t\t\t\t        <p class=\"eael-testimonial-user\" >Megan Charles<\/p>\n        <p class=\"eael-testimonial-user-company\">Owner-Operator, Texas<\/p>\n\t\t                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t                        <div class=\"eael-testimonial-item clearfix swiper-slide testimonial-avatar-rounded eael-testimonial-align-left\">\n                            <div class=\"eael-testimonial-item-inner clearfix\">\n                                <div class=\"eael-testimonial-content \" style=\" height: %;\">\n\t\t\t\t\t\t\t\t\t<span class=\"eael-testimonial-quote\"><\/span><div class=\"eael-testimonial-text \"><p>Managing a large fleet is not easy. You have so many things on your plate. There was a time where I used to sit with my accountant to get these paper files right but at the same time, I knew this is not what I should be focusing on if I want to grow my business. So, I simply outsourced all my HVUT files to EZ2290, and to say the least, it\u2019s a burden off me. They have made my life easy and I\u2019ve never had to worry about non-compliance since.<\/p><\/div>\t\t\t\t\t\t\t\t\t        <div class=\"eael-testimonial-image\">\n\t\t\t            <figure>\n                <img decoding=\"async\" src=\"https:\/\/ez2290.com\/hvut\/wp-content\/uploads\/2024\/03\/3.png\" alt=\"Fleet Owner\">\n            <\/figure>\n        <\/div>\n\t\t                                    <div class=\"middle-style-content\">\n\t\t\t\t\t\t\t\t\t\t        <p class=\"eael-testimonial-user\" >Richard Garret<\/p>\n        <p class=\"eael-testimonial-user-company\">Fleet Owner, Arizona <\/p>\n\t\t                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t                        <div class=\"eael-testimonial-item clearfix swiper-slide testimonial-avatar-rounded eael-testimonial-align-left\">\n                            <div class=\"eael-testimonial-item-inner clearfix\">\n                                <div class=\"eael-testimonial-content \" style=\" height: %;\">\n\t\t\t\t\t\t\t\t\t<span class=\"eael-testimonial-quote\"><\/span><div class=\"eael-testimonial-text \"><p><span class=\"ui-provider a b c d e f g h i j k l m n o p q r s t u v w x y z ab ac ae af ag ah ai aj ak\">ez2290's bulk pricing is a game-changer for fleet owners. Undoubtedly the best rates in the market, ensuring substantial savings. The simplicity of the pricing structure and generous bulk filing discounts make ez2290 the clear choice for affordability without compromising quality, making tax season a breeze for fleet managers like myself.<\/span><\/p><\/div>\t\t\t\t\t\t\t\t\t        <div class=\"eael-testimonial-image\">\n\t\t\t            <figure>\n                <img decoding=\"async\" src=\"https:\/\/ez2290.com\/hvut\/wp-content\/uploads\/2024\/03\/2.png\" alt=\"Fleet Manager\">\n            <\/figure>\n        <\/div>\n\t\t                                    <div class=\"middle-style-content\">\n\t\t\t\t\t\t\t\t\t\t        <p class=\"eael-testimonial-user\" >Mike Rodriguez<\/p>\n        <p class=\"eael-testimonial-user-company\">Fleet Manager<\/p>\n\t\t                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t                        <div class=\"eael-testimonial-item clearfix swiper-slide testimonial-avatar-rounded eael-testimonial-align-left\">\n                            <div class=\"eael-testimonial-item-inner clearfix\">\n                                <div class=\"eael-testimonial-content \" style=\" height: %;\">\n\t\t\t\t\t\t\t\t\t<span class=\"eael-testimonial-quote\"><\/span><div class=\"eael-testimonial-text \">Truck Driver\nFiling with ez2290 was easy and stress-free. The step-by-step guidance and user-friendly setup made it smooth for me. I appreciate the straightforward service, making tax season hassle-free.<\/div>\t\t\t\t\t\t\t\t\t        <div class=\"eael-testimonial-image\">\n\t\t\t            <figure>\n                <img decoding=\"async\" src=\"https:\/\/ez2290.com\/hvut\/wp-content\/uploads\/2024\/03\/5.png\" alt=\"Sarah\">\n            <\/figure>\n        <\/div>\n\t\t                                    <div class=\"middle-style-content\">\n\t\t\t\t\t\t\t\t\t\t        <p class=\"eael-testimonial-user\" >Sarah Thompson<\/p>\n        <p class=\"eael-testimonial-user-company\">Freelance<\/p>\n\t\t                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t                        <div class=\"eael-testimonial-item clearfix swiper-slide testimonial-avatar-rounded eael-testimonial-align-left\">\n                            <div class=\"eael-testimonial-item-inner clearfix\">\n                                <div class=\"eael-testimonial-content \" style=\" height: %;\">\n\t\t\t\t\t\t\t\t\t<span class=\"eael-testimonial-quote\"><\/span><div class=\"eael-testimonial-text \"><p><span class=\"ui-provider a b c d e f g h i j k l m n o p q r s t u v w x y z ab ac ae af ag ah ai aj ak\">I had a fantastic experience with ez2290, especially their customer support. I faced a hiccup, but Robert from support \u00a0reached out via email, and he was quick to respond, guiding me through the solution patiently. It's reassuring to know that they have excellent support in place. ez2290 not only simplifies filing but also ensures that assistance is just an email away when needed. Kudos to Robert!<\/span><\/p><\/div>\t\t\t\t\t\t\t\t\t        <div class=\"eael-testimonial-image\">\n\t\t\t            <figure>\n                <img decoding=\"async\" src=\"https:\/\/ez2290.com\/hvut\/wp-content\/uploads\/2024\/03\/1.png\" alt=\"Jhonson\">\n            <\/figure>\n        <\/div>\n\t\t                                    <div class=\"middle-style-content\">\n\t\t\t\t\t\t\t\t\t\t        <p class=\"eael-testimonial-user\" >Mark Johnson<\/p>\n        <p class=\"eael-testimonial-user-company\">Owner<\/p>\n\t\t                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t                        <div class=\"eael-testimonial-item clearfix swiper-slide testimonial-avatar-rounded eael-testimonial-align-left\">\n                            <div class=\"eael-testimonial-item-inner clearfix\">\n                                <div class=\"eael-testimonial-content \" style=\" height: %;\">\n\t\t\t\t\t\t\t\t\t<span class=\"eael-testimonial-quote\"><\/span><div class=\"eael-testimonial-text \"><p><span class=\"ui-provider a b c d e f g h i j k l m n o p q r s t u v w x y z ab ac ae af ag ah ai aj ak\">I've been using ez2290 for the past two years for 2-6 filings, and it's always been a reliable ally. The software's simple,it's been consistent in easing my tax responsibilities without unnecessary complexities. For anyone seeking a reliable and straightforward solution, ez2290 has has to be a go-to choice.<\/span><\/p><\/div>\t\t\t\t\t\t\t\t\t        <div class=\"eael-testimonial-image\">\n\t\t\t            <figure>\n                <img decoding=\"async\" src=\"https:\/\/ez2290.com\/hvut\/wp-content\/uploads\/2024\/03\/6.png\" alt=\"Small Fleet Owner\">\n            <\/figure>\n        <\/div>\n\t\t                                    <div class=\"middle-style-content\">\n\t\t\t\t\t\t\t\t\t\t        <p class=\"eael-testimonial-user\" >Emily Davis<\/p>\n        <p class=\"eael-testimonial-user-company\">Small Fleet Owner<\/p>\n\t\t                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t                <\/div>\n\t\t\t\t            <\/div>\n\t\t\t        <\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-3bb0970 e-con-full e-flex e-con e-parent\" data-id=\"3bb0970\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2e697c3 elementor-widget__width-inherit elementor-widget elementor-widget-aux_modern_button\" data-id=\"2e697c3\" data-element_type=\"widget\" data-widget_type=\"aux_modern_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t    <div class=\"aux-modern-button-wrapper aux-modern-button-align-left\" >\n                    <a class=\"aux-modern-button aux-black aux-modern-button-lg aux-modern-button-curve aux-modern-button-default aux-icon-right\" href=\"https:\/\/www.ez2290.com\/Account\/Login?utm_source=LP_SDP&#038;utm_medium=referral&#038;utm_campaign=Missouri+Trucking+Association\">\n                <div class=\"aux-overlay\"><\/div>\n                                    <div class=\"aux-icon \">\n                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"28\" height=\"28\" viewBox=\"0 0 28 28\" fill=\"none\"><g id=\"arrow_outward\"><mask id=\"mask0_1_367\" style=\"mask-type:alpha\" maskUnits=\"userSpaceOnUse\" x=\"0\" y=\"0\" width=\"28\" height=\"28\"><rect id=\"Bounding box\" width=\"28\" height=\"28\" fill=\"#D9D9D9\"><\/rect><\/mask><g mask=\"url(#mask0_1_367)\"><path id=\"arrow_outward_2\" d=\"M7.53732 21.2299L5.67383 19.3664L16.7134 8.32687H6.91023V5.6727H21.2311V19.9935H18.5769V10.1904L7.53732 21.2299Z\" fill=\"white\"><\/path><\/g><\/g><\/svg>                    <\/div>\n                                <div class=\"aux-text\">\n<span class=\"aux-text-before\">Avail 2290 Discount Now<\/span>                <\/div>\n            <\/a>\n            \n    <\/div>\n\n    \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-46f911dc e-con-full e-flex e-con e-parent\" data-id=\"46f911dc\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-48c9d257 elementor-widget elementor-widget-heading\" data-id=\"48c9d257\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Terms and Conditions<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-398ef98a elementor-align-left elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"398ef98a\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">The coupon code MTA10MOT provides a 10% discount on e-filing services for all 2290 & 8849 forms. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">This discount is exclusively available for first-time users and is applicable for a single transaction per account. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">To avail of the 10% discount, make sure to apply the coupon code during the checkout process. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Any attempts to claim the discount after the transaction has been completed will be considered null and void <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-2d3d2fa e-con-full e-flex e-con e-parent\" data-id=\"2d3d2fa\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f196ab4 elementor-widget elementor-widget-text-editor\" data-id=\"f196ab4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span class=\"ui-provider a b c d e f g h i j k l m n o p q r s t u v w x y z ab ac ae af ag ah ai aj ak\" dir=\"ltr\">Missouri Trucking Association (MTA), its logo, and trademarks are the exclusive property of MTA, Inc. All other trademarks are owned by their respective holders.<\/span><\/p><p>Copyright \u00a9 2024 MTA, Inc. All rights reserved.<\/p><p><span class=\"ui-provider a b c d e f g h i j k l m n o p q r s t u v w x y z ab ac ae af ag ah ai aj ak\" dir=\"ltr\">The special discount offered to MTA members by EZ2290 is an independent arrangement and is not endorsed or affiliated with MTA.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Special 2290 eFiling Discount for Missouri Trucking Association Members Use EZ2290 Coupon MTA10MOT to get 10% OFF on HVUT eFiling fee. eFile 2290 Now EZ2290 Discount for MTA Members eFile 2290 with EZ2290 and get 10% discount Bid farewell to paperwork burdens with EZ2290 eFiling Service, now complimented with 2290 Discount for eFiling. Avail 2290 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1222","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Missouri Trucking Association - EZ2290<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ez2290.com\/hvut\/missouri-trucking-association-mota\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Missouri Trucking Association - EZ2290\" \/>\n<meta property=\"og:description\" content=\"Special 2290 eFiling Discount for Missouri Trucking Association Members Use EZ2290 Coupon MTA10MOT to get 10% OFF on HVUT eFiling fee. eFile 2290 Now EZ2290 Discount for MTA Members eFile 2290 with EZ2290 and get 10% discount Bid farewell to paperwork burdens with EZ2290 eFiling Service, now complimented with 2290 Discount for eFiling. Avail 2290 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ez2290.com\/hvut\/missouri-trucking-association-mota\/\" \/>\n<meta property=\"og:site_name\" content=\"EZ2290\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-29T10:08:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ez2290.com\/hvut\/wp-content\/uploads\/2024\/03\/irslogo.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ez2290.com\/hvut\/missouri-trucking-association-mota\/\",\"url\":\"https:\/\/www.ez2290.com\/hvut\/missouri-trucking-association-mota\/\",\"name\":\"Missouri Trucking Association - EZ2290\",\"isPartOf\":{\"@id\":\"https:\/\/www.ez2290.com\/hvut\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.ez2290.com\/hvut\/missouri-trucking-association-mota\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.ez2290.com\/hvut\/missouri-trucking-association-mota\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ez2290.com\/hvut\/wp-content\/uploads\/2024\/03\/irslogo.png\",\"datePublished\":\"2024-03-07T11:56:18+00:00\",\"dateModified\":\"2025-04-29T10:08:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ez2290.com\/hvut\/missouri-trucking-association-mota\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ez2290.com\/hvut\/missouri-trucking-association-mota\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.ez2290.com\/hvut\/missouri-trucking-association-mota\/#primaryimage\",\"url\":\"https:\/\/ez2290.com\/hvut\/wp-content\/uploads\/2024\/03\/irslogo.png\",\"contentUrl\":\"https:\/\/ez2290.com\/hvut\/wp-content\/uploads\/2024\/03\/irslogo.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ez2290.com\/hvut\/missouri-trucking-association-mota\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ez2290.com\/hvut\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Missouri Trucking Association\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ez2290.com\/hvut\/#website\",\"url\":\"https:\/\/www.ez2290.com\/hvut\/\",\"name\":\"EZ2290\",\"description\":\"eFile Form 2290 Online\",\"publisher\":{\"@id\":\"https:\/\/www.ez2290.com\/hvut\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ez2290.com\/hvut\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.ez2290.com\/hvut\/#organization\",\"name\":\"EZ2290\",\"url\":\"https:\/\/www.ez2290.com\/hvut\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.ez2290.com\/hvut\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ez2290.com\/hvut\/wp-content\/uploads\/2024\/03\/Zenwork_SubBrandLogos-01-1.png\",\"contentUrl\":\"https:\/\/www.ez2290.com\/hvut\/wp-content\/uploads\/2024\/03\/Zenwork_SubBrandLogos-01-1.png\",\"width\":232,\"height\":62,\"caption\":\"EZ2290\"},\"image\":{\"@id\":\"https:\/\/www.ez2290.com\/hvut\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Missouri Trucking Association - EZ2290","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ez2290.com\/hvut\/missouri-trucking-association-mota\/","og_locale":"en_US","og_type":"article","og_title":"Missouri Trucking Association - EZ2290","og_description":"Special 2290 eFiling Discount for Missouri Trucking Association Members Use EZ2290 Coupon MTA10MOT to get 10% OFF on HVUT eFiling fee. eFile 2290 Now EZ2290 Discount for MTA Members eFile 2290 with EZ2290 and get 10% discount Bid farewell to paperwork burdens with EZ2290 eFiling Service, now complimented with 2290 Discount for eFiling. Avail 2290 [&hellip;]","og_url":"https:\/\/www.ez2290.com\/hvut\/missouri-trucking-association-mota\/","og_site_name":"EZ2290","article_modified_time":"2025-04-29T10:08:37+00:00","og_image":[{"url":"https:\/\/ez2290.com\/hvut\/wp-content\/uploads\/2024\/03\/irslogo.png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ez2290.com\/hvut\/missouri-trucking-association-mota\/","url":"https:\/\/www.ez2290.com\/hvut\/missouri-trucking-association-mota\/","name":"Missouri Trucking Association - EZ2290","isPartOf":{"@id":"https:\/\/www.ez2290.com\/hvut\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ez2290.com\/hvut\/missouri-trucking-association-mota\/#primaryimage"},"image":{"@id":"https:\/\/www.ez2290.com\/hvut\/missouri-trucking-association-mota\/#primaryimage"},"thumbnailUrl":"https:\/\/ez2290.com\/hvut\/wp-content\/uploads\/2024\/03\/irslogo.png","datePublished":"2024-03-07T11:56:18+00:00","dateModified":"2025-04-29T10:08:37+00:00","breadcrumb":{"@id":"https:\/\/www.ez2290.com\/hvut\/missouri-trucking-association-mota\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ez2290.com\/hvut\/missouri-trucking-association-mota\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.ez2290.com\/hvut\/missouri-trucking-association-mota\/#primaryimage","url":"https:\/\/ez2290.com\/hvut\/wp-content\/uploads\/2024\/03\/irslogo.png","contentUrl":"https:\/\/ez2290.com\/hvut\/wp-content\/uploads\/2024\/03\/irslogo.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ez2290.com\/hvut\/missouri-trucking-association-mota\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ez2290.com\/hvut\/"},{"@type":"ListItem","position":2,"name":"Missouri Trucking Association"}]},{"@type":"WebSite","@id":"https:\/\/www.ez2290.com\/hvut\/#website","url":"https:\/\/www.ez2290.com\/hvut\/","name":"EZ2290","description":"eFile Form 2290 Online","publisher":{"@id":"https:\/\/www.ez2290.com\/hvut\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ez2290.com\/hvut\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.ez2290.com\/hvut\/#organization","name":"EZ2290","url":"https:\/\/www.ez2290.com\/hvut\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.ez2290.com\/hvut\/#\/schema\/logo\/image\/","url":"https:\/\/www.ez2290.com\/hvut\/wp-content\/uploads\/2024\/03\/Zenwork_SubBrandLogos-01-1.png","contentUrl":"https:\/\/www.ez2290.com\/hvut\/wp-content\/uploads\/2024\/03\/Zenwork_SubBrandLogos-01-1.png","width":232,"height":62,"caption":"EZ2290"},"image":{"@id":"https:\/\/www.ez2290.com\/hvut\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.ez2290.com\/hvut\/wp-json\/wp\/v2\/pages\/1222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ez2290.com\/hvut\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ez2290.com\/hvut\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ez2290.com\/hvut\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ez2290.com\/hvut\/wp-json\/wp\/v2\/comments?post=1222"}],"version-history":[{"count":25,"href":"https:\/\/www.ez2290.com\/hvut\/wp-json\/wp\/v2\/pages\/1222\/revisions"}],"predecessor-version":[{"id":3169,"href":"https:\/\/www.ez2290.com\/hvut\/wp-json\/wp\/v2\/pages\/1222\/revisions\/3169"}],"wp:attachment":[{"href":"https:\/\/www.ez2290.com\/hvut\/wp-json\/wp\/v2\/media?parent=1222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}